{"id":17158,"date":"2013-12-20T16:33:52","date_gmt":"2013-12-20T15:33:52","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=17158"},"modified":"2023-01-14T17:14:44","modified_gmt":"2023-01-14T16:14:44","slug":"windows-8-1-store-mit-neuer-ansicht","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/","title":{"rendered":"Windows 8.1 Store mit neuer Ansicht"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht.jpg\" rel=\"lightbox[17158]\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht-122x150.jpg\" alt=\"windows-store-mit-neuer-ansicht\" width=\"122\" height=\"150\" class=\"alignleft size-medium wp-image-17159\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht-122x150.jpg 122w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht-408x500.jpg 408w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht.jpg 738w\" sizes=\"auto, (max-width: 122px) 100vw, 122px\" \/><\/a>Heute hab ich einmal wieder einen obligatorischen Blick in den Windows Store geworfen. <\/p>\n<p>Und ich war \u00fcberrascht, denn Microsoft hat (endlich) die Ansicht ge\u00e4ndert. Denn jetzt sieht man die Kategorien schon auf der Startseite im Store und muss nicht, wie gewohnt, erst per Rechtsklick die Kategorien von oben einblenden lassen.<\/p>\n<p>Somit kommt man schneller in die einzelnen Kategorien und kann nach den neuesten Apps im Store schn\u00f6kern.<\/p>\n<p>Sollte es bei euch noch nicht angezeigt werden, dann: <!--more--><\/p>\n<p>\u25aa Den Store <a href='http:\/\/www.deskmodder.de\/wiki\/index.php?title=Apps_komplett_beenden_Windows_8.1'\" target=\"_blank\"'>komplett beenden<\/a><br \/>\n\u25aa Win + R dr\u00fccken wsreset.exe eingeben und auf OK dr\u00fccken.<br \/>\n\u25aa Ein Eingabefenster \u00f6ffnet sich kurz.<\/p>\n<p>Jetzt kann man den Store wieder \u00f6ffnen und die Anzeige der Kategorien ist sichtbar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute hab ich einmal wieder einen obligatorischen Blick in den Windows Store geworfen. Und ich war \u00fcberrascht, denn Microsoft hat (endlich) die Ansicht ge\u00e4ndert. Denn jetzt sieht man die Kategorien schon auf der Startseite im Store und muss nicht, wie&hellip; <\/p>\n","protected":false},"author":134,"featured_media":17159,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,3031],"tags":[9750,4000],"class_list":["post-17158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows","category-windows-apps","tag-windows-8-1","tag-windows-store-ansicht-der-kategorien"],"wp_featured_image":{"id":17159,"alt_text":"","description":"","media_type":"image","media_details":{"width":738,"height":904,"file":"2013\/12\/windows-store-mit-neuer-ansicht.jpg","sizes":{"thumbnail":{"file":"windows-store-mit-neuer-ansicht-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht-150x150.jpg"},"medium":{"file":"windows-store-mit-neuer-ansicht-122x150.jpg","width":122,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht-122x150.jpg"},"large":{"file":"windows-store-mit-neuer-ansicht-408x500.jpg","width":408,"height":500,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht-408x500.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":17158,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht.jpg"},"commentcount":2,"wp_comments":[{"id":4359,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"http:\/\/aurum2rivi.wordpress.com\/","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2013-12-21T04:23:48","cld_nonce":"82f011626f","content":{"rendered":"<p>Konkrete Nachfrage zur Verdeutlichung dazu:<\/p>\n<p>&#8222;Den Store komplett beenden&#8220; usw. usw. &#8211; das ergibt doch den selben Effekt, als wenn ich den gleich im Taskmanager &#8222;alle&#8220; mache, oder? So handhabe ich das n\u00e4mlich, das geht bei mir fast automatisch wenn ich (selten) mal im Store war und ihn verlasse.<\/p>\n<p>Aber zur neuen Ansicht: die war bei mir schon da, sie mag auch \u00fcbersichtlicher sein &#8211; aber schon bei 24&#8243; ist das alles VIEL zu gro\u00df, um auch nur einigerma\u00dfen ernsthaft zu wirken.<\/p>\n<p>Man kann alle Apps zwar mit z.B. &#8222;ModernMix&#8220; im Fenstermodus laufen lassen, aber die Kacheln im Store werden auch nicht kleiner davon&#8230;<\/p>\n<p>Win8.1 ohne Kacheln auf einem PC w\u00e4re sicher nicht schlechter, grins. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_confused.gif\" alt=\":???:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":4361,"parent":0,"author":134,"author_name":"&#109;&#111;&#105;&#110;&#109;&#111;&#105;&#110;","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2013-12-21T10:31:14","cld_nonce":"82f011626f","content":{"rendered":"<p>Jo richtig, egal ob Task Manager oder mit der Maus nach unten ziehen und dort ein paar Sekunden halten.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Windows 8.1 Store mit neuer Ansicht - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windows 8.1 Store mit neuer Ansicht\" \/>\n<meta property=\"og:description\" content=\"Heute hab ich einmal wieder einen obligatorischen Blick in den Windows Store geworfen. Und ich war \u00fcberrascht, denn Microsoft hat (endlich) die Ansicht ge\u00e4ndert. Denn jetzt sieht man die Kategorien schon auf der Startseite im Store und muss nicht, wie&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-20T15:33:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-14T16:14:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"738\" \/>\n\t<meta property=\"og:image:height\" content=\"904\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Windows 8.1 Store mit neuer Ansicht\",\"datePublished\":\"2013-12-20T15:33:52+00:00\",\"dateModified\":\"2023-01-14T16:14:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/\"},\"wordCount\":85,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/windows-store-mit-neuer-ansicht.jpg\",\"keywords\":[\"Windows 8.1\",\"Windows Store Ansicht der Kategorien\"],\"articleSection\":[\"Windows \u00e4lter\",\"Windows Apps\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/#respond\"]}],\"copyrightYear\":\"2013\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/\",\"name\":\"Windows 8.1 Store mit neuer Ansicht - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/windows-store-mit-neuer-ansicht.jpg\",\"datePublished\":\"2013-12-20T15:33:52+00:00\",\"dateModified\":\"2023-01-14T16:14:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/windows-store-mit-neuer-ansicht.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/windows-store-mit-neuer-ansicht.jpg\",\"width\":738,\"height\":904},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/20\\\/windows-8-1-store-mit-neuer-ansicht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Windows 8.1 Store mit neuer Ansicht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Windows 8.1 Store mit neuer Ansicht - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/","og_locale":"de_DE","og_type":"article","og_title":"Windows 8.1 Store mit neuer Ansicht","og_description":"Heute hab ich einmal wieder einen obligatorischen Blick in den Windows Store geworfen. Und ich war \u00fcberrascht, denn Microsoft hat (endlich) die Ansicht ge\u00e4ndert. Denn jetzt sieht man die Kategorien schon auf der Startseite im Store und muss nicht, wie&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2013-12-20T15:33:52+00:00","article_modified_time":"2023-01-14T16:14:44+00:00","og_image":[{"width":738,"height":904,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Windows 8.1 Store mit neuer Ansicht","datePublished":"2013-12-20T15:33:52+00:00","dateModified":"2023-01-14T16:14:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/"},"wordCount":85,"commentCount":2,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht.jpg","keywords":["Windows 8.1","Windows Store Ansicht der Kategorien"],"articleSection":["Windows \u00e4lter","Windows Apps"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/#respond"]}],"copyrightYear":"2013","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/","url":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/","name":"Windows 8.1 Store mit neuer Ansicht - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht.jpg","datePublished":"2013-12-20T15:33:52+00:00","dateModified":"2023-01-14T16:14:44+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht.jpg","width":738,"height":904},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/20\/windows-8-1-store-mit-neuer-ansicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Windows 8.1 Store mit neuer Ansicht"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/windows-store-mit-neuer-ansicht.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/17158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=17158"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/17158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/17159"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=17158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=17158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=17158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}