{"id":17093,"date":"2013-12-19T09:37:21","date_gmt":"2013-12-19T08:37:21","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=17093"},"modified":"2013-12-19T09:39:16","modified_gmt":"2013-12-19T08:39:16","slug":"opera-hat-das-youtube-problem-mit-einem-patch-behoben","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/","title":{"rendered":"Opera hat das YouTube Problem mit einem Patch behoben"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/07\/Opera-Chromium.png\" rel=\"lightbox[17093]\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/07\/Opera-Chromium-150x150.png\" alt=\"Opera-Chromium\" width=\"150\" height=\"150\" class=\"alignleft size-medium wp-image-8761\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/07\/Opera-Chromium-150x150.png 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/07\/Opera-Chromium.png 257w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Als Kurzmitteilung f\u00fcr die gebeutelten Opera User der Version 18, 19 und 20.<br \/>\nViele hatten in letzter Zeit ein Problem, um Videos auf YouTube abzuspielen, bzw. die richtige Aufl\u00f6sung wurde nicht angezeigt.<br \/>\nOpera hat dazu nun einen Patch bereitgestellt, der nach \u00f6ffnen des Opera-Browsers automatisch eingespielt wird.<br \/>\nSollte dies nicht der Fall sein, dann einfach:<br \/>\n\u25aa Opera beenden<br \/>\n\u25aa Zum Profile Ordner ( in etwa: %appdata%\/Opera Software\/Opera\/) gehen und die browser.js l\u00f6schen<br \/>\n\u25aa Opera starten.<br \/>\nJetzt wird der Download der neuen browser.js erzwungen. Man erkennt es am \u00c4nderungsdatum der browser.js im Profile-Ordner.<br \/>\n<a href='http:\/\/blogs.opera.com\/desktop\/2013\/12\/youtube-is-back\/'\" target=\"_blank\"'>blogs.opera.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als Kurzmitteilung f\u00fcr die gebeutelten Opera User der Version 18, 19 und 20. Viele hatten in letzter Zeit ein Problem, um Videos auf YouTube abzuspielen, bzw. die richtige Aufl\u00f6sung wurde nicht angezeigt. Opera hat dazu nun einen Patch bereitgestellt, der&hellip; <\/p>\n","protected":false},"author":134,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166],"tags":[46,2236,984,1256],"class_list":["post-17093","post","type-post","status-publish","format-standard","hentry","category-browser","tag-opera","tag-patch","tag-problem","tag-youtube"],"wp_featured_image":null,"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Opera hat das YouTube Problem mit einem Patch behoben - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opera hat das YouTube Problem mit einem Patch behoben\" \/>\n<meta property=\"og:description\" content=\"Als Kurzmitteilung f\u00fcr die gebeutelten Opera User der Version 18, 19 und 20. Viele hatten in letzter Zeit ein Problem, um Videos auf YouTube abzuspielen, bzw. die richtige Aufl\u00f6sung wurde nicht angezeigt. Opera hat dazu nun einen Patch bereitgestellt, der&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-19T08:37:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-12-19T08:39:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/07\/Opera-Chromium-150x150.png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Opera hat das YouTube Problem mit einem Patch behoben\",\"datePublished\":\"2013-12-19T08:37:21+00:00\",\"dateModified\":\"2013-12-19T08:39:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/\"},\"wordCount\":102,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/Opera-Chromium-150x150.png\",\"keywords\":[\"Opera\",\"Patch\",\"Problem\",\"Youtube\"],\"articleSection\":[\"Browser\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/#respond\"]}],\"copyrightYear\":\"2013\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/\",\"name\":\"Opera hat das YouTube Problem mit einem Patch behoben - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/Opera-Chromium-150x150.png\",\"datePublished\":\"2013-12-19T08:37:21+00:00\",\"dateModified\":\"2013-12-19T08:39:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/Opera-Chromium.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/Opera-Chromium.png\",\"width\":257,\"height\":257},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/19\\\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opera hat das YouTube Problem mit einem Patch behoben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Opera hat das YouTube Problem mit einem Patch behoben - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/","og_locale":"de_DE","og_type":"article","og_title":"Opera hat das YouTube Problem mit einem Patch behoben","og_description":"Als Kurzmitteilung f\u00fcr die gebeutelten Opera User der Version 18, 19 und 20. Viele hatten in letzter Zeit ein Problem, um Videos auf YouTube abzuspielen, bzw. die richtige Aufl\u00f6sung wurde nicht angezeigt. Opera hat dazu nun einen Patch bereitgestellt, der&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2013-12-19T08:37:21+00:00","article_modified_time":"2013-12-19T08:39:16+00:00","og_image":[{"url":"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/07\/Opera-Chromium-150x150.png","type":"","width":"","height":""}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Opera hat das YouTube Problem mit einem Patch behoben","datePublished":"2013-12-19T08:37:21+00:00","dateModified":"2013-12-19T08:39:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/"},"wordCount":102,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/#primaryimage"},"thumbnailUrl":"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/07\/Opera-Chromium-150x150.png","keywords":["Opera","Patch","Problem","Youtube"],"articleSection":["Browser"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/#respond"]}],"copyrightYear":"2013","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/","url":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/","name":"Opera hat das YouTube Problem mit einem Patch behoben - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/#primaryimage"},"thumbnailUrl":"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/07\/Opera-Chromium-150x150.png","datePublished":"2013-12-19T08:37:21+00:00","dateModified":"2013-12-19T08:39:16+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/07\/Opera-Chromium.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/07\/Opera-Chromium.png","width":257,"height":257},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/19\/opera-hat-das-youtube-problem-mit-einem-patch-behoben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Opera hat das YouTube Problem mit einem Patch behoben"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/17093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=17093"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/17093\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=17093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=17093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=17093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}