{"id":16955,"date":"2013-12-16T18:32:18","date_gmt":"2013-12-16T17:32:18","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=16955"},"modified":"2013-12-16T18:32:18","modified_gmt":"2013-12-16T17:32:18","slug":"steam-machine-einmal-auseinander-genommen-video","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/","title":{"rendered":"Steam Machine &#8211; Einmal auseinander genommen (Video)"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine.jpg\" rel=\"lightbox[16955]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-16956\" alt=\"steam-machine\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine-150x96.jpg\" width=\"150\" height=\"96\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine-150x96.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine-500x320.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine.jpg 726w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Das Ger\u00e4t ist noch gar nicht auf dem Markt, denn es wurden bisher nur Prototypen verschickt. Corey Nelson hat sich einmal bei gemacht und genau diesen Spiele-Computer auseinander genommen.<br \/>\nJe nach Ausstattung ist ein i7, i5 oder i3 als CPU eingebaut.<br \/>\nAls Grafik eine GTX 780,760 oder 660. 16 GB Ram werden drin sein. Sowie ein 1 TB &#8211; 8GB Hybridfestplatte. Und nat\u00fcrlich das <a href=\"http:\/\/www.deskmodder.de\/blog\/2013\/12\/15\/steamos-1-0-verfuegbar\/\" target=\"_blank\">Steam OS<\/a> als Linux-Betriebssystem.<br \/>\n<!--more--><br \/>\nAb Mitte 2014 soll es dann diese, kann man sie noch PC nennen?, Spiele Computer zu kaufen geben.<br \/>\nDer Preis geht dabei bis auf 1.500$ (inkl. Wasserk\u00fchlung). Also Auswahl wird genug sein.<br \/>\nWird man sehen, ob sich die Steam Machine auch so gut verkaufen l\u00e4sst wie eine Spielekonsole.<\/p>\n<p>Und hier das Video:<\/p>\n<p><center><iframe loading=\"lazy\" src=\"\/\/www.youtube-nocookie.com\/embed\/xVkas2E3NAg?rel=0\" height=\"360\" width=\"640\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/center><\/p>\n<p style=\"text-align: right;\">(<a href=\"http:\/\/derstandard.at\/1385171149805\/Steam-Machine-ausgepackt-Das-steckt-im-Inneren-des-Spiele-PCs\" target=\"_blank\">via<\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Ger\u00e4t ist noch gar nicht auf dem Markt, denn es wurden bisher nur Prototypen verschickt. Corey Nelson hat sich einmal bei gemacht und genau diesen Spiele-Computer auseinander genommen. Je nach Ausstattung ist ein i7, i5 oder i3 als CPU&hellip; <\/p>\n","protected":false},"author":134,"featured_media":16956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286],"tags":[3949,3218],"class_list":["post-16955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","tag-das-innere","tag-steam-machine"],"wp_featured_image":{"id":16956,"alt_text":"","description":"","media_type":"image","media_details":{"width":726,"height":466,"file":"2013\/12\/steam-machine.jpg","sizes":{"thumbnail":{"file":"steam-machine-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine-150x150.jpg"},"medium":{"file":"steam-machine-150x96.jpg","width":150,"height":96,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine-150x96.jpg"},"large":{"file":"steam-machine-500x320.jpg","width":500,"height":320,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine-500x320.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":16955,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Steam Machine - Einmal auseinander genommen (Video) - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steam Machine - Einmal auseinander genommen (Video)\" \/>\n<meta property=\"og:description\" content=\"Das Ger\u00e4t ist noch gar nicht auf dem Markt, denn es wurden bisher nur Prototypen verschickt. Corey Nelson hat sich einmal bei gemacht und genau diesen Spiele-Computer auseinander genommen. Je nach Ausstattung ist ein i7, i5 oder i3 als CPU&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-16T17:32:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"726\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Steam Machine &#8211; Einmal auseinander genommen (Video)\",\"datePublished\":\"2013-12-16T17:32:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/\"},\"wordCount\":126,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/steam-machine.jpg\",\"keywords\":[\"das innere\",\"Steam Machine\"],\"articleSection\":[\"Hardware\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/#respond\"]}],\"copyrightYear\":\"2013\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/\",\"name\":\"Steam Machine - Einmal auseinander genommen (Video) - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/steam-machine.jpg\",\"datePublished\":\"2013-12-16T17:32:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/steam-machine.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/steam-machine.jpg\",\"width\":726,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/12\\\/16\\\/steam-machine-einmal-auseinander-genommen-video\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Steam Machine &#8211; Einmal auseinander genommen (Video)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Steam Machine - Einmal auseinander genommen (Video) - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/","og_locale":"de_DE","og_type":"article","og_title":"Steam Machine - Einmal auseinander genommen (Video)","og_description":"Das Ger\u00e4t ist noch gar nicht auf dem Markt, denn es wurden bisher nur Prototypen verschickt. Corey Nelson hat sich einmal bei gemacht und genau diesen Spiele-Computer auseinander genommen. Je nach Ausstattung ist ein i7, i5 oder i3 als CPU&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2013-12-16T17:32:18+00:00","og_image":[{"width":726,"height":466,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Steam Machine &#8211; Einmal auseinander genommen (Video)","datePublished":"2013-12-16T17:32:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/"},"wordCount":126,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine.jpg","keywords":["das innere","Steam Machine"],"articleSection":["Hardware"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/#respond"]}],"copyrightYear":"2013","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/","url":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/","name":"Steam Machine - Einmal auseinander genommen (Video) - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine.jpg","datePublished":"2013-12-16T17:32:18+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine.jpg","width":726,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/12\/16\/steam-machine-einmal-auseinander-genommen-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Steam Machine &#8211; Einmal auseinander genommen (Video)"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/steam-machine.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/16955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=16955"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/16955\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/16956"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=16955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=16955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=16955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}