{"id":168552,"date":"2022-08-18T13:00:54","date_gmt":"2022-08-18T11:00:54","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=168552"},"modified":"2022-08-18T15:53:40","modified_gmt":"2022-08-18T13:53:40","slug":"libreoffice-7-4-mit-vielen-verbesserungen-erschienen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/","title":{"rendered":"LibreOffice 7.4 (Final) mit vielen Verbesserungen erschienen"},"content":{"rendered":"<p>LibreOffice, die kostenlose Office-Version, hat ein neues Update auf LibreOffice 7.4 Community zum Download f\u00fcr Windows, Linux und macOS bereitgestellt. LibreOffice im Unternehmensumfeld wird dann sp\u00e4ter folgen. Mit dabei wieder neue Funktionen und viele Verbesserungen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74-500x323.jpg\" alt=\"\" width=\"500\" height=\"323\" class=\"aligncenter size-medium wp-image-168553\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74-500x323.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74-810x524.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74-306x198.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74.jpg 1120w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Mal ein paar interessante Zahlen dazu: <em>Die neuen Funktionen von LibreOffice 7.4 Community wurden von 147 Mitwirkenden entwickelt. Dar\u00fcber hinaus haben 528 Freiwillige \u00dcbersetzungen in 158 Sprachen zur Verf\u00fcgung gestellt. LibreOffice 7.4 Community wird in 120 verschiedenen Sprachversionen ver\u00f6ffentlicht, mehr als jede andere freie oder propriet\u00e4re Software, und kann somit von \u00fcber 5,4 Milliarden Menschen weltweit in ihrer Muttersprache (L1) verwendet werden. <\/em> Aber jetzt erst einmal zu den neuen Funktionen:<\/p>\n<ul>\n<li><strong>ALLGEMEINES<\/strong><\/li>\n<li>Unterst\u00fctzung f\u00fcr WebP-Bilder und EMZ\/WMZ-Dateien<\/li>\n<li>Hilfeseiten f\u00fcr die ScriptForge-Skriptbibliothek<\/li>\n<li>Suchfeld f\u00fcr den Extension Manager<\/li>\n<li>Leistungs- und Kompatibilit\u00e4tsverbesserungen<\/li>\n<li><strong>WRITER<\/strong><\/li>\n<li>Bessere \u00c4nderungsverfolgung im Fu\u00dfnotenbereich<\/li>\n<li>Bearbeitete Listen zeigen in der \u00c4nderungsverfolgung die Originalnummern an<\/li>\n<li>Neue typografische Einstellungen f\u00fcr die Silbentrennung<\/li>\n<li><strong>CALC<\/strong><\/li>\n<li>Unterst\u00fctzung f\u00fcr 16.384 Spalten in Tabellenkalkulationen<\/li>\n<li>Zus\u00e4tzliche Funktionen im Dropdown-Widget AutoSum<\/li>\n<li>Neuer Men\u00fcpunkt zur Suche nach Tabellennamen<\/li>\n<li><strong>IMPRESS<\/strong><\/li>\n<li>Neue Unterst\u00fctzung f\u00fcr Dokument-Themen<\/li>\n<\/ul>\n<div class=\"video-container\"><div style=\"position:relative;width:100%;max-width:810px;height:456px;background-color:black;color:white;padding:0px;\" data-video-id=\"PC8M4UzqpqE\">\n\t\t\t\t\t\t<div style=\"text-align: center;\">\n\t\t\t\t\t\t\t<span class=\"hint-text\">Erst durch Klick auf den Button werden Daten an Youtube \u00fcbermittelt und dir das Video angezeigt.<br\/>Mehr dazu in unserer <a href=\"https:\/\/www.deskmodder.de\/blog\/datenschutz-auf-deskmodder-de\/\" target=\"_blank\">Datenschutzrichtlinie<\/a><\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div style=\"text-align: center; margin-top: 10px;\">\n\t\t\t\t\t\t\t<button onclick=\"showVideo(this)\">Verstanden!<\/button>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"video-container\" style=\"display:none;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/PC8M4UzqpqE\/hqdefault.jpg\" alt=\"Vorschaubild\" style=\"width:100%; max-width:810px;\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script>\n\t\t\t\t\t\tfunction showVideo(button) {\n\t\t\t\t\t\t\tconst videoID = button.parentElement.parentElement.getAttribute(\"data-video-id\");\n\t\t\t\t\t\t\tconsole.log(\"Video ID:\", videoID); \/\/ Debugging\n\t\t\t\t\t\t\tconst iframeHTML = \"<iframe width='810' height='456' src='https:\/\/www.youtube-nocookie.com\/embed\/\" + videoID + \"?feature=oembed' frameborder='0' allow='accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture' allowfullscreen><\/iframe>\";\n\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".video-container\").innerHTML = iframeHTML;\n\n\t\t\t\t\t\t\t\/\/ Video-Container sichtbar machen\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".video-container\").style.display = \"block\";\n\t\t\t\t\t\t\tbutton.parentElement.parentElement.querySelector(\".hint-text\").style.display = \"none\";\n\t\t\t\t\t\t\tbutton.remove();\n\t\t\t\t\t\t}\n\t\t\t\t\t<\/script><\/div>\n<p>Die komplette Release Notes wurde auf <a href=\"https:\/\/wiki.documentfoundation.org\/ReleaseNotes\/7.4\/de\" rel=\"noopener\" target=\"_blank\">dieser Seite bereitgestellt<\/a>. Den Download f\u00fcr die verschiedenen Systeme findet ihr wie <a href=\"https:\/\/de.libreoffice.org\/download\/download\/\" rel=\"noopener\" target=\"_blank\">immer auf dieser Seite<\/a>. Wer LibreOffice noch nicht kennen sollte, hier <a href=\"https:\/\/de.libreoffice.org\/discover\/libreoffice\/\" rel=\"noopener\" target=\"_blank\">ein kleiner \u00dcberblick<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LibreOffice, die kostenlose Office-Version, hat ein neues Update auf LibreOffice 7.4 Community zum Download f\u00fcr Windows, Linux und macOS bereitgestellt. LibreOffice im Unternehmensumfeld wird dann sp\u00e4ter folgen. Mit dabei wieder neue Funktionen und viele Verbesserungen. Mal ein paar interessante Zahlen&hellip; <\/p>\n","protected":false},"author":134,"featured_media":168553,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[152],"tags":[83683],"class_list":["post-168552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software","tag-libreoffice-7-4"],"wp_featured_image":{"id":168553,"alt_text":"","description":"","media_type":"image","media_details":{"width":1120,"height":724,"file":"2022\/08\/libreoffice-74.jpg","filesize":98525,"sizes":{"medium":{"file":"libreoffice-74-500x323.jpg","width":500,"height":323,"mime-type":"image\/jpeg","filesize":13914,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74-500x323.jpg"},"large":{"file":"libreoffice-74-810x524.jpg","width":810,"height":524,"mime-type":"image\/jpeg","filesize":23055,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74-810x524.jpg"},"thumbnail":{"file":"libreoffice-74-306x198.jpg","width":306,"height":198,"mime-type":"image\/jpeg","filesize":6490,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74-306x198.jpg"},"blog-large":{"file":"libreoffice-74-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","filesize":17813,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74-642x300.jpg"},"blog-medium":{"file":"libreoffice-74-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","filesize":7105,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74-306x205.jpg"},"recent-thumb":{"file":"libreoffice-74-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","filesize":9647,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74-350x316.jpg"},"service-featured":{"file":"libreoffice-74-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","filesize":15917,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74-600x330.jpg"},"wp_rp_thumbnail":{"file":"libreoffice-74-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","filesize":878,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":168552,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74.jpg"},"commentcount":28,"wp_comments":[{"id":218200,"parent":0,"author":0,"author_name":"Pat","author_email":"quarkfrosch@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6aa0abfd851f59f54e37309b4c9d60fcb15d8fe2c4da50cbeaea4f16ed96dc68?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6aa0abfd851f59f54e37309b4c9d60fcb15d8fe2c4da50cbeaea4f16ed96dc68?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6aa0abfd851f59f54e37309b4c9d60fcb15d8fe2c4da50cbeaea4f16ed96dc68?s=96&d=mm&r=g"},"date":"2022-08-18T13:22:11","cld_nonce":"b6d6726996","content":{"rendered":"<p>IMPRESSUM [&#8230;] Dokumententhemen<br \/>\nIch liebe maschinelle \u00dcbersetzungen, Impress, der Powerpoint fake ist wohl gemeint.<\/p>\n<p>Gesendet von meiner Mittagessen box (Chassis-WMI Typ 16) &#8211; siehe docs.microsoft.com<\/p>\n"},"status":"1"},{"id":218201,"parent":218200,"author":0,"author_name":"Viktor","author_email":"sorix@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6845611b9beed1aeb311429a00391ece5f305d2523140e8feadaa8c147b04d23?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6845611b9beed1aeb311429a00391ece5f305d2523140e8feadaa8c147b04d23?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6845611b9beed1aeb311429a00391ece5f305d2523140e8feadaa8c147b04d23?s=96&d=mm&r=g"},"date":"2022-08-18T14:11:19","cld_nonce":"b6d6726996","content":{"rendered":"<p>Impress, Impressum kann auch nur eine Autokorrektur sein&#8230; gleich eine maschinelle \u00dcbersetzung &#8222;vorzuwerfen&#8220; ist kurz gesprungen, sehr kurz&#8230;<\/p>\n<p>Das Impress ein &#8222;Powerpoint fake&#8220; ist, ist mir neu und zeigt nur, dass du eine &#8222;Abneigung&#8220; gegen freie Software wie LO hast. Es ist eine Pr\u00e4sentationssoftware wie viele andere auch&#8230;<br \/>\nEin BMW ist ja schlie\u00dflich auch kein Mercedes fake&#8230;.<\/p>\n<p>Wenn man LO objektiv betrachtet ist es auf jeden Fall eine Super Office Suite f\u00fcr ALLE und dass dann auch noch ohne Abo oder zus\u00e4tzliche Kosten.<br \/>\nAuch im gesch\u00e4ftlichen Bereich f\u00fcr mich eine Bereicherung.<\/p>\n<p>Man sollte sich aber mal fragen warum MS es mit der gro\u00dfen Entwicklertruppe nicht hinbekommt, den offenen &#8222;openDocument&#8220; Standard fehlerfrei zu implementieren. Klar, dann w\u00e4re es ja zum Vorteil f\u00fcr den Marktbegleiter und das will nat\u00fcrlich keiner&#8230;<\/p>\n"},"status":"1"},{"id":218208,"parent":0,"author":6551,"author_name":"haw1961","author_email":"hwitt@mailbox.org","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c0b3b83962ed57778b86639b8dffb64ef1eb3b7c7e2d22e464e1e5436e0841db?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c0b3b83962ed57778b86639b8dffb64ef1eb3b7c7e2d22e464e1e5436e0841db?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c0b3b83962ed57778b86639b8dffb64ef1eb3b7c7e2d22e464e1e5436e0841db?s=96&d=mm&r=g"},"date":"2022-08-18T16:39:42","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich freue mich vor allem das es nun einen wirklichen &#8222;Dark Mode&#8220; unter Windows gibt.<br \/>\nOk, ist noch experimentell, funktioniert hier aber schon recht gut.<br \/>\nNutze LibreOffice\/OpenOffice\/StarOffice schon ewig und bin sehr zufrieden damit.<\/p>\n"},"status":"1"},{"id":218210,"parent":0,"author":0,"author_name":"Malsabku","author_email":"malsabku@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d2a5eb8defc8af5dd72eb89ab2733065ff6990b98c5feb7bb025054e52712293?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d2a5eb8defc8af5dd72eb89ab2733065ff6990b98c5feb7bb025054e52712293?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d2a5eb8defc8af5dd72eb89ab2733065ff6990b98c5feb7bb025054e52712293?s=96&d=mm&r=g"},"date":"2022-08-18T17:24:27","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wann kommt es endlich als original in den Windows Store? :\/  Gerade bei dieser Applikation w\u00e4re es w\u00fcnschenswert aufgrund der eher mangelhaften (nett ausgedr\u00fcckt) Updateverwaltung von LibreOffice.<\/p>\n"},"status":"1"},{"id":218211,"parent":218208,"author":6352,"author_name":"Yee Haw","author_email":"forenpost@mailbox.org","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0743c35a5121502c503c249539327c0376796e72b9c916b354570f78eebda367?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0743c35a5121502c503c249539327c0376796e72b9c916b354570f78eebda367?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0743c35a5121502c503c249539327c0376796e72b9c916b354570f78eebda367?s=96&d=mm&r=g"},"date":"2022-08-18T17:27:34","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8222;Das Impress ein \u201ePowerpoint fake\u201c ist, ist mir neu  &#8230;&#8220;<\/p>\n<p>Davon habe ich aber auch schon gelesen\/-h\u00f6rt. Als Eingest\u00e4ndnis aus LO-Entwicklerkreisen.<\/p>\n<p>Da auch ich eine Zeit lang mit Impress gearbeitet habe, kann ich beide Module ganz gut vergleichen. Mir fallen immer wieder die vielen kleinen Unterst\u00fctzungen beim Erstellen einer Pr\u00e4sentation mit PowerPoint auf.<\/p>\n"},"status":"1"},{"id":218216,"parent":0,"author":2038,"author_name":"GwenDragon","author_email":"info@gwendragon.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=96&d=mm&r=g"},"date":"2022-08-18T19:35:27","cld_nonce":"b6d6726996","content":{"rendered":"<p>Da wird die \ud83d\udc0f\ud83d\udc11 noch warten, bis f\u00fcr Firmenumgebungen die Version hoch gestuft wird.<\/p>\n"},"status":"1"},{"id":218218,"parent":0,"author":2038,"author_name":"GwenDragon","author_email":"info@gwendragon.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=96&d=mm&r=g"},"date":"2022-08-18T19:53:25","cld_nonce":"b6d6726996","content":{"rendered":"<p>Mal sehen welche Linux-Distries die neue 7.4 schon \u00fcber die Repos raus bringen.<\/p>\n"},"status":"1"},{"id":218219,"parent":0,"author":0,"author_name":"dieterr","author_email":"z0@fn.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/afa0fb6d663dc63b102d9f3ef60ff1e2e4303238e5f2d41d24887d5f062c6f8f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/afa0fb6d663dc63b102d9f3ef60ff1e2e4303238e5f2d41d24887d5f062c6f8f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/afa0fb6d663dc63b102d9f3ef60ff1e2e4303238e5f2d41d24887d5f062c6f8f?s=96&d=mm&r=g"},"date":"2022-08-18T20:55:56","cld_nonce":"b6d6726996","content":{"rendered":"<p>und?<br \/>\nhat es endlich ein funktionierenden updater f\u00fcr windows?<\/p>\n"},"status":"1"},{"id":218231,"parent":218218,"author":0,"author_name":"Teyro","author_email":"c.stake@posteo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ae4cb8440c17cf9117dacbd0bc1c139262a3e1f08d8dc6be281889d016bf04ce?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ae4cb8440c17cf9117dacbd0bc1c139262a3e1f08d8dc6be281889d016bf04ce?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ae4cb8440c17cf9117dacbd0bc1c139262a3e1f08d8dc6be281889d016bf04ce?s=96&d=mm&r=g"},"date":"2022-08-19T06:46:21","cld_nonce":"b6d6726996","content":{"rendered":"<p>ArchLinux hatte das gestern drinne<\/p>\n"},"status":"1"},{"id":218236,"parent":0,"author":0,"author_name":"Arnie","author_email":"arnie_do@yahoo.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d9dec36b651da50369c564bab95db64c933912769d190e9f4d16b746b043e091?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d9dec36b651da50369c564bab95db64c933912769d190e9f4d16b746b043e091?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d9dec36b651da50369c564bab95db64c933912769d190e9f4d16b746b043e091?s=96&d=mm&r=g"},"date":"2022-08-19T08:48:23","cld_nonce":"b6d6726996","content":{"rendered":"<p>Schade, bei mir sind der Writer und der Launcher unter Win 10 immer im Fenstermodus gestartet.<br \/>\nBin deshalb zur\u00fcck zur 7.3.<\/p>\n"},"status":"1"},{"id":218241,"parent":218236,"author":6551,"author_name":"haw1961","author_email":"hwitt@mailbox.org","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c0b3b83962ed57778b86639b8dffb64ef1eb3b7c7e2d22e464e1e5436e0841db?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c0b3b83962ed57778b86639b8dffb64ef1eb3b7c7e2d22e464e1e5436e0841db?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c0b3b83962ed57778b86639b8dffb64ef1eb3b7c7e2d22e464e1e5436e0841db?s=96&d=mm&r=g"},"date":"2022-08-19T09:46:07","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ja, ist hier auch so.<br \/>\nAber dem kann man schnell abhelfen:<br \/>\nC:\\ProgramData\\Microsoft\\Windows\\Start Menu\\Programs\\LibreOffice 7.4<br \/>\naufrufen.<br \/>\nRechtsklick auf die Starter&#8212;&gt; Eigenschaften&#8212;&gt; Ausf\u00fchren auf maximiert stellen.<br \/>\nKommt noch eine Abfrage, diese best\u00e4tigen.<br \/>\nDas war&#8217;s.<br \/>\nLeider startet LO aber immer noch im Fenstermodus wenn man ein Dokument direkt anklickt.<\/p>\n"},"status":"1"},{"id":218242,"parent":218241,"author":0,"author_name":"Arnie","author_email":"arnie_do@yahoo.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d9dec36b651da50369c564bab95db64c933912769d190e9f4d16b746b043e091?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d9dec36b651da50369c564bab95db64c933912769d190e9f4d16b746b043e091?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d9dec36b651da50369c564bab95db64c933912769d190e9f4d16b746b043e091?s=96&d=mm&r=g"},"date":"2022-08-19T10:00:20","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hi haw1961,<\/p>\n<p>vielen Dank f\u00fcr den Tipp, aber dass LO bei Doppelklick auf ein Dokument immer noch im Fenstermodus startet, nervt doch ziemlich.<br \/>\nIch warte auf die *.1.<\/p>\n<p>Nochmals Danke.<br \/>\nArnie<\/p>\n"},"status":"1"},{"id":218259,"parent":218219,"author":2038,"author_name":"GwenDragon","author_email":"info@gwendragon.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=96&d=mm&r=g"},"date":"2022-08-19T15:38:48","cld_nonce":"b6d6726996","content":{"rendered":"<p>Das ist eben das migeschleppte Drama unter Windows seit Jahren, dass Nicht-Microsoftprogramme keine gemeinsame Update-Strategie bez\u00fcglich Online-Updates entwickelt haben. Sicher w\u00e4re der MS Store eine L\u00f6sung.<br \/>\nAber das bei\u00dft sich dann mit &#8222;Freier Software&#8220;, den MS Store zu benutzen.<\/p>\n"},"status":"1"},{"id":218260,"parent":218242,"author":0,"author_name":"Ich wei\u00df von nix","author_email":".@ms.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/adc78ba288580dde8f02c4314d7ef845ac17c1e721e2ea73817330a8be6fa729?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/adc78ba288580dde8f02c4314d7ef845ac17c1e721e2ea73817330a8be6fa729?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/adc78ba288580dde8f02c4314d7ef845ac17c1e721e2ea73817330a8be6fa729?s=96&d=mm&r=g"},"date":"2022-08-19T15:51:14","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wenn man in den Eigenschaften <b>jeder Datei<\/b> festlegt, dass im Vollbildmodus (maximiert) gestartet werden soll, dann funktioniert es auf jeden Fall ( und nicht \u00fcber den Starter)<\/p>\n"},"status":"1"},{"id":218344,"parent":218259,"author":0,"author_name":"Heisenberg","author_email":"newworldorder23@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fc8a36362c5cc0dd73aff23683d6ccc384067b358840a7dc0db638d6578c035c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fc8a36362c5cc0dd73aff23683d6ccc384067b358840a7dc0db638d6578c035c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fc8a36362c5cc0dd73aff23683d6ccc384067b358840a7dc0db638d6578c035c?s=96&d=mm&r=g"},"date":"2022-08-22T08:03:38","cld_nonce":"b6d6726996","content":{"rendered":"<p>Sie k\u00f6nnten ja neben der Windows Store Version die normale Webseiten Version weiter anbieten, dann k\u00f6nnten normale Menschen das \u00fcber den Windows Store installieren und diese alles Open source muss super frei sein Freaks k\u00f6nnen das ja weiter von Hand runterladen. \ud83d\ude05<\/p>\n"},"status":"1"},{"id":218615,"parent":0,"author":0,"author_name":"Rudi","author_email":"r.feistel@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0b0ec18a003c92a4cd252e396acb3611afcc9b78180bc6e37df48bd5493c04a7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0b0ec18a003c92a4cd252e396acb3611afcc9b78180bc6e37df48bd5493c04a7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0b0ec18a003c92a4cd252e396acb3611afcc9b78180bc6e37df48bd5493c04a7?s=96&d=mm&r=g"},"date":"2022-08-25T21:44:34","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei allen fr\u00fcheren Versionen von LibreOffice war es so, dass sich jede Anwendung die von mir gew\u00e4hlte Fenstergr\u00f6\u00dfe und Position gemerkt hat. Warum nun pl\u00f6tzlich nicht mehr? Entweder \u00f6ffnet sich das Fenster mittig zentriert (Writer) oder im Vollbildmodus. Ist das bisherige Verhalten einstellbar?<\/p>\n"},"status":"1"},{"id":218637,"parent":0,"author":3956,"author_name":"John-Boy","author_email":"edv.fst@gmx.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/36d3d6b28ddfa30d30dc8bed484ba2a32c95cfd9c83bde308d8fb476bb1abc84?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/36d3d6b28ddfa30d30dc8bed484ba2a32c95cfd9c83bde308d8fb476bb1abc84?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/36d3d6b28ddfa30d30dc8bed484ba2a32c95cfd9c83bde308d8fb476bb1abc84?s=96&d=mm&r=g"},"date":"2022-08-26T11:09:14","cld_nonce":"b6d6726996","content":{"rendered":"<p>Fenstergr\u00f6\u00dfe wird nicht gespeichert<\/p>\n<p>bekanntes und bereits gemeldetes Problem Bug 150236<\/p>\n<p><a href=\"https:\/\/bugs.documentfoundation.org\/show_bug.cgi?id=150236\" rel=\"nofollow ugc\">https:\/\/bugs.documentfoundation.org\/show_bug.cgi?id=150236<\/a><\/p>\n"},"status":"1"},{"id":218643,"parent":218637,"author":0,"author_name":"Rudi","author_email":"r.feistel@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0b0ec18a003c92a4cd252e396acb3611afcc9b78180bc6e37df48bd5493c04a7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0b0ec18a003c92a4cd252e396acb3611afcc9b78180bc6e37df48bd5493c04a7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0b0ec18a003c92a4cd252e396acb3611afcc9b78180bc6e37df48bd5493c04a7?s=96&d=mm&r=g"},"date":"2022-08-26T14:58:03","cld_nonce":"b6d6726996","content":{"rendered":"<p>Danke, hei\u00dft es also warten.<\/p>\n"},"status":"1"},{"id":219165,"parent":0,"author":0,"author_name":"NaJa","author_email":"blnccs@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5837dd5696bdead310fb8c508343a22637536ca069517a4decc94f6bd70c7811?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5837dd5696bdead310fb8c508343a22637536ca069517a4decc94f6bd70c7811?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5837dd5696bdead310fb8c508343a22637536ca069517a4decc94f6bd70c7811?s=96&d=mm&r=g"},"date":"2022-09-04T13:04:37","cld_nonce":"b6d6726996","content":{"rendered":"<p>Fenstergr\u00f6\u00dfe repariert seit 7.4.1.1, maximiert und in allen individuellen Gr\u00f6\u00dfen (W11)<\/p>\n"},"status":"1"},{"id":219212,"parent":0,"author":0,"author_name":"Rudi","author_email":"r.feistel@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0b0ec18a003c92a4cd252e396acb3611afcc9b78180bc6e37df48bd5493c04a7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0b0ec18a003c92a4cd252e396acb3611afcc9b78180bc6e37df48bd5493c04a7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0b0ec18a003c92a4cd252e396acb3611afcc9b78180bc6e37df48bd5493c04a7?s=96&d=mm&r=g"},"date":"2022-09-05T18:38:25","cld_nonce":"b6d6726996","content":{"rendered":"<p>Seit? Wann wird die denn ausgeliefert? Heute ist es noch die 7.4.0.3.<\/p>\n"},"status":"1"},{"id":219214,"parent":219212,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2022-09-05T18:53:33","cld_nonce":"b6d6726996","content":{"rendered":"<p>Die 7.4.1.1 ist die RC1. Die Tage m\u00fcsste die RC2 erscheinen und die endg\u00fcltige Version dann in Woche 37.<\/p>\n<p><a href=\"https:\/\/de.libreoffice.org\/download\/pre-releases\/\" rel=\"nofollow ugc\">https:\/\/de.libreoffice.org\/download\/pre-releases\/<\/a><\/p>\n"},"status":"1"},{"id":219850,"parent":0,"author":5818,"author_name":"alles","author_email":"alles.geheim@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=96&d=mm&r=g"},"date":"2022-09-15T13:35:50","cld_nonce":"b6d6726996","content":{"rendered":"<p>LibreOffice 7.4.1<\/p>\n<p><a href=\"https:\/\/www.libreoffice.org\/download\/download-libreoffice\/\" rel=\"nofollow ugc\">https:\/\/www.libreoffice.org\/download\/download-libreoffice\/<\/a><\/p>\n"},"status":"1"},{"id":221941,"parent":0,"author":0,"author_name":"juergen","author_email":"jkluth@dokom.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/320886e4e24f6efda228d76bdd595992466dafe009598d59764fcb759786a0a5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/320886e4e24f6efda228d76bdd595992466dafe009598d59764fcb759786a0a5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/320886e4e24f6efda228d76bdd595992466dafe009598d59764fcb759786a0a5?s=96&d=mm&r=g"},"date":"2022-10-15T13:40:34","cld_nonce":"b6d6726996","content":{"rendered":"<p>7.4.2 ist raus :<\/p>\n<p><a href=\"http:\/\/www.libreoffice.org\/\" rel=\"nofollow ugc\">http:\/\/www.libreoffice.org\/<\/a><\/p>\n"},"status":"1"},{"id":222619,"parent":0,"author":0,"author_name":"Daniel","author_email":"dkohlbach@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3c6fdb551ee24967c524ffe43380003ecee53ad35f8007e16b3e4e97da21d601?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3c6fdb551ee24967c524ffe43380003ecee53ad35f8007e16b3e4e97da21d601?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3c6fdb551ee24967c524ffe43380003ecee53ad35f8007e16b3e4e97da21d601?s=96&d=mm&r=g"},"date":"2022-10-25T19:02:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>Schade, dass es immer noch keinen richtigen DarkMode f\u00fcr Windows gibt <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":224552,"parent":0,"author":5818,"author_name":"alles","author_email":"alles.geheim@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=96&d=mm&r=g"},"date":"2022-11-24T12:01:23","cld_nonce":"b6d6726996","content":{"rendered":"<p>LibreOffice 7.4.3<\/p>\n<p><a href=\"https:\/\/www.libreoffice.org\/download\/download-libreoffice\/\" rel=\"nofollow ugc\">https:\/\/www.libreoffice.org\/download\/download-libreoffice\/<\/a><\/p>\n"},"status":"1"},{"id":230661,"parent":224552,"author":5818,"author_name":"alles","author_email":"alles.geheim@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=96&d=mm&r=g"},"date":"2023-01-12T16:43:04","cld_nonce":"b6d6726996","content":{"rendered":"<p>LibreOffice 7.4.4<\/p>\n"},"status":"1"},{"id":230670,"parent":230661,"author":0,"author_name":"Rush","author_email":"djmajorrush@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=96&d=mm&r=g"},"date":"2023-01-12T17:43:58","cld_nonce":"b6d6726996","content":{"rendered":"<p><a href=\"https:\/\/blog.documentfoundation.org\/blog\/2023\/01\/12\/libreoffice-7-4-4-community\/\" rel=\"nofollow ugc\">https:\/\/blog.documentfoundation.org\/blog\/2023\/01\/12\/libreoffice-7-4-4-community\/<\/a><\/p>\n"},"status":"1"},{"id":231897,"parent":230661,"author":5818,"author_name":"alles","author_email":"alles.geheim@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=96&d=mm&r=g"},"date":"2023-01-27T03:30:54","cld_nonce":"b6d6726996","content":{"rendered":"<p>LibreOffice 7.4.3<\/p>\n<p><a href=\"https:\/\/www.libreoffice.org\/download\/download-libreoffice\/\" rel=\"nofollow ugc\">https:\/\/www.libreoffice.org\/download\/download-libreoffice\/<\/a><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LibreOffice 7.4 (Final) mit vielen Verbesserungen erschienen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LibreOffice 7.4 (Final) mit vielen Verbesserungen erschienen\" \/>\n<meta property=\"og:description\" content=\"LibreOffice, die kostenlose Office-Version, hat ein neues Update auf LibreOffice 7.4 Community zum Download f\u00fcr Windows, Linux und macOS bereitgestellt. LibreOffice im Unternehmensumfeld wird dann sp\u00e4ter folgen. Mit dabei wieder neue Funktionen und viele Verbesserungen. Mal ein paar interessante Zahlen&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-18T11:00:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-18T13:53:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1120\" \/>\n\t<meta property=\"og:image:height\" content=\"724\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"LibreOffice 7.4 (Final) mit vielen Verbesserungen erschienen\",\"datePublished\":\"2022-08-18T11:00:54+00:00\",\"dateModified\":\"2022-08-18T13:53:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/\"},\"wordCount\":222,\"commentCount\":28,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/libreoffice-74.jpg\",\"keywords\":[\"LibreOffice 7.4\"],\"articleSection\":[\"Software &amp; Updates\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/\",\"name\":\"LibreOffice 7.4 (Final) mit vielen Verbesserungen erschienen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/libreoffice-74.jpg\",\"datePublished\":\"2022-08-18T11:00:54+00:00\",\"dateModified\":\"2022-08-18T13:53:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/libreoffice-74.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/libreoffice-74.jpg\",\"width\":1120,\"height\":724},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/08\\\/18\\\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LibreOffice 7.4 (Final) mit vielen Verbesserungen erschienen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LibreOffice 7.4 (Final) mit vielen Verbesserungen erschienen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/","og_locale":"de_DE","og_type":"article","og_title":"LibreOffice 7.4 (Final) mit vielen Verbesserungen erschienen","og_description":"LibreOffice, die kostenlose Office-Version, hat ein neues Update auf LibreOffice 7.4 Community zum Download f\u00fcr Windows, Linux und macOS bereitgestellt. LibreOffice im Unternehmensumfeld wird dann sp\u00e4ter folgen. Mit dabei wieder neue Funktionen und viele Verbesserungen. Mal ein paar interessante Zahlen&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2022-08-18T11:00:54+00:00","article_modified_time":"2022-08-18T13:53:40+00:00","og_image":[{"width":1120,"height":724,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"LibreOffice 7.4 (Final) mit vielen Verbesserungen erschienen","datePublished":"2022-08-18T11:00:54+00:00","dateModified":"2022-08-18T13:53:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/"},"wordCount":222,"commentCount":28,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74.jpg","keywords":["LibreOffice 7.4"],"articleSection":["Software &amp; Updates"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/","url":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/","name":"LibreOffice 7.4 (Final) mit vielen Verbesserungen erschienen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74.jpg","datePublished":"2022-08-18T11:00:54+00:00","dateModified":"2022-08-18T13:53:40+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74.jpg","width":1120,"height":724},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2022\/08\/18\/libreoffice-7-4-mit-vielen-verbesserungen-erschienen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"LibreOffice 7.4 (Final) mit vielen Verbesserungen erschienen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/08\/libreoffice-74.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/168552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=168552"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/168552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/168553"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=168552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=168552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=168552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}