{"id":167106,"date":"2022-06-30T08:37:12","date_gmt":"2022-06-30T06:37:12","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=167106"},"modified":"2022-06-30T08:37:12","modified_gmt":"2022-06-30T06:37:12","slug":"msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/","title":{"rendered":"MSEdgeRedirect 0.7.0.0 unterst\u00fctzt die Entfernung des Microsoft Edge, Umleitung der Bildersuche und mehr"},"content":{"rendered":"<p>Das kleine Tool MSEdgeRedirect kann die Links in den Widgets und andere, die sonst direkt den Microsoft Edge aufrufen auf euren Standardbrowser umgeleitet werden. Er ersetzt den EdgeDeflector, der nicht mehr weiterentwickelt wird.<\/p>\n<div id='gallery-1' class='gallery galleryid-167106 gallery-columns-2 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-001.jpg' rel=\"lightbox[167106]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"183\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-001-306x183.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-001-306x183.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-001-500x299.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-001-810x485.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-001.jpg 1059w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002.jpg' rel=\"lightbox[167106]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"188\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002-306x188.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002-306x188.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002-500x307.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002-810x497.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002.jpg 1042w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Mit der neuen Version 0.7 gibt es ein paar gute Neue Funktionen, die integriert wurden. So wurde jetzt auch die Umleitung der Bildersuche zum Standardbrowser hinzugef\u00fcgt. Als Beta hat Robert das &#8222;News De-Embedding&#8220; hinzugef\u00fcgt. Dieses verwendet das &#8222;I&#8217;m Feeling Lucky&#8220; (Auf gut Gl\u00fcck) von Google oder DuckDuckGo. Von AveYo hat Robert jetzt auch das Script zum Entfernen vom Microsoft Edge hinzugef\u00fcgt.<\/p>\n<p>Weitere Korrekturen:<\/p>\n<ul>\n<li>Apps (wieder) korrigiert<\/li>\n<li>Suchdaten aufger\u00e4umt<\/li>\n<li>\u00dcbrig gebliebene Dialogfelder f\u00fcr die Fehlersuche entfernt<\/li>\n<li>Korrektur der IEFO-Einstellungen, die bestehende IEFO-Auswahlen nicht erkennen<\/li>\n<\/ul>\n<h3>Info und Download:<\/h3>\n<ul>\n<li><a href=\"https:\/\/github.com\/rcmaehl\/MSEdgeRedirect\" rel=\"noopener\" target=\"_blank\">github.com\/MSEdgeRedirect<\/a><\/li>\n<li><a href=\"https:\/\/github.com\/rcmaehl\/MSEdgeRedirect\/releases\" rel=\"noopener\" target=\"_blank\">github.com\/MSEdgeRedirect\/releases<\/a><\/li>\n<\/ul>\n<p><em>Danke an Davito f\u00fcr den Hinweis.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das kleine Tool MSEdgeRedirect kann die Links in den Widgets und andere, die sonst direkt den Microsoft Edge aufrufen auf euren Standardbrowser umgeleitet werden. Er ersetzt den EdgeDeflector, der nicht mehr weiterentwickelt wird. Mit der neuen Version 0.7 gibt es&hellip; <\/p>\n","protected":false},"author":134,"featured_media":167107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166,2689,80310],"tags":[83276,83277,83278,83279,81465,8312],"class_list":["post-167106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-browser","category-windows-10","category-windows-11","tag-0-7","tag-edge-entfernen","tag-edge-loeschen","tag-links-umleiten","tag-msedgeredirect","tag-script"],"wp_featured_image":{"id":167107,"alt_text":"","description":"","media_type":"image","media_details":{"width":1042,"height":639,"file":"2022\/06\/msedgeredirect-07-edge-deinstallieren-002.jpg","filesize":338131,"sizes":{"medium":{"file":"msedgeredirect-07-edge-deinstallieren-002-500x307.jpg","width":500,"height":307,"mime-type":"image\/jpeg","filesize":25567,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002-500x307.jpg"},"large":{"file":"msedgeredirect-07-edge-deinstallieren-002-810x497.jpg","width":810,"height":497,"mime-type":"image\/jpeg","filesize":53495,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002-810x497.jpg"},"thumbnail":{"file":"msedgeredirect-07-edge-deinstallieren-002-306x188.jpg","width":306,"height":188,"mime-type":"image\/jpeg","filesize":11829,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002-306x188.jpg"},"blog-large":{"file":"msedgeredirect-07-edge-deinstallieren-002-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","filesize":30987,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002-642x300.jpg"},"blog-medium":{"file":"msedgeredirect-07-edge-deinstallieren-002-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","filesize":12371,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002-306x205.jpg"},"recent-thumb":{"file":"msedgeredirect-07-edge-deinstallieren-002-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","filesize":19203,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002-350x316.jpg"},"service-featured":{"file":"msedgeredirect-07-edge-deinstallieren-002-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","filesize":31223,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002-600x330.jpg"},"wp_rp_thumbnail":{"file":"msedgeredirect-07-edge-deinstallieren-002-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","filesize":1353,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":167106,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"af1c80fd5f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>MSEdgeRedirect 0.7.0.0 unterst\u00fctzt die Entfernung des Microsoft Edge, Umleitung der Bildersuche und mehr - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MSEdgeRedirect 0.7.0.0 unterst\u00fctzt die Entfernung des Microsoft Edge, Umleitung der Bildersuche und mehr\" \/>\n<meta property=\"og:description\" content=\"Das kleine Tool MSEdgeRedirect kann die Links in den Widgets und andere, die sonst direkt den Microsoft Edge aufrufen auf euren Standardbrowser umgeleitet werden. Er ersetzt den EdgeDeflector, der nicht mehr weiterentwickelt wird. Mit der neuen Version 0.7 gibt es&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-30T06:37:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1042\" \/>\n\t<meta property=\"og:image:height\" content=\"639\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"MSEdgeRedirect 0.7.0.0 unterst\u00fctzt die Entfernung des Microsoft Edge, Umleitung der Bildersuche und mehr\",\"datePublished\":\"2022-06-30T06:37:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/\"},\"wordCount\":157,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/msedgeredirect-07-edge-deinstallieren-002.jpg\",\"keywords\":[\"0.7\",\"Edge entfernen\",\"Edge l\u00f6schen\",\"Links umleiten\",\"MSEdgeRedirect\",\"script\"],\"articleSection\":[\"Browser\",\"Windows 10\",\"Windows 11\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/\",\"name\":\"MSEdgeRedirect 0.7.0.0 unterst\u00fctzt die Entfernung des Microsoft Edge, Umleitung der Bildersuche und mehr - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/msedgeredirect-07-edge-deinstallieren-002.jpg\",\"datePublished\":\"2022-06-30T06:37:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/msedgeredirect-07-edge-deinstallieren-002.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/msedgeredirect-07-edge-deinstallieren-002.jpg\",\"width\":1042,\"height\":639},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/30\\\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MSEdgeRedirect 0.7.0.0 unterst\u00fctzt die Entfernung des Microsoft Edge, Umleitung der Bildersuche und mehr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MSEdgeRedirect 0.7.0.0 unterst\u00fctzt die Entfernung des Microsoft Edge, Umleitung der Bildersuche und mehr - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/","og_locale":"de_DE","og_type":"article","og_title":"MSEdgeRedirect 0.7.0.0 unterst\u00fctzt die Entfernung des Microsoft Edge, Umleitung der Bildersuche und mehr","og_description":"Das kleine Tool MSEdgeRedirect kann die Links in den Widgets und andere, die sonst direkt den Microsoft Edge aufrufen auf euren Standardbrowser umgeleitet werden. Er ersetzt den EdgeDeflector, der nicht mehr weiterentwickelt wird. Mit der neuen Version 0.7 gibt es&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2022-06-30T06:37:12+00:00","og_image":[{"width":1042,"height":639,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"MSEdgeRedirect 0.7.0.0 unterst\u00fctzt die Entfernung des Microsoft Edge, Umleitung der Bildersuche und mehr","datePublished":"2022-06-30T06:37:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/"},"wordCount":157,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002.jpg","keywords":["0.7","Edge entfernen","Edge l\u00f6schen","Links umleiten","MSEdgeRedirect","script"],"articleSection":["Browser","Windows 10","Windows 11"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/","url":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/","name":"MSEdgeRedirect 0.7.0.0 unterst\u00fctzt die Entfernung des Microsoft Edge, Umleitung der Bildersuche und mehr - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002.jpg","datePublished":"2022-06-30T06:37:12+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002.jpg","width":1042,"height":639},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/30\/msedgeredirect-0-7-0-0-unterstuetzt-die-entfernung-des-microsoft-edge-umleitung-der-bildersuche-und-mehr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"MSEdgeRedirect 0.7.0.0 unterst\u00fctzt die Entfernung des Microsoft Edge, Umleitung der Bildersuche und mehr"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/msedgeredirect-07-edge-deinstallieren-002.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/167106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=167106"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/167106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/167107"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=167106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=167106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=167106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}