{"id":166911,"date":"2022-06-24T10:00:50","date_gmt":"2022-06-24T08:00:50","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=166911"},"modified":"2022-06-24T10:24:59","modified_gmt":"2022-06-24T08:24:59","slug":"microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/","title":{"rendered":"Microsoft Edge 103.0.1264.37 korrigiert 11 Sicherheitsl\u00fccken sowie neue Funktionen"},"content":{"rendered":"<p>Mal kurz nachgeholt: Microsoft hat gestern Abend den Microsoft Edge im Stable-Kanal auf die 103.0.1264.37 aktualisiert. Hier wurden insgesamt 11 Sicherheitsl\u00fccken korrigiert. Zwei davon sind nur f\u00fcr den Edge selber. Die <a href=\"https:\/\/msrc.microsoft.com\/update-guide\/vulnerability\/CVE-2022-33638\" rel=\"noopener\" target=\"_blank\">CVE-2022-33638<\/a> und <a href=\"https:\/\/msrc.microsoft.com\/update-guide\/vulnerability\/CVE-2022-30192\" rel=\"noopener\" target=\"_blank\">CVE-2022-30192<\/a><\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103.jpg\" rel=\"lightbox[166911]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103-500x338.jpg\" alt=\"\" width=\"500\" height=\"338\" class=\"aligncenter size-medium wp-image-166912\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103-500x338.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103-810x547.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103-303x205.jpg 303w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103.jpg 1101w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Alle Sicherheitsl\u00fccken in der \u00dcbersicht findet <a href=\"https:\/\/msrc.microsoft.com\/update-guide\" rel=\"noopener\" target=\"_blank\">ihr hier<\/a>. Durch den Wechsel auf die Version 103 wurden aber auch neue \/ aktualisierten Funktionen und Richtlinien hinzugef\u00fcgt. Die Release Notes ist aber wie \u00fcblich eher f\u00fcr die Firmen.<\/p>\n<ul>\n<li>Die <a href=\"https:\/\/www.deskmodder.de\/blog\/2022\/04\/27\/microsoft-edge-vorschau-funktionen-werden-jetzt-in-den-einstellungen-hinzugefuegt-aktuell-canary-und-dev\/\" rel=\"noopener\" target=\"_blank\">Vorschau-Funktionen<\/a> sind auch in der Stable angekommen. <em>(Danke an Joern)<\/em><\/li>\n<li>M\u00f6glichkeit zur Steuerung des automatischen Profilwechsels. Mit der GuidedSwitchEnabled-Richtlinie kann Microsoft Edge den Benutzer auffordern, zum entsprechenden Profil zu wechseln, wenn Microsoft Edge erkennt, dass es sich bei einem Link um einen pers\u00f6nlichen oder beruflichen Link handelt.<\/li>\n<li>Client-Zertifikat-Wechsler. Diese Funktion bietet Benutzern die M\u00f6glichkeit, das gespeicherte Zertifikat zu l\u00f6schen und die Zertifikatsauswahl erneut aufzurufen, wenn sie eine Webseite besuchen, die eine http-Zertifikatsauthentifizierung erfordert. Der Wechsel kann ohne manuelles Beenden von Microsoft Edge erfolgen.<\/li>\n<li>Zuverl\u00e4ssigerer Web-Schutz. Surfen Sie im Internet mit zuverl\u00e4ssigerem Schutz dank der neu geschriebenen Microsoft Defender SmartScreen-Bibliothek f\u00fcr Microsoft Edge unter Windows. Die Richtlinie NewSmartScreenLibraryEnabled erm\u00f6glicht es Unternehmenskunden, die alte Version der Bibliothek weiterzuverwenden, bis sie in Microsoft Edge Version 105 veraltet ist.<\/li>\n<li>Work Search Banner in der Adressleiste von Microsoft Edge. Dieses Banner hilft Ihnen, in Ihrem Arbeitsfluss zu bleiben, indem es Ihren Suchfokus auf reine Arbeitsergebnisse eingrenzt. W\u00e4hlen Sie das Banner zu Beginn Ihrer Suche aus, um die auf die Arbeit fokussierten Ergebnisse Ihrer Organisation anzuzeigen. W\u00e4hlen Sie das Banner an einem beliebigen Punkt Ihrer Suche aus, um zur Seite mit den Suchergebnissen f\u00fcr den Arbeitsplatz Ihrer Organisation zu gelangen. Verwenden Sie die Richtlinie AddressBarMicrosoftSearchInBingProviderEnabled, um diese Funktion ein- oder auszuschalten.<\/li>\n<li>Neue Richtlinien:\n<ul>\n<li>GuidedSwitchEnabled &#8211; Gesteuerter Wechsel Aktiviert<br \/>\nInternetExplorerZoomDisplay &#8211; Zoom in IE Mode Tabs mit DPI-Skala wie im Internet Explorer anzeigen<\/li>\n<li>LiveCaptionsAllowed &#8211; Live-Beschriftungen sind erlaubt<\/li>\n<li>OriginAgentClusterDefaultEnabled &#8211; Agent-Clustering mit Origin-Schl\u00fcssel standardm\u00e4\u00dfig aktiviert<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Auch die Extended Stable hat ein Update auf die Version 102.0.1245.50 erhalten. Hier wurden aber nur verschiedene Fehler und Leistungsprobleme korrigiert. Diese wird erst wieder mit dem Edge 104 einen &#8222;Sprung&#8220; machen.<\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/docs.microsoft.com\/en-us\/deployedge\/microsoft-edge-relnote-stable-channel#version-1030126437-june-23\" rel=\"noopener\" target=\"_blank\">docs.microsoft<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mal kurz nachgeholt: Microsoft hat gestern Abend den Microsoft Edge im Stable-Kanal auf die 103.0.1264.37 aktualisiert. Hier wurden insgesamt 11 Sicherheitsl\u00fccken korrigiert. Zwei davon sind nur f\u00fcr den Edge selber. Die CVE-2022-33638 und CVE-2022-30192 Alle Sicherheitsl\u00fccken in der \u00dcbersicht findet&hellip; <\/p>\n","protected":false},"author":134,"featured_media":166912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166],"tags":[83232],"class_list":["post-166911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-browser","tag-microsoft-edge-103"],"wp_featured_image":{"id":166912,"alt_text":"","description":"","media_type":"image","media_details":{"width":1101,"height":744,"file":"2022\/06\/microsoft-edge-103.jpg","filesize":73968,"sizes":{"medium":{"file":"microsoft-edge-103-500x338.jpg","width":500,"height":338,"mime-type":"image\/jpeg","filesize":8916,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103-500x338.jpg"},"large":{"file":"microsoft-edge-103-810x547.jpg","width":810,"height":547,"mime-type":"image\/jpeg","filesize":16810,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103-810x547.jpg"},"thumbnail":{"file":"microsoft-edge-103-303x205.jpg","width":303,"height":205,"mime-type":"image\/jpeg","filesize":4389,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103-303x205.jpg"},"blog-large":{"file":"microsoft-edge-103-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","filesize":12177,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103-642x300.jpg"},"blog-medium":{"file":"microsoft-edge-103-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","filesize":4510,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103-306x205.jpg"},"recent-thumb":{"file":"microsoft-edge-103-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","filesize":7682,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103-350x316.jpg"},"service-featured":{"file":"microsoft-edge-103-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","filesize":10665,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103-600x330.jpg"},"wp_rp_thumbnail":{"file":"microsoft-edge-103-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","filesize":711,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":166911,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103.jpg"},"commentcount":12,"wp_comments":[{"id":215227,"parent":0,"author":0,"author_name":"Andi","author_email":"andi-lau@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/34bb8232f4348a8d38ff737adfe7e3c84f628ed0e0884f073e4a67529af1e992?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/34bb8232f4348a8d38ff737adfe7e3c84f628ed0e0884f073e4a67529af1e992?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/34bb8232f4348a8d38ff737adfe7e3c84f628ed0e0884f073e4a67529af1e992?s=96&d=mm&r=g"},"date":"2022-06-24T10:10:04","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Und Spiele in Einstellungen und mehr&#8230; Brauch ich nicht.<\/p>\n"},"status":"1"},{"id":215228,"parent":0,"author":4291,"author_name":"Joern311","author_email":"joern.luehrs@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=96&d=mm&r=g"},"date":"2022-06-24T10:20:15","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Auch das hier scheint in der stable Version angekommen zu sein.<br \/>\n<a href=\"https:\/\/www.deskmodder.de\/blog\/2022\/04\/27\/microsoft-edge-vorschau-funktionen-werden-jetzt-in-den-einstellungen-hinzugefuegt-aktuell-canary-und-dev\/\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2022\/04\/27\/microsoft-edge-vorschau-funktionen-werden-jetzt-in-den-einstellungen-hinzugefuegt-aktuell-canary-und-dev\/<\/a><\/p>\n<p>Bei mir ist es in zwei Edge stable vorhanden.<\/p>\n"},"status":"1"},{"id":215229,"parent":215228,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2022-06-24T10:25:37","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Ja, hier auch. Habs oben mal hinzugef\u00fcgt. Danke dir.<\/p>\n"},"status":"1"},{"id":215230,"parent":215228,"author":2463,"author_name":"MikeNeoMike","author_email":"mike.ina@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/819a1c1f586e4a8c728367c0beac23b04a0158a90529518f5dbead2401833fdf?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/819a1c1f586e4a8c728367c0beac23b04a0158a90529518f5dbead2401833fdf?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/819a1c1f586e4a8c728367c0beac23b04a0158a90529518f5dbead2401833fdf?s=96&d=mm&r=g"},"date":"2022-06-24T10:26:35","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Hier bei mir in der stable Version leider noch nicht.<\/p>\n"},"status":"1"},{"id":215231,"parent":215230,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2022-06-24T10:30:45","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>In den Flags nachgeschaut?<\/p>\n"},"status":"1"},{"id":215232,"parent":215230,"author":4291,"author_name":"Joern311","author_email":"joern.luehrs@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=96&d=mm&r=g"},"date":"2022-06-24T10:32:10","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Das die Einstellungen erst in den Flags aktiviert werden m\u00fcssen ist klar, oder?<\/p>\n"},"status":"1"},{"id":215242,"parent":215231,"author":2463,"author_name":"MikeNeoMike","author_email":"mike.ina@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/819a1c1f586e4a8c728367c0beac23b04a0158a90529518f5dbead2401833fdf?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/819a1c1f586e4a8c728367c0beac23b04a0158a90529518f5dbead2401833fdf?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/819a1c1f586e4a8c728367c0beac23b04a0158a90529518f5dbead2401833fdf?s=96&d=mm&r=g"},"date":"2022-06-24T11:20:47","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Ok, alles klar, mein Fehler<\/p>\n"},"status":"1"},{"id":215243,"parent":215232,"author":2463,"author_name":"MikeNeoMike","author_email":"mike.ina@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/819a1c1f586e4a8c728367c0beac23b04a0158a90529518f5dbead2401833fdf?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/819a1c1f586e4a8c728367c0beac23b04a0158a90529518f5dbead2401833fdf?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/819a1c1f586e4a8c728367c0beac23b04a0158a90529518f5dbead2401833fdf?s=96&d=mm&r=g"},"date":"2022-06-24T11:27:11","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Alles klar, war mein Fehler, jetzt gehts auch hier.<\/p>\n"},"status":"1"},{"id":215337,"parent":0,"author":5818,"author_name":"alles","author_email":"alles.geheim@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=96&d=mm&r=g"},"date":"2022-06-25T21:34:39","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Die Zahl der m\u00f6glichen Direktlinks auf der Startseite des Browsers ist pl\u00f6tzlich von 15 auf 19 angewachsen. Keinen blassen Schimmer, ob das mit der v103 zu tun hat.<\/p>\n"},"status":"1"},{"id":215339,"parent":215337,"author":5818,"author_name":"alles","author_email":"alles.geheim@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=96&d=mm&r=g"},"date":"2022-06-25T21:41:11","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Oder hat es doch was mit dem aktuellen optionalen Update von Win 11 zu tun!?!<\/p>\n"},"status":"1"},{"id":215349,"parent":215339,"author":5818,"author_name":"alles","author_email":"alles.geheim@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=96&d=mm&r=g"},"date":"2022-06-26T08:45:15","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Ich verga\u00df, das h\u00e4ngt ja weder mit dem einen, noch mit dem anderen zusammen, weshalb es sich erledigt hat.<\/p>\n"},"status":"1"},{"id":215699,"parent":0,"author":5818,"author_name":"alles","author_email":"alles.geheim@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/322affe10c780c064378d9bfdf304bf675794c9e3dac000d0078bfe9dfa3d663?s=96&d=mm&r=g"},"date":"2022-06-30T22:19:29","cld_nonce":"af1c80fd5f","content":{"rendered":"<p>Microsoft Edge 103.0.1264.44 Stable<\/p>\n<p>x86<br \/>\n<a href=\"https:\/\/go.microsoft.com\/fwlink\/?LinkID=2093505\" rel=\"nofollow ugc\">https:\/\/go.microsoft.com\/fwlink\/?LinkID=2093505<\/a><\/p>\n<p>x64<br \/>\n<a href=\"https:\/\/go.microsoft.com\/fwlink\/?LinkID=2093437\" rel=\"nofollow ugc\">https:\/\/go.microsoft.com\/fwlink\/?LinkID=2093437<\/a><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"af1c80fd5f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Microsoft Edge 103.0.1264.37 korrigiert 11 Sicherheitsl\u00fccken sowie neue Funktionen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft Edge 103.0.1264.37 korrigiert 11 Sicherheitsl\u00fccken sowie neue Funktionen\" \/>\n<meta property=\"og:description\" content=\"Mal kurz nachgeholt: Microsoft hat gestern Abend den Microsoft Edge im Stable-Kanal auf die 103.0.1264.37 aktualisiert. Hier wurden insgesamt 11 Sicherheitsl\u00fccken korrigiert. Zwei davon sind nur f\u00fcr den Edge selber. Die CVE-2022-33638 und CVE-2022-30192 Alle Sicherheitsl\u00fccken in der \u00dcbersicht findet&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-24T08:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-24T08:24:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1101\" \/>\n\t<meta property=\"og:image:height\" content=\"744\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Microsoft Edge 103.0.1264.37 korrigiert 11 Sicherheitsl\u00fccken sowie neue Funktionen\",\"datePublished\":\"2022-06-24T08:00:50+00:00\",\"dateModified\":\"2022-06-24T08:24:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/\"},\"wordCount\":367,\"commentCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/microsoft-edge-103.jpg\",\"keywords\":[\"Microsoft Edge 103\"],\"articleSection\":[\"Browser\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/\",\"name\":\"Microsoft Edge 103.0.1264.37 korrigiert 11 Sicherheitsl\u00fccken sowie neue Funktionen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/microsoft-edge-103.jpg\",\"datePublished\":\"2022-06-24T08:00:50+00:00\",\"dateModified\":\"2022-06-24T08:24:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/microsoft-edge-103.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/microsoft-edge-103.jpg\",\"width\":1101,\"height\":744},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2022\\\/06\\\/24\\\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft Edge 103.0.1264.37 korrigiert 11 Sicherheitsl\u00fccken sowie neue Funktionen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Microsoft Edge 103.0.1264.37 korrigiert 11 Sicherheitsl\u00fccken sowie neue Funktionen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/","og_locale":"de_DE","og_type":"article","og_title":"Microsoft Edge 103.0.1264.37 korrigiert 11 Sicherheitsl\u00fccken sowie neue Funktionen","og_description":"Mal kurz nachgeholt: Microsoft hat gestern Abend den Microsoft Edge im Stable-Kanal auf die 103.0.1264.37 aktualisiert. Hier wurden insgesamt 11 Sicherheitsl\u00fccken korrigiert. Zwei davon sind nur f\u00fcr den Edge selber. Die CVE-2022-33638 und CVE-2022-30192 Alle Sicherheitsl\u00fccken in der \u00dcbersicht findet&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2022-06-24T08:00:50+00:00","article_modified_time":"2022-06-24T08:24:59+00:00","og_image":[{"width":1101,"height":744,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Microsoft Edge 103.0.1264.37 korrigiert 11 Sicherheitsl\u00fccken sowie neue Funktionen","datePublished":"2022-06-24T08:00:50+00:00","dateModified":"2022-06-24T08:24:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/"},"wordCount":367,"commentCount":12,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103.jpg","keywords":["Microsoft Edge 103"],"articleSection":["Browser"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/","url":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/","name":"Microsoft Edge 103.0.1264.37 korrigiert 11 Sicherheitsl\u00fccken sowie neue Funktionen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103.jpg","datePublished":"2022-06-24T08:00:50+00:00","dateModified":"2022-06-24T08:24:59+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103.jpg","width":1101,"height":744},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2022\/06\/24\/microsoft-edge-103-0-1264-37-korrigiert-11-sicherheitsluecken-sowie-neue-funktionen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Microsoft Edge 103.0.1264.37 korrigiert 11 Sicherheitsl\u00fccken sowie neue Funktionen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2022\/06\/microsoft-edge-103.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/166911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=166911"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/166911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/166912"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=166911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=166911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=166911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}