{"id":150249,"date":"2021-03-04T19:10:11","date_gmt":"2021-03-04T18:10:11","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=150249"},"modified":"2021-03-04T19:10:11","modified_gmt":"2021-03-04T18:10:11","slug":"logitech-folio-touch-fuer-ipad-pro-ausprobiert","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/","title":{"rendered":"Logitech Folio Touch f\u00fcr iPad Pro ausprobiert"},"content":{"rendered":"<p>Vor ziemlich genau einem Jahr hat Apple seinen iPads einen umfassenden Maus-Support spendiert. Die Kalifornier bieten seitdem f\u00fcr das iPad Pro auch selbst ein entsprechendes Tastatur-Cover mit Trackpad f\u00fcr deutlich mehr als 300 Euro an (<a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/03\/20\/apple-ipad-pro-2020-vorgestellt\/\" target=\"_blank\" rel=\"noopener\">wir berichteten<\/a>). Zahlreiche andere Zubeh\u00f6rhersteller haben aber inzwischen eigene Produkte am Start &#8211; so beispielsweise auch Logitech mit seinem <i>Folio Touch Keyboard Case<\/i>. Das geh\u00f6rt ebenfalls eher zu den teureren Modellen und ist im Falle der 11\u201c-Variante <a href=\"https:\/\/www.amazon.de\/Logitech-Tastatur-Trackpad-Connector-Modell\/dp\/B07W7JYP94\/ref=sr_1_1?__mk_de_DE=\u00c5M\u00c5\u017d\u00d5\u00d1&amp;dchild=1&amp;keywords=B07W7JYP94&amp;qid=1614714555&amp;sr=8-1&amp;tag=deskmodderde-21\" target=\"_blank\" rel=\"noopener\">bei Amazon<\/a> zurzeit f\u00fcr rund 130 Euro zu haben.<\/p>\n<div id='gallery-1' class='gallery galleryid-150249 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638.jpg' rel=\"lightbox[150249]\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-480x360.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-480x360.jpg 480w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-777x583.jpg 777w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-273x205.jpg 273w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-1536x1152.jpg 1536w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9873-scaled.jpg' rel=\"lightbox[150249]\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9873-480x360.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9873-480x360.jpg 480w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9873-777x583.jpg 777w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9873-273x205.jpg 273w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9873-1536x1152.jpg 1536w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9873-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Das iPad wird hier von einem Silikon-Bumper eingefasst und sitzt dann bombenfest im Case.\u00a0Auf der R\u00fcckseite befindet sich ein Kickstand, der sich stufenlos einstellen l\u00e4sst und auch eine sehr flache Aufstellung erlaubt. Sieht dann optisch einem Surface (oder auch jedem anderen Notebook) sehr \u00e4hnlich.<\/p>\n<p>Die Oberfl\u00e4che ist aus einer Art Stoff, aber relativ glatt und nicht sonderlich offenporig. Dadurch sollte man das Case im Falle einer Verschmutzung relativ gut reinigen k\u00f6nnen.<\/p>\n<p>Nachdem man das iPad das erste Mal ins Case gesteckt hat, zeigt iPadOS sofort einen Hinweis an, dass neues Zubeh\u00f6r gefunden wurde und bietet die Installation der LogitechControl App an, mit der man nach Updates f\u00fcr das Case suchen kann.<\/p>\n<p>Auf der mit einer Hintergrundbeleuchtung ausgestatteten und fest verbundenen Tastatur l\u00e4sst es sich wirklich gut tippen und auch Umlaute sind auf dem deutschen Layout zu finden. Die Tasten \u00dc und \u00c4 fallen allerdings etwas kleiner aus. Das Trackpad hat eine angenehme Oberfl\u00e4che, ist sehr pr\u00e4zise und macht in Verbindung mit der Gestensteuerung richtig Spa\u00df &#8211; einziger Kritikpunkt hier: Es l\u00e4sst sich nur in der unteren H\u00e4lfte Klicken. Wer hier die Trackpads der MacBooks gewohnt ist, wird sicher zwischendurch mal fluchen.<\/p>\n<p>An Aussparungen f\u00fcr die Kameras, Lautsprecher, USB-Anschluss, Mikrofone und den Apple Pencil ist beim Folio Case gedacht. Die Stromversorgung und Kopplung erfolgt \u00fcber den Smart-Connector auf der R\u00fcckseite des iPads, sodass man sich dar\u00fcber auch keine Gedanken machen muss.<\/p>\n<p>Wird die Tastatur nach hinten umgeklappt, werden Tastatur und Trackpad automatisch deaktiviert, sodass es nicht zu Fehleingaben kommen kann. Als klassisches Tablet m\u00f6chte man das iPad dann aber eigentlich nicht mehr nutzen: Das Gesamtpaket ist dann wirklich dick, schwer und klobig.\u00a0Gleiches gilt \u00fcbrigens auch f\u00fcr den geschlossenen Zustand &#8211; man b\u00fc\u00dft doch einiges an Portabilit\u00e4t ein. W\u00e4hrend das iPad ohne alles auf meiner K\u00fcchenwaage 473 Gramm wiegt, kommt man mit dem Case auf 1.117 Gramm &#8211; also mehr als doppelt so viel.<\/p>\n<p>Mein kurzes Fazit nach mehreren Wochen Nutzung f\u00e4llt daher wie folgt aus: Tolles und sehr robust wirkendes Keyboard-Case mit Trackpad, aber f\u00fcr meinen Geschmack zu schwer. Klare Kaufempfehlung f\u00fcr Leute, die viel schreiben wollen und eher keine Kaufempfehlung f\u00fcr diejenigen, die das iPad \u00f6fter als reines\/klassisches Tablet nutzen wollen oder gerne mal hin- und herswitchen. Letzteres ist n\u00e4mlich etwas fummelig.<\/p>\n<p><i>Hinweis: Das Logitech Folio Touch wurde von Logitech zu Testzwecken bereitgestellt.<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor ziemlich genau einem Jahr hat Apple seinen iPads einen umfassenden Maus-Support spendiert. Die Kalifornier bieten seitdem f\u00fcr das iPad Pro auch selbst ein entsprechendes Tastatur-Cover mit Trackpad f\u00fcr deutlich mehr als 300 Euro an (wir berichteten). Zahlreiche andere Zubeh\u00f6rhersteller&hellip; <\/p>\n","protected":false},"author":1525,"featured_media":150697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286,232,4016],"tags":[4703,79291,1744],"class_list":["post-150249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","category-ios","category-testberichte","tag-ipad-pro","tag-logitech-folio-touch","tag-test"],"wp_featured_image":{"id":150697,"alt_text":"","description":"","media_type":"image","media_details":{"width":2560,"height":1920,"file":"2021\/03\/img-9872-scaled-e1614880302638.jpg","sizes":{"medium":{"file":"img-9872-scaled-e1614880302638-480x360.jpg","width":480,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-480x360.jpg"},"large":{"file":"img-9872-scaled-e1614880302638-777x583.jpg","width":777,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-777x583.jpg"},"thumbnail":{"file":"img-9872-scaled-e1614880302638-273x205.jpg","width":273,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-273x205.jpg"},"1536x1536":{"file":"img-9872-scaled-e1614880302638-1536x1152.jpg","width":1536,"height":1152,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-1536x1152.jpg"},"2048x2048":{"file":"img-9872-scaled-e1614880302638-2048x1536.jpg","width":2048,"height":1536,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-2048x1536.jpg"},"blog-large":{"file":"img-9872-scaled-e1614880302638-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-642x300.jpg"},"blog-medium":{"file":"img-9872-scaled-e1614880302638-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-306x205.jpg"},"recent-thumb":{"file":"img-9872-scaled-e1614880302638-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-350x316.jpg"},"service-featured":{"file":"img-9872-scaled-e1614880302638-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-600x330.jpg"},"wp_rp_thumbnail":{"file":"img-9872-scaled-e1614880302638-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638-50x50.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"iPhone SE (1st generation)","caption":"","created_timestamp":"1614882766","copyright":"","focal_length":"4.15","iso":"250","shutter_speed":"0.058823529411765","title":"","orientation":"0","keywords":[]},"original_image":"img-9872.jpg"},"post":150249,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":1525,"name":"W8U","description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Logitech Folio Touch f\u00fcr iPad Pro ausprobiert - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logitech Folio Touch f\u00fcr iPad Pro ausprobiert\" \/>\n<meta property=\"og:description\" content=\"Vor ziemlich genau einem Jahr hat Apple seinen iPads einen umfassenden Maus-Support spendiert. Die Kalifornier bieten seitdem f\u00fcr das iPad Pro auch selbst ein entsprechendes Tastatur-Cover mit Trackpad f\u00fcr deutlich mehr als 300 Euro an (wir berichteten). Zahlreiche andere Zubeh\u00f6rhersteller&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-04T18:10:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"W8U\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/\"},\"author\":{\"name\":\"W8U\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\"},\"headline\":\"Logitech Folio Touch f\u00fcr iPad Pro ausprobiert\",\"datePublished\":\"2021-03-04T18:10:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/\"},\"wordCount\":506,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/img-9872-scaled-e1614880302638.jpg\",\"keywords\":[\"iPad Pro\",\"Logitech Folio Touch\",\"Test\"],\"articleSection\":[\"Hardware\",\"iOS\",\"Testberichte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/\",\"name\":\"Logitech Folio Touch f\u00fcr iPad Pro ausprobiert - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/img-9872-scaled-e1614880302638.jpg\",\"datePublished\":\"2021-03-04T18:10:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/img-9872-scaled-e1614880302638.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/img-9872-scaled-e1614880302638.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/03\\\/04\\\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Logitech Folio Touch f\u00fcr iPad Pro ausprobiert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\",\"name\":\"W8U\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"caption\":\"W8U\"},\"description\":\"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/w8u\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Logitech Folio Touch f\u00fcr iPad Pro ausprobiert - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/","og_locale":"de_DE","og_type":"article","og_title":"Logitech Folio Touch f\u00fcr iPad Pro ausprobiert","og_description":"Vor ziemlich genau einem Jahr hat Apple seinen iPads einen umfassenden Maus-Support spendiert. Die Kalifornier bieten seitdem f\u00fcr das iPad Pro auch selbst ein entsprechendes Tastatur-Cover mit Trackpad f\u00fcr deutlich mehr als 300 Euro an (wir berichteten). Zahlreiche andere Zubeh\u00f6rhersteller&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2021-03-04T18:10:11+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638.jpg","type":"image\/jpeg"}],"author":"W8U","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/"},"author":{"name":"W8U","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469"},"headline":"Logitech Folio Touch f\u00fcr iPad Pro ausprobiert","datePublished":"2021-03-04T18:10:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/"},"wordCount":506,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638.jpg","keywords":["iPad Pro","Logitech Folio Touch","Test"],"articleSection":["Hardware","iOS","Testberichte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/","url":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/","name":"Logitech Folio Touch f\u00fcr iPad Pro ausprobiert - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638.jpg","datePublished":"2021-03-04T18:10:11+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2021\/03\/04\/logitech-folio-touch-fuer-ipad-pro-ausprobiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Logitech Folio Touch f\u00fcr iPad Pro ausprobiert"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469","name":"W8U","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","caption":"W8U"},"description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","url":"https:\/\/www.deskmodder.de\/blog\/author\/w8u\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2021\/03\/img-9872-scaled-e1614880302638.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/150249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/1525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=150249"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/150249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/150697"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=150249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=150249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=150249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}