{"id":149796,"date":"2021-02-09T19:15:44","date_gmt":"2021-02-09T18:15:44","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=149796"},"modified":"2021-02-11T19:16:52","modified_gmt":"2021-02-11T18:16:52","slug":"kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/","title":{"rendered":"KB4601315 und KB4601395 als SSU [Manueller Download] Windows 10 1909"},"content":{"rendered":"<p><strong>[Update 11.02.21.]:<\/strong> Microsoft hat ein Out-of-band Update KB5001028 bereitgestellt, der ein WLAN Problem mit diesem Update hier beheben wird. Mehr dazu und der Download hier <a href=\"https:\/\/www.deskmodder.de\/blog\/2021\/02\/11\/kb5001028-windows-10-1909-out-of-band-update-manueller-download\/\" rel=\"noopener\" target=\"_blank\">in diesem Beitrag<\/a><\/p>\n<p>Microsoft hat f\u00fcr die Windows 10 1909 ein neues kumulatives Sicherheitsupdate zum Patchday Februar bereitgestellt. Die KB 4601315 erh\u00f6ht die Versionsnummer auf die Windows 10 1909 18363.1377.<\/p>\n<p>Die Windows 10 1903 bekommt seit Dezember 2020 keine Updates mehr. Wer damit noch unterwegs ist, sollte mit dem kleinen Update <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/10\/09\/kb4517245-feature-update-auf-die-windows-10-version-1909\/\" rel=\"noopener\" target=\"_blank\">KB4517245<\/a> wenigstens auf die Windows 10 1909 wechseln. Die Windows 10 1909 selber wurde jetzt <a href=\"https:\/\/www.deskmodder.de\/blog\/2021\/02\/04\/windows-10-2004-und-1909-wird-nun-ueber-windows-update-direkt-auf-die-aktuelle-version-aktualisiert\/\" rel=\"noopener\" target=\"_blank\">f\u00fcr ein automatisches Update<\/a> auf die Windows 10 2004 freigegeben.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/windows-update-logo-2.jpg\" rel=\"lightbox[149796]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/windows-update-logo-2-500x360.jpg\" alt=\"\" width=\"500\" height=\"360\" class=\"aligncenter size-medium wp-image-143551\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/windows-update-logo-2-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/windows-update-logo-2-810x583.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/windows-update-logo-2-285x205.jpg 285w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/windows-update-logo-2-1536x1106.jpg 1536w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/windows-update-logo-2.jpg 1964w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<h3>Bekannte Probleme durch die KB4601315<\/h3>\n<ul>\n<li>System- und Benutzerzertifikate k\u00f6nnen verloren gehen, wenn ein Ger\u00e4t von Windows 10, Version 1809 oder sp\u00e4ter auf eine sp\u00e4tere Version von Windows 10 aktualisiert wird. Ger\u00e4te sind nur betroffen, wenn sie bereits ein aktuelles kumulatives Update (LCU) installiert haben, das am 16. September 2020 oder sp\u00e4ter ver\u00f6ffentlicht wurde, und dann ein Update auf eine sp\u00e4tere Version von Windows 10 von einem Medium oder einer Installationsquelle durchf\u00fchren, die kein LCU vom 13. Oktober 2020 oder sp\u00e4ter integriert hat. Dies geschieht haupts\u00e4chlich, wenn verwaltete Ger\u00e4te mit veralteten Bundles oder Medien \u00fcber ein Update-Verwaltungstool wie Windows Server Update Services (WSUS) oder Microsoft Endpoint Configuration Manager aktualisiert werden. Dies kann auch passieren, wenn veraltete physische Medien oder ISO-Images verwendet werden, die nicht die neuesten Updates integriert haben. Hinweis: Ger\u00e4te, die Windows Update for Business verwenden oder eine direkte Verbindung zu Windows Update herstellen, sind nicht betroffen. Jedes Ger\u00e4t, das eine Verbindung zu Windows Update herstellt, sollte immer die neuesten Versionen des Funktionsupdates erhalten, einschlie\u00dflich der neuesten LCU, ohne zus\u00e4tzliche Schritte.\n<ul>\n<li>Workaround: Wenn dieses Problem auf Ihrem Ger\u00e4t bereits aufgetreten ist, k\u00f6nnen Sie es innerhalb des Deinstallationsfensters entsch\u00e4rfen, indem Sie zu Ihrer vorherigen Windows-Version zur\u00fcckkehren und die Anweisungen hier befolgen. Das Deinstallationsfenster kann 10 oder 30 Tage betragen, abh\u00e4ngig von der Konfiguration Ihrer Umgebung und der Version, auf die Sie aktualisieren. Sie m\u00fcssen dann auf die neuere Version von Windows 10 aktualisieren, nachdem das Problem in Ihrer Umgebung behoben wurde. Hinweis Innerhalb des Deinstallationsfensters k\u00f6nnen Sie mit dem DISM-Befehl \/Set-OSUninstallWindow die Anzahl der Tage erh\u00f6hen, die Ihnen zur Verf\u00fcgung stehen, um zu Ihrer vorherigen Version von Windows 10 zur\u00fcckzukehren. Sie m\u00fcssen diese \u00c4nderung vornehmen, bevor das Standard-Deinstallationsfenster abgelaufen ist. Weitere Informationen finden Sie unter DISM-Befehlszeilenoptionen f\u00fcr die Deinstallation des Betriebssystems. Wir arbeiten an einer L\u00f6sung und werden in den kommenden Wochen aktualisierte Bundles und aufgefrischte Medien bereitstellen.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3>Behobene Probleme durch die KB4601315<\/h3>\n<ul>\n<li>Behebt eine m\u00f6gliche &#8222;elevation of privilege&#8220;-Schwachstelle in der Komponente win32k.<\/li>\n<li>Sicherheitsupdates f\u00fcr Windows App Platform und Frameworks, Windows Apps, Windows Input und Composition, Windows Cloud Infrastructure, Windows Management, Windows Authentication, Windows Fundamentals, Windows Cryptography, Windows Virtualization, Windows Core Networking und Windows Hybrid Cloud Networking.<\/li>\n<\/ul>\n<h3>Manueller Download der KB4601395 als SSU<\/h3>\n<ul>\n<li>Wer manuell installiert, muss das SSU als erstes installieren. Danach dann das Februar-Update.<\/li>\n<li><a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/secu\/2021\/02\/windows10.0-kb4601395-x64_4e16fc7e7f52ea51753a0775adfe1f894bd89707.msu\" rel=\"noopener\" target=\"_blank\">windows10.0-kb4601395-x64.msu<\/a><\/li>\n<li><a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/secu\/2021\/02\/windows10.0-kb4601395-x86_4322bcfc07b93b88bbd918e0fe02ed9078a69566.msu\" rel=\"noopener\" target=\"_blank\">windows10.0-kb4601395-x86.msu<\/a><\/li>\n<li>ARM: <a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/secu\/2021\/02\/windows10.0-kb4601395-arm64_dd5436b08fd05af9ca861d0d80b397e8ac7719ee.msu\" rel=\"noopener\" target=\"_blank\">windows10.0-kb4601395-arm64.msu<\/a><\/li>\n<\/ul>\n<h3>Manueller Download der KB4601315<\/h3>\n<ul>\n<li><a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/secu\/2021\/02\/windows10.0-kb4601315-x64_1275ac584e5469b35f6671bc4891ebefacd0212e.msu\" rel=\"noopener\" target=\"_blank\">windows10.0-kb4601315-x64.msu<\/a><\/li>\n<li><a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/secu\/2021\/02\/windows10.0-kb4601315-x86_4ac843d1192c5b95dfe1b2e2342b5fc6cdbec14b.msu\" rel=\"noopener\" target=\"_blank\">windows10.0-kb4601315-x86.msu<\/a><\/li>\n<li>ARM: <a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/secu\/2021\/02\/windows10.0-kb4601315-arm64_0b6fc97a972352c6d5c0f559c7c79162f1fe2224.cab\" rel=\"noopener\" target=\"_blank\">windows10.0-kb4601315-arm64.msu<\/a><\/li>\n<\/ul>\n<h3>Windows 10 Tutorials und Hilfe<\/h3>\n<p>In unserem <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 Wiki<\/a> findet ihr sehr viele hilfreiche Tipps und Tricks. Falls ihr Fragen habt, dann stellt diese ganz einfach bei uns im <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewforum.php?f=326\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Forum<\/strong><\/a>.<\/p>\n<ul>\n<li><strong>Installationsmedien:<\/strong> Aktuelle Installationsdateien findet ihr hier immer in der rechten Sidebar. <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/12\/11\/windows-10-19041-iso-esd-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004 ISO (19041)<\/a>, oder <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/06\/17\/windows-10-20h2-19042-iso-esd-inkl-updates-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">20H2 (2009) ISO (19042)<\/a> <\/li>\n<li><strong>Installation:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_clean_neu_installieren\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 Clean installieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_2004_neu_installieren_Anleitung_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 2004 neu installieren<\/a><\/li>\n<li><strong>Aktuelle Probleme mit der:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/04\/11\/windows-10-2004-bekannte-und-behobene-probleme\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004 \/ 20H2<\/a>\n    <\/li>\n<li><strong>Reparaturen:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Inplace_Upgrade_Windows_10_schnell_reparieren\" rel=\"noopener noreferrer\" target=\"_blank\">Inplace Upgrade Reparatur<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_reparieren_wiederherstellen_mit_DISM_Inplace_Upgrade_und_vielen_weiteren_Varianten\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 reparieren  \u00fcber DISM, sfc und weiteres<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_Update_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Windows Update reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Startmen%C3%BC_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Startmen\u00fc reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Apps_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Apps reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Store_reparieren\" rel=\"noopener noreferrer\" target=\"_blank\">Store reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Netzwerkverbindung_-adapter_reparieren_zur%C3%BCcksetzen_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Netzwerk reparieren<\/a><\/li>\n<li><strong>Anmeldung:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_automatisch_anmelden_ohne_Passworteingabe\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 automatische Anmeldung<\/a><\/li>\n<li><strong>Entfernen, Deinstallieren<\/strong>:  <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Apps_entfernen_deinstallieren\" rel=\"noopener noreferrer\" target=\"_blank\">Apps deinstallieren<\/a><\/li>\n<li><strong>Datei Explorer:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Dieser_PC_Ordner_entfernen_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Ordner unter Dieser PC entfernen<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Datei_Explorer_Windows_10_Netzwerk_Heimnetzgruppe_OneDrive_entfernen\" rel=\"noopener noreferrer\" target=\"_blank\">Netzwerk, OneDrive u.a. im Explorer entfernen<\/a><\/li>\n<li><strong>Richtige Nutzung:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Das_Windows_10_Startmen%C3%BC_richtig_einrichten_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Startmen\u00fc richtig nutzen<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Die_Suche_in_Windows_10_richtig_nutzen\" rel=\"noopener noreferrer\" target=\"_blank\">Suche richtig nutzen<\/a>,<\/li>\n<li><strong>Wichtig:<\/strong> In jedem Tutorial steht, f\u00fcr welche Version es geeignet ist.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>[Update 11.02.21.]: Microsoft hat ein Out-of-band Update KB5001028 bereitgestellt, der ein WLAN Problem mit diesem Update hier beheben wird. Mehr dazu und der Download hier in diesem Beitrag Microsoft hat f\u00fcr die Windows 10 1909 ein neues kumulatives Sicherheitsupdate zum&hellip; <\/p>\n","protected":false},"author":134,"featured_media":146591,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[60129,16002,7811,79065,79064,79063,4597,1457,9751],"class_list":["post-149796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","tag-60129","tag-16002","tag-februar","tag-kb-4601315","tag-kb4601315","tag-kb4601395","tag-patchday","tag-sicherheitsupdate","tag-windows-10"],"wp_featured_image":{"id":146591,"alt_text":"","description":"","media_type":"image","media_details":{"width":500,"height":360,"file":"2020\/11\/windows-update-logo-2-500x360-1.jpg","sizes":{"medium":{"file":"windows-update-logo-2-500x360-1-500x360.jpg","width":500,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1-500x360.jpg"},"thumbnail":{"file":"windows-update-logo-2-500x360-1-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1-50x50.jpg"},"blog-large":{"file":"windows-update-logo-2-500x360-1-500x300.jpg","width":500,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1-500x300.jpg"},"blog-medium":{"file":"windows-update-logo-2-500x360-1-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1-306x205.jpg"},"recent-thumb":{"file":"windows-update-logo-2-500x360-1-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1-350x316.jpg"},"service-featured":{"file":"windows-update-logo-2-500x360-1-500x330.jpg","width":500,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1-500x330.jpg"},"wp_rp_thumbnail":{"file":"windows-update-logo-2-500x360-1-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":146589,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>KB4601315 und KB4601395 als SSU [Manueller Download] Windows 10 1909 - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KB4601315 und KB4601395 als SSU [Manueller Download] Windows 10 1909\" \/>\n<meta property=\"og:description\" content=\"[Update 11.02.21.]: Microsoft hat ein Out-of-band Update KB5001028 bereitgestellt, der ein WLAN Problem mit diesem Update hier beheben wird. Mehr dazu und der Download hier in diesem Beitrag Microsoft hat f\u00fcr die Windows 10 1909 ein neues kumulatives Sicherheitsupdate zum&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-09T18:15:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-11T18:16:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"KB4601315 und KB4601395 als SSU [Manueller Download] Windows 10 1909\",\"datePublished\":\"2021-02-09T18:15:44+00:00\",\"dateModified\":\"2021-02-11T18:16:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/\"},\"wordCount\":644,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/windows-update-logo-2-500x360-1.jpg\",\"keywords\":[\"1909\",\"2021\",\"Februar\",\"KB 4601315\",\"KB4601315\",\"KB4601395\",\"Patchday\",\"Sicherheitsupdate\",\"Windows 10\"],\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/\",\"name\":\"KB4601315 und KB4601395 als SSU [Manueller Download] Windows 10 1909 - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/windows-update-logo-2-500x360-1.jpg\",\"datePublished\":\"2021-02-09T18:15:44+00:00\",\"dateModified\":\"2021-02-11T18:16:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/windows-update-logo-2-500x360-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/windows-update-logo-2-500x360-1.jpg\",\"width\":500,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2021\\\/02\\\/09\\\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KB4601315 und KB4601395 als SSU [Manueller Download] Windows 10 1909\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"KB4601315 und KB4601395 als SSU [Manueller Download] Windows 10 1909 - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/","og_locale":"de_DE","og_type":"article","og_title":"KB4601315 und KB4601395 als SSU [Manueller Download] Windows 10 1909","og_description":"[Update 11.02.21.]: Microsoft hat ein Out-of-band Update KB5001028 bereitgestellt, der ein WLAN Problem mit diesem Update hier beheben wird. Mehr dazu und der Download hier in diesem Beitrag Microsoft hat f\u00fcr die Windows 10 1909 ein neues kumulatives Sicherheitsupdate zum&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2021-02-09T18:15:44+00:00","article_modified_time":"2021-02-11T18:16:52+00:00","og_image":[{"width":500,"height":360,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"KB4601315 und KB4601395 als SSU [Manueller Download] Windows 10 1909","datePublished":"2021-02-09T18:15:44+00:00","dateModified":"2021-02-11T18:16:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/"},"wordCount":644,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1.jpg","keywords":["1909","2021","Februar","KB 4601315","KB4601315","KB4601395","Patchday","Sicherheitsupdate","Windows 10"],"articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/","url":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/","name":"KB4601315 und KB4601395 als SSU [Manueller Download] Windows 10 1909 - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1.jpg","datePublished":"2021-02-09T18:15:44+00:00","dateModified":"2021-02-11T18:16:52+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1.jpg","width":500,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2021\/02\/09\/kb4601315-und-kb4601395-als-ssu-manueller-download-windows-10-1909\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"KB4601315 und KB4601395 als SSU [Manueller Download] Windows 10 1909"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/11\/windows-update-logo-2-500x360-1.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/149796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=149796"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/149796\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/146591"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=149796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=149796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=149796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}