{"id":144981,"date":"2020-09-28T16:11:46","date_gmt":"2020-09-28T14:11:46","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=144981"},"modified":"2020-09-28T16:12:23","modified_gmt":"2020-09-28T14:12:23","slug":"in-eigener-sache-blog-login-funktioniert-wieder","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/","title":{"rendered":"In eigener Sache: Blog-Login funktioniert wieder"},"content":{"rendered":"<p>Ein kurzer Hinweis: Nach dem Foren-Update funktionierte der Login im Blog nicht mehr, da phpBB etwas ge\u00e4ndert hat. Entschuldigt bitte den Fehler. Gumfuzi hat es nun korrigiert, sodass der Login wieder wie gew\u00f6hnlich klappt. Bitte so vorgehen:<\/p>\n<ul>\n<li>Im Forum abmelden und wieder anmelden<\/li>\n<li>Danach im Blog die Anmeldung (Login) vornehmen<\/li>\n<li>Jetzt sollte alles wieder so klappen, wie bisher.<\/li>\n<li>Falls nicht, dann bitte einmal die Cookies l\u00f6schen.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ein kurzer Hinweis: Nach dem Foren-Update funktionierte der Login im Blog nicht mehr, da phpBB etwas ge\u00e4ndert hat. Entschuldigt bitte den Fehler. Gumfuzi hat es nun korrigiert, sodass der Login wieder wie gew\u00f6hnlich klappt. Bitte so vorgehen: Im Forum abmelden&hellip; <\/p>\n","protected":false},"author":134,"featured_media":41749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-144981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"wp_featured_image":{"id":41749,"alt_text":"","description":"","media_type":"image","media_details":{"width":820,"height":590,"file":"2015\/04\/deskmodder_a.png","sizes":{"thumbnail":{"file":"deskmodder_a-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a-150x150.png"},"medium":{"file":"deskmodder_a-150x108.png","width":150,"height":108,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a-150x108.png"},"large":{"file":"deskmodder_a-500x360.png","width":500,"height":360,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a-500x360.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":41708,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png"},"commentcount":13,"wp_comments":[{"id":147162,"parent":0,"author":0,"author_name":"Ingridl","author_email":"ingrid@attnetwork.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=96&d=mm&r=g"},"date":"2020-09-28T16:49:04","cld_nonce":"82f011626f","content":{"rendered":"<p>\ud83d\udc4d\ud83d\udc4d\ud83d\udc4d&#8230;<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":147163,"parent":0,"author":6279,"author_name":"Schnyff","author_email":"douz@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4795eaa13e57717a03242a86aaa411a12320be0e47a7b7231a9bc87370577868?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4795eaa13e57717a03242a86aaa411a12320be0e47a7b7231a9bc87370577868?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4795eaa13e57717a03242a86aaa411a12320be0e47a7b7231a9bc87370577868?s=96&d=mm&r=g"},"date":"2020-09-28T16:52:07","cld_nonce":"82f011626f","content":{"rendered":"<p>So wie beschrieben funktioniert wieder. Danke. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":147165,"parent":0,"author":0,"author_name":"Kristof Steichert","author_email":"kr.st@list.ru","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/89025cc708238f6d79db3ecb91d18af92592c5912906566fec52d238a4b7a3e7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/89025cc708238f6d79db3ecb91d18af92592c5912906566fec52d238a4b7a3e7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/89025cc708238f6d79db3ecb91d18af92592c5912906566fec52d238a4b7a3e7?s=96&d=mm&r=g"},"date":"2020-09-28T17:02:09","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich habe Javascript f\u00fcr deskmodder.de und wp.com erlaubt, kann aber nicht wie fr\u00fcher die &#8222;Daumen&#8220;-Funktion benutzen. Beim Mouse-Over steht &#8222;javascript:void(0)&#8220;. Muss ich jetzt tats\u00e4chlich Google daf\u00fcr aktivieren? Wenn ja, gibts halt keine Bewertung mehr f\u00fcr mich. Posten von Beitr\u00e4gen geht ja zum Gl\u00fcck trotzdem weiterhin.<\/p>\n"},"status":"1"},{"id":147166,"parent":147165,"author":2038,"author_name":"GwenDragon","author_email":"info@gwendragon.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=96&d=mm&r=g"},"date":"2020-09-28T17:10:16","cld_nonce":"82f011626f","content":{"rendered":"<p>Beim mir klappt das.<br \/>\nBin allerdings hier angemeldet.<\/p>\n"},"status":"1"},{"id":147168,"parent":147165,"author":1525,"author_name":"W8U","author_email":"windows-8-user@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"},"date":"2020-09-28T17:12:47","cld_nonce":"82f011626f","content":{"rendered":"<p>@Kristof<br \/>\nDas Bewerten von Kommentaren geht nur noch im eingeloggten Zustand, um Missbrauch zu vermeiden.<\/p>\n"},"status":"1"},{"id":147171,"parent":147168,"author":118,"author_name":"Gumfuzi","author_email":"deskmodder.de@noweb.at","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f1bc2c203701f27d2dde3720ed7f08333a7654f9aa87d73e429ceb3f14076533?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f1bc2c203701f27d2dde3720ed7f08333a7654f9aa87d73e429ceb3f14076533?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f1bc2c203701f27d2dde3720ed7f08333a7654f9aa87d73e429ceb3f14076533?s=96&d=mm&r=g"},"date":"2020-09-28T17:44:13","cld_nonce":"82f011626f","content":{"rendered":"<p>Mal sehen, wie sich das neue System bew\u00e4hrt, dann kann man eventuell(!) mal auch f\u00fcr G\u00e4ste das voten aktivieren.<\/p>\n"},"status":"1"},{"id":147174,"parent":147171,"author":0,"author_name":"Benjamin","author_email":"bwolkchen@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4d02f70732d0d7b8dc88137fa5696baa330bd13a711c7a07b4bf52b1013ac8b5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4d02f70732d0d7b8dc88137fa5696baa330bd13a711c7a07b4bf52b1013ac8b5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4d02f70732d0d7b8dc88137fa5696baa330bd13a711c7a07b4bf52b1013ac8b5?s=96&d=mm&r=g"},"date":"2020-09-28T18:34:13","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich bin nicht angemeldet und das voting funktioniert ohne das ich Scripts von Google erlaube.<\/p>\n"},"status":"1"},{"id":147175,"parent":147171,"author":2564,"author_name":"Nemo_G","author_email":"guenter.niemann@arcor.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1c7dc1e83f70168311f80d8c6dabdd6bc0e2819647b31be718aefbc97e5089dd?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1c7dc1e83f70168311f80d8c6dabdd6bc0e2819647b31be718aefbc97e5089dd?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1c7dc1e83f70168311f80d8c6dabdd6bc0e2819647b31be718aefbc97e5089dd?s=96&d=mm&r=g"},"date":"2020-09-28T18:40:12","cld_nonce":"82f011626f","content":{"rendered":"<p>Hallo Gumfuzzi,<\/p>\n<p>Ich habe Dir mal einen &#8218;Daumen runter&#8216; spendiert.<br \/>\n&#8211; Aber <i>nicht<\/i> f\u00fcr Deine aufopferungsvolle und anerkennenswerte Arbeit als Administrator,<br \/>\n&#8211; sondern f\u00fcr die \u00dcberlegung, auch G\u00e4sten das Abstimmen zu erm\u00f6glichen.<\/p>\n<p>Schlimm genug, wie es bei WF trotz Anmeldung zugeht:<br \/>\nEinmal etwas ge\u00e4u\u00dfert, das nicht PC- oder MSM-konform ist &#8212; und schon hagelt es Minusse!<\/p>\n<p>Gru\u00df, Nemo<\/p>\n"},"status":"1"},{"id":147176,"parent":0,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-09-28T18:41:11","cld_nonce":"82f011626f","content":{"rendered":"<p>Musste erst die Kekse entsorgen, danach funktionierte es wieder.<\/p>\n"},"status":"1"},{"id":147177,"parent":0,"author":0,"author_name":"Nashman01","author_email":"big_daddy_sr@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b24526e9319e13045f658da7763ea4ee68ab59df70a2c600a184140c80cbdc99?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b24526e9319e13045f658da7763ea4ee68ab59df70a2c600a184140c80cbdc99?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b24526e9319e13045f658da7763ea4ee68ab59df70a2c600a184140c80cbdc99?s=96&d=mm&r=g"},"date":"2020-09-28T19:03:45","cld_nonce":"82f011626f","content":{"rendered":"<p>Danke, meine Kommentare in der App funzen auch wieder\ud83d\ude0a\ud83d\udc4d\ud83d\udc4d\ud83d\udc4d <\/p>\n<p><i>gepostet mit der <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.deskmodder\" rel=\"nofollow ugc\">Deskmodder.de-App f\u00fcr Android<\/a><\/i><\/p>\n"},"status":"1"},{"id":147180,"parent":0,"author":0,"author_name":"seger85","author_email":"gerlach-rewe@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/20036cbc733a7961cf9c4d1407551270a3a0159b6e66963a24fee9f1dd30b635?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/20036cbc733a7961cf9c4d1407551270a3a0159b6e66963a24fee9f1dd30b635?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/20036cbc733a7961cf9c4d1407551270a3a0159b6e66963a24fee9f1dd30b635?s=96&d=mm&r=g"},"date":"2020-09-28T20:23:13","cld_nonce":"82f011626f","content":{"rendered":"<p>Also bei mir geht es seit Jahren nicht und keiner von euch bekommt es hin. Ins Forum komme ich, aber in die Windows 10 App nicht, auf dem Handy (ios) geht es manchmal und auf der Hauptseite im Blog auch nicht&#8230; Benutzer: seger85<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":147186,"parent":147171,"author":118,"author_name":"Gumfuzi","author_email":"deskmodder.de@noweb.at","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f1bc2c203701f27d2dde3720ed7f08333a7654f9aa87d73e429ceb3f14076533?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f1bc2c203701f27d2dde3720ed7f08333a7654f9aa87d73e429ceb3f14076533?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f1bc2c203701f27d2dde3720ed7f08333a7654f9aa87d73e429ceb3f14076533?s=96&d=mm&r=g"},"date":"2020-09-28T21:42:26","cld_nonce":"82f011626f","content":{"rendered":"<p>&#8230; kann aber auch sein, dass das mit dem voten via App nichts wird und wir das voten ganz deaktivieren m\u00fcssen. Da ist noch alles m\u00f6glich.<\/p>\n<p>Aber unser stets bem\u00fchtes App-Team wird alles versuchen.<\/p>\n"},"status":"1"},{"id":147193,"parent":147180,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-09-29T06:31:13","cld_nonce":"82f011626f","content":{"rendered":"<p>Wenn du mit der App ein Problem hast, dann melde es direkt \u00fcber die App. Dann k\u00f6nnen dir Jonas, bzw. Tim besser helfen.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>In eigener Sache: Blog-Login funktioniert wieder - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In eigener Sache: Blog-Login funktioniert wieder\" \/>\n<meta property=\"og:description\" content=\"Ein kurzer Hinweis: Nach dem Foren-Update funktionierte der Login im Blog nicht mehr, da phpBB etwas ge\u00e4ndert hat. Entschuldigt bitte den Fehler. Gumfuzi hat es nun korrigiert, sodass der Login wieder wie gew\u00f6hnlich klappt. Bitte so vorgehen: Im Forum abmelden&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-28T14:11:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-28T14:12:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"In eigener Sache: Blog-Login funktioniert wieder\",\"datePublished\":\"2020-09-28T14:11:46+00:00\",\"dateModified\":\"2020-09-28T14:12:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/\"},\"wordCount\":75,\"commentCount\":13,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/deskmodder_a.png\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/\",\"name\":\"In eigener Sache: Blog-Login funktioniert wieder - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/deskmodder_a.png\",\"datePublished\":\"2020-09-28T14:11:46+00:00\",\"dateModified\":\"2020-09-28T14:12:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/deskmodder_a.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/deskmodder_a.png\",\"width\":820,\"height\":590},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/28\\\/in-eigener-sache-blog-login-funktioniert-wieder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In eigener Sache: Blog-Login funktioniert wieder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"In eigener Sache: Blog-Login funktioniert wieder - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/","og_locale":"de_DE","og_type":"article","og_title":"In eigener Sache: Blog-Login funktioniert wieder","og_description":"Ein kurzer Hinweis: Nach dem Foren-Update funktionierte der Login im Blog nicht mehr, da phpBB etwas ge\u00e4ndert hat. Entschuldigt bitte den Fehler. Gumfuzi hat es nun korrigiert, sodass der Login wieder wie gew\u00f6hnlich klappt. Bitte so vorgehen: Im Forum abmelden&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-09-28T14:11:46+00:00","article_modified_time":"2020-09-28T14:12:23+00:00","og_image":[{"width":820,"height":590,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"In eigener Sache: Blog-Login funktioniert wieder","datePublished":"2020-09-28T14:11:46+00:00","dateModified":"2020-09-28T14:12:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/"},"wordCount":75,"commentCount":13,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/","name":"In eigener Sache: Blog-Login funktioniert wieder - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png","datePublished":"2020-09-28T14:11:46+00:00","dateModified":"2020-09-28T14:12:23+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png","width":820,"height":590},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/28\/in-eigener-sache-blog-login-funktioniert-wieder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"In eigener Sache: Blog-Login funktioniert wieder"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/144981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=144981"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/144981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/41749"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=144981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=144981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=144981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}