{"id":144728,"date":"2020-09-22T17:21:29","date_gmt":"2020-09-22T15:21:29","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=144728"},"modified":"2020-09-22T17:21:29","modified_gmt":"2020-09-22T15:21:29","slug":"linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/","title":{"rendered":"Linux: Microsoft Edge startet offiziell als Preview im Oktober und weitere Verbesserungen"},"content":{"rendered":"<p>Einige haben immer wieder gefragt, wann der Microsoft Edge Linux nun endlich bereitgestellt wird. Jetzt hat Microsoft einen Termin genannt. Im Oktober startet der Edge f\u00fcr Linux im Dev-Kanal und kann dort oder einen Linux-Paketmanager heruntergeladen werden.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png\" rel=\"lightbox[144728]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-500x335.png\" alt=\"\" width=\"500\" height=\"335\" class=\"aligncenter size-medium wp-image-129486\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-500x335.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-306x205.png 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png 744w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Zus\u00e4tzlich wird das Edge Team f\u00fcr die Entwickler das Toolkit WebView2 und die Visual Studio Code 1.0 von der Vorschau-Version dann allen zur Verf\u00fcgung stellen.<\/p>\n<p><em>&#8222;WebView2 ist von bestimmten Windows-Versionen entkoppelt, um die volle Webfunktionalit\u00e4t f\u00fcr alle Windows-Anwendungen zu bieten, und die Visual Studio Code 1.0-Erweiterung (im VS Studio-Erweiterungsspeicher zu finden) erm\u00f6glicht nahtlose Workflows f\u00fcr Entwickler, wenn sie zwischen Kontexten wechseln.&#8220;<\/em><\/p>\n<p>Der Edge wird in der Preview demn\u00e4chst dann auch den Kiosk-Modus hinzuf\u00fcgen, den die Unternehmen aus dem alten Edge kennen. Somit kann der Zugriff ma\u00dfgeschneidert eingestellt werden. Weiterhin bekommt die PDF-Funktion im Browser demn\u00e4chst die M\u00f6glichkeit digitale Signaturen anzuzeigen und zu validieren. Also es bleibt spannend und es wird nicht langweilig rund um den Browser.<\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/blogs.windows.com\/windowsexperience\/2020\/09\/22\/whats-new-in-web-experiences-ignite-2020-need-to-secure-your-remote-workers-choose-microsoft-edge-as-your-browser-for-business\/\" rel=\"noopener noreferrer\" target=\"_blank\">blogs.windows<\/a><\/div>\n<h3>Alle Microsoft Edge Downloads auch Insider:<\/h3>\n<ul>\n<li>Microsoft Edge Stable (Windows, macOS, iOS, Android) <a href=\"https:\/\/www.microsoft.com\/de-de\/edge\" rel=\"noopener noreferrer\" target=\"_blank\">microsoft.com\/de-de\/edge<\/a><\/li>\n<li>Canary, Dev, Beta (Windows, macOS)<a href=\"https:\/\/www.microsoftedgeinsider.com\/de-de\/download\/\" target=\"_blank\" rel=\"noopener noreferrer\">microsoftedgeinsider.com\/de-de\/download\/<\/a>,<\/li>\n<li><strong>Business:<\/strong> Microsoft Edge Stable, Beta und Dev (Windows, macOS: <a href=\"https:\/\/www.microsoft.com\/de-de\/edge\/business\/download\" rel=\"noopener noreferrer\" target=\"_blank\">microsoft.com\/de-de\/edge\/business<\/a><\/li>\n<li>Die <strong>portablen Versionen:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/05\/27\/portabler-microsoft-edge-chromium-updater-fuer-canary-developer-beta-und-spaeter-auch-der-finale-edge\/\" target=\"_blank\" rel=\"noopener noreferrer\">Portable Edge Updater<\/a><\/li>\n<li>Android: <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.microsoft.emmx&amp;hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">play.google.com\/microsoft.emmx<\/a><\/li>\n<li>iOS: <a href=\"https:\/\/apps.apple.com\/de\/app\/microsoft-edge\/id1288723196\" target=\"_blank\" rel=\"noopener noreferrer\">apps.apple.com\/microsoft-edge<\/a><\/li>\n<li><strong>Deinstallation<\/strong> Microsoft Edge: Sollte der Edge nicht selbst installiert worden sein, kann man den Edge trotzdem entfernen, wenn man denn m\u00f6chte\n<ul>\n<li><a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/07\/05\/microsoft-edge-deinstallieren-auch-wenn-es-grau-hinterlegt-ist\/\" rel=\"noopener noreferrer\" target=\"_blank\">Microsoft Edge deinstallieren \u2013 Auch wenn es grau hinterlegt ist<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Einige haben immer wieder gefragt, wann der Microsoft Edge Linux nun endlich bereitgestellt wird. Jetzt hat Microsoft einen Termin genannt. Im Oktober startet der Edge f\u00fcr Linux im Dev-Kanal und kann dort oder einen Linux-Paketmanager heruntergeladen werden. Zus\u00e4tzlich wird das&hellip; <\/p>\n","protected":false},"author":134,"featured_media":129486,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166,10],"tags":[64203,9740,8501,547,1533],"class_list":["post-144728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-browser","category-linux","tag-kiosk-modus","tag-linux","tag-microsoft-edge","tag-pdf","tag-preview"],"wp_featured_image":{"id":129486,"alt_text":"","description":"","media_type":"image","media_details":{"width":744,"height":499,"file":"2019\/11\/microsoft-edge-logo-2019.png","sizes":{"thumbnail":{"file":"microsoft-edge-logo-2019-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-306x205.png"},"medium":{"file":"microsoft-edge-logo-2019-500x335.png","width":500,"height":335,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-500x335.png"},"wp_review_large":{"file":"microsoft-edge-logo-2019-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-320x200.png"},"wp_review_small":{"file":"microsoft-edge-logo-2019-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-65x65.png"},"blog-large":{"file":"microsoft-edge-logo-2019-642x300.png","width":642,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-642x300.png"},"blog-medium":{"file":"microsoft-edge-logo-2019-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-306x205.png"},"recent-thumb":{"file":"microsoft-edge-logo-2019-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-350x316.png"},"service-featured":{"file":"microsoft-edge-logo-2019-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-600x330.png"},"wp_rp_thumbnail":{"file":"microsoft-edge-logo-2019-50x50.png","width":50,"height":50,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-50x50.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":129484,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png"},"commentcount":3,"wp_comments":[{"id":146665,"parent":0,"author":5243,"author_name":"eRaz0r","author_email":"spam84@ymail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=96&d=mm&r=g"},"date":"2020-09-22T19:41:40","cld_nonce":"82f011626f","content":{"rendered":"<p>Na endlich, kanns kaum erwarten ^^ Dank dem AUR wird EDGE f\u00fcr Manjaro ja mit sicherheit recht schnell verf\u00fcgbar sein.<\/p>\n<p>Mir auf jeden Fall lieber als Google Chrome<\/p>\n"},"status":"1"},{"id":146669,"parent":146665,"author":5243,"author_name":"eRaz0r","author_email":"spam84@ymail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=96&d=mm&r=g"},"date":"2020-09-22T19:48:57","cld_nonce":"82f011626f","content":{"rendered":"<p>Auf der anderen Seite ist der DEV ja nicht mit der Retail Synchronisierbar, oder? Das w\u00e4re wieder sch*** <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":146709,"parent":146669,"author":5243,"author_name":"eRaz0r","author_email":"spam84@ymail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=96&d=mm&r=g"},"date":"2020-09-23T06:10:02","cld_nonce":"82f011626f","content":{"rendered":"<p>Ok, gerade unter Win10 getestet, also zumindest synchronisiert er dort alles (Favs\/Erweiterungen) auch zwischen Retail und DEV Version &#8211; Also wird das wohl auch unter Linux so sein. Na dann kann EDGE ja kommen <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Linux: Microsoft Edge startet offiziell als Preview im Oktober und weitere Verbesserungen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Linux: Microsoft Edge startet offiziell als Preview im Oktober und weitere Verbesserungen\" \/>\n<meta property=\"og:description\" content=\"Einige haben immer wieder gefragt, wann der Microsoft Edge Linux nun endlich bereitgestellt wird. Jetzt hat Microsoft einen Termin genannt. Im Oktober startet der Edge f\u00fcr Linux im Dev-Kanal und kann dort oder einen Linux-Paketmanager heruntergeladen werden. Zus\u00e4tzlich wird das&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-22T15:21:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png\" \/>\n\t<meta property=\"og:image:width\" content=\"744\" \/>\n\t<meta property=\"og:image:height\" content=\"499\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Linux: Microsoft Edge startet offiziell als Preview im Oktober und weitere Verbesserungen\",\"datePublished\":\"2020-09-22T15:21:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/\"},\"wordCount\":270,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/microsoft-edge-logo-2019.png\",\"keywords\":[\"Kiosk-Modus\",\"Linux\",\"Microsoft Edge\",\"pdf\",\"Preview\"],\"articleSection\":[\"Browser\",\"Linux\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/\",\"name\":\"Linux: Microsoft Edge startet offiziell als Preview im Oktober und weitere Verbesserungen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/microsoft-edge-logo-2019.png\",\"datePublished\":\"2020-09-22T15:21:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/microsoft-edge-logo-2019.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/microsoft-edge-logo-2019.png\",\"width\":744,\"height\":499},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/22\\\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Linux: Microsoft Edge startet offiziell als Preview im Oktober und weitere Verbesserungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Linux: Microsoft Edge startet offiziell als Preview im Oktober und weitere Verbesserungen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/","og_locale":"de_DE","og_type":"article","og_title":"Linux: Microsoft Edge startet offiziell als Preview im Oktober und weitere Verbesserungen","og_description":"Einige haben immer wieder gefragt, wann der Microsoft Edge Linux nun endlich bereitgestellt wird. Jetzt hat Microsoft einen Termin genannt. Im Oktober startet der Edge f\u00fcr Linux im Dev-Kanal und kann dort oder einen Linux-Paketmanager heruntergeladen werden. Zus\u00e4tzlich wird das&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-09-22T15:21:29+00:00","og_image":[{"width":744,"height":499,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Linux: Microsoft Edge startet offiziell als Preview im Oktober und weitere Verbesserungen","datePublished":"2020-09-22T15:21:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/"},"wordCount":270,"commentCount":3,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png","keywords":["Kiosk-Modus","Linux","Microsoft Edge","pdf","Preview"],"articleSection":["Browser","Linux"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/","name":"Linux: Microsoft Edge startet offiziell als Preview im Oktober und weitere Verbesserungen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png","datePublished":"2020-09-22T15:21:29+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png","width":744,"height":499},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/22\/linux-microsoft-edge-startet-offiziell-als-preview-im-oktober-und-weitere-verbesserungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Linux: Microsoft Edge startet offiziell als Preview im Oktober und weitere Verbesserungen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/144728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=144728"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/144728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/129486"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=144728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=144728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=144728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}