{"id":144537,"date":"2020-09-16T14:15:03","date_gmt":"2020-09-16T12:15:03","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=144537"},"modified":"2020-09-16T14:15:03","modified_gmt":"2020-09-16T12:15:03","slug":"windows-10-suche-bietet-nun-dunkle-suchergebnisse","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/","title":{"rendered":"Windows 10 Suche bietet nun dunkle Suchergebnisse"},"content":{"rendered":"<p>Das dunkle Theme in Windows 10 gibt es nun schon eine Weile. Aber die Suchfunktion, egal ob \u00fcber das Startmen\u00fc oder in der Suche direkt \u00fcber die Taskleiste war bislang immer noch hell.<\/p>\n<p>Jetzt hat Microsoft diese Funktion aktuell in der Insider aktualisiert. \u00d6ffnet man die Suche und klickt auf die (&#8230;) drei Punkte dann wird die Build: 2020.09.15.15207570 angezeigt. Also vom 15.09. Hat man in den Einstellungen -> Personalisierung -> Farben auf Dunkel, oder Benutzerdefiniert beides auf Dunkel gestellt, werden auch sofort die lokalen oder Web-Suchergebnisse so angezeigt.<\/p>\n<div id='gallery-1' class='gallery galleryid-144537 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001.jpg' rel=\"lightbox[144537]\"><img loading=\"lazy\" decoding=\"async\" width=\"266\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001-266x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001-266x205.jpg 266w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001-467x360.jpg 467w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001-756x583.jpg 756w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001.jpg 941w\" sizes=\"auto, (max-width: 266px) 100vw, 266px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-002.jpg' rel=\"lightbox[144537]\"><img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-002-284x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-002-284x205.jpg 284w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-002-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-002-808x583.jpg 808w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-002.jpg 976w\" sizes=\"auto, (max-width: 284px) 100vw, 284px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-003.jpg' rel=\"lightbox[144537]\"><img loading=\"lazy\" decoding=\"async\" width=\"273\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-003-273x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-003-273x205.jpg 273w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-003-480x360.jpg 480w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-003-777x583.jpg 777w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-003.jpg 997w\" sizes=\"auto, (max-width: 273px) 100vw, 273px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Lange hat es ja gedauert, bis Microsoft auch hier eine \u00c4nderung vornimmt. Kann man nur hoffen, dass diese \u00c4nderung dann schnell in den anderen Windows 10 Versionen aktiviert werden. Ist ja Versionsunabh\u00e4ngig, da nur die Suche selber serverseitig aktualisiert werden muss.<\/p>\n<div class=\"viaquelle\">via: <a href=\"https:\/\/twitter.com\/flobo09\/status\/1306144755164872704\" rel=\"noopener noreferrer\" target=\"_blank\">@flobo09<\/a><\/div>\n<h3>Windows 10 Tutorials und Hilfe<\/h3>\n<p>In unserem <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 Wiki<\/a> findet ihr sehr viele hilfreiche Tipps und Tricks. Falls ihr Fragen habt, dann stellt diese ganz einfach bei uns im <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewforum.php?f=326\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Forum<\/strong><\/a>.<\/p>\n<ul>\n<li><strong>Installationsmedien:<\/strong> Aktuelle Installationsdateien findet ihr hier immer in der rechten Sidebar. <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/12\/11\/windows-10-19041-iso-esd-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004 ISO (19041)<\/a>, oder <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/06\/17\/windows-10-20h2-19042-iso-esd-inkl-updates-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">20H2 (2009) ISO (19042)<\/a> <\/li>\n<li><strong>Installation:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_clean_neu_installieren\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 Clean installieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_2004_neu_installieren_Anleitung_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 2004 neu installieren<\/a><\/li>\n<li><strong>Aktuelle Probleme mit der:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/04\/11\/windows-10-2004-bekannte-und-behobene-probleme\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004 \/ 20H2<\/a>\n    <\/li>\n<li><strong>Reparaturen:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Inplace_Upgrade_Windows_10_schnell_reparieren\" rel=\"noopener noreferrer\" target=\"_blank\">Inplace Upgrade Reparatur<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_reparieren_wiederherstellen_mit_DISM_Inplace_Upgrade_und_vielen_weiteren_Varianten\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 reparieren  \u00fcber DISM, sfc und weiteres<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_Update_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Windows Update reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Startmen%C3%BC_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Startmen\u00fc reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Apps_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Apps reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Store_reparieren\" rel=\"noopener noreferrer\" target=\"_blank\">Store reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Netzwerkverbindung_-adapter_reparieren_zur%C3%BCcksetzen_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Netzwerk reparieren<\/a><\/li>\n<li><strong>Anmeldung:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_automatisch_anmelden_ohne_Passworteingabe\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 automatische Anmeldung<\/a><\/li>\n<li><strong>Entfernen, Deinstallieren<\/strong>:  <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Apps_entfernen_deinstallieren\" rel=\"noopener noreferrer\" target=\"_blank\">Apps deinstallieren<\/a><\/li>\n<li><strong>Datei Explorer:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Dieser_PC_Ordner_entfernen_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Ordner unter Dieser PC entfernen<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Datei_Explorer_Windows_10_Netzwerk_Heimnetzgruppe_OneDrive_entfernen\" rel=\"noopener noreferrer\" target=\"_blank\">Netzwerk, OneDrive u.a. im Explorer entfernen<\/a><\/li>\n<li><strong>Richtige Nutzung:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Das_Windows_10_Startmen%C3%BC_richtig_einrichten_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Startmen\u00fc richtig nutzen<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Die_Suche_in_Windows_10_richtig_nutzen\" rel=\"noopener noreferrer\" target=\"_blank\">Suche richtig nutzen<\/a>,<\/li>\n<li><strong>Wichtig:<\/strong> In jedem Tutorial steht, f\u00fcr welche Version es geeignet ist.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Das dunkle Theme in Windows 10 gibt es nun schon eine Weile. Aber die Suchfunktion, egal ob \u00fcber das Startmen\u00fc oder in der Suche direkt \u00fcber die Taskleiste war bislang immer noch hell. Jetzt hat Microsoft diese Funktion aktuell in&hellip; <\/p>\n","protected":false},"author":134,"featured_media":144538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[3366,126,2161,5851,15,9751],"class_list":["post-144537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","tag-dunkel","tag-startmenu","tag-suche","tag-suchergebnisse","tag-taskleiste","tag-windows-10"],"wp_featured_image":{"id":144538,"alt_text":"","description":"","media_type":"image","media_details":{"width":941,"height":726,"file":"2020\/09\/windows-10-suche-dunkle-suchergebnisse-001.jpg","sizes":{"medium":{"file":"windows-10-suche-dunkle-suchergebnisse-001-467x360.jpg","width":467,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001-467x360.jpg"},"large":{"file":"windows-10-suche-dunkle-suchergebnisse-001-756x583.jpg","width":756,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001-756x583.jpg"},"thumbnail":{"file":"windows-10-suche-dunkle-suchergebnisse-001-266x205.jpg","width":266,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001-266x205.jpg"},"blog-large":{"file":"windows-10-suche-dunkle-suchergebnisse-001-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001-642x300.jpg"},"blog-medium":{"file":"windows-10-suche-dunkle-suchergebnisse-001-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001-306x205.jpg"},"recent-thumb":{"file":"windows-10-suche-dunkle-suchergebnisse-001-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001-350x316.jpg"},"service-featured":{"file":"windows-10-suche-dunkle-suchergebnisse-001-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001-600x330.jpg"},"wp_rp_thumbnail":{"file":"windows-10-suche-dunkle-suchergebnisse-001-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":144537,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001.jpg"},"commentcount":5,"wp_comments":[{"id":146341,"parent":0,"author":0,"author_name":"\u2615","author_email":"SFB@aim.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6777b6807e38a7d60c64ca7c6954542a1dc89ab9a28b7f234735323d96006a07?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6777b6807e38a7d60c64ca7c6954542a1dc89ab9a28b7f234735323d96006a07?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6777b6807e38a7d60c64ca7c6954542a1dc89ab9a28b7f234735323d96006a07?s=96&d=mm&r=g"},"date":"2020-09-16T14:34:14","cld_nonce":"82f011626f","content":{"rendered":"<p>funktioniert allerdings NUR wenn man auch die Websuche in der Suche aktiviert hat <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":146342,"parent":146341,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-09-16T14:35:14","cld_nonce":"82f011626f","content":{"rendered":"<p>Haste nen Grund, die wieder zu aktivieren. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":146343,"parent":0,"author":0,"author_name":"\u2615\u2615","author_email":"SFB@aim.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6777b6807e38a7d60c64ca7c6954542a1dc89ab9a28b7f234735323d96006a07?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6777b6807e38a7d60c64ca7c6954542a1dc89ab9a28b7f234735323d96006a07?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6777b6807e38a7d60c64ca7c6954542a1dc89ab9a28b7f234735323d96006a07?s=96&d=mm&r=g"},"date":"2020-09-16T14:46:31","cld_nonce":"82f011626f","content":{"rendered":"<p>um Gottes Willen, man(n) muss ja nicht alles annehmen was MS einem &#8222;vorkaut&#8220;, das war nur ein Test &#8211; stellt man Websuche wieder aus, dann sieht es auch wieder &#8222;normal&#8220; aus &#8211; vor allem OHNE die Schnellsuche, was man mMn eh nicht braucht ( nach einem Neustart &#8211; sogar die Versionsanzeige \u00e4ndert sich dann wieder auf die &#8222;alte&#8220; Version)<\/p>\n"},"status":"1"},{"id":146352,"parent":0,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=96&d=mm&r=g"},"date":"2020-09-16T16:38:03","cld_nonce":"82f011626f","content":{"rendered":"<p>Bei unseren Laptops ist der Dark Modus schon eine ganze Weile &#8211; seit Edge Junior. Hat Windows von sich aus geschaltet. Deswegen wohl, weil es uns und denen besonders gefallen hat. \ud83d\ude0a<\/p>\n"},"status":"1"},{"id":146581,"parent":0,"author":6555,"author_name":"Unbreakable44","author_email":"sascha.renneberg@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/102ef2b6fcfdbf073835e881a4a94f7e888aee6f04c516edfce9463f0ddb667d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/102ef2b6fcfdbf073835e881a4a94f7e888aee6f04c516edfce9463f0ddb667d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/102ef2b6fcfdbf073835e881a4a94f7e888aee6f04c516edfce9463f0ddb667d?s=96&d=mm&r=g"},"date":"2020-09-21T13:48:09","cld_nonce":"82f011626f","content":{"rendered":"<p>Bei mir leider noch nicht im darkmode <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Windows 10 Suche bietet nun dunkle Suchergebnisse - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windows 10 Suche bietet nun dunkle Suchergebnisse\" \/>\n<meta property=\"og:description\" content=\"Das dunkle Theme in Windows 10 gibt es nun schon eine Weile. Aber die Suchfunktion, egal ob \u00fcber das Startmen\u00fc oder in der Suche direkt \u00fcber die Taskleiste war bislang immer noch hell. Jetzt hat Microsoft diese Funktion aktuell in&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-16T12:15:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"941\" \/>\n\t<meta property=\"og:image:height\" content=\"726\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Windows 10 Suche bietet nun dunkle Suchergebnisse\",\"datePublished\":\"2020-09-16T12:15:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/\"},\"wordCount\":262,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/windows-10-suche-dunkle-suchergebnisse-001.jpg\",\"keywords\":[\"dunkel\",\"Startmen\u00fc\",\"Suche\",\"suchergebnisse\",\"taskleiste\",\"Windows 10\"],\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/\",\"name\":\"Windows 10 Suche bietet nun dunkle Suchergebnisse - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/windows-10-suche-dunkle-suchergebnisse-001.jpg\",\"datePublished\":\"2020-09-16T12:15:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/windows-10-suche-dunkle-suchergebnisse-001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/windows-10-suche-dunkle-suchergebnisse-001.jpg\",\"width\":941,\"height\":726},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/16\\\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Windows 10 Suche bietet nun dunkle Suchergebnisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Windows 10 Suche bietet nun dunkle Suchergebnisse - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/","og_locale":"de_DE","og_type":"article","og_title":"Windows 10 Suche bietet nun dunkle Suchergebnisse","og_description":"Das dunkle Theme in Windows 10 gibt es nun schon eine Weile. Aber die Suchfunktion, egal ob \u00fcber das Startmen\u00fc oder in der Suche direkt \u00fcber die Taskleiste war bislang immer noch hell. Jetzt hat Microsoft diese Funktion aktuell in&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-09-16T12:15:03+00:00","og_image":[{"width":941,"height":726,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Windows 10 Suche bietet nun dunkle Suchergebnisse","datePublished":"2020-09-16T12:15:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/"},"wordCount":262,"commentCount":5,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001.jpg","keywords":["dunkel","Startmen\u00fc","Suche","suchergebnisse","taskleiste","Windows 10"],"articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/","name":"Windows 10 Suche bietet nun dunkle Suchergebnisse - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001.jpg","datePublished":"2020-09-16T12:15:03+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001.jpg","width":941,"height":726},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/16\/windows-10-suche-bietet-nun-dunkle-suchergebnisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Windows 10 Suche bietet nun dunkle Suchergebnisse"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/windows-10-suche-dunkle-suchergebnisse-001.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/144537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=144537"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/144537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/144538"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=144537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=144537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=144537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}