{"id":144114,"date":"2020-09-05T10:02:48","date_gmt":"2020-09-05T08:02:48","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=144114"},"modified":"2020-09-05T10:02:48","modified_gmt":"2020-09-05T08:02:48","slug":"video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/","title":{"rendered":"Video Hub &#8211; Neue Anlaufstelle f\u00fcr  Microsoft Videos der Tech Community"},"content":{"rendered":"<p>Microsoft wird ab dem 22. September 2020 den Microsoft Tech Community Video Hub starten. Eine neue Anlaufstelle nicht nur f\u00fcr Videos, die auf den einzelnen Tech-Community Seiten eingebettet werden, zur Erkl\u00e4rung von Anleitungen und Produkten.<\/p>\n<p>Mit dem 22.09. wird man zuerst die Inhalte der Microsoft Ignite &#8222;f\u00fcttern&#8220;, die ja dieses Jahr als digitales Event vom 22. bis 24. September stattfinden wird. Danach folgen dann die Videos zu den Hilfestellungen, Ratgebern und mehr. Aber der Video Hub kann noch mehr, als nur Videos zeigen.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft.jpg\" rel=\"lightbox[144114]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft-438x360.jpg\" alt=\"\" width=\"438\" height=\"360\" class=\"aligncenter size-medium wp-image-144115\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft-438x360.jpg 438w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft-709x583.jpg 709w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft-249x205.jpg 249w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft.jpg 999w\" sizes=\"auto, (max-width: 438px) 100vw, 438px\" \/><\/a><\/p>\n<p><em>&#8222;Der neue Video Hub wird der Ort sein, an dem Sie Videos ansehen, sich durch unsere interaktiven Anleitungen klicken (eine Click-through-Demo-Erfahrung) und sich mit anderen Community-Mitgliedern \u00fcber diese Inhalte unterhalten k\u00f6nnen. Wir werden auch, soweit verf\u00fcgbar, zeigen, wer die Fachexperten sind, und wenn dieses Video zu einer Serie geh\u00f6rt, werden wir einen Link zum n\u00e4chsten Video in dieser Serie bereitstellen.&#8220;<\/em><\/p>\n<p>Wenn es so funktioniert, wie Microsoft es sich erhofft, w\u00e4re es eine durchaus gute Verbesserung. Ab dem 22. September werden wir dann mehr wissen. Der Video Hub wird dann unter dieser Adresse erreichbar sein: <a href=\"https:\/\/aka.ms\/VideoHub\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/aka.ms\/VideoHub<\/a><\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/techcommunity.microsoft.com\/t5\/tech-community-blog\/coming-soon-video-hub\/ba-p\/1636820\" rel=\"noopener noreferrer\" target=\"_blank\">techcommunity<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft wird ab dem 22. September 2020 den Microsoft Tech Community Video Hub starten. Eine neue Anlaufstelle nicht nur f\u00fcr Videos, die auf den einzelnen Tech-Community Seiten eingebettet werden, zur Erkl\u00e4rung von Anleitungen und Produkten. Mit dem 22.09. wird man&hellip; <\/p>\n","protected":false},"author":134,"featured_media":144115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[60884],"tags":[148,77698,77697],"class_list":["post-144114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internet","tag-microsoft","tag-tech-community","tag-video-hub"],"wp_featured_image":{"id":144115,"alt_text":"","description":"","media_type":"image","media_details":{"width":999,"height":822,"file":"2020\/09\/video-hub-tech-community-microsoft.jpg","sizes":{"medium":{"file":"video-hub-tech-community-microsoft-438x360.jpg","width":438,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft-438x360.jpg"},"large":{"file":"video-hub-tech-community-microsoft-709x583.jpg","width":709,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft-709x583.jpg"},"thumbnail":{"file":"video-hub-tech-community-microsoft-249x205.jpg","width":249,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft-249x205.jpg"},"blog-large":{"file":"video-hub-tech-community-microsoft-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft-642x300.jpg"},"blog-medium":{"file":"video-hub-tech-community-microsoft-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft-306x205.jpg"},"recent-thumb":{"file":"video-hub-tech-community-microsoft-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft-350x316.jpg"},"service-featured":{"file":"video-hub-tech-community-microsoft-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft-600x330.jpg"},"wp_rp_thumbnail":{"file":"video-hub-tech-community-microsoft-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":144114,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft.jpg"},"commentcount":2,"wp_comments":[{"id":145406,"parent":0,"author":0,"author_name":"Ingridl","author_email":"Ingrid@attnetwork.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=96&d=mm&r=g"},"date":"2020-09-05T10:11:05","cld_nonce":"82f011626f","content":{"rendered":"<p>\ud83d\udc4d\ud83d\udc4d\ud83d\udc4d<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":145415,"parent":145406,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=96&d=mm&r=g"},"date":"2020-09-05T12:21:06","cld_nonce":"82f011626f","content":{"rendered":"<p>auch \ud83d\udc4d\ud83d\udc4d\ud83d\udc4d. Schafft irgendwie durch die audio-visuelle Darstellung von Anleitungen pers\u00f6nliche N\u00e4he. Man bekommt ja \u00f6fters mal kleine Bitten um Bewertung von Dies und Das auf den Rechner. Ich beantworte grunds\u00e4tzlich solche Anfragen, weil ich glaube, dass das eine M\u00f6glichkeit ist der Kontaktaufnahme Kunde\/Microsoft; wenn auch nur virtueller Art. Au\u00dferdem werden solche Bewertungen auch von Microsoft genutzt, um nach L\u00f6sungen und Verbesserungen zu suchen, \u00e4hnlich dem Feedback-Hub.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Video Hub - Neue Anlaufstelle f\u00fcr Microsoft Videos der Tech Community - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Video Hub - Neue Anlaufstelle f\u00fcr Microsoft Videos der Tech Community\" \/>\n<meta property=\"og:description\" content=\"Microsoft wird ab dem 22. September 2020 den Microsoft Tech Community Video Hub starten. Eine neue Anlaufstelle nicht nur f\u00fcr Videos, die auf den einzelnen Tech-Community Seiten eingebettet werden, zur Erkl\u00e4rung von Anleitungen und Produkten. Mit dem 22.09. wird man&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-05T08:02:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"999\" \/>\n\t<meta property=\"og:image:height\" content=\"822\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Video Hub &#8211; Neue Anlaufstelle f\u00fcr Microsoft Videos der Tech Community\",\"datePublished\":\"2020-09-05T08:02:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/\"},\"wordCount\":199,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/video-hub-tech-community-microsoft.jpg\",\"keywords\":[\"Microsoft\",\"Tech Community\",\"Video Hub\"],\"articleSection\":[\"Welt des Internets\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/\",\"name\":\"Video Hub - Neue Anlaufstelle f\u00fcr Microsoft Videos der Tech Community - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/video-hub-tech-community-microsoft.jpg\",\"datePublished\":\"2020-09-05T08:02:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/video-hub-tech-community-microsoft.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/video-hub-tech-community-microsoft.jpg\",\"width\":999,\"height\":822},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/09\\\/05\\\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video Hub &#8211; Neue Anlaufstelle f\u00fcr Microsoft Videos der Tech Community\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Video Hub - Neue Anlaufstelle f\u00fcr Microsoft Videos der Tech Community - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/","og_locale":"de_DE","og_type":"article","og_title":"Video Hub - Neue Anlaufstelle f\u00fcr Microsoft Videos der Tech Community","og_description":"Microsoft wird ab dem 22. September 2020 den Microsoft Tech Community Video Hub starten. Eine neue Anlaufstelle nicht nur f\u00fcr Videos, die auf den einzelnen Tech-Community Seiten eingebettet werden, zur Erkl\u00e4rung von Anleitungen und Produkten. Mit dem 22.09. wird man&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-09-05T08:02:48+00:00","og_image":[{"width":999,"height":822,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Video Hub &#8211; Neue Anlaufstelle f\u00fcr Microsoft Videos der Tech Community","datePublished":"2020-09-05T08:02:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/"},"wordCount":199,"commentCount":2,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft.jpg","keywords":["Microsoft","Tech Community","Video Hub"],"articleSection":["Welt des Internets"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/","name":"Video Hub - Neue Anlaufstelle f\u00fcr Microsoft Videos der Tech Community - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft.jpg","datePublished":"2020-09-05T08:02:48+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft.jpg","width":999,"height":822},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/09\/05\/video-hub-neue-anlaufstelle-fuer-microsoft-videos-der-tech-community\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Video Hub &#8211; Neue Anlaufstelle f\u00fcr Microsoft Videos der Tech Community"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/09\/video-hub-tech-community-microsoft.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/144114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=144114"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/144114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/144115"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=144114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=144114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=144114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}