{"id":143141,"date":"2020-08-14T10:59:01","date_gmt":"2020-08-14T08:59:01","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=143141"},"modified":"2020-08-14T10:59:01","modified_gmt":"2020-08-14T08:59:01","slug":"google-wear-os-grosses-update-soll-im-herbst-kommen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/","title":{"rendered":"Google Wear OS: Gro\u00dfes Update soll im Herbst kommen"},"content":{"rendered":"<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501.jpg\" rel=\"lightbox[143141]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-143144\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-500x213.jpg\" alt=\"\" width=\"500\" height=\"213\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-500x213.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-810x345.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-306x130.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501.jpg 915w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>F\u00fcr Smartwatches stellt Google bekanntlich sein Wear OS zur Verf\u00fcgung, behandelt dies aber meiner Meinung nach doch etwas stiefm\u00fctterlich. Nun hat man im Google Entwicklerblog das n\u00e4chste gro\u00dfe Update auf Version 11 f\u00fcr den Herbst angek\u00fcndigt. Aktuell gibt&#8217;s ja die Version 9 (basierend auf Android 9) und Version 10 \u00fcberspringt man.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105447.jpg\" rel=\"lightbox[143141]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-143145\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105447-500x191.jpg\" alt=\"\" width=\"500\" height=\"191\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105447-500x191.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105447-810x310.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105447-306x117.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105447.jpg 1080w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Das neue Update soll einige neue Features an Bord haben. Zudem soll damit dann auch der Qualcomm Snapdragon Wear 4100 (+) unterst\u00fctzt werden. Der Pairing-Prozess soll vereinfacht und beschleunigt und die generelle Leistung verbessert werden. Hierdurch sollen schnellere und verbesserte Informationen ausgegeben werden und auch Apps sollen schneller starten.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/image-1-handwash.gif\" rel=\"lightbox[143141]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-143146\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/image-1-handwash-360x360.gif\" alt=\"\" width=\"360\" height=\"360\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/image-1-handwash-360x360.gif 360w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/image-1-handwash-205x205.gif 205w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/image-1-handwash-65x65.gif 65w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/image-1-handwash-50x50.gif 50w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/a><\/p>\n<p>Gerade hier soll es Verbesserungen f\u00fcr den CPU Kern geben. Verbesserungen soll es auch an der SysUI geben. Neue Funktionen f\u00fcr LTE sollen auch Einzug erhalten. Ein genauer Termin f\u00fcr das Upgrade steht noch nicht fest. Weitere Informationen findet ihr im Google Entwicklerblog.<\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/android-developers.googleblog.com\/2020\/08\/whats-happening-in-wear-os-by-google.html?m=1\" target=\"_blank\" rel=\"noopener noreferrer\">Google<\/a> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr Smartwatches stellt Google bekanntlich sein Wear OS zur Verf\u00fcgung, behandelt dies aber meiner Meinung nach doch etwas stiefm\u00fctterlich. Nun hat man im Google Entwicklerblog das n\u00e4chste gro\u00dfe Update auf Version 11 f\u00fcr den Herbst angek\u00fcndigt. Aktuell gibt&#8217;s ja die&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":143144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,894,231,152],"tags":[77469],"class_list":["post-143141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-android","category-mobile","category-software","tag-wear-os-by-google"],"wp_featured_image":{"id":143144,"alt_text":"","description":"","media_type":"image","media_details":{"width":915,"height":390,"file":"2020\/08\/screenshot-20200814-105501.jpg","sizes":{"medium":{"file":"screenshot-20200814-105501-500x213.jpg","width":500,"height":213,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-500x213.jpg"},"large":{"file":"screenshot-20200814-105501-810x345.jpg","width":810,"height":345,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-810x345.jpg"},"thumbnail":{"file":"screenshot-20200814-105501-306x130.jpg","width":306,"height":130,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-306x130.jpg"},"wp_review_large":{"file":"screenshot-20200814-105501-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-320x200.jpg"},"wp_review_small":{"file":"screenshot-20200814-105501-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-65x65.jpg"},"blog-large":{"file":"screenshot-20200814-105501-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-642x300.jpg"},"blog-medium":{"file":"screenshot-20200814-105501-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-306x205.jpg"},"recent-thumb":{"file":"screenshot-20200814-105501-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-350x316.jpg"},"service-featured":{"file":"screenshot-20200814-105501-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-600x330.jpg"},"wp_rp_thumbnail":{"file":"screenshot-20200814-105501-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"CLT-L09","caption":"","created_timestamp":"1597402459","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":143141,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Google Wear OS: Gro\u00dfes Update soll im Herbst kommen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google Wear OS: Gro\u00dfes Update soll im Herbst kommen\" \/>\n<meta property=\"og:description\" content=\"F\u00fcr Smartwatches stellt Google bekanntlich sein Wear OS zur Verf\u00fcgung, behandelt dies aber meiner Meinung nach doch etwas stiefm\u00fctterlich. Nun hat man im Google Entwicklerblog das n\u00e4chste gro\u00dfe Update auf Version 11 f\u00fcr den Herbst angek\u00fcndigt. Aktuell gibt&#8217;s ja die&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-14T08:59:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"915\" \/>\n\t<meta property=\"og:image:height\" content=\"390\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Google Wear OS: Gro\u00dfes Update soll im Herbst kommen\",\"datePublished\":\"2020-08-14T08:59:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/\"},\"wordCount\":163,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/screenshot-20200814-105501.jpg\",\"keywords\":[\"Wear OS by Google\"],\"articleSection\":{\"1\":\"Android\",\"2\":\"Mobile\",\"3\":\"Software &amp; Updates\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/\",\"name\":\"Google Wear OS: Gro\u00dfes Update soll im Herbst kommen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/screenshot-20200814-105501.jpg\",\"datePublished\":\"2020-08-14T08:59:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/screenshot-20200814-105501.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/screenshot-20200814-105501.jpg\",\"width\":915,\"height\":390},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/14\\\/google-wear-os-grosses-update-soll-im-herbst-kommen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google Wear OS: Gro\u00dfes Update soll im Herbst kommen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Google Wear OS: Gro\u00dfes Update soll im Herbst kommen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/","og_locale":"de_DE","og_type":"article","og_title":"Google Wear OS: Gro\u00dfes Update soll im Herbst kommen","og_description":"F\u00fcr Smartwatches stellt Google bekanntlich sein Wear OS zur Verf\u00fcgung, behandelt dies aber meiner Meinung nach doch etwas stiefm\u00fctterlich. Nun hat man im Google Entwicklerblog das n\u00e4chste gro\u00dfe Update auf Version 11 f\u00fcr den Herbst angek\u00fcndigt. Aktuell gibt&#8217;s ja die&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-08-14T08:59:01+00:00","og_image":[{"width":915,"height":390,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Google Wear OS: Gro\u00dfes Update soll im Herbst kommen","datePublished":"2020-08-14T08:59:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/"},"wordCount":163,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501.jpg","keywords":["Wear OS by Google"],"articleSection":{"1":"Android","2":"Mobile","3":"Software &amp; Updates"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/","name":"Google Wear OS: Gro\u00dfes Update soll im Herbst kommen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501.jpg","datePublished":"2020-08-14T08:59:01+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501.jpg","width":915,"height":390},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/14\/google-wear-os-grosses-update-soll-im-herbst-kommen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Google Wear OS: Gro\u00dfes Update soll im Herbst kommen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/screenshot-20200814-105501.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/143141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=143141"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/143141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/143144"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=143141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=143141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=143141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}