{"id":143131,"date":"2020-08-13T15:18:47","date_gmt":"2020-08-13T13:18:47","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=143131"},"modified":"2020-08-13T15:18:47","modified_gmt":"2020-08-13T13:18:47","slug":"surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/","title":{"rendered":"Surface Duo mit 3 Jahren OS-Updates und freischaltbarem Bootloader"},"content":{"rendered":"<p>Gestern haben sich die Meldungen \u00fcber das neue Microsoft Surface Duo regelrecht \u00fcberschlagen im Netz. <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/08\/12\/microsoft-surface-duo-der-preis-ab-1399-dollar-ist-offiziell-auslieferung-ab-10-september\/\" rel=\"noopener noreferrer\" target=\"_blank\">Wie wir nun wissen<\/a>, kommt es ab 1.399 Dollar erst einmal in den USA auf den Markt. Jetzt sind aber weitere Infos bekannt geworden.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis.jpg\" rel=\"lightbox[143131]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis-433x360.jpg\" alt=\"\" width=\"433\" height=\"360\" class=\"aligncenter size-medium wp-image-143058\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis-433x360.jpg 433w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis-246x205.jpg 246w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis.jpg 636w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/><\/a><\/p>\n<p>So wird Microsoft wie auch Google oder Samsung drei Jahre lang OS-Updates f\u00fcr das neue Ger\u00e4t bereitstellen. Da es mit Android 10 kommt, sollte so Android 13 dann auch noch m\u00f6glich sein. Bei den Sicherheitsupdates hat man sich derzeit noch auf keinen Plan festgelegt. Wie vorgeschrieben, kommen diese im ersten Jahr monatlich. Sp\u00e4ter wird man dann, sicherlich wie auch Samsung, in den viertel-j\u00e4hrlichen Rhythmus wechseln.<\/p>\n<p>F\u00fcr viele vielleicht interessant, der Bootloader wird freischaltbar sein. Somit k\u00f6nnte man eine benutzerdefinierte Rom installieren, (wenn man denn will). Die Bastler wird es sicherlich freuen. Aber schon alleine die drei Jahre OS-Update sind ein gutes Zeichen und sicherlich auch notwendig, im gesch\u00e4ftlichen Bereich das Ger\u00e4t absetzen zu k\u00f6nnen.<\/p>\n<p>F\u00fcr viele wird es sicherlich ne Schippe zu teuer sein. Aber Microsoft selber zielt ihr auch eher auf den Business-Bereich und wird es dort eher verkaufen. Die Synergie zwischen Android, Apps, Windows und Cloud ist daf\u00fcr eine gute Voraussetzung. Und telefonieren kann man mit dem kleinen &#8222;Klapp-PC&#8220; ja auch.<\/p>\n<p><em>Danke an Turniquet f\u00fcr den Hinweis<\/em><\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/www.xda-developers.com\/microsoft-surface-duo-3-years-os-security-updates-unlockable-bootloader\/\" rel=\"noopener noreferrer\" target=\"_blank\">xda-developers<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gestern haben sich die Meldungen \u00fcber das neue Microsoft Surface Duo regelrecht \u00fcberschlagen im Netz. Wie wir nun wissen, kommt es ab 1.399 Dollar erst einmal in den USA auf den Markt. Jetzt sind aber weitere Infos bekannt geworden. So&hellip; <\/p>\n","protected":false},"author":134,"featured_media":143058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[894,1286],"tags":[3010,77466,639,148,77465,64081,44442],"class_list":["post-143131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-android","category-hardware","tag-bootloader","tag-eigene-rom","tag-freischalten","tag-microsoft","tag-os-update","tag-surface-duo","tag-wie-lange-updates"],"wp_featured_image":{"id":143058,"alt_text":"","description":"","media_type":"image","media_details":{"width":636,"height":529,"file":"2020\/08\/microsoft-surface-duo-preis.jpg","sizes":{"medium":{"file":"microsoft-surface-duo-preis-433x360.jpg","width":433,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis-433x360.jpg"},"thumbnail":{"file":"microsoft-surface-duo-preis-246x205.jpg","width":246,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis-246x205.jpg"},"wp_review_large":{"file":"microsoft-surface-duo-preis-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis-320x200.jpg"},"wp_review_small":{"file":"microsoft-surface-duo-preis-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis-65x65.jpg"},"blog-large":{"file":"microsoft-surface-duo-preis-636x300.jpg","width":636,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis-636x300.jpg"},"blog-medium":{"file":"microsoft-surface-duo-preis-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis-306x205.jpg"},"recent-thumb":{"file":"microsoft-surface-duo-preis-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis-350x316.jpg"},"service-featured":{"file":"microsoft-surface-duo-preis-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis-600x330.jpg"},"wp_rp_thumbnail":{"file":"microsoft-surface-duo-preis-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":143056,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis.jpg"},"commentcount":10,"wp_comments":[{"id":143354,"parent":0,"author":0,"author_name":"7four7","author_email":"ghjsu@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/28b73154e494885721345f3a15951e96700653aa7f34b2009f65fa236f3df296?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/28b73154e494885721345f3a15951e96700653aa7f34b2009f65fa236f3df296?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/28b73154e494885721345f3a15951e96700653aa7f34b2009f65fa236f3df296?s=96&d=mm&r=g"},"date":"2020-08-13T17:04:17","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ein Mini PC f\u00fcr unterwegs, diese Idee ist nun schon 20 Jahre alt. Der Vorteil, erf\u00fcllt das Duo wohl nicht ?, man hat f\u00fcr das Internet einen ausf\u00fcllenden Bereich \u00fcber das ganze Ger\u00e4t. Warum ? Nur so empfinde ich es als komfortabel Recherche und Online Aktivit\u00e4ten zu t\u00e4ten. Ein Smartphone ist f\u00fcr mich bis heute daf\u00fcr immer noch eine Kr\u00fccke.<\/p>\n"},"status":"1"},{"id":143361,"parent":0,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icloud.vom","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8bff18280285e98355135b9d313d4d77622daccb66020de1e3bfe805a28fb6b6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8bff18280285e98355135b9d313d4d77622daccb66020de1e3bfe805a28fb6b6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8bff18280285e98355135b9d313d4d77622daccb66020de1e3bfe805a28fb6b6?s=96&d=mm&r=g"},"date":"2020-08-13T17:55:45","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich geh\u00f6re zum &#8222;Business-Bereich&#8220;. Und f\u00fcr mich als Unternehmer geh\u00f6re ich zu denen, die ganz bestimmt nicht alle 3 Jahre 1399,- $ auf den Tisch legen wird.<br \/>\nAbgesehen mal vom Preis, der wohl kaum in der Nutzen\/Kostenrelation zu verorten ist, bringt das Ger\u00e4t nicht viel mehr, als die \u00fcblichen Smartphones. Und zum Basteln haben wir im Unternehmen weniger Zeit.<\/p>\n"},"status":"1"},{"id":143369,"parent":0,"author":0,"author_name":"Ichhalt","author_email":"m.b.1991@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=96&d=mm&r=g"},"date":"2020-08-13T19:46:19","cld_nonce":"b6d6726996","content":{"rendered":"<p>3 Jahre sind ein guter Anfang aber nicht genug. Ob das Ger\u00e4t \u00fcberhaupt 3 Jahre h\u00e4lt will ich mir nicht vorstellen. Um den Planeten zu sch\u00fctzen ist es wichtig das wir unseren Konsum regulieren und eben nicht jedes Jahr oder alle 2 Jahre ein neues Ger\u00e4t kaufen. 5 Jahre finde ich besser deswegen habe ich ein iPhone 11 und weil Android nur Spielerei f\u00fcr mich ist.<\/p>\n"},"status":"1"},{"id":143372,"parent":0,"author":0,"author_name":"arcticocean","author_email":"trash_acc@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4c7424dc5ab84a9d1ea050f4bc8293af5505cf90e7cade0001f388ea02806ef9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4c7424dc5ab84a9d1ea050f4bc8293af5505cf90e7cade0001f388ea02806ef9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4c7424dc5ab84a9d1ea050f4bc8293af5505cf90e7cade0001f388ea02806ef9?s=96&d=mm&r=g"},"date":"2020-08-13T21:23:02","cld_nonce":"b6d6726996","content":{"rendered":"<p>Machen wir mal eine einfache Rechnung: 1400 x 2 = 2800. Daf\u00fcr bekommt man das neueste iPhone in der besten Ausf\u00fchrung und ein iPad Pro in der besten Ausf\u00fchrung. Etwas an beiden gespart, bekommt man zu dem Preis sogar beide Ger\u00e4te mit AirPods Pro, Magic Keyboard und Trackpad. Wir haben also f\u00fcnf Ger\u00e4te f\u00fcr den Preis von zwei Surface Duo. Und jetzt?<\/p>\n<p>Unsere Apple Hardware h\u00e4lt locker acht Jahre (ich kenne Leute, die nutzen sogar noch 2009er MacBooks), sechs davon bekommen unser Smartphone und Tablet Softwareupdates ohne Bootloader Fummelei und ewige Wartezeiten f\u00fcr Security Updates (was ein abartiges System bei Android). Wir haben wirkliche Premium Hardware mit einem ressourcensparenden Betriebssystem. Wir haben ein Tablet, welches einen VOLLWERTIGEN Notebook Ersatz darstellt und somit alles, was man gesch\u00e4ftlich braucht.<\/p>\n<p>Also wer ein Duo kauft, Business oder nicht, der l\u00e4uft v\u00f6llig am Leben vorbei.<\/p>\n<p>PS: das ist kein \u201eApple is the greatest, Android is shit\u201c-Post, aber das Beispiel passt am besten, man kann sich sicherlich auch eine gute, lang haltende Android Office Umgebung basteln mit Custom ROMs<\/p>\n"},"status":"1"},{"id":143379,"parent":0,"author":0,"author_name":"Rmb32","author_email":"ralfb32@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9db86c9a6535bd5d3d3e982d9397f43c60fc1e2c65b1176331ede2c0afa73aa1?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9db86c9a6535bd5d3d3e982d9397f43c60fc1e2c65b1176331ede2c0afa73aa1?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9db86c9a6535bd5d3d3e982d9397f43c60fc1e2c65b1176331ede2c0afa73aa1?s=96&d=mm&r=g"},"date":"2020-08-13T22:06:20","cld_nonce":"b6d6726996","content":{"rendered":"<p>Also ich finde das Ger\u00e4t super und habe mir eines bestellt<\/p>\n"},"status":"1"},{"id":143385,"parent":143361,"author":0,"author_name":"Micheal Gant","author_email":"micheal.gant66@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a4f4454afd2e465319fcb2fb8b41466b718020635df9d490a13cdb8cd697fb77?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a4f4454afd2e465319fcb2fb8b41466b718020635df9d490a13cdb8cd697fb77?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a4f4454afd2e465319fcb2fb8b41466b718020635df9d490a13cdb8cd697fb77?s=96&d=mm&r=g"},"date":"2020-08-13T23:53:12","cld_nonce":"b6d6726996","content":{"rendered":"<p>1 Mann Business dann wohl.<br \/>\nbei uns wird jeder Mini Chef mit MacBooks, Apple Tablets und Co vollgeschmissen. Alle 3-6 Monate gehts ein neuer Satz an die Hansel raus. Die alten d\u00fcrfen diese Deppen dann auch noch bevorzugt kaufen. Macbooks 10\u20ac, Apple Tablet 5\u20ac, Iphone 5\u20ac  etc.<br \/>\nDu glaubst garnicht wie sich diese Schweine in einer fetten AG mit 60% Wasserkopfanteil noch die Taschen voll machen. Die Dell Workstations gehen im 10er Pack pro Person raus f\u00fcr kleine \u20ac Betr\u00e4ge nach unter 1 jahr obwohl die Leasingvertr\u00e4ge 5 Jahre f\u00fcr die Desktops sind. Gleiches Spiel mit den Druckern.<\/p>\n"},"status":"1"},{"id":143408,"parent":143372,"author":0,"author_name":"Hans","author_email":"isdn4ever@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4c7de59f9c992990d02dadd33ba123917722efb8935559a3fef89adb0943c3d8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4c7de59f9c992990d02dadd33ba123917722efb8935559a3fef89adb0943c3d8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4c7de59f9c992990d02dadd33ba123917722efb8935559a3fef89adb0943c3d8?s=96&d=mm&r=g"},"date":"2020-08-14T07:37:05","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wow, da hat jemand den kompletten Durchblick wie es in Unternehmen aussieht&#8230;<br \/>\nSry, aber diese Aussage von Apple, das iPad sei ein vollwertiger PC, ist leider so l\u00e4cherlich. Was denkt ihr eigentlich warum Windows \u00fcber 80% am Markt h\u00e4lt? Entschuldigung wenn ich das so sage, aber niemanden im PC Bereich interessiert sich f\u00fcr Privatanwender. Es ist halt einfach wie Micheal Gant sagt. Windows ist wei\u00df Gott nicht fehlerfrei und nervig, aber sie waren zur richtigen Zeit am richtigen Ort. Und jetzt stellt das niemand mehr um. Da stecken Milliarden Entwicklungskosten drin. Es gibt diverse Software exklusiv f\u00fcr Windows und dann werden genug Eigenentwicklungen darauf aufgebaut.<\/p>\n"},"status":"1"},{"id":143410,"parent":143379,"author":0,"author_name":"Ingridl","author_email":"Ingrid@attnetwork.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=96&d=mm&r=g"},"date":"2020-08-14T08:11:19","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ja, die Minderheiten mu\u00df man sch\u00fctzen.(Au\u00dfer die Werbe-Futzis)<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":143416,"parent":143379,"author":0,"author_name":"Saschman","author_email":"saschman@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/038b92b011a37e6bf1d48274e7abe50c50ea7790910f7f2a73dc5ae6d73e19ba?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/038b92b011a37e6bf1d48274e7abe50c50ea7790910f7f2a73dc5ae6d73e19ba?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/038b92b011a37e6bf1d48274e7abe50c50ea7790910f7f2a73dc5ae6d73e19ba?s=96&d=mm&r=g"},"date":"2020-08-14T10:30:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>@Rmb32 hast du ne US Adresse oder wie hat es mit der Bestellung geklappt? Hatte das nicht hinbekommen, da keine US Adresse?<\/p>\n"},"status":"1"},{"id":143468,"parent":143410,"author":0,"author_name":"Lenny","author_email":"ruedigerochel@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/55f9c5644bffd65429da859d9b0c99b432825e0481ccb3cb1ab0f33523e67eda?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/55f9c5644bffd65429da859d9b0c99b432825e0481ccb3cb1ab0f33523e67eda?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/55f9c5644bffd65429da859d9b0c99b432825e0481ccb3cb1ab0f33523e67eda?s=96&d=mm&r=g"},"date":"2020-08-14T19:40:48","cld_nonce":"b6d6726996","content":{"rendered":"<p>Der l\u00fcgt sich was in die Tasche, mehr nicht\ud83d\udc4e<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Surface Duo mit 3 Jahren OS-Updates und freischaltbarem Bootloader - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Surface Duo mit 3 Jahren OS-Updates und freischaltbarem Bootloader\" \/>\n<meta property=\"og:description\" content=\"Gestern haben sich die Meldungen \u00fcber das neue Microsoft Surface Duo regelrecht \u00fcberschlagen im Netz. Wie wir nun wissen, kommt es ab 1.399 Dollar erst einmal in den USA auf den Markt. Jetzt sind aber weitere Infos bekannt geworden. So&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-13T13:18:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"636\" \/>\n\t<meta property=\"og:image:height\" content=\"529\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Surface Duo mit 3 Jahren OS-Updates und freischaltbarem Bootloader\",\"datePublished\":\"2020-08-13T13:18:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/\"},\"wordCount\":230,\"commentCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/microsoft-surface-duo-preis.jpg\",\"keywords\":[\"Bootloader\",\"eigene ROM\",\"freischalten\",\"Microsoft\",\"OS-Update\",\"Surface Duo\",\"Wie lange Updates.\"],\"articleSection\":[\"Android\",\"Hardware\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/\",\"name\":\"Surface Duo mit 3 Jahren OS-Updates und freischaltbarem Bootloader - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/microsoft-surface-duo-preis.jpg\",\"datePublished\":\"2020-08-13T13:18:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/microsoft-surface-duo-preis.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/microsoft-surface-duo-preis.jpg\",\"width\":636,\"height\":529},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/13\\\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Surface Duo mit 3 Jahren OS-Updates und freischaltbarem Bootloader\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Surface Duo mit 3 Jahren OS-Updates und freischaltbarem Bootloader - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/","og_locale":"de_DE","og_type":"article","og_title":"Surface Duo mit 3 Jahren OS-Updates und freischaltbarem Bootloader","og_description":"Gestern haben sich die Meldungen \u00fcber das neue Microsoft Surface Duo regelrecht \u00fcberschlagen im Netz. Wie wir nun wissen, kommt es ab 1.399 Dollar erst einmal in den USA auf den Markt. Jetzt sind aber weitere Infos bekannt geworden. So&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-08-13T13:18:47+00:00","og_image":[{"width":636,"height":529,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Surface Duo mit 3 Jahren OS-Updates und freischaltbarem Bootloader","datePublished":"2020-08-13T13:18:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/"},"wordCount":230,"commentCount":10,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis.jpg","keywords":["Bootloader","eigene ROM","freischalten","Microsoft","OS-Update","Surface Duo","Wie lange Updates."],"articleSection":["Android","Hardware"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/","name":"Surface Duo mit 3 Jahren OS-Updates und freischaltbarem Bootloader - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis.jpg","datePublished":"2020-08-13T13:18:47+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis.jpg","width":636,"height":529},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/13\/surface-duo-mit-3-jahren-os-updates-und-freischaltbarem-bootloader\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Surface Duo mit 3 Jahren OS-Updates und freischaltbarem Bootloader"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/microsoft-surface-duo-preis.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/143131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=143131"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/143131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/143058"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=143131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=143131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=143131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}