{"id":142917,"date":"2020-08-09T10:13:38","date_gmt":"2020-08-09T08:13:38","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=142917"},"modified":"2020-08-09T10:13:38","modified_gmt":"2020-08-09T08:13:38","slug":"google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/","title":{"rendered":"Google Chrome: PWAs \u00fcber die Windows Einstellungen l\u00f6schen kommt ab Version 86"},"content":{"rendered":"<p>Seitdem der Microsoft Edge auf Chromium setzt, hat das Edge Team schon bei sehr vielen Funktionen und Korrekturen im Chromium geholfen. Nun wurde ein Vorschlag unterbreitet, der es erm\u00f6glicht, dass installierte PWAs direkt aus den Einstellungen deinstalliert werden k\u00f6nnen.<\/p>\n<p>Vor einem Jahr etwa hatte man den Chromium Entwicklern vorgeschlagen, dass man installierte PWAs, die bspw. dann im Windows 10 Startmen\u00fc erscheinen auch von dort aus zu deinstallieren, ohne dass man erst im Chrome Browser diese unter chrome:\/\/Apps deinstallieren muss. Aktuell funktioniert dies mit dem Microsoft Edge.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg\" rel=\"lightbox[142917]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-454x360.jpg\" alt=\"\" width=\"454\" height=\"360\" class=\"aligncenter size-medium wp-image-142919\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-454x360.jpg 454w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-735x583.jpg 735w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-259x205.jpg 259w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg 1009w\" sizes=\"auto, (max-width: 454px) 100vw, 454px\" \/><\/a><\/p>\n<p>Unter Einstellungen -> Apps oder Systemsteuerung -> Installierte Programme und Features l\u00e4sst sich die PWA deinstallieren und sie ist dann auch im Edge Browser unter Apps weg, wenn man den Haken gesetzt hatte. Diese Funktion wird nun im Google Chrome 86 auch integriert werden.<\/p>\n<p>Derzeit wird man im Windows 10 Startmen\u00fc -> PWA-Name -> Rechtsklick auf Deinstallieren in die Systemsteuerung verwiesen, doch dort ist die PWA nicht aufgelistet. Das wird sich dann ab Google Chrome 86 \u00e4ndern. Der Entwickler hat auch <a href=\"https:\/\/drive.google.com\/file\/d\/1iy6n0p2pr3YP7hn1J3kgGi34L-LkXY_9\/view\" rel=\"noopener noreferrer\" target=\"_blank\">ein Video davon gemacht<\/a>, welches ihr euch ansehen k\u00f6nnt.<\/p>\n<p>Im <a href=\"https:\/\/chromium-review.googlesource.com\/c\/chromium\/src\/+\/2316848\" rel=\"noopener noreferrer\" target=\"_blank\">Chromium Gerrit<\/a> ist dies nun eingetragen und auch in <a href=\"https:\/\/bugs.chromium.org\/p\/chromium\/issues\/detail?id=957043\" rel=\"noopener noreferrer\" target=\"_blank\">bugs.chromium<\/a> wurde es als Feature f\u00fcr Windows f\u00fcr Chrome 86 gekennzeichnet.<\/p>\n<p>Etwas Interessantes hat <a href=\"https:\/\/www.reddit.com\/r\/chrome\/comments\/i6ccpc\/it_seems_that_the_option_to_uninstall_chrome_pwas\/\" rel=\"noopener noreferrer\" target=\"_blank\">LEOPEVA64<\/a> auf reddit noch geschrieben. &#8222;PS, ein auf Gerrit hochgeladener Patch ist erst dann ein &#8222;Commit&#8220;, wenn das Wort &#8222;MERGED&#8220; in der oberen linken Ecke erscheint&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seitdem der Microsoft Edge auf Chromium setzt, hat das Edge Team schon bei sehr vielen Funktionen und Korrekturen im Chromium geholfen. Nun wurde ein Vorschlag unterbreitet, der es erm\u00f6glicht, dass installierte PWAs direkt aus den Einstellungen deinstalliert werden k\u00f6nnen. Vor&hellip; <\/p>\n","protected":false},"author":134,"featured_media":142919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166],"tags":[21,1842,57,27844,38],"class_list":["post-142917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-browser","tag-deinstallieren","tag-einstellungen","tag-google-chrome","tag-pwa","tag-systemsteuerung"],"wp_featured_image":{"id":142919,"alt_text":"","description":"","media_type":"image","media_details":{"width":1009,"height":800,"file":"2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg","sizes":{"medium":{"file":"google-chrome-pwa-in-einstellungen-deinstallieren-454x360.jpg","width":454,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-454x360.jpg"},"large":{"file":"google-chrome-pwa-in-einstellungen-deinstallieren-735x583.jpg","width":735,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-735x583.jpg"},"thumbnail":{"file":"google-chrome-pwa-in-einstellungen-deinstallieren-259x205.jpg","width":259,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-259x205.jpg"},"wp_review_large":{"file":"google-chrome-pwa-in-einstellungen-deinstallieren-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-320x200.jpg"},"wp_review_small":{"file":"google-chrome-pwa-in-einstellungen-deinstallieren-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-65x65.jpg"},"blog-large":{"file":"google-chrome-pwa-in-einstellungen-deinstallieren-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-642x300.jpg"},"blog-medium":{"file":"google-chrome-pwa-in-einstellungen-deinstallieren-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-306x205.jpg"},"recent-thumb":{"file":"google-chrome-pwa-in-einstellungen-deinstallieren-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-350x316.jpg"},"service-featured":{"file":"google-chrome-pwa-in-einstellungen-deinstallieren-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-600x330.jpg"},"wp_rp_thumbnail":{"file":"google-chrome-pwa-in-einstellungen-deinstallieren-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":142917,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg"},"commentcount":3,"wp_comments":[{"id":142814,"parent":0,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=96&d=mm&r=g"},"date":"2020-08-09T13:14:57","cld_nonce":"82f011626f","content":{"rendered":"<p>Habe auch schon bemerkt, dass das Edge Developer Team mit ziemlicher Begeisterung an ihrem &#8222;New Edge&#8220; arbeiten. F\u00fcr Vorschl\u00e4ge aus der Community ist man immer offen.<\/p>\n"},"status":"1"},{"id":142827,"parent":0,"author":2746,"author_name":"Lurtz","author_email":"tobias.marty@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9893b41a75cc28a7fc7a768a582be10689f8981402cef19a7e211c264f972fdd?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9893b41a75cc28a7fc7a768a582be10689f8981402cef19a7e211c264f972fdd?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9893b41a75cc28a7fc7a768a582be10689f8981402cef19a7e211c264f972fdd?s=96&d=mm&r=g"},"date":"2020-08-09T17:15:29","cld_nonce":"82f011626f","content":{"rendered":"<p>F\u00fcr Chromium-User nat\u00fcrlich sehr sch\u00f6n wie hier Betriebssystem und Browser mehr zusammenwachsen. F\u00fcr alternative Browser wie Firefox nat\u00fcrlich eine Hiobsbotschaft, die werden sich immer &#8222;fremder&#8220; anf\u00fchlen.<br \/>\nWas h\u00e4tte das f\u00fcr einen sch\u00f6nen Boost geben k\u00f6nnen, h\u00e4tte MS sich f\u00fcr Gecko entschieden. Aber da wurden in der Vergangenheit sicher auch zu viele Fehlentscheidungen bei Mozilla getroffen, der Desktop-Firefox hat bis heute ja noch nicht ma einen PWA-Modus.<\/p>\n"},"status":"1"},{"id":142844,"parent":142827,"author":0,"author_name":"Ichhalt","author_email":"m.b.1991@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=96&d=mm&r=g"},"date":"2020-08-09T23:19:51","cld_nonce":"82f011626f","content":{"rendered":"<p>Das w\u00e4re eine fatale Entscheidung gewesen. Microsoft hatte 2 m\u00f6gliche Optionen. Entweder die eigene Engine weiterentwickeln oder zur Konkurrenz wechseln. Sie haben den einfachen Weg gew\u00e4hlt. Chromium ist zwar Open Source aber Google hat die Finger drauf und wenn denen was nicht passt wissen wir was rauskommt. Google Dienste die regelm\u00e4\u00dfig aufgrund von &#8222;Problemen&#8220; nicht richtig im Edge funktionieren. Ich sehe das erst als Anfang. Google hat durchaus die Macht die Engine f\u00fcr den Edge zu sperren. Damit w\u00fcrden sie sich zwar auch schaden aber das juckt im Endeffekt nur Microsoft und deren Nutzer, denn die meisten verwenden Chrome und das wird sich auch nicht mehr \u00e4ndern.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Google Chrome: PWAs \u00fcber die Windows Einstellungen l\u00f6schen kommt ab Version 86 - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google Chrome: PWAs \u00fcber die Windows Einstellungen l\u00f6schen kommt ab Version 86\" \/>\n<meta property=\"og:description\" content=\"Seitdem der Microsoft Edge auf Chromium setzt, hat das Edge Team schon bei sehr vielen Funktionen und Korrekturen im Chromium geholfen. Nun wurde ein Vorschlag unterbreitet, der es erm\u00f6glicht, dass installierte PWAs direkt aus den Einstellungen deinstalliert werden k\u00f6nnen. Vor&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-09T08:13:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1009\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Google Chrome: PWAs \u00fcber die Windows Einstellungen l\u00f6schen kommt ab Version 86\",\"datePublished\":\"2020-08-09T08:13:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/\"},\"wordCount\":241,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg\",\"keywords\":[\"Deinstallieren\",\"Einstellungen\",\"Google Chrome\",\"PWA\",\"systemsteuerung\"],\"articleSection\":[\"Browser\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/\",\"name\":\"Google Chrome: PWAs \u00fcber die Windows Einstellungen l\u00f6schen kommt ab Version 86 - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg\",\"datePublished\":\"2020-08-09T08:13:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg\",\"width\":1009,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/08\\\/09\\\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google Chrome: PWAs \u00fcber die Windows Einstellungen l\u00f6schen kommt ab Version 86\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Google Chrome: PWAs \u00fcber die Windows Einstellungen l\u00f6schen kommt ab Version 86 - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/","og_locale":"de_DE","og_type":"article","og_title":"Google Chrome: PWAs \u00fcber die Windows Einstellungen l\u00f6schen kommt ab Version 86","og_description":"Seitdem der Microsoft Edge auf Chromium setzt, hat das Edge Team schon bei sehr vielen Funktionen und Korrekturen im Chromium geholfen. Nun wurde ein Vorschlag unterbreitet, der es erm\u00f6glicht, dass installierte PWAs direkt aus den Einstellungen deinstalliert werden k\u00f6nnen. Vor&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-08-09T08:13:38+00:00","og_image":[{"width":1009,"height":800,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Google Chrome: PWAs \u00fcber die Windows Einstellungen l\u00f6schen kommt ab Version 86","datePublished":"2020-08-09T08:13:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/"},"wordCount":241,"commentCount":3,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg","keywords":["Deinstallieren","Einstellungen","Google Chrome","PWA","systemsteuerung"],"articleSection":["Browser"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/","name":"Google Chrome: PWAs \u00fcber die Windows Einstellungen l\u00f6schen kommt ab Version 86 - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg","datePublished":"2020-08-09T08:13:38+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg","width":1009,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/08\/09\/google-chrome-pwas-ueber-die-windows-einstellungen-loeschen-kommt-ab-version-86\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Google Chrome: PWAs \u00fcber die Windows Einstellungen l\u00f6schen kommt ab Version 86"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/08\/google-chrome-pwa-in-einstellungen-deinstallieren.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/142917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=142917"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/142917\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/142919"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=142917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=142917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=142917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}