{"id":141000,"date":"2020-07-02T07:46:53","date_gmt":"2020-07-02T05:46:53","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=141000"},"modified":"2020-07-03T14:08:23","modified_gmt":"2020-07-03T12:08:23","slug":"windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/","title":{"rendered":"Windows 10 20161 im Dev-Kanal + Server ISO, erste SDK, ADK und WDK"},"content":{"rendered":"<p>Es steht eine neue Windows 10 Insider Build (Codename Iron) im Dev-Kanal (ehem. Fast-Ring) mit einem doch ordentlichen Versionssprung zum Download bereit. Die Windows 10 20161.1000, genauer die 10.0.20161.1000 rs_prerelease vom 27.06. kann nun getestet werden.<\/p>\n<p>Diesmal auch gleich mit dabei eine neue Windows Server Insider Preview ISO bzw. VHDX sowie die erste SDK, ADK und WDK seit dem Wechsel zur 20xxx. Sicherlich f\u00fcr die Entwickler interessant. Auch wir werden wieder die ISO-Dateien sammeln und werden dann den Link hier hineinstellen. <strong>[Update]:<\/strong> Da ist der <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-iso-esd-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">Link zu den ISOs<\/a> auch schon.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/07\/windows-10-20161.jpg\" rel=\"lightbox[141000]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/07\/windows-10-20161-500x313.jpg\" alt=\"\" width=\"500\" height=\"313\" class=\"aligncenter size-medium wp-image-141021\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/07\/windows-10-20161-500x313.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/07\/windows-10-20161-810x506.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/07\/windows-10-20161-306x191.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/07\/windows-10-20161-320x200.jpg 320w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/07\/windows-10-20161.jpg 1080w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Aber kommen wir zu den \u00c4nderungen in der neuen Windows 10 20161. Einige neue Funktionen wurden eingebaut, die aber noch nicht allen Insidern zur Verf\u00fcgung stehen. Diese will man nach und nach bereitstellen.<\/p>\n<ul>\n<li>Das Startmen\u00fc \u00e4ndert sich nun im Aussehen. Wie es schon einmal angek\u00fcndigt wurde. Die Farbe kann \u00fcber Einstellungen -> Personalisierung -> Farbe angepasst werden.<\/li>\n<li>Alt + Tab kann nun nicht nur zwischen Apps und Programmen, sondern auch zwischen offenen Tabs im Browser wechseln. Die Alt + Tab Funktion kann unter Einstellungen -> System -> Multitasking angepasst, oder abgeschaltet werden<\/li>\n<li>Die Taskleiste kann besser angepasst werden. &#8222;Wir m\u00f6chten unseren Kunden dabei helfen, vom ersten Tag an das Beste aus ihren PCs herauszuholen, und das beginnt damit, dass wir ein saubereres, personalisierteres, sofort einsatzbereites Erlebnis bieten, um Ihnen die gew\u00fcnschten Inhalte und weniger Unordnung zu bieten.&#8220; Bitte beachten Sie, dass diese Ma\u00dfnahmen <strong>auf die Erstellung neuer Konten<\/strong> oder Szenarien f\u00fcr die Erstanmeldung beschr\u00e4nkt sind.<\/li>\n<li>Die Einstellungen wurden \u00fcberarbeitet. So zum Beispiel Einstellungen -> System -> Info (\u00dcber) Informationen daraus k\u00f6nnen nun kopiert werden.<\/li>\n<li>Auch neu hinzugekommen: <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-sandbox-neue-gruppenrichtlinien-die-man-aktivieren-oder-deaktivieren-kann\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows Sandbox \u2013 Neue Gruppenrichtlinien, die man aktivieren oder deaktivieren kann<\/a><\/li>\n<\/ul>\n<h3>Bekannte Probleme in der Windows 10 20161<\/h3>\n<ul>\n<li>Wir arbeiten an der Behebung eines Problems, das einige Systeme mit einem HYPERVISOR_ERROR-Bugcheck zum Absturz brachte.<\/li>\n<li>Wir untersuchen Berichte, dass der Update-Prozess beim Versuch, einen neuen Build zu installieren, f\u00fcr l\u00e4ngere Zeit hing.<\/li>\n<li>Uns ist ein Problem bekannt, bei dem Notepad m\u00f6glicherweise Dateien nicht wieder \u00f6ffnen kann, die w\u00e4hrend eines PC-Neustarts automatisch gespeichert wurden (wenn diese Option in den Einstellungen aktiviert ist). Dokumente k\u00f6nnen von %localappdata%\\Notepad wiederhergestellt werden. &#8211; Wir untersuchen Berichte, dass der Bildschirm nach dem Upgrade auf die vorherige Version dunkler wird.<\/li>\n<li>Uns ist ein Problem bekannt, bei dem der Task-Manager auf der Registerkarte Leistung eine CPU-Auslastung von 0,00 GHz meldet.<\/li>\n<li>Wir untersuchen Berichte, dass beim Dr\u00fccken der Leertaste w\u00e4hrend der Verwendung des koreanischen IME in bestimmten Anwendungen das letzte Zeichen gel\u00f6scht wird.<\/li>\n<li>Wir arbeiten an der Feinabstimmung der Kachelanimationen in Start, um Farbabweichungen zu vermeiden.<\/li>\n<li>F\u00fcr Insider mit der oben erw\u00e4hnten neuen Alt+Tab-Erfahrung beachten Sie bitte, dass die Einstellung unter Einstellungen > System > Multitasking, Alt+Tab auf &#8222;Nur Fenster \u00f6ffnen&#8220; zu setzen, derzeit nicht funktioniert.<\/li>\n<\/ul>\n<h3>Behobene Probleme in der Windows 10 20161<\/h3>\n<ul>\n<li>Wir haben ein Problem behoben, das dazu f\u00fchrte, dass Insider bei der Verbindung und Interaktion mit einem <strong>Xbox-Controller<\/strong> Fehlerpr\u00fcfungen durchf\u00fchrten.<\/li>\n<li>Wir haben ein Problem behoben, das dazu f\u00fchrte, dass einige Spiele und Anwendungen beim Start abst\u00fcrzten oder sich nicht installieren lie\u00dfen.<\/li>\n<li>Wir haben ein Problem behoben, das dazu f\u00fchrte, dass Microsoft Edge nicht zu Websites navigiert, wenn WDAG auf den letzten 2 Builds aktiviert war.<\/li>\n<li>Wir haben ein Problem behoben, das die Abmeldezeit in den letzten Builds erh\u00f6ht hat.<\/li>\n<li>Wir haben ein Problem mit dem Chinese Pinyin IME behoben, das dazu f\u00fchrte, dass Sie nach der Einstellung Ihrer bevorzugten IME-Symbolleistenausrichtung diese nach dem Neustart Ihres PCs m\u00f6glicherweise nicht mehr \u00e4ndern k\u00f6nnen.<\/li>\n<li>Wir haben ein Problem behoben, das dazu f\u00fchrte, dass &#8222;Reset this PC&#8220; immer den Fehler &#8220; Es gab ein Problem beim Zur\u00fccksetzen dieses PCs&#8220; anzeigte, wenn er in den letzten Builds aus den Einstellungen heraus gestartet wurde.<\/li>\n<li>Wir haben ein Problem behoben, das dazu f\u00fchrte, dass einige Bluetooth-Ger\u00e4te in den Einstellungen der letzten paar Builds ihren Akkustand nicht mehr anzeigten.<\/li>\n<li>Wir haben ein Problem behoben, bei dem die Einstellungen abst\u00fcrzten, wenn Sie zu Einstellungen > Privatsph\u00e4re > Mikrofon gingen, w\u00e4hrend eine win32-App Audio aufnahm.<\/li>\n<li>Wir haben ein Problem behoben, bei dem die Einstellungen abst\u00fcrzten, wenn in den Toneinstellungen in der Eingabedropdown-Liste &#8222;keine Eingabeger\u00e4te gefunden&#8220; angezeigt wurde und man darauf klickte.<\/li>\n<li>Wir haben ein Problem behoben, bei dem das Dialogfeld beim Hinzuf\u00fcgen eines Druckers abst\u00fcrzen konnte, wenn Sie in neueren Versionen zum Dialogfeld &#8222;Druckertreiber hinzuf\u00fcgen&#8220; navigierten.<\/li>\n<li>Wir haben ein Problem im Zusammenhang mit Grafiken behoben, das bei einigen Benutzern zu Fehlerpr\u00fcfungen f\u00fchrte.<\/li>\n<li><a href=\"https:\/\/blogs.windows.com\/windowsexperience\/2020\/07\/01\/announcing-windows-10-insider-preview-build-20161\/\" rel=\"noopener noreferrer\" target=\"_blank\">blogs.windows<\/a><\/li>\n<\/ul>\n<h3>Download der Server Preview ISO, SDK, ADK und WDK<\/h3>\n<p>Die neue Server ISO \/ VHDX bzw. die SDK, ADK oder WDK + EWDK kann entweder hier \u00fcber die Seite <a href=\"https:\/\/tb.32767.ga\/products.php?search=20161&#038;prod=all\" rel=\"noopener noreferrer\" target=\"_blank\">tb.32767.ga\/20161<\/a> (Anmeldung als Insider ist auch hier notwendig), oder \u00fcber die <a href=\"https:\/\/www.microsoft.com\/en-us\/software-download\/windowsinsiderpreviewSDK\" rel=\"noopener noreferrer\" target=\"_blank\">Microsoft-Seite<\/a> heruntergeladen werden. [Update]: Jetzt sind sie da<\/p>\n<h3>Windows 10 Tutorials und Hilfe<\/h3>\n<p>In unserem <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 Wiki<\/a> findet ihr sehr viele hilfreiche Tipps und Tricks. Falls ihr Fragen habt, dann stellt diese ganz einfach bei uns im <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewforum.php?f=326\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Forum<\/strong><\/a>.<\/p>\n<ul>\n<li><strong>Installationsmedien:<\/strong> Aktuelle Installationsdateien findet ihr hier immer in der rechten Sidebar. <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/12\/11\/windows-10-19041-iso-esd-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004 ISO (19041)<\/a>, oder <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/08\/27\/windows-10-1909-18363-iso-esd-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">1909 ISO (18363)<\/a> <\/li>\n<li><strong>Installation:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_clean_neu_installieren\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 Clean installieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_1909_neu_installieren_Anleitung_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 1909 neu installieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_2004_neu_installieren_Anleitung_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 2004 neu installieren<\/a><\/li>\n<li><strong>Aktuelle Probleme mit der:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/04\/11\/windows-10-2004-bekannte-und-behobene-probleme\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004<\/a>\n    <\/li>\n<li><strong>Reparaturen:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Inplace_Upgrade_Windows_10_schnell_reparieren\" rel=\"noopener noreferrer\" target=\"_blank\">Inplace Upgrade Reparatur<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_reparieren_wiederherstellen_mit_DISM_Inplace_Upgrade_und_vielen_weiteren_Varianten\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 reparieren  \u00fcber DISM, sfc und weiteres<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_Update_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Windows Update reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Startmen%C3%BC_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Startmen\u00fc reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Apps_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Apps reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Store_reparieren\" rel=\"noopener noreferrer\" target=\"_blank\">Store reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Netzwerkverbindung_-adapter_reparieren_zur%C3%BCcksetzen_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Netzwerk reparieren<\/a><\/li>\n<li><strong>Anmeldung:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_automatisch_anmelden_ohne_Passworteingabe\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 automatische Anmeldung<\/a><\/li>\n<li><strong>Entfernen, Deinstallieren<\/strong>:  <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Apps_entfernen_deinstallieren\" rel=\"noopener noreferrer\" target=\"_blank\">Apps deinstallieren<\/a><\/li>\n<li><strong>Datei Explorer:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Dieser_PC_Ordner_entfernen_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Ordner unter Dieser PC entfernen<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Datei_Explorer_Windows_10_Netzwerk_Heimnetzgruppe_OneDrive_entfernen\" rel=\"noopener noreferrer\" target=\"_blank\">Netzwerk, OneDrive u.a. im Explorer entfernen<\/a><\/li>\n<li><strong>Richtige Nutzung:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Das_Windows_10_Startmen%C3%BC_richtig_einrichten_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Startmen\u00fc richtig nutzen<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Die_Suche_in_Windows_10_richtig_nutzen\" rel=\"noopener noreferrer\" target=\"_blank\">Suche richtig nutzen<\/a>,<\/li>\n<li><strong>Wichtig:<\/strong> In jedem Tutorial steht, f\u00fcr welche Version es geeignet ist.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Es steht eine neue Windows 10 Insider Build (Codename Iron) im Dev-Kanal (ehem. Fast-Ring) mit einem doch ordentlichen Versionssprung zum Download bereit. Die Windows 10 20161.1000, genauer die 10.0.20161.1000 rs_prerelease vom 27.06. kann nun getestet werden. Diesmal auch gleich mit&hellip; <\/p>\n","protected":false},"author":134,"featured_media":111270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[14697,68111,75156,8444,9816,4579,15197,75814],"class_list":["post-141000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","tag-adk","tag-aktuelle-insider","tag-dev-kanal","tag-fast-ring","tag-neue-insider","tag-sdk","tag-wdk","tag-windows-10-20161"],"wp_featured_image":{"id":111270,"alt_text":"","description":"","media_type":"image","media_details":{"width":558,"height":401,"file":"2018\/11\/windows-insider-update-app-einstellungen-logo.png","sizes":{"thumbnail":{"file":"windows-insider-update-app-einstellungen-logo-285x205.png","width":285,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-285x205.png"},"medium":{"file":"windows-insider-update-app-einstellungen-logo-500x360.png","width":500,"height":360,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-500x360.png"},"wp_review_large":{"file":"windows-insider-update-app-einstellungen-logo-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-320x200.png"},"wp_review_small":{"file":"windows-insider-update-app-einstellungen-logo-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-65x65.png"},"blog-large":{"file":"windows-insider-update-app-einstellungen-logo-558x300.png","width":558,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-558x300.png"},"blog-medium":{"file":"windows-insider-update-app-einstellungen-logo-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-306x205.png"},"recent-thumb":{"file":"windows-insider-update-app-einstellungen-logo-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-350x316.png"},"service-featured":{"file":"windows-insider-update-app-einstellungen-logo-558x330.png","width":558,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-558x330.png"},"wp_rp_thumbnail":{"file":"windows-insider-update-app-einstellungen-logo-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":118123,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png"},"commentcount":83,"wp_comments":[{"id":138878,"parent":0,"author":6251,"author_name":"MANU","author_email":"manu.beitz@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=96&d=mm&r=g"},"date":"2020-07-02T08:14:22","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hardware-beschleunigte GPU-Planung<\/p>\n<p>ist auto. auf &#8222;Ein&#8220; gestellt.<\/p>\n"},"status":"1"},{"id":138879,"parent":138878,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T08:19:09","cld_nonce":"b6d6726996","content":{"rendered":"<p>war (bei mir) auch bei der vorherigen Version so &#8211; durch Aktualisierung hat sich das auch nicht ge\u00e4ndert<\/p>\n"},"status":"1"},{"id":138880,"parent":0,"author":3965,"author_name":"peboka","author_email":"h.p.borcherd@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/87cc760c460d0be4d31610073ff407cd5be3750bccdfeec211e72012ec4666d9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/87cc760c460d0be4d31610073ff407cd5be3750bccdfeec211e72012ec4666d9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/87cc760c460d0be4d31610073ff407cd5be3750bccdfeec211e72012ec4666d9?s=96&d=mm&r=g"},"date":"2020-07-02T08:19:46","cld_nonce":"b6d6726996","content":{"rendered":"<p>schon installiert und l\u00e4uft<\/p>\n"},"status":"1"},{"id":138881,"parent":138879,"author":6251,"author_name":"MANU","author_email":"manu.beitz@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=96&d=mm&r=g"},"date":"2020-07-02T08:22:45","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei mir nicht.<\/p>\n"},"status":"1"},{"id":138882,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T08:26:20","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8222;Alte&#8220; Systemsteuerung ( wer es noch braucht \/brauchen sollte z.B. f\u00fcr Computerschutz etc.)<\/p>\n<p>Verkn\u00fcpfung erstellen &#8211; C:\\Windows\\explorer.exe shell:ControlPanelFolder hineinkopieren &#8211; Namen vergeben und dann (nachtr\u00e4glich) noch ein Icon ausw\u00e4hlen<\/p>\n<p>in den neuen Einstellungen findet man das auch schon : Einstellungen \/ System \/ Info &#8211; rechte Seite unter Verwandte Einstellungen auf Systemschutz klicken &#8211; dann kommt man in die &#8222;Systemeigenschaften&#8220; f\u00fcr Computername \/ Hardware \/ Erweitert \/ Computerschutz und Remote<\/p>\n"},"status":"1"},{"id":138883,"parent":0,"author":0,"author_name":"Martin","author_email":"bk.bezahlen@gmx.at","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bc16ef53683a2840933b64e7e9fbc7918533492ddcc9d89a43a8294bcb87c87a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bc16ef53683a2840933b64e7e9fbc7918533492ddcc9d89a43a8294bcb87c87a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bc16ef53683a2840933b64e7e9fbc7918533492ddcc9d89a43a8294bcb87c87a?s=96&d=mm&r=g"},"date":"2020-07-02T08:44:12","cld_nonce":"b6d6726996","content":{"rendered":"<p>Haben die fast ring eine Timebomb und Wasserzeichen?<\/p>\n"},"status":"1"},{"id":138884,"parent":138883,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-07-02T08:49:46","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wie immer. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138885,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T08:54:33","cld_nonce":"b6d6726996","content":{"rendered":"<p>20161.1000 X64 Home, Pro &#8211; auch als N-Version<br \/>\n(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<\/p>\n<p> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138886,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T08:55:07","cld_nonce":"b6d6726996","content":{"rendered":"<p>20161.1000 X86 Home, Pro &#8211; auch als N-Version<\/p>\n<p>20161.1000.200627-1754.RS_PRERELEASE_CLIENTCOMBINED_UUP_X86FRE_DE-DE.ISO<br \/>\n2,92 GB (3.138.613.248 Bytes)<br \/>\n<a href=\"https:\/\/t1p.de\/u8hh\" rel=\"nofollow ugc\">https:\/\/t1p.de\/u8hh<\/a><br \/>\n <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138887,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T08:55:28","cld_nonce":"b6d6726996","content":{"rendered":"<p>20161.1000 ARM Home, Pro<br \/>\n(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<br \/>\n <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138889,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T08:55:54","cld_nonce":"b6d6726996","content":{"rendered":"<p>20161.1000 ARM Enterprise (ohne N-Version, ohne ESD):<br \/>\n(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<br \/>\n <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138890,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T08:56:12","cld_nonce":"b6d6726996","content":{"rendered":"<p>20161.1000 X64 Enterprise (ohne N-Version, ohne ESD):<br \/>\n(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<br \/>\n <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138891,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T08:56:31","cld_nonce":"b6d6726996","content":{"rendered":"<p>20161.1000 X86 Enterprise (ohne N-Version, ohne ESD):<br \/>\n(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<br \/>\n <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138893,"parent":138884,"author":0,"author_name":"Martin","author_email":"bk.bezahlen@gmx.at","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bc16ef53683a2840933b64e7e9fbc7918533492ddcc9d89a43a8294bcb87c87a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bc16ef53683a2840933b64e7e9fbc7918533492ddcc9d89a43a8294bcb87c87a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bc16ef53683a2840933b64e7e9fbc7918533492ddcc9d89a43a8294bcb87c87a?s=96&d=mm&r=g"},"date":"2020-07-02T09:09:07","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich merke mir das nie. Welche Versioen haben keine Timebomb bzw Wasserzeichen neben der 2004\/2009?<\/p>\n"},"status":"1"},{"id":138898,"parent":138893,"author":5243,"author_name":"eRaz0r","author_email":"spam84@ymail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=96&d=mm&r=g"},"date":"2020-07-02T09:41:28","cld_nonce":"b6d6726996","content":{"rendered":"<p>Release Builds im RP\/Production Ring, wie schon seit 5 Jahren unter Windows 10. Fast\/Slow &#8211; DEV\/BETA Builds haben in der Regel IMMER eine Timebomb, da sie keine fertigen Versionen sind &#8230;.<\/p>\n<p>Bleib einfach im RP Channel und du wirst niemals ein Wasserzeichen zu Gesicht bekommen, wenn du dich f\u00fcr Insider Versionen interessierst. Dann braucht man auch nicht immer Fragen ;D<\/p>\n"},"status":"1"},{"id":138900,"parent":0,"author":0,"author_name":"Armin","author_email":"charmin.armin@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/58cf8f478910858fc967898cac9e00d77e1a04c7680cbfe11156a65db5a235e2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/58cf8f478910858fc967898cac9e00d77e1a04c7680cbfe11156a65db5a235e2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/58cf8f478910858fc967898cac9e00d77e1a04c7680cbfe11156a65db5a235e2?s=96&d=mm&r=g"},"date":"2020-07-02T09:54:22","cld_nonce":"b6d6726996","content":{"rendered":"<p>Windows Server Insider (angemeldet) liefert bei mir via TechBench nur &#8222;Bad Request&#8220; und bei Microsoft Build 20152<\/p>\n"},"status":"1"},{"id":138904,"parent":0,"author":0,"author_name":"Alex","author_email":"alexriedenburg@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ce98e131f56bf3379713b8f73eaa9e3cfed362fb83abd2d298e76c37cdc50ba3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ce98e131f56bf3379713b8f73eaa9e3cfed362fb83abd2d298e76c37cdc50ba3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ce98e131f56bf3379713b8f73eaa9e3cfed362fb83abd2d298e76c37cdc50ba3?s=96&d=mm&r=g"},"date":"2020-07-02T10:28:51","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wer die neuen Sachen mit dem ViveTool freischalten m\u00f6chte (alles getestet und funktioniert):<\/p>\n<p>Neue Info Ansicht Einstellungen<br \/>\nViVeTool.exe addconfig 25175482 2<\/p>\n<p>Start-Men\u00fc neues Aussehen (ben\u00f6tigt Neustart)<br \/>\nViveTool.exe addconfig 23615618 2<\/p>\n<p>Alt Tab Browser (neue Einstellungen)<br \/>\nViveTool.exe addconfig 25478404 2<br \/>\nViveTool.exe addconfig 25292146 2<\/p>\n<p>Benachrichtigungen neues Aussehen<br \/>\nViveTool.exe addconfig 23282664 2<br \/>\nViveTool.exe addconfig 23447524 2<br \/>\nViveTool.exe addconfig 23454425 2<\/p>\n<p>Standard-Apps Suche<br \/>\nViveTool.exe addconfig 19400537 2<\/p>\n<p>Funktioniert ebenfalls noch:<\/p>\n<p>Mediensteuerung Lautst\u00e4rke (ben\u00f6tigt Neustart)<br \/>\nViVeTool.exe addconfig 23403403 2<br \/>\nViVeTool.exe addconfig 23674478 2<\/p>\n<p>Neuigkeiten-Seite in den Update-Einstellungen (zeigt aber nur bei en-us Sprache was an)<br \/>\nViVeTool.exe addconfig 20446796 2<\/p>\n<p>Aufgeteilte Ansicht Konten-Einstellungen (Familiengruppe, Personen auf diesem Ger\u00e4t)<br \/>\nViVeTool.exe addconfig 20271969 2<\/p>\n"},"status":"1"},{"id":138907,"parent":138904,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-07-02T10:50:49","cld_nonce":"b6d6726996","content":{"rendered":"<p>Danke Alex.<\/p>\n<p>F\u00fcr die, die mit den Befehlen nichts anfangen k\u00f6nnen<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/04\/10\/mit-vive-vivetool-versteckte-funktionen-in-der-windows-10-aktivieren-oder-deaktivieren\/\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2020\/04\/10\/mit-vive-vivetool-versteckte-funktionen-in-der-windows-10-aktivieren-oder-deaktivieren\/<\/a><\/p>\n"},"status":"1"},{"id":138911,"parent":138882,"author":3170,"author_name":"McIcke","author_email":"mcicke@gmx.eu","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d51e8d2d2e9cecc46ffc9f0a448d34b23a925a2518cc2b7f8b2de1daa8e0afab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d51e8d2d2e9cecc46ffc9f0a448d34b23a925a2518cc2b7f8b2de1daa8e0afab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d51e8d2d2e9cecc46ffc9f0a448d34b23a925a2518cc2b7f8b2de1daa8e0afab?s=96&d=mm&r=g"},"date":"2020-07-02T12:03:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>Alternative:<br \/>\nWindows-Taste + Pause dr\u00fccken, dann findet man unter &#8218;System&#8216; links oben die &#8218;Startseite der Systemsteuerung&#8216;<\/p>\n"},"status":"1"},{"id":138912,"parent":0,"author":0,"author_name":"Nashman01","author_email":"big_daddy_sr@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b24526e9319e13045f658da7763ea4ee68ab59df70a2c600a184140c80cbdc99?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b24526e9319e13045f658da7763ea4ee68ab59df70a2c600a184140c80cbdc99?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b24526e9319e13045f658da7763ea4ee68ab59df70a2c600a184140c80cbdc99?s=96&d=mm&r=g"},"date":"2020-07-02T12:08:20","cld_nonce":"b6d6726996","content":{"rendered":"<p>Danke\ud83d\ude0a<\/p>\n<p>werd ich heute mal testen, aber erst nachdem ich meinen Xbox Controller gestetet hab \ud83d\ude09 <\/p>\n<p><i>gepostet mit der <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.deskmodder\" rel=\"nofollow ugc\">Deskmodder.de-App f\u00fcr Android<\/a><\/i><\/p>\n"},"status":"1"},{"id":138913,"parent":138882,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T12:33:24","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei mir nicht, da kome ich h\u00f6chstens wieder in die &#8222;neuen&#8220; Einstellungen &#8211; System &#8211; Info<\/p>\n"},"status":"1"},{"id":138914,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T12:50:15","cld_nonce":"b6d6726996","content":{"rendered":"<p>Juhu !!! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/><br \/>\nDiese Build l\u00e4\u00dft sich auch wieder auf den Lenovo-Notebooks der R-, T-, W- und X-Serien installieren !!! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/><br \/>\nM\u00f6glicherweise haben meine Eintr\u00e4ge (und nat\u00fcrlich die von Anderen) im Feedback-Hub und die Telemetrie-Daten meiner \u00fcberaus vielen Installations-(Fehl-)Versuche ja geholfen, das Problem zu l\u00f6sen &#8230;<br \/>\nAuch die &#8222;alte&#8220; Systemsteuerung ist nach wie vor vorhanden: Mit rechter Maustaste auf den Desktop -&gt; Anpassen -&gt; Designs -&gt; Desktopsymboleinstellungen -&gt; (eventuell ben\u00f6tigte) Haken setzen -&gt; OK.<br \/>\nOb und falls ja, welche der neuen Optionen nutzbar sind, teste ich sp\u00e4ter mal aus &#8211; irgendwann &#8230; Vielleicht &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138915,"parent":138913,"author":3170,"author_name":"McIcke","author_email":"mcicke@gmx.eu","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d51e8d2d2e9cecc46ffc9f0a448d34b23a925a2518cc2b7f8b2de1daa8e0afab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d51e8d2d2e9cecc46ffc9f0a448d34b23a925a2518cc2b7f8b2de1daa8e0afab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d51e8d2d2e9cecc46ffc9f0a448d34b23a925a2518cc2b7f8b2de1daa8e0afab?s=96&d=mm&r=g"},"date":"2020-07-02T12:55:42","cld_nonce":"b6d6726996","content":{"rendered":"<p>Sonderbar! K\u00f6nnte bei mir deshalb gezeigt werden, weil ich seit der Umstellung vom Windows 7 auf W10 ausschlie\u00dflich Inplace-Upgrades, niemals eine Neuinstallation ausf\u00fchre.<br \/>\nGilt bis heute, auch bei der 21H1.20161.<\/p>\n"},"status":"1"},{"id":138917,"parent":138913,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T13:11:02","cld_nonce":"b6d6726996","content":{"rendered":"<p>naja, so wichtig isses ja (noch) nicht- Clean Install der 20161 habe ich auch nicht gemacht, Aktualisierung nur \u00fcber WU. Ich denke das die ja auch daran noch weiter &#8222;arbeiten&#8220; was die &#8222;alte&#8220; betrifft <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138918,"parent":138914,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T13:15:24","cld_nonce":"b6d6726996","content":{"rendered":"<p>dann probier mal aus der alten Systemsteuerung z.B. direkt in den Computerschutz zu kommen <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138920,"parent":138918,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T13:29:57","cld_nonce":"b6d6726996","content":{"rendered":"<p>@Manny<br \/>\nWozu dieser Umweg? Rechte Maustaste auf &#8222;Dieser PC&#8220; -&gt; Eigenschaften (vorausgesetzt, das Symbol liegt auf dem Desktop &#8211; und nicht etwa nur ein l\u00e4ppischer Link) &#8230; Da steht er links in der Liste &#8230;<br \/>\nIst in etwa der gleiche Aufruf wie \u00fcber (alte) Systemsteuerung -&gt; System (hier nur eben noch einen Klick weiter) &#8230;<\/p>\n"},"status":"1"},{"id":138921,"parent":138918,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T13:44:20","cld_nonce":"b6d6726996","content":{"rendered":"<p>N\u00f6, (bei mir) funktioniert es so nicht, aber egal &#8211; wie ich schon schrieb so wichtig ist das ja nicht<\/p>\n"},"status":"1"},{"id":138922,"parent":138882,"author":5243,"author_name":"eRaz0r","author_email":"spam84@ymail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=96&d=mm&r=g"},"date":"2020-07-02T13:54:09","cld_nonce":"b6d6726996","content":{"rendered":"<p>2004 Clean installiert &#8211; Upgrade per WU auf 20152 und nun auf die 20161 &#8211; Systemsteuerung funktioniert &#8222;ohne&#8220; Workaround absolut einwandfrei.<\/p>\n"},"status":"1"},{"id":138923,"parent":138921,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T13:56:49","cld_nonce":"b6d6726996","content":{"rendered":"<p>Also ich hab das jetzt auf mehreren Rechenknechten &#8211; Pro und Home, 32- und auch 64-Bit &#8211; ausprobiert &#8230; ist so wie seit XP\/2000-Zeiten: Rechts auf Arbeitsplatz (neu: Dieser PC) und Eigenschaften &#8211; schon ist man im &#8222;System&#8220; &#8230;<br \/>\nHast Du manchmal Dein System wieder &#8222;kastriert&#8220; ??? Wie auch immer &#8211; macht nichts, wenn&#8217;s nichts macht &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138934,"parent":138921,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T17:07:51","cld_nonce":"b6d6726996","content":{"rendered":"<p>@Manny<br \/>\nDu wei\u00dft schon, da\u00df da jetzt was auf Dich zu kommt &#8211; weil: Du hast Recht !!! Und wer Recht hat, gibt Einen aus!<\/p>\n<p>Also: Auf einem meiner vielen Test-Rechner kam jetzt auch diese neumodische, langweilige &#8222;System&#8220;-Anzeige &#8211; gleich, auf welchem Weg die aufgerufen wurde &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":-(\" class=\"wp-smiley\" \/><br \/>\nDort ist aber auch der (ehemalige) Computerschutz sofort zug\u00e4nglich: Der hei\u00dft nur jetzt &#8222;Systemschutz&#8220; und steht ganz rechts unter &#8222;Verwandte Einstellungen&#8220; (an 4. Stelle) &#8230;<br \/>\nEs lebe das gro\u00dfe Suchen! Ich werde das Gef\u00fchl nicht los, da\u00df alle User systematisch in die Irre \/ in den Wahnsinn getrieben werden sollen &#8230;<br \/>\nSt\u00e4ndig wird irgend was verschlimmbessert &#8211; ohne ersichtlichen Sinn und Zweck !!!<br \/>\nNa ja, zumindest kommt man (noch) dran &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138935,"parent":138921,"author":4241,"author_name":"Ben","author_email":"benderarsch@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=96&d=mm&r=g"},"date":"2020-07-02T17:13:21","cld_nonce":"b6d6726996","content":{"rendered":"<p>Deshalb giebt es doch die A\/B Bests um die User zu Nerven. Denn die einen reagieren genervt auf A und die anderen eben auf B. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138936,"parent":138921,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T17:19:47","cld_nonce":"b6d6726996","content":{"rendered":"<p>Da ist was dran !!! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_cool.gif\" alt=\"8-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138937,"parent":138921,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T18:00:55","cld_nonce":"b6d6726996","content":{"rendered":"<p>@Harry S<\/p>\n<p>das was du unter<br \/>\n<a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/#comment-138934\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/#comment-138934<\/a><br \/>\ngeschrieben hast, habe ich (teilweise) auch schon um 08:26 geschrieben<br \/>\nbzw. als Antwort auf Ben\u00b4s Kommentar auch schon unter<br \/>\n<a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/06\/24\/windows-10-20152-server-iso-vhdx-und-arm-als-preview-und-downloadlink\/#comment-138872\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2020\/06\/24\/windows-10-20152-server-iso-vhdx-und-arm-als-preview-und-downloadlink\/#comment-138872<\/a><br \/>\n<img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_razz.gif\" alt=\":P\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138940,"parent":138921,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T18:22:45","cld_nonce":"b6d6726996","content":{"rendered":"<p>Och Menno, verdirbst mir wieder den ganzen Spa\u00df! Wo ich es doch so hasse, wenn <b>Andere<\/b> Recht haben &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":-(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138942,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T18:49:01","cld_nonce":"b6d6726996","content":{"rendered":"<p>Und wer sich die passenden Verkn\u00fcpfungen machen m\u00f6chte von den &#8222;alten&#8220; Klamotten:<br \/>\nPfad zu den Dateien C:\\Windows\\System32<\/p>\n<p>SystemPropertiesDataExecutionPrevention<br \/>\nSystemPropertiesHardware<br \/>\nSystemPropertiesPerformance<br \/>\nSystemPropertiesProtection<br \/>\nSystemPropertiesRemote<br \/>\nSystemPropertiesAdvanced<br \/>\nSystemPropertiesComputerName<\/p>\n"},"status":"1"},{"id":138943,"parent":138942,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T18:51:57","cld_nonce":"b6d6726996","content":{"rendered":"<p>passt ja super zu (meinem) Men\u00fcprogramm <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138944,"parent":138943,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T19:03:33","cld_nonce":"b6d6726996","content":{"rendered":"<p>Jau! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138945,"parent":138943,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T19:07:29","cld_nonce":"b6d6726996","content":{"rendered":"<p>das &#8222;Teil&#8220; wird ja immer gr\u00f6\u00dfer \/ bzw. immer &#8222;komplexer&#8220; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138946,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T19:10:05","cld_nonce":"b6d6726996","content":{"rendered":"<p>Und wer hat mir diese uralte Windows-3.11-Programm-Manager-Schriftart in den Bootsector-Editor (EasyBCD) gepackt ???<br \/>\nDie taucht sicher auch noch anderswo auf in dieser Build  &#8230;<\/p>\n"},"status":"1"},{"id":138947,"parent":138945,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T19:11:45","cld_nonce":"b6d6726996","content":{"rendered":"<p>Macht doch nichts! Mist wird&#8217;s erst, wenn Du daf\u00fcr mehrere PC&#8217;s (nicht Bildschirme) brauchst! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138948,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T19:16:02","cld_nonce":"b6d6726996","content":{"rendered":"<p>alternativ noch genannt: Windows Suche, dort eingeben erweiterte System(einstellungen)<\/p>\n"},"status":"1"},{"id":138949,"parent":0,"author":2502,"author_name":"Oely","author_email":"gaxoely@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dd15e13c926e16f627cd684f76111572b8e0b8c0bb98cca51f8df7406d72dfb4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dd15e13c926e16f627cd684f76111572b8e0b8c0bb98cca51f8df7406d72dfb4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dd15e13c926e16f627cd684f76111572b8e0b8c0bb98cca51f8df7406d72dfb4?s=96&d=mm&r=g"},"date":"2020-07-02T19:19:05","cld_nonce":"b6d6726996","content":{"rendered":"<p>Musste leider wieder zur\u00fcck zur alten Version.<br \/>\nKeinerlei Funktion von Soundblaster Z<br \/>\nKeinerlei Funktion von Logitech G935<\/p>\n"},"status":"1"},{"id":138950,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T19:47:10","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ehm, kommt da von MS heute noch was? Angek\u00fcndigt wurden\/werden im Feedback Hub 2 x 20161 &#8230;<br \/>\nEinmal kam ja gestern schon &#8211; m\u00fc\u00dfte also noch 1 kommen, wenn ich richtig mitgez\u00e4hlt habe &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138951,"parent":138948,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-07-02T19:58:07","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei mir gen\u00fcgt &#8222;sy&#8220; einzugeben, da erscheint dann eine ganze Liste. Mir ist es auch schnuppe, ob das Teil System oder Info hei\u00dft. Beide verlinken nur weiter zu den gewohnten Einstellungen. Au\u00dferdem habe ich diverse Einstellungen an Start angeheftet um mir die ganze Klickerei, was auch in der Klassischen Systemsteuerung von N\u00f6ten war, zu ersparen. Noch hab ich die M\u00f6glichkeit beide (System\/Info) zu sehen, da nur 2 von 3 PC Info anzeigen 1 PC System.<\/p>\n"},"status":"1"},{"id":138953,"parent":138942,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T20:34:39","cld_nonce":"b6d6726996","content":{"rendered":"<p>So gehts auch <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><br \/>\n<b> <a href=\"https:\/\/t1p.de\/pnt9\" rel=\"nofollow ugc\">System<\/a> <\/b><\/p>\n"},"status":"1"},{"id":138955,"parent":138953,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-02T20:45:03","cld_nonce":"b6d6726996","content":{"rendered":"<p>Da hast Du stimmt !!! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138957,"parent":138950,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-02T22:13:53","cld_nonce":"b6d6726996","content":{"rendered":"<p>dann w\u00e4ren wir ja schon bei Version 40322.XXX <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_surprised.gif\" alt=\":o\" class=\"wp-smiley\" \/> <\/p>\n<p><img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138962,"parent":138950,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-07-02T22:54:30","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich hab die Link nicht weiter verfolgt, von den &#8222;Neuen Funktionen&#8220; habe ich 2 Unterschiedliche Versionen. Was der PC 2 hat, hat PC 1 und Dell nicht. Ich hoffe nur, das nicht schon wieder die Falschen Feature auf den Falschen Ger\u00e4ten sind. &#8222;Verbesserung des Tablet-Erlebnisses f\u00fcr 2-in-1-Ger\u00e4te&#8220; geh\u00f6rt z.B. zum Dell.\ud83d\ude01\ud83d\ude1c<\/p>\n"},"status":"1"},{"id":138965,"parent":138962,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-03T08:08:42","cld_nonce":"b6d6726996","content":{"rendered":"<p>Die &#8222;neuen&#8220; Funktionen werden derzeit offensichtlich per Zufallsgenerator zugeteilt &#8211; vorerst eh nur zum Testen.<br \/>\nBis die (und ob \u00fcberhaupt) Alle bekommen, ist also noch nicht entschieden &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138966,"parent":138957,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-03T08:14:23","cld_nonce":"b6d6726996","content":{"rendered":"<p>Nee, Manny &#8211; die 20161 wird doppelt angeboten!<br \/>\nNicht zum Zusammenz\u00e4hlen &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":-(\" class=\"wp-smiley\" \/> Du verstehst?<br \/>\nZweimal zweimal !!!<br \/>\nAndreasrum (nicht sorum, sondern rosum &#8211; von Andrea Seite) ausgequetscht: Eine und noch Eine &#8230;<br \/>\nWir Fachleute sagen auch &#8222;dupliziert&#8220; dazu &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><br \/>\n<img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139002,"parent":138946,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-03T19:42:39","cld_nonce":"b6d6726996","content":{"rendered":"<p>Diese v\u00f6llig unpassende Schriftart taucht auch in anderen Teilen des Systems auf &#8211; zum Beispiel in den &#8222;Internet-Optionen&#8220; &#8230;<\/p>\n"},"status":"1"},{"id":139003,"parent":138946,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-03T20:08:36","cld_nonce":"b6d6726996","content":{"rendered":"<p>kann diesbez\u00fcglich &#8211; auch wegen clean install &#8211; nichts feststellen <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><br \/>\n&#8211; hab ja sogar die alte Systemsteuerung &#8222;wieder gefunden&#8220; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139008,"parent":138946,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-03T23:23:24","cld_nonce":"b6d6726996","content":{"rendered":"<p>@Manny, @[alle]<br \/>\nDann guckt mal hier Bildschirmfotos:<br \/>\n<a href=\"http:\/\/pc-harry.de\/files\/Seltsame_Schrift_20161.jpg\"  rel=\"lightbox[141000] nofollow ugc\">http:\/\/pc-harry.de\/files\/Seltsame_Schrift_20161.jpg<\/a><br \/>\n&#8230; fast wieder wie vor 30 Jahren! Toll !!!<br \/>\nSo richtig mit <b>&#8222;Browserverla&#8220;<\/b> und so &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139009,"parent":139008,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2020-07-03T23:53:07","cld_nonce":"b6d6726996","content":{"rendered":"<p>Sieht bei mir genauso aus. Keine Ahnung, wieso.<\/p>\n"},"status":"1"},{"id":139010,"parent":139003,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-04T02:27:02","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8230;<br \/>\nund da war es schon wieder &#8222;vorbei&#8220; mit dem anzeigen von Teilen der alten Systemsteuerung &#8211; mittlerweile die (restliche) Konfiguration der 20161 fertig und nun geht es wieder nur \u00fcber die neuen Einstellen &#8211; u.a. Systemschutz \/Erweiterte Systemeinstellungen <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139026,"parent":138917,"author":0,"author_name":"Nimda","author_email":"passt@nnnn.ii","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/2a3c46cf733f1febf5c3fbc85f4c48b4a1b77334165a479c616f7dee72f9f585?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/2a3c46cf733f1febf5c3fbc85f4c48b4a1b77334165a479c616f7dee72f9f585?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/2a3c46cf733f1febf5c3fbc85f4c48b4a1b77334165a479c616f7dee72f9f585?s=96&d=mm&r=g"},"date":"2020-07-04T11:51:02","cld_nonce":"b6d6726996","content":{"rendered":"<p>Rechtsklick auf &#8222;Dieser PC&#8220; \/ Eigenschaften &#8211; dort kommt man (nur) auf die Startpage der Systemsteuerung. Hier kamm man auch Verkn\u00fcpfungen wegziehen.<\/p>\n<p>Ich gehe seit Windows 8 diesen Weg:<\/p>\n<pre>Windows Registry Editor Version 5.00\n\n[HKEY_CLASSES_ROOT\\Directory\\Background\\shell\\ControlPanel]\n\"MUIVerb\"=\"Systemsteuerung\"\n\"Icon\"=hex(2):25,00,53,00,79,00,73,00,74,00,65,00,6d,00,52,00,6f,00,6f,00,74,\\\n  00,25,00,5c,00,73,00,79,00,73,00,74,00,65,00,6d,00,33,00,32,00,5c,00,73,00,\\\n  68,00,65,00,6c,00,6c,00,33,00,32,00,2e,00,64,00,6c,00,6c,00,2c,00,32,00,31,\\\n  00,00,00\n\"Position\"=\"Bottom\"\n\n[HKEY_CLASSES_ROOT\\Directory\\Background\\shell\\ControlPanel\\command]\n@=hex(2):22,00,25,00,53,00,79,00,73,00,74,00,65,00,6d,00,52,00,6f,00,6f,00,74,\\\n  00,25,00,5c,00,73,00,79,00,73,00,74,00,65,00,6d,00,33,00,32,00,5c,00,63,00,\\\n  6f,00,6e,00,74,00,72,00,6f,00,6c,00,2e,00,65,00,78,00,65,00,22,00,00,00<\/pre>\n"},"status":"1"},{"id":139027,"parent":138917,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-07-04T11:54:19","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich hab das man eingebettet, da sonst der WordPress-Fehler mit den &#8222;&#8220; kommt.<\/p>\n"},"status":"1"},{"id":139028,"parent":138965,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-07-04T12:45:56","cld_nonce":"b6d6726996","content":{"rendered":"<p>\u00c4hnlich verh\u00e4lt es sich auch mit der Systemsteuerung, einige haben noch die &#8222;Alte&#8220;, andere die Info.<br \/>\nEs gibt auch noch den Ordner (.{ED7BA470-8E54-465E-825C-99712043E01C}).<\/p>\n"},"status":"1"},{"id":139029,"parent":138965,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-07-04T13:18:20","cld_nonce":"b6d6726996","content":{"rendered":"<p>Der wird wohl auch noch lange bleiben. Hab mal geschaut. Da hat sich im Prinzip gegen\u00fcber der 1909 vs 20161 nichts ge\u00e4ndert.<\/p>\n"},"status":"1"},{"id":139030,"parent":138965,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-04T13:18:55","cld_nonce":"b6d6726996","content":{"rendered":"<p>Du meinst den Gott-Modus? Den kennen aber nur wenige &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139031,"parent":138965,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-07-04T13:19:51","cld_nonce":"b6d6726996","content":{"rendered":"<p>Nennt sich offiziell &#8222;Alle Aufgaben&#8220; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139033,"parent":138965,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-04T13:53:30","cld_nonce":"b6d6726996","content":{"rendered":"<p>Jau. Nimmt aber seit einigen Jahren keine Benennung mehr an &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":-(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139034,"parent":138965,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-04T13:54:22","cld_nonce":"b6d6726996","content":{"rendered":"<p>also was den &#8222;Gott-Modus&#8220; angeht &#8211; ich wei\u00df zwar das es den gibt, aber selber nie genutzt \ud83d\ude07<\/p>\n<p>ich mach\u00b4s mir dann lieber mit meinem &#8222;Systemmen\u00fc&#8220; &#8211; es w\u00fcrde zwar reichen daf\u00fcr den &#8222;Hauptlink&#8220; zu nutzen, habe es aber einzeln gelistet um in jede Kategorie einzeln zu gelangen  <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n<p><b> <a href=\"https:\/\/t1p.de\/0j3w\" rel=\"nofollow ugc\">Men\u00fc-Script<\/a> <\/b><\/p>\n<p><img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139035,"parent":0,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2020-07-04T14:02:43","cld_nonce":"b6d6726996","content":{"rendered":"<p>L\u00e4sst sich bei euch das ADK f\u00fcr die 20161 installieren? Bei geh das nicht. Kommt wohl beim Setup zu diesem Fehler, wenn ich die Log richtig deute:<\/p>\n<p>Unbekannte Struktur im Datenformat &#8222;Rich Text Format&#8220;<\/p>\n<p>Damit ist das Setup am Ende.<\/p>\n"},"status":"1"},{"id":139036,"parent":139035,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-04T14:13:27","cld_nonce":"b6d6726996","content":{"rendered":"<p>hab ich schon l\u00e4nger nicht benutzt \/ installiert (teste es aber gerade)<\/p>\n<p>EDIT:<\/p>\n<p>ist bei mir ebenso, in der 2. Fehlermeldung kommt noch was von fehlenden Registry-Werten<\/p>\n"},"status":"1"},{"id":139037,"parent":0,"author":0,"author_name":"Opal76","author_email":"opal76a@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0af4c02bb2c3242126efa06e5d40c5693cc88c61c93fb6cf5e87cfaca562d509?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0af4c02bb2c3242126efa06e5d40c5693cc88c61c93fb6cf5e87cfaca562d509?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0af4c02bb2c3242126efa06e5d40c5693cc88c61c93fb6cf5e87cfaca562d509?s=96&d=mm&r=g"},"date":"2020-07-04T14:18:20","cld_nonce":"b6d6726996","content":{"rendered":"<p>Registry Tweak f\u00fcr das Kontextmenue Rechte Maustaste ( Alle Aufgaben GodMode )<\/p>\n<p><a href=\"https:\/\/easyupload.io\/nhrinx\" rel=\"nofollow ugc\">https:\/\/easyupload.io\/nhrinx<\/a><\/p>\n<pre>Windows Registry Editor Version 5.00\n\n[HKEY_CLASSES_ROOT\\DesktopBackground\\Shell]\n@=\"none\"\n\n[HKEY_CLASSES_ROOT\\DesktopBackground\\Shell\\Alle Aufgaben GodMode]\n\"Icon\"=\"%SystemRoot%\\\\System32\\\\imageres.dll,-109\"\n\n[HKEY_CLASSES_ROOT\\DesktopBackground\\Shell\\Alle Aufgaben GodMode\\command]\n@=\"explorer.exe shell:::{ED7BA470-8E54-465E-825C-99712043E01C}\"<\/pre>\n"},"status":"1"},{"id":139038,"parent":139036,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2020-07-04T14:21:58","cld_nonce":"b6d6726996","content":{"rendered":"<p>Danke f\u00fcr das Testen. Eine zweite Fehlermeldung kommt da bei mir gar nicht mehr. Mh?<\/p>\n<p>Aber gut, liegt dann wohl nicht an meiner Installation. Irgendetwas passt da wohl nicht zusammen.<\/p>\n"},"status":"1"},{"id":139039,"parent":139038,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-04T14:27:19","cld_nonce":"b6d6726996","content":{"rendered":"<p>schicke dir beide mal als PN <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139041,"parent":139035,"author":4241,"author_name":"Ben","author_email":"benderarsch@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=96&d=mm&r=g"},"date":"2020-07-04T14:57:44","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ist bei mir auch so. Aber \u00fcber die Commandline Option l\u00e4sst es sich installieren. mit z.B. <\/p>\n<pre>adksetup.exe \/features + \/q<\/pre>\n<p> Soweit ich es jetzt getestet habe funktioniert das aber nur mit dem Zusatz &#8222;\/q&#8220; f\u00fcr Quiet-Install.<\/p>\n"},"status":"1"},{"id":139044,"parent":139041,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2020-07-04T15:08:38","cld_nonce":"b6d6726996","content":{"rendered":"<p>Mit \/q ist klar, das das geht. Da hat das Setup nicht das Bed\u00fcrfnis, die Eula anzuzeigen. Und genau die scheitert ja. Die kann das Setup wegen &#8222;Unbekannte Struktur im Datenformat \u201eRich Text Format\u201c&#8220; nicht anzeigen.<\/p>\n<p>Gut, also vorher mittels adksetup \/list sich die Feature List ausdrucken lassen und dann mittel \/features die gew\u00fcnschten Features installieren lassen, z.B.:<\/p>\n<p><code>adksetup \/features OptionId.DeploymentTools \/q<\/code><\/p>\n"},"status":"1"},{"id":139084,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-05T08:46:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>Haaaa ERWISCHT !<\/p>\n<p>also entweder kann MS zaubern oder hat an zu viel Lachgas geschn\u00fcffelt <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><br \/>\n(oder ich hab jetzt &#8222;Schulden&#8220; bei denen in Form von Datentr\u00e4gerkapazit\u00e4t)<\/p>\n<p>Systemdatentr\u00e4ger laut Datentr\u00e4gerverwaltung = 238,46 GB<br \/>\nlaut Einstellungen \/ Speicher 245 GB verwendet <b>und<\/b> noch 231 GB frei  <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n<p>&#8211; und das seit Clean Install (vorgestern), und ja, ich wei\u00df das ist eine Insider \/ Beta wo auch mal &#8222;Fehler&#8220; auftauchen k\u00f6nnen <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/> )<\/p>\n<p><b> <a href=\"https:\/\/t1p.de\/ys5a\" rel=\"nofollow ugc\">20161.1000-Speicherkapazit\u00e4t<\/a> <\/b><\/p>\n"},"status":"1"},{"id":139282,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-07T19:30:29","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich h\u00e4tte da gern auch mal ein Problem:<br \/>\nDie (ur)alte M\u00f6glichkeit, auf jedem angeschlossenen Monitor ein eigenes Hintergrundbild einzurichten, funzt nicht mehr &#8230;<br \/>\nGew\u00fcnscht:<br \/>\nMonitor 1 (Notebook-Display) = Standard-Hintergrund,<br \/>\nMonitor 2 (Beamer) = Testbild.<br \/>\nDer Beamer soll so lange ein Testbild anzeigen, bis dort was Anderes ablaufen soll (Pr\u00e4sentation, Diashow, Spielfilm oder so). Dabei soll der Haupt-Monitor (Notebook-Display) zwecks Steuerung aber recht dunkel bleiben, um nicht st\u00f6rend zu wirken oder gar zu blenden &#8230;<br \/>\nHat irgendjemand eine Idee?<br \/>\nAnmerkung: Wird ein Bild mit rechts angeklickt, st\u00fcrzt die Einstellung sang- und klanglos ab (ohne jede Fehlermeldung) &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":-(\" class=\"wp-smiley\" \/><br \/>\nDie hier bei Deskmodder oder auch anderswo publizierten Tipps funzen leider nicht mehr &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":-(\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":-(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139288,"parent":139084,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-07T20:02:47","cld_nonce":"b6d6726996","content":{"rendered":"<p>Manny, der Trick ist (ur)alt: Schon bei XP pa\u00dften (angeblich) auf eine CD mehrere DVD-Images &#8211; laut Windows-Rechnerei !!!<br \/>\nFier pr\u00e4fekte Mathetik mu\u00df man \u00e4hm minstens 5 Silvester auf der Unit\u00e4t stiert ham !!! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139290,"parent":139084,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-07T20:21:11","cld_nonce":"b6d6726996","content":{"rendered":"<p>na dann bin ich ja mal gespannt, wie &#8222;gro\u00df&#8220; laut MS meine heute neue Samsung Evo Plus ist <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n<p>(Update auf genau diese Version l\u00e4uft gerade)<\/p>\n"},"status":"1"},{"id":139293,"parent":139282,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-07T20:48:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>Probier es mal mit dem Tool Dexpot, ich meine da kann man jeden Monitor wie man es selber will<br \/>\n ( und nicht das System) <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139294,"parent":0,"author":0,"author_name":"Ernie Bert","author_email":"tzluv@huhhu.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c65a68e26d7229d29f2990d48d108497ef47cae92c496ce9fa1a4d08e2c65dfe?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c65a68e26d7229d29f2990d48d108497ef47cae92c496ce9fa1a4d08e2c65dfe?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c65a68e26d7229d29f2990d48d108497ef47cae92c496ce9fa1a4d08e2c65dfe?s=96&d=mm&r=g"},"date":"2020-07-07T20:56:42","cld_nonce":"b6d6726996","content":{"rendered":"<p>meinste nicht das k\u00f6nnte am Beamer liege ?<br \/>\nbei mir funktioniert das.<\/p>\n<p>Habe einen infocus.<\/p>\n"},"status":"1"},{"id":139297,"parent":139293,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-07T21:15:06","cld_nonce":"b6d6726996","content":{"rendered":"<p>Virtuelle Desktops hab ich bei Bedarf ja schon durch TNT (TheNextTool) &#8211; die werden aber alle durch die Windows-Einstellungen gesteuert &#8230;<br \/>\nOK &#8211; mal probieren &#8230;<\/p>\n"},"status":"1"},{"id":139298,"parent":139294,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-07T21:16:50","cld_nonce":"b6d6726996","content":{"rendered":"<p>Nee, ist auch, wenn ich mehrere Monitore anschlie\u00dfe: 1 extern am Notebook und ggf. weitere 2 an der Zusatz-Grafikkarte in der Dockingstation) &#8230;<\/p>\n"},"status":"1"},{"id":139300,"parent":139297,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-07T21:28:20","cld_nonce":"b6d6726996","content":{"rendered":"<p>Klappt nicht: Keine (getrennte) Hintergrund-Auswahl (mehr?) &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":-(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139305,"parent":139297,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-07-07T23:10:46","cld_nonce":"b6d6726996","content":{"rendered":"<p>Dexpot habe ich schon lange nicht mehr benutzt und TNT kenn ich gar nicht  &#8211; bin gerade noch am &#8222;umkonfigurieren&#8220; wegen Einbau meiner neuen Samsung NVME <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139396,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-09T17:22:16","cld_nonce":"b6d6726996","content":{"rendered":"<p>So langsam werde ich auf MS auch stink-sauer:<br \/>\nNach 22-st\u00fcndiger Laufzeit (intensive Datenrettung &#8211; Einlesen einer 2-TB-Festplatte) dr\u00e4ngelte sich (unwissentlich) <b>zum wiederholten Mal dieses bescheuerte .NET-Update<\/b> auf den betreffenden Rechner und es kam, wie es kommen mu\u00dfte: Neustart &#8211; gleichfalls ungefragt !!!<br \/>\nDas hei\u00dft nichts mehr und nichts weniger als Abbruch der Datenrettung nach 22 Stunden (also bei knapp 1\/3) &#8230;<br \/>\nBedeutet: Alles nochmal von Vorne !!!<br \/>\nUnd bereits schwer gesch\u00e4digte Datentr\u00e4ger &#8222;freuen&#8220; sich ja bekanntlich \u00fcber jeden weiteren Zugriff &#8230;<br \/>\nDaraus hab ich 4 Sachen gelernt:<br \/>\n1. Mit den Rechnern nur noch ins Internet, wenn&#8217;s gar nicht mehr anders geht !!!<br \/>\n2. Niemals Datentr\u00e4ger mit Gesamt-Kapazit\u00e4ten von mehr als 512 GB verwenden !!!<br \/>\n3. Anspruchsvolle Aufgaben am PC niemals unbeaufsichtigt ablaufen lassen (notfalls \u00dcberwachung beauftragen) !!!<br \/>\n4. Microsoft Windows &#8211; wenn irgend m\u00f6glich &#8211; meiden !!!<\/p>\n<p>Einziger Trost f\u00fcr mich: Es handelte sich nicht um meine Daten \/ Festplatte !!!<\/p>\n<p>Ich bin (und bleibe wohl auch mindestens noch ein paar Wochen) stink-sauer !!!<\/p>\n"},"status":"1"},{"id":139915,"parent":0,"author":4241,"author_name":"Ben","author_email":"benderarsch@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=96&d=mm&r=g"},"date":"2020-07-15T19:01:21","cld_nonce":"b6d6726996","content":{"rendered":"<p>20170.1000 Ist im Dev Channel. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":139922,"parent":139915,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-07-15T19:29:14","cld_nonce":"b6d6726996","content":{"rendered":"<p>Jau !!! Siehe <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/07\/15\/windows-10-20170-steht-fuer-die-insider-im-dev-kanal-bereit\/#comment-139919\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2020\/07\/15\/windows-10-20170-steht-fuer-die-insider-im-dev-kanal-bereit\/#comment-139919<\/a><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Windows 10 20161 im Dev-Kanal + Server ISO, erste SDK, ADK und WDK - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windows 10 20161 im Dev-Kanal + Server ISO, erste SDK, ADK und WDK\" \/>\n<meta property=\"og:description\" content=\"Es steht eine neue Windows 10 Insider Build (Codename Iron) im Dev-Kanal (ehem. Fast-Ring) mit einem doch ordentlichen Versionssprung zum Download bereit. Die Windows 10 20161.1000, genauer die 10.0.20161.1000 rs_prerelease vom 27.06. kann nun getestet werden. Diesmal auch gleich mit&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-02T05:46:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-03T12:08:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"558\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Windows 10 20161 im Dev-Kanal + Server ISO, erste SDK, ADK und WDK\",\"datePublished\":\"2020-07-02T05:46:53+00:00\",\"dateModified\":\"2020-07-03T12:08:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/\"},\"wordCount\":934,\"commentCount\":83,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/windows-insider-update-app-einstellungen-logo.png\",\"keywords\":[\"ADK\",\"Aktuelle Insider\",\"Dev-Kanal\",\"Fast Ring\",\"neue Insider\",\"SDK\",\"WDK\",\"Windows 10 20161\"],\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/\",\"name\":\"Windows 10 20161 im Dev-Kanal + Server ISO, erste SDK, ADK und WDK - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/windows-insider-update-app-einstellungen-logo.png\",\"datePublished\":\"2020-07-02T05:46:53+00:00\",\"dateModified\":\"2020-07-03T12:08:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/windows-insider-update-app-einstellungen-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/windows-insider-update-app-einstellungen-logo.png\",\"width\":558,\"height\":401},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/07\\\/02\\\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Windows 10 20161 im Dev-Kanal + Server ISO, erste SDK, ADK und WDK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Windows 10 20161 im Dev-Kanal + Server ISO, erste SDK, ADK und WDK - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/","og_locale":"de_DE","og_type":"article","og_title":"Windows 10 20161 im Dev-Kanal + Server ISO, erste SDK, ADK und WDK","og_description":"Es steht eine neue Windows 10 Insider Build (Codename Iron) im Dev-Kanal (ehem. Fast-Ring) mit einem doch ordentlichen Versionssprung zum Download bereit. Die Windows 10 20161.1000, genauer die 10.0.20161.1000 rs_prerelease vom 27.06. kann nun getestet werden. Diesmal auch gleich mit&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-07-02T05:46:53+00:00","article_modified_time":"2020-07-03T12:08:23+00:00","og_image":[{"width":558,"height":401,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Windows 10 20161 im Dev-Kanal + Server ISO, erste SDK, ADK und WDK","datePublished":"2020-07-02T05:46:53+00:00","dateModified":"2020-07-03T12:08:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/"},"wordCount":934,"commentCount":83,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png","keywords":["ADK","Aktuelle Insider","Dev-Kanal","Fast Ring","neue Insider","SDK","WDK","Windows 10 20161"],"articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/","name":"Windows 10 20161 im Dev-Kanal + Server ISO, erste SDK, ADK und WDK - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png","datePublished":"2020-07-02T05:46:53+00:00","dateModified":"2020-07-03T12:08:23+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png","width":558,"height":401},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/07\/02\/windows-10-20161-im-dev-kanal-server-iso-erste-sdk-adk-und-wdk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Windows 10 20161 im Dev-Kanal + Server ISO, erste SDK, ADK und WDK"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/141000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=141000"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/141000\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/111270"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=141000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=141000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=141000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}