{"id":140844,"date":"2020-06-27T13:48:46","date_gmt":"2020-06-27T11:48:46","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=140844"},"modified":"2021-01-07T12:42:15","modified_gmt":"2021-01-07T11:42:15","slug":"windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/","title":{"rendered":"Windows File Recovery App &#8211; Gel\u00f6schte Daten ab Windows 10 2004 wiederherstellen"},"content":{"rendered":"<p><strong>[Update 7.01.2021]:<\/strong> Es gibt eine neue Version von der Windows File Recovery App mit neuen, einfacheren Befehlen. Mehr dazu unter: <a href=\"https:\/\/www.deskmodder.de\/blog\/2021\/01\/07\/windows-file-recovery-daten-wiederherstellen-in-einer-neuen-version\/\" rel=\"noopener\" target=\"_blank\">Windows File Recovery \u2013 Daten wiederherstellen in einer neuen Version<\/a><\/p>\n<p>Es gibt Unmengen an Software und Tools, um unwiderruflich gel\u00f6schte Dateien auf einer Partition, Stick oder SD-Karte wiederherzustellen. Microsoft hat daf\u00fcr jetzt eine App &#8222;Windows File Recovery&#8220; im Microsoft Store bereitgestellt, die das \u00fcber die Eingabeaufforderung erledigen kann.<\/p>\n<p>Unterst\u00fctzt wird NTFS (auch \u00fcber 4 GB), FAT, exFAT (bis 4 GB) und ReFS. Wiederhergestellt werden k\u00f6nnen JPEG, PDF, PNG, MPEG, Office Dateien, MP3, MP4, ZIP und viele mehr. Alles erfolgt \u00fcber den Befehl <strong>winfr<\/strong>. Dies ist mit der App ab Windows 10 2004 m\u00f6glich. Warum Microsoft daf\u00fcr nun extra eine App gebastelt hat, nun gut.<\/p>\n<p>Ok, nach einem K\u00e4ffchen ergibt es dann schon Sinn. Denn so kann die App inklusive der winfr.exe au\u00dferhalb von Updates \u00fcber den Microsoft Store aktualisiert werden.<\/p>\n<div id='gallery-1' class='gallery galleryid-140844 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-001.jpg' rel=\"lightbox[140844]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"189\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-001-306x189.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-001-306x189.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-001-500x310.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-001-810x502.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-001.jpg 961w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-002.jpg' rel=\"lightbox[140844]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"178\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-002-306x178.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-002-306x178.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-002-500x290.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-002-810x470.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-002.jpg 1139w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-003.jpg' rel=\"lightbox[140844]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"187\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-003-306x187.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-003-306x187.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-003-500x305.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-003-810x494.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-windows-file-recovery-app-windwos-10-003.jpg 1066w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>\u00dcber winfr stehen drei verschiedene Funktionen zur Verf\u00fcgung.<\/p>\n<ul>\n<li>Der <strong>Default mode<\/strong> \u00fcber den Zusatz \/n  &#8211; Stellt eine bestimmte Datei oder Ordner vom Laufwerk X: im Wiederherstellungsordner auf einem Laufwerk Y: wieder her. Beispiel<\/li>\n<\/ul>\n<pre>winfr C: E: \/n \\Users\\username\\Documents\\QuarterlyStatement.docx<\/pre>\n<ul>\n<li>Segment mode \u00fcber den Zusatz \/r &#8211; Stellt Dateien wieder her oder nutzt auch die M\u00f6glichkeit von Dateinamen mit Platzhaltern Beispiel &#8222;Deskmodder&#8220;. Beispiel<\/li>\n<\/ul>\n<pre>winfr C: E: \/r \/n *Deskmodder*<\/pre>\n<ul>\n<li>Signature mode \u00fcber den Zusatz \/x &#8211; Damit k\u00f6nnen ganze Dateigruppen wie Beispielweise JPEG, PNG wiederhergestellt werden. Beispiel<\/li>\n<\/ul>\n<pre>winfr C: E: \/x \/y:JPEG,PNG<\/pre>\n<ul>\n<li>Wichtig: Quell und Ziellaufwerke m\u00fcssen unterschiedlich sein. Auf dem Ziellaufwerk wird ein Ordner mit dem Namen Recovery_<datum und Uhrzeit> erstellt und die gefundenen Dateien gespeichert.<\/datum><\/li>\n<li>Die Wiederherstellung kann eine Weile dauern. Will man es abbrechen, dr\u00fcckt man Ctrl+C.<\/li>\n<\/ul>\n<p>Beim ersten Aufruf werden die &#8222;einfachen&#8220; Erkl\u00e4rungen angezeigt. M\u00f6chte man die erweiterten Funktionen sehen, gibt man <strong>winfr \/!<\/strong> ein. Bevor ich hier nun anfange weitere Beispiele zu verlinken, k\u00f6nnt ihr euch die <a href=\"https:\/\/support.microsoft.com\/en-us\/help\/4538642\/windows-10-restore-lost-files\" rel=\"noopener noreferrer\" target=\"_blank\">Anleitung von Microsoft<\/a> in Ruhe durchlesen, welches schon im April 2020 angelegt wurde.<\/p>\n<!-- WP-Appbox (Version: 4.5.13 \/\/ Store: microsoftstore \/\/ ID: 9n26s50ln705) -->\n<div class=\"wpappbox wpappbox-c22997cad0f87ba71f9fdf24cbe94a4b microsoftstore simple\">\n\t<div class=\"qrcode\"><img decoding=\"async\" src=\"https:\/\/api.qrserver.com\/v1\/create-qr-code\/?data=https%3A%2F%2Fwww.microsoft.com%2Fde-de%2Fp%2Fapp%2F9n26s50ln705&size=200x200&ecc=M&margin=0\" alt=\"Windows File Recovery\" \/><\/div>\n\t<div class=\"appicon\">\n\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/p\/app\/9n26s50ln705\" aria-label=\"Windows File Recovery\"><img decoding=\"async\" src=\"\/\/store-images.s-microsoft.com\/image\/apps.24219.13962106574996230.bf0d4490-07ff-4c8a-860e-26399fb1a8fb.a1a827be-0eb6-429d-b6d2-ac96df2f7fa6?background=%230078D4&#038;w=92&#038;q=80\" alt=\"Windows File Recovery\" \/><\/a>\n\t<\/div>\n\t<div class=\"applinks\">\n\t\t<div class=\"appbuttons\">\n\t\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/p\/app\/9n26s50ln705\" aria-label=\"Windows File Recovery\">Download<\/a>\n\t\t\t<span onMouseOver=\"jQuery('.wpappbox-c22997cad0f87ba71f9fdf24cbe94a4b .qrcode').show();\" onMouseOut=\"jQuery('.wpappbox-c22997cad0f87ba71f9fdf24cbe94a4b .qrcode').hide();\">QR-Code<\/span>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"appdetails\">\n\t\t<div class=\"apptitle\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.microsoft.com\/de-de\/p\/app\/9n26s50ln705\" title=\"Windows File Recovery\" aria-label=\"Windows File Recovery\" class=\"apptitle\">Windows File Recovery<\/a><\/div>\n\t\t<div class=\"developer\">\n\t\t\t<span class=\"label\">Entwickler: <\/span>\n\t\t\t<span class=\"value\">\u202aMicrosoft Corporation\u202c<\/span>\n\t\t<\/div>\n\t\t<div class=\"price\">\n\t\t\t<span class=\"label\">Preis: <\/span>\n\t\t\t<span class=\"value\">Kostenlos<\/span> \n\t\t\t<span class=\"rating\"><\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div><!-- \/WP-Appbox -->\n<p>Sollte der Download noch nicht klappen, dann:<\/p>\n<ul>\n<li><a href=\"https:\/\/store.rg-adguard.net\/\" rel=\"noopener noreferrer\" target=\"_blank\">store.rg-adguard.net\/<\/a> aufrufen <\/li>\n<li>Von Links nach Rechts ProductId, 9n26s50ln705 hineinkopieren und auf den Haken dr\u00fccken.<\/li>\n<li>Die Microsoft.WindowsFileRecovery  &#8230; _8wekyb3d8bbwe.appxbundle herunterladen<\/li>\n<li>Die Installation erfolgt dann wegen den erh\u00f6hten Rechten der App \u00fcber PowerShell<\/li>\n<li>PowerShell als Administrator starten<\/li>\n<li>Add-AppPackage -path eingeben &#8211; Mit gedr\u00fcckter Umschalttaste ein Rechtsklick auf die appxbundle und Pfad kopieren<\/li>\n<li>Hinter -path ein Leerzeichen und den Pfad hineinkopieren und Enter dr\u00fccken.<\/li>\n<\/ul>\n<p><strong>Als PS hinterher:<\/strong> Ist die App installiert, muss man diese nicht explizit nehmen. Die Eingabeaufforderung (Administrator) mit dem Befehl <strong>winfr \/?<\/strong> funktioniert ebenso.<\/p>\n<p>Auch im Paket enthalten ist eine WinFRUI.exe. Diese hat aber noch keine Funktion. L\u00e4sst aber darauf hoffen, dass die App auch bald eine GUI-Oberfl\u00e4che bekommt.<\/p>\n<div class=\"viaquelle\">via: <a href=\"https:\/\/twitter.com\/h0x0d\/status\/1276810514157297664\" rel=\"noopener noreferrer\" target=\"_blank\">@h0x0d<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>[Update 7.01.2021]: Es gibt eine neue Version von der Windows File Recovery App mit neuen, einfacheren Befehlen. Mehr dazu unter: Windows File Recovery \u2013 Daten wiederherstellen in einer neuen Version Es gibt Unmengen an Software und Tools, um unwiderruflich gel\u00f6schte&hellip; <\/p>\n","protected":false},"author":134,"featured_media":140856,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[924,75669,9751,75668,75667,75708,75707],"class_list":["post-140844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","tag-app","tag-datei-wiederherstellen","tag-windows-10","tag-windows-file-recovery","tag-winfr","tag-winfr-exe","tag-winfrui-exe"],"wp_featured_image":{"id":140856,"alt_text":"","description":"","media_type":"image","media_details":{"width":256,"height":256,"file":"2020\/06\/winfr-44targetsize-256-altform-unplated.png","sizes":{"thumbnail":{"file":"winfr-44targetsize-256-altform-unplated-205x205.png","width":205,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated-205x205.png"},"wp_review_large":{"file":"winfr-44targetsize-256-altform-unplated-256x200.png","width":256,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated-256x200.png"},"wp_review_small":{"file":"winfr-44targetsize-256-altform-unplated-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated-65x65.png"},"blog-medium":{"file":"winfr-44targetsize-256-altform-unplated-256x205.png","width":256,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated-256x205.png"},"wp_rp_thumbnail":{"file":"winfr-44targetsize-256-altform-unplated-50x50.png","width":50,"height":50,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated-50x50.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":140844,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated.png"},"commentcount":35,"wp_comments":[{"id":138580,"parent":0,"author":0,"author_name":"Konstantin","author_email":"paradonym@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/de521e67b68e80c9ef1fe35ca56c9a53ea739da34c6c5ac6c4ef27bd9fed186f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/de521e67b68e80c9ef1fe35ca56c9a53ea739da34c6c5ac6c4ef27bd9fed186f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/de521e67b68e80c9ef1fe35ca56c9a53ea739da34c6c5ac6c4ef27bd9fed186f?s=96&d=mm&r=g"},"date":"2020-06-27T15:22:52","cld_nonce":"b6d6726996","content":{"rendered":"<p>Das wurde aber auch Zeit, dass Microsoft ein Tool schreibt, dass den NTFS Index neu schreiben kann&#8230;<\/p>\n"},"status":"1"},{"id":138581,"parent":0,"author":0,"author_name":"Mquadrat","author_email":"deskmodder@marvinbeer.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c586aba5317c289ab2d01b5166002df0341bc753cc00383c060cb2bce79979c8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c586aba5317c289ab2d01b5166002df0341bc753cc00383c060cb2bce79979c8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c586aba5317c289ab2d01b5166002df0341bc753cc00383c060cb2bce79979c8?s=96&d=mm&r=g"},"date":"2020-06-27T16:00:32","cld_nonce":"b6d6726996","content":{"rendered":"<p>Das wirft bei mir folgendes Verlangen auf: Ein kleines aber wirkungsvolles Tool, welches sowas verhindert. Also Daten wirklich sicher l\u00f6scht und zwar ohne die lebenszeit von SSDs zu verringern. Hat jemand eins auf lager?<\/p>\n"},"status":"1"},{"id":138585,"parent":0,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=96&d=mm&r=g"},"date":"2020-06-27T17:22:30","cld_nonce":"b6d6726996","content":{"rendered":"<p>Na, das ist doch mal ein Signal f\u00fcr gute Entwicklerarbeit bei Microsoft. Nun fehlt nur noch ein Windows eigene Tool f\u00fcr ein Image-BackUp.<\/p>\n"},"status":"1"},{"id":138589,"parent":0,"author":0,"author_name":"PeterK","author_email":"pkeunecke@alice-dsl.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a6953cb7502c65f5b540100e7b5f5afc61416b099ef3dd7b4c19219ce1efd339?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a6953cb7502c65f5b540100e7b5f5afc61416b099ef3dd7b4c19219ce1efd339?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a6953cb7502c65f5b540100e7b5f5afc61416b099ef3dd7b4c19219ce1efd339?s=96&d=mm&r=g"},"date":"2020-06-27T18:35:39","cld_nonce":"b6d6726996","content":{"rendered":"<p>Sind die gel\u00f6schten Daten auf SSDs, auf denen Trim l\u00e4uft, nicht sowieso nach k\u00fcrzester Zeit f\u00fcr immer gel\u00f6scht bzw. unbrauchbar?<\/p>\n"},"status":"1"},{"id":138602,"parent":0,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-06-28T06:42:19","cld_nonce":"b6d6726996","content":{"rendered":"<p>Erinnert mich irgendwie an testdisk, mit dem Tool hatte ich eine 1 TB System\/Daten HDD mit 2 Partitionen zu etwa 90% der Dateien wieder hergestellt. Ich hatte damals die Dateien nicht gel\u00f6scht, sondern hatte sich Windows 7 geweigert eben die Systempartition neu zu erstellen.<\/p>\n"},"status":"1"},{"id":138607,"parent":0,"author":0,"author_name":"Andreas","author_email":"andreas@kuropka.eu","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e0dcfe5cab115a95e05dfcaf88b187397a3b158f6f486180f18b1ad8d0bf9e6b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e0dcfe5cab115a95e05dfcaf88b187397a3b158f6f486180f18b1ad8d0bf9e6b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e0dcfe5cab115a95e05dfcaf88b187397a3b158f6f486180f18b1ad8d0bf9e6b?s=96&d=mm&r=g"},"date":"2020-06-28T08:31:04","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wozu eine App daf\u00fcr? WinFR.exe extrahiert und gut ist es&#8230; (kleines Tool mit 793KB)<\/p>\n"},"status":"1"},{"id":138608,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-28T09:00:29","cld_nonce":"b6d6726996","content":{"rendered":"<p>und wie sieht die &#8222;Umkehrung&#8220; der ganzen Geschichte aus ? &#8211; wie bekommt man <b>wirklich alle Daten gel\u00f6scht<\/b> das man sie nicht mehr wieder hergestellt bekommt.<\/p>\n<p>Denke die Frage ist genau so berechtigt, denn egal was f\u00fcr einen Datentr\u00e4ger ich benutze &#8211; ob nach einer Formatierung \/ Neu-Partitionierung \/ Low-Level-Format &#8211; bekomme ich &#8211; sogar mit einem Freeware-Programm  &#8211; diese Daten noch wieder hergestellt<\/p>\n"},"status":"1"},{"id":138609,"parent":0,"author":0,"author_name":"Kelly Meiers","author_email":"k.meiers@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/39bb0c9a71ce1e9fed91f16455d0b10ad80c7bba6ac69f0bd8bea7a684256d3e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/39bb0c9a71ce1e9fed91f16455d0b10ad80c7bba6ac69f0bd8bea7a684256d3e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/39bb0c9a71ce1e9fed91f16455d0b10ad80c7bba6ac69f0bd8bea7a684256d3e?s=96&d=mm&r=g"},"date":"2020-06-28T09:49:17","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ein f\u00fcr mich eher unangenehmes Tool, eine st\u00e4ndige Vereinfachung auf meine Daten zu greifen zu k\u00f6nnen verunsichert mich. Auch ist der Papierkorb vom Papierkorb auch nur f\u00fcr mich eine Verl\u00e4ngerung der Zugriffm\u00f6glichkeiten mit dem Argument das wichtige Dateien st\u00e4ndig verloren gehen. Ich denke die Selbstverantwortung f\u00fcr Dokumente etc. steht im Vordergrund.<\/p>\n"},"status":"1"},{"id":138610,"parent":138609,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-06-28T09:59:46","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wie soll das Tool denn sonst deine Daten wiederherstellen k\u00f6nnen, wenn kein Zugriff auf die Daten erfolgt, sowie die cmd gestartet ist?<\/p>\n"},"status":"1"},{"id":138612,"parent":138581,"author":0,"author_name":"Konstantin","author_email":"paradonym@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/de521e67b68e80c9ef1fe35ca56c9a53ea739da34c6c5ac6c4ef27bd9fed186f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/de521e67b68e80c9ef1fe35ca56c9a53ea739da34c6c5ac6c4ef27bd9fed186f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/de521e67b68e80c9ef1fe35ca56c9a53ea739da34c6c5ac6c4ef27bd9fed186f?s=96&d=mm&r=g"},"date":"2020-06-28T13:21:02","cld_nonce":"b6d6726996","content":{"rendered":"<p>SSDs funktionieren anders, w\u00e4hrend HDDs nur den Index wegl\u00f6schen ist es bei der SSD kein Problem mal ein paar Zellen zu nullen, also ist das Ding eher f\u00fcr HDD.<\/p>\n<p>F\u00fcrs normale L\u00f6schen gibts bei SSDs die Secure Erease funktion in der Treibersoftware&#8230;<\/p>\n"},"status":"1"},{"id":138613,"parent":138585,"author":0,"author_name":"FS","author_email":"sevenacids@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/859999bc2e9cb34e8480bea5abb12a4a072e6eb7d8e7e26ba94fede4c3ba65e0?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/859999bc2e9cb34e8480bea5abb12a4a072e6eb7d8e7e26ba94fede4c3ba65e0?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/859999bc2e9cb34e8480bea5abb12a4a072e6eb7d8e7e26ba94fede4c3ba65e0?s=96&d=mm&r=g"},"date":"2020-06-28T14:00:19","cld_nonce":"b6d6726996","content":{"rendered":"<p>Geht doch mit DISM.<\/p>\n"},"status":"1"},{"id":138621,"parent":0,"author":0,"author_name":"Rolix","author_email":"roland.moser@mosimail.ch","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f67f2cc79ba1007ca86ea9a530b2ad9283b44a161c08dc623caa87cf87377e71?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f67f2cc79ba1007ca86ea9a530b2ad9283b44a161c08dc623caa87cf87377e71?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f67f2cc79ba1007ca86ea9a530b2ad9283b44a161c08dc623caa87cf87377e71?s=96&d=mm&r=g"},"date":"2020-06-28T18:10:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8222;&#8230;Warum Microsoft daf\u00fcr nun extra eine App gebastelt hat, nun gut&#8230;&#8220;<br \/>\nF\u00fcr die Normalverbraucher.<\/p>\n"},"status":"1"},{"id":138624,"parent":138607,"author":4435,"author_name":"Jens1976","author_email":"jens1976@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4c4bac72cd4f4ef7ba8f01eef01405e8991b7796d077f7911828c58367f26534?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4c4bac72cd4f4ef7ba8f01eef01405e8991b7796d077f7911828c58367f26534?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4c4bac72cd4f4ef7ba8f01eef01405e8991b7796d077f7911828c58367f26534?s=96&d=mm&r=g"},"date":"2020-06-28T18:24:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>funktioniert wie?<\/p>\n"},"status":"1"},{"id":138626,"parent":138624,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-06-28T18:27:10","cld_nonce":"b6d6726996","content":{"rendered":"<p>App manuell herunterladen (siehe oben), entpacken und die exe herausholen.<\/p>\n"},"status":"1"},{"id":138628,"parent":138608,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-06-28T18:37:32","cld_nonce":"b6d6726996","content":{"rendered":"<p>@Manny<br \/>\nLowLevelFormatTool (ich benutze aktuell HDLLF 4.40) &#8230; Stellt den Auslieferungszustand wieder her &#8211; es verbleiben absolut keine Datenreste mehr auf dem Datentr\u00e4ger. Funzt auch bei SSDs, Karten, Sticks &#8230; Aber Vorsicht: Einmal ausgef\u00fchrt, f\u00fchrt absolut kein Weg zur\u00fcck!<\/p>\n"},"status":"1"},{"id":138629,"parent":138608,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-28T18:46:04","cld_nonce":"b6d6726996","content":{"rendered":"<p>HDLLF 4.40 benutze ich selber, aber das dann wirklich alles weg ist stimmt so nicht<br \/>\n(jeden Falls bei mir nicht <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/> )  &#8222;&#8230;sogar mit einem Freeware-Programm \u2013 diese Daten noch wieder hergestellt&#8220; und damit meine ich das Recuva, hab da trotzdem noch (alte) Daten gefunden und auch wieder herstellen k\u00f6nnen, glaube das mit den Daten sichern \/ l\u00f6schen ist alles Augenwischerei, wenn man nicht so Programme wie die NSA hat <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n<p>&#8211; so mal kurz Ventoy starten f\u00fcr die neuen Linux(e)<\/p>\n"},"status":"1"},{"id":138630,"parent":138629,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-06-28T18:51:56","cld_nonce":"b6d6726996","content":{"rendered":"<p>Dann hast Du nicht den kompletten Datentr\u00e4ger Low-Level-Formatiert! Das kann n\u00e4mlich &#8211; je nach Datentr\u00e4gergr\u00f6\u00dfe, Schnittstelle und \u00dcbertragungsrate mehrere Tage bis Wochen dauern!<br \/>\nDanach hab ich aber &#8211; trotz intensivster Suche &#8211; nichts wieder finden k\u00f6nnen (nicht mal was Unbrauchbares) &#8230;<br \/>\nOder Du hattest keine Profi-Vollversion (mit entsprechender Lizenz) &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><br \/>\nF\u00fcr&#8217;s endg\u00fcltige Datenvernichten gibt&#8217;s aber mechanische Schredder (bei Sticks und Karten tut&#8217;s notfalls auch &#8217;ne Kaffeem\u00fchle) &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138631,"parent":138629,"author":0,"author_name":"Manny mit Linux Mint 20","author_email":"SFB@aim.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6777b6807e38a7d60c64ca7c6954542a1dc89ab9a28b7f234735323d96006a07?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6777b6807e38a7d60c64ca7c6954542a1dc89ab9a28b7f234735323d96006a07?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6777b6807e38a7d60c64ca7c6954542a1dc89ab9a28b7f234735323d96006a07?s=96&d=mm&r=g"},"date":"2020-06-28T18:52:30","cld_nonce":"b6d6726996","content":{"rendered":"<p>Funktioniert <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138632,"parent":138629,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-06-28T18:54:58","cld_nonce":"b6d6726996","content":{"rendered":"<p>Neue Linux(e)? Ich auch wissen wollen !!!!!!!!!!!!!!!!!!!!!<\/p>\n"},"status":"1"},{"id":138633,"parent":138630,"author":0,"author_name":"Manny mit Linux Mint 20","author_email":"SFB@aim.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6777b6807e38a7d60c64ca7c6954542a1dc89ab9a28b7f234735323d96006a07?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6777b6807e38a7d60c64ca7c6954542a1dc89ab9a28b7f234735323d96006a07?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6777b6807e38a7d60c64ca7c6954542a1dc89ab9a28b7f234735323d96006a07?s=96&d=mm&r=g"},"date":"2020-06-28T18:56:32","cld_nonce":"b6d6726996","content":{"rendered":"<p>also in meinem Fall war das eine SSD &#8211;  da dauert das ja keine Ewigkeiten &#8211; und das Teil benutze ich NUR mit Lizenz und auch bei Tiefenscan mit Recuva habe ich da noch was gefunden <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138634,"parent":138630,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-06-28T19:00:26","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hattest Du die SSD auch im LEGACY-Modus betrieben (also 32-Bit OHNE AHCI und <b>nicht<\/b> am USB) ??? <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138635,"parent":138632,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-28T19:00:27","cld_nonce":"b6d6726996","content":{"rendered":"<p>Linux Mint 20 ist da: Ulyana basiert auf Ubuntu 20.04 LTS<br \/>\n(News \u00fcber Microsoft , ca. 20 Stunden alt) <\/p>\n<p><a href=\"https:\/\/www.msn.com\/de-de\/nachrichten\/digital\/linux-mint-20-steht-ab-sofort-zum-download-bereit\/ar-BB162HWx?ocid=msedgdhp\" rel=\"nofollow ugc\">https:\/\/www.msn.com\/de-de\/nachrichten\/digital\/linux-mint-20-steht-ab-sofort-zum-download-bereit\/ar-BB162HWx?ocid=msedgdhp<\/a><\/p>\n<p>Einfach Downloads suchen <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138636,"parent":138632,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-06-28T19:02:40","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ah ja &#8211; mach ich mich gleich (nach meinem Steak) mal auf die Suche. Danke!<\/p>\n"},"status":"1"},{"id":138637,"parent":138632,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-28T19:03:10","cld_nonce":"b6d6726996","content":{"rendered":"<p>kein Thema <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n<p>&#8211; lief bei mir (ohne Installation) als Live-System direkt \u00fcber Ventoy-Datentr\u00e4ger <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n<p>Guten Apetitt ! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138638,"parent":138632,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-06-28T19:14:55","cld_nonce":"b6d6726996","content":{"rendered":"<p>Steak schnell runtergew\u00fcrgt &#8211; Download der MATE angeschubst (MATE nutze ich seit PEARL Linux &#8230;<br \/>\nJetzt noch ein (oder 2 oder 3) Bierchen zum Nachsp\u00fclen &#8211; dann Linux-TESTEN !!! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138639,"parent":138632,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-28T19:17:48","cld_nonce":"b6d6726996","content":{"rendered":"<p>Au jaaa, ein &#8222;paar&#8220; Bierchen ist eine gute Idee <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n<p>&#8211; in Verbindung mit einer gro\u00dfen Portion Chilli con Carne kommt das gut \ud83d\ude07<\/p>\n"},"status":"1"},{"id":138640,"parent":138632,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-06-28T19:29:05","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ja ja, jedes B\u00f6hnchen &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138641,"parent":138630,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-28T19:38:27","cld_nonce":"b6d6726996","content":{"rendered":"<p>ich habe meine SSD\u00b4s nicht an USB-h\u00e4ngen, NVME und immer 64 Bier (Bit) <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138642,"parent":138632,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-06-28T19:49:31","cld_nonce":"b6d6726996","content":{"rendered":"<p>Endlich mal wieder &#8222;Boot Repair&#8220; mit an Board &#8211; prima! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><br \/>\nKann ich endlich mal wieder zerschossene Grub-Konfigurationen reparieren &#8230; Toll !!! Hab ich schon lange vermi\u00dft &#8211; die anderen &#8222;Ubuntu&#8220;&#8217;s hatten das geflissentlich unterdr\u00fcckt und f\u00fcr Terminal-Tipparbeit ohne Ende war\/bin ich einfach mal zu faul &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":138643,"parent":138628,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2020-06-28T19:52:44","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8222;diskpart clean all&#8220; w\u00fcrde da auch reichen. Ein Extra Tool ist da nicht n\u00f6tig. Ein &#8222;Low Level Format&#8220; wird so oder so schon seit Jahren von keiner HDD mehr f\u00fcr Endanwender unterst\u00fctzt und von einer SSD schon gar nicht. Diese Tools machen auch nichts anderes, als alle Sektoren mind. 1x zu \u00fcberschreiben. Bei SSDs ist das nat\u00fcrlich kontraproduktiv.<\/p>\n"},"status":"1"},{"id":138646,"parent":138639,"author":0,"author_name":"Jens1976","author_email":"jens1976@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4c4bac72cd4f4ef7ba8f01eef01405e8991b7796d077f7911828c58367f26534?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4c4bac72cd4f4ef7ba8f01eef01405e8991b7796d077f7911828c58367f26534?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4c4bac72cd4f4ef7ba8f01eef01405e8991b7796d077f7911828c58367f26534?s=96&d=mm&r=g"},"date":"2020-06-28T20:07:09","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei DEM Wetter Chilli con Carne???<br \/>\nDas k\u00f6nnte man mir schenken <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/> <\/p>\n<p><i>gepostet mit der <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.deskmodder\" rel=\"nofollow ugc\">Deskmodder.de-App f\u00fcr Android<\/a><\/i><\/p>\n"},"status":"1"},{"id":138654,"parent":138621,"author":0,"author_name":"Rolix","author_email":"roland.moser@mosimail.ch","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f67f2cc79ba1007ca86ea9a530b2ad9283b44a161c08dc623caa87cf87377e71?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f67f2cc79ba1007ca86ea9a530b2ad9283b44a161c08dc623caa87cf87377e71?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f67f2cc79ba1007ca86ea9a530b2ad9283b44a161c08dc623caa87cf87377e71?s=96&d=mm&r=g"},"date":"2020-06-29T08:37:16","cld_nonce":"b6d6726996","content":{"rendered":"<p>War wohl ein Trugschluss! Es ist auch ein Befehlszeilen-Programm, und somit f\u00fcr Normalverbraucher nicht geeignet.<\/p>\n"},"status":"1"},{"id":138700,"parent":0,"author":0,"author_name":"Holgi","author_email":"holger_freese@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=96&d=mm&r=g"},"date":"2020-06-29T19:10:18","cld_nonce":"b6d6726996","content":{"rendered":"<p>ist der Doppel-Backslash<br \/>\nhinter Users<br \/>\nwinfr C: E: \/n \\Users\\\\Documents\\QuarterlyStatement.docx<\/p>\n<p>so korrekt? Oder egal?<\/p>\n"},"status":"1"},{"id":138701,"parent":138700,"author":4241,"author_name":"Ben","author_email":"benderarsch@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=96&d=mm&r=g"},"date":"2020-06-29T19:16:05","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich glaube da sollte der Benutzername dazwischen hinein. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n<pre>winfr C: E: \/n \\Users\\Ben\\Documents\\QuarterlyStatement.docx<\/pre>\n"},"status":"1"},{"id":138702,"parent":138700,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-06-29T19:16:34","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hat WordPress wieder zugeschlagen, weil username in <> stand<br \/>\nIst korrigiert.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Windows File Recovery App - Gel\u00f6schte Daten ab Windows 10 2004 wiederherstellen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windows File Recovery App - Gel\u00f6schte Daten ab Windows 10 2004 wiederherstellen\" \/>\n<meta property=\"og:description\" content=\"[Update 7.01.2021]: Es gibt eine neue Version von der Windows File Recovery App mit neuen, einfacheren Befehlen. Mehr dazu unter: Windows File Recovery \u2013 Daten wiederherstellen in einer neuen Version Es gibt Unmengen an Software und Tools, um unwiderruflich gel\u00f6schte&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-27T11:48:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-07T11:42:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated.png\" \/>\n\t<meta property=\"og:image:width\" content=\"256\" \/>\n\t<meta property=\"og:image:height\" content=\"256\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Windows File Recovery App &#8211; Gel\u00f6schte Daten ab Windows 10 2004 wiederherstellen\",\"datePublished\":\"2020-06-27T11:48:46+00:00\",\"dateModified\":\"2021-01-07T11:42:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/\"},\"wordCount\":471,\"commentCount\":35,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/winfr-44targetsize-256-altform-unplated.png\",\"keywords\":[\"App\",\"Datei wiederherstellen\",\"Windows 10\",\"Windows File Recovery\",\"winfr\",\"winfr.exe\",\"WinFRUI.exe\"],\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/\",\"name\":\"Windows File Recovery App - Gel\u00f6schte Daten ab Windows 10 2004 wiederherstellen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/winfr-44targetsize-256-altform-unplated.png\",\"datePublished\":\"2020-06-27T11:48:46+00:00\",\"dateModified\":\"2021-01-07T11:42:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/winfr-44targetsize-256-altform-unplated.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/winfr-44targetsize-256-altform-unplated.png\",\"width\":256,\"height\":256},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/27\\\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Windows File Recovery App &#8211; Gel\u00f6schte Daten ab Windows 10 2004 wiederherstellen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Windows File Recovery App - Gel\u00f6schte Daten ab Windows 10 2004 wiederherstellen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/","og_locale":"de_DE","og_type":"article","og_title":"Windows File Recovery App - Gel\u00f6schte Daten ab Windows 10 2004 wiederherstellen","og_description":"[Update 7.01.2021]: Es gibt eine neue Version von der Windows File Recovery App mit neuen, einfacheren Befehlen. Mehr dazu unter: Windows File Recovery \u2013 Daten wiederherstellen in einer neuen Version Es gibt Unmengen an Software und Tools, um unwiderruflich gel\u00f6schte&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-06-27T11:48:46+00:00","article_modified_time":"2021-01-07T11:42:15+00:00","og_image":[{"width":256,"height":256,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Windows File Recovery App &#8211; Gel\u00f6schte Daten ab Windows 10 2004 wiederherstellen","datePublished":"2020-06-27T11:48:46+00:00","dateModified":"2021-01-07T11:42:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/"},"wordCount":471,"commentCount":35,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated.png","keywords":["App","Datei wiederherstellen","Windows 10","Windows File Recovery","winfr","winfr.exe","WinFRUI.exe"],"articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/","name":"Windows File Recovery App - Gel\u00f6schte Daten ab Windows 10 2004 wiederherstellen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated.png","datePublished":"2020-06-27T11:48:46+00:00","dateModified":"2021-01-07T11:42:15+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated.png","width":256,"height":256},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/27\/windows-file-recovery-app-geloeschte-daten-ab-windows-10-2004-wiederherstellen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Windows File Recovery App &#8211; Gel\u00f6schte Daten ab Windows 10 2004 wiederherstellen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/winfr-44targetsize-256-altform-unplated.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/140844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=140844"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/140844\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/140856"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=140844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=140844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=140844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}