{"id":140615,"date":"2020-06-22T19:18:29","date_gmt":"2020-06-22T17:18:29","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=140615"},"modified":"2020-06-22T19:18:29","modified_gmt":"2020-06-22T17:18:29","slug":"microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/","title":{"rendered":"Microsoft Teams f\u00fcr die private Nutzung und neuen Funktionen"},"content":{"rendered":"<p>Wer heute schon Microsoft Teams beruflich nutzen sollte, kann dies dann auch mit einem zus\u00e4tzlichen Konto f\u00fcr die privaten Kontakte nutzen. Wer die Teams App bislang nicht genutzt hat, kann diese nun auch installieren.<\/p>\n<p>Alles, was man ben\u00f6tigt, ist die Anmeldung mit dem Microsoft Konto, oder wer keines hat \u00fcber die Telefonnummer ist es auch m\u00f6glich. Microsoft will damit eine All-In-One App schaffen, mit der man nicht nur chattet oder sich per Video unterh\u00e4lt, sondern auch f\u00fcr Gruppenaktivit\u00e4ten und die Koordination.<\/p>\n<div id='gallery-1' class='gallery galleryid-140615 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-chat.gif' rel=\"lightbox[140615]\"><img loading=\"lazy\" decoding=\"async\" width=\"103\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-chat-103x205.gif\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-chat-103x205.gif 103w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-chat-180x360.gif 180w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-chat-292x583.gif 292w\" sizes=\"auto, (max-width: 103px) 100vw, 103px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-dateien-teilen.png' rel=\"lightbox[140615]\"><img loading=\"lazy\" decoding=\"async\" width=\"101\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-dateien-teilen-101x205.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-dateien-teilen-101x205.png 101w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-dateien-teilen-178x360.png 178w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-dateien-teilen-289x583.png 289w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-dateien-teilen.png 450w\" sizes=\"auto, (max-width: 101px) 100vw, 101px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-dashboard.gif' rel=\"lightbox[140615]\"><img loading=\"lazy\" decoding=\"async\" width=\"103\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-dashboard-103x205.gif\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-dashboard-103x205.gif 103w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-dashboard-180x360.gif 180w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/teams-consumer-dashboard-292x583.gif 292w\" sizes=\"auto, (max-width: 103px) 100vw, 103px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h3>Was ist m\u00f6glich in der privaten Nutzung:<\/h3>\n<ul>\n<li>Chatten oder Videokonferenzen durchf\u00fchren. Es k\u00f6nnen Termine vereinbart und diese in der ToDo hinterlegt werden.<\/li>\n<li>Listen, Dokumente oder Kalender f\u00fcr bestimmte Gruppen k\u00f6nnen angelegt werden. Alles \u00fcber das Dashboard m\u00f6glich<\/li>\n<li>Dokumente (Word etc) k\u00f6nnen miteinander geteilt werden. Diese werden auf OneDrive gespeichert und man hat von \u00fcberall aus Zugriff<\/li>\n<li>Wichtige Dokumente oder Anmeldedaten k\u00f6nnen sicher im Tresor (mit Zwei-Faktor-Authentifizierung und \u201eEnd-to-End-Verschl\u00fcsselung) auf OneDrive abgelegt werden.<\/li>\n<li>Mit der Standortfreigabe kann man sehen, wo sich der Partner gerade befindet.<\/li>\n<\/ul>\n<p>Dies alles wird in der n\u00e4chsten Zeit in einer Preview f\u00fcr Android und iOS dann zur Verf\u00fcgung stehen.<\/p>\n<div class=\"quelle\">Quelle: Microsoft <a href=\"https:\/\/www.microsoft.com\/en-us\/microsoft-365\/blog\/2020\/06\/22\/introducing-features-microsoft-teams-connect-friends-family-available-mobile-preview\/\" rel=\"noopener noreferrer\" target=\"_blank\">1<\/a>, <a href=\"https:\/\/news.microsoft.com\/de-de\/microsoft-teams-fuer-familie-freundinnen\/\" rel=\"noopener noreferrer\" target=\"_blank\">2<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wer heute schon Microsoft Teams beruflich nutzen sollte, kann dies dann auch mit einem zus\u00e4tzlichen Konto f\u00fcr die privaten Kontakte nutzen. Wer die Teams App bislang nicht genutzt hat, kann diese nun auch installieren. Alles, was man ben\u00f6tigt, ist die&hellip; <\/p>\n","protected":false},"author":134,"featured_media":98407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[894,232],"tags":[],"class_list":["post-140615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-android","category-ios"],"wp_featured_image":{"id":98407,"alt_text":"","description":"","media_type":"image","media_details":{"width":446,"height":250,"file":"2018\/02\/microsoft-teams-logo.jpg","sizes":{"thumbnail":{"file":"microsoft-teams-logo-306x172.jpg","width":306,"height":172,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo-306x172.jpg"},"wp_review_large":{"file":"microsoft-teams-logo-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo-320x200.jpg"},"wp_review_small":{"file":"microsoft-teams-logo-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo-65x65.jpg"},"blog-medium":{"file":"microsoft-teams-logo-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo-306x205.jpg"},"recent-thumb":{"file":"microsoft-teams-logo-350x250.jpg","width":350,"height":250,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo-350x250.jpg"},"wp_rp_thumbnail":{"file":"microsoft-teams-logo-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":98404,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Microsoft Teams f\u00fcr die private Nutzung und neuen Funktionen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft Teams f\u00fcr die private Nutzung und neuen Funktionen\" \/>\n<meta property=\"og:description\" content=\"Wer heute schon Microsoft Teams beruflich nutzen sollte, kann dies dann auch mit einem zus\u00e4tzlichen Konto f\u00fcr die privaten Kontakte nutzen. Wer die Teams App bislang nicht genutzt hat, kann diese nun auch installieren. Alles, was man ben\u00f6tigt, ist die&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-22T17:18:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"446\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Microsoft Teams f\u00fcr die private Nutzung und neuen Funktionen\",\"datePublished\":\"2020-06-22T17:18:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/\"},\"wordCount\":220,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/microsoft-teams-logo.jpg\",\"articleSection\":[\"Android\",\"iOS\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/\",\"name\":\"Microsoft Teams f\u00fcr die private Nutzung und neuen Funktionen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/microsoft-teams-logo.jpg\",\"datePublished\":\"2020-06-22T17:18:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/microsoft-teams-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/microsoft-teams-logo.jpg\",\"width\":446,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/22\\\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft Teams f\u00fcr die private Nutzung und neuen Funktionen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Microsoft Teams f\u00fcr die private Nutzung und neuen Funktionen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/","og_locale":"de_DE","og_type":"article","og_title":"Microsoft Teams f\u00fcr die private Nutzung und neuen Funktionen","og_description":"Wer heute schon Microsoft Teams beruflich nutzen sollte, kann dies dann auch mit einem zus\u00e4tzlichen Konto f\u00fcr die privaten Kontakte nutzen. Wer die Teams App bislang nicht genutzt hat, kann diese nun auch installieren. Alles, was man ben\u00f6tigt, ist die&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-06-22T17:18:29+00:00","og_image":[{"width":446,"height":250,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Microsoft Teams f\u00fcr die private Nutzung und neuen Funktionen","datePublished":"2020-06-22T17:18:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/"},"wordCount":220,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo.jpg","articleSection":["Android","iOS"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/","name":"Microsoft Teams f\u00fcr die private Nutzung und neuen Funktionen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo.jpg","datePublished":"2020-06-22T17:18:29+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo.jpg","width":446,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/22\/microsoft-teams-fuer-die-private-nutzung-und-neuen-funktionen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Microsoft Teams f\u00fcr die private Nutzung und neuen Funktionen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/02\/microsoft-teams-logo.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/140615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=140615"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/140615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/98407"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=140615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=140615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=140615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}