{"id":139896,"date":"2020-06-09T19:04:19","date_gmt":"2020-06-09T17:04:19","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=139896"},"modified":"2020-06-13T11:37:43","modified_gmt":"2020-06-13T09:37:43","slug":"kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/","title":{"rendered":"KB4557957 + KB4560366 als SSU (Manueller Download) Windows 10 2004 19041.329  Sicherheitsupdate Juni"},"content":{"rendered":"<p>Patchday Juni 2020: Nachdem Microsoft die Windows 10 2004 (Mai 2020 Update) nun offiziell freigegeben hat ist es nun Zeit f\u00fcr das neue kumulative Sicherheitsupdate KB 4557957. Dadurch erh\u00f6ht sich die Versionsnummer auf die Windows 10 19041.329<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/kb4557957.jpg\" rel=\"lightbox[139896]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/kb4557957-500x319.jpg\" alt=\"\" width=\"500\" height=\"319\" class=\"aligncenter size-medium wp-image-140003\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/kb4557957-500x319.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/kb4557957-810x517.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/kb4557957-306x195.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/06\/kb4557957.jpg 1049w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<ul>\n<li><a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/03\/15\/windows-10-2004-die-aenderungen-in-der-uebersicht\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004 Die \u00c4nderungen in der \u00dcbersicht<\/a><\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/12\/11\/windows-10-19041-iso-esd-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004 19041 ISO \/ ESD inkl. Updates<\/a><\/li>\n<\/ul>\n<h3>Bekannte Probleme durch die KB4557957<\/h3>\n<ul>\n<li><strong>Drucker:<\/strong> Druckauftr\u00e4ge werden nicht ausgef\u00fchrt. Bislang hilft hier nur das kumulative Update \u00fcber die alte Systemstererung -> Programme und Feature -> Installierte Updates wieder zu deinstallieren. Ein Workaround w\u00e4re noch der Versuch den PCL6 Universal Treiber zu installieren. Diese stellt jeder Drucker-Hersteller zur Verf\u00fcgung (<a href=\"https:\/\/www.google.de\/search?newwindow=1&#038;source=hp&#038;ei=cJfjXpHeN9uAi-gPjpuFqAw&#038;q=PCL6+universal+driver&#038;oq=PCL6+universal+driver\" rel=\"noopener noreferrer\" target=\"_blank\">Google-Suche<\/a>) Microsoft arbeitet an dem Problem und wird es mit einem n\u00e4chsten Update beheben.<\/li>\n<li>Es kann vorkommen, dass nach der Datentr\u00e4gerbereinigung weiterhin bspw. 54 MB f\u00fcr Windows Update steht. Das ist kein wirkliches Problem. <\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/04\/11\/windows-10-2004-bekannte-und-behobene-probleme\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004 \u2013 Bekannte und behobene Probleme in der \u00dcbersicht<\/a> <em>(Wird nach dem Update aktualisiert)<\/em><\/li>\n<\/ul>\n<h3>Behobene Probleme durch die KB4557957<\/h3>\n<ul>\n<li>Neu: Avast oder AVG kann Programme und Apps daran hindern zu starten. Das Problem wurde extern von Avast \/ AVG behoben.<\/li>\n<li><a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_reparieren_wiederherstellen_mit_DISM_Inplace_Upgrade_und_vielen_weiteren_Varianten\" rel=\"noopener noreferrer\" target=\"_blank\">DISM-Reparatur<\/a> mit einem Anzeigefehler. Der Vorgang wird bei 84,9% als erfolgreich beendet angezeigt wurde behoben.<\/li>\n<li>Problem bei Ger\u00e4ten mit Always On, Always Connected bspw. beim Surface Pro 7 oder Surface Laptop 3 wurde mit diesem Update behoben. Die Update-Sperre f\u00fcr die Ger\u00e4te wird nun aufgehoben.<\/li>\n<li>Behebt ein Problem, das Sie daran hindert, einige Sprachbefehle in Windows Mixed Reality zu verwenden, wenn die Windows-Standardsprache kanadisches oder australisches Englisch ist.<\/li>\n<li>Verbessert die Zuverl\u00e4ssigkeit der f\u00fcr Sprachassistenten verwendeten Schl\u00fcsselw\u00f6rter, einschlie\u00dflich Cortana.<\/li>\n<li>Aktualisierungen zur Verbesserung der Sicherheit bei der Verwendung von Internet Explorer und Microsoft Edge.<\/li>\n<li>Updates zur Verbesserung der Sicherheit, wenn Windows grundlegende Operationen ausf\u00fchrt.<\/li>\n<li>Updates zur Verbesserung der Sicherheit bei der Verwendung von Microsoft Office-Produkten.<\/li>\n<li>Updates zur Verbesserung der Sicherheit bei der Verwendung von externen Ger\u00e4ten (z. B. Gamecontroller, Drucker und Webkameras) und Eingabeger\u00e4ten (z. B. Maus, Tastatur oder Eingabestift).<\/li>\n<li>Verbessert die Sicherheit in Microsoft Xbox und im Microsoft Store.<\/li>\n<li>Updates zur \u00dcberpr\u00fcfung von Benutzernamen und Kennw\u00f6rtern.<\/li>\n<li>Updates f\u00fcr die Speicherung und Verwaltung von Dateien.<\/li>\n<li>Verbessert die Zuverl\u00e4ssigkeit der Sprachaktivierung von Cortana bei der Verwendung des Schl\u00fcsselworts &#8222;Cortana&#8220; auf Ger\u00e4ten, die Low-Power-Schl\u00fcsselw\u00f6rter unterst\u00fctzen. <\/li>\n<li>Behebt ein Problem, dass Benutzer daran hindert, .msi-Dateien aus einem Netzwerkordner zu aktualisieren. <\/li>\n<li>Die \u00fcbliche Beschreibung, wenn dicke Sicherheitsl\u00fccken gestopft wurden: Sicherheitsupdates f\u00fcr Internet Explorer, die Microsoft Scripting Engine, Windows App Plattform und Frameworks, Microsoft Grafikkomponente, Windows Input und Komposition, Windows Media, Windows Shell, Microsoft Xbox, Microsoft Edge, Windows Grundlagen, Windows Kryptografie, Windows Authentifizierung, Windows Kernel, Windows Virtualisierung, Windows Update Stack, Windows Kernnetzwerk, Internetinformationsdienste, Windows Netzwerksicherheit und Container, Windows Active Directory, Windows Server und die Microsoft JET Datenbank-Engine.\n<ul>\n<li>Genaue Beschreibung der einzelnen CVEs: <a href=\"https:\/\/portal.msrc.microsoft.com\/en-us\/security-guidance\" rel=\"noopener noreferrer\" target=\"_blank\">portal.msrc.microsoft.com\/security-guidance<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3>KB4560366 als SSU<\/h3>\n<ul>\n<li>Wer manuell installiert <strong>muss<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=SSU_Servicing_Stack_Update_Stapel_Update_Windows_10_einmal_erkl%C3%A4rt\" rel=\"noopener noreferrer\" target=\"_blank\">das SSU<\/a> als Erstes installieren<\/li>\n<li><a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/secu\/2020\/06\/windows10.0-kb4560366-x64_653c88cde27a1adff38843c1b054fbbcef380b6f.msu\" rel=\"noopener noreferrer\" target=\"_blank\">windows10.0-kb4560366-x64.msu<\/a><\/li>\n<li><a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/secu\/2020\/06\/windows10.0-kb4560366-x86_a3e87cf039c5a25ba3e4200892cfee30911d4689.msu\" rel=\"noopener noreferrer\" target=\"_blank\">windows10.0-kb4560366-x86.msu<\/a><\/li>\n<li>ARM: <a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/secu\/2020\/06\/windows10.0-kb4560366-arm64_704ad2f236d248453da13e967e5d6ead0b3eeebd.msu\" rel=\"noopener noreferrer\" target=\"_blank\">windows10.0-kb4560366-arm64.msu<\/a><\/li>\n<\/ul>\n<h3>Manueller Download der KB4557957<\/h3>\n<ul>\n<li><a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/secu\/2020\/06\/windows10.0-kb4557957-x64_ce530e139ad0d12d33f185a5db868248110b93eb.msu\" rel=\"noopener noreferrer\" target=\"_blank\">windows10.0-kb4557957-x64.msu<\/a><\/li>\n<li><a href=\"http:\/\/download.windowsupdate.com\/d\/msdownload\/update\/software\/secu\/2020\/06\/windows10.0-kb4557957-x86_c711f2cbf308606b4cf7d02172f9dd96c2f24a60.msu\" rel=\"noopener noreferrer\" target=\"_blank\">windows10.0-kb4557957-x86.msu<\/a><\/li>\n<li>ARM: <a href=\"http:\/\/download.windowsupdate.com\/d\/msdownload\/update\/software\/secu\/2020\/06\/windows10.0-kb4557957-arm64_ee41a411a4df7deac83ad27c27fb19e5bdecfa2a.msu\" rel=\"noopener noreferrer\" target=\"_blank\">windows10.0-kb4557957-arm64.msu<\/a><\/li>\n<\/ul>\n<h3>Windows 10 Tutorials und Hilfe<\/h3>\n<p>In unserem <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 Wiki<\/a> findet ihr sehr viele hilfreiche Tipps und Tricks. Falls ihr Fragen habt, dann stellt diese ganz einfach bei uns im <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewforum.php?f=326\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Forum<\/strong><\/a>.<\/p>\n<ul>\n<li><strong>Installationsmedien:<\/strong> Aktuelle Installationsdateien findet ihr hier immer in der rechten Sidebar. <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/12\/11\/windows-10-19041-iso-esd-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004 ISO (19041)<\/a>, oder <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/08\/27\/windows-10-1909-18363-iso-esd-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">1909 ISO (18363)<\/a> <\/li>\n<li><strong>Installation:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_clean_neu_installieren\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 Clean installieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_1909_neu_installieren_Anleitung_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 1909 neu installieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_2004_neu_installieren_Anleitung_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 2004 neu installieren<\/a><\/li>\n<li><strong>Aktuelle Probleme mit der:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/04\/11\/windows-10-2004-bekannte-und-behobene-probleme\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004<\/a>\n    <\/li>\n<li><strong>Reparaturen:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Inplace_Upgrade_Windows_10_schnell_reparieren\" rel=\"noopener noreferrer\" target=\"_blank\">Inplace Upgrade Reparatur<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_reparieren_wiederherstellen_mit_DISM_Inplace_Upgrade_und_vielen_weiteren_Varianten\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 reparieren  \u00fcber DISM, sfc und weiteres<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_Update_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Windows Update reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Startmen%C3%BC_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Startmen\u00fc reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Apps_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Apps reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Store_reparieren\" rel=\"noopener noreferrer\" target=\"_blank\">Store reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Netzwerkverbindung_-adapter_reparieren_zur%C3%BCcksetzen_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Netzwerk reparieren<\/a><\/li>\n<li><strong>Anmeldung:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_automatisch_anmelden_ohne_Passworteingabe\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 automatische Anmeldung<\/a><\/li>\n<li><strong>Entfernen, Deinstallieren<\/strong>:  <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Apps_entfernen_deinstallieren\" rel=\"noopener noreferrer\" target=\"_blank\">Apps deinstallieren<\/a><\/li>\n<li><strong>Datei Explorer:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Dieser_PC_Ordner_entfernen_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Ordner unter Dieser PC entfernen<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Datei_Explorer_Windows_10_Netzwerk_Heimnetzgruppe_OneDrive_entfernen\" rel=\"noopener noreferrer\" target=\"_blank\">Netzwerk, OneDrive u.a. im Explorer entfernen<\/a><\/li>\n<li><strong>Richtige Nutzung:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Das_Windows_10_Startmen%C3%BC_richtig_einrichten_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Startmen\u00fc richtig nutzen<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Die_Suche_in_Windows_10_richtig_nutzen\" rel=\"noopener noreferrer\" target=\"_blank\">Suche richtig nutzen<\/a>,<\/li>\n<li><strong>Wichtig:<\/strong> In jedem Tutorial steht, f\u00fcr welche Version es geeignet ist.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Patchday Juni 2020: Nachdem Microsoft die Windows 10 2004 (Mai 2020 Update) nun offiziell freigegeben hat ist es nun Zeit f\u00fcr das neue kumulative Sicherheitsupdate KB 4557957. Dadurch erh\u00f6ht sich die Versionsnummer auf die Windows 10 19041.329 Windows 10 2004&hellip; <\/p>\n","protected":false},"author":134,"featured_media":111268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[74951,74950,74949,9954,6381,74889,74890,66244,74960,74961],"class_list":["post-139896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","tag-19041-329","tag-kb-4557957","tag-kb4557957","tag-msu","tag-neues-update","tag-patchday-juni-2020","tag-win-10-2004","tag-windows-10-2004","tag-windows10-0-kb4557957-x64-msu","tag-windows10-0-kb4560366-x64"],"wp_featured_image":{"id":111268,"alt_text":"","description":"","media_type":"image","media_details":{"width":558,"height":401,"file":"2018\/11\/windows-update-logo.png","sizes":{"thumbnail":{"file":"windows-update-logo-285x205.png","width":285,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo-285x205.png"},"medium":{"file":"windows-update-logo-500x360.png","width":500,"height":360,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo-500x360.png"},"wp_review_large":{"file":"windows-update-logo-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo-320x200.png"},"wp_review_small":{"file":"windows-update-logo-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo-65x65.png"},"blog-large":{"file":"windows-update-logo-558x300.png","width":558,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo-558x300.png"},"blog-medium":{"file":"windows-update-logo-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo-306x205.png"},"recent-thumb":{"file":"windows-update-logo-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo-350x316.png"},"service-featured":{"file":"windows-update-logo-558x330.png","width":558,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo-558x330.png"},"wp_rp_thumbnail":{"file":"windows-update-logo-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":118054,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo.png"},"commentcount":64,"wp_comments":[{"id":136825,"parent":0,"author":0,"author_name":"Schlammhamster","author_email":"noe@aol.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/905910a5f6a668bb0f838217463b5a1fb62030e60837b0cfe02bbe97be02b85b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/905910a5f6a668bb0f838217463b5a1fb62030e60837b0cfe02bbe97be02b85b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/905910a5f6a668bb0f838217463b5a1fb62030e60837b0cfe02bbe97be02b85b?s=96&d=mm&r=g"},"date":"2020-06-09T19:06:56","cld_nonce":"b6d6726996","content":{"rendered":"<p>\u00dcbersetzt mit <a href=\"http:\/\/www.DeepL.com\/Translator\" rel=\"nofollow ugc\">http:\/\/www.DeepL.com\/Translator<\/a> (kostenlose Version) <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136826,"parent":0,"author":6222,"author_name":"ftth-rayong","author_email":"ont.ftth@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/627da27fc0158789d7f1de266589141db9981eb2e397ef851c5c1af46648ed19?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/627da27fc0158789d7f1de266589141db9981eb2e397ef851c5c1af46648ed19?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/627da27fc0158789d7f1de266589141db9981eb2e397ef851c5c1af46648ed19?s=96&d=mm&r=g"},"date":"2020-06-09T19:13:53","cld_nonce":"b6d6726996","content":{"rendered":"<p>Guten Morgen, bestens dank rennt<\/p>\n<p>per <a href=\"https:\/\/thinkwiki.de\/W530\" rel=\"nofollow ugc\">https:\/\/thinkwiki.de\/W530<\/a><\/p>\n<p>Es sind updates verf\u00fcgbar&#8230;.<\/p>\n<p>2020-06 Sicherheitsupdate f\u00fcr Adobe Flash Player f\u00fcr Windows 10 Version 1909 f\u00fcr x64-basierte Systeme (KB4561600)<\/p>\n<p>und<\/p>\n<p>2020-06 Kumulatives Update f\u00fcr Windows 10 Version 1909 f\u00fcr x64-basierte Systeme (KB4560960)<\/p>\n<p>alles bestens einwandfrei  per update Happy 10 Juni 2563<\/p>\n<p>00:14<\/p>\n<p>Schlammhamster><br \/>\nNutze denn hier<\/p>\n<p><a href=\"https:\/\/quest-app.appspot.com\/\" rel=\"nofollow ugc\">https:\/\/quest-app.appspot.com\/<\/a><\/p>\n"},"status":"1"},{"id":136827,"parent":0,"author":0,"author_name":"Tobi","author_email":"h.wiki@gmx.ch","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0b2e89b59afb2ccec986acfe00c1e514179a010a27359fdac4e36bc0198fe39f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0b2e89b59afb2ccec986acfe00c1e514179a010a27359fdac4e36bc0198fe39f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0b2e89b59afb2ccec986acfe00c1e514179a010a27359fdac4e36bc0198fe39f?s=96&d=mm&r=g"},"date":"2020-06-09T19:37:48","cld_nonce":"b6d6726996","content":{"rendered":"<p>Habe Probleme mit den Download der Updates es wird bei mir 0% wird heruntergeladen angezeigt gef\u00fchlt schon \u00fcber 25min. Jemand selbe Erfahrungen? Dies bei dem Flash Update und dem KB4557957<\/p>\n"},"status":"1"},{"id":136829,"parent":136827,"author":0,"author_name":"Tobi","author_email":"h.wiki@gmx.ch","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0b2e89b59afb2ccec986acfe00c1e514179a010a27359fdac4e36bc0198fe39f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0b2e89b59afb2ccec986acfe00c1e514179a010a27359fdac4e36bc0198fe39f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0b2e89b59afb2ccec986acfe00c1e514179a010a27359fdac4e36bc0198fe39f?s=96&d=mm&r=g"},"date":"2020-06-09T19:46:28","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hat sich erledigt nach einem PC Neustart ging der Download.<\/p>\n"},"status":"1"},{"id":136831,"parent":0,"author":6251,"author_name":"MANU","author_email":"manu.beitz@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=96&d=mm&r=g"},"date":"2020-06-09T19:51:42","cld_nonce":"b6d6726996","content":{"rendered":"<p>(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<\/p>\n"},"status":"1"},{"id":136834,"parent":0,"author":0,"author_name":"Guiseppe","author_email":"G.S@tiscali.it","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b5b1428117a6d88dc007b884753509b0c3f4453a63fc745bfa6b59e2e8ce085e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b5b1428117a6d88dc007b884753509b0c3f4453a63fc745bfa6b59e2e8ce085e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b5b1428117a6d88dc007b884753509b0c3f4453a63fc745bfa6b59e2e8ce085e?s=96&d=mm&r=g"},"date":"2020-06-09T20:01:23","cld_nonce":"b6d6726996","content":{"rendered":"<p>DU for sources<\/p>\n<p><a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/crup\/2020\/06\/windows10.0-kb4557956-x64_483c9e81af42062a297ae13022855ad19cf3df25.cab\" rel=\"nofollow ugc\">http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/crup\/2020\/06\/windows10.0-kb4557956-x64_483c9e81af42062a297ae13022855ad19cf3df25.cab<\/a><\/p>\n<p><a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/crup\/2020\/06\/windows10.0-kb4557956-arm64_881ebc64acf44326a5f36e4b017158aa64bb454f.cab\" rel=\"nofollow ugc\">http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/crup\/2020\/06\/windows10.0-kb4557956-arm64_881ebc64acf44326a5f36e4b017158aa64bb454f.cab<\/a><\/p>\n<p><a href=\"http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/crup\/2020\/06\/windows10.0-kb4557956-x86_bc7c4a051d6ea74ca4a2e6a98bdb7b325eef352f.cab\" rel=\"nofollow ugc\">http:\/\/download.windowsupdate.com\/c\/msdownload\/update\/software\/crup\/2020\/06\/windows10.0-kb4557956-x86_bc7c4a051d6ea74ca4a2e6a98bdb7b325eef352f.cab<\/a><\/p>\n"},"status":"1"},{"id":136836,"parent":0,"author":0,"author_name":"Guiseppe","author_email":"G.S@tiscali.it","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b5b1428117a6d88dc007b884753509b0c3f4453a63fc745bfa6b59e2e8ce085e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b5b1428117a6d88dc007b884753509b0c3f4453a63fc745bfa6b59e2e8ce085e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b5b1428117a6d88dc007b884753509b0c3f4453a63fc745bfa6b59e2e8ce085e?s=96&d=mm&r=g"},"date":"2020-06-09T20:04:49","cld_nonce":"b6d6726996","content":{"rendered":"<p>Adobe Flash<\/p>\n<p><a href=\"http:\/\/download.windowsupdate.com\/d\/msdownload\/update\/software\/secu\/2020\/06\/windows10.0-kb4561600-x64_c1b68e8ebc584fba22606561477bfd8d6ca553d6.msu\" rel=\"nofollow ugc\">http:\/\/download.windowsupdate.com\/d\/msdownload\/update\/software\/secu\/2020\/06\/windows10.0-kb4561600-x64_c1b68e8ebc584fba22606561477bfd8d6ca553d6.msu<\/a><\/p>\n<p><a href=\"http:\/\/download.windowsupdate.com\/d\/msdownload\/update\/software\/secu\/2020\/06\/windows10.0-kb4561600-arm64_fae0a85abcb9cbb73f2c168610c53823bf55dd4c.msu\" rel=\"nofollow ugc\">http:\/\/download.windowsupdate.com\/d\/msdownload\/update\/software\/secu\/2020\/06\/windows10.0-kb4561600-arm64_fae0a85abcb9cbb73f2c168610c53823bf55dd4c.msu<\/a><\/p>\n<p><a href=\"http:\/\/download.windowsupdate.com\/d\/msdownload\/update\/software\/secu\/2020\/06\/windows10.0-kb4561600-x86_a1c151c7310f1ef50641d35d2f7575c305831d94.msu\" rel=\"nofollow ugc\">http:\/\/download.windowsupdate.com\/d\/msdownload\/update\/software\/secu\/2020\/06\/windows10.0-kb4561600-x86_a1c151c7310f1ef50641d35d2f7575c305831d94.msu<\/a><\/p>\n"},"status":"1"},{"id":136837,"parent":0,"author":0,"author_name":"Guiseppe","author_email":"G.S@tiscali.it","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b5b1428117a6d88dc007b884753509b0c3f4453a63fc745bfa6b59e2e8ce085e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b5b1428117a6d88dc007b884753509b0c3f4453a63fc745bfa6b59e2e8ce085e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b5b1428117a6d88dc007b884753509b0c3f4453a63fc745bfa6b59e2e8ce085e?s=96&d=mm&r=g"},"date":"2020-06-09T20:06:27","cld_nonce":"b6d6726996","content":{"rendered":"<p>Sorry 1x Doppel Post von mir.<\/p>\n"},"status":"1"},{"id":136838,"parent":0,"author":6251,"author_name":"MANU","author_email":"manu.beitz@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=96&d=mm&r=g"},"date":"2020-06-09T20:10:00","cld_nonce":"b6d6726996","content":{"rendered":"<p>Haben wir wieder Vollmond???<\/p>\n"},"status":"1"},{"id":136839,"parent":0,"author":0,"author_name":"Guiseppe","author_email":"G.S@tiscali.it","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b5b1428117a6d88dc007b884753509b0c3f4453a63fc745bfa6b59e2e8ce085e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b5b1428117a6d88dc007b884753509b0c3f4453a63fc745bfa6b59e2e8ce085e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b5b1428117a6d88dc007b884753509b0c3f4453a63fc745bfa6b59e2e8ce085e?s=96&d=mm&r=g"},"date":"2020-06-09T20:11:24","cld_nonce":"b6d6726996","content":{"rendered":"<p>hmm nein *g<\/p>\n<p>glaube die m\u00fcssen noch freigeschaltet werden.<\/p>\n"},"status":"1"},{"id":136840,"parent":0,"author":2367,"author_name":"throkr","author_email":"audiopearls@yahoo.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ae60d1c352522ec98268a4f28b5d0923b8d1eef4f9b002c2e846d483d3467fd9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ae60d1c352522ec98268a4f28b5d0923b8d1eef4f9b002c2e846d483d3467fd9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ae60d1c352522ec98268a4f28b5d0923b8d1eef4f9b002c2e846d483d3467fd9?s=96&d=mm&r=g"},"date":"2020-06-09T20:16:18","cld_nonce":"b6d6726996","content":{"rendered":"<p>Problemlose (und schnelle) Installation \u00fcber WU; es kam auch noch KB4561600 &#8211; Update f\u00fcr Adobe FP dazu.<br \/>\nLeider ist die Defrag Funktion noch immer unbrauchbar &#8230;<\/p>\n"},"status":"1"},{"id":136841,"parent":136838,"author":4241,"author_name":"Ben","author_email":"benderarsch@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=96&d=mm&r=g"},"date":"2020-06-09T20:21:21","cld_nonce":"b6d6726996","content":{"rendered":"<p>Warum Vollmond? <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_confused.gif\" alt=\":???:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136843,"parent":0,"author":0,"author_name":"FAULESAU","author_email":"pumphut02681@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5ee5c6b3d5723097f1e1ba5237db06bd86e13959f35edff2075451aa3efdcfdc?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5ee5c6b3d5723097f1e1ba5237db06bd86e13959f35edff2075451aa3efdcfdc?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5ee5c6b3d5723097f1e1ba5237db06bd86e13959f35edff2075451aa3efdcfdc?s=96&d=mm&r=g"},"date":"2020-06-09T20:23:46","cld_nonce":"b6d6726996","content":{"rendered":"<p>Guten Abend,<br \/>\n2-Rechner sind fertig, der Rest folgt dann Morgen, ohne Probleme.<\/p>\n"},"status":"1"},{"id":136844,"parent":0,"author":4861,"author_name":"Windows","author_email":"windows@opentrash.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e183a28a441456e6797f82bd2b2870aeb206a0b00c2d207925e54df950ec7aba?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e183a28a441456e6797f82bd2b2870aeb206a0b00c2d207925e54df950ec7aba?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e183a28a441456e6797f82bd2b2870aeb206a0b00c2d207925e54df950ec7aba?s=96&d=mm&r=g"},"date":"2020-06-09T20:34:15","cld_nonce":"b6d6726996","content":{"rendered":"<p>Installiert.<br \/>\nOhne Problme.<\/p>\n"},"status":"1"},{"id":136845,"parent":136840,"author":0,"author_name":"FAULESAU","author_email":"pumphut02681@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5ee5c6b3d5723097f1e1ba5237db06bd86e13959f35edff2075451aa3efdcfdc?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5ee5c6b3d5723097f1e1ba5237db06bd86e13959f35edff2075451aa3efdcfdc?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5ee5c6b3d5723097f1e1ba5237db06bd86e13959f35edff2075451aa3efdcfdc?s=96&d=mm&r=g"},"date":"2020-06-09T20:37:26","cld_nonce":"b6d6726996","content":{"rendered":"<p>Die Verkalkung ist bei der PRO-Version g\u00f6sser (Programme\/Features) Anzeige wie er gern M\u00f6chte der Herr Windows, bei HOME ist das nicht.<\/p>\n"},"status":"1"},{"id":136846,"parent":136837,"author":4861,"author_name":"Windows","author_email":"windows@opentrash.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e183a28a441456e6797f82bd2b2870aeb206a0b00c2d207925e54df950ec7aba?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e183a28a441456e6797f82bd2b2870aeb206a0b00c2d207925e54df950ec7aba?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e183a28a441456e6797f82bd2b2870aeb206a0b00c2d207925e54df950ec7aba?s=96&d=mm&r=g"},"date":"2020-06-09T20:37:31","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wenn dich J\u00fcrgen dabei erwischt, musst du dein Ausweis bei ihm abgeben. Ich m\u00f6chte nicht in deiner Haut stecken. Es gibt einige User, die beim Doppelposten erwischt wurde, wurden nie wieder gesehen. Viel Gl\u00fcck!<\/p>\n"},"status":"1"},{"id":136847,"parent":136840,"author":0,"author_name":"max","author_email":"correncourt@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7c18d5b1d39040eb3e8094c075261c07727f0d183920b777056f1fb9e1fadd5d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7c18d5b1d39040eb3e8094c075261c07727f0d183920b777056f1fb9e1fadd5d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7c18d5b1d39040eb3e8094c075261c07727f0d183920b777056f1fb9e1fadd5d?s=96&d=mm&r=g"},"date":"2020-06-09T20:45:39","cld_nonce":"b6d6726996","content":{"rendered":"<p>@throkr<br \/>\nimmer noch gleich bei dir mit Einstellung System und Nvidia?<\/p>\n"},"status":"1"},{"id":136848,"parent":0,"author":5243,"author_name":"eRaz0r","author_email":"spam84@ymail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=96&d=mm&r=g"},"date":"2020-06-09T20:52:40","cld_nonce":"b6d6726996","content":{"rendered":"<p>Keine Probleme bisher auf 3 PCs nach einigen Tests, au\u00dfer das bekannte Probleme (Defrag \/ DISM \/ etc) immer noch nicht behoben wurden haha.<\/p>\n<p>Naja &#8230; vielleicht n\u00e4chste Woche, oder \u00fcbern\u00e4chste, sofern Microsoft unter 2004 nicht auch die C&amp;D Updates ausgesetzt hat <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_razz.gif\" alt=\":P\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136849,"parent":136847,"author":0,"author_name":"throkr","author_email":"audiopearls@yahoo.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ae60d1c352522ec98268a4f28b5d0923b8d1eef4f9b002c2e846d483d3467fd9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ae60d1c352522ec98268a4f28b5d0923b8d1eef4f9b002c2e846d483d3467fd9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ae60d1c352522ec98268a4f28b5d0923b8d1eef4f9b002c2e846d483d3467fd9?s=96&d=mm&r=g"},"date":"2020-06-09T20:54:05","cld_nonce":"b6d6726996","content":{"rendered":"<p>@max<br \/>\nja leider keine \u00c4nderung &#8230;.. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":-(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136851,"parent":136841,"author":6251,"author_name":"MANU","author_email":"manu.beitz@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=96&d=mm&r=g"},"date":"2020-06-09T22:02:06","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich wollte es nirgendwo anh\u00e4ngen, aber da werden<br \/>\nSeiten verlinkt, die keiner braucht. (Text 1+2)<\/p>\n"},"status":"1"},{"id":136852,"parent":0,"author":0,"author_name":"F","author_email":"fff@ggg.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6f40f575a44f1482e16c9ba0bf0c036d3f8a2ead1aaed065b510b98d9b9a1408?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6f40f575a44f1482e16c9ba0bf0c036d3f8a2ead1aaed065b510b98d9b9a1408?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6f40f575a44f1482e16c9ba0bf0c036d3f8a2ead1aaed065b510b98d9b9a1408?s=96&d=mm&r=g"},"date":"2020-06-09T22:08:30","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei mir funktionierte nach dem Update von KB4557957 der Drucker nicht mehr. Allgemein stockte alles in den Ger\u00e4te und Drucker Optionen. Habe das Update wieder deinstalliert.<\/p>\n"},"status":"1"},{"id":136853,"parent":136851,"author":4241,"author_name":"Ben","author_email":"benderarsch@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=96&d=mm&r=g"},"date":"2020-06-09T22:09:21","cld_nonce":"b6d6726996","content":{"rendered":"<p>Achso! OK stimmt auch wieder.<\/p>\n"},"status":"1"},{"id":136854,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-09T22:26:24","cld_nonce":"b6d6726996","content":{"rendered":"<p>Man ist das lustig &#8211; &#8222;Endlosschleife beim downloaden  &amp; installieren&#8220; , aber irgendwie fehlt da die Aufforderung zum neu starten <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136855,"parent":136854,"author":4861,"author_name":"Windows","author_email":"windows@opentrash.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e183a28a441456e6797f82bd2b2870aeb206a0b00c2d207925e54df950ec7aba?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e183a28a441456e6797f82bd2b2870aeb206a0b00c2d207925e54df950ec7aba?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e183a28a441456e6797f82bd2b2870aeb206a0b00c2d207925e54df950ec7aba?s=96&d=mm&r=g"},"date":"2020-06-09T22:34:45","cld_nonce":"b6d6726996","content":{"rendered":"<p>Das ist die Aufforderung zum Kaffee holen  <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136858,"parent":136854,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-09T22:56:17","cld_nonce":"b6d6726996","content":{"rendered":"<p>dann st\u00e4nd da aber ( f\u00fcr Bier : GmBh ) und f\u00fcr Kaffe demzufolge GmKh <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136860,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-09T23:08:26","cld_nonce":"b6d6726996","content":{"rendered":"<p>im ISO-Script ist (auch bzw. wieder) kb4557964 (WinPE) enthalten<\/p>\n"},"status":"1"},{"id":136863,"parent":0,"author":3691,"author_name":"mcbloch","author_email":"mcbloch@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=96&d=mm&r=g"},"date":"2020-06-09T23:32:09","cld_nonce":"b6d6726996","content":{"rendered":"<p>Mir ist aufgefallen das sich nach dem Update der Feiertagskalender nicht mehr aktivieren l\u00e4sst.<br \/>\nAlso in der Kalender App im Startmen\u00fc.<br \/>\nIst da was bekannt dr\u00fcber ??<\/p>\n"},"status":"1"},{"id":136864,"parent":136863,"author":0,"author_name":"Sebastian DI","author_email":"bastidir@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f74125b1621d003c75a4a67fa8e334d99c2ed5211b87fafb8d90860ac53abb2d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f74125b1621d003c75a4a67fa8e334d99c2ed5211b87fafb8d90860ac53abb2d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f74125b1621d003c75a4a67fa8e334d99c2ed5211b87fafb8d90860ac53abb2d?s=96&d=mm&r=g"},"date":"2020-06-10T00:10:51","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei mir das selbe Problem.<br \/>\nHabe mich dann \u00fcber mein MS Konto eingeloggt.<br \/>\nDann wieder ausgeloggt dann gings.<br \/>\nOder eben ein bug.<\/p>\n<p>Und mach mal CMD dann tippe das ein:<br \/>\nDism \/Online \/Cleanup-Image \/RestoreHealth<\/p>\n"},"status":"1"},{"id":136867,"parent":0,"author":6279,"author_name":"Schnyff","author_email":"douz@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4795eaa13e57717a03242a86aaa411a12320be0e47a7b7231a9bc87370577868?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4795eaa13e57717a03242a86aaa411a12320be0e47a7b7231a9bc87370577868?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4795eaa13e57717a03242a86aaa411a12320be0e47a7b7231a9bc87370577868?s=96&d=mm&r=g"},"date":"2020-06-10T00:58:18","cld_nonce":"b6d6726996","content":{"rendered":"<p>Auf Button &#8222;Jetzt installieren&#8220; geklickt, Updates (incl. Adobe Flash) installiert, Neustart, fertig. Konnte bis jetzt keine ungewollten Ereignisse ausmachen. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136868,"parent":136867,"author":0,"author_name":"Sebastian DI","author_email":"bastidir@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f74125b1621d003c75a4a67fa8e334d99c2ed5211b87fafb8d90860ac53abb2d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f74125b1621d003c75a4a67fa8e334d99c2ed5211b87fafb8d90860ac53abb2d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f74125b1621d003c75a4a67fa8e334d99c2ed5211b87fafb8d90860ac53abb2d?s=96&d=mm&r=g"},"date":"2020-06-10T01:07:49","cld_nonce":"b6d6726996","content":{"rendered":"<p>Same here. Alles lief ohne Probleme durch.<br \/>\nDer Bug mit der Laufwerksoptimierung bleibt aber bestehen (Laufwerke wurden nie optimiert blabla)..<\/p>\n<p>Dism Restore geht aber zu 100% durch.<\/p>\n"},"status":"1"},{"id":136869,"parent":136864,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-10T01:34:55","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8222;Und mach mal CMD dann tippe das ein:<br \/>\nDism \/Online \/Cleanup-Image \/RestoreHealth&#8220;<\/p>\n<p>Geht auch \u00fcber Kontextmen\u00fc, wenn man die entsprechenden Reg-Eintr\u00e4ge  ausf\u00fchrt <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136870,"parent":136869,"author":0,"author_name":"Sebastian DI","author_email":"bastidir@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f74125b1621d003c75a4a67fa8e334d99c2ed5211b87fafb8d90860ac53abb2d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f74125b1621d003c75a4a67fa8e334d99c2ed5211b87fafb8d90860ac53abb2d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f74125b1621d003c75a4a67fa8e334d99c2ed5211b87fafb8d90860ac53abb2d?s=96&d=mm&r=g"},"date":"2020-06-10T02:58:10","cld_nonce":"b6d6726996","content":{"rendered":"<p>Oder so!<\/p>\n<p>;=)<\/p>\n"},"status":"1"},{"id":136871,"parent":136851,"author":0,"author_name":"Sebastian DI","author_email":"bastidir@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f74125b1621d003c75a4a67fa8e334d99c2ed5211b87fafb8d90860ac53abb2d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f74125b1621d003c75a4a67fa8e334d99c2ed5211b87fafb8d90860ac53abb2d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f74125b1621d003c75a4a67fa8e334d99c2ed5211b87fafb8d90860ac53abb2d?s=96&d=mm&r=g"},"date":"2020-06-10T03:05:03","cld_nonce":"b6d6726996","content":{"rendered":"<p>HAHA!<\/p>\n<p><img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136872,"parent":0,"author":0,"author_name":"Nelley","author_email":"fragmal@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c15c76d48504d655f6e7d749e8361534baeab73bab0b6cbc0d5913fb4f10db2d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c15c76d48504d655f6e7d749e8361534baeab73bab0b6cbc0d5913fb4f10db2d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c15c76d48504d655f6e7d749e8361534baeab73bab0b6cbc0d5913fb4f10db2d?s=96&d=mm&r=g"},"date":"2020-06-10T06:03:34","cld_nonce":"b6d6726996","content":{"rendered":"<p>1 Notebook ohne Probleme<br \/>\n2tes Notebook nach 100% Installation #Fehlermeldung + Wiederholen und klappt auch dann nicht.<\/p>\n<p>Desweiteren ist mir aufgefallen das unter Einstellungen \/ System \/ Speicher \/ Temporary Internet Files<br \/>\njetzt 54 MB Windows Update angezeigt werden die sich weder hier noch mit der Datentr\u00e4gerbereinigung l\u00f6schen lassen.<\/p>\n"},"status":"1"},{"id":136874,"parent":136872,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-10T06:15:58","cld_nonce":"b6d6726996","content":{"rendered":"<p>Cleanmgr+ <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136875,"parent":136874,"author":0,"author_name":"Nelley","author_email":"fragmal@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c15c76d48504d655f6e7d749e8361534baeab73bab0b6cbc0d5913fb4f10db2d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c15c76d48504d655f6e7d749e8361534baeab73bab0b6cbc0d5913fb4f10db2d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c15c76d48504d655f6e7d749e8361534baeab73bab0b6cbc0d5913fb4f10db2d?s=96&d=mm&r=g"},"date":"2020-06-10T06:39:45","cld_nonce":"b6d6726996","content":{"rendered":"<p>OK, Danke. Scheint recht einfach zu sein. Werde ich heute Abend probieren.<\/p>\n<p>Gr\u00fc\u00dfe<\/p>\n"},"status":"1"},{"id":136876,"parent":136846,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-06-10T06:43:40","cld_nonce":"b6d6726996","content":{"rendered":"<p><img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136877,"parent":136852,"author":0,"author_name":"FF","author_email":"fff@ggg.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6f40f575a44f1482e16c9ba0bf0c036d3f8a2ead1aaed065b510b98d9b9a1408?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6f40f575a44f1482e16c9ba0bf0c036d3f8a2ead1aaed065b510b98d9b9a1408?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6f40f575a44f1482e16c9ba0bf0c036d3f8a2ead1aaed065b510b98d9b9a1408?s=96&d=mm&r=g"},"date":"2020-06-10T07:31:12","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ist ein Lenovo ThinkPad T420<\/p>\n"},"status":"1"},{"id":136879,"parent":136874,"author":2897,"author_name":"Bastardo","author_email":"joachim@lindengang.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c5ae2c5c74c37695ef5316999d5a84b3a4e47dc9575577705c8f995c23394b51?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c5ae2c5c74c37695ef5316999d5a84b3a4e47dc9575577705c8f995c23394b51?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c5ae2c5c74c37695ef5316999d5a84b3a4e47dc9575577705c8f995c23394b51?s=96&d=mm&r=g"},"date":"2020-06-10T07:53:10","cld_nonce":"b6d6726996","content":{"rendered":"<p>Das gleiche hier, hab&#8216; es bis jetzt auch noch nicht im Griff.<\/p>\n"},"status":"1"},{"id":136893,"parent":136868,"author":0,"author_name":"Carsten","author_email":"c.richter@jazzvisions.eu","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=96&d=mm&r=g"},"date":"2020-06-10T11:19:53","cld_nonce":"b6d6726996","content":{"rendered":"<p>Kann ich best\u00e4tigen. DISM RestoreHealth l\u00e4uft auch bei mir wieder bis 100% durch.<\/p>\n"},"status":"1"},{"id":136895,"parent":136847,"author":0,"author_name":"throkr","author_email":"audiopearls@yahoo.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ae60d1c352522ec98268a4f28b5d0923b8d1eef4f9b002c2e846d483d3467fd9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ae60d1c352522ec98268a4f28b5d0923b8d1eef4f9b002c2e846d483d3467fd9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ae60d1c352522ec98268a4f28b5d0923b8d1eef4f9b002c2e846d483d3467fd9?s=96&d=mm&r=g"},"date":"2020-06-10T11:21:09","cld_nonce":"b6d6726996","content":{"rendered":"<p>@max<br \/>\nDamit es nicht st\u00f6rt, ein Workaround: Einstellungen &gt; Update &amp; Sicherheit &gt; Speicher (an der rechten Seite)&#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":136901,"parent":136838,"author":2038,"author_name":"GwenDragon","author_email":"info@gwendragon.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ab9cf037d6cbcba5c651656468693c8727c7122d9141dfa149b5ce8cc5923c48?s=96&d=mm&r=g"},"date":"2020-06-10T13:51:23","cld_nonce":"b6d6726996","content":{"rendered":"<p>Nein, es sind Schulferien, dann kommen alle, die sich langweilen.<\/p>\n"},"status":"1"},{"id":136908,"parent":136895,"author":0,"author_name":"max","author_email":"correncourt@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7c18d5b1d39040eb3e8094c075261c07727f0d183920b777056f1fb9e1fadd5d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7c18d5b1d39040eb3e8094c075261c07727f0d183920b777056f1fb9e1fadd5d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7c18d5b1d39040eb3e8094c075261c07727f0d183920b777056f1fb9e1fadd5d?s=96&d=mm&r=g"},"date":"2020-06-10T16:17:00","cld_nonce":"b6d6726996","content":{"rendered":"<p>@throkr<br \/>\nBin am richtig bl\u00f6d um den Fehler im Googeln nachforschen. Leider bis jetzt mit keiner L\u00f6sung. Ok danke f\u00fcr den Tipp!<\/p>\n"},"status":"1"},{"id":136911,"parent":0,"author":0,"author_name":"Eisenvater","author_email":"rolle.andre@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/165fe2c09ed4e271f0372a64ff5bc9bdfc8c027bc4f6be36eb601cad0eac35f9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/165fe2c09ed4e271f0372a64ff5bc9bdfc8c027bc4f6be36eb601cad0eac35f9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/165fe2c09ed4e271f0372a64ff5bc9bdfc8c027bc4f6be36eb601cad0eac35f9?s=96&d=mm&r=g"},"date":"2020-06-10T17:29:21","cld_nonce":"b6d6726996","content":{"rendered":"<p>Kam heute Nacht per WU, seit dem habe ich das Problem, das mein Wlan regelm\u00e4\u00dfig abbricht.<br \/>\nIch nutze den AWUS036NHA von Alfa.<\/p>\n"},"status":"1"},{"id":136913,"parent":136901,"author":4861,"author_name":"Windows","author_email":"windows@opentrash.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e183a28a441456e6797f82bd2b2870aeb206a0b00c2d207925e54df950ec7aba?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e183a28a441456e6797f82bd2b2870aeb206a0b00c2d207925e54df950ec7aba?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e183a28a441456e6797f82bd2b2870aeb206a0b00c2d207925e54df950ec7aba?s=96&d=mm&r=g"},"date":"2020-06-10T18:01:33","cld_nonce":"b6d6726996","content":{"rendered":"<p>GwenDragon mache dir bitte ein Avatar&#8230;<\/p>\n"},"status":"1"},{"id":136920,"parent":0,"author":3838,"author_name":"Hagal2","author_email":"jann1977@arcor.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/62f5edf9319ff6932d0c655e4795c8d8bd19e0e9482edd8d475331215183d76d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/62f5edf9319ff6932d0c655e4795c8d8bd19e0e9482edd8d475331215183d76d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/62f5edf9319ff6932d0c655e4795c8d8bd19e0e9482edd8d475331215183d76d?s=96&d=mm&r=g"},"date":"2020-06-10T20:37:19","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ja kann ich best\u00e4tigen Defrag verh\u00e4lt sich Merkw\u00fcrdig habe es per Hand bei der SSD ausschalten m\u00fcssen, dennoch Fummelt der da im Hintergrund was rum, in der Ereignissanzeige steht immer was das Win Defrag auf C: was analisiert. Wozu und wenn es deaktivert ist sollte der da ja gar nichts mehr Rumwurschteln.<\/p>\n<p>WLAN Weltkugel Bug ist auch noch da. Alles in allem finde ich die 2004 bis jetzt sehr nervig.<\/p>\n<p>mfg<\/p>\n"},"status":"1"},{"id":136921,"parent":136879,"author":0,"author_name":"Nelley","author_email":"fragmal@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c15c76d48504d655f6e7d749e8361534baeab73bab0b6cbc0d5913fb4f10db2d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c15c76d48504d655f6e7d749e8361534baeab73bab0b6cbc0d5913fb4f10db2d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c15c76d48504d655f6e7d749e8361534baeab73bab0b6cbc0d5913fb4f10db2d?s=96&d=mm&r=g"},"date":"2020-06-10T20:58:45","cld_nonce":"b6d6726996","content":{"rendered":"<p>Also Cleanmgr+ hat nichts gebracht.<br \/>\nDie 54MB werden immer noch bei der Suche in den  Temporary Internet Files angezeigt.<br \/>\nKomischerweise au\u00dferhalb nicht da werden ca. 6MB angezeigt.<\/p>\n"},"status":"1"},{"id":136951,"parent":136872,"author":0,"author_name":"DarkBasic86","author_email":"darkbasic@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1fa6d0714bb82e0b8d9bfd0121cf76fbc531fade454cb9a81d15ec3022319cee?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1fa6d0714bb82e0b8d9bfd0121cf76fbc531fade454cb9a81d15ec3022319cee?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1fa6d0714bb82e0b8d9bfd0121cf76fbc531fade454cb9a81d15ec3022319cee?s=96&d=mm&r=g"},"date":"2020-06-11T02:01:37","cld_nonce":"b6d6726996","content":{"rendered":"<p>Gleiches Problem hier, er bricht mit Fehlercode 0x800f0988 ab.<br \/>\nHab schon alles per DISM \u00fcberpr\u00fcfen\/reparieren\/cleanen lassen, aber keine Ver\u00e4nderung.<\/p>\n<p>Mit der Datentr\u00e4gerbereinigung\/Cleanmgr+ hab ich kein Problem, aber das betrifft 19041.264 wahrscheinlich nicht, wohl erst nach den Update auf die .329 !?<\/p>\n<p>Irgend welche Tipps? Immer her damit.<\/p>\n"},"status":"1"},{"id":136972,"parent":0,"author":0,"author_name":"sabine","author_email":"sabi1967@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0684d1ad4d68692d07efac8e093bf049abf877197aeb0bae658ea1e872970d2c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0684d1ad4d68692d07efac8e093bf049abf877197aeb0bae658ea1e872970d2c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0684d1ad4d68692d07efac8e093bf049abf877197aeb0bae658ea1e872970d2c?s=96&d=mm&r=g"},"date":"2020-06-11T11:55:43","cld_nonce":"b6d6726996","content":{"rendered":"<p>Nach dem Update von KB4557957 druckt der Brother DCP nicht mehr.<br \/>\nPC ist Desktop AMD FX-9370, 16GB, Win10 prof.<br \/>\nDer Scanner wird bei der Brother Installationspr\u00fcfung  positiv angezeigt,<br \/>\nder Druckertreiber als fehlerhaft.<br \/>\nTreiberpaket komplett neu installiert, Drucker wird richtigerweise als USB001 angezeigt.<br \/>\nBeim Druckversuch aus verschiedenen Anwendungen blitzt das Druckerdisplay nur kurz auf.<br \/>\nNach stundenlangen Versuchen half nur eine Deinstallation des Updates.<br \/>\nJetzt funktioniert alles wieder normal.<br \/>\nAlso wieder mal ein Murks-Update-Verschlechterung von MS  <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":137003,"parent":136972,"author":0,"author_name":"F","author_email":"fff@gg.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ee1e6b27e791834843e32ce6a0451d2c1c8f7e2e1d3eac8381011add87752f36?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ee1e6b27e791834843e32ce6a0451d2c1c8f7e2e1d3eac8381011add87752f36?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ee1e6b27e791834843e32ce6a0451d2c1c8f7e2e1d3eac8381011add87752f36?s=96&d=mm&r=g"},"date":"2020-06-11T18:46:49","cld_nonce":"b6d6726996","content":{"rendered":"<p>Habe \u00e4hnliche Probleme mit meinem Lenovo T420 und Brother MFC-Drucker. Das Update habe ich auch wieder deinstalliert.<\/p>\n"},"status":"1"},{"id":137004,"parent":136972,"author":3838,"author_name":"Hagal2","author_email":"jann1977@arcor.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/62f5edf9319ff6932d0c655e4795c8d8bd19e0e9482edd8d475331215183d76d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/62f5edf9319ff6932d0c655e4795c8d8bd19e0e9482edd8d475331215183d76d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/62f5edf9319ff6932d0c655e4795c8d8bd19e0e9482edd8d475331215183d76d?s=96&d=mm&r=g"},"date":"2020-06-11T18:48:31","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hui du hast ein Centruion FX <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/> seltenes St\u00fcck.<\/p>\n<p>Ja ich habe ihr auch \u00e4rger mit der 2004, so viel Stress mit Win10 hatte ich das letzte Mal als die erste Verion rauskam&#8230;<\/p>\n<p>mfg<\/p>\n"},"status":"1"},{"id":137153,"parent":136872,"author":0,"author_name":"Mirko Siepmann","author_email":"msiepmann0406@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a8cd0dd10ae280cf817d0d7342319aa1d7a002a64bb1d1da3d1fe93f6978468d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a8cd0dd10ae280cf817d0d7342319aa1d7a002a64bb1d1da3d1fe93f6978468d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a8cd0dd10ae280cf817d0d7342319aa1d7a002a64bb1d1da3d1fe93f6978468d?s=96&d=mm&r=g"},"date":"2020-06-13T13:50:01","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei mir das selbe&#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/> Nach der angeblichen installation zeigt er Wiederholen an. Update leider nicht m\u00f6glich zu installieren.<\/p>\n"},"status":"1"},{"id":137361,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-06-16T08:32:28","cld_nonce":"b6d6726996","content":{"rendered":"<p>So ganz am Rande:<br \/>\nIst Euch schon aufgefallen, da\u00df nach diesem Update (KB4557957 )der &#8222;Klammeraffe&#8220; (@) nicht mehr \u00fcber die Tasten STRG+ALT+Q erreichbar ist ???<br \/>\nRief mich gestern Abend doch ein (schon etwas \u00e4lterer) Kunde an, er k\u00f6nne &#8222;keine eMail mehr versenden &#8211; das @ w\u00fcrde zwar noch eingegeben und angezeigt, aber rot unterlegt und ohne Wirkung&#8220; &#8230;<br \/>\nDa war selbst dem lieben Harry sein Gesicht ratlos! Erst nach fast 2 Stunden &#8222;Diagnose&#8220; mit anschlie\u00dfender gr\u00fcndlichster &#8222;Anamnese&#8220; brachte es ans Licht: Auch er mu\u00df ab sofort die ALTGR+Q-Tasten benuitzen! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><br \/>\nNa ja, zumindest hat er seinen Lebensmut zur\u00fcckgewonnen!<br \/>\nJetzt wartet der liebe Harry nur noch darauf, da\u00df ihm daf\u00fcr endlich jemand auf die Schulter klopft &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":137367,"parent":0,"author":0,"author_name":"Guiseppe","author_email":"MyCarRadio@tiscali.it","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7bb9ba3202ba87a6d0db6e5eac1347adb08ac9d9420b33cdf2f1da4754b01e57?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7bb9ba3202ba87a6d0db6e5eac1347adb08ac9d9420b33cdf2f1da4754b01e57?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7bb9ba3202ba87a6d0db6e5eac1347adb08ac9d9420b33cdf2f1da4754b01e57?s=96&d=mm&r=g"},"date":"2020-06-16T10:46:53","cld_nonce":"b6d6726996","content":{"rendered":"<p>Welches E-Mail Programm wurde denn benutzt, denn bei mir funktionieren alle Kombinationen.<br \/>\nGerade getestet mit Yahoo Web Mail.<br \/>\nAllerdings nur auf 19041.329 X86 getestet.<\/p>\n"},"status":"1"},{"id":137368,"parent":137367,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-06-16T10:48:27","cld_nonce":"b6d6726996","content":{"rendered":"<p>Direkt auf der Website von Web.de &#8211; kein separates Mail-Programm. Browser: Edge (neu) &#8230;<br \/>\nWar auch Win 10 Pro x86 .329 &#8230;<br \/>\nAnmerkung: Vor dem Update hatte Alles noch funktioniert.<\/p>\n"},"status":"1"},{"id":137369,"parent":137361,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-16T10:53:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>auch mal die Taste ALT in Verbindung mit Eingabe von 64 auf dem Nummerblock probiert ?<\/p>\n<p>&#8211; wollte gerade schreiben &#8222;Also bei mir funktioniert STRG+ALT+Q&#8220; <b>aber<\/b> bin gerade ja mit der 19645.1 unterwegs <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":137371,"parent":137369,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-06-16T10:59:21","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ehm, Manny, Notebook ohne separaten Nummern-Block &#8230; Da h\u00e4tte er &#8222;mitten im Tippen&#8220; (upps &#8211; ein Reim) auch noch Fn+Num (und danach zur\u00fcck) eingeben m\u00fcssen &#8211; das h\u00e4tte er wohl kaum verstanden bzw. mitmachen k\u00f6nnen &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":-(\" class=\"wp-smiley\" \/><br \/>\nMacht aber nix &#8211; er meinte eh, so w\u00e4re das sogar einfacher (weil nur 2 statt 3 Tasten n\u00f6tig).<\/p>\n"},"status":"1"},{"id":137372,"parent":0,"author":0,"author_name":"Guiseppe","author_email":"MyCarRadio@tiscali.it","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7bb9ba3202ba87a6d0db6e5eac1347adb08ac9d9420b33cdf2f1da4754b01e57?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7bb9ba3202ba87a6d0db6e5eac1347adb08ac9d9420b33cdf2f1da4754b01e57?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7bb9ba3202ba87a6d0db6e5eac1347adb08ac9d9420b33cdf2f1da4754b01e57?s=96&d=mm&r=g"},"date":"2020-06-16T11:04:35","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich hatte das erst mit dem Firefox 77.0.1 auf der Yahoo Seite getestet,<br \/>\nund eben nochmals mit dem neuem Edge.<br \/>\nHier funktioniert es tatellos.<\/p>\n"},"status":"1"},{"id":137373,"parent":137369,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-16T11:06:19","cld_nonce":"b6d6726996","content":{"rendered":"<p>@Harry S<\/p>\n<p>also bei mir geht es bei der *.329 mit STRG ALT Q &#8211; bei Notebook m\u00fcsste es eigentlich auch gehen, dr\u00fccke ich in <b>einem<\/b> FN-ALTGr &#8211; die rechte Kombinationsm\u00f6glichkeit bei meiner Logitech MX710 mit FN-Taste &#8211; kommt auch das @<\/p>\n"},"status":"1"},{"id":137375,"parent":137372,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-06-16T11:12:19","cld_nonce":"b6d6726996","content":{"rendered":"<p>@Manny, @Guiseppe<br \/>\nHab das auf mehreren Rechnern auch nochmal ausgetestet &#8211; konnte das Verhalten auch nicht reproduzieren. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":-(\" class=\"wp-smiley\" \/><br \/>\nWer wei\u00df, was da auf dem Kunden-Notebook noch so alles im Hintergrund mitl\u00e4uft &#8230;<br \/>\nKann man am Telefon ganz schlecht sehen bzw. \u00fcberpr\u00fcfen &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><br \/>\nNa ja, ich treffe den Kunden demn\u00e4chst bei unserem n\u00e4chsten Grill-Abend wieder und werde da nochmal intensiv nachhaken. Bin echt angestachelt &#8211; weil: Sowas war\/ist mir v\u00f6llig neu !!! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":137380,"parent":0,"author":0,"author_name":"Guiseppe","author_email":"MyCarRadio@tiscali.it","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7bb9ba3202ba87a6d0db6e5eac1347adb08ac9d9420b33cdf2f1da4754b01e57?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7bb9ba3202ba87a6d0db6e5eac1347adb08ac9d9420b33cdf2f1da4754b01e57?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7bb9ba3202ba87a6d0db6e5eac1347adb08ac9d9420b33cdf2f1da4754b01e57?s=96&d=mm&r=g"},"date":"2020-06-16T12:16:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>AltGr  und den Klammeraffe  ( Taste Q ), ist eh die geschicktlichste Tasten Kombi, zumindestens finde ich es so.<\/p>\n<p>Rechter Zeigefinger auf AltGr und mit dem Linken Zeigefinger das Q gedr\u00fcckt.<\/p>\n<p>Manny hat die 19645.1  noch Wasserzeichen, falls ja nimmt die das Wasserzeichen raus , sobald es zum Final Update kommt, und man es einspielt ?<\/p>\n"},"status":"1"},{"id":137384,"parent":137380,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-16T13:16:14","cld_nonce":"b6d6726996","content":{"rendered":"<p><a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/06\/11\/windows-10-19645-iso-esd-deutsch-english\/\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2020\/06\/11\/windows-10-19645-iso-esd-deutsch-english\/<\/a><br \/>\n&#8211; 2.Absatz von oben<\/p>\n"},"status":"1"},{"id":137857,"parent":0,"author":0,"author_name":"Fa","author_email":"ff@ff.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6867e103912b72d2119f26f0c5ccaceb9acf38a69cc76f9864726c2105a99afe?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6867e103912b72d2119f26f0c5ccaceb9acf38a69cc76f9864726c2105a99afe?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6867e103912b72d2119f26f0c5ccaceb9acf38a69cc76f9864726c2105a99afe?s=96&d=mm&r=g"},"date":"2020-06-18T21:03:24","cld_nonce":"b6d6726996","content":{"rendered":"<p><a href=\"https:\/\/support.microsoft.com\/de-de\/help\/4567523\" rel=\"nofollow ugc\">https:\/\/support.microsoft.com\/de-de\/help\/4567523<\/a><\/p>\n<p>Neues Update f\u00fcr die 2004er-Version<\/p>\n"},"status":"1"},{"id":137861,"parent":137857,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-06-18T21:05:58","cld_nonce":"b6d6726996","content":{"rendered":"<p>das ist &#8222;nur&#8220; ein Update f\u00fcr gewisse Drucker bzw. deren &#8222;Probleme&#8220;<br \/>\n&#8222;Aktualisiert ein Problem, das m\u00f6glicherweise verhindert, dass bestimmte Drucker drucken, Druckfehler generieren oder dazu f\u00fchren, dass Apps und Druckspooler unerwartet geschlossen werden.&#8220;<\/p>\n<p>wurde auch schon im Artikel<br \/>\n<a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/06\/18\/kb4567523-drucker-update-windows-10-2004-2009-1709-1703-1607-und1507\/\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2020\/06\/18\/kb4567523-drucker-update-windows-10-2004-2009-1709-1703-1607-und1507\/<\/a><br \/>\nerw\u00e4hnt<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>KB4557957 + KB4560366 als SSU (Manueller Download) Windows 10 2004 19041.329 Sicherheitsupdate Juni - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KB4557957 + KB4560366 als SSU (Manueller Download) Windows 10 2004 19041.329 Sicherheitsupdate Juni\" \/>\n<meta property=\"og:description\" content=\"Patchday Juni 2020: Nachdem Microsoft die Windows 10 2004 (Mai 2020 Update) nun offiziell freigegeben hat ist es nun Zeit f\u00fcr das neue kumulative Sicherheitsupdate KB 4557957. Dadurch erh\u00f6ht sich die Versionsnummer auf die Windows 10 19041.329 Windows 10 2004&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-09T17:04:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-13T09:37:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"558\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"KB4557957 + KB4560366 als SSU (Manueller Download) Windows 10 2004 19041.329 Sicherheitsupdate Juni\",\"datePublished\":\"2020-06-09T17:04:19+00:00\",\"dateModified\":\"2020-06-13T09:37:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/\"},\"wordCount\":632,\"commentCount\":64,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/windows-update-logo.png\",\"keywords\":[\"19041.329\",\"KB 4557957\",\"KB4557957\",\"msu\",\"neues Update\",\"Patchday Juni 2020\",\"Win 10 2004\",\"Windows 10 2004\",\"windows10.0-kb4557957-x64.msu\",\"windows10.0-kb4560366-x64\"],\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/\",\"name\":\"KB4557957 + KB4560366 als SSU (Manueller Download) Windows 10 2004 19041.329 Sicherheitsupdate Juni - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/windows-update-logo.png\",\"datePublished\":\"2020-06-09T17:04:19+00:00\",\"dateModified\":\"2020-06-13T09:37:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/windows-update-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/windows-update-logo.png\",\"width\":558,\"height\":401},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/06\\\/09\\\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KB4557957 + KB4560366 als SSU (Manueller Download) Windows 10 2004 19041.329 Sicherheitsupdate Juni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"KB4557957 + KB4560366 als SSU (Manueller Download) Windows 10 2004 19041.329 Sicherheitsupdate Juni - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/","og_locale":"de_DE","og_type":"article","og_title":"KB4557957 + KB4560366 als SSU (Manueller Download) Windows 10 2004 19041.329 Sicherheitsupdate Juni","og_description":"Patchday Juni 2020: Nachdem Microsoft die Windows 10 2004 (Mai 2020 Update) nun offiziell freigegeben hat ist es nun Zeit f\u00fcr das neue kumulative Sicherheitsupdate KB 4557957. Dadurch erh\u00f6ht sich die Versionsnummer auf die Windows 10 19041.329 Windows 10 2004&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-06-09T17:04:19+00:00","article_modified_time":"2020-06-13T09:37:43+00:00","og_image":[{"width":558,"height":401,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"KB4557957 + KB4560366 als SSU (Manueller Download) Windows 10 2004 19041.329 Sicherheitsupdate Juni","datePublished":"2020-06-09T17:04:19+00:00","dateModified":"2020-06-13T09:37:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/"},"wordCount":632,"commentCount":64,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo.png","keywords":["19041.329","KB 4557957","KB4557957","msu","neues Update","Patchday Juni 2020","Win 10 2004","Windows 10 2004","windows10.0-kb4557957-x64.msu","windows10.0-kb4560366-x64"],"articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/","name":"KB4557957 + KB4560366 als SSU (Manueller Download) Windows 10 2004 19041.329 Sicherheitsupdate Juni - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo.png","datePublished":"2020-06-09T17:04:19+00:00","dateModified":"2020-06-13T09:37:43+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo.png","width":558,"height":401},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/06\/09\/kb4557957-kb4560366-als-ssu-manueller-download-windows-10-2004-19041-329-sicherheitsupdate-juni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"KB4557957 + KB4560366 als SSU (Manueller Download) Windows 10 2004 19041.329 Sicherheitsupdate Juni"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-update-logo.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/139896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=139896"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/139896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/111268"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=139896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=139896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=139896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}