{"id":139079,"date":"2020-05-21T19:05:46","date_gmt":"2020-05-21T17:05:46","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=139079"},"modified":"2020-05-25T10:05:03","modified_gmt":"2020-05-25T08:05:03","slug":"windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/","title":{"rendered":"Windows 10 19631 + SDK steht f\u00fcr die Insider zum Download bereit + 19624 ARM VHDX"},"content":{"rendered":"<p>Eine neue Insider Build hat Microsoft bereitgestellt. Die 19631.1, genauer die 10.0.19631.1 mn _release (Codename Manganese) vom 14.05.2020. Wie schon in der Vorg\u00e4ngerversion wurden hier nur wieder Fehler korrigiert.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/05\/windows-10-19631.jpg\" rel=\"lightbox[139079]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/05\/windows-10-19631-500x317.jpg\" alt=\"\" width=\"500\" height=\"317\" class=\"aligncenter size-medium wp-image-139144\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/05\/windows-10-19631-500x317.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/05\/windows-10-19631-810x514.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/05\/windows-10-19631-306x194.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/05\/windows-10-19631.jpg 1097w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Richtig interessant wird es erst im Juni, wenn das Insider-Team dann auf den Unterbau der Windows 10 21H1 (Codename Iron [FE]) wechselt. Dann werden wir auch wieder (endlich) ein paar \u00c4nderungen ausprobieren k\u00f6nnen. Die Windows 10 19042 20H2 wird dann wie auch schon bei der 1909 Insider im Slow Ring abgearbeitet werden. Wir hatten ja <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/05\/16\/integration-der-windows-10-2009-funktionen-in-die-windows-10-2004-hat-schon-begonnen\/\" rel=\"noopener noreferrer\" target=\"_blank\">schon dar\u00fcber berichtet<\/a>.<\/p>\n<p>Wie immer werden wir nat\u00fcrlich versuchen die ISO Dateien zu sammeln und stellen dann den Link hier rein. Oder ihr schaut in der rechten Sidebar vorbei. <strong>[Update]:<\/strong> Hier ist der <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/05\/22\/windows-10-19631-iso-esd-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">Link zu den ISO Dateien<\/a> auch schon. Nebenbei hat Microsoft auch gleich wieder das aktuelle <strong>Windows SDK 19631<\/strong> zum Download bereitgestellt. Dies erhaltet ihr <a href=\"https:\/\/www.microsoft.com\/en-us\/software-download\/windowsinsiderpreviewSDK\" rel=\"noopener noreferrer\" target=\"_blank\">hier<\/a>, bzw. falls nicht vorhanden \u00fcber <a href=\"https:\/\/tb.32767.ga\/products.php?search=19631&#038;prod=all\" rel=\"noopener noreferrer\" target=\"_blank\">diesen Link<\/a> (Insider-Konto vorausgesetzt).<\/p>\n<h3>Windows 10 Insider ARM als VHDX direkt von Microsoft<\/h3>\n<p>Neben dem SDK hat Microsoft nun auch die ARM  in der Version 19624 bereitgestellt. Diese findet ihr \u00fcber <a href=\"https:\/\/tb.32767.ga\/products.php?search=ARM&#038;prod=all\" rel=\"noopener noreferrer\" target=\"_blank\">diesen Link<\/a> oder sp\u00e4ter dann auch bei <a href=\"https:\/\/www.microsoft.com\/en-us\/software-download\/windowsinsiderpreviewadvanced\" rel=\"noopener noreferrer\" target=\"_blank\">Microsoft<\/a> direkt. Auch hier ist das Insider-Konto notwendig. Die offizielle Insider ISO f\u00fcr x64 und x84 ist derzeit immer noch die 19619. Eine aktuelle ARM ISO bekommt ihr auch bei uns. Wer also lieber die neue ARM oder x64 \/ x86 installieren m\u00f6chte, muss noch ein wenig warten. Nun kommen aber die \u00c4nderungen in der Windows 10 19631<\/p>\n<h3>Bekannte Probleme in der Windows 10 19631<\/h3>\n<ul>\n<li>Wir untersuchen ein Problem, bei dem einige Ger\u00e4te, die vom eMMC-Speicher booten, einen Bugcheck durchf\u00fchren, wenn sie aus dem Ruhezustand fortfahren.<\/li>\n<li>Wir befassen uns mit Berichten \u00fcber den Aktualisierungsprozess, der f\u00fcr l\u00e4ngere Zeit beim Versuch, einen neuen Build zu installieren, h\u00e4ngen bleibt.<\/li>\n<li>Wir arbeiten daran, ein Problem f\u00fcr einen zuk\u00fcnftigen Insider Preview-Build zu beheben, bei dem in Einstellungen > Datenschutz in den Abschnitten Dokumente und Downloads neben dem Seitennamen ein kaputtes Symbol angezeigt wird (nur ein Rechteck).<\/li>\n<li>Wir untersuchen Berichte, bei denen die Vorschau-Miniaturansichten in der Taskleiste nicht konsistent dargestellt werden (ein leerer Bereich wird angezeigt).<\/li>\n<li>Windows Store App: Automatische App Update lassen sich in der Store App nicht deaktivieren. &#8211; Das ist kein direkter Fehler. Microsoft scheint etwas zu \u00e4ndern, da auch die dazugeh\u00f6rigen Registry Eintr\u00e4ge gegen\u00fcber den \u00e4lteren Windows Versionen fehlen.<\/li>\n<\/ul>\n<h3>Behobene Probleme in der Windows 10 19631<\/h3>\n<ul>\n<li>Wir haben die Konfiguration von Windows Hello aktualisiert, um sicherzustellen, dass es gut mit Kameras mit 940 nm Wellenl\u00e4nge funktioniert.<br \/>\n-Wir haben das Problem behoben, das dazu f\u00fchrte, dass die IIS-Konfiguration nach einem neuen Build auf die Standardeinstellung gesetzt wurde.<\/li>\n<li>Wir haben ein Problem behoben, das dazu f\u00fchren konnte, dass ein Ger\u00e4t in bestimmten Szenarien durch einen Tastendruck nicht aus dem verbundenen Standby-Modus aufgeweckt werden konnte.<\/li>\n<li>Bei Windows-Sandbox-WSB-Dateien wird jetzt nicht mehr zwischen Gro\u00df- und Kleinschreibung unterschieden.<\/li>\n<li>Wir haben ein Problem behoben, das die Zuverl\u00e4ssigkeit von Remote Desktop beeintr\u00e4chtigt.<\/li>\n<\/ul>\n<h3>Windows 10 Tutorials und Hilfe<\/h3>\n<p>In unserem <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 Wiki<\/a> findet ihr sehr viele hilfreiche Tipps und Tricks. Falls ihr Fragen habt, dann stellt diese ganz einfach bei uns im <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewforum.php?f=326\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Forum<\/strong><\/a>.<\/p>\n<ul>\n<li><strong>Installationsmedien:<\/strong> Aktuelle Installationsdateien findet ihr hier immer in der rechten Sidebar. <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/12\/11\/windows-10-19041-iso-esd-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004 ISO (19041)<\/a>, oder <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/08\/27\/windows-10-1909-18363-iso-esd-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">1909 ISO (18363)<\/a> <\/li>\n<li><strong>Installation:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_clean_neu_installieren\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 Clean installieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_1909_neu_installieren_Anleitung_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 1909 neu installieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_2004_neu_installieren_Anleitung_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 2004 neu installieren<\/a><\/li>\n<li><strong>Aktuelle Probleme mit der:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/04\/11\/windows-10-2004-bekannte-und-behobene-probleme\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 2004<\/a>\n    <\/li>\n<li><strong>Reparaturen:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Inplace_Upgrade_Windows_10_schnell_reparieren\" rel=\"noopener noreferrer\" target=\"_blank\">Inplace Upgrade Reparatur<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_reparieren_wiederherstellen_mit_DISM_Inplace_Upgrade_und_vielen_weiteren_Varianten\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 reparieren  \u00fcber DISM, sfc und weiteres<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_Update_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Windows Update reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Startmen%C3%BC_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Startmen\u00fc reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Apps_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Apps reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Store_reparieren\" rel=\"noopener noreferrer\" target=\"_blank\">Store reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Netzwerkverbindung_-adapter_reparieren_zur%C3%BCcksetzen_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Netzwerk reparieren<\/a><\/li>\n<li><strong>Anmeldung:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_automatisch_anmelden_ohne_Passworteingabe\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 automatische Anmeldung<\/a><\/li>\n<li><strong>Entfernen, Deinstallieren<\/strong>:  <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Apps_entfernen_deinstallieren\" rel=\"noopener noreferrer\" target=\"_blank\">Apps deinstallieren<\/a><\/li>\n<li><strong>Datei Explorer:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Dieser_PC_Ordner_entfernen_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Ordner unter Dieser PC entfernen<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Datei_Explorer_Windows_10_Netzwerk_Heimnetzgruppe_OneDrive_entfernen\" rel=\"noopener noreferrer\" target=\"_blank\">Netzwerk, OneDrive u.a. im Explorer entfernen<\/a><\/li>\n<li><strong>Richtige Nutzung:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Das_Windows_10_Startmen%C3%BC_richtig_einrichten_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Startmen\u00fc richtig nutzen<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Die_Suche_in_Windows_10_richtig_nutzen\" rel=\"noopener noreferrer\" target=\"_blank\">Suche richtig nutzen<\/a>,<\/li>\n<li><strong>Wichtig:<\/strong> In jedem Tutorial steht, f\u00fcr welche Version es geeignet ist.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Eine neue Insider Build hat Microsoft bereitgestellt. Die 19631.1, genauer die 10.0.19631.1 mn _release (Codename Manganese) vom 14.05.2020. Wie schon in der Vorg\u00e4ngerversion wurden hier nur wieder Fehler korrigiert. Richtig interessant wird es erst im Juni, wenn das Insider-Team dann&hellip; <\/p>\n","protected":false},"author":134,"featured_media":111270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[30673,74186,25742,74185,63470],"class_list":["post-139079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10","tag-aktuelle-insider-build","tag-insider-build-19631","tag-neue-insider-build","tag-windows-10-19631","tag-windows-10-20h2"],"wp_featured_image":{"id":111270,"alt_text":"","description":"","media_type":"image","media_details":{"width":558,"height":401,"file":"2018\/11\/windows-insider-update-app-einstellungen-logo.png","sizes":{"thumbnail":{"file":"windows-insider-update-app-einstellungen-logo-285x205.png","width":285,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-285x205.png"},"medium":{"file":"windows-insider-update-app-einstellungen-logo-500x360.png","width":500,"height":360,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-500x360.png"},"wp_review_large":{"file":"windows-insider-update-app-einstellungen-logo-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-320x200.png"},"wp_review_small":{"file":"windows-insider-update-app-einstellungen-logo-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-65x65.png"},"blog-large":{"file":"windows-insider-update-app-einstellungen-logo-558x300.png","width":558,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-558x300.png"},"blog-medium":{"file":"windows-insider-update-app-einstellungen-logo-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-306x205.png"},"recent-thumb":{"file":"windows-insider-update-app-einstellungen-logo-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-350x316.png"},"service-featured":{"file":"windows-insider-update-app-einstellungen-logo-558x330.png","width":558,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-558x330.png"},"wp_rp_thumbnail":{"file":"windows-insider-update-app-einstellungen-logo-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":118123,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png"},"commentcount":39,"wp_comments":[{"id":134983,"parent":0,"author":6251,"author_name":"MANU","author_email":"manu.beitz@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=96&d=mm&r=g"},"date":"2020-05-21T19:53:02","cld_nonce":"b6d6726996","content":{"rendered":"<p>ISO 19631.1 X64 Enterprise<br \/>\n(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<\/p>\n"},"status":"1"},{"id":134987,"parent":134983,"author":4453,"author_name":"Seven of Nine","author_email":"seven-of-nine@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e2d1432d71d3f1b0d78e78b20e56e41fb743282197b71276db702a0feb565cb4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e2d1432d71d3f1b0d78e78b20e56e41fb743282197b71276db702a0feb565cb4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e2d1432d71d3f1b0d78e78b20e56e41fb743282197b71276db702a0feb565cb4?s=96&d=mm&r=g"},"date":"2020-05-21T20:30:57","cld_nonce":"b6d6726996","content":{"rendered":"<p>Danke f\u00fcr den Link <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/> Und bleibe Gesund <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":134990,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-21T21:01:02","cld_nonce":"b6d6726996","content":{"rendered":"<p>Soo, 15 GB im Upload <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":134995,"parent":134990,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-05-21T21:23:20","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wie jetzt &#8211; bei Dir auch ??? Na gut &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/><br \/>\nUnd &#8211; Installationen laufen auch schon: \u00dcber WU und per Inplace Upgrade (auch diversen Rechnern) &#8230;<\/p>\n"},"status":"1"},{"id":134998,"parent":134990,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-21T21:40:44","cld_nonce":"b6d6726996","content":{"rendered":"<p>Installation hatte ich (diesmal) zuerst gemacht, da nicht direkt alle Daten der ISOS verf\u00fcgbar waren<br \/>\n(Downloadfehler im Scriptverlauf &#8211; bei mir jeden Falls) <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n<p>&#8211; (bin auch erst um 19:30 aufgestanden \ud83d\ude07 )<\/p>\n"},"status":"1"},{"id":134999,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-21T21:46:49","cld_nonce":"b6d6726996","content":{"rendered":"<p><b>20H2 19631 X64 PRO<\/b><\/p>\n<p>SHA512:<br \/>\n8944C92A856AC85215C680D501B4A2C94F8197F76A984EA1A1B29A5F08C8ED934BBEE80CE7C53758B33A59965FE0B34780C66562167F9FE00CBCFBC38DFDA9AB<\/p>\n<p>(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<\/p>\n<p>Viel Spa\u00df  damit <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":135000,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-21T21:47:22","cld_nonce":"b6d6726996","content":{"rendered":"<p><b>20H2 19631 X64 HOME<\/b><\/p>\n<p>SHA512:<br \/>\n323C4D8CC4299744BB3DBB76CE1183F70E2F705BE40F59FD26536AE1124DDFFB88442FDC0399A5CC52E65FC0F83D82408C9781A87F3AE3D2A8098B29F0D628B5<\/p>\n<p>(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<\/p>\n<p>Viel Spa\u00df  damit <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":135001,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-21T21:47:47","cld_nonce":"b6d6726996","content":{"rendered":"<p><b>20H2 19631 X64 PROPLUS <\/b><\/p>\n<p>SHA512:<br \/>\nA2B2EF3E04A0AEAF765C8A33E5F5D7BA8EED9FABED4187F5F91D1C9D6B640151B2AD097ACCAD93203C7186FE0ACD6DC0D375B18D874BBC59185E46CE98DC4AD5<\/p>\n<p>(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<\/p>\n<p>Viel Spa\u00df  damit <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":135002,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-21T21:49:34","cld_nonce":"b6d6726996","content":{"rendered":"<p><b>20H2 19631 X64 SUPERMULTI<\/b><\/p>\n<p>SHA512:<br \/>\n330B41A06A316746A61EFB37C61EA2BFCC31D2A3342021111BE78882BC15A76A433D713F54ADE23632465C7D60F20747C3201A4E31644C5F0EABD0B3FC770B73<\/p>\n<p>(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<\/p>\n<p>Viel Spa\u00df  damit <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":135003,"parent":134998,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-05-21T21:54:37","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich hab mit den Downloads bereits 19:06 Uhr (MESZ = Mitteleurop\u00e4ische Schummel-Zeit)  begonnen = 18:06 Uhr Normalzeit &#8211; v\u00f6llig ohne Download-Fehler &#8230;<br \/>\nAllerdings bin ich derzeit (etwas) \u00fcberhopft &#8211; dauert also Alles irgendwie etwas l\u00e4nger(die Ohrl\u00e4ppchen werden schon langsam pelzig) &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":135004,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-05-21T21:57:09","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hier meine ISO X86 Windows 10 19631.1 Home, Pro, Home N, Pro N<br \/>\n(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<br \/>\n<img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":135005,"parent":134998,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-21T21:58:39","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8222;Mitteleurop\u00e4ische Schummel-Zeit&#8220; \ud83e\udd23 aber gut \ud83d\udc4d<\/p>\n"},"status":"1"},{"id":135006,"parent":0,"author":4453,"author_name":"Seven of Nine","author_email":"seven-of-nine@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e2d1432d71d3f1b0d78e78b20e56e41fb743282197b71276db702a0feb565cb4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e2d1432d71d3f1b0d78e78b20e56e41fb743282197b71276db702a0feb565cb4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e2d1432d71d3f1b0d78e78b20e56e41fb743282197b71276db702a0feb565cb4?s=96&d=mm&r=g"},"date":"2020-05-21T22:00:15","cld_nonce":"b6d6726996","content":{"rendered":"<p>Die bauen immer mehr Schei\u00dfe ein, es ist nicht mehr m\u00f6glich mit der Maus im Start Men\u00fc zu scrollen.<\/p>\n"},"status":"1"},{"id":135007,"parent":135006,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-21T22:02:58","cld_nonce":"b6d6726996","content":{"rendered":"<p>geht bei mir einwandfrei &#8211; Logitech Maus MX 705<br \/>\n ( aber ohne installiertem &#8222;Originaltreiber&#8220;)<\/p>\n"},"status":"1"},{"id":135008,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-21T22:16:01","cld_nonce":"b6d6726996","content":{"rendered":"<p>Noch als <b>Anmerkung zu dieser Version:<\/b><br \/>\n(bevor wieder &#8211; unn\u00f6tigerweise &#8211; Nachfragen kommen)<\/p>\n<p>auch diese <b>Insiderversion<\/b> hat ein Wasserzeichen UND Timebomb ( 01.08.2020 )<\/p>\n"},"status":"1"},{"id":135009,"parent":135005,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-05-21T22:21:27","cld_nonce":"b6d6726996","content":{"rendered":"<p>Na ja &#8211; weicht genau 1 Stunde von der Echtzeit (Sonnenuhr) ab &#8230;<br \/>\nVon einigen durchgeknallten Politikern versucht, einzuf\u00fchren &#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_cool.gif\" alt=\"8-)\" class=\"wp-smiley\" \/><br \/>\nDen Effekt hab ich auf meinen Rechnern mehrmals t\u00e4glich: Betriebssystem-Wechsel = Zeit-Verstellung !!! Das nervt !!!\u00b4MacOS -&gt; Windows 10 = 1 Stunde; Windows 10 -&gt; Windows XP = 2 Stunden; Dann zu Linux = weitere 2 Stunden! Also: 4 Betriebssysteme gestartet = Tag rum !!! Geil !!! Juhu !!!!!!!<br \/>\nKeine(r) mu\u00df mehr arbeiten &#8211; 4 Minuten am Computer gen\u00fcgen !!! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_cool.gif\" alt=\"8-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":135010,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-05-21T22:26:43","cld_nonce":"b6d6726996","content":{"rendered":"<p>Und noch eine &#8230;<br \/>\nHier meine ISO ARM64 Windows 10 19631.1 Home, Pro<br \/>\n(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<br \/>\n<img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":135011,"parent":0,"author":6266,"author_name":"Harry S","author_email":"pc_harry@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/31105d10c5aa63ddeef463c780744beb8c9c34ac522b7c1275703903f679a6ca?s=96&d=mm&r=g"},"date":"2020-05-21T23:41:43","cld_nonce":"b6d6726996","content":{"rendered":"<p>Und weiter geht&#8217;s &#8230;<br \/>\nHier meine ISO X64 Windows 10 19631.1 Home, Pro, Home N, Pro N<br \/>\n(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<br \/>\n<img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":135012,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-22T00:10:35","cld_nonce":"b6d6726996","content":{"rendered":"<p><b>20H2 19631 X86-X64<\/b><\/p>\n<p>SHA512:<br \/>\n216D50904842F318882AA0DE23C63BC1EB35901C3897B097AEDD8A8A35D788C64F8551AE72105CE9D5AAE0FA61BA21B95E384ECD3039A3D4E66F78CC8520A802<\/p>\n<p>(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<\/p>\n<p>Viel Spa\u00df  damit <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":135013,"parent":135012,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-22T00:50:21","cld_nonce":"b6d6726996","content":{"rendered":"<p>&#8230;<br \/>\n<b>Anmerkung<\/b><\/p>\n<p>diese Version ist <b> nicht<\/b> 100%ig Ventoydatentr\u00e4ger-kompatibel !<\/p>\n"},"status":"1"},{"id":135016,"parent":135013,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2020-05-22T05:58:59","cld_nonce":"b6d6726996","content":{"rendered":"<p>Kubuntu 20.04 leider auch nicht.<\/p>\n"},"status":"1"},{"id":135017,"parent":135013,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-22T06:10:05","cld_nonce":"b6d6726996","content":{"rendered":"<p>meinte ausschlie\u00dflich die letzte ISO ( X86 &amp; X64 ) &#8211; die normalen (X64) funktionieren auf Ventoy <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":135027,"parent":0,"author":4989,"author_name":"Cyromus","author_email":"cyromus1974@googlemail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7ce5f4c614a8c7e403668cc663441c8b67a9c42143d7ec185e63e9688a3793f0?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7ce5f4c614a8c7e403668cc663441c8b67a9c42143d7ec185e63e9688a3793f0?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7ce5f4c614a8c7e403668cc663441c8b67a9c42143d7ec185e63e9688a3793f0?s=96&d=mm&r=g"},"date":"2020-05-22T09:10:42","cld_nonce":"b6d6726996","content":{"rendered":"<p>19631.1 all editions german x64<br \/>\n(Platzhalter f\u00fcr einen Text, welcher f\u00fcr G\u00e4ste nicht sichtbar ist.)<br \/>\nSHA 256<br \/>\n513CD4FE3616E98A3E76B737AD2297CC5DBBFD234747FB200DAB3E33F2602A85<\/p>\n"},"status":"1"},{"id":135038,"parent":135002,"author":6323,"author_name":"rescenic","author_email":"adminrescen@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9df590560a8ebe005f550731a6173351c146e173f5c81aa6e6848d8f499358ad?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9df590560a8ebe005f550731a6173351c146e173f5c81aa6e6848d8f499358ad?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9df590560a8ebe005f550731a6173351c146e173f5c81aa6e6848d8f499358ad?s=96&d=mm&r=g"},"date":"2020-05-22T11:54:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ist englishe Version dabei?<\/p>\n"},"status":"1"},{"id":135047,"parent":135002,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-22T12:41:18","cld_nonce":"b6d6726996","content":{"rendered":"<p>Diese ist die Deutsche<br \/>\n &#8211; unter <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/05\/22\/windows-10-19631-iso-esd-deutsch-english\/\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2020\/05\/22\/windows-10-19631-iso-esd-deutsch-english\/<\/a><br \/>\nfindst du aber auch die Englische<\/p>\n"},"status":"1"},{"id":135130,"parent":0,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-05-23T09:35:34","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bin gespannt, wann die Erste 196xx.xxx(?) im Slow Ring erscheint. Das Update auf die 19631 verlief nach langer Zeit wieder z\u00fcgig.<\/p>\n"},"status":"1"},{"id":135131,"parent":135130,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-05-23T09:39:41","cld_nonce":"b6d6726996","content":{"rendered":"<p>Wenn wird es eher die 19041.10xx<br \/>\nAnsonsten bekommt MS Probleme mit der Bezeichnung f\u00fcr das 19042 Release<\/p>\n<p>Nachtrag: Das wird wohl aber erst Ende Juni passieren. War bisher immer 2-3 Wochen nach dem Release der finalen Version.<\/p>\n"},"status":"1"},{"id":135132,"parent":135130,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2020-05-23T09:40:51","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich erwarte da eigentlich mehr eine 19042.x im Slow Ring. Oder eventuell f\u00fcr den Anfang noch eine 19041.x. Aber eine 196xx.x erwarte ich da im Moment nicht.<\/p>\n"},"status":"1"},{"id":135135,"parent":135130,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-05-23T10:09:47","cld_nonce":"b6d6726996","content":{"rendered":"<p>Auf den MS Servern liegt schon eine [10.0.19041.1713] &#8211; Submission Validator. Aber bislang noch ohne weitere Infos. Muss man abwarten. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":135137,"parent":135135,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2020-05-23T10:23:12","cld_nonce":"b6d6726996","content":{"rendered":"<p>Die geh\u00f6rt wohl zum Zweig rs_xbox_release_2004. Jedenfalls wenn man danach sucht.<\/p>\n"},"status":"1"},{"id":135139,"parent":135137,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-05-23T10:40:09","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ok, dann bleibt MS ja wieder nur 19041.10000 f\u00fcr die 19042<\/p>\n"},"status":"1"},{"id":135142,"parent":135135,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-05-23T11:53:53","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich habe meinen 2. PC 19631 in den Slow Ring verschoben. Mal sehen, was zur gegebenen Zeit passiert. Bisher gab es noch keine Warnung, wie es bei der 2004 ja der Fall war. Ich denke da hat MS schon einiges getan.<\/p>\n"},"status":"1"},{"id":135144,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-23T12:49:40","cld_nonce":"b6d6726996","content":{"rendered":"<p>Frage nebenbei weil mir das gerade erst auff\u00e4llt \/ aufgefallen ist:<\/p>\n<p>Kann es sein das MS die &#8222;Protokollierung&#8220; der Defender Aktualisierungen aus dem Updateverlauf rausgenommen hat, oder ist das ein Bug ? &#8211; laut Defender hab ich die aktuellen Schutzupdates<br \/>\n( von 11 Uhr heute) aber im (allgemeinen) Updateverlauf steht kein einziges Update f\u00fcr den Defender drin. Dort stehen &#8211; nur noch &#8211; Funktionsupdates und Qualit\u00e4tsupdates &#8211; bei mir jeden Falls<\/p>\n"},"status":"1"},{"id":135145,"parent":135144,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2020-05-23T13:02:34","cld_nonce":"b6d6726996","content":{"rendered":"<p>Das ist bei mir auch nicht so ganz klar, wa da protokolliert wird.<\/p>\n<p>Installiert ist: April-2020 (Platform: 4.18.2004.6 | Engine: 1.1.17000.7)<\/p>\n<p>Letzter Eintrag im Updateverlauf: January-2020 (Platform: 4.18.2001.10 | Engine: 1.1.16700.2)<\/p>\n<p>Letzteres erfolgreich installier am 03.05.2020. Davon dass auch das April-2020 erfolgreich installiert wurde, steht da nichts. Und warum das Januar Update im Mai erneut installiert wurde, erschlie\u00dft sich mir da auch nicht. Von weiteren Updates in der Richtung steht da nichts. Kann aber damit zusammenh\u00e4nge, dass diese Defender Updates vom Defender selber am Windows Update vorbei geholt werden.<\/p>\n"},"status":"1"},{"id":135148,"parent":135142,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2020-05-23T13:47:02","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ist halt die Frage, wie die Ringe aufgeteilt werden. Ziel f\u00fcr die 20H2 ist auf jeden Fall Build 19042.x, au\u00dfer Microsoft \u00e4ndert da noch etwas. Aber lt. dem letzen kumulativen Update wird &#8222;ProductData&#8220; f\u00fcr die 2009 auf 10.19042.19041.264 angepasst (wie bei der 1909). Das Update ist sowohl f\u00fcr die 19041.264, als auch f\u00fcr die 19042.264 gedacht. Diese Zahlen f\u00fcr die 2009 existieren bereits so alle im Update, einschlie\u00dflich &#8222;DisplayVersion=20H2&#8220;, was auch immer das bewirken mag.<\/p>\n<p>Das was wohl noch fehlt, ist das &#8222;2009 Enablement Package&#8220;, damit das alles aktiviert wird.<\/p>\n"},"status":"1"},{"id":135158,"parent":135144,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-23T17:02:10","cld_nonce":"b6d6726996","content":{"rendered":"<p>Kann es evtl. auch sein das da nix mehr auftaucht, wenn man  das entsprechende Script f\u00fcr den Updateverlauf bereinigen benutzt hat  ( was sich Windows ja merkt bei aktivierter Synchronisation ?<\/p>\n"},"status":"1"},{"id":135182,"parent":135158,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-05-23T23:43:06","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei mir werden sie nach wie vor eingetragen. Ich glaube max. 50 Eintr\u00e4ge.<\/p>\n"},"status":"1"},{"id":135183,"parent":135182,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-05-23T23:49:50","cld_nonce":"b6d6726996","content":{"rendered":"<p>2 von 3 Update wurden Heute eingetragen, die  KB2267602 (Version 1.315.1277.0) nicht.<\/p>\n"},"status":"1"},{"id":135184,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-05-24T01:30:23","cld_nonce":"b6d6726996","content":{"rendered":"<p>Guten Morgen zusammen <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n<p>meinen Post weiter oben<br \/>\n<a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/#comment-135144\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/#comment-135144<\/a><br \/>\nmuss \/ kann ich wieder revidieren &#8211; die Definitionsupdates werden (seit gerade) wieder im Updateverlauf angezeigt <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><br \/>\n<b> <a href=\"https:\/\/t1p.de\/eqirw\" rel=\"nofollow ugc\"> Updateverlauf 19631.1<\/a> <\/b><br \/>\n&#8211; das die vorherige Build 19628 da nicht (mehr) gelistet ist, liegt dann aber an der Updatebereinigung &#8211; weil Aktualisierung war kein Clean Install, sondern \u00fcber WU <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Windows 10 19631 + SDK steht f\u00fcr die Insider zum Download bereit + 19624 ARM VHDX - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windows 10 19631 + SDK steht f\u00fcr die Insider zum Download bereit + 19624 ARM VHDX\" \/>\n<meta property=\"og:description\" content=\"Eine neue Insider Build hat Microsoft bereitgestellt. Die 19631.1, genauer die 10.0.19631.1 mn _release (Codename Manganese) vom 14.05.2020. Wie schon in der Vorg\u00e4ngerversion wurden hier nur wieder Fehler korrigiert. Richtig interessant wird es erst im Juni, wenn das Insider-Team dann&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-21T17:05:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-25T08:05:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"558\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Windows 10 19631 + SDK steht f\u00fcr die Insider zum Download bereit + 19624 ARM VHDX\",\"datePublished\":\"2020-05-21T17:05:46+00:00\",\"dateModified\":\"2020-05-25T08:05:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/\"},\"wordCount\":618,\"commentCount\":39,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/windows-insider-update-app-einstellungen-logo.png\",\"keywords\":[\"Aktuelle Insider Build\",\"Insider Build 19631\",\"Neue Insider Build\",\"Windows 10 19631\",\"Windows 10 20H2\"],\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/\",\"name\":\"Windows 10 19631 + SDK steht f\u00fcr die Insider zum Download bereit + 19624 ARM VHDX - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/windows-insider-update-app-einstellungen-logo.png\",\"datePublished\":\"2020-05-21T17:05:46+00:00\",\"dateModified\":\"2020-05-25T08:05:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/windows-insider-update-app-einstellungen-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/windows-insider-update-app-einstellungen-logo.png\",\"width\":558,\"height\":401},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/21\\\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Windows 10 19631 + SDK steht f\u00fcr die Insider zum Download bereit + 19624 ARM VHDX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Windows 10 19631 + SDK steht f\u00fcr die Insider zum Download bereit + 19624 ARM VHDX - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/","og_locale":"de_DE","og_type":"article","og_title":"Windows 10 19631 + SDK steht f\u00fcr die Insider zum Download bereit + 19624 ARM VHDX","og_description":"Eine neue Insider Build hat Microsoft bereitgestellt. Die 19631.1, genauer die 10.0.19631.1 mn _release (Codename Manganese) vom 14.05.2020. Wie schon in der Vorg\u00e4ngerversion wurden hier nur wieder Fehler korrigiert. Richtig interessant wird es erst im Juni, wenn das Insider-Team dann&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-05-21T17:05:46+00:00","article_modified_time":"2020-05-25T08:05:03+00:00","og_image":[{"width":558,"height":401,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Windows 10 19631 + SDK steht f\u00fcr die Insider zum Download bereit + 19624 ARM VHDX","datePublished":"2020-05-21T17:05:46+00:00","dateModified":"2020-05-25T08:05:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/"},"wordCount":618,"commentCount":39,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png","keywords":["Aktuelle Insider Build","Insider Build 19631","Neue Insider Build","Windows 10 19631","Windows 10 20H2"],"articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/","name":"Windows 10 19631 + SDK steht f\u00fcr die Insider zum Download bereit + 19624 ARM VHDX - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png","datePublished":"2020-05-21T17:05:46+00:00","dateModified":"2020-05-25T08:05:03+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png","width":558,"height":401},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/21\/windows-10-19631-sdk-steht-fuer-die-insider-zum-download-bereit-19624-arm-vhdx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Windows 10 19631 + SDK steht f\u00fcr die Insider zum Download bereit + 19624 ARM VHDX"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/11\/windows-insider-update-app-einstellungen-logo.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/139079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=139079"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/139079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/111270"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=139079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=139079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=139079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}