{"id":137806,"date":"2020-05-27T08:40:05","date_gmt":"2020-05-27T06:40:05","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=137806"},"modified":"2020-05-27T08:41:02","modified_gmt":"2020-05-27T06:41:02","slug":"amd-adrenalin-2020-20-4-2-steht-zum-download-bereit","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/","title":{"rendered":"AMD Adrenalin 2020 20.4.2 [Update: WHQL] steht zum Download bereit"},"content":{"rendered":"<p><strong>[Update 27.05.2020]:<\/strong> AMD hat den Adrenalin 2020 20.4.2 jetzt als finalen Treiber zum Download bereitgestellt. Der Download-Link \u00e4ndert sich dadurch auf die win10-radeon-software-adrenalin-2020-edition-20.4.2-<strong>may25<\/strong>.exe. Changelog ist soweit unver\u00e4ndert.<\/p>\n<p>[Original 24.04.2020]: AMD hat einen neuen Grafiktreiber bereitgestellt. Der Adrenalin 2020 20.4.2 unterst\u00fctzt nun die Spiele Gears Tactics und Predator: Hunting Grounds. Aber nat\u00fcrlich wurden auch wieder Fehler behoben und auch bekannte Probleme sind noch vorhanden.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1.jpg\" rel=\"lightbox[137806]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1.jpg\" alt=\"\" width=\"500\" height=\"335\" class=\"aligncenter size-full wp-image-133824\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1-306x205.jpg 306w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<h3>Behobene Probleme im Adrenalin 2020 20.4.2<\/h3>\n<ul>\n<li>Bei Grafikprodukten der Radeon RX Vega-Serie kann es zu einem Systemabsturz oder einem schwarzen Bildschirm kommen, wenn Folding@Home ausgef\u00fchrt wird und gleichzeitig eine Anwendung ausgef\u00fchrt wird, die die Hardwarebeschleunigung von Videoinhalten nutzt.<\/li>\n<li>Ein Systemabsturz oder H\u00e4ngenbleiben kann auftreten, wenn der Edge-Browser zur Wiedergabe von Netflix Inhalten verwendet wird.<\/li>\n<li>XSplit kann beim Ausf\u00fchren eines Szenenwechsels zum H\u00e4ngenbleiben oder Einfrieren einer Anwendung f\u00fchren.<\/li>\n<li>Geringf\u00fcgiges Stottern kann beim Ausf\u00fchren eines Task-Wechsels mit offener \u00dcberlagerung der Leistungsparameter in einigen Spielen auftreten.<\/li>\n<li>Overwatch kann bei der Eingabe eines Spiels oder bei l\u00e4ngeren Spielsitzungen zeitweise abst\u00fcrzen.<\/li>\n<li>Bei Systemkonfigurationen von Grafikprodukten der Serie Radeon RX 5700 kann es w\u00e4hrend eines Spiels oder auf einem Desktop mit einer bestimmten Anzahl von Bildschirmen sporadisch zu einem Anzeigeverlust oder einem schwarzen Bildschirm kommen.<\/li>\n<li>Bei Radeon Software kann es beim Spielen von Games mit nicht alphanumerischen Zeichen im Spieltitel zu einem Absturz der Anwendung kommen.<\/li>\n<li>Bei Grafikprodukten der Radeon RX Vega-Serie kann es zu einem Anwendungsabsturz bei Microsoft Teams kommen, wenn die Hardwarebeschleunigung aktiviert ist.<\/li>\n<li>Beim Anzeigen der Registerkarte &#8222;Upgrade Advisor&#8220; in Radeon Software kann zeitweilig die Fehlermeldung &#8222;Unable to get requirements&#8220; angezeigt werden.<\/li>\n<li>Bei Grafikprodukten der Serie Radeon RX Vega kann es zu einem Systemabsturz oder TDR-Fehler kommen, wenn Spiele mit aktivierter Instant-Wiedergabe oder Record Desktop gespielt werden.<\/li>\n<li>Es wurde ein Installationsproblem behoben, bei dem Fehler 1603 auftreten konnte, wenn eine Installationsvoraussetzung f\u00fcr Visual C++ nicht korrekt als installiert erkannt wurde.<\/li>\n<\/ul>\n<h3>Bekannte Probleme<\/h3>\n<ul>\n<li>Enhanced Sync kann zu einem schwarzen Bildschirm f\u00fchren, wenn es bei einigen Spielen und Systemkonfigurationen aktiviert ist. Alle Benutzer, bei denen Probleme mit aktivierter Enhanced Sync-Funktion auftreten k\u00f6nnen, sollten diese als vor\u00fcbergehende Notl\u00f6sung deaktivieren.<\/li>\n<li>Die Verwendung des Webbrowsers Edge zur Wiedergabe von Videoinhalten mit einer Systemkonfiguration mit mehreren Bildschirmen kann nach l\u00e4ngerer Nutzung zum H\u00e4ngen oder Absturz des Systems f\u00fchren.<\/li>\n<li>Performance Metrics Overlay und Radeon WattMan melden f\u00e4lschlicherweise h\u00f6here als erwartete Leerlauf-Taktgeschwindigkeiten auf Grafikprodukten der Radeon RX 5700 Serie. Leistung und Stromverbrauch werden durch diese falsche Meldung nicht beeintr\u00e4chtigt.<\/li>\n<li>Eine \u00c4nderung des Schiebereglers f\u00fcr die HDMI-Skalierung kann dazu f\u00fchren, dass die FPS auf 30 gesperrt werden.<\/li>\n<li>Einige Spiele k\u00f6nnen w\u00e4hrend des Spielens auf Grafikprodukten der Serie Radeon RX 5000 gelegentlich Stottern.<\/li>\n<li>Bei Grafikprodukten der Serie Radeon RX Vega kann es zu einem Systemabsturz oder TDR kommen, wenn mehrere Aufgabenwechsel mit Alt+Tab ausgef\u00fchrt werden.<\/li>\n<li>Bei aktivierter HDR-Funktion kann es zeitweise zu St\u00f6rungen auf dem Desktop oder im Spiel kommen.<\/li>\n<li>Direkte ML Media-Filter sind derzeit in der Radeon Software Media-Galerie f\u00fcr Video- oder Bildinhalte nicht verf\u00fcgbar.<\/li>\n<li>Einige Benutzer k\u00f6nnen w\u00e4hrend l\u00e4ngerer Spielzeiten immer noch Probleme mit schwarzen Bildschirmen oder Systemst\u00f6rungen haben. AMD wird Berichte \u00fcber diese Probleme weiterhin genau beobachten und untersuchen.<\/li>\n<li>Bei einigen Laptops kann ein BSOD auftreten, wenn Radeon\u2122 Software Adrenalin 2020 Edition \u00fcber einen vorhandenen OEM-Grafiktreiber installiert wird. Um dieses Problem zu umgehen, deinstallieren Sie zun\u00e4chst den OEM-Grafiktreiber \u00fcber Programme und Funktionen in der Systemsteuerung. Installieren Sie dann das Radeon Software Adrenalin 2020 Edition-Paket und w\u00e4hlen Sie w\u00e4hrend des Setups die Option Factory Reset.<\/li>\n<\/ul>\n<h3>Info und Download<\/h3>\n<ul>\n<li><a href=\"https:\/\/www.amd.com\/en\/support\/kb\/release-notes\/rn-rad-win-20-4-2\" rel=\"noopener noreferrer\" target=\"_blank\">amd.com\/release-notes\/rn-rad-win-20-4-2<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>[Update 27.05.2020]: AMD hat den Adrenalin 2020 20.4.2 jetzt als finalen Treiber zum Download bereitgestellt. Der Download-Link \u00e4ndert sich dadurch auf die win10-radeon-software-adrenalin-2020-edition-20.4.2-may25.exe. Changelog ist soweit unver\u00e4ndert. [Original 24.04.2020]: AMD hat einen neuen Grafiktreiber bereitgestellt. Der Adrenalin 2020 20.4.2 unterst\u00fctzt&hellip; <\/p>\n","protected":false},"author":134,"featured_media":133824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286,152],"tags":[72934,66883,4246],"class_list":["post-137806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","category-software","tag-20-4-2","tag-adrenalin-2020","tag-amd"],"wp_featured_image":{"id":133824,"alt_text":"","description":"","media_type":"image","media_details":{"width":500,"height":335,"file":"2020\/02\/amd-radeon-logo-500x335-1.jpg","sizes":{"thumbnail":{"file":"amd-radeon-logo-500x335-1-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1-306x205.jpg"},"wp_review_large":{"file":"amd-radeon-logo-500x335-1-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1-320x200.jpg"},"wp_review_small":{"file":"amd-radeon-logo-500x335-1-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1-65x65.jpg"},"blog-large":{"file":"amd-radeon-logo-500x335-1-500x300.jpg","width":500,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1-500x300.jpg"},"blog-medium":{"file":"amd-radeon-logo-500x335-1-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1-306x205.jpg"},"recent-thumb":{"file":"amd-radeon-logo-500x335-1-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1-350x316.jpg"},"service-featured":{"file":"amd-radeon-logo-500x335-1-500x330.jpg","width":500,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1-500x330.jpg"},"wp_rp_thumbnail":{"file":"amd-radeon-logo-500x335-1-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":133821,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1.jpg"},"commentcount":5,"wp_comments":[{"id":132883,"parent":0,"author":0,"author_name":"Marc","author_email":"marc_reinsdorf@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/22ba48ede3af5a22a4c5166b90ecbad2d4f6c65a74bc6ab62f803a926d010a7d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/22ba48ede3af5a22a4c5166b90ecbad2d4f6c65a74bc6ab62f803a926d010a7d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/22ba48ede3af5a22a4c5166b90ecbad2d4f6c65a74bc6ab62f803a926d010a7d?s=96&d=mm&r=g"},"date":"2020-04-24T07:21:13","cld_nonce":"b6d6726996","content":{"rendered":"<p>Fehler 1603 bei der Installation <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":132884,"parent":0,"author":3965,"author_name":"peboka","author_email":"h.p.borcherd@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/87cc760c460d0be4d31610073ff407cd5be3750bccdfeec211e72012ec4666d9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/87cc760c460d0be4d31610073ff407cd5be3750bccdfeec211e72012ec4666d9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/87cc760c460d0be4d31610073ff407cd5be3750bccdfeec211e72012ec4666d9?s=96&d=mm&r=g"},"date":"2020-04-24T07:29:39","cld_nonce":"b6d6726996","content":{"rendered":"<p>Install ok<\/p>\n"},"status":"1"},{"id":132885,"parent":132883,"author":5243,"author_name":"eRaz0r","author_email":"spam84@ymail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=96&d=mm&r=g"},"date":"2020-04-24T07:32:57","cld_nonce":"b6d6726996","content":{"rendered":"<p>Du musst &#8222;neuinstallation&#8220; anhaken um das Problem zu umgehen.<\/p>\n"},"status":"1"},{"id":135484,"parent":0,"author":0,"author_name":"golem","author_email":"knolle1@mein.gmx","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/df3fb81243c10a4beb42091b2746549b55437f2a45d52886fbd5366529b44095?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/df3fb81243c10a4beb42091b2746549b55437f2a45d52886fbd5366529b44095?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/df3fb81243c10a4beb42091b2746549b55437f2a45d52886fbd5366529b44095?s=96&d=mm&r=g"},"date":"2020-05-27T15:33:46","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei den fertigen Profilen gab es zum relaese ein einziges mal einen unterschied zwischen &#8222;spiele&#8220; und &#8222;esport&#8220;, danach inkl. hier ist das aber die absolut gleiche vorauswahl<\/p>\n"},"status":"1"},{"id":135528,"parent":0,"author":4948,"author_name":"HotShot","author_email":"hot_pussy_sucker@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/77d2fdea91d1047b572e1739c93eed44eebc4328410e8c591ecd3118831606b6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/77d2fdea91d1047b572e1739c93eed44eebc4328410e8c591ecd3118831606b6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/77d2fdea91d1047b572e1739c93eed44eebc4328410e8c591ecd3118831606b6?s=96&d=mm&r=g"},"date":"2020-05-28T00:04:47","cld_nonce":"b6d6726996","content":{"rendered":"<p>20.5.1 wurde ebenfalls released:<\/p>\n<p><a href=\"https:\/\/community.amd.com\/thread\/253438\" rel=\"nofollow ugc\">https:\/\/community.amd.com\/thread\/253438<\/a><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AMD Adrenalin 2020 20.4.2 [Update: WHQL] steht zum Download bereit - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMD Adrenalin 2020 20.4.2 [Update: WHQL] steht zum Download bereit\" \/>\n<meta property=\"og:description\" content=\"[Update 27.05.2020]: AMD hat den Adrenalin 2020 20.4.2 jetzt als finalen Treiber zum Download bereitgestellt. Der Download-Link \u00e4ndert sich dadurch auf die win10-radeon-software-adrenalin-2020-edition-20.4.2-may25.exe. Changelog ist soweit unver\u00e4ndert. [Original 24.04.2020]: AMD hat einen neuen Grafiktreiber bereitgestellt. Der Adrenalin 2020 20.4.2 unterst\u00fctzt&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-27T06:40:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-27T06:41:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"AMD Adrenalin 2020 20.4.2 [Update: WHQL] steht zum Download bereit\",\"datePublished\":\"2020-05-27T06:40:05+00:00\",\"dateModified\":\"2020-05-27T06:41:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/\"},\"wordCount\":605,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/amd-radeon-logo-500x335-1.jpg\",\"keywords\":[\"20.4.2\",\"Adrenalin 2020\",\"AMD\"],\"articleSection\":[\"Hardware\",\"Software &amp; Updates\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/\",\"name\":\"AMD Adrenalin 2020 20.4.2 [Update: WHQL] steht zum Download bereit - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/amd-radeon-logo-500x335-1.jpg\",\"datePublished\":\"2020-05-27T06:40:05+00:00\",\"dateModified\":\"2020-05-27T06:41:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/amd-radeon-logo-500x335-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/amd-radeon-logo-500x335-1.jpg\",\"width\":500,\"height\":335},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/05\\\/27\\\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AMD Adrenalin 2020 20.4.2 [Update: WHQL] steht zum Download bereit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AMD Adrenalin 2020 20.4.2 [Update: WHQL] steht zum Download bereit - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/","og_locale":"de_DE","og_type":"article","og_title":"AMD Adrenalin 2020 20.4.2 [Update: WHQL] steht zum Download bereit","og_description":"[Update 27.05.2020]: AMD hat den Adrenalin 2020 20.4.2 jetzt als finalen Treiber zum Download bereitgestellt. Der Download-Link \u00e4ndert sich dadurch auf die win10-radeon-software-adrenalin-2020-edition-20.4.2-may25.exe. Changelog ist soweit unver\u00e4ndert. [Original 24.04.2020]: AMD hat einen neuen Grafiktreiber bereitgestellt. Der Adrenalin 2020 20.4.2 unterst\u00fctzt&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-05-27T06:40:05+00:00","article_modified_time":"2020-05-27T06:41:02+00:00","og_image":[{"width":500,"height":335,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"AMD Adrenalin 2020 20.4.2 [Update: WHQL] steht zum Download bereit","datePublished":"2020-05-27T06:40:05+00:00","dateModified":"2020-05-27T06:41:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/"},"wordCount":605,"commentCount":5,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1.jpg","keywords":["20.4.2","Adrenalin 2020","AMD"],"articleSection":["Hardware","Software &amp; Updates"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/","name":"AMD Adrenalin 2020 20.4.2 [Update: WHQL] steht zum Download bereit - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1.jpg","datePublished":"2020-05-27T06:40:05+00:00","dateModified":"2020-05-27T06:41:02+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1.jpg","width":500,"height":335},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/05\/27\/amd-adrenalin-2020-20-4-2-steht-zum-download-bereit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"AMD Adrenalin 2020 20.4.2 [Update: WHQL] steht zum Download bereit"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/amd-radeon-logo-500x335-1.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/137806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=137806"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/137806\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/133824"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=137806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=137806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=137806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}