{"id":137389,"date":"2020-04-16T07:35:16","date_gmt":"2020-04-16T05:35:16","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=137389"},"modified":"2020-04-16T07:35:16","modified_gmt":"2020-04-16T05:35:16","slug":"microsoft-edge-pdf-reader-bekommt-weitere-funktionen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/","title":{"rendered":"Microsoft Edge &#8211; PDF-Reader bekommt weitere Funktionen"},"content":{"rendered":"<p>Der &#8222;alte&#8220; Microsoft Edge war als PDF-Reader gut mit Funktionen ausgestattet. Deshalb hat das Edge-Team auch schon viele Anfragen erhalten. Nun hat man eine \u00dcbersicht gezeigt, welche Funktionen mit dem Edge 83 (Stable), also der finalen Version kommen werden und noch in Planung sind.<\/p>\n<p>Wer mit der Canary oder Dev Version unterwegs ist, der hat viele der Funktionen schon. So l\u00e4sst sich die St\u00e4rke f\u00fcr eine Markierung im Text dann dicker oder schmaler einstellen und auch die Farbauswahl ist dann vorhanden. Markiert man einen Text hat man \u00fcber das Kontextmen\u00fc die Auswahl verschiedener Farben. Diese Funktion wird auch in das obere Men\u00fc integriert werden.<\/p>\n<div id='gallery-1' class='gallery galleryid-137389 gallery-columns-2 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001.jpg' rel=\"lightbox[137389]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"183\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-306x183.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-306x183.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-500x298.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-810x483.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001.jpg 1195w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-002.jpg' rel=\"lightbox[137389]\"><img loading=\"lazy\" decoding=\"async\" width=\"279\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-002-279x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-002-279x205.jpg 279w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-002-491x360.jpg 491w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-002-795x583.jpg 795w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-002.jpg 1198w\" sizes=\"auto, (max-width: 279px) 100vw, 279px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Somit braucht man dann nur noch die Funktion aktivieren und kann mehrere Textstellen markieren, ohne erst immer ins Kontextmen\u00fc zu m\u00fcssen. Aber das Team arbeitet weiter an neuen Funktionen.<\/p>\n<p>&#8222;Wir wissen, dass viele von Ihnen den PDF-Reader in Microsoft Edge lieben, und wir haben viele R\u00fcckmeldungen und Bitten um Unterst\u00fctzung f\u00fcr Anmerkungen geh\u00f6rt. Wir werden daran arbeiten, die M\u00f6glichkeit der leichten Bearbeitung von PDF-Dateien zu verbessern, damit Sie direkt im Browser produktiv arbeiten k\u00f6nnen. Als Teil dieser Bem\u00fchungen wird das Team an diesen Szenarien arbeiten:&#8220;<\/p>\n<ul>\n<li>Verbesserung der Lesbarkeit von bereits in einer PDF-Datei vorhandenen Textnotizen. <\/li>\n<li>Die F\u00e4higkeit, Textnotizen in eine PDF-Datei einzuf\u00fcgen.  <\/li>\n<\/ul>\n<p>Es kann also nur besser werden.<\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/techcommunity.microsoft.com\/t5\/articles\/microsoft-edge-extends-tools-for-the-pdf-reader\/m-p\/1303243\/thread-id\/2660\" rel=\"noopener noreferrer\" target=\"_blank\">techcommunity<\/a><\/div>\n<h3>Alle Microsoft Edge Downloads auch Insider:<\/h3>\n<ul>\n<li><strong>Stable Version:<\/strong> Auswahl alle Versionen <a href=\"https:\/\/www.microsoft.com\/en-us\/edge\" target=\"_blank\" rel=\"noopener noreferrer\">microsoft.com\/edge<\/a> Direkt Windows 10: <a href=\"https:\/\/go.microsoft.com\/fwlink\/?linkid=2069324&amp;Channel=Stable&amp;language=de\" target=\"_blank\" rel=\"noopener noreferrer\">go.microsoft.com\/Channel=Stable<\/a><\/li>\n<li>Die <strong>portablen Versionen:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/05\/27\/portabler-microsoft-edge-chromium-updater-fuer-canary-developer-beta-und-spaeter-auch-der-finale-edge\/\" target=\"_blank\" rel=\"noopener noreferrer\">Portable Edge Updater<\/a><\/li>\n<li>Offline-Installer Stable Enterprise <a href=\"http:\/\/go.microsoft.com\/fwlink\/?LinkID=2093437\" target=\"_blank\" rel=\"noopener noreferrer\">X64.msi <\/a>, <a href=\"http:\/\/go.microsoft.com\/fwlink\/?LinkID=2093505\" target=\"_blank\" rel=\"noopener noreferrer\">X86.msi <\/a><\/li>\n<li>Mac Enterprise Stable: <a href=\"http:\/\/go.microsoft.com\/fwlink\/?LinkID=2093438\" target=\"_blank\" rel=\"noopener noreferrer\">macOS.pkg <\/a><\/li>\n<li>Android: <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.microsoft.emmx&amp;hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">play.google.com\/microsoft.emmx<\/a><\/li>\n<li>iOS: <a href=\"https:\/\/apps.apple.com\/de\/app\/microsoft-edge\/id1288723196\" target=\"_blank\" rel=\"noopener noreferrer\">apps.apple.com\/microsoft-edge<\/a><\/li>\n<li><strong>Die weiteren Links f\u00fcr Insider<\/strong><\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/\" target=\"_blank\" rel=\"noopener noreferrer\">win10<\/a>, <a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win8dot1\" target=\"_blank\" rel=\"noopener noreferrer\">win8dot1<\/a>, <a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win8\" target=\"_blank\" rel=\"noopener noreferrer\">platform=win8<\/a>, <a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win7\" target=\"_blank\" rel=\"noopener noreferrer\">platform=win7<\/a><\/li>\n<li>Und f\u00fcr die Macs:<\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=macos\" target=\"_blank\" rel=\"noopener noreferrer\">microsoftedgeinsider.com\/download\/platform=macos<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Der &#8222;alte&#8220; Microsoft Edge war als PDF-Reader gut mit Funktionen ausgestattet. Deshalb hat das Edge-Team auch schon viele Anfragen erhalten. Nun hat man eine \u00dcbersicht gezeigt, welche Funktionen mit dem Edge 83 (Stable), also der finalen Version kommen werden und&hellip; <\/p>\n","protected":false},"author":134,"featured_media":137391,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166],"tags":[8501,1633,525],"class_list":["post-137389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-browser","tag-microsoft-edge","tag-neue-funktionen","tag-pdf-reader"],"wp_featured_image":{"id":137391,"alt_text":"","description":"","media_type":"image","media_details":{"width":1195,"height":713,"file":"2020\/04\/microsoft-edge-pdf-reader-001.jpg","sizes":{"medium":{"file":"microsoft-edge-pdf-reader-001-500x298.jpg","width":500,"height":298,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-500x298.jpg"},"large":{"file":"microsoft-edge-pdf-reader-001-810x483.jpg","width":810,"height":483,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-810x483.jpg"},"thumbnail":{"file":"microsoft-edge-pdf-reader-001-306x183.jpg","width":306,"height":183,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-306x183.jpg"},"wp_review_large":{"file":"microsoft-edge-pdf-reader-001-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-320x200.jpg"},"wp_review_small":{"file":"microsoft-edge-pdf-reader-001-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-65x65.jpg"},"blog-large":{"file":"microsoft-edge-pdf-reader-001-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-642x300.jpg"},"blog-medium":{"file":"microsoft-edge-pdf-reader-001-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-306x205.jpg"},"recent-thumb":{"file":"microsoft-edge-pdf-reader-001-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-350x316.jpg"},"service-featured":{"file":"microsoft-edge-pdf-reader-001-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-600x330.jpg"},"wp_rp_thumbnail":{"file":"microsoft-edge-pdf-reader-001-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":137389,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001.jpg"},"commentcount":14,"wp_comments":[{"id":132216,"parent":0,"author":0,"author_name":"Frank","author_email":"tanky79@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ebc1d89687a6b24b1742d7f631e83f177d8e2191edae748618cd5937c0e51aff?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ebc1d89687a6b24b1742d7f631e83f177d8e2191edae748618cd5937c0e51aff?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ebc1d89687a6b24b1742d7f631e83f177d8e2191edae748618cd5937c0e51aff?s=96&d=mm&r=g"},"date":"2020-04-16T08:21:01","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich bin inzwischen wieder zum alten Edge zur\u00fcckgekehrt. Nicht nur, dass er so ziemlich alles besser kann, er sieht auch besser aus.<\/p>\n"},"status":"1"},{"id":132225,"parent":0,"author":0,"author_name":"Andi","author_email":"andi-lau@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/34bb8232f4348a8d38ff737adfe7e3c84f628ed0e0884f073e4a67529af1e992?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/34bb8232f4348a8d38ff737adfe7e3c84f628ed0e0884f073e4a67529af1e992?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/34bb8232f4348a8d38ff737adfe7e3c84f628ed0e0884f073e4a67529af1e992?s=96&d=mm&r=g"},"date":"2020-04-16T10:55:26","cld_nonce":"82f011626f","content":{"rendered":"<p>Da wist du aber nicht mehr lange Freude dran haben. Da er durch den neuen Edge ersetzt wird.<\/p>\n"},"status":"1"},{"id":132226,"parent":132216,"author":0,"author_name":"Matthias","author_email":"matthiasboerner@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/cd7d9d38e52332b9fc56956ccbe103f4c549bc79ffc6a9a67ee89e9a8fae8c5e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/cd7d9d38e52332b9fc56956ccbe103f4c549bc79ffc6a9a67ee89e9a8fae8c5e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/cd7d9d38e52332b9fc56956ccbe103f4c549bc79ffc6a9a67ee89e9a8fae8c5e?s=96&d=mm&r=g"},"date":"2020-04-16T11:12:37","cld_nonce":"82f011626f","content":{"rendered":"<p>Hatte ich auch vor, da ich die PDF Tools oder SetAside einfach haben wollte, macht letztendlich aber keinen Sinn (leider).<br \/>\nEdge wird bald automatisch ersetzt, dann kann man auch nichts mehr \u00e4ndern. Lieber jetzt langsam den neuen Edge &#8222;kennen lernen&#8220; als einfach so alles verlieren.<\/p>\n"},"status":"1"},{"id":132229,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2020-04-16T11:25:31","cld_nonce":"82f011626f","content":{"rendered":"<p>&#8222;&#8230;Wir wissen, dass viele von Ihnen den PDF-Reader in Microsoft Edge lieben&#8230;&#8220; &#8211; ja nun &#8211; manche lieben den Adobe Reader noch ein bi\u00dfchen mehr. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_mrgreen.gif\" alt=\":mrgreen:\" class=\"wp-smiley\" \/> <\/p>\n<p>\u00b4t\u00fcrlich ist der \u00fcberladen, \u00b4t\u00fcrlich w\u00fcrde ein schlichterer reichen &#8211; aber der AR macht, was er f\u00fcr mich soll: man damit kann PDFs ganz gut lesen. Also bleibe ich beim gewohnten. Dass man den extra installieren mu\u00df, dass er \u00b4n paar hundert MB belegt &#8211; so what. Keine meiner C-Partitionen steht kurz vorm platzen, grins.<\/p>\n"},"status":"1"},{"id":132241,"parent":0,"author":0,"author_name":"golem","author_email":"knolle1@mein.gmx","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/df3fb81243c10a4beb42091b2746549b55437f2a45d52886fbd5366529b44095?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/df3fb81243c10a4beb42091b2746549b55437f2a45d52886fbd5366529b44095?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/df3fb81243c10a4beb42091b2746549b55437f2a45d52886fbd5366529b44095?s=96&d=mm&r=g"},"date":"2020-04-16T13:24:01","cld_nonce":"82f011626f","content":{"rendered":"<p>Ein Browser ist ein Browser. Mehr soll das Ding nicht k\u00f6nnen. Wenn MS einen tollen PDF Betrachter auf den Markt schmei\u00dfen will k\u00f6nnen sie den gerne aller Paint als native Anwendung in Windows integrieren und nicht in den Browser Stopfen!<\/p>\n"},"status":"1"},{"id":132242,"parent":132241,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-04-16T13:28:03","cld_nonce":"82f011626f","content":{"rendered":"<p>Jeder Browser hat diese Funktion. Keine Ahnung warum du da gleich wieder mosern musst.<\/p>\n"},"status":"1"},{"id":132256,"parent":0,"author":0,"author_name":"Holgi","author_email":"holger_freese@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=96&d=mm&r=g"},"date":"2020-04-16T15:12:02","cld_nonce":"82f011626f","content":{"rendered":"<p>grds. bin ich ja auch nicht so der Fan von Eierlegenden Wollmichs\u00e4uen.<br \/>\nAber bei einem Browser macht es irgendwie schon Sinn:<br \/>\nOft finde ich Online PDF-Dokumente zum Download (Preislisten, Bedienungsanleitungen etc.) und wenn die mir gleich angezeigt werden, ohne dass ich extra einen externen Reader anwerfen muss, finde ich das prima.<br \/>\nInsofern finde ich es auch nur konseqent, wenn dieser eingebaute PDF-Reader dann gleich die ganzen Zusatzfunktionen (Marker etc.) bekommt. Wer wei\u00df, vlt. ersetzt der Edge Chromium ja irgendwenn komplett meinen externen PDF Reader?<br \/>\nBTW:<br \/>\nwie kann man mit einem Befehl den Chromium Edge zum Default-Reader machen, also ohne die &#8222;\u00d6ffnen mit&#8220;, &#8222;Andere App ausw\u00e4hlen&#8220;, &#8222;immer die App zum \u00d6ffnen von&#8230;&#8220; -Methode zu bem\u00fchen?<br \/>\nhabe da mal mit Assoc und Ftype sowie &#8222;Dism \/Online \/Export-DefaultAppAssociations&#8220; und &#8222;Dism \/Online \/Import-DefaultAppAssociations&#8220; herumexperimentiert, aber noch keine gescheite L\u00f6sung gefunden.<\/p>\n"},"status":"1"},{"id":132270,"parent":132256,"author":2564,"author_name":"Nemo_G","author_email":"guenter.niemann@arcor.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1c7dc1e83f70168311f80d8c6dabdd6bc0e2819647b31be718aefbc97e5089dd?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1c7dc1e83f70168311f80d8c6dabdd6bc0e2819647b31be718aefbc97e5089dd?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1c7dc1e83f70168311f80d8c6dabdd6bc0e2819647b31be718aefbc97e5089dd?s=96&d=mm&r=g"},"date":"2020-04-16T17:38:33","cld_nonce":"82f011626f","content":{"rendered":"<p>Noch aus NT4-Zeiten und &#8222;still going strong&#8220;:<br \/>\n<code><br \/>\nRegisters or Unregisters a file extension with the NT 4.0 shell.<\/p>\n<p>ASSOCIATE .ext filename [\/q \/d \/f]<\/p>\n<p>  .ext          Extension to be associated.<br \/>\n  filename      Execuatble program to associate .ext with.<br \/>\n  \/q            Quiet - Suppresses all interactive prompts.<br \/>\n  \/d            Delete - Deletes the association if it exists.<br \/>\n  \/f            Force - Forces overwrite or delete without questions.<\/p>\n<p>Examples:<br \/>\n  Associate .Lst NotePad.Exe<br \/>\n  Adds the association of .Lst with Notepad.Exe.<\/p>\n<p>  Associate .Lst \/d<br \/>\n  Deletes the association of .Lst from Notepad.Exe.<\/p>\n<p>  Associate .Lst<br \/>\n  Returns the association for .Lst if it exists.<\/p>\n<p>Return Value:<br \/>\n  A return value of zero indicates success.<br \/>\n<\/code><\/p>\n<p>Sieht dann so aus, wenn associate. exe im Suchpfad liegt:<br \/>\n<code><br \/>\nassociate .pdf \"C:\\Program Files (x86)\\Microsoft\\Edge\\Application\\msedge.exe\"<br \/>\n<\/code><\/p>\n<p>Dabei stellt sich mir die Frage:<br \/>\nWarum installiert sich der Chromium-Enterprise-Edge (x64) ins &#8218;falsche&#8216; Programmverzeichnis?<\/p>\n<p>Gru\u00df, Nemo<\/p>\n"},"status":"1"},{"id":132273,"parent":132270,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-04-16T17:50:49","cld_nonce":"82f011626f","content":{"rendered":"<p>&#8222;Warum installiert&#8230;&#8220; &#8211; das ist &#8222;modern&#8220; , man muss nicht verstehen warum das MS macht &#8211; \u00fcbrigens nicht das einzige was da so ( trotz X64-System) sich so &#8222;rumtreibt&#8220; ( bei mir momentan 28 Verzeichnisse)<\/p>\n"},"status":"1"},{"id":132285,"parent":132270,"author":0,"author_name":"Holgi","author_email":"holger_freese@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0b9a7e8e22fe490941487d0cbe59d0e7232454955198e0bd0f0fc8b2f4a0043e?s=96&d=mm&r=g"},"date":"2020-04-16T19:05:05","cld_nonce":"82f011626f","content":{"rendered":"<p>danke Nemo_G<br \/>\njetzt erinnere ich mich daran; hatte es fr\u00fcher auch schon mal genutzt.<br \/>\nHier im WIKI gibt es auch noch Hinweise darauf:<br \/>\n<a href=\"http:\/\/www.deskmodder.de\/wiki\/index.php?title=Standardprogramm_oder_Dateityp_zuordnen_Windows_10\" rel=\"ugc\">http:\/\/www.deskmodder.de\/wiki\/index.php?title=Standardprogramm_oder_Dateityp_zuordnen_Windows_10<\/a><\/p>\n"},"status":"1"},{"id":132288,"parent":132273,"author":2564,"author_name":"Nemo_G","author_email":"guenter.niemann@arcor.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1c7dc1e83f70168311f80d8c6dabdd6bc0e2819647b31be718aefbc97e5089dd?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1c7dc1e83f70168311f80d8c6dabdd6bc0e2819647b31be718aefbc97e5089dd?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1c7dc1e83f70168311f80d8c6dabdd6bc0e2819647b31be718aefbc97e5089dd?s=96&d=mm&r=g"},"date":"2020-04-16T19:31:51","cld_nonce":"82f011626f","content":{"rendered":"<p>Auch der Halbbruder ist so ein Schlawiner:<br \/>\n&#8222;c:\\Program Files (x86)\\Google\\Chrome\\Application\\chrome.exe&#8220;<\/p>\n"},"status":"1"},{"id":138157,"parent":0,"author":0,"author_name":"MB","author_email":"mabu94@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/cb4a83b6ed35b77d5ac796e2cd231624f8a86666b2c88e461904c3050bb0d926?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/cb4a83b6ed35b77d5ac796e2cd231624f8a86666b2c88e461904c3050bb0d926?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/cb4a83b6ed35b77d5ac796e2cd231624f8a86666b2c88e461904c3050bb0d926?s=96&d=mm&r=g"},"date":"2020-06-22T15:44:47","cld_nonce":"82f011626f","content":{"rendered":"<p>Texte am Surface markieren ist nicht mehr ohne weiteres M\u00f6glich &#8211; wie schlecht kann man bitte ein update machen. Ein absolutes \u00c4rgernis!<\/p>\n"},"status":"1"},{"id":144325,"parent":0,"author":0,"author_name":"Anni","author_email":"superdagobert@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/16103ab89540e181fb99bf76998853961455d0b78921bceacbedc8c38c67d9bd?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/16103ab89540e181fb99bf76998853961455d0b78921bceacbedc8c38c67d9bd?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/16103ab89540e181fb99bf76998853961455d0b78921bceacbedc8c38c67d9bd?s=96&d=mm&r=g"},"date":"2020-08-24T11:33:08","cld_nonce":"82f011626f","content":{"rendered":"<p>Habe beim alten Edge geliebt, wie einfach man PDFs bearbeiten (markieren + reinschreiben) konnte. Jetzt geht nur noch eine Farbe zum Schreiben, Textmarkern gar nicht mehr?! Wei\u00df jemand, ob das wieder kommt oder kann ich direkt zu einem anderen Programm wechseln? ^^ Im Artikel sieht es sehr sch\u00f6n aus, allerdings fehlt mir das Dreieck, um die weiteren Optionen beim Bearbeiten zu erhalten.. also quasi nutzlos<\/p>\n"},"status":"1"},{"id":144327,"parent":144325,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-08-24T11:45:35","cld_nonce":"82f011626f","content":{"rendered":"<p>In der Canary gibt es auch schon das &#8222;Textmarkern&#8220;. Auch die Men\u00fcleiste sieht schon viel besser aus. Der Artikel ist von April. Seitdem hat sich einiges getan, bzw. kommt noch. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n<p><a href=\"https:\/\/abload.de\/img\/1z3kic.jpg\"  rel=\"lightbox[137389] nofollow ugc\">https:\/\/abload.de\/img\/1z3kic.jpg<\/a><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Microsoft Edge - PDF-Reader bekommt weitere Funktionen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft Edge - PDF-Reader bekommt weitere Funktionen\" \/>\n<meta property=\"og:description\" content=\"Der &#8222;alte&#8220; Microsoft Edge war als PDF-Reader gut mit Funktionen ausgestattet. Deshalb hat das Edge-Team auch schon viele Anfragen erhalten. Nun hat man eine \u00dcbersicht gezeigt, welche Funktionen mit dem Edge 83 (Stable), also der finalen Version kommen werden und&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-16T05:35:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1195\" \/>\n\t<meta property=\"og:image:height\" content=\"713\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Microsoft Edge &#8211; PDF-Reader bekommt weitere Funktionen\",\"datePublished\":\"2020-04-16T05:35:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/\"},\"wordCount\":313,\"commentCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/microsoft-edge-pdf-reader-001.jpg\",\"keywords\":[\"Microsoft Edge\",\"Neue Funktionen\",\"PDF Reader\"],\"articleSection\":[\"Browser\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/\",\"name\":\"Microsoft Edge - PDF-Reader bekommt weitere Funktionen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/microsoft-edge-pdf-reader-001.jpg\",\"datePublished\":\"2020-04-16T05:35:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/microsoft-edge-pdf-reader-001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/microsoft-edge-pdf-reader-001.jpg\",\"width\":1195,\"height\":713},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/04\\\/16\\\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft Edge &#8211; PDF-Reader bekommt weitere Funktionen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Microsoft Edge - PDF-Reader bekommt weitere Funktionen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/","og_locale":"de_DE","og_type":"article","og_title":"Microsoft Edge - PDF-Reader bekommt weitere Funktionen","og_description":"Der &#8222;alte&#8220; Microsoft Edge war als PDF-Reader gut mit Funktionen ausgestattet. Deshalb hat das Edge-Team auch schon viele Anfragen erhalten. Nun hat man eine \u00dcbersicht gezeigt, welche Funktionen mit dem Edge 83 (Stable), also der finalen Version kommen werden und&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-04-16T05:35:16+00:00","og_image":[{"width":1195,"height":713,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Microsoft Edge &#8211; PDF-Reader bekommt weitere Funktionen","datePublished":"2020-04-16T05:35:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/"},"wordCount":313,"commentCount":14,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001.jpg","keywords":["Microsoft Edge","Neue Funktionen","PDF Reader"],"articleSection":["Browser"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/","name":"Microsoft Edge - PDF-Reader bekommt weitere Funktionen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001.jpg","datePublished":"2020-04-16T05:35:16+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001.jpg","width":1195,"height":713},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/04\/16\/microsoft-edge-pdf-reader-bekommt-weitere-funktionen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Microsoft Edge &#8211; PDF-Reader bekommt weitere Funktionen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/04\/microsoft-edge-pdf-reader-001.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/137389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=137389"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/137389\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/137391"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=137389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=137389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=137389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}