{"id":135086,"date":"2020-03-01T18:36:59","date_gmt":"2020-03-01T17:36:59","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=135086"},"modified":"2020-03-01T19:22:38","modified_gmt":"2020-03-01T18:22:38","slug":"build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/","title":{"rendered":"Build 7850 &#8211; Erster Win 8 Leak &#8211; Man, da werden Erinnerungen geweckt"},"content":{"rendered":"<p>Albacore hat gerade den ersten Leak der Windows 8 Build 7850 Milestone 1 herausgekramt. Das ist nun fast 10 Jahre her und der Anfang von Metro und den \u00c4nderungen. Da werden wirklich Erinnerungen wach.<\/p>\n<p>Damals gab es noch Leaks, die Microsoft (noch) nicht unterbinden konnte. Die Build 7850 war damals die erste, die so ins Netz gelangte. Viel zu sehen gab es da noch nicht. Im Prinzip eine Windows 7 mit ein paar kleinen \u00c4nderungen. Aber mit der Zeit kamen diese dann ja. Metro-Style, Kacheln, das neue Startmen\u00fc und die Sidebar, die hier im Bild noch sehr unfertig aussieht.<\/p>\n<div id='gallery-1' class='gallery galleryid-135086 gallery-columns-2 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001.jpg' rel=\"lightbox[135086]\"><img loading=\"lazy\" decoding=\"async\" width=\"273\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-273x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-273x205.jpg 273w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-480x360.jpg 480w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-777x583.jpg 777w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001.jpg 1024w\" sizes=\"auto, (max-width: 273px) 100vw, 273px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-002.jpg' rel=\"lightbox[135086]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"191\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-002-306x191.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-002-306x191.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-002-500x313.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-002-810x506.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-002-320x200.jpg 320w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-002.jpg 1024w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>K\u00f6nnt ihr euch auch noch daran erinnern? Man war schon gespannt, was Microsoft da aus dem Hut zaubert. Die Grundidee war nicht schlecht. Aber im Endeffekt war man der Zeit vielleicht zu weit voraus, sodass man es nicht wirklich vermarkten konnte und mit Windows 10 dann zur\u00fcckgerudert ist. Immerhin fast 10 Jahre her. Albacore will noch weitere Screenshots <a href=\"https:\/\/twitter.com\/thebookisclosed\/status\/1234140468570705922\" target=\"_blank\" rel=\"noopener noreferrer\">auf Twitter posten<\/a>. Also bleibt neugierig.<\/p>\n<p>Das war auch f\u00fcr uns der Zeitraum, wo wir damals einen absoluten Cut gemacht hatten und &#8222;<a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php\/Die_Geschichte_von_deskmodder.de#Styling_is_everything_ist_nun_Geschichte\" target=\"_blank\" rel=\"noopener noreferrer\">Styling is Everything<\/a>&#8220; in den Ruhestand geschickt hatten. Ab diesem Zeitraum hatten wir uns dann auf Windows 8 und eben sp\u00e4ter auf Windows 10 und den Blog konzentriert. Man ist das lange her.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Albacore hat gerade den ersten Leak der Windows 8 Build 7850 Milestone 1 herausgekramt. Das ist nun fast 10 Jahre her und der Anfang von Metro und den \u00c4nderungen. Da werden wirklich Erinnerungen wach. Damals gab es noch Leaks, die&hellip; <\/p>\n","protected":false},"author":134,"featured_media":135088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[60884],"tags":[70155,9742],"class_list":["post-135086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internet","tag-build-7850","tag-windows-8"],"wp_featured_image":{"id":135088,"alt_text":"","description":"","media_type":"image","media_details":{"width":1024,"height":768,"file":"2020\/03\/build-7850-001.jpg","sizes":{"medium":{"file":"build-7850-001-480x360.jpg","width":480,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-480x360.jpg"},"large":{"file":"build-7850-001-777x583.jpg","width":777,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-777x583.jpg"},"thumbnail":{"file":"build-7850-001-273x205.jpg","width":273,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-273x205.jpg"},"wp_review_large":{"file":"build-7850-001-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-320x200.jpg"},"wp_review_small":{"file":"build-7850-001-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-65x65.jpg"},"blog-large":{"file":"build-7850-001-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-642x300.jpg"},"blog-medium":{"file":"build-7850-001-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-306x205.jpg"},"recent-thumb":{"file":"build-7850-001-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-350x316.jpg"},"service-featured":{"file":"build-7850-001-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-600x330.jpg"},"wp_rp_thumbnail":{"file":"build-7850-001-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":135086,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001.jpg"},"commentcount":12,"wp_comments":[{"id":128489,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2020-03-01T21:26:48","cld_nonce":"82f011626f","content":{"rendered":"<p>Oh ja &#8211; Erinnerungen werde da wach&#8230; Ungef\u00e4hr so: &#8222;Das ist ja, das ist ja, das ist ja &#8211; haben die Redmonder einen an der M\u00fctze? Meinen die das ernstlich? Herr im Himmel, G.s.D. hat Win7 noch laaange Support!&#8220;<\/p>\n<p>Auf einem Comp habe ich Win8 installiert, dabei ist es geblieben. und ich D\u00f6del hatte es mir 1x im Karton f\u00fcr 50,- plus 1x als Key f\u00fcr 30,- &#8222;geg\u00f6nnt&#8220;. Na, den Key habe ich sp\u00e4ter einem Net-Bekannten geschenkt, der sein Win7 HP auf Win8 Pro und dann auf Win10 Pro bringen konnte. Die 50,- habe ich unter: &#8222;Voll ins Klo gegriffen&#8230;&#8220; abgehakt. So. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_mrgreen.gif\" alt=\":mrgreen:\" class=\"wp-smiley\" \/> Weiter gehts &gt;<\/p>\n<p>&gt; ich habe Win8\/8.1 &#8222;ganz nebenher&#8220; \u00fcberlebt, der Comp auch. Inzwischen stand er mit Win10 im Eckchen, weil kein Platz mehr war. Bis ich vor kurz in der K\u00fcche Platz geschaffen habe &#8211; f\u00fcr ihn, 2 Monitore, Tastatur, Maus etc.<\/p>\n<p>Mir d\u00fcnkt, selbst MS spricht nicht mehr soo gerne von Win8\/8.1 &#8211; aber ungeschehen machen ist nicht. Viele haben ein langes Ged\u00e4chtnis, grins. Ein Fest f\u00fcr &#8222;Vollbildner&#8220; war\u00b4s &#8211; ich bin alles andere als das. Sehe ich da meine sch\u00f6nen Wallpaper? Neien, kein Fitzelchen davon! Also halte ich mich strikt an: &#8222;Windows hei\u00dft Fenster.&#8220;<\/p>\n"},"status":"1"},{"id":128490,"parent":0,"author":0,"author_name":"Jens1976","author_email":"jens1976@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4c4bac72cd4f4ef7ba8f01eef01405e8991b7796d077f7911828c58367f26534?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4c4bac72cd4f4ef7ba8f01eef01405e8991b7796d077f7911828c58367f26534?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4c4bac72cd4f4ef7ba8f01eef01405e8991b7796d077f7911828c58367f26534?s=96&d=mm&r=g"},"date":"2020-03-01T22:13:29","cld_nonce":"82f011626f","content":{"rendered":"<p>Den Windows 8\/8.1 Rotz h\u00e4tten die sich besser verkniffen. Keine Ahnung welcher Praktikant da federf\u00fchrend war&#8230;. <\/p>\n<p><i>gepostet mit der <a href='https:\/\/play.google.com\/store\/apps\/details?id=com.deskmodder' rel=\"nofollow ugc\">Deskmodder.de-App f\u00fcr Android<\/a><\/i><\/p>\n"},"status":"1"},{"id":128491,"parent":0,"author":0,"author_name":"Brokoli1","author_email":"bujalskische@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fe1cc970b6b92623301adc91e1f26b3a8dfe927649868a0caf16f1ba02511edd?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fe1cc970b6b92623301adc91e1f26b3a8dfe927649868a0caf16f1ba02511edd?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fe1cc970b6b92623301adc91e1f26b3a8dfe927649868a0caf16f1ba02511edd?s=96&d=mm&r=g"},"date":"2020-03-01T22:46:14","cld_nonce":"82f011626f","content":{"rendered":"<p>Oh man, ja das wei\u00df ich noch genau. Da war ich damals s\u00fcchtig nach neuen Builds. Ich hatte sogar eine eigene Website zusammengebaut und in meiner freien Zeit jeden Tag versucht an neue ISOs zu kommen, um Screenshots zu machen und Texte zu schreiben. Damals war es ja noch total \u201eillegal\u201c diese Versionen zu testen. Das ist dann mit dem Insiderprogramm und den ganzen Publoc Betas bei Apple und Co. total langweilig geworden. Der Reiz ist weg. <\/p>\n<p>Damals habe ich die Windows 8.0 Developer noch auf meinem Gamer-PC als Produktivsystem installiert, weil ich vor meinem Kumpels auf der LAN-Party der Trendsetter sein wollte und allen die \u201eZukunft\u201c pr\u00e4sentieren. Da war ModernUI Bzw Metro damals noch total neu. <\/p>\n<p>Das war auch die Zeit, als ich jede Windows Version im Regal stehen haben wollte und jede Windows Longhorn Iso aus dem Netz gefischt und auf die VM installiert habe. <\/p>\n<p>F\u00fchlt sich an, als w\u00e4re es gestern gewesen&#8230;ist aber schon lange her. <\/p>\n<p>Eines meiner Hobbys eben&#8230;als MS dann fast w\u00f6chentlich neue Builds rausgehauen hat von Windows 10 hatte ich dann irgendwann keine Lust mehr auf die Website und habe nichts mehr gemacht daran. <\/p>\n<p>Ab und zu w\u00fcnsche ich mir so ein geleaktes, halb fertiges und total verbuggted Pre-Alpha Windows zur\u00fcck. Ein perfektes OS ist doch langweilig. Da gibt es nichts zu entdecken <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n<p><a href=\"https:\/\/windowseight.jimdofree.com\/windows-8-1-8-0\/milestones-1\/build-7850\/\" rel=\"nofollow ugc\">https:\/\/windowseight.jimdofree.com\/windows-8-1-8-0\/milestones-1\/build-7850\/<\/a><\/p>\n<p>PS: F\u00fcr weiter Artikel dieser Art (und das w\u00fcrde mich freuen), d\u00fcrfen gerne meine Bilder und Infos benutzt werden.<\/p>\n"},"status":"1"},{"id":128492,"parent":0,"author":5243,"author_name":"eRaz0r","author_email":"spam84@ymail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=96&d=mm&r=g"},"date":"2020-03-01T22:49:14","cld_nonce":"82f011626f","content":{"rendered":"<p>War das beste Windows \u00fcberhaupt- Speziell 8.1 &#8230; 2012 bis 2018 machte es spa\u00df seinen PC zu nutzen. 10 ist ok, aber lahmer und fehleranf\u00e4lliger. Aber nachdem 8.1 auf meinem Ryzen nicht mehr l\u00e4uft &#8211; muss man sich mit 10 ohnehin anfreunden. Ob man will, oder nicht <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":128493,"parent":128492,"author":0,"author_name":"Dark","author_email":"darklegio@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/2e3527a096877296991026564b81f0f2e16f9241a963542d317f0cf0fd3de885?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/2e3527a096877296991026564b81f0f2e16f9241a963542d317f0cf0fd3de885?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/2e3527a096877296991026564b81f0f2e16f9241a963542d317f0cf0fd3de885?s=96&d=mm&r=g"},"date":"2020-03-01T22:56:37","cld_nonce":"82f011626f","content":{"rendered":"<p>&#8222;War das beste Windows \u00fcberhaupt [&#8230;]&#8220; \u00e4hm, Scherz oder?<\/p>\n"},"status":"1"},{"id":128496,"parent":128493,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-03-02T00:48:59","cld_nonce":"82f011626f","content":{"rendered":"<p>Aber immer. Kein Bl\u00f6des Startmen\u00fc, kein Freeze des Router mehr, den musste ich unter 7 etwa 2 Mal die Woche zur\u00fccksetzen, mit 8.1 nicht mehr. Warum das Teil aus der Steinzeit (Startmen\u00fc) den Weg zur\u00fcckfand ist mir ein R\u00e4tsel.<\/p>\n"},"status":"1"},{"id":128497,"parent":128493,"author":0,"author_name":"Carsten","author_email":"jazzvisions@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5f195933fd350bb65ea264d4021dcb6c20301f81f546463b23e4362da8e15bf6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5f195933fd350bb65ea264d4021dcb6c20301f81f546463b23e4362da8e15bf6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5f195933fd350bb65ea264d4021dcb6c20301f81f546463b23e4362da8e15bf6?s=96&d=mm&r=g"},"date":"2020-03-02T00:49:12","cld_nonce":"82f011626f","content":{"rendered":"<p>Ne, ich denke das war und ist kein Scherz.<\/p>\n<p>Win 8\/8.1 lief damals auf jedem Rechner problemlos, selbst auf den Schw\u00e4chsten und \u00c4ltesten. Da gab es auch keine Treiberprobleme. Und schneller lief es allemahl. Mein damaliges Notebook war f\u00fcr Win 7 schon zu alt, es lie\u00df sich darauf nicht installieren. Ich war dann sehr \u00fcberrascht, dass es mit Win 8 jedoch anstandslos funktionierte. 15 Minuten dauerte der gesamte Installationsprozess.<\/p>\n<p>Das war ja auch das Konzept hinter Win 8. Dass es ein sehr recourcenschonendes Betriebssystem sein sollte, welches auch auf \u00e4lterer und schwacher Hardware problemlos l\u00e4uft. Und das tat es ja auch.<\/p>\n<p>In sofern ja, da wird man schon wehm\u00fctig.<\/p>\n<p>Gut, das fehlende Startmen\u00fc h\u00e4tte wirklich nicht sein m\u00fcssen (obwohl das Men\u00fc von Win 7  &#8211; in deaktivierter Form &#8211; immer noch im System war). Der Entwickler von StartIsBack hat es dann als einzigster geschafft, den Code aufzubrechen und schon hatte man das 7er Originalmen\u00fc &#8211; und nicht nur einen Nachbau, wie bei allen anderen Herstellern &#8211; in seinem Win 8. Aber MS hat das dann ja sp\u00e4ter von den Usern gelernt und in komplett neuer Form wieder eingebaut.<\/p>\n"},"status":"1"},{"id":128503,"parent":0,"author":0,"author_name":"Hugo Portwisch","author_email":"gagagaga@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/862f8b53abdc2e450eef541022e19d979763de4333e1f2156dd09025525aa1d4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/862f8b53abdc2e450eef541022e19d979763de4333e1f2156dd09025525aa1d4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/862f8b53abdc2e450eef541022e19d979763de4333e1f2156dd09025525aa1d4?s=96&d=mm&r=g"},"date":"2020-03-02T06:18:02","cld_nonce":"82f011626f","content":{"rendered":"<p>*Mann<\/p>\n"},"status":"1"},{"id":128512,"parent":0,"author":5893,"author_name":"stay_connected_3","author_email":"fettabroiler@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7712d17514f0731c3faf869661c939c9538b3368cede42d661256097be0a33a9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7712d17514f0731c3faf869661c939c9538b3368cede42d661256097be0a33a9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7712d17514f0731c3faf869661c939c9538b3368cede42d661256097be0a33a9?s=96&d=mm&r=g"},"date":"2020-03-02T10:17:00","cld_nonce":"82f011626f","content":{"rendered":"<p>[&#8230;] Keine Ahnung welcher Praktikant da federf\u00fchrend war\u2026. [&#8230;\/]<\/p>\n<p>Um die Frage von oben zu beantworten:<br \/>\nDer damals Verantwortliche f\u00fcr die Windows-Entwicklung hie\u00df Steven Sinowsky.<br \/>\nEr verlie\u00df MS ein paar Wochen nach Ver\u00f6ffentlichung von Windows 8.<br \/>\n&#8230;. oder wurde gegangen&#8230; Wer wei\u00df das schon&#8230; Steve Ballmer vielleicht&#8230;.<\/p>\n"},"status":"1"},{"id":128517,"parent":0,"author":0,"author_name":"arcticocean","author_email":"trash_acc@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4c7424dc5ab84a9d1ea050f4bc8293af5505cf90e7cade0001f388ea02806ef9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4c7424dc5ab84a9d1ea050f4bc8293af5505cf90e7cade0001f388ea02806ef9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4c7424dc5ab84a9d1ea050f4bc8293af5505cf90e7cade0001f388ea02806ef9?s=96&d=mm&r=g"},"date":"2020-03-02T10:51:12","cld_nonce":"82f011626f","content":{"rendered":"<p>Mit Windows 8, 8.1 und 10 verbinde ich vor allem eines: den Start der Generation von ressourcensparenden und absturzfreien MS Betriebssystemen. Die Kommentare der ewig gestrigen hier belustigen mich eigentlich nur noch. Windows 7 war in KEINERLEI Aspekt besser als 10. Bei 8 lasse ich noch wegen des Wegfalls des Startmen\u00fc mit mir reden, das kam f\u00fcr einige vielleicht zu pl\u00f6tzlich. Wer aber jetzt noch mit 7 rumgammelt, ist entweder nicht die hellste LED auf dem Mainboard oder Admin in einem Unternehmen mit einem Chef, der noch Schreibmaschine nutzt.<\/p>\n"},"status":"1"},{"id":128522,"parent":128517,"author":0,"author_name":"freetux","author_email":"dxmatze@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/909ee2cee4ff2c034d2757967de0e5dbeaeda96336e169826f80fbc849f9b7de?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/909ee2cee4ff2c034d2757967de0e5dbeaeda96336e169826f80fbc849f9b7de?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/909ee2cee4ff2c034d2757967de0e5dbeaeda96336e169826f80fbc849f9b7de?s=96&d=mm&r=g"},"date":"2020-03-02T12:28:37","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich habe zum Supportende einige meiner alten Kisten meiner Rechnersammlung auf 8.1 statt 10 gehoben. Ist einfach stressfreier wenn diese eh nicht so oft gebootet werden, das wenigstens keine Upgradeorgie ansteht.<\/p>\n<p>Ein paar wenige bleiben auf Windows 7 und fr\u00fcher. Werden halt entsprechend in einem eigenen Netz isoliert. Wer das nicht kann, der sollte zumindest das Gateway entfernen..<\/p>\n<p>Windows 7 hat sehr wohl Aspekte wo es f\u00fcr Endanwender angenehmer war:<br \/>\n&#8211; Vollst\u00e4ndige Kontrolle \u00fcber das Patchverhalten<br \/>\n&#8211; Weniger eingeschr\u00e4nkte Pro-Edition (unter anderem die Kastrierten Gruppenrichtlinien)<br \/>\n&#8211; Stabilere Patches, generell bessere Qualit\u00e4tskontrolle als heute<br \/>\n&#8211; Generell kein Druck durch das OS zu MS Clouddiensten gepusht zu werden, schlicht weil diese Dienste noch nicht existiert haben<\/p>\n"},"status":"1"},{"id":128543,"parent":128490,"author":3899,"author_name":"Andre45","author_email":"cloudstrife97@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3ad52e495196ca15817024481e3a5517674dbebf9e2a65bf8b178bb2afd69d76?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3ad52e495196ca15817024481e3a5517674dbebf9e2a65bf8b178bb2afd69d76?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3ad52e495196ca15817024481e3a5517674dbebf9e2a65bf8b178bb2afd69d76?s=96&d=mm&r=g"},"date":"2020-03-02T19:42:19","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich fands nicht Rotz, ich kam mit 8 und auch 8.1 klar, seitdem es Windows 8 gab, bin ich auch nie wieder zu 7 zur\u00fcck gegangen, da ich es nicht vermisst habe. Und heute bin ich mit Windows 10 Gl\u00fccklich. Ich tanz vielleicht ein bisschen aus der Reihe, aber jeder hat einen anderen Geschmack.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Build 7850 - Erster Win 8 Leak - Man, da werden Erinnerungen geweckt - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Build 7850 - Erster Win 8 Leak - Man, da werden Erinnerungen geweckt\" \/>\n<meta property=\"og:description\" content=\"Albacore hat gerade den ersten Leak der Windows 8 Build 7850 Milestone 1 herausgekramt. Das ist nun fast 10 Jahre her und der Anfang von Metro und den \u00c4nderungen. Da werden wirklich Erinnerungen wach. Damals gab es noch Leaks, die&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-01T17:36:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-01T18:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Build 7850 &#8211; Erster Win 8 Leak &#8211; Man, da werden Erinnerungen geweckt\",\"datePublished\":\"2020-03-01T17:36:59+00:00\",\"dateModified\":\"2020-03-01T18:22:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/\"},\"wordCount\":222,\"commentCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/build-7850-001.jpg\",\"keywords\":[\"Build 7850\",\"Windows 8\"],\"articleSection\":[\"Welt des Internets\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/\",\"name\":\"Build 7850 - Erster Win 8 Leak - Man, da werden Erinnerungen geweckt - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/build-7850-001.jpg\",\"datePublished\":\"2020-03-01T17:36:59+00:00\",\"dateModified\":\"2020-03-01T18:22:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/build-7850-001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/build-7850-001.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Build 7850 &#8211; Erster Win 8 Leak &#8211; Man, da werden Erinnerungen geweckt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Build 7850 - Erster Win 8 Leak - Man, da werden Erinnerungen geweckt - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/","og_locale":"de_DE","og_type":"article","og_title":"Build 7850 - Erster Win 8 Leak - Man, da werden Erinnerungen geweckt","og_description":"Albacore hat gerade den ersten Leak der Windows 8 Build 7850 Milestone 1 herausgekramt. Das ist nun fast 10 Jahre her und der Anfang von Metro und den \u00c4nderungen. Da werden wirklich Erinnerungen wach. Damals gab es noch Leaks, die&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-03-01T17:36:59+00:00","article_modified_time":"2020-03-01T18:22:38+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Build 7850 &#8211; Erster Win 8 Leak &#8211; Man, da werden Erinnerungen geweckt","datePublished":"2020-03-01T17:36:59+00:00","dateModified":"2020-03-01T18:22:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/"},"wordCount":222,"commentCount":12,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001.jpg","keywords":["Build 7850","Windows 8"],"articleSection":["Welt des Internets"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/","name":"Build 7850 - Erster Win 8 Leak - Man, da werden Erinnerungen geweckt - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001.jpg","datePublished":"2020-03-01T17:36:59+00:00","dateModified":"2020-03-01T18:22:38+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/build-7850-erster-win-8-leak-man-da-werden-erinnerungen-geweckt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Build 7850 &#8211; Erster Win 8 Leak &#8211; Man, da werden Erinnerungen geweckt"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/build-7850-001.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/135086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=135086"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/135086\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/135088"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=135086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=135086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=135086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}