{"id":135069,"date":"2020-03-01T09:46:38","date_gmt":"2020-03-01T08:46:38","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=135069"},"modified":"2020-03-01T12:51:07","modified_gmt":"2020-03-01T11:51:07","slug":"microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/","title":{"rendered":"Microsoft Edge: Mit einem Geheimcode mit Ninjacat surfen"},"content":{"rendered":"<p>Es ist Wochenende und da passt dann auch ein kleiner Hinweis auf einen versteckten Spiel-Modus im Microsoft Edge in der Canary und Developer Version. Denn man kann auch mit NinjaCat surfen. NinjaCat kennen die Insider ja.<\/p>\n<p>Gibt man edge:\/\/surf ein und dr\u00fcckt die Enter-Taste so kann man zwischen verschiedenen Figuren ausw\u00e4hlen. M\u00f6chte man aber mit NinjaCat surfen, dann muss man den bekannten Konami-Code, dessen Erfinder Kazuhisa Hashimoto gerade gestorben ist eingeben. Ist die Seite aktiv dann ganz einfach die Pfeiltasten:<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat.jpg\" rel=\"lightbox[135069]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-135071\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-500x325.jpg\" alt=\"\" width=\"500\" height=\"325\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-500x325.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-810x527.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-306x199.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat.jpg 1246w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<ul>\n<li>hoch, hoch, runter, runter, links, rechts, links, rechts, b, a &#8211; \u2191 \u2191 \u2193 \u2193 \u2190 \u2192 \u2190 \u2192 b a<\/li>\n<li>Nun erscheint nur NinjaCat und man kann loslegen.<\/li>\n<\/ul>\n<p>Nebenbei hat Microsoft das kleine Game nun auch offline verf\u00fcgbar gemacht.<\/p>\n<h3>Alle Microsoft Edge Downloads auch Insider:<\/h3>\n<ul>\n<li><strong>Stable Version:<\/strong> Auswahl alle Versionen <a href=\"https:\/\/www.microsoft.com\/en-us\/edge\" target=\"_blank\" rel=\"noopener noreferrer\">microsoft.com\/edge<\/a> Direkt Windows 10: <a href=\"https:\/\/go.microsoft.com\/fwlink\/?linkid=2069324&amp;Channel=Stable&amp;language=de\" target=\"_blank\" rel=\"noopener noreferrer\">go.microsoft.com\/Channel=Stable<\/a><\/li>\n<li>Die <strong>portablen Versionen:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/05\/27\/portabler-microsoft-edge-chromium-updater-fuer-canary-developer-beta-und-spaeter-auch-der-finale-edge\/\" target=\"_blank\" rel=\"noopener noreferrer\">Portable Edge Updater<\/a><\/li>\n<li>Offline-Installer Stable Enterprise <a href=\"http:\/\/go.microsoft.com\/fwlink\/?LinkID=2093437\" target=\"_blank\" rel=\"noopener noreferrer\">X64.msi <\/a>, <a href=\"http:\/\/go.microsoft.com\/fwlink\/?LinkID=2093505\" target=\"_blank\" rel=\"noopener noreferrer\">X86.msi <\/a><\/li>\n<li>Mac Enterprise Stable: <a href=\"http:\/\/go.microsoft.com\/fwlink\/?LinkID=2093438\" target=\"_blank\" rel=\"noopener noreferrer\">macOS.pkg <\/a><\/li>\n<li>Android: <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.microsoft.emmx&amp;hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">play.google.com\/microsoft.emmx<\/a><\/li>\n<li>iOS: <a href=\"https:\/\/apps.apple.com\/de\/app\/microsoft-edge\/id1288723196\" target=\"_blank\" rel=\"noopener noreferrer\">apps.apple.com\/microsoft-edge<\/a><\/li>\n<li><strong>Die weiteren Links f\u00fcr Insider<\/strong><\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/\" target=\"_blank\" rel=\"noopener noreferrer\">win10<\/a>, <a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win8dot1\" target=\"_blank\" rel=\"noopener noreferrer\">win8dot1<\/a>, <a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win8\" target=\"_blank\" rel=\"noopener noreferrer\">platform=win8<\/a>, <a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win7\" target=\"_blank\" rel=\"noopener noreferrer\">platform=win7<\/a><\/li>\n<li>Und f\u00fcr die Macs:<\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=macos\" target=\"_blank\" rel=\"noopener noreferrer\">microsoftedgeinsider.com\/download\/platform=macos<\/a><\/li>\n<\/ul>\n<div class=\"viaquelle\">via: <a href=\"https:\/\/techdows.com\/2020\/03\/ninjacat-in-edge-surf-game.html\" target=\"_blank\" rel=\"noopener noreferrer\">techdows<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Es ist Wochenende und da passt dann auch ein kleiner Hinweis auf einen versteckten Spiel-Modus im Microsoft Edge in der Canary und Developer Version. Denn man kann auch mit NinjaCat surfen. NinjaCat kennen die Insider ja. Gibt man edge:\/\/surf ein&hellip; <\/p>\n","protected":false},"author":134,"featured_media":135071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166],"tags":[70140,8501,70139,70138],"class_list":["post-135069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-browser","tag-konami-code","tag-microsoft-edge","tag-ninjacat","tag-surf"],"wp_featured_image":{"id":135071,"alt_text":"","description":"","media_type":"image","media_details":{"width":1246,"height":810,"file":"2020\/03\/microsoft-edge-surf-ninjacat.jpg","sizes":{"medium":{"file":"microsoft-edge-surf-ninjacat-500x325.jpg","width":500,"height":325,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-500x325.jpg"},"large":{"file":"microsoft-edge-surf-ninjacat-810x527.jpg","width":810,"height":527,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-810x527.jpg"},"thumbnail":{"file":"microsoft-edge-surf-ninjacat-306x199.jpg","width":306,"height":199,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-306x199.jpg"},"wp_review_large":{"file":"microsoft-edge-surf-ninjacat-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-320x200.jpg"},"wp_review_small":{"file":"microsoft-edge-surf-ninjacat-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-65x65.jpg"},"blog-large":{"file":"microsoft-edge-surf-ninjacat-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-642x300.jpg"},"blog-medium":{"file":"microsoft-edge-surf-ninjacat-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-306x205.jpg"},"recent-thumb":{"file":"microsoft-edge-surf-ninjacat-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-350x316.jpg"},"service-featured":{"file":"microsoft-edge-surf-ninjacat-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-600x330.jpg"},"wp_rp_thumbnail":{"file":"microsoft-edge-surf-ninjacat-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":135069,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat.jpg"},"commentcount":18,"wp_comments":[{"id":128476,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2020-03-01T12:12:35","cld_nonce":"82f011626f","content":{"rendered":"<p>Was? Wie? Wo? Konami?<\/p>\n<p>&#8211; hoch, hoch, runter, runter, links, rechts, links, rechts, b, a \u2013 \u2191 \u2191 \u2193 \u2193 \u2190 \u2192 \u2190 \u2192 b a<\/p>\n<p>Mann, da verknote ich ja meine Finger &#8211; das mache ich lieber nicht&#8230;  <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_mrgreen.gif\" alt=\":mrgreen:\" class=\"wp-smiley\" \/> <\/p>\n<p>&#8211; Nun erscheint nur NinjaCat und man kann loslegen.<\/p>\n<p>Leider nicht, da ich ja meine Finger geschont habe <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/> <\/p>\n<p>Da lob\u00b4 ich mir das eSheep, eine der wenigen sinnvollen (grins) Apps aus dem MS Store &#8211; a.j.F. eine, die ich benutze und f\u00fcr gut befinde&#8230;<\/p>\n<p>&#8230;weil das kleine Schaf mit allem m\u00f6glichen fertig wird\/macht : es trottet, es springt, es g\u00e4hnt, es fri\u00dft Blumen und, und&#8230;kommt klaglos mit 2 oder gar 3 Monitoren zurecht &#8211; es l\u00e4uft einfach \u00fcberall, sogar an der &#8222;Decke&#8220; (oberer Screenrand, dann mit den F\u00fc\u00dfen oben, Kopf unten).<\/p>\n<p>Ohne, das ich iwi eingreifen oder was tun mu\u00df &#8211; au\u00dfer, das ich den Autostart zulasse. Dieses Schaf k\u00f6nnte fast ein Freund werden.<\/p>\n"},"status":"1"},{"id":128480,"parent":0,"author":0,"author_name":"Stefan D.","author_email":"Mail@Stefan-Dahlmann.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/83b271bb8bb9cd18d9b9a58431fe65f387a4b8fb4eab3e8dc7a8f2aaf6da45e6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/83b271bb8bb9cd18d9b9a58431fe65f387a4b8fb4eab3e8dc7a8f2aaf6da45e6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/83b271bb8bb9cd18d9b9a58431fe65f387a4b8fb4eab3e8dc7a8f2aaf6da45e6?s=96&d=mm&r=g"},"date":"2020-03-01T14:06:06","cld_nonce":"82f011626f","content":{"rendered":"<p>Mir ist schleierhaft, warum Microsoft ein Spiel und dann noch so versteckt in den Edge Chromium einbaut. Ich brauche kein eingebautes Spiel im Edge Browser. Auch die App Spiele unter Windows 10 k\u00f6nnten von mir aus entfernt werden. Das Kartenspiel kann von mir aus drin bleiben. <\/p>\n<p><i>gepostet mit der <a href='https:\/\/play.google.com\/store\/apps\/details?id=com.deskmodder' rel=\"nofollow ugc\">Deskmodder.de-App f\u00fcr Android<\/a><\/i><\/p>\n"},"status":"1"},{"id":128483,"parent":128480,"author":5437,"author_name":"Xeraan","author_email":"thomas.ulloth@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d29f453d27a067cb6fcaf28d43db23cae741e48e8b789758805480812b21cdd9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d29f453d27a067cb6fcaf28d43db23cae741e48e8b789758805480812b21cdd9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d29f453d27a067cb6fcaf28d43db23cae741e48e8b789758805480812b21cdd9?s=96&d=mm&r=g"},"date":"2020-03-01T15:07:13","cld_nonce":"82f011626f","content":{"rendered":"<p>Hmm. Ganz oben steht geschrieben, das das Spiel in den Testversionen enthalten ist. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_razz.gif\" alt=\":-P\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":128484,"parent":128476,"author":5437,"author_name":"Xeraan","author_email":"thomas.ulloth@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d29f453d27a067cb6fcaf28d43db23cae741e48e8b789758805480812b21cdd9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d29f453d27a067cb6fcaf28d43db23cae741e48e8b789758805480812b21cdd9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d29f453d27a067cb6fcaf28d43db23cae741e48e8b789758805480812b21cdd9?s=96&d=mm&r=g"},"date":"2020-03-01T15:09:25","cld_nonce":"82f011626f","content":{"rendered":"<p>Danke f\u00fcr den Tipp mit den Schafen, die sind lustig und sogar Open Source. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":128486,"parent":128476,"author":0,"author_name":"Ingridl","author_email":"Ingrid@attnetwork.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=96&d=mm&r=g"},"date":"2020-03-01T16:27:43","cld_nonce":"82f011626f","content":{"rendered":"<p>F\u00fcr Freunde der Schafe.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=nvVdbdM8C0E\" rel=\"nofollow ugc\">https:\/\/www.youtube.com\/watch?v=nvVdbdM8C0E<\/a><\/p>\n<p><i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":128495,"parent":128476,"author":0,"author_name":"Carsten","author_email":"c.richter@jazzvisions.eu","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=96&d=mm&r=g"},"date":"2020-03-01T23:54:41","cld_nonce":"82f011626f","content":{"rendered":"<p>Auch von mir ein Dankesch\u00f6n f\u00fcr den eSheep-Tipp. Ist ja schon s\u00fc\u00df, das Sch\u00e4fchen.<\/p>\n<p>Besser noch ist das neue gr\u00fcn geh\u00f6rnte Schaf (muss man erst innerhalb der App herunterladen). Das hat dann auch Ton (m\u00e4h) und einige \u00dcberraschungen. Nur so viel, es tauchen manchmal die ber\u00fchmt-ber\u00fcchtigten &#8222;schwarzen Schafe&#8220; auf und sogar auch&#8230; aber nein, das verrate ich doch nicht schon vorab. Und wenn man die Taskleiste transparent eingestellt hat, dann kann man manchmal direkt dahinter die Schatten von den sich anschleichenden schwarzen Schafen sehen, bzw. erahnen (huch). Unserem eigenen Sch\u00e4fchen tun die aber zum Gl\u00fcck nichts, zumindest bisher nicht.  <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/> <\/p>\n<p>Zugriffsrechte hat diese App allerdings auf ALLE Dateien, Peripherieger\u00e4te, Apps und Programme und die Registry (auf die ganze?), was bei mir ein mulmiges Gef\u00fchl hinterl\u00e4sst. Ich meine auf alle Dateien ist schon sehr krass.<\/p>\n"},"status":"1"},{"id":128498,"parent":128495,"author":0,"author_name":"Carsten","author_email":"c.richter@jazzvisions.eu","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=96&d=mm&r=g"},"date":"2020-03-02T01:21:05","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich sehe gerade, eSheep telefoniert nach Hause. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":128504,"parent":128495,"author":0,"author_name":"Ingridl","author_email":"Ingrid@attnetwork.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=96&d=mm&r=g"},"date":"2020-03-02T07:28:14","cld_nonce":"82f011626f","content":{"rendered":"<p>Hast du wirklich geglaubt das es irgendwas umsonst gibt? <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_cry.gif\" alt=\":cry:\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":128506,"parent":128495,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-03-02T07:59:55","cld_nonce":"82f011626f","content":{"rendered":"<p>umsonst ist nur der Tod &#8211; aber auch der kostet etwas, n\u00e4mlich das Leben <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n<p>&#8211; aber das sowas &#8222;eingebautes&#8220; nach Hause telefoniert war doch eigentlich klar &#8211; schrieb ja Carsten schon &#8222;Zugriffsrechte auf ALLE Dateien &#8222;<\/p>\n"},"status":"1"},{"id":128523,"parent":128495,"author":0,"author_name":"Carsten","author_email":"c.richter@jazzvisions.eu","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=96&d=mm&r=g"},"date":"2020-03-02T13:49:23","cld_nonce":"82f011626f","content":{"rendered":"<p>@ Ingridl, @Manny<\/p>\n<p>Also ich habe ja nicht von &#8222;umsonst&#8220; gesprochen und das auch nicht als Bedingung erwartet. Diese Art Apps habe ich seither auch noch nie irgendwo installiert. Herr Hugo&#8217;s Tipp hat mich halt neugierig gemacht. Und selbst moinmoin hat hier ja neulich diese Gans, eine ganz \u00e4hnliche App empfohlen.<\/p>\n<p>Doch es stimmt schon, ich war in diesem Fall trotz meiner Skepsis etwas zu blau\u00e4ugig. Man versucht halt manchmal eben doch an das Gute im Menschen zu glauben. Soll man das g\u00e4nzlich aufgeben?<\/p>\n"},"status":"1"},{"id":128524,"parent":128523,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-03-02T14:27:34","cld_nonce":"82f011626f","content":{"rendered":"<p>Vorgestellt. Empfohlen ist was anderes. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":128525,"parent":128506,"author":0,"author_name":"Ingridl","author_email":"Ingrid@attnetwork.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=96&d=mm&r=g"},"date":"2020-03-02T14:53:21","cld_nonce":"82f011626f","content":{"rendered":"<p>+Bestatter,Friedhof \u26fc,Kr\u00e4nze und Blumen,bei uns der &#8222;Leichenschmaus&#8220; zum Abschluss !<br \/>\nNa dann viel Spa\u00df&#8230;&#8230;warum ging es eigentlich..<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":128526,"parent":128523,"author":0,"author_name":"Ingridl","author_email":"Ingrid@attnetwork.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=96&d=mm&r=g"},"date":"2020-03-02T14:55:41","cld_nonce":"82f011626f","content":{"rendered":"<p>Na ja, der HUGO wars. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_mrgreen.gif\" alt=\":mrgreen:\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":128538,"parent":128523,"author":0,"author_name":"Carsten","author_email":"c.richter@jazzvisions.eu","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=96&d=mm&r=g"},"date":"2020-03-02T18:12:56","cld_nonce":"82f011626f","content":{"rendered":"<p>Der arme, arme Herr Hugo, das hat er wirklich nicht verdient. M\u00e4h.  <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_cry.gif\" alt=\":cry:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":128610,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2020-03-03T21:39:10","cld_nonce":"82f011626f","content":{"rendered":"<p>Herr Hugo wird mit der Last des telefonierenden Schafes leben m\u00fcssen, grins. Wobei mich schon interessieren w\u00fcrde, WAS telefoniert wird <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_confused.gif\" alt=\":???:\" class=\"wp-smiley\" \/> <\/p>\n<p>Aber auch so: ich lasse mir mein Schaf nicht vermiesen. So. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_mrgreen.gif\" alt=\":mrgreen:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":128630,"parent":128610,"author":0,"author_name":"Carsten","author_email":"c.richter@jazzvisions.eu","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=96&d=mm&r=g"},"date":"2020-03-04T05:47:59","cld_nonce":"82f011626f","content":{"rendered":"<p>So ist&#8217;s recht. Schlie\u00dflich bist Du ja auch Individualist. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n<p>Was genau telefoniert wird, kann man ja leider nicht so einfach feststellen. Ich w\u00fcrde ganz einfach die Netzwerkverbindung der App blockieren. Ich glaube, Du nutzt ja den Defender, da kann man das recht einfach in der Firewall konfigurieren. Sollte es aber bei der App Probleme mit dem Blockieren geben, dann nimm die Desktop-Version, da geht es dann auf jeden Fall. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":128659,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2020-03-04T11:23:51","cld_nonce":"82f011626f","content":{"rendered":"<p>Nachklapp: an das Gute im Menschen glaub\u00b4 ich schon lange nicht mehr &#8211; ich glaub\u00b4 halt an das nicht so ganz Schlechte im Schaf. Will hei\u00dfen: ich werde bzgl. des Schafes &#8222;gaanix&#8220; unternehmen.<\/p>\n"},"status":"1"},{"id":128786,"parent":128659,"author":0,"author_name":"Carsten","author_email":"c.richter@jazzvisions.eu","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/62def086192be6c76255e5f9c5156fe2abdd71e6addf01d28307b9e335594165?s=96&d=mm&r=g"},"date":"2020-03-05T19:50:30","cld_nonce":"82f011626f","content":{"rendered":"<p>Gute Vibes verbreiten sich ja bekanntlich (zumindest manchmal). So sage ich jetzt, dass ich an das Gute in Herrn Hugo glaube. Wenn wir nicht dran glauben oder es wenigstens versuchen, wer tut es dann? Jeder einzelne wird gebraucht, um das Leben hier ein wenig besser zu machen, indem man einen positiven Einfluss nimmt. Peace on earth.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Microsoft Edge: Mit einem Geheimcode mit Ninjacat surfen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft Edge: Mit einem Geheimcode mit Ninjacat surfen\" \/>\n<meta property=\"og:description\" content=\"Es ist Wochenende und da passt dann auch ein kleiner Hinweis auf einen versteckten Spiel-Modus im Microsoft Edge in der Canary und Developer Version. Denn man kann auch mit NinjaCat surfen. NinjaCat kennen die Insider ja. Gibt man edge:\/\/surf ein&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-01T08:46:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-01T11:51:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1246\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Microsoft Edge: Mit einem Geheimcode mit Ninjacat surfen\",\"datePublished\":\"2020-03-01T08:46:38+00:00\",\"dateModified\":\"2020-03-01T11:51:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/\"},\"wordCount\":202,\"commentCount\":18,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/microsoft-edge-surf-ninjacat.jpg\",\"keywords\":[\"Konami-Code\",\"Microsoft Edge\",\"NinjaCat\",\"surf\"],\"articleSection\":[\"Browser\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/\",\"name\":\"Microsoft Edge: Mit einem Geheimcode mit Ninjacat surfen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/microsoft-edge-surf-ninjacat.jpg\",\"datePublished\":\"2020-03-01T08:46:38+00:00\",\"dateModified\":\"2020-03-01T11:51:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/microsoft-edge-surf-ninjacat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/microsoft-edge-surf-ninjacat.jpg\",\"width\":1246,\"height\":810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/01\\\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft Edge: Mit einem Geheimcode mit Ninjacat surfen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Microsoft Edge: Mit einem Geheimcode mit Ninjacat surfen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/","og_locale":"de_DE","og_type":"article","og_title":"Microsoft Edge: Mit einem Geheimcode mit Ninjacat surfen","og_description":"Es ist Wochenende und da passt dann auch ein kleiner Hinweis auf einen versteckten Spiel-Modus im Microsoft Edge in der Canary und Developer Version. Denn man kann auch mit NinjaCat surfen. NinjaCat kennen die Insider ja. Gibt man edge:\/\/surf ein&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-03-01T08:46:38+00:00","article_modified_time":"2020-03-01T11:51:07+00:00","og_image":[{"width":1246,"height":810,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Microsoft Edge: Mit einem Geheimcode mit Ninjacat surfen","datePublished":"2020-03-01T08:46:38+00:00","dateModified":"2020-03-01T11:51:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/"},"wordCount":202,"commentCount":18,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat.jpg","keywords":["Konami-Code","Microsoft Edge","NinjaCat","surf"],"articleSection":["Browser"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/","name":"Microsoft Edge: Mit einem Geheimcode mit Ninjacat surfen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat.jpg","datePublished":"2020-03-01T08:46:38+00:00","dateModified":"2020-03-01T11:51:07+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat.jpg","width":1246,"height":810},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/01\/microsoft-edge-mit-einem-geheimcode-mit-ninjacat-surfen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Microsoft Edge: Mit einem Geheimcode mit Ninjacat surfen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/03\/microsoft-edge-surf-ninjacat.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/135069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=135069"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/135069\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/135071"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=135069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=135069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=135069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}