{"id":134564,"date":"2020-03-08T07:35:25","date_gmt":"2020-03-08T06:35:25","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=134564"},"modified":"2020-03-08T07:43:08","modified_gmt":"2020-03-08T06:43:08","slug":"microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/","title":{"rendered":"Microsoft Edge: Erweiterungen aus dem Google Web Store &#8211; Google empfiehlt den Chrome [Update]"},"content":{"rendered":"<p><strong>[Update 08.03.2020]<\/strong> Google hat (scheinbar Kommentarlos) das Popup f\u00fcr den Wechsel zum Chrome im Web Store im Microsoft Edge Browser entfernt. Es wird nun nicht mehr angezeigt.<\/p>\n<p>Wer aber denkt, dass dies auch f\u00fcr <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/02\/24\/google-geht-nun-aggressiver-gegen-microsoft-edge-nutzer-vor\/\" rel=\"noopener noreferrer\" target=\"_blank\">die anderen Dienste<\/a> passiert ist, den muss ich entt\u00e4uschen. Egal ob im Play Store, Google News etc. wird weiterhin flei\u00dfig mit einem Popup  Werbung f\u00fcr den eigenen Browser betrieben. Auch wenn es vielleicht ihr gutes Recht ist, es nervt aber. (<a href=\"https:\/\/techdows.com\/2020\/03\/google-drops-secure-extensions-warning-for-edge.html\" rel=\"noopener noreferrer\" target=\"_blank\">via<\/a>)<\/p>\n<p>[Original 20.02.2020]: Der Microsoft Edge hat Chromium als Untergrund und kann daher auch Google Chrome Erweiterungen laden. Alles kein Problem kennen wir schon. Jetzt \u00e4rgert Google die Edge Nutzer wieder mit einem Banner und macht die Nutzer unsicher.<\/p>\n<p>Auf dem Popup steht: F\u00fcr die sichere Verwendung von Erweiterungen empfiehlt Google den Wechsel zu Chrome. &#8211; Google Chrome herunterladen. Ist ja nicht das erste Mal, dass solche Meldungen irgendwo erscheinen. Denn der Edge hat seinen eigenen &#8222;User Agent String&#8220;.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/edge-erweiterungen-sicherheit.jpg\" rel=\"lightbox[134564]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/edge-erweiterungen-sicherheit-500x338.jpg\" alt=\"\" width=\"500\" height=\"338\" class=\"aligncenter size-medium wp-image-134567\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/edge-erweiterungen-sicherheit-500x338.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/edge-erweiterungen-sicherheit-810x548.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/edge-erweiterungen-sicherheit-303x205.jpg 303w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/edge-erweiterungen-sicherheit.jpg 1104w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Obwohl der Opera oder Vivaldi auch Chromium Browser sind, zeigt Google dort dieses Popup nicht an. Vivaldi selber hat ja schon im Dezember 2019 &#8222;<a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/12\/19\/vivaldi-2-10-mit-besserer-kompatibilitaet-fuer-webseiten-durch-aenderung-des-user-agents\/\" rel=\"noopener noreferrer\" target=\"_blank\">Dampf abgelassen<\/a>&#8220; und den User Agent String auf Chrome umgestellt, damit es keine Probleme gibt. Auch Microsoft hatte schon mal eine \u00c4nderung vorgenommen, die aber scheinbar nichts mehr bewirkt.<\/p>\n<p>Google selber hatte im Januar beschrieben, dass man den User Agent String einfrieren will. Wir hatten <a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/01\/26\/chrome-user-agent-string-wird-eingefroren-und-vereinheitlicht\/\" rel=\"noopener noreferrer\" target=\"_blank\">dar\u00fcber berichtet<\/a>. Aber bis es so weit ist, will man die Redmonder wohl noch \u00e4rgern. Ich k\u00f6nnte mir vorstellen, dass als Entschuldigung von Google kommt <em>&#8222;Das war ein Fehler und keine Absicht&#8220;<\/em>&#8230;..<\/p>\n<p>Logisch an der Sache ist, dass wenn man den User Agent im Edge \u00e4ndert, ist auch das Popup verschwindet. Also lasst euch nicht von dieser Meldung im Web Store von Google beeinflussen und installiert die Erweiterungen in den Edge.<\/p>\n<h3>Alle Microsoft Edge Downloads auch Insider:<\/h3>\n<ul>\n<li><strong>Stable Version:<\/strong> Auswahl alle Versionen <a href=\"https:\/\/www.microsoft.com\/en-us\/edge\" rel=\"noopener noreferrer\" target=\"_blank\">microsoft.com\/edge<\/a> Direkt Windows 10:  <a href=\"https:\/\/go.microsoft.com\/fwlink\/?linkid=2069324&#038;Channel=Stable&#038;language=de\" rel=\"noopener noreferrer\" target=\"_blank\">go.microsoft.com\/Channel=Stable<\/a><\/li>\n<li>Die <strong>portablen Versionen:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/05\/27\/portabler-microsoft-edge-chromium-updater-fuer-canary-developer-beta-und-spaeter-auch-der-finale-edge\/\" target=\"_blank\" rel=\"noopener noreferrer\">Portable Edge Updater<\/a><\/li>\n<li>Offline-Installer Stable Enterprise  <a href=\"http:\/\/go.microsoft.com\/fwlink\/?LinkID=2093437\" rel=\"noopener noreferrer\" target=\"_blank\">X64.msi <\/a>, <a href=\"http:\/\/go.microsoft.com\/fwlink\/?LinkID=2093505\" rel=\"noopener noreferrer\" target=\"_blank\">X86.msi <\/a><\/li>\n<li>Mac Enterprise Stable: <a href=\"http:\/\/go.microsoft.com\/fwlink\/?LinkID=2093438\" rel=\"noopener noreferrer\" target=\"_blank\">macOS.pkg <\/a><\/li>\n<li>Android: <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.microsoft.emmx&#038;hl=de\" rel=\"noopener noreferrer\" target=\"_blank\">play.google.com\/microsoft.emmx<\/a><\/li>\n<li>iOS: <a href=\"https:\/\/apps.apple.com\/de\/app\/microsoft-edge\/id1288723196\" rel=\"noopener noreferrer\" target=\"_blank\">apps.apple.com\/microsoft-edge<\/a><\/li>\n<li><strong>Die weiteren Links f\u00fcr Insider<\/strong><\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/\" target=\"_blank\" rel=\"noopener noreferrer\">win10<\/a>, <a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win8dot1\" target=\"_blank\" rel=\"noopener noreferrer\">win8dot1<\/a>, <a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win8\" target=\"_blank\" rel=\"noopener noreferrer\">platform=win8<\/a>, <a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win7\" target=\"_blank\" rel=\"noopener noreferrer\">platform=win7<\/a><\/li>\n<li>Und f\u00fcr die Macs:<\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=macos\" target=\"_blank\" rel=\"noopener noreferrer\">microsoftedgeinsider.com\/download\/platform=macos<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>[Update 08.03.2020] Google hat (scheinbar Kommentarlos) das Popup f\u00fcr den Wechsel zum Chrome im Web Store im Microsoft Edge Browser entfernt. Es wird nun nicht mehr angezeigt. Wer aber denkt, dass dies auch f\u00fcr die anderen Dienste passiert ist, den&hellip; <\/p>\n","protected":false},"author":134,"featured_media":129486,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166],"tags":[69624,69625,8501],"class_list":["post-134564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-browser","tag-chrome-web-store","tag-meldung-sicherheit","tag-microsoft-edge"],"wp_featured_image":{"id":129486,"alt_text":"","description":"","media_type":"image","media_details":{"width":744,"height":499,"file":"2019\/11\/microsoft-edge-logo-2019.png","sizes":{"thumbnail":{"file":"microsoft-edge-logo-2019-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-306x205.png"},"medium":{"file":"microsoft-edge-logo-2019-500x335.png","width":500,"height":335,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-500x335.png"},"wp_review_large":{"file":"microsoft-edge-logo-2019-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-320x200.png"},"wp_review_small":{"file":"microsoft-edge-logo-2019-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-65x65.png"},"blog-large":{"file":"microsoft-edge-logo-2019-642x300.png","width":642,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-642x300.png"},"blog-medium":{"file":"microsoft-edge-logo-2019-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-306x205.png"},"recent-thumb":{"file":"microsoft-edge-logo-2019-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-350x316.png"},"service-featured":{"file":"microsoft-edge-logo-2019-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-600x330.png"},"wp_rp_thumbnail":{"file":"microsoft-edge-logo-2019-50x50.png","width":50,"height":50,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019-50x50.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":129484,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png"},"commentcount":26,"wp_comments":[{"id":127573,"parent":0,"author":3899,"author_name":"Andre45","author_email":"cloudstrife97@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3ad52e495196ca15817024481e3a5517674dbebf9e2a65bf8b178bb2afd69d76?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3ad52e495196ca15817024481e3a5517674dbebf9e2a65bf8b178bb2afd69d76?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3ad52e495196ca15817024481e3a5517674dbebf9e2a65bf8b178bb2afd69d76?s=96&d=mm&r=g"},"date":"2020-02-20T09:52:39","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich glaube da hat jemand Angst, dass der Edge beliebter als Chrome werden k\u00f6nnte. Ich glaube Google sollte mal damit klarkommen, dass man nicht f\u00fcr immer und ewig die Nummer 1 bleiben kann, irgendwann kommt immer jemand anderes. Zumal dieser Move von denen mittlerweile Alt und nicht Erwachsen ist, wie ein Kind was versucht auf sich aufmerksam zu machen, mehr ist dass f\u00fcr mich nicht.<\/p>\n"},"status":"1"},{"id":127574,"parent":0,"author":0,"author_name":"MANU","author_email":"manu.beitz@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e5a3af9fe1a43fc59046946ea6fe036f1aa0fe7de4405255d37420456b002327?s=96&d=mm&r=g"},"date":"2020-02-20T09:56:31","cld_nonce":"82f011626f","content":{"rendered":"<p>Lasst doch Google Chrome den Spass!<\/p>\n<p>Da steht der  Microsoft Edge-ler doch dr\u00fcber!<\/p>\n"},"status":"1"},{"id":127575,"parent":0,"author":0,"author_name":"aerf","author_email":"awevf@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f470dac5f9e70a3be091540b0af3527742ff7625fcb7d45a1e20a0d1d51f56bd?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f470dac5f9e70a3be091540b0af3527742ff7625fcb7d45a1e20a0d1d51f56bd?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f470dac5f9e70a3be091540b0af3527742ff7625fcb7d45a1e20a0d1d51f56bd?s=96&d=mm&r=g"},"date":"2020-02-20T10:10:26","cld_nonce":"82f011626f","content":{"rendered":"<p>Google empfiehlt den Chrome&#8230;&#8230;&#8230;..ja ne is klar&#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":127580,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2020-02-20T10:40:33","cld_nonce":"82f011626f","content":{"rendered":"<p>Google empfiehlt Chrome? Den eigenen Browser? UNerh\u00f6rt &#8211; Microsoft w\u00fcrde sowas NIEmals tun. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_mrgreen.gif\" alt=\":mrgreen:\" class=\"wp-smiley\" \/><\/p>\n<p>Au\u00dfer beim Edge nat\u00fcrlich, und One Drive, und dem MS-Account, und der Foto App, und&#8230; denn es gilt auch hier die Unschuldsvermutung und: &#8222;Ausnahmen best\u00e4tigen die Regel.&#8220; <\/p>\n<p>PS: Chrome mag iwann nicht mehr die Nr. 1 bei Browsern sein &#8211; aber der Edge auch nicht&#8230;<\/p>\n"},"status":"1"},{"id":127581,"parent":0,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-02-20T10:41:52","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich meide die  Google Chrome Erweiterungen wie der Teufel das Weihwasser, bin aber der Meinung Eigenwerbung sollte immer m\u00f6glich sein. Ich erinnere mich noch daran, das Microsoft dazu gedr\u00e4ngt wurde eine &#8222;Browserwahl&#8220; auf dem Desktop zu schmei\u00dfen, was in meinen Augen verwerflicher ist. Wenn ich mich richtig erinnere war es damals Mozilla, die das gefordert hatten.<\/p>\n"},"status":"1"},{"id":127582,"parent":127581,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-02-20T10:46:04","cld_nonce":"82f011626f","content":{"rendered":"<p>Nichts gegen Eigenwerbung. Aber mit dem Satz &#8222;F\u00fcr die sichere Verwendung von Erweiterungen&#8230;&#8220; ist etwas dreist gegen\u00fcber Nutzern, die wenig Ahnung von der Materie haben.<\/p>\n"},"status":"1"},{"id":127583,"parent":127582,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-02-20T10:54:51","cld_nonce":"82f011626f","content":{"rendered":"<p>Dem stimme ich zu.<\/p>\n"},"status":"1"},{"id":127601,"parent":0,"author":0,"author_name":"Eisenvater","author_email":"rolle.andre@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/165fe2c09ed4e271f0372a64ff5bc9bdfc8c027bc4f6be36eb601cad0eac35f9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/165fe2c09ed4e271f0372a64ff5bc9bdfc8c027bc4f6be36eb601cad0eac35f9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/165fe2c09ed4e271f0372a64ff5bc9bdfc8c027bc4f6be36eb601cad0eac35f9?s=96&d=mm&r=g"},"date":"2020-02-20T13:13:24","cld_nonce":"82f011626f","content":{"rendered":"<p>Beim Brave werden auch keine Warnungen angezeigt.<\/p>\n<p>Mich w\u00fcrde ja mal interessieren wie Microsoft das mit der &#8222;webRequest API&#8220; handhabt.<br \/>\nBrave pflegt die Schnittstelle ja weiter. Bez\u00fcglich des Edge Chrome finde ich nichts dazu.<\/p>\n"},"status":"1"},{"id":127602,"parent":127601,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-02-20T13:17:50","cld_nonce":"82f011626f","content":{"rendered":"<p>Bislang hat MS dazu nichts gesagt. Aber rund um das Thema ist es in letzter Zeit sehr ruhig geworden.<br \/>\nIch sch\u00e4tze mal, die warten alle noch ab.<\/p>\n"},"status":"1"},{"id":127606,"parent":127602,"author":3888,"author_name":"Holunder1957","author_email":"ahrensdetlef@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/775c35869d509bf7b59e377f93ef7c9d230f7fc6471d4cf864dc077823a02246?s=96&d=mm&r=g"},"date":"2020-02-20T13:38:27","cld_nonce":"82f011626f","content":{"rendered":"<p>F\u00fcr mich hat es den Anschein, dass Google und Microsoft schon seit ein Paar Jahren das Kriegsbeil begraben haben. Sp\u00e4testens, seit es von Google keine Meldungen \u00fcber Schwachstellen in Windows mehr gibt.<\/p>\n"},"status":"1"},{"id":127617,"parent":0,"author":0,"author_name":"Thomas H\u00f6llriegl","author_email":"thomas.hoellriegl.at@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5cbba9d58f33b4a083376884546c28a3146a607ce6e2dda065e8f9d8b0b27167?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5cbba9d58f33b4a083376884546c28a3146a607ce6e2dda065e8f9d8b0b27167?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5cbba9d58f33b4a083376884546c28a3146a607ce6e2dda065e8f9d8b0b27167?s=96&d=mm&r=g"},"date":"2020-02-20T14:35:02","cld_nonce":"82f011626f","content":{"rendered":"<p>W\u00fcrde ich auch empfehlen. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":127634,"parent":0,"author":0,"author_name":"Tobias R.","author_email":"jetebo8167@jetsmails.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/429a56ea95125a0f777c7c426a5cf04ab554a499e80eb25ced2f4ecc531832ac?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/429a56ea95125a0f777c7c426a5cf04ab554a499e80eb25ced2f4ecc531832ac?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/429a56ea95125a0f777c7c426a5cf04ab554a499e80eb25ced2f4ecc531832ac?s=96&d=mm&r=g"},"date":"2020-02-20T15:58:51","cld_nonce":"82f011626f","content":{"rendered":"<p>Habe bei Edge Canary den User String eingefroren.Hat aber noch nichts gebracht.<\/p>\n"},"status":"1"},{"id":127743,"parent":127634,"author":0,"author_name":"ordner","author_email":"123@123.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/070011335df9d7ba4cd2f1fa1e2eddede325356b4bbe45879c5e8de8c99d3101?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/070011335df9d7ba4cd2f1fa1e2eddede325356b4bbe45879c5e8de8c99d3101?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/070011335df9d7ba4cd2f1fa1e2eddede325356b4bbe45879c5e8de8c99d3101?s=96&d=mm&r=g"},"date":"2020-02-21T13:20:46","cld_nonce":"82f011626f","content":{"rendered":"<p>modfity header plugin laden:<br \/>\nfolgendes eintragen:<br \/>\nUser-Agent -&gt;Googlebot\/2.1 (+http:\/\/www.google.com\/bot.html)<br \/>\nServer -&gt; Linux-IIS\/6.0<br \/>\nAccept -&gt; text\/html,application\/xhtml+xml,application\/xml;q=0.9,image\/webp,image\/apng,*\/*;q=0.8,application\/signed-exchange;v=b3<br \/>\nAccept Encoding -&gt; gzip, deflate<br \/>\nHTTP-Protocol -&gt; HTTP\/1.1<br \/>\nXServer -&gt; smc-web-02<br \/>\nX-UIDH -&gt; user42178<\/p>\n"},"status":"1"},{"id":127799,"parent":127743,"author":0,"author_name":"Tobias R.","author_email":"sohig94024@jszmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a2653d268d04cfcf0b68624b0210da1ab8a66dabefee620d4d4bb7a6d379373f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a2653d268d04cfcf0b68624b0210da1ab8a66dabefee620d4d4bb7a6d379373f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a2653d268d04cfcf0b68624b0210da1ab8a66dabefee620d4d4bb7a6d379373f?s=96&d=mm&r=g"},"date":"2020-02-21T21:23:13","cld_nonce":"82f011626f","content":{"rendered":"<p>habe mir das plugin heruntergeladen aber kein plan wo ich was eintragen soll<\/p>\n"},"status":"1"},{"id":127813,"parent":0,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-02-22T05:10:12","cld_nonce":"82f011626f","content":{"rendered":"<p>Also DEN Link muss man sich unbedingt merken bzw. das Datum im Kalender rot anstreichen:<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/2020\/02\/20\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/#comment-127743\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2020\/02\/20\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/#comment-127743<\/a><\/p>\n<p>ich seh da nix von Spionage \/ Malware Telemetrie  etc.  etc <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_surprised.gif\" alt=\":o\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":127815,"parent":127580,"author":4179,"author_name":"reschef","author_email":"illusion80.gofk@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e493e7761cd9eb29bb162d42ef36b1040df41ee632453c679176af6b0ff8ef4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e493e7761cd9eb29bb162d42ef36b1040df41ee632453c679176af6b0ff8ef4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e493e7761cd9eb29bb162d42ef36b1040df41ee632453c679176af6b0ff8ef4?s=96&d=mm&r=g"},"date":"2020-02-22T05:21:30","cld_nonce":"82f011626f","content":{"rendered":"<p>Dein PS-Inhalt ist falsch. Nutzer der unerfahrenen und\/oder \u00e4lteren Generation nutzen immer den Browser, der schon da ist, wenn er gut funktioniert. Das w\u00e4re dann also in naher Zukunft sicherlich der Edge. Nicht ohne Grund war damals der IE der meist genutzte Browser.<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":127816,"parent":127606,"author":4179,"author_name":"reschef","author_email":"illusion80.gofk@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e493e7761cd9eb29bb162d42ef36b1040df41ee632453c679176af6b0ff8ef4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e493e7761cd9eb29bb162d42ef36b1040df41ee632453c679176af6b0ff8ef4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e493e7761cd9eb29bb162d42ef36b1040df41ee632453c679176af6b0ff8ef4?s=96&d=mm&r=g"},"date":"2020-02-22T05:25:13","cld_nonce":"82f011626f","content":{"rendered":"<p>Richtig, weil Google ja schon seit so vielen Jahren keine Schwachstellen mehr heraus gibt <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\":wink:\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":128972,"parent":0,"author":0,"author_name":"Micha","author_email":"m.b.1991@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=96&d=mm&r=g"},"date":"2020-03-08T14:47:34","cld_nonce":"82f011626f","content":{"rendered":"<p>Meine Meinung dazu: Ja Plugins k\u00f6nnen gef\u00e4hrlich sein aber a) dann f\u00fcr alle chromium Browser und b) liegt das Problem bei der unzureichenden Pr\u00fcfung wie auch bei Android Apps. Der Gro\u00dfteil der Apps im Play Store sind Schrott weil sie entweder zu Fehlern f\u00fchren, andere Apps nur kopieren oder einfach unn\u00f6tig sind. Wenn man den Schrott aus dem Play Store entfernt hat man das gleiche Problem wie im Microsoft Store &#8211; Es gibt zu wenig Apps. Ich werde auf IOS wechseln weil Android mir noch nie gefallen hat und ich schon oft genug Apps hatte die zu Problemen gef\u00fchrt haben oder einfach Schrott waren. Nat\u00fcrlich wei\u00df ich nicht wie es bei IOS ist bin aber guter Dinge, sobald mein Ger\u00e4t geliefert wird werde ich es ja sehen. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":128981,"parent":0,"author":0,"author_name":"Hugo","author_email":"hugo@hugo.at","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9bbd764a989e3557f98dd1944f256dfff18ce347852cd77cfe4edebdb9ab0c68?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9bbd764a989e3557f98dd1944f256dfff18ce347852cd77cfe4edebdb9ab0c68?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9bbd764a989e3557f98dd1944f256dfff18ce347852cd77cfe4edebdb9ab0c68?s=96&d=mm&r=g"},"date":"2020-03-08T18:54:10","cld_nonce":"82f011626f","content":{"rendered":"<p>Wie von einem Kind geschrieben. Den Chrome? Einfach nur Chrome gen\u00fcgt auch. Den Opera&#8230; usw&#8230;<\/p>\n<p>Also lasst euch nicht von dieser Meldung im Web Store von Google beeinflussen und installiert die Erweiterungen in den Edge.<\/p>\n<p>Auch eher ungeschickt formuliert.<\/p>\n"},"status":"1"},{"id":128984,"parent":0,"author":2074,"author_name":"Thors","author_email":"dkb210@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3a943ac2784cca5e9a86278089ca03844a04cab358a5ba6c98ca9f521a944bdd?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3a943ac2784cca5e9a86278089ca03844a04cab358a5ba6c98ca9f521a944bdd?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3a943ac2784cca5e9a86278089ca03844a04cab358a5ba6c98ca9f521a944bdd?s=96&d=mm&r=g"},"date":"2020-03-08T20:32:44","cld_nonce":"82f011626f","content":{"rendered":"<p>Geh\u00f6rt vielleicht nicht hier rein. Wie kann ich den Browser dazu bringen das Videos nicht automatisch abspielen? Danke!<\/p>\n"},"status":"1"},{"id":128986,"parent":128984,"author":0,"author_name":"Micha","author_email":"m.b.1991@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=96&d=mm&r=g"},"date":"2020-03-08T23:00:19","cld_nonce":"82f011626f","content":{"rendered":"<p>Einen Browser verwenden der diese Einstellung standardm\u00e4\u00dfig bietet? <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":-D\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":128988,"parent":128984,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-03-08T23:57:42","cld_nonce":"82f011626f","content":{"rendered":"<p>z.B:<br \/>\n<a href=\"edge:\/\/settings\/content\/mediaAutoplay\" rel=\"ugc\">edge:\/\/settings\/content\/mediaAutoplay<\/a> ?<\/p>\n"},"status":"1"},{"id":128990,"parent":0,"author":5902,"author_name":"Neutronenstern","author_email":"a-l-i-a-s_hauptadresse@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8c25b09a32824c05155884fe1abbca079f9e599f7086b85345259e472dc58368?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8c25b09a32824c05155884fe1abbca079f9e599f7086b85345259e472dc58368?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8c25b09a32824c05155884fe1abbca079f9e599f7086b85345259e472dc58368?s=96&d=mm&r=g"},"date":"2020-03-09T01:26:44","cld_nonce":"82f011626f","content":{"rendered":"<p>&#8222;F\u00fcr die sichere Verwendung von Erweiterungen empfiehlt Google den Wechsel zu Chrome.&#8220;<\/p>\n<p>Das muss ein Witz sein, denn beweisen k\u00f6nnen die das garantiert nicht, ne ich revidiere, das ist eindeutige verarsche.<br \/>\nDenen f\u00e4llt es sicher nicht mal auf, aber damit reden sie ihren Google Store indirekt schlecht, sie sagen das sie jeden Schrott darauf lassen und erst der Browser soll es sicher machen (Grins).<br \/>\nGoogle und Sicherheit in Verbindung zu bringen ist doch h\u00f6hnisch und l\u00e4cherlich, Android und Chrome sind bei dem Thema doch zum Fremdschemen, Google f\u00fchrt die Liste der L\u00fccken doch an:<br \/>\n<a href=\"https:\/\/www.cvedetails.com\/top-50-products.php?year=2019\" rel=\"nofollow ugc\">https:\/\/www.cvedetails.com\/top-50-products.php?year=2019<\/a><br \/>\nPunkto Datenschutz muss man denke ich erst gar nicht anfangen, die klauen und verkaufen doch mehr Daten als Gesichtsbuch und Co zusammen.<\/p>\n"},"status":"1"},{"id":129001,"parent":128990,"author":0,"author_name":"Micha","author_email":"m.b.1991@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=96&d=mm&r=g"},"date":"2020-03-09T10:39:31","cld_nonce":"82f011626f","content":{"rendered":"<p>Weiter oben habe ich das bereits in einer Form angesprochen, aber sch\u00f6n das ich nicht der Einzige bin der sich nicht blenden l\u00e4sst.<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":129003,"parent":128988,"author":2074,"author_name":"Thors","author_email":"dkb210@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3a943ac2784cca5e9a86278089ca03844a04cab358a5ba6c98ca9f521a944bdd?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3a943ac2784cca5e9a86278089ca03844a04cab358a5ba6c98ca9f521a944bdd?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3a943ac2784cca5e9a86278089ca03844a04cab358a5ba6c98ca9f521a944bdd?s=96&d=mm&r=g"},"date":"2020-03-09T10:45:10","cld_nonce":"82f011626f","content":{"rendered":"<p>Danke , ganz abschalten kann man es scheinbar nicht, sondern nur einschr\u00e4nken<\/p>\n"},"status":"1"},{"id":129004,"parent":128988,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-03-09T10:56:29","cld_nonce":"82f011626f","content":{"rendered":"<p>ja stimmt, aber f\u00fcr einige Sachen \/ Seiten reicht es &#8211; ging mir auch immer auf den S&#8230;. &#8211; alternativ wie ich damit verfahre, solchen Seiten gar nicht mehr benutzen die die User mit wer wei\u00df was f\u00fcr einen Sch&#8230;. &#8222;zudr\u00f6hnen&#8220;<br \/>\n( will jetzt keine Namen nennen aber am besten direkt auf Blockliste so Seiten)<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Microsoft Edge: Erweiterungen aus dem Google Web Store - Google empfiehlt den Chrome [Update] - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft Edge: Erweiterungen aus dem Google Web Store - Google empfiehlt den Chrome [Update]\" \/>\n<meta property=\"og:description\" content=\"[Update 08.03.2020] Google hat (scheinbar Kommentarlos) das Popup f\u00fcr den Wechsel zum Chrome im Web Store im Microsoft Edge Browser entfernt. Es wird nun nicht mehr angezeigt. Wer aber denkt, dass dies auch f\u00fcr die anderen Dienste passiert ist, den&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-08T06:35:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-08T06:43:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png\" \/>\n\t<meta property=\"og:image:width\" content=\"744\" \/>\n\t<meta property=\"og:image:height\" content=\"499\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Microsoft Edge: Erweiterungen aus dem Google Web Store &#8211; Google empfiehlt den Chrome [Update]\",\"datePublished\":\"2020-03-08T06:35:25+00:00\",\"dateModified\":\"2020-03-08T06:43:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/\"},\"wordCount\":385,\"commentCount\":26,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/microsoft-edge-logo-2019.png\",\"keywords\":[\"Chrome Web Store\",\"Meldung Sicherheit\",\"Microsoft Edge\"],\"articleSection\":[\"Browser\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/\",\"name\":\"Microsoft Edge: Erweiterungen aus dem Google Web Store - Google empfiehlt den Chrome [Update] - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/microsoft-edge-logo-2019.png\",\"datePublished\":\"2020-03-08T06:35:25+00:00\",\"dateModified\":\"2020-03-08T06:43:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/microsoft-edge-logo-2019.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/microsoft-edge-logo-2019.png\",\"width\":744,\"height\":499},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/03\\\/08\\\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft Edge: Erweiterungen aus dem Google Web Store &#8211; Google empfiehlt den Chrome [Update]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Microsoft Edge: Erweiterungen aus dem Google Web Store - Google empfiehlt den Chrome [Update] - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/","og_locale":"de_DE","og_type":"article","og_title":"Microsoft Edge: Erweiterungen aus dem Google Web Store - Google empfiehlt den Chrome [Update]","og_description":"[Update 08.03.2020] Google hat (scheinbar Kommentarlos) das Popup f\u00fcr den Wechsel zum Chrome im Web Store im Microsoft Edge Browser entfernt. Es wird nun nicht mehr angezeigt. Wer aber denkt, dass dies auch f\u00fcr die anderen Dienste passiert ist, den&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-03-08T06:35:25+00:00","article_modified_time":"2020-03-08T06:43:08+00:00","og_image":[{"width":744,"height":499,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Microsoft Edge: Erweiterungen aus dem Google Web Store &#8211; Google empfiehlt den Chrome [Update]","datePublished":"2020-03-08T06:35:25+00:00","dateModified":"2020-03-08T06:43:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/"},"wordCount":385,"commentCount":26,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png","keywords":["Chrome Web Store","Meldung Sicherheit","Microsoft Edge"],"articleSection":["Browser"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/","name":"Microsoft Edge: Erweiterungen aus dem Google Web Store - Google empfiehlt den Chrome [Update] - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png","datePublished":"2020-03-08T06:35:25+00:00","dateModified":"2020-03-08T06:43:08+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png","width":744,"height":499},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/03\/08\/microsoft-edge-erweiterungen-aus-dem-google-web-store-google-empfiehlt-den-chrome\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Microsoft Edge: Erweiterungen aus dem Google Web Store &#8211; Google empfiehlt den Chrome [Update]"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-logo-2019.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/134564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=134564"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/134564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/129486"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=134564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=134564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=134564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}