{"id":134111,"date":"2020-02-10T13:32:19","date_gmt":"2020-02-10T12:32:19","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=134111"},"modified":"2020-02-10T15:14:13","modified_gmt":"2020-02-10T14:14:13","slug":"windows-12-lite-wie-man-windows-nutzer-linux-erklaert","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/","title":{"rendered":"Windows 12 Lite &#8211; Wie man Windows-Nutzern Linux erkl\u00e4rt"},"content":{"rendered":"<p>Auf einer lokalen Messe hat hexsayeed eine Windows 12 Lite Installations-DVD und eine Beschreibung dazu gesehen und musste laut lachen. Auch ich musste schmunzeln. Aber die Idee dahinter ist gar nicht mal so schlecht.<\/p>\n<p>Denn man hat hier nichts weiter als ein Linux-System in Windows verpackt. Das Linux Lite OS &#8222;Lite 4.8 LTS&#8220;. Auf der <a href=\"https:\/\/webhouses.co.uk\/lite\/\" rel=\"noopener noreferrer\" target=\"_blank\">Webseite<\/a> selber wird es dann in der \u00dcberschrift so beschrieben: &#8222;Installing Windows 12 Lite 4.8 and Creating Windows 12&#8220;. Auch wird dort in einfachen Schritten gezeigt, wie man das Linux OS installieren und eben wie Windows aussehen lassen kann.<\/p>\n<figure id=\"attachment_134113\" aria-describedby=\"caption-attachment-134113\" style=\"width: 270px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite.jpg\" rel=\"lightbox[134111]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-270x360.jpg\" alt=\"\" width=\"270\" height=\"360\" class=\"size-medium wp-image-134113\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-270x360.jpg 270w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-437x583.jpg 437w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-154x205.jpg 154w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite.jpg 1037w\" sizes=\"auto, (max-width: 270px) 100vw, 270px\" \/><\/a><figcaption id=\"caption-attachment-134113\" class=\"wp-caption-text\">Quelle: hexsayeed<br \/><\/figcaption><\/figure>\n<p>Einfach zu sagen: &#8222;Steig doch auf Linux um, wenn du Windows 10 nicht magst&#8220;, schreckt viele ab. Es aber als Windows 12 zu bezeichnen und dann auch mit Bildern zu untermalen wird mit Sicherheit mehr Neugierde auf sich ziehen. Eine lustige Sache finde ich, die ich euch nicht vorenthalten wollte.<\/p>\n<p>Falls die Redmonder es mitbekommen, wird die Seite sicherlich \u00c4rger bekommen. Denn Windows ist ein gesch\u00fctzter Name. Aber f\u00fcr den Moment haben wir was zum Schmunzeln.<\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/www.reddit.com\/r\/Windows10\/comments\/f1ame1\/saw_this_at_a_local_computer_fair_and_couldnt\/\" rel=\"noopener noreferrer\" target=\"_blank\">reddit<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Auf einer lokalen Messe hat hexsayeed eine Windows 12 Lite Installations-DVD und eine Beschreibung dazu gesehen und musste laut lachen. Auch ich musste schmunzeln. Aber die Idee dahinter ist gar nicht mal so schlecht. Denn man hat hier nichts weiter&hellip; <\/p>\n","protected":false},"author":134,"featured_media":134114,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[60884],"tags":[69148,69147],"class_list":["post-134111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internet","tag-lite-4-8-lts","tag-windows-12-lite"],"wp_featured_image":{"id":134114,"alt_text":"","description":"","media_type":"image","media_details":{"width":1037,"height":595,"file":"2020\/02\/windows-12-lite-preview.jpg","sizes":{"medium":{"file":"windows-12-lite-preview-500x287.jpg","width":500,"height":287,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview-500x287.jpg"},"large":{"file":"windows-12-lite-preview-810x465.jpg","width":810,"height":465,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview-810x465.jpg"},"thumbnail":{"file":"windows-12-lite-preview-306x176.jpg","width":306,"height":176,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview-306x176.jpg"},"wp_review_large":{"file":"windows-12-lite-preview-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview-320x200.jpg"},"wp_review_small":{"file":"windows-12-lite-preview-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview-65x65.jpg"},"blog-large":{"file":"windows-12-lite-preview-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview-642x300.jpg"},"blog-medium":{"file":"windows-12-lite-preview-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview-306x205.jpg"},"recent-thumb":{"file":"windows-12-lite-preview-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview-350x316.jpg"},"service-featured":{"file":"windows-12-lite-preview-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview-600x330.jpg"},"wp_rp_thumbnail":{"file":"windows-12-lite-preview-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":134111,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview.jpg"},"commentcount":27,"wp_comments":[{"id":126738,"parent":0,"author":0,"author_name":"Rush","author_email":"djmajorrush@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=96&d=mm&r=g"},"date":"2020-02-10T14:05:47","cld_nonce":"82f011626f","content":{"rendered":"<p>und wo kann man das downloaden <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/> ?<\/p>\n"},"status":"1"},{"id":126739,"parent":126738,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-02-10T14:12:18","cld_nonce":"82f011626f","content":{"rendered":"<p><a href=\"https:\/\/www.linuxliteos.com\/forums\/release-announcements\/linux-lite-4-8-final-released\" rel=\"nofollow ugc\">https:\/\/www.linuxliteos.com\/forums\/release-announcements\/linux-lite-4-8-final-released<\/a><\/p>\n<p>Ob das nun die LTS ist, keine Ahnung.<\/p>\n"},"status":"1"},{"id":126740,"parent":0,"author":3679,"author_name":"blackTears","author_email":"maikrosoft@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/64277d4947658dc236c5dd267f036084d4eb6174978ae74785d32ce4d40aba33?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/64277d4947658dc236c5dd267f036084d4eb6174978ae74785d32ce4d40aba33?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/64277d4947658dc236c5dd267f036084d4eb6174978ae74785d32ce4d40aba33?s=96&d=mm&r=g"},"date":"2020-02-10T14:12:28","cld_nonce":"82f011626f","content":{"rendered":"<p>Keine Viren oder Ransomware, v\u00f6lliger Bl\u00f6dsinn.<br \/>\nEs gibt auch f\u00fcr Linux Viren, aber da es ein Frickel-OS mit unbedeutender Verbreitung auf Desktoprechnern ist, bekommt man davon nicht viel mit.<\/p>\n"},"status":"1"},{"id":126741,"parent":0,"author":0,"author_name":"Wolfgang D.","author_email":"wolfgang362@habmalnefrage.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=96&d=mm&r=g"},"date":"2020-02-10T14:12:36","cld_nonce":"82f011626f","content":{"rendered":"<p>Das wird f\u00fcr den Anbieter wegen des gesch\u00fctzten Namens eventuell ein teurer Spa\u00df. <\/p>\n<p>Und der tats\u00e4chlich unbedarfte Nutzer wird sp\u00e4testens beim Installationsversuch von seiner Outlook (Office HuP)2016 DVD den Unsinn in die Ecke werfen. Oder wenn er seine Tomtom App (oder bezahlte andere Anwendungen wie Lexware, Finanzverwaltung, Steuererkl\u00e4rung, VTech, usw.) wieder nutzen m\u00f6chte.<\/p>\n<p>Linux ist nicht die L\u00f6sung f\u00fcr alle Probleme, aber dieses &#8222;W12Lite&#8220; ein netter Spa\u00df.<\/p>\n"},"status":"1"},{"id":126744,"parent":126740,"author":0,"author_name":"Wolfgang D.","author_email":"wolfgang362@habmalnefrage.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=96&d=mm&r=g"},"date":"2020-02-10T14:22:53","cld_nonce":"82f011626f","content":{"rendered":"<p>@blackTears<br \/>\nIch w\u00e4re ja \u00fcber ein funktionierendes Drag and Drop bei manchen Distris ja schon gl\u00fccklich, scheint aber nicht so einfach zu sein, das Ziehen einer URL aus dem Browser als Verkn\u00fcpfung auf den Desktop umzusetzen. <\/p>\n<p>Je nach Browser und DesktopEnvironment klappt es, oder auch nicht. Da hat Microsoft mit seiner Chim\u00e4re als Symbol leider recht, kaum was passt sauber zusammen. Obwohl bei W10 Copy und Paste ebenfalls schon l\u00e4nger eine Baustelle ist.<\/p>\n"},"status":"1"},{"id":126745,"parent":0,"author":0,"author_name":"Skylla","author_email":"skyllaandcharybdis@vivaldi.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/2d21dd4fd9235fdf46ae6743e1b2375644b6ba9541784cb27b1c2f4ec70867a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/2d21dd4fd9235fdf46ae6743e1b2375644b6ba9541784cb27b1c2f4ec70867a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/2d21dd4fd9235fdf46ae6743e1b2375644b6ba9541784cb27b1c2f4ec70867a3?s=96&d=mm&r=g"},"date":"2020-02-10T14:25:32","cld_nonce":"82f011626f","content":{"rendered":"<blockquote><p>Einfach zu sagen: \u201eSteig doch auf Linux um, wenn du Windows 10 nicht magst\u201c, schreckt viele ab. <\/p><\/blockquote>\n<p>Abschreckend ist die Lizenzpolitik von Microsoft, das Abgreifen\/Cloudhosting von Nutzerdaten,<br \/>\nOffice 365 mit Zwangsabo, das nur mit Serveranbindung l\u00e4uft, und auch schon mal streikt wenn die Lizenzserver down sind. <\/p>\n<p>Wer Microsoft finaziell unterst\u00fctzen will, so das weiterhin tun, bis Windows und dessen Apps dauerhaft ein Abomodell werden.<\/p>\n"},"status":"1"},{"id":126747,"parent":0,"author":0,"author_name":"Skylla","author_email":"SkyllaAndCharybdis@vivaldi.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/2d21dd4fd9235fdf46ae6743e1b2375644b6ba9541784cb27b1c2f4ec70867a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/2d21dd4fd9235fdf46ae6743e1b2375644b6ba9541784cb27b1c2f4ec70867a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/2d21dd4fd9235fdf46ae6743e1b2375644b6ba9541784cb27b1c2f4ec70867a3?s=96&d=mm&r=g"},"date":"2020-02-10T14:31:21","cld_nonce":"82f011626f","content":{"rendered":"<p>Wer nun noch auf so einem Linux Wine (PlayOnLinux) braucht, ist ein armer User, der besser bei Windows 7 geblieben w\u00e4re.<\/p>\n<p>Ansonsten halte ich dieses WinLite f\u00fcr einen Murks. Eine weitere von zig DIstributionen im Wirrwar der Linuxe.<\/p>\n"},"status":"1"},{"id":126748,"parent":0,"author":4813,"author_name":"Nikolaus","author_email":"manfred.hamernik@gmx.at","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/21b46c4f7e47ff6bb28b51f3310a50ac0e9f8d0c05b986d3bec6f6cf90a0540c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/21b46c4f7e47ff6bb28b51f3310a50ac0e9f8d0c05b986d3bec6f6cf90a0540c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/21b46c4f7e47ff6bb28b51f3310a50ac0e9f8d0c05b986d3bec6f6cf90a0540c?s=96&d=mm&r=g"},"date":"2020-02-10T14:37:52","cld_nonce":"82f011626f","content":{"rendered":"<p>Windows 12 also, im Normalfall w\u00fcrde ich so eine CD\/DVD noch nicht mal mit der Kneifzange anfassen, da ich davon ausgehe dass diese Scheiben ein Tummelplatz von Viren, W\u00fcrmern, Spyware und Malware sind.<\/p>\n"},"status":"1"},{"id":126750,"parent":126739,"author":0,"author_name":"Rush","author_email":"djmajorrush@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=96&d=mm&r=g"},"date":"2020-02-10T14:58:18","cld_nonce":"82f011626f","content":{"rendered":"<p>super danke <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":126751,"parent":0,"author":0,"author_name":"Rush","author_email":"djmajorrush@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=96&d=mm&r=g"},"date":"2020-02-10T15:00:45","cld_nonce":"82f011626f","content":{"rendered":"<p>ich habe sonst immer &#8230;<\/p>\n<p>&#8212; &gt; <a href=\"https:\/\/xpq4.sourceforge.io\/\" rel=\"nofollow ugc\">https:\/\/xpq4.sourceforge.io\/<\/a><br \/>\nund<br \/>\n&#8212; &gt; <a href=\"https:\/\/q4os.org\/index.html\" rel=\"nofollow ugc\">https:\/\/q4os.org\/index.html<\/a><\/p>\n<p>genutzt <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":126782,"parent":0,"author":0,"author_name":"Absynth","author_email":"absynth@0box.eu","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b52ca3453907f4078f59814f610e5f0703b7d2f9011f5fbba48114f2b874d776?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b52ca3453907f4078f59814f610e5f0703b7d2f9011f5fbba48114f2b874d776?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b52ca3453907f4078f59814f610e5f0703b7d2f9011f5fbba48114f2b874d776?s=96&d=mm&r=g"},"date":"2020-02-11T08:55:28","cld_nonce":"82f011626f","content":{"rendered":"<p>Lieber w\u00e4re mir ein echtes Win10 Lite ohne diesen ganzen Microsoft M\u00fcll, also ohne One Drive Cortana, Edge und die ganze Telemetrie. So eine Version kursiert im Internet, leider nur auf englisch <a href=\"https:\/\/oprekin.com\/windows-10-pro-1903-lite\/\" rel=\"nofollow ugc\">https:\/\/oprekin.com\/windows-10-pro-1903-lite\/<\/a><br \/>\nWenn ich Linux haben will, kann ich das runterladen und installieren. Wozu eine Lite Version?<\/p>\n"},"status":"1"},{"id":126828,"parent":0,"author":0,"author_name":"Yps","author_email":"yps@yps.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1e835d929bbf90e2ce62b4bc6869ddac5d6b7902fc3193f2ee2dc651e2aa9e51?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1e835d929bbf90e2ce62b4bc6869ddac5d6b7902fc3193f2ee2dc651e2aa9e51?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1e835d929bbf90e2ce62b4bc6869ddac5d6b7902fc3193f2ee2dc651e2aa9e51?s=96&d=mm&r=g"},"date":"2020-02-11T17:00:41","cld_nonce":"82f011626f","content":{"rendered":"<p>Windows ist kein gesch\u00fctzter Name. Sonst d\u00fcrfte dieses Wort in der englischen Sprache nicht mehr benutzt werden. Microsoft Windows ist gesch\u00fctzt.<\/p>\n"},"status":"1"},{"id":126830,"parent":126782,"author":4418,"author_name":"Manny","author_email":"mbd29963@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cf181304435aaa7d897037277405d2dcaa7493a43571af77a9d3e82895b291d?s=96&d=mm&r=g"},"date":"2020-02-11T17:05:45","cld_nonce":"82f011626f","content":{"rendered":"<p>kann man sich doch selber machen so eine Installations-ISO- dann auch in Deutsch<\/p>\n<p>wenn man das &#8222;anpassen&#8220; oder modifizieren mit Windows Lite \u00fcbersetzen kann, dann benutze ich sowas schon recht lange bzw. seit ich mit DISM( plusplus )  arbeite<br \/>\n&#8211; warum kann man WordPress hier eigentlich nicht direkt 2 Pluszeichen posten ???<\/p>\n"},"status":"1"},{"id":126832,"parent":0,"author":0,"author_name":"FAULESAU","author_email":"pumphut02681@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5ee5c6b3d5723097f1e1ba5237db06bd86e13959f35edff2075451aa3efdcfdc?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5ee5c6b3d5723097f1e1ba5237db06bd86e13959f35edff2075451aa3efdcfdc?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5ee5c6b3d5723097f1e1ba5237db06bd86e13959f35edff2075451aa3efdcfdc?s=96&d=mm&r=g"},"date":"2020-02-11T17:18:06","cld_nonce":"82f011626f","content":{"rendered":"<p>Hier kann man Kaufen?<\/p>\n<p><a href=\"https:\/\/www.window11updates.com\/windows-12-download-iso-32bit-64-bit-free-release-date\/\" rel=\"nofollow ugc\">https:\/\/www.window11updates.com\/windows-12-download-iso-32bit-64-bit-free-release-date\/<\/a><\/p>\n"},"status":"1"},{"id":126833,"parent":126739,"author":0,"author_name":"Harry S.","author_email":"root@pc-harry.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/efe8fa5be068f54ea1870aed4b7822b12a89c3cc3d3e51a4a10a4dd59b31d1e7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/efe8fa5be068f54ea1870aed4b7822b12a89c3cc3d3e51a4a10a4dd59b31d1e7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/efe8fa5be068f54ea1870aed4b7822b12a89c3cc3d3e51a4a10a4dd59b31d1e7?s=96&d=mm&r=g"},"date":"2020-02-11T17:24:14","cld_nonce":"82f011626f","content":{"rendered":"<p>Zitat: &#8222;Linux Lite is based on the Ubuntu LTS series giving you 5 years of support per major release.&#8220;<br \/>\n<img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":126834,"parent":126828,"author":0,"author_name":"Wolfgang D.","author_email":"wolfgang362@habmalnefrage.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=96&d=mm&r=g"},"date":"2020-02-11T17:30:23","cld_nonce":"82f011626f","content":{"rendered":"<p>@Yps &#8222;kein gesch\u00fctzter Name&#8220;<\/p>\n<p>Ja, deshalb wurde der Herr Ghisler auch schon vor Jahren von Microsoft h\u00f6flich aber nachdr\u00fccklich darum gebeten seinen &#8222;Windows Commander&#8220; anders zu nennen.<\/p>\n<p>Man &#8222;Wortmarke, Markenrecht&#8220;.<\/p>\n"},"status":"1"},{"id":126850,"parent":126782,"author":0,"author_name":"knigge111","author_email":"martin.staiger@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c075ad3e3443c785a499488b26da484b4531ca18f782128e5df176aac1685b57?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c075ad3e3443c785a499488b26da484b4531ca18f782128e5df176aac1685b57?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c075ad3e3443c785a499488b26da484b4531ca18f782128e5df176aac1685b57?s=96&d=mm&r=g"},"date":"2020-02-11T19:30:08","cld_nonce":"82f011626f","content":{"rendered":"<p>Die kannst du sehr einfach selbst erstellen. NTLite nutze ich schon sehr lange um ein total angepasstes Windows zu erstellen. <\/p>\n<p><a href=\"https:\/\/www.ntlite.com\" rel=\"nofollow ugc\">https:\/\/www.ntlite.com<\/a> <\/p>\n<p><i>gepostet mit der <a href='https:\/\/play.google.com\/store\/apps\/details?id=com.deskmodder' rel=\"nofollow ugc\">Deskmodder.de-App f\u00fcr Android<\/a><\/i><\/p>\n"},"status":"1"},{"id":126885,"parent":0,"author":0,"author_name":"ordner","author_email":"ramadan@jesus.christ","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d76b2e41a2ab909675855d832474f65c025658912c7aec744471538a8021f334?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d76b2e41a2ab909675855d832474f65c025658912c7aec744471538a8021f334?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d76b2e41a2ab909675855d832474f65c025658912c7aec744471538a8021f334?s=96&d=mm&r=g"},"date":"2020-02-11T22:59:34","cld_nonce":"82f011626f","content":{"rendered":"<p>nuja..gleich aussehen und gleich funktionieren\u2026sind 2 paar schuhe.<br \/>\nich kann mein win7\/10 auch wie win 3.11\/linux aussehen lassen\u2026darum funktioniert es nicht gleich.<\/p>\n<p>solange die programme nicht platform\u00fcbergreifend funktionieren (alle!)\u2026gibt es keine alternative zu linux\u2026.oder zu windoof\u2026oder macos\u2026<br \/>\nda das aus geldintressen der firmen (apple und microsoft) scheitern wird\u2026mu\u00df sich linux endlich mal trauen verbraucherfreundlicher zu werden\u2026und nicht ein nischenprodukt sein, das f\u00fcr studierte ist\u2026denn vieles im linux funktioniert so, das es verbraucherfeindlich ist\u2026auch weil linux programmier \u201eder king\u201c sein wollen.<\/p>\n"},"status":"1"},{"id":126888,"parent":126745,"author":0,"author_name":"ordner","author_email":"ramadan@jesus.ch","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/533aa8ea77cc02616217b0abfeb5bd53c325c8e63a87e76027803cfa78cab4c0?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/533aa8ea77cc02616217b0abfeb5bd53c325c8e63a87e76027803cfa78cab4c0?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/533aa8ea77cc02616217b0abfeb5bd53c325c8e63a87e76027803cfa78cab4c0?s=96&d=mm&r=g"},"date":"2020-02-11T23:10:01","cld_nonce":"82f011626f","content":{"rendered":"<p>wenn win im abomodel kommt (von der cloud)&#8230;sp\u00e4testens dann ist windows geschichte.<\/p>\n<p>fast alle die ich kenne updaten win10 schon nicht mehr&#8230;weil fast immer irgend etwas schief geht&#8230;einstellungen verstellt werden usw. windows10 hat doch nur den gleichen zusprich, wie seinerzeit vista.<\/p>\n"},"status":"1"},{"id":126900,"parent":0,"author":0,"author_name":"Nimda","author_email":"nein@nein.ne","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d9c630d9ae48c14c03dce769e95d6a15d8f9c715220473fb93bd43c06d76c45b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d9c630d9ae48c14c03dce769e95d6a15d8f9c715220473fb93bd43c06d76c45b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d9c630d9ae48c14c03dce769e95d6a15d8f9c715220473fb93bd43c06d76c45b?s=96&d=mm&r=g"},"date":"2020-02-12T05:11:40","cld_nonce":"82f011626f","content":{"rendered":"<p>In der bunten Zeitung von meinem Papa stand dazu, sowas nutzen nur ganz krasse Cyber-Leute um ihre Absichten zu verschleiern. Die schieben dir im Schlaf so &#8217;ne fertig gebootete Installer-CD in den USB-Schacht &#8211; so schnell kommt man garnicht hinterher, wenn man es versucht.<br \/>\nDer Monitor wird quasi bis zu dreimal transparenter als mit einem normalem Windows.<br \/>\n<img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":127560,"parent":0,"author":0,"author_name":"Hitman","author_email":"geisspeter9@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/50d63520a61f0eeb60cd87af81198b355d0021d756c3d17b3c94ede8812fe7e1?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/50d63520a61f0eeb60cd87af81198b355d0021d756c3d17b3c94ede8812fe7e1?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/50d63520a61f0eeb60cd87af81198b355d0021d756c3d17b3c94ede8812fe7e1?s=96&d=mm&r=g"},"date":"2020-02-20T05:49:24","cld_nonce":"82f011626f","content":{"rendered":"<p>W\u00fcrde mich doch mal interessieren, bin an Betriebssystemen f\u00fcr alte Rechner interessiert da ich das furchtbar finde einen an sich guten PC wegzuschmeissen weil Win10 nur auf Hitec PCs l\u00e4uft, in der Beziehung ist Microsoft n\u00e4mlich der letzte Schei\u00df, erst Kohle machen und dann die Kunden von den Damals relatief teueren PCs in den Arsch zu treten. Da ist so ein Linuxsystem f\u00fcr 32 Bit und alter Hardware eine doch eine interessante und Sinnvolle L\u00f6sung, der Umwelt zu liebe, es wird sowieso immer mehr weggeschmissen was eigentlich nicht gut ist, das ist echt schade, ich habe sehr viele alte Ger\u00e4te die teilweise 50 Jahre alt sind, zb. JVC Hifi System was richtig knallt, da kann man alles was heute auf dem Markt ist in die Tonne kloppen. Und das ist ja heute normal wegschmei\u00dfen und neu kaufen. Sei es PC, TV, Hifi oder sonst was, die Industrie beschei\u00dft uns alle die wollen nur Verkaufen.<\/p>\n"},"status":"1"},{"id":128199,"parent":0,"author":0,"author_name":"Torsten","author_email":"tb21680@vivaldi.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ef0b7c583724f731a91f4ec1ed293acad11b4455d4ef3c9839f43ff2551330ae?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ef0b7c583724f731a91f4ec1ed293acad11b4455d4ef3c9839f43ff2551330ae?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ef0b7c583724f731a91f4ec1ed293acad11b4455d4ef3c9839f43ff2551330ae?s=96&d=mm&r=g"},"date":"2020-02-26T15:30:55","cld_nonce":"82f011626f","content":{"rendered":"<p>Die Macher von Linux Lite haben jedoch NICHTS mit dem &#8222;Windows 12 Lite&#8220; zu tun und sie distanzieren sich davon. Dies h\u00e4tte man auch einmal erw\u00e4hnen sollen.<\/p>\n"},"status":"1"},{"id":128200,"parent":128199,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-02-26T15:37:43","cld_nonce":"82f011626f","content":{"rendered":"<p>Kommt darauf an wann sie sich davon distanziert haben.<br \/>\nDas die Entwickler damit nichts zu tun haben, d\u00fcrfte wohl jedem klar sein.<\/p>\n"},"status":"1"},{"id":132682,"parent":0,"author":5495,"author_name":"pbird","author_email":"pbird.ac@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7d9ee55a0344f123177dd1b609d5b73dc008dcb3ec47d61badf76ee88c0d9c6e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7d9ee55a0344f123177dd1b609d5b73dc008dcb3ec47d61badf76ee88c0d9c6e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7d9ee55a0344f123177dd1b609d5b73dc008dcb3ec47d61badf76ee88c0d9c6e?s=96&d=mm&r=g"},"date":"2020-04-21T17:24:12","cld_nonce":"82f011626f","content":{"rendered":"<p>Solange die Linuxe gleich welcher Art mit Gnomen, Kobolden und D\u00e4monen oder sonst welchen Fabelwesen arbeitet. die man einh\u00e4ngen oder aufh\u00e4ngen kann oder mu\u00df, um da irgendwas in einem undurchschaubaren Dateisystem zu finden, ist und wird Linux f\u00fcr mich keine keine ernst zu nehmende Option.<\/p>\n"},"status":"1"},{"id":136508,"parent":0,"author":0,"author_name":"Diplom XXX","author_email":"frank1302@emailn.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3bef64ea60cace169e551ad2368674fac30130ba69265c15cc5f8a8589a3a41e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3bef64ea60cace169e551ad2368674fac30130ba69265c15cc5f8a8589a3a41e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3bef64ea60cace169e551ad2368674fac30130ba69265c15cc5f8a8589a3a41e?s=96&d=mm&r=g"},"date":"2020-06-05T15:25:44","cld_nonce":"82f011626f","content":{"rendered":"<p>A:  Das wort &#8222;Windows&#8220; stammt aus der Umstellung als die SteinzeitLeutz das Salz entdeckt hamm<br \/>\n(&#8230;.) Es ist also ein lexikaisches Wort und damit NICHT sch\u00fctzbar. Siehe Gerichtsurteil aus 2014<br \/>\nwo jemend Ferrario anpissen wollte. (&#8230;)<br \/>\nBegr\u00fcndung: Wenn der Chef sich vor dem Urknall seine Worte h\u00e4tte sch\u00fctzen lassen, w\u00fcrde es heute KEIN  &#8222;MS&#8220;, KINDER-Rochee, Chochlate-Chips, &#8222;Windows&#8220; &#8211;ja<br \/>\nnoch nicht mal die Mutter ERDE (Helios3 oder Sol3) w\u00fcrde es geben. Vermutlich auch kein Helios, Lorenz, Sol-0, oder Sonne ??<\/p>\n"},"status":"1"},{"id":136510,"parent":126741,"author":0,"author_name":"Diplom XXX","author_email":"frank1302@emailn.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3bef64ea60cace169e551ad2368674fac30130ba69265c15cc5f8a8589a3a41e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3bef64ea60cace169e551ad2368674fac30130ba69265c15cc5f8a8589a3a41e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3bef64ea60cace169e551ad2368674fac30130ba69265c15cc5f8a8589a3a41e?s=96&d=mm&r=g"},"date":"2020-06-05T15:31:41","cld_nonce":"82f011626f","content":{"rendered":"<p>War da nicht noch was ? OpenSuse 10.10 kimmt mit WINE daher.<br \/>\nEinfach konfigurieren &#8211; dauert ca. 1 Wochenende und LEXware l\u00e4uft weiter.<br \/>\nDer neueste WINE-Jahrgang soll sogar autokonfigurierend sein. (Drag &amp; Dr\u00f6pchen)<\/p>\n"},"status":"1"},{"id":136513,"parent":132682,"author":0,"author_name":"SonntagszeitungsAnw\u00e4rter","author_email":"frank1302@emailn.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3bef64ea60cace169e551ad2368674fac30130ba69265c15cc5f8a8589a3a41e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3bef64ea60cace169e551ad2368674fac30130ba69265c15cc5f8a8589a3a41e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3bef64ea60cace169e551ad2368674fac30130ba69265c15cc5f8a8589a3a41e?s=96&d=mm&r=g"},"date":"2020-06-05T16:05:58","cld_nonce":"82f011626f","content":{"rendered":"<p>Hi<br \/>\nDein D\u00e4mon schreibt sich korreggt DEmon, was nix anders hei\u00dft als &#8222;DEV-EL-oopement-Monitor!&#8220;<br \/>\nOh shit happens DEVEList eine sehr fr\u00fche indische Gottheit, die dank Inquisation beiseite geschoben mu\u00dfte.  Ein Monitor-Proggy kann u.a. Maschinensprache anwenderfreundlich n\u00e4herbringen.<br \/>\nDie anderen Teile bekommen wir auch noch entmystifiziert oder ent-Tron-t, keine Panik.<br \/>\nTschuldigung Gnome stehen schon unten.<br \/>\nHast Du a LinuX a la Joachim L\u00f6w irgendwo  gesehen ?  Gnome-Voll=ca. 4GB &#8211; wieviel GB m\u00fc\u00dfte<br \/>\neine L\u00f6w-Install-DVD-mitbringen ??<br \/>\nDie Herrscher hamm fr\u00fcher L\u00f6wen aus Gips an die Haupteing\u00e4nge  zur Bewachung abgestellt<br \/>\nein L\u00f6w rechtz ein L\u00f6w links.   Diie B\u00fcrgerschaft konnte sich nur Zwerge leisten<br \/>\nFortsetzung folgt<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Windows 12 Lite - Wie man Windows-Nutzern Linux erkl\u00e4rt - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windows 12 Lite - Wie man Windows-Nutzern Linux erkl\u00e4rt\" \/>\n<meta property=\"og:description\" content=\"Auf einer lokalen Messe hat hexsayeed eine Windows 12 Lite Installations-DVD und eine Beschreibung dazu gesehen und musste laut lachen. Auch ich musste schmunzeln. Aber die Idee dahinter ist gar nicht mal so schlecht. Denn man hat hier nichts weiter&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-10T12:32:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-10T14:14:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1037\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Windows 12 Lite &#8211; Wie man Windows-Nutzern Linux erkl\u00e4rt\",\"datePublished\":\"2020-02-10T12:32:19+00:00\",\"dateModified\":\"2020-02-10T14:14:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/\"},\"wordCount\":187,\"commentCount\":27,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/windows-12-lite-preview.jpg\",\"keywords\":[\"Lite 4.8 LTS\",\"Windows 12 Lite\"],\"articleSection\":[\"Welt des Internets\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/\",\"name\":\"Windows 12 Lite - Wie man Windows-Nutzern Linux erkl\u00e4rt - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/windows-12-lite-preview.jpg\",\"datePublished\":\"2020-02-10T12:32:19+00:00\",\"dateModified\":\"2020-02-10T14:14:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/windows-12-lite-preview.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/windows-12-lite-preview.jpg\",\"width\":1037,\"height\":595},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/10\\\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Windows 12 Lite &#8211; Wie man Windows-Nutzern Linux erkl\u00e4rt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Windows 12 Lite - Wie man Windows-Nutzern Linux erkl\u00e4rt - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/","og_locale":"de_DE","og_type":"article","og_title":"Windows 12 Lite - Wie man Windows-Nutzern Linux erkl\u00e4rt","og_description":"Auf einer lokalen Messe hat hexsayeed eine Windows 12 Lite Installations-DVD und eine Beschreibung dazu gesehen und musste laut lachen. Auch ich musste schmunzeln. Aber die Idee dahinter ist gar nicht mal so schlecht. Denn man hat hier nichts weiter&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-02-10T12:32:19+00:00","article_modified_time":"2020-02-10T14:14:13+00:00","og_image":[{"width":1037,"height":595,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Windows 12 Lite &#8211; Wie man Windows-Nutzern Linux erkl\u00e4rt","datePublished":"2020-02-10T12:32:19+00:00","dateModified":"2020-02-10T14:14:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/"},"wordCount":187,"commentCount":27,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview.jpg","keywords":["Lite 4.8 LTS","Windows 12 Lite"],"articleSection":["Welt des Internets"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/","name":"Windows 12 Lite - Wie man Windows-Nutzern Linux erkl\u00e4rt - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview.jpg","datePublished":"2020-02-10T12:32:19+00:00","dateModified":"2020-02-10T14:14:13+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview.jpg","width":1037,"height":595},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/10\/windows-12-lite-wie-man-windows-nutzer-linux-erklaert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Windows 12 Lite &#8211; Wie man Windows-Nutzern Linux erkl\u00e4rt"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/windows-12-lite-preview.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/134111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=134111"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/134111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/134114"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=134111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=134111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=134111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}