{"id":133841,"date":"2020-02-04T18:31:57","date_gmt":"2020-02-04T17:31:57","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=133841"},"modified":"2020-02-04T18:35:50","modified_gmt":"2020-02-04T17:35:50","slug":"microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/","title":{"rendered":"Microsoft Edge Dev Tools (Entwicklungstools) nun auch in Deutsch und weiteren Sprachen"},"content":{"rendered":"<p>Wie das Edge Team eben bekannt gegeben hat, wurden im Microsoft Edge (Chromium) ab Version 80 die Dev Tools (Entwicklungstools) nun neben englisch in 10 weiteren Sprachen freigeschaltet. Neben deutsch auch in franz\u00f6sisch, italienisch, koreanisch, russisch, portugiesisch, japanisch und chinesisch auch russisch.<\/p>\n<p>In der aktuellen Canary und Dev Version, wird dies schon automatisch in Deutsch angezeigt. Wem das nicht gef\u00e4llt braucht nur die Entwicklungstools \u00f6ffnen, dort die drei Punkte f\u00fcr das Men\u00fc anklicken und den Haken entfernen bei &#8222;Browsersprache anpassen&#8220;. Schon ist es wieder wie gewohnt in Englisch.<\/p>\n<div id='gallery-1' class='gallery galleryid-133841 gallery-columns-2 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001.jpg' rel=\"lightbox[133841]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"197\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-306x197.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-306x197.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-500x321.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-810x521.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001.jpg 1192w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-002.jpg' rel=\"lightbox[133841]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"189\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-002-306x189.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-002-306x189.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-002-500x309.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-002-810x500.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-002.jpg 1230w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>In der Beta, die ja auch schon die Version 80 ist, musste es erst bei mir \u00fcber die Flags &#8222;Enable localized Developer Tools&#8220; aktiviert werden. Demn\u00e4chst sollen dann weitere Sprachen folgen.<\/p>\n<p><em>&#8222;Diese Version ist das Ergebnis einer monatelangen Zusammenarbeit zwischen unserem Team und den Teams von DevTools, Lighthouse und dem Chrome-Team&#8230; Damit erg\u00e4nzen unsere neuen Browser-Tools eine lange Liste anderer lokalisierter Microsoft-Entwicklungen, darunter VS Code, Azure Portal und mehr.&#8220;<\/em><\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/blogs.windows.com\/msedgedev\/2020\/02\/04\/localizing-edge-devtools\/\" rel=\"noopener noreferrer\" target=\"_blank\">blogs.windows<\/a><\/div>\n<h3>Alle Microsoft Edge Downloads auch Insider:<\/h3>\n<ul>\n<li>Offline-Installer Stable Enterprise  <a href=\"http:\/\/go.microsoft.com\/fwlink\/?LinkID=2093437\" rel=\"noopener noreferrer\" target=\"_blank\">X64.msi <\/a>, <a href=\"http:\/\/go.microsoft.com\/fwlink\/?LinkID=2093505\" rel=\"noopener noreferrer\" target=\"_blank\">X86.msi <\/a><\/li>\n<li><strong>Stable Version:<\/strong> <a href=\"https:\/\/go.microsoft.com\/fwlink\/?linkid=2069324&#038;Channel=Stable&#038;language=de\" rel=\"noopener noreferrer\" target=\"_blank\">go.microsoft.com\/Channel=Stable<\/a><\/li>\n<li>Die weiteren Links<\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/\" target=\"_blank\" rel=\"noopener noreferrer\">win10<\/a>, <a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win8dot1\" target=\"_blank\" rel=\"noopener noreferrer\">win8dot1<\/a>, <a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win8\" target=\"_blank\" rel=\"noopener noreferrer\">platform=win8<\/a>, <a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win7\" target=\"_blank\" rel=\"noopener noreferrer\">platform=win7<\/a><\/li>\n<li>Die portablen Versionen: <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/05\/27\/portabler-microsoft-edge-chromium-updater-fuer-canary-developer-beta-und-spaeter-auch-der-finale-edge\/\" target=\"_blank\" rel=\"noopener noreferrer\">Portable Edge Updater<\/a><\/li>\n<li>Und f\u00fcr die Macs:<\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=macos\" target=\"_blank\" rel=\"noopener noreferrer\">microsoftedgeinsider.com\/download\/platform=macos<\/a><\/li>\n<li>Enterprise Stable: <a href=\"http:\/\/go.microsoft.com\/fwlink\/?LinkID=2093438\" rel=\"noopener noreferrer\" target=\"_blank\">macOS.pkg <\/a><\/li>\n<li>Android: <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.microsoft.emmx&#038;hl=de\" rel=\"noopener noreferrer\" target=\"_blank\">play.google.com\/microsoft.emmx<\/a><\/li>\n<li>iOS: <a href=\"https:\/\/apps.apple.com\/de\/app\/microsoft-edge\/id1288723196\" rel=\"noopener noreferrer\" target=\"_blank\">apps.apple.com\/microsoft-edge<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Wie das Edge Team eben bekannt gegeben hat, wurden im Microsoft Edge (Chromium) ab Version 80 die Dev Tools (Entwicklungstools) nun neben englisch in 10 weiteren Sprachen freigeschaltet. Neben deutsch auch in franz\u00f6sisch, italienisch, koreanisch, russisch, portugiesisch, japanisch und chinesisch&hellip; <\/p>\n","protected":false},"author":134,"featured_media":133843,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166],"tags":[75,1174,63984,68924,8501],"class_list":["post-133841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-browser","tag-chromium","tag-deutsch","tag-dev-tools","tag-entwicklungstools","tag-microsoft-edge"],"wp_featured_image":{"id":133843,"alt_text":"","description":"","media_type":"image","media_details":{"width":1192,"height":766,"file":"2020\/02\/microsoft-edge-dev-tools-deutsch-001.jpg","sizes":{"medium":{"file":"microsoft-edge-dev-tools-deutsch-001-500x321.jpg","width":500,"height":321,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-500x321.jpg"},"large":{"file":"microsoft-edge-dev-tools-deutsch-001-810x521.jpg","width":810,"height":521,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-810x521.jpg"},"thumbnail":{"file":"microsoft-edge-dev-tools-deutsch-001-306x197.jpg","width":306,"height":197,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-306x197.jpg"},"wp_review_large":{"file":"microsoft-edge-dev-tools-deutsch-001-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-320x200.jpg"},"wp_review_small":{"file":"microsoft-edge-dev-tools-deutsch-001-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-65x65.jpg"},"blog-large":{"file":"microsoft-edge-dev-tools-deutsch-001-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-642x300.jpg"},"blog-medium":{"file":"microsoft-edge-dev-tools-deutsch-001-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-306x205.jpg"},"recent-thumb":{"file":"microsoft-edge-dev-tools-deutsch-001-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-350x316.jpg"},"service-featured":{"file":"microsoft-edge-dev-tools-deutsch-001-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-600x330.jpg"},"wp_rp_thumbnail":{"file":"microsoft-edge-dev-tools-deutsch-001-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":133841,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Microsoft Edge Dev Tools (Entwicklungstools) nun auch in Deutsch und weiteren Sprachen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft Edge Dev Tools (Entwicklungstools) nun auch in Deutsch und weiteren Sprachen\" \/>\n<meta property=\"og:description\" content=\"Wie das Edge Team eben bekannt gegeben hat, wurden im Microsoft Edge (Chromium) ab Version 80 die Dev Tools (Entwicklungstools) nun neben englisch in 10 weiteren Sprachen freigeschaltet. Neben deutsch auch in franz\u00f6sisch, italienisch, koreanisch, russisch, portugiesisch, japanisch und chinesisch&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-04T17:31:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-04T17:35:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1192\" \/>\n\t<meta property=\"og:image:height\" content=\"766\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Microsoft Edge Dev Tools (Entwicklungstools) nun auch in Deutsch und weiteren Sprachen\",\"datePublished\":\"2020-02-04T17:31:57+00:00\",\"dateModified\":\"2020-02-04T17:35:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/\"},\"wordCount\":242,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/microsoft-edge-dev-tools-deutsch-001.jpg\",\"keywords\":[\"Chromium\",\"deutsch\",\"Dev Tools\",\"Entwicklungstools\",\"Microsoft Edge\"],\"articleSection\":[\"Browser\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/\",\"name\":\"Microsoft Edge Dev Tools (Entwicklungstools) nun auch in Deutsch und weiteren Sprachen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/microsoft-edge-dev-tools-deutsch-001.jpg\",\"datePublished\":\"2020-02-04T17:31:57+00:00\",\"dateModified\":\"2020-02-04T17:35:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/microsoft-edge-dev-tools-deutsch-001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/microsoft-edge-dev-tools-deutsch-001.jpg\",\"width\":1192,\"height\":766},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/04\\\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft Edge Dev Tools (Entwicklungstools) nun auch in Deutsch und weiteren Sprachen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Microsoft Edge Dev Tools (Entwicklungstools) nun auch in Deutsch und weiteren Sprachen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/","og_locale":"de_DE","og_type":"article","og_title":"Microsoft Edge Dev Tools (Entwicklungstools) nun auch in Deutsch und weiteren Sprachen","og_description":"Wie das Edge Team eben bekannt gegeben hat, wurden im Microsoft Edge (Chromium) ab Version 80 die Dev Tools (Entwicklungstools) nun neben englisch in 10 weiteren Sprachen freigeschaltet. Neben deutsch auch in franz\u00f6sisch, italienisch, koreanisch, russisch, portugiesisch, japanisch und chinesisch&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-02-04T17:31:57+00:00","article_modified_time":"2020-02-04T17:35:50+00:00","og_image":[{"width":1192,"height":766,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Microsoft Edge Dev Tools (Entwicklungstools) nun auch in Deutsch und weiteren Sprachen","datePublished":"2020-02-04T17:31:57+00:00","dateModified":"2020-02-04T17:35:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/"},"wordCount":242,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001.jpg","keywords":["Chromium","deutsch","Dev Tools","Entwicklungstools","Microsoft Edge"],"articleSection":["Browser"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/","name":"Microsoft Edge Dev Tools (Entwicklungstools) nun auch in Deutsch und weiteren Sprachen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001.jpg","datePublished":"2020-02-04T17:31:57+00:00","dateModified":"2020-02-04T17:35:50+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001.jpg","width":1192,"height":766},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/04\/microsoft-edge-dev-tools-entwicklungstools-nun-auch-in-deutsch-und-weiteren-sprachen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Microsoft Edge Dev Tools (Entwicklungstools) nun auch in Deutsch und weiteren Sprachen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/microsoft-edge-dev-tools-deutsch-001.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/133841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=133841"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/133841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/133843"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=133841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=133841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=133841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}