{"id":133746,"date":"2020-02-02T12:58:50","date_gmt":"2020-02-02T11:58:50","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=133746"},"modified":"2023-01-14T15:52:14","modified_gmt":"2023-01-14T14:52:14","slug":"spielspass-zum-sonntag-gans-auf-dem-desktop","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/","title":{"rendered":"Spielspa\u00df zum Sonntag &#8211; Gans auf dem Desktop"},"content":{"rendered":"<p>Wer ein wenig Abwechslung und Unterhaltung auf dem Desktop m\u00f6chte, der kann sich mal die Desktop Goose von Samperson anschauen. Einmal gestartet, tr\u00f6delt die Gans (noch) brav \u00fcber den Desktop.<\/p>\n<p>Aber mit der Zeit wird es dann lustig. Die Gans klaut den Cursor. Schiebt Nachrichten ins Fenster, so wie im Bild zu sehen, als ich gerade die Animation abspeichern wollte. Nur den Desktop sollte man nicht unbeaufsichtigt lassen. Ansonsten pflastert die Gans den Bildschirm mit vielen  lustigen Bildern und Spr\u00fcchen zu.<\/p>\n<div id='gallery-1' class='gallery galleryid-133746 gallery-columns-2 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool.jpg' rel=\"lightbox[133746]\"><img loading=\"lazy\" decoding=\"async\" width=\"299\" height=\"205\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-299x205.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-299x205.jpg 299w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-500x343.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-810x556.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool.jpg 1316w\" sizes=\"auto, (max-width: 299px) 100vw, 299px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/gans.gif' rel=\"lightbox[133746]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"192\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/gans-306x192.gif\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-133749\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/gans-306x192.gif 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/gans-500x314.gif 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/gans-810x509.gif 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/gans-320x200.gif 320w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-133749'>\n\t\t\t\tEinfach das Bild anklicken f\u00fcr die Animation\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>Wer dann doch die Nase von der Gans voll hat, braucht nur etwas l\u00e4nger die ESC-Taste dr\u00fccken. Dann zieht sich die Gans auch wieder zur\u00fcck. Ein sch\u00f6ner kleiner Spielspa\u00df nicht nur am Sonntag.<\/p>\n<h3>Info und Download<\/h3>\n<ul>\n<li><a href=\"https:\/\/samperson.itch.io\/desktop-goose\" rel=\"noopener noreferrer\" target=\"_blank\">samperson.itch.io\/desktop-goose<\/a><\/li>\n<li>Die Gans ist kostenlos, man kann aber auch ein, zwei Euro spenden. \u00dcber der Euro-Anzeige geht es weiter zum Download.<\/li>\n<\/ul>\n<p>\u200f<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer ein wenig Abwechslung und Unterhaltung auf dem Desktop m\u00f6chte, der kann sich mal die Desktop Goose von Samperson anschauen. Einmal gestartet, tr\u00f6delt die Gans (noch) brav \u00fcber den Desktop. Aber mit der Zeit wird es dann lustig. Die Gans&hellip; <\/p>\n","protected":false},"author":134,"featured_media":133748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[152,2689,11],"tags":[66,68803,68802,9741],"class_list":["post-133746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software","category-windows-10","category-windows","tag-desktop","tag-desktop-goose","tag-gans","tag-windows"],"wp_featured_image":{"id":133748,"alt_text":"","description":"","media_type":"image","media_details":{"width":1316,"height":903,"file":"2020\/02\/desktop-gans-tool.jpg","sizes":{"medium":{"file":"desktop-gans-tool-500x343.jpg","width":500,"height":343,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-500x343.jpg"},"large":{"file":"desktop-gans-tool-810x556.jpg","width":810,"height":556,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-810x556.jpg"},"thumbnail":{"file":"desktop-gans-tool-299x205.jpg","width":299,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-299x205.jpg"},"wp_review_large":{"file":"desktop-gans-tool-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-320x200.jpg"},"wp_review_small":{"file":"desktop-gans-tool-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-65x65.jpg"},"blog-large":{"file":"desktop-gans-tool-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-642x300.jpg"},"blog-medium":{"file":"desktop-gans-tool-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-306x205.jpg"},"recent-thumb":{"file":"desktop-gans-tool-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-350x316.jpg"},"service-featured":{"file":"desktop-gans-tool-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-600x330.jpg"},"wp_rp_thumbnail":{"file":"desktop-gans-tool-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":133746,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool.jpg"},"commentcount":12,"wp_comments":[{"id":126152,"parent":0,"author":0,"author_name":"uhu","author_email":"ursula-hess@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0769d800b9f1aa8a463b7579c50a6bc1d9aa57440649cafa57b0a578ae204e07?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0769d800b9f1aa8a463b7579c50a6bc1d9aa57440649cafa57b0a578ae204e07?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0769d800b9f1aa8a463b7579c50a6bc1d9aa57440649cafa57b0a578ae204e07?s=96&d=mm&r=g"},"date":"2020-02-02T13:40:41","cld_nonce":"82f011626f","content":{"rendered":"<p>lustig, sie wird richtig sauer, sobald man ihre Schildchen schlie\u00dft. Das eSheep 64&lt;bit ist pflegeleichter.<\/p>\n"},"status":"1"},{"id":126154,"parent":0,"author":3017,"author_name":"euromichel","author_email":"michael@schreiber-stolberg.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8b0f826b9e97ce3709da13c48fce7b07b525acd437858ccff724cb456bec3fbd?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8b0f826b9e97ce3709da13c48fce7b07b525acd437858ccff724cb456bec3fbd?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8b0f826b9e97ce3709da13c48fce7b07b525acd437858ccff724cb456bec3fbd?s=96&d=mm&r=g"},"date":"2020-02-02T13:58:26","cld_nonce":"82f011626f","content":{"rendered":"<p>Ja, prima, lustig &#8211; gsd wird nicht die Festplatte formatiert<\/p>\n"},"status":"1"},{"id":126155,"parent":0,"author":0,"author_name":"Ingridl","author_email":"Ingrid@attnetwork.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=96&d=mm&r=g"},"date":"2020-02-02T14:30:45","cld_nonce":"82f011626f","content":{"rendered":"<p>??? <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_confused.gif\" alt=\":???:\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":126156,"parent":126155,"author":4440,"author_name":"DK2000","author_email":"kleiner.dicker.tiger@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f47c5818487788ab85c373f448667f574e8c0e789a076cd59313e685780305a2?s=96&d=mm&r=g"},"date":"2020-02-02T14:44:07","cld_nonce":"82f011626f","content":{"rendered":"<p>Nicht wundern. Solche Sachen gab und gibt es mit Hunden, Katzen,  Fliegen und sonstigem Getiers, dass dann mehr oder weniger selbstst\u00e4ndig dummes Zeug auf dem Desktop macht.<\/p>\n"},"status":"1"},{"id":126159,"parent":126156,"author":0,"author_name":"Harry S.","author_email":"root@pc-harry.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/efe8fa5be068f54ea1870aed4b7822b12a89c3cc3d3e51a4a10a4dd59b31d1e7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/efe8fa5be068f54ea1870aed4b7822b12a89c3cc3d3e51a4a10a4dd59b31d1e7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/efe8fa5be068f54ea1870aed4b7822b12a89c3cc3d3e51a4a10a4dd59b31d1e7?s=96&d=mm&r=g"},"date":"2020-02-02T15:18:08","cld_nonce":"82f011626f","content":{"rendered":"<p>&#8230; und mit Kakerlaken, die sich unter den Fenstern verstecken (und mit gro\u00dfen Flecken platzen, wenn man sie erwischt) &#8230;<\/p>\n"},"status":"1"},{"id":126160,"parent":0,"author":0,"author_name":"Jens","author_email":"rest@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9ad6ca70c2ed9bd1094e96c304a28e5c9876876ebdab7c1dcfe36676bcc79070?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9ad6ca70c2ed9bd1094e96c304a28e5c9876876ebdab7c1dcfe36676bcc79070?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9ad6ca70c2ed9bd1094e96c304a28e5c9876876ebdab7c1dcfe36676bcc79070?s=96&d=mm&r=g"},"date":"2020-02-02T15:46:04","cld_nonce":"82f011626f","content":{"rendered":"<p>Ja, lustig, aber die Sounds m\u00fcssten \u00fcberarbeitet werden^^<\/p>\n"},"status":"1"},{"id":126177,"parent":0,"author":4453,"author_name":"Seven of Nine","author_email":"seven-of-nine@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e2d1432d71d3f1b0d78e78b20e56e41fb743282197b71276db702a0feb565cb4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e2d1432d71d3f1b0d78e78b20e56e41fb743282197b71276db702a0feb565cb4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e2d1432d71d3f1b0d78e78b20e56e41fb743282197b71276db702a0feb565cb4?s=96&d=mm&r=g"},"date":"2020-02-02T20:43:28","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich halte von solchen Sachen gar nix, Es ist meiner Meiner Meinung nach nicht Cool.<br \/>\nEs sorgt nur f\u00fcr zus\u00e4tzlichen Support, und mehr nicht.<\/p>\n"},"status":"1"},{"id":126181,"parent":0,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2020-02-02T22:08:39","cld_nonce":"82f011626f","content":{"rendered":"<p>Die Terror-Gans <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_mrgreen.gif\" alt=\":mrgreen:\" class=\"wp-smiley\" \/> rennt l\u00e4\u00e4\u00e4ngst (vor dem Artikel) \u00fcber 3 Win-Rechner &#8211; auf den 4. mache ich sie gleich drauf!<\/p>\n<p>Gutes ist zu vermelden: sie &#8222;kann&#8220; mit mehreren Monitoren. Normal wetzt sie zwar nur auf\u00b4m Haupt-Moni, wenn man ihr aber das Bild\/fenster klaut, auf den anderen Monitor schiebt UND es schlie\u00dft&#8230;<\/p>\n<p>&#8230;dann rennt sie wie vom Teufel gebissen hin und will den Cursor packen und ihn stehlen. Ich schaff\u00b4 es aber m\u00fchelos, mit dem Cursor noch schneller auszuweichen &#8211; dann verliert sie die Lust und wetzt zum Haupt-Moni zur\u00fcck. Falls man sie den Cursor stehlen l\u00e4\u00dft, passiert auch nix schlimmes: sie tr\u00e4gt ihn nur auf den Haupt-Moni und l\u00e4\u00dft ihn da wieder los.<\/p>\n<p>&#8211; das vom Herrn uhu erw\u00e4hnte eSheep 64 habe ich mir gleich auch noch besorgt &#8211; und mal Gans und Sheep gleichzeitig agieren lassen<\/p>\n<p>Kleines Manko bei beiden: die Tiere sind ziemlich klein und je nach Hintergrund nicht so gut zu sehen. Wirklichen Schaden richten sie aber nicht an &#8211; eine Supportanfrage an Nine of Seven \u00e4\u00e4\u00e4h Seven of Nine ist deswegen von mir nicht zu erwarten.<\/p>\n<p>F\u00fcr solche Sp\u00e4\u00dfe bin ich immer zu haben, auch die uralten Binary Toys hab ich noch auf der Platte. Fix noch einen Ordner im Startmen\u00fc gemacht und mit &#8222;TERRORtiere etc.&#8220; benamt &#8211; da passen noch jede Menge Unsinnstools rein.<\/p>\n"},"status":"1"},{"id":126192,"parent":0,"author":5243,"author_name":"eRaz0r","author_email":"spam84@ymail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d16f80a69776be75a752dbfd4f08206e6f1cc91acf6ad0c940ccbf03336bc76a?s=96&d=mm&r=g"},"date":"2020-02-03T06:50:53","cld_nonce":"82f011626f","content":{"rendered":"<p>F\u00fchle mich irgendwie nach 1999~2000 zur\u00fcck versetzt. Damals gab es solch einen Mumpitz ja f\u00fcr Windows 95\/98 ja auch zu kaufen und war eine regelrechte Epidemie. (Hund\/Katze als virtuelles Haustier am Desktop).<\/p>\n<p>20 Jahre sp\u00e4ter &#8211; revival, nur mit einer Gans <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":126193,"parent":0,"author":0,"author_name":"ydfgb","author_email":"dvsdf@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9892f746bc8b7e718aee3a609860f3ada6ae35140a4d79df4c4a2a574acd88d9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9892f746bc8b7e718aee3a609860f3ada6ae35140a4d79df4c4a2a574acd88d9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9892f746bc8b7e718aee3a609860f3ada6ae35140a4d79df4c4a2a574acd88d9?s=96&d=mm&r=g"},"date":"2020-02-03T08:22:25","cld_nonce":"82f011626f","content":{"rendered":"<p>seeehr inovative nachricht..seehr brauchbar..und von seehr grosser sinnhaftigkeit..danach habe ich schon immer gesucht nun bin ich in meinem wissen deutlich weiter gekommen..wuste doch da war doch noch was..!!!danke..das gibt meinem leben wieder einen sinn..!!<\/p>\n"},"status":"1"},{"id":126194,"parent":126181,"author":0,"author_name":"Ingridl","author_email":"Ingrid@attnetwork.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=96&d=mm&r=g"},"date":"2020-02-03T08:26:51","cld_nonce":"82f011626f","content":{"rendered":"<p>Du musst ja viel Zeit \u23f2 haben,ich hoffe f\u00fcr dich das die Gans kein &#8220; Korona-Virus &#8220; hat. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\":wink:\" class=\"wp-smiley\" \/> <\/p>\n<p>Ps: Jeder hat seine Tierchen, oder halt was anderes.<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" rel=\"nofollow ugc\">Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":126204,"parent":126194,"author":0,"author_name":"Herr Hugo","author_email":"hugohilter@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc5176746c873787fa3f8df5f9bdfbd2f7688721f771100eb4d7b4e82e2d655b?s=96&d=mm&r=g"},"date":"2020-02-03T11:43:41","cld_nonce":"82f011626f","content":{"rendered":"<p>Rentener haben NIE Zeit, Frau Ingridl! Ich bin aber recht geschickt mit der Maus und kann sowas fix erledigen. Bei einem Rechner hab\u00b4 ich einen Film runtergeladen und nebenher die Gans ge\u00e4rgert, grins! <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Spielspa\u00df zum Sonntag - Gans auf dem Desktop - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spielspa\u00df zum Sonntag - Gans auf dem Desktop\" \/>\n<meta property=\"og:description\" content=\"Wer ein wenig Abwechslung und Unterhaltung auf dem Desktop m\u00f6chte, der kann sich mal die Desktop Goose von Samperson anschauen. Einmal gestartet, tr\u00f6delt die Gans (noch) brav \u00fcber den Desktop. Aber mit der Zeit wird es dann lustig. Die Gans&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-02T11:58:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-14T14:52:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1316\" \/>\n\t<meta property=\"og:image:height\" content=\"903\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Spielspa\u00df zum Sonntag &#8211; Gans auf dem Desktop\",\"datePublished\":\"2020-02-02T11:58:50+00:00\",\"dateModified\":\"2023-01-14T14:52:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/\"},\"wordCount\":161,\"commentCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/desktop-gans-tool.jpg\",\"keywords\":[\"Desktop\",\"Desktop Goose\",\"Gans\",\"Windows \u00e4lter\"],\"articleSection\":[\"Software &amp; Updates\",\"Windows 10\",\"Windows \u00e4lter\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/\",\"name\":\"Spielspa\u00df zum Sonntag - Gans auf dem Desktop - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/desktop-gans-tool.jpg\",\"datePublished\":\"2020-02-02T11:58:50+00:00\",\"dateModified\":\"2023-01-14T14:52:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/desktop-gans-tool.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/desktop-gans-tool.jpg\",\"width\":1316,\"height\":903},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/02\\\/02\\\/spielspass-zum-sonntag-gans-auf-dem-desktop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spielspa\u00df zum Sonntag &#8211; Gans auf dem Desktop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Spielspa\u00df zum Sonntag - Gans auf dem Desktop - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/","og_locale":"de_DE","og_type":"article","og_title":"Spielspa\u00df zum Sonntag - Gans auf dem Desktop","og_description":"Wer ein wenig Abwechslung und Unterhaltung auf dem Desktop m\u00f6chte, der kann sich mal die Desktop Goose von Samperson anschauen. Einmal gestartet, tr\u00f6delt die Gans (noch) brav \u00fcber den Desktop. Aber mit der Zeit wird es dann lustig. Die Gans&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-02-02T11:58:50+00:00","article_modified_time":"2023-01-14T14:52:14+00:00","og_image":[{"width":1316,"height":903,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Spielspa\u00df zum Sonntag &#8211; Gans auf dem Desktop","datePublished":"2020-02-02T11:58:50+00:00","dateModified":"2023-01-14T14:52:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/"},"wordCount":161,"commentCount":12,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool.jpg","keywords":["Desktop","Desktop Goose","Gans","Windows \u00e4lter"],"articleSection":["Software &amp; Updates","Windows 10","Windows \u00e4lter"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/","name":"Spielspa\u00df zum Sonntag - Gans auf dem Desktop - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool.jpg","datePublished":"2020-02-02T11:58:50+00:00","dateModified":"2023-01-14T14:52:14+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool.jpg","width":1316,"height":903},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/02\/02\/spielspass-zum-sonntag-gans-auf-dem-desktop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Spielspa\u00df zum Sonntag &#8211; Gans auf dem Desktop"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2020\/02\/desktop-gans-tool.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/133746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=133746"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/133746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/133748"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=133746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=133746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=133746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}