{"id":133261,"date":"2020-01-22T08:57:46","date_gmt":"2020-01-22T07:57:46","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=133261"},"modified":"2020-01-22T09:02:05","modified_gmt":"2020-01-22T08:02:05","slug":"windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/","title":{"rendered":"Windows 10 1909 per Windows Update f\u00fcr weitere Ger\u00e4te mit Windows 10 1809 verf\u00fcgbar"},"content":{"rendered":"<p>Wer noch mit der Windows 10 1809 unterwegs sein sollte, wird nun nach und nach das Windows 10 1909 angeboten bekommen. Dementsprechend hat Microsoft den Text auf der Status-Seite der Windows 10 1909 ge\u00e4ndert.<\/p>\n<p>Anfang Dezember 2019 stand noch: <em>&#8222;Ab heute beginnen wir langsam mit dem schrittweisen Prozess, um automatisch ein Funktions-Update f\u00fcr Ger\u00e4te zu initiieren, auf denen das Oktober 2018 Update (Windows 10, Version 1809) Home und Pro Editionen ausgef\u00fchrt wird, wobei diese Ger\u00e4te weiterhin unterst\u00fctzt werden und die monatlichen Updates erhalten, die f\u00fcr die Sicherheit der Ger\u00e4te und den Zustand des \u00d6kosystems entscheidend sind&#8220;<\/em><\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341.png\" rel=\"lightbox[133261]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341-500x341.png\" alt=\"\" width=\"500\" height=\"341\" class=\"aligncenter size-medium wp-image-130012\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341-301x205.png 301w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Dieser Text wurde nun (21.01.2020) ge\u00e4ndert in: <em>&#8222;Wir beginnen die n\u00e4chste Phase unseres kontrollierten Ansatzes, automatisch ein Feature-Update f\u00fcr eine gr\u00f6\u00dfere Anzahl von Ger\u00e4ten zu initiieren, auf denen das Oktober 2018 Update (Windows 10, Version 1809) Home und Pro Editionen ausgef\u00fchrt wird, wobei diese Ger\u00e4te weiterhin unterst\u00fctzt werden und die monatlichen Updates erhalten, die f\u00fcr die Sicherheit der Ger\u00e4te und den Zustand des \u00d6kosystems entscheidend sind.&#8220;<\/em><\/p>\n<p>Microsoft m\u00f6chte also langsam aber sicher diese Ger\u00e4te auf die aktuelle Version bringen. Denn der Support f\u00fcr die Windows 10 1809 (Home, Pro= endet am <strong>12. Mai 2020<\/strong>. Die Enterprise ein Jahr sp\u00e4ter und die LTSC hat noch bis 2029 Zeit.<\/p>\n<p>F\u00fcr die Windows 10 1903 Nutzer ist die 1909 ja kein Funktionsupdate, wie wir es bisher kannten. Sondern wird als Future Update to 1909 via Enablement Package als kleines Update (<a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/10\/09\/kb4517245-feature-update-auf-die-windows-10-version-1909\/\" rel=\"noopener noreferrer\" target=\"_blank\">KB4517245<\/a>) ausgeliefert.<\/p>\n<div class=\"quellenzeile\"><div class=\"quelle\">Quelle: <a href=\"https:\/\/docs.microsoft.com\/de-de\/windows\/release-information\/status-windows-10-1909\" rel=\"noopener noreferrer\" target=\"_blank\">docs.microsoft<\/a><\/div> <div class=\"viaquelle\">via: <a href=\"https:\/\/twitter.com\/WindowsUpdate\/status\/1219746643492261888\" rel=\"noopener noreferrer\" target=\"_blank\">@WinUpdate<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wer noch mit der Windows 10 1809 unterwegs sein sollte, wird nun nach und nach das Windows 10 1909 angeboten bekommen. Dementsprechend hat Microsoft den Text auf der Status-Seite der Windows 10 1909 ge\u00e4ndert. Anfang Dezember 2019 stand noch: &#8222;Ab&hellip; <\/p>\n","protected":false},"author":134,"featured_media":130012,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[],"class_list":["post-133261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10"],"wp_featured_image":{"id":130012,"alt_text":"","description":"","media_type":"image","media_details":{"width":500,"height":341,"file":"2019\/11\/november-update-2019-by-geralt-500x341.png","sizes":{"thumbnail":{"file":"november-update-2019-by-geralt-500x341-301x205.png","width":301,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341-301x205.png"},"medium":{"file":"november-update-2019-by-geralt-500x341-500x341.png","width":500,"height":341,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341-500x341.png"},"wp_review_large":{"file":"november-update-2019-by-geralt-500x341-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341-320x200.png"},"wp_review_small":{"file":"november-update-2019-by-geralt-500x341-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341-65x65.png"},"blog-large":{"file":"november-update-2019-by-geralt-500x341-500x300.png","width":500,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341-500x300.png"},"blog-medium":{"file":"november-update-2019-by-geralt-500x341-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341-306x205.png"},"recent-thumb":{"file":"november-update-2019-by-geralt-500x341-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341-350x316.png"},"service-featured":{"file":"november-update-2019-by-geralt-500x341-500x330.png","width":500,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341-500x330.png"},"wp_rp_thumbnail":{"file":"november-update-2019-by-geralt-500x341-50x50.png","width":50,"height":50,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341-50x50.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":130008,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341.png"},"commentcount":3,"wp_comments":[{"id":125398,"parent":0,"author":0,"author_name":"Rolix","author_email":"roland.moser@mosimail.ch","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f67f2cc79ba1007ca86ea9a530b2ad9283b44a161c08dc623caa87cf87377e71?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f67f2cc79ba1007ca86ea9a530b2ad9283b44a161c08dc623caa87cf87377e71?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f67f2cc79ba1007ca86ea9a530b2ad9283b44a161c08dc623caa87cf87377e71?s=96&d=mm&r=g"},"date":"2020-01-22T20:10:36","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich bin noch mit 1809 Pro unterwegs und habe als Verz\u00f6gerung 330 Tage eingestellt. Erhalte ich direkt 1909 und nicht vorher noch 1903 und ein halbes Jahr sp\u00e4ter 1909?<\/p>\n"},"status":"1"},{"id":125423,"parent":125398,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2020-01-23T07:29:33","cld_nonce":"82f011626f","content":{"rendered":"<p>Wenn die 330 Tage um sind, bekommst du die 1909, wenn nicht sogar die 2004.<\/p>\n"},"status":"1"},{"id":125478,"parent":125423,"author":0,"author_name":"Rolix","author_email":"roland.moser@mosimail.ch","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f67f2cc79ba1007ca86ea9a530b2ad9283b44a161c08dc623caa87cf87377e71?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f67f2cc79ba1007ca86ea9a530b2ad9283b44a161c08dc623caa87cf87377e71?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f67f2cc79ba1007ca86ea9a530b2ad9283b44a161c08dc623caa87cf87377e71?s=96&d=mm&r=g"},"date":"2020-01-23T20:07:34","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich habe einen Test gemacht.<br \/>\nSemi annual channel und 180 Tage Verz\u00f6gerung. Dann wurde mir 1903 installiert. Was weiter passieren w\u00fcrde, weiss ich nicht, da ich danach wieder zu 1809 bin.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Windows 10 1909 per Windows Update f\u00fcr weitere Ger\u00e4te mit Windows 10 1809 verf\u00fcgbar - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windows 10 1909 per Windows Update f\u00fcr weitere Ger\u00e4te mit Windows 10 1809 verf\u00fcgbar\" \/>\n<meta property=\"og:description\" content=\"Wer noch mit der Windows 10 1809 unterwegs sein sollte, wird nun nach und nach das Windows 10 1909 angeboten bekommen. Dementsprechend hat Microsoft den Text auf der Status-Seite der Windows 10 1909 ge\u00e4ndert. Anfang Dezember 2019 stand noch: &#8222;Ab&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-22T07:57:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-22T08:02:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"341\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Windows 10 1909 per Windows Update f\u00fcr weitere Ger\u00e4te mit Windows 10 1809 verf\u00fcgbar\",\"datePublished\":\"2020-01-22T07:57:46+00:00\",\"dateModified\":\"2020-01-22T08:02:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/\"},\"wordCount\":259,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/november-update-2019-by-geralt-500x341.png\",\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/\",\"name\":\"Windows 10 1909 per Windows Update f\u00fcr weitere Ger\u00e4te mit Windows 10 1809 verf\u00fcgbar - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/november-update-2019-by-geralt-500x341.png\",\"datePublished\":\"2020-01-22T07:57:46+00:00\",\"dateModified\":\"2020-01-22T08:02:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/november-update-2019-by-geralt-500x341.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/november-update-2019-by-geralt-500x341.png\",\"width\":500,\"height\":341},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2020\\\/01\\\/22\\\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Windows 10 1909 per Windows Update f\u00fcr weitere Ger\u00e4te mit Windows 10 1809 verf\u00fcgbar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Windows 10 1909 per Windows Update f\u00fcr weitere Ger\u00e4te mit Windows 10 1809 verf\u00fcgbar - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/","og_locale":"de_DE","og_type":"article","og_title":"Windows 10 1909 per Windows Update f\u00fcr weitere Ger\u00e4te mit Windows 10 1809 verf\u00fcgbar","og_description":"Wer noch mit der Windows 10 1809 unterwegs sein sollte, wird nun nach und nach das Windows 10 1909 angeboten bekommen. Dementsprechend hat Microsoft den Text auf der Status-Seite der Windows 10 1909 ge\u00e4ndert. Anfang Dezember 2019 stand noch: &#8222;Ab&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2020-01-22T07:57:46+00:00","article_modified_time":"2020-01-22T08:02:05+00:00","og_image":[{"width":500,"height":341,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Windows 10 1909 per Windows Update f\u00fcr weitere Ger\u00e4te mit Windows 10 1809 verf\u00fcgbar","datePublished":"2020-01-22T07:57:46+00:00","dateModified":"2020-01-22T08:02:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/"},"wordCount":259,"commentCount":3,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341.png","articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/","url":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/","name":"Windows 10 1909 per Windows Update f\u00fcr weitere Ger\u00e4te mit Windows 10 1809 verf\u00fcgbar - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341.png","datePublished":"2020-01-22T07:57:46+00:00","dateModified":"2020-01-22T08:02:05+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341.png","width":500,"height":341},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2020\/01\/22\/windows-10-1909-per-windows-update-fuer-weitere-geraete-mit-windows-10-1809-verfuegbar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Windows 10 1909 per Windows Update f\u00fcr weitere Ger\u00e4te mit Windows 10 1809 verf\u00fcgbar"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/november-update-2019-by-geralt-500x341.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/133261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=133261"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/133261\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/130012"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=133261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=133261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=133261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}