{"id":13280,"date":"2013-10-11T15:13:36","date_gmt":"2013-10-11T13:13:36","guid":{"rendered":"http:\/\/www.deskmodder.de\/blog\/?p=13280"},"modified":"2013-10-11T15:13:36","modified_gmt":"2013-10-11T13:13:36","slug":"vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/","title":{"rendered":"Vorstellung des &#8222;HTC One Max&#8220; wird auf lustige Art &#038; Weise beworben"},"content":{"rendered":"<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3.png\" rel=\"lightbox[13280]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-13281\" alt=\"Bildschirmfoto\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3-150x43.png\" width=\"150\" height=\"43\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3-150x43.png 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3-500x143.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3.png 594w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Ich mach es kurz, nachdem ich ja heute zum HTC One MAx schon etwas geschrieben hatte.<\/p>\n<p>Es gibt die ersten Werbungen f\u00fcr die anstehende Pr\u00e4sentation des gro\u00dfen Bruders des HTC One. Hier bedient sich HTC der Cartoon-Figuren der &#8222;3 Amigos&#8220;. 3 Amogis = HTC One, HTC One Mini und HTC One Max.<\/p>\n<p>Im offiziellen HTC Blog wurde die Ank\u00fcndigung ver\u00f6ffentlicht und in der n\u00e4chsten Woche soll die Pr\u00e4sentation dann auch erfolgen.<\/p>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/great-trios-in-history-730x3630.jpg\" rel=\"lightbox[13280]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-13282\" alt=\"great-trios-in-history-730x3630\" src=\"http:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/great-trios-in-history-730x3630.jpg\" width=\"700\" height=\"3481\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/great-trios-in-history-730x3630.jpg 700w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/great-trios-in-history-730x3630-30x150.jpg 30w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich mach es kurz, nachdem ich ja heute zum HTC One MAx schon etwas geschrieben hatte. Es gibt die ersten Werbungen f\u00fcr die anstehende Pr\u00e4sentation des gro\u00dfen Bruders des HTC One. Hier bedient sich HTC der Cartoon-Figuren der &#8222;3 Amigos&#8220;.&hellip; <\/p>\n","protected":false},"author":1462,"featured_media":13281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286,231],"tags":[2246],"class_list":["post-13280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","category-mobile","tag-htc-one-max"],"wp_featured_image":{"id":13281,"alt_text":"","description":"","media_type":"image","media_details":{"width":594,"height":171,"file":"2013\/10\/Bildschirmfoto3.png","sizes":{"thumbnail":{"file":"Bildschirmfoto3-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3-150x150.png"},"medium":{"file":"Bildschirmfoto3-150x43.png","width":150,"height":43,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3-150x43.png"},"large":{"file":"Bildschirmfoto3-500x143.png","width":500,"height":143,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3-500x143.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":13280,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3.png"},"commentcount":0,"wp_comments":[],"wp_author":{"id":null,"name":null,"description":null,"author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g"}},"cld_nonce":"d8513d7dba","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vorstellung des &quot;HTC One Max&quot; wird auf lustige Art &amp; Weise beworben - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vorstellung des &quot;HTC One Max&quot; wird auf lustige Art &amp; Weise beworben\" \/>\n<meta property=\"og:description\" content=\"Ich mach es kurz, nachdem ich ja heute zum HTC One MAx schon etwas geschrieben hatte. Es gibt die ersten Werbungen f\u00fcr die anstehende Pr\u00e4sentation des gro\u00dfen Bruders des HTC One. Hier bedient sich HTC der Cartoon-Figuren der &#8222;3 Amigos&#8220;.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-11T13:13:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"594\" \/>\n\t<meta property=\"og:image:height\" content=\"171\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Vorstellung des &#8222;HTC One Max&#8220; wird auf lustige Art &#038; Weise beworben\",\"datePublished\":\"2013-10-11T13:13:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/\"},\"wordCount\":87,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/Bildschirmfoto3.png\",\"keywords\":[\"HTC One Max\"],\"articleSection\":{\"1\":\"Hardware\",\"2\":\"Mobile\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/#respond\"]}],\"copyrightYear\":\"2013\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/\",\"name\":\"Vorstellung des \\\"HTC One Max\\\" wird auf lustige Art & Weise beworben - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/Bildschirmfoto3.png\",\"datePublished\":\"2013-10-11T13:13:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/Bildschirmfoto3.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/Bildschirmfoto3.png\",\"width\":594,\"height\":171},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2013\\\/10\\\/11\\\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vorstellung des &#8222;HTC One Max&#8220; wird auf lustige Art &#038; Weise beworben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vorstellung des \"HTC One Max\" wird auf lustige Art & Weise beworben - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/","og_locale":"de_DE","og_type":"article","og_title":"Vorstellung des \"HTC One Max\" wird auf lustige Art & Weise beworben","og_description":"Ich mach es kurz, nachdem ich ja heute zum HTC One MAx schon etwas geschrieben hatte. Es gibt die ersten Werbungen f\u00fcr die anstehende Pr\u00e4sentation des gro\u00dfen Bruders des HTC One. Hier bedient sich HTC der Cartoon-Figuren der &#8222;3 Amigos&#8220;.&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2013-10-11T13:13:36+00:00","og_image":[{"width":594,"height":171,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/"},"author":{"name":"","@id":""},"headline":"Vorstellung des &#8222;HTC One Max&#8220; wird auf lustige Art &#038; Weise beworben","datePublished":"2013-10-11T13:13:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/"},"wordCount":87,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3.png","keywords":["HTC One Max"],"articleSection":{"1":"Hardware","2":"Mobile"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/#respond"]}],"copyrightYear":"2013","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/","url":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/","name":"Vorstellung des \"HTC One Max\" wird auf lustige Art & Weise beworben - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3.png","datePublished":"2013-10-11T13:13:36+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3.png","width":594,"height":171},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2013\/10\/11\/vorstellung-des-htc-one-max-wird-auf-lustige-art-weise-beworben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Vorstellung des &#8222;HTC One Max&#8220; wird auf lustige Art &#038; Weise beworben"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"","url":"https:\/\/www.deskmodder.de\/blog\/author\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/10\/Bildschirmfoto3.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/13280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/1462"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=13280"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/13280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/13281"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=13280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=13280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=13280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}