{"id":131475,"date":"2019-12-10T19:47:55","date_gmt":"2019-12-10T18:47:55","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=131475"},"modified":"2019-12-10T19:47:55","modified_gmt":"2019-12-10T18:47:55","slug":"apple-veroeffentlicht-ios-13-3","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/","title":{"rendered":"Apple ver\u00f6ffentlicht iOS 13.3"},"content":{"rendered":"<p>Apple hat am Abend iOS 13.3 ver\u00f6ffentlicht &#8211; und auch dieses Update behebt in erste Linie wieder einige der &#8222;Kinderkrankheiten&#8220; von iOS 13 (siehe lange Liste unten). Mal sehen, ob die Mail-App jetzt anst\u00e4ndig l\u00e4uft. Neu sind zudem einige Einstellungen bei der Kindersicherung sowie &#8222;Weiterlesen&#8220;-Links in der Aktien-App.<\/p>\n<p>Bei mir wird das Update mit einer Downloadgr\u00f6\u00dfe von 320,3 MB angegeben. Im Vergleich zu den letzten Updates ist es damit deutlich gr\u00f6\u00dfer. Wie immer braucht ihr f\u00fcr die Installation mindestens 50% Akku oder ein angeschlossenes Netzkabel.<\/p>\n<h3>Changelog iOS 13.3 f\u00fcr iPhone, iPod und iPod touch<\/h3>\n<p class=\"plain\">iOS 13.3 enth\u00e4lt Verbesserungen, Fehlerbehebungen und zus\u00e4tzliche Kindersicherungseinstellungen f\u00fcr \u201eBildschirmzeit\u201c.<\/p>\n<p class=\"title\"><b>Bildschirmzeit<\/b><\/p>\n<ul>\n<li class=\"bullet\">Neue Kindersicherungseinstellungen mit weiteren Kommunikationslimits, die steuern, mit wem Kinder per FaceTime, \u201eNachrichten\u201c oder dem Telefon Kontakt aufnehmen k\u00f6nnen<\/li>\n<li class=\"bullet\">Eine Kontaktliste f\u00fcr Kinder, mit der Erziehungsberechtigte die Kontakte verwalten k\u00f6nnen, die auf dem Ger\u00e4t des Kindes angezeigt werden<\/li>\n<\/ul>\n<p class=\"title\"><b>App \u201eAktien\u201c<\/b><\/p>\n<ul>\n<li class=\"bullet\">Mithilfe von Links zu \u00e4hnlichen Storys oder weiteren Storys der selben Ver\u00f6ffentlichung weiterlesen<\/li>\n<\/ul>\n<p class=\"plain\"><b>Dieses Update enth\u00e4lt zudem Fehlerbehebungen und weitere Verbesserungen. Dieses Update:<\/b><\/p>\n<ul>\n<li class=\"bullet\">Erm\u00f6glicht das Erstellen von neuen Clips beim K\u00fcrzen von Videos in \u201eFotos\u201c<\/li>\n<li class=\"bullet\">F\u00fcgt Unterst\u00fctzung f\u00fcr FIDO2-kompatible NFC-, USB- und Lightning-Sicherheitsschl\u00fcssel in Safari hinzu<\/li>\n<li class=\"bullet\">Behebt Probleme in Mail, die das Laden neuer E-Mails verhindern k\u00f6nnen<\/li>\n<li class=\"bullet\">Korrigiert ein Problem, bei dem E-Mails in Gmail-Accounts nicht gel\u00f6scht werden k\u00f6nnen<\/li>\n<li class=\"bullet\">L\u00f6st Probleme, bei denen bei Exchange-Accounts in E-Mails inkorrekte Zeichen angezeigt oder gesendete E-Mails dupliziert werden k\u00f6nnen<\/li>\n<li class=\"bullet\">Behebt ein Problem, bei dem sich der Cursor nach l\u00e4ngerem Dr\u00fccken der Leertaste m\u00f6glicherweise nicht mehr bewegt<\/li>\n<li class=\"bullet\">Korrigiert ein Problem, bei dem Bildschirmfotos nach dem Senden \u00fcber \u201eNachrichten\u201c unscharf erscheinen k\u00f6nnen<\/li>\n<li class=\"bullet\">L\u00f6st ein Problem, bei dem Zuschnitt oder Anmerkungen bei Bildschirmfotos nicht in \u201eFotos\u201c gesichert werden<\/li>\n<li class=\"bullet\">Behebt ein Problem, bei dem Sprachmemo-Aufnahmen nicht mit anderen Audio-Apps geteilt werden k\u00f6nnen<\/li>\n<li class=\"bullet\">Korrigiert ein Problem, bei dem das Kennzeichen der App \u201eTelefon\u201c f\u00fcr verpasste Anrufe m\u00f6glicherweise nicht entfernt wird<\/li>\n<li class=\"bullet\">L\u00f6st ein Problem, bei dem die Einstellung \u201eMobile Daten\u201c f\u00e4lschlicherweise als \u201eAus\u201c angezeigt wird<\/li>\n<li class=\"bullet\">Behebt ein Problem, bei dem der Dunkelmodus nicht ausgeschaltet wird, wenn \u201eUmkehren &#8211; Intelligent\u201c aktiviert ist<\/li>\n<li class=\"bullet\">Korrigiert ein Problem, bei dem einige kabellose Ladeger\u00e4te unerwartet langsam laden<\/li>\n<\/ul>\n<p class=\"plain\">Informationen zu den Sicherheitsinhalten von Apple-Softwareupdates findest du unter:<\/p>\n<p class=\"plain\">https:\/\/support.apple.com\/kb\/HT201222<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apple hat am Abend iOS 13.3 ver\u00f6ffentlicht &#8211; und auch dieses Update behebt in erste Linie wieder einige der &#8222;Kinderkrankheiten&#8220; von iOS 13 (siehe lange Liste unten). Mal sehen, ob die Mail-App jetzt anst\u00e4ndig l\u00e4uft. Neu sind zudem einige Einstellungen&hellip; <\/p>\n","protected":false},"author":1525,"featured_media":126834,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[232],"tags":[5247,66844,3347,104],"class_list":["post-131475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ios","tag-changelog","tag-ios-13-3","tag-kindersicherung","tag-update"],"wp_featured_image":{"id":126834,"alt_text":"","description":"","media_type":"image","media_details":{"width":2880,"height":1568,"file":"2019\/09\/ios-13.png","sizes":{"thumbnail":{"file":"ios-13-306x167.png","width":306,"height":167,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-306x167.png"},"medium":{"file":"ios-13-500x272.png","width":500,"height":272,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-500x272.png"},"large":{"file":"ios-13-810x441.png","width":810,"height":441,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-810x441.png"},"wp_review_large":{"file":"ios-13-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-320x200.png"},"wp_review_small":{"file":"ios-13-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-65x65.png"},"blog-large":{"file":"ios-13-642x300.png","width":642,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-642x300.png"},"blog-medium":{"file":"ios-13-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-306x205.png"},"recent-thumb":{"file":"ios-13-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-350x316.png"},"service-featured":{"file":"ios-13-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-600x330.png"},"wp_rp_thumbnail":{"file":"ios-13-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":126833,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13.png"},"commentcount":3,"wp_comments":[{"id":119963,"parent":0,"author":0,"author_name":"Dominik Plangg","author_email":"plangg@yahoo.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/db7b7631053fa756d7ad0a7c008de3712da40744aff6590b633f82930c66a104?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/db7b7631053fa756d7ad0a7c008de3712da40744aff6590b633f82930c66a104?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/db7b7631053fa756d7ad0a7c008de3712da40744aff6590b633f82930c66a104?s=96&d=mm&r=g"},"date":"2019-12-10T19:55:21","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ist der l\u00e4stige Safari Bug nun endlich behoben?<\/p>\n"},"status":"1"},{"id":120206,"parent":119963,"author":0,"author_name":"Iphoner","author_email":"iphoner@byom.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc855845776668d5a5e24a71a36556a15bd56dfb73aa488dda79ad5629ec67ec?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc855845776668d5a5e24a71a36556a15bd56dfb73aa488dda79ad5629ec67ec?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc855845776668d5a5e24a71a36556a15bd56dfb73aa488dda79ad5629ec67ec?s=96&d=mm&r=g"},"date":"2019-12-11T13:06:06","cld_nonce":"b6d6726996","content":{"rendered":"<p>Dank deiner sehr ausf\u00fchrlichen Beschreibung, sollte jedem klar sein welchen Bug du meinst. Danke dir!<br \/>\nBtw. hatte keine Bugs in Verbindung mit Safari in iOS 13.2<\/p>\n"},"status":"1"},{"id":121756,"parent":0,"author":0,"author_name":"Axel60","author_email":"axel.schmeissner@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9435a43dd49215dd8ef999063d52c6140b21abd9435bf57f79c6cfc273fe52c3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9435a43dd49215dd8ef999063d52c6140b21abd9435bf57f79c6cfc273fe52c3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9435a43dd49215dd8ef999063d52c6140b21abd9435bf57f79c6cfc273fe52c3?s=96&d=mm&r=g"},"date":"2019-12-20T14:35:56","cld_nonce":"b6d6726996","content":{"rendered":"<p>Kinderkrankheiten?<\/p>\n"},"status":"1"}],"wp_author":{"id":1525,"name":"W8U","description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Apple ver\u00f6ffentlicht iOS 13.3 - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apple ver\u00f6ffentlicht iOS 13.3\" \/>\n<meta property=\"og:description\" content=\"Apple hat am Abend iOS 13.3 ver\u00f6ffentlicht &#8211; und auch dieses Update behebt in erste Linie wieder einige der &#8222;Kinderkrankheiten&#8220; von iOS 13 (siehe lange Liste unten). Mal sehen, ob die Mail-App jetzt anst\u00e4ndig l\u00e4uft. Neu sind zudem einige Einstellungen&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-10T18:47:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-810x441.png\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"W8U\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/\"},\"author\":{\"name\":\"W8U\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\"},\"headline\":\"Apple ver\u00f6ffentlicht iOS 13.3\",\"datePublished\":\"2019-12-10T18:47:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/\"},\"wordCount\":401,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ios-13.png\",\"keywords\":[\"changelog\",\"iOS 13.3\",\"Kindersicherung\",\"Update\"],\"articleSection\":[\"iOS\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/\",\"name\":\"Apple ver\u00f6ffentlicht iOS 13.3 - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ios-13.png\",\"datePublished\":\"2019-12-10T18:47:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ios-13.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ios-13.png\",\"width\":2880,\"height\":1568},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/12\\\/10\\\/apple-veroeffentlicht-ios-13-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apple ver\u00f6ffentlicht iOS 13.3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\",\"name\":\"W8U\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"caption\":\"W8U\"},\"description\":\"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/w8u\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Apple ver\u00f6ffentlicht iOS 13.3 - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/","og_locale":"de_DE","og_type":"article","og_title":"Apple ver\u00f6ffentlicht iOS 13.3","og_description":"Apple hat am Abend iOS 13.3 ver\u00f6ffentlicht &#8211; und auch dieses Update behebt in erste Linie wieder einige der &#8222;Kinderkrankheiten&#8220; von iOS 13 (siehe lange Liste unten). Mal sehen, ob die Mail-App jetzt anst\u00e4ndig l\u00e4uft. Neu sind zudem einige Einstellungen&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2019-12-10T18:47:55+00:00","og_image":[{"width":810,"height":441,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-810x441.png","type":"image\/png"}],"author":"W8U","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/"},"author":{"name":"W8U","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469"},"headline":"Apple ver\u00f6ffentlicht iOS 13.3","datePublished":"2019-12-10T18:47:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/"},"wordCount":401,"commentCount":3,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13.png","keywords":["changelog","iOS 13.3","Kindersicherung","Update"],"articleSection":["iOS"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/","url":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/","name":"Apple ver\u00f6ffentlicht iOS 13.3 - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13.png","datePublished":"2019-12-10T18:47:55+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13.png","width":2880,"height":1568},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/12\/10\/apple-veroeffentlicht-ios-13-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Apple ver\u00f6ffentlicht iOS 13.3"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469","name":"W8U","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","caption":"W8U"},"description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","url":"https:\/\/www.deskmodder.de\/blog\/author\/w8u\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/131475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/1525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=131475"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/131475\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/126834"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=131475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=131475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=131475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}