{"id":130658,"date":"2019-11-26T10:33:18","date_gmt":"2019-11-26T09:33:18","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=130658"},"modified":"2019-11-26T10:33:18","modified_gmt":"2019-11-26T09:33:18","slug":"microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/","title":{"rendered":"Microsoft Edge: PWAs werden wie eine native App erscheinen"},"content":{"rendered":"<p>Microsoft bastelt an den PWAs (Progressive Web Apps) und verbessert die Integrit\u00e4t und die Funktionalit\u00e4t. Derzeit erscheint eine PWA im Task-Manager als Microsoft Edge Prozess. Man kann also nicht genau erkennen, welcher Prozess nun f\u00fcr die PWA zust\u00e4ndig ist.<\/p>\n<p>Das will man nun verbessern. So wie im Bild zu sehen, erscheint die gestartete PWA dann mit dem korrekten Namen der Webseite. Im aktuellen Microsoft Edge 80.0.344.0 (Canary) ist auch noch eine neue Flag hinzugekommen. <a href=\"edge:\/\/flags\/#edge-webapp-identity-proxy\" rel=\"noopener noreferrer\" target=\"_blank\">edge:\/\/flags\/#edge-webapp-identity-proxy<\/a>. Diese Flag ist f\u00fcr die Insider Version 19022 und h\u00f6her interessant. Denn Microsoft will die PWAs eher als eine native App arbeiten, die st\u00e4rker in die Windows Shell integriert wird.<\/p>\n<div id='gallery-1' class='gallery galleryid-130658 gallery-columns-2 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg' rel=\"lightbox[130658]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"203\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-306x203.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-306x203.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-500x331.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-810x537.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg 1388w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-002.jpg' rel=\"lightbox[130658]\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"169\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-002-306x169.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-002-306x169.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-002-500x276.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-002-810x448.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-002-600x330.jpg 600w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-002.jpg 1114w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Das bedeutet zum Beispiel, dass man dann in der Taskleiste auch eine Jumplist erh\u00e4lt. Badges (Benachrichtigungen) in der Taskleiste werden so m\u00f6glich Auch eine einfache Deinstallation wird dann m\u00f6glich sein und vieles mehr. Noch ist dies Zukunftsmusik. Aber da Microsoft im Moment verst\u00e4rkt an PWAs arbeitet, so zum Beispiel Outlook Online als PWA d\u00fcrfte es nicht lange dauern, bis diese Funktionen m\u00f6glich sein werden.<\/p>\n<div class=\"quellenzeile\"><div class=\"quelle\">Quelle: <a href=\"https:\/\/techcommunity.microsoft.com\/t5\/Discussions\/Need-more-info-about-Web-Apps-Identity-Proxy\/m-p\/1032448#M17878\" rel=\"noopener noreferrer\" target=\"_blank\">techcommunity<\/a><\/div> <div class=\"viaquelle\">via: <a href=\"https:\/\/techdows.com\/2019\/11\/microsoft-to-make-edge-web-apps-more-native-in-windows-10.html\" rel=\"noopener noreferrer\" target=\"_blank\">techdows<\/a><\/div><\/div>\n<h3>Info und Download<\/h3>\n<ul>\n<li>Offline-Installer Dev Enterprise <a href=\"https:\/\/www.microsoftedgeinsider.com\/de-de\/enterprise\" target=\"_blank\" rel=\"noopener noreferrer\">microsoftedgeinsider.com\/de-de\/enterprise<\/a><\/li>\n<li><strong>Stable Version:<\/strong> <a href=\"https:\/\/go.microsoft.com\/fwlink\/?linkid=2069324&amp;Channel=Stable&amp;language=de\" target=\"_blank\" rel=\"noopener noreferrer\">go.microsoft.com\/Channel=Stable<\/a><\/li>\n<li>Die weiteren Links<\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/\" target=\"_blank\" rel=\"noopener noreferrer\">microsoftedgeinsider.com\/download\/win10<\/a><\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win8dot1\" target=\"_blank\" rel=\"noopener noreferrer\">microsoftedgeinsider.com\/download\/platform=win8dot1<\/a><\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win8\" target=\"_blank\" rel=\"noopener noreferrer\">microsoftedgeinsider.com\/download\/platform=win8<\/a><\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=win7\" target=\"_blank\" rel=\"noopener noreferrer\">microsoftedgeinsider.com\/download\/platform=win7<\/a><\/li>\n<li><strong>Die portablen Versionen<\/strong>: <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/05\/27\/portabler-microsoft-edge-chromium-updater-fuer-canary-developer-beta-und-spaeter-auch-der-finale-edge\/\" target=\"_blank\" rel=\"noopener noreferrer\">Portable Edge Updater<\/a><\/li>\n<li>Und f\u00fcr die Macs:<\/li>\n<li><a href=\"https:\/\/www.microsoftedgeinsider.com\/en-us\/download\/?platform=macos\" target=\"_blank\" rel=\"noopener noreferrer\">microsoftedgeinsider.com\/download\/platform=macos<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft bastelt an den PWAs (Progressive Web Apps) und verbessert die Integrit\u00e4t und die Funktionalit\u00e4t. Derzeit erscheint eine PWA im Task-Manager als Microsoft Edge Prozess. Man kann also nicht genau erkennen, welcher Prozess nun f\u00fcr die PWA zust\u00e4ndig ist. Das&hellip; <\/p>\n","protected":false},"author":134,"featured_media":130660,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[166,2689],"tags":[75,8501,66192,27844,66193],"class_list":["post-130658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-browser","category-windows-10","tag-chromium","tag-microsoft-edge","tag-native-app","tag-pwa","tag-shell-integration"],"wp_featured_image":{"id":130660,"alt_text":"","description":"","media_type":"image","media_details":{"width":1388,"height":920,"file":"2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg","sizes":{"medium":{"file":"microsoft-edge-pwa-native-integration-in-die-shell-001-500x331.jpg","width":500,"height":331,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-500x331.jpg"},"large":{"file":"microsoft-edge-pwa-native-integration-in-die-shell-001-810x537.jpg","width":810,"height":537,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-810x537.jpg"},"thumbnail":{"file":"microsoft-edge-pwa-native-integration-in-die-shell-001-306x203.jpg","width":306,"height":203,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-306x203.jpg"},"wp_review_large":{"file":"microsoft-edge-pwa-native-integration-in-die-shell-001-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-320x200.jpg"},"wp_review_small":{"file":"microsoft-edge-pwa-native-integration-in-die-shell-001-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-65x65.jpg"},"blog-large":{"file":"microsoft-edge-pwa-native-integration-in-die-shell-001-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-642x300.jpg"},"blog-medium":{"file":"microsoft-edge-pwa-native-integration-in-die-shell-001-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-306x205.jpg"},"recent-thumb":{"file":"microsoft-edge-pwa-native-integration-in-die-shell-001-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-350x316.jpg"},"service-featured":{"file":"microsoft-edge-pwa-native-integration-in-die-shell-001-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-600x330.jpg"},"wp_rp_thumbnail":{"file":"microsoft-edge-pwa-native-integration-in-die-shell-001-50x50.jpg","width":50,"height":50,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001-50x50.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":130658,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Microsoft Edge: PWAs werden wie eine native App erscheinen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft Edge: PWAs werden wie eine native App erscheinen\" \/>\n<meta property=\"og:description\" content=\"Microsoft bastelt an den PWAs (Progressive Web Apps) und verbessert die Integrit\u00e4t und die Funktionalit\u00e4t. Derzeit erscheint eine PWA im Task-Manager als Microsoft Edge Prozess. Man kann also nicht genau erkennen, welcher Prozess nun f\u00fcr die PWA zust\u00e4ndig ist. Das&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-26T09:33:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1388\" \/>\n\t<meta property=\"og:image:height\" content=\"920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Microsoft Edge: PWAs werden wie eine native App erscheinen\",\"datePublished\":\"2019-11-26T09:33:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/\"},\"wordCount\":262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg\",\"keywords\":[\"Chromium\",\"Microsoft Edge\",\"native APP\",\"PWA\",\"Shell Integration\"],\"articleSection\":[\"Browser\",\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/\",\"name\":\"Microsoft Edge: PWAs werden wie eine native App erscheinen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg\",\"datePublished\":\"2019-11-26T09:33:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg\",\"width\":1388,\"height\":920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/26\\\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft Edge: PWAs werden wie eine native App erscheinen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Microsoft Edge: PWAs werden wie eine native App erscheinen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/","og_locale":"de_DE","og_type":"article","og_title":"Microsoft Edge: PWAs werden wie eine native App erscheinen","og_description":"Microsoft bastelt an den PWAs (Progressive Web Apps) und verbessert die Integrit\u00e4t und die Funktionalit\u00e4t. Derzeit erscheint eine PWA im Task-Manager als Microsoft Edge Prozess. Man kann also nicht genau erkennen, welcher Prozess nun f\u00fcr die PWA zust\u00e4ndig ist. Das&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2019-11-26T09:33:18+00:00","og_image":[{"width":1388,"height":920,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Microsoft Edge: PWAs werden wie eine native App erscheinen","datePublished":"2019-11-26T09:33:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/"},"wordCount":262,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg","keywords":["Chromium","Microsoft Edge","native APP","PWA","Shell Integration"],"articleSection":["Browser","Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/","url":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/","name":"Microsoft Edge: PWAs werden wie eine native App erscheinen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg","datePublished":"2019-11-26T09:33:18+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg","width":1388,"height":920},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/26\/microsoft-edge-pwas-werden-wie-eine-native-app-erscheinen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Microsoft Edge: PWAs werden wie eine native App erscheinen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/11\/microsoft-edge-pwa-native-integration-in-die-shell-001.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/130658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=130658"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/130658\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/130660"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=130658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=130658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=130658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}