{"id":130143,"date":"2019-11-15T18:38:54","date_gmt":"2019-11-15T17:38:54","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=130143"},"modified":"2019-11-15T18:38:54","modified_gmt":"2019-11-15T17:38:54","slug":"11-d-netz-vodafone-netz-bekommt-lte","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/","title":{"rendered":"1&#038;1: D-Netz (Vodafone Netz) bekommt LTE"},"content":{"rendered":"<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover.jpg\" rel=\"lightbox[130143]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-67655\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-500x272.jpg\" alt=\"\" width=\"500\" height=\"272\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-500x272.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-306x166.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-810x440.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover.jpg 1600w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Pers\u00f6nlich habe ich immer mal wieder mit dem Gedanken gespielt meinen Mobilfunkvertrag bei 1&amp;1 abzuschlie\u00dfen. F\u00fcr mich kam hier immer nur der D-Netz Tarif in Frage. Ausschlie\u00dfungsgrund war aber bislang, dass man im D-Netz kein LTE bekommen hat. Nun \u00e4ndert sich das aber. Denn ENDLICH (muss man schon so deutlich sagen) zieht 1&amp;1 nach und wird ab kommender Woche LTE im D-Netz mit bis zu 50 Mbit\/s bieten.<\/p>\n<p>Bestandskunden von 1&amp;1, welche einen D-Netz Tarif nutzen, werden automatisch und kostenlos LTE erhalten. Hier braucht man selbst nichts anpassen.<\/p>\n<div class=\"viaquelle\">via: <a href=\"https:\/\/www.mobiflip.de\/shortnews\/1und1-lte-vodafone\/\" rel=\"noopener noreferrer\" target=\"_blank\">Mobiflip<\/a> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pers\u00f6nlich habe ich immer mal wieder mit dem Gedanken gespielt meinen Mobilfunkvertrag bei 1&amp;1 abzuschlie\u00dfen. F\u00fcr mich kam hier immer nur der D-Netz Tarif in Frage. Ausschlie\u00dfungsgrund war aber bislang, dass man im D-Netz kein LTE bekommen hat. Nun \u00e4ndert&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":67655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,231],"tags":[65757],"class_list":["post-130143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-mobile","tag-1-und-1-d-netz-lte"],"wp_featured_image":{"id":67655,"alt_text":"","description":"","media_type":"image","media_details":{"width":1600,"height":869,"file":"2016\/07\/1und1-cover.jpg","sizes":{"thumbnail":{"file":"1und1-cover-306x166.jpg","width":306,"height":166,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-306x166.jpg"},"medium":{"file":"1und1-cover-500x272.jpg","width":500,"height":272,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-500x272.jpg"},"large":{"file":"1und1-cover-810x440.jpg","width":810,"height":440,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-810x440.jpg"},"wp_review_large":{"file":"1und1-cover-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-320x200.jpg"},"wp_review_small":{"file":"1und1-cover-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-65x65.jpg"},"blog-large":{"file":"1und1-cover-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-642x300.jpg"},"blog-medium":{"file":"1und1-cover-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-306x205.jpg"},"recent-thumb":{"file":"1und1-cover-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-350x316.jpg"},"service-featured":{"file":"1und1-cover-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-600x330.jpg"},"wp_rp_thumbnail":{"file":"1und1-cover-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":67650,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover.jpg"},"commentcount":22,"wp_comments":[{"id":116450,"parent":0,"author":0,"author_name":"Meister Eda","author_email":"edamaeister@wirkubk.kg","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b00c56f20a2a66f12b02d0653fbeeed0a2121d1176923fe927498ca5ee90a612?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b00c56f20a2a66f12b02d0653fbeeed0a2121d1176923fe927498ca5ee90a612?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b00c56f20a2a66f12b02d0653fbeeed0a2121d1176923fe927498ca5ee90a612?s=96&d=mm&r=g"},"date":"2019-11-15T18:46:52","cld_nonce":"b6d6726996","content":{"rendered":"<p>Man sollte vielleicht anmerken das dieses Schrott Unternehmen !&amp;! kein eigenes Netz hat sondern nur Reseller (Wiederverk\u00e4ufer) ist, also ist es ratsamer gleich zu T-Mobil zu gehen dem Original.<\/p>\n"},"status":"1"},{"id":116451,"parent":0,"author":4980,"author_name":"BillyBoy66","author_email":"willy.pilgrim@freenet.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/cacd1f982c7bbd5a857391e5dfc015aa663162506f1d4b1c321abe0152bd5616?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/cacd1f982c7bbd5a857391e5dfc015aa663162506f1d4b1c321abe0152bd5616?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/cacd1f982c7bbd5a857391e5dfc015aa663162506f1d4b1c321abe0152bd5616?s=96&d=mm&r=g"},"date":"2019-11-15T18:47:28","cld_nonce":"b6d6726996","content":{"rendered":"<p>Vielleicht nicht bei 1&amp;1, aber LTE im D1-Netz gibt es schon seit einigen Monaten!<br \/>\nAlso keine News, sondern einfach nur Werbung f\u00fcr 1&amp;1 &#8230;<\/p>\n"},"status":"1"},{"id":116455,"parent":116451,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2019-11-15T19:03:13","cld_nonce":"b6d6726996","content":{"rendered":"<p>Und auch hier:<\/p>\n<p>@BillyBoy66<\/p>\n<p>Bitte informiere dich erst einmal \u00fcber die Begriffe Werbung und Information (News)<br \/>\nDanke.<\/p>\n<p>Wenn wir hier einen Werbeartikel haben, dann kennzeichnen wir den auch.<\/p>\n"},"status":"1"},{"id":116458,"parent":116455,"author":4980,"author_name":"BillyBoy66","author_email":"willy.pilgrim@freenet.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/cacd1f982c7bbd5a857391e5dfc015aa663162506f1d4b1c321abe0152bd5616?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/cacd1f982c7bbd5a857391e5dfc015aa663162506f1d4b1c321abe0152bd5616?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/cacd1f982c7bbd5a857391e5dfc015aa663162506f1d4b1c321abe0152bd5616?s=96&d=mm&r=g"},"date":"2019-11-15T19:14:08","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ich sehe das jetzt nicht als Zurechtweisung, sondern als Kritik.<br \/>\nDeswegen danke f\u00fcr den Hinweis, bin da wohl etwas \u00fcber die Str\u00e4nge geschlagen &#8230;<\/p>\n"},"status":"1"},{"id":116459,"parent":0,"author":5437,"author_name":"Xeraan","author_email":"thomas.ulloth@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d29f453d27a067cb6fcaf28d43db23cae741e48e8b789758805480812b21cdd9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d29f453d27a067cb6fcaf28d43db23cae741e48e8b789758805480812b21cdd9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d29f453d27a067cb6fcaf28d43db23cae741e48e8b789758805480812b21cdd9?s=96&d=mm&r=g"},"date":"2019-11-15T19:17:02","cld_nonce":"b6d6726996","content":{"rendered":"<p>Es gibt auch zufriedene 1&amp;1 Kunden: Mich zum Beispiel und ich habe mich \u00fcber diese News gefreut.<br \/>\nVielen Dank f\u00fcr deine M\u00fchen @moinmoin<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":116477,"parent":0,"author":0,"author_name":"Konrad","author_email":"konrad.sauerbier@netdolk.re","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1a6985e4bd7dd5bb294211099829bf55d7ffae4535433182c88054da596e1337?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1a6985e4bd7dd5bb294211099829bf55d7ffae4535433182c88054da596e1337?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1a6985e4bd7dd5bb294211099829bf55d7ffae4535433182c88054da596e1337?s=96&d=mm&r=g"},"date":"2019-11-15T19:51:19","cld_nonce":"b6d6726996","content":{"rendered":"<p>Naja 50 mbps. Lass Dich \u00fcberraschen. Bei einer Testmessung hatte ich mal 100 mbps. Allerdings war ich da der einzige Nutzer in der Zelle (20 MHz Frequenzblock) &#8211; und stand direkt vor dem eNodeB. Am Zellrand, kurz vor dem Handoff zur Nachbarzelle, da waren es nur noch 5 mbps- aufgrund des schw\u00e4cheren und gest\u00f6rten Signals ging der Rest vermutlich f\u00fcr die Forward Error Correction drauf. Auch beim Handoff war ich der einzige Nutzer in der Zelle.<\/p>\n"},"status":"1"},{"id":116499,"parent":0,"author":0,"author_name":"Wolfgang D.","author_email":"wolfgang362@habmalnefrage.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=96&d=mm&r=g"},"date":"2019-11-15T22:28:46","cld_nonce":"b6d6726996","content":{"rendered":"<p>D-Netz ja gerne, aber ganz sicher nicht das von Vodafone. Scheint den Anbietern ebenfalls peinlich zu sein, so wie sie immer den wahren Netzbetreiber verschleiern.<\/p>\n"},"status":"1"},{"id":116500,"parent":116499,"author":0,"author_name":"Wolfgang D.","author_email":"wolfgang362@habmalnefrage.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8c2cdcb93bad312838c0c22ec8fe38476c9f1fe8d48edc19d15fa8adfbe95f3f?s=96&d=mm&r=g"},"date":"2019-11-15T22:35:03","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bin dann mal gespannt, wann 1&amp;1 auf meine kostenlose SIM das LTE aufschaltet &#8211; 100MB inklusive Daten wollen schliesslich verbraucht sein. Ich finde 1&amp;1 mittlerweile \u00fcbrigens richtig gut, die haben in punkto Leistungen und Support unglaublich aufgeholt.<\/p>\n"},"status":"1"},{"id":116502,"parent":116500,"author":0,"author_name":"Chris","author_email":"chris.h97@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c360576d398e133786efbb528e187955c4a829d5b498b0255f4ed45eeb436aa8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c360576d398e133786efbb528e187955c4a829d5b498b0255f4ed45eeb436aa8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c360576d398e133786efbb528e187955c4a829d5b498b0255f4ed45eeb436aa8?s=96&d=mm&r=g"},"date":"2019-11-15T23:01:39","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bin auch schon gespannt ob 1&amp;1 die kostenlosen 100 MB SIM Karten ebenso umstellt. Das w\u00e4re schon sehr \u00fcberraschend, wenn das LTE Netz wirklich so unkompliziert und ohne Aufpreis freigeschaltet wird.<\/p>\n"},"status":"1"},{"id":116506,"parent":116450,"author":0,"author_name":"Hans","author_email":"Hans@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/645255c772551f3a36cd81ee2bc819152371e184d2608cc08d4fccb583d7a9f3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/645255c772551f3a36cd81ee2bc819152371e184d2608cc08d4fccb583d7a9f3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/645255c772551f3a36cd81ee2bc819152371e184d2608cc08d4fccb583d7a9f3?s=96&d=mm&r=g"},"date":"2019-11-16T07:31:57","cld_nonce":"b6d6726996","content":{"rendered":"<p>Seit wann nutzt 1&amp;1 das Netz der Telekom?<\/p>\n"},"status":"1"},{"id":116509,"parent":0,"author":3634,"author_name":"m0skito","author_email":"info@tinogottschalk.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3c90a63b17a4d5ba8774b079239cbe27f063554238465ac09f42f233222df61f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3c90a63b17a4d5ba8774b079239cbe27f063554238465ac09f42f233222df61f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3c90a63b17a4d5ba8774b079239cbe27f063554238465ac09f42f233222df61f?s=96&d=mm&r=g"},"date":"2019-11-16T08:03:38","cld_nonce":"b6d6726996","content":{"rendered":"<p>war mit 1und1 immer sehr zufrieden, aber finde die Preise sind im D2 Netz nicht mehr Konkurrenzf\u00e4hig. 65 Euro waren mir dann zu viel, bin dann zur Telekom und der Fullflat&#8230;.Habe ich mehr von auch wenn es 80 Euro kostet. Immerhin nicht begrenzt in Geschwindigkeit und Volumen.<\/p>\n"},"status":"1"},{"id":116513,"parent":0,"author":5400,"author_name":"AdiSimpson","author_email":"a.konarzewski@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1a303bfeca875129867b1a27dc3e4fe1de30acf9d65093d404e0bdc5365a52f5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1a303bfeca875129867b1a27dc3e4fe1de30acf9d65093d404e0bdc5365a52f5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1a303bfeca875129867b1a27dc3e4fe1de30acf9d65093d404e0bdc5365a52f5?s=96&d=mm&r=g"},"date":"2019-11-16T09:19:27","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hatte auch 1&amp;1, fand es immer komisch das trotz guten Netz Empfang kein Durchsatz vorhanden war, obwohl Leute von Vodafone keine Probleme hatten. Nachdem ich gek\u00fcndigt hatte bekam ich einen Anruf von 1&amp;1, da wurde mir best\u00e4tigt das Vodafone Kunden bei h\u00f6herer Netzauslastung Vorrang haben. Wollte keinen Vertrag bei Vodafone, habe deswegen Prepaid gew\u00e4hlt und bin gl\u00fccklich, Preis auch.<\/p>\n"},"status":"1"},{"id":116519,"parent":116500,"author":0,"author_name":"Christian","author_email":"superuser123@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8c35c6fec7eb3a7c76895e86352cd7b3fca488d9500a349ea9ca40cede1b76ad?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8c35c6fec7eb3a7c76895e86352cd7b3fca488d9500a349ea9ca40cede1b76ad?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8c35c6fec7eb3a7c76895e86352cd7b3fca488d9500a349ea9ca40cede1b76ad?s=96&d=mm&r=g"},"date":"2019-11-16T10:00:11","cld_nonce":"b6d6726996","content":{"rendered":"<p>Darauf bin ich auch sehr gespannt&#8230; ich nutze die 4 m\u00f6glichen kostenlosen SIM-Karten. Und wenn die 100 MB Datenvolumen auch l\u00e4cherlich wenig sind &#8211; LTE w\u00e4re manchmal doch ganz n\u00fctzlich, einfach aufgrund der schlechteren Verf\u00fcgbarkeit von 3G.<\/p>\n"},"status":"1"},{"id":116570,"parent":116450,"author":0,"author_name":"golem","author_email":"hkl@ruck.zuck.ru","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/03cfb7bf37217650cb3cb3c869e491c95b07cb5b749625f5ff8d689a836feca5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/03cfb7bf37217650cb3cb3c869e491c95b07cb5b749625f5ff8d689a836feca5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/03cfb7bf37217650cb3cb3c869e491c95b07cb5b749625f5ff8d689a836feca5?s=96&d=mm&r=g"},"date":"2019-11-16T19:02:48","cld_nonce":"b6d6726996","content":{"rendered":"<p>Als ich habe 1&amp;1 tarife \u00fcber web\/gmx.de abgeschlossen, der &#8222;Schrott&#8220; Reseller ist da mal einfach so 50% g\u00fcnstiger als wenn ich direkt zu D2\/O2 gehe. Noch absolut nie im Leben erh\u00e4lt man direkt beim Provider irgend etwas g\u00fcnstiger.<\/p>\n"},"status":"1"},{"id":116571,"parent":116519,"author":0,"author_name":"golem","author_email":"hkl@ruck.zuck.ru","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/03cfb7bf37217650cb3cb3c869e491c95b07cb5b749625f5ff8d689a836feca5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/03cfb7bf37217650cb3cb3c869e491c95b07cb5b749625f5ff8d689a836feca5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/03cfb7bf37217650cb3cb3c869e491c95b07cb5b749625f5ff8d689a836feca5?s=96&d=mm&r=g"},"date":"2019-11-16T19:06:59","cld_nonce":"b6d6726996","content":{"rendered":"<p>Bei aller liebe, wo bitte soll man LTE haben und dann aber kein 3G. Gibts aktuell einfach nicht PUNKT.<br \/>\nLTE Only Zellen gibts nicht PUNKT.<\/p>\n"},"status":"1"},{"id":116577,"parent":116519,"author":0,"author_name":"Felix aus Bayern","author_email":"phanosworld@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/21ba38322f37faf7804c52d9a0b9e147578ff4cf4b1912636bc618309bb541ce?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/21ba38322f37faf7804c52d9a0b9e147578ff4cf4b1912636bc618309bb541ce?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/21ba38322f37faf7804c52d9a0b9e147578ff4cf4b1912636bc618309bb541ce?s=96&d=mm&r=g"},"date":"2019-11-16T20:19:10","cld_nonce":"b6d6726996","content":{"rendered":"<p>Vielleicht auch ein Hinweis darauf, das in absehbarer Zeit mit der Abschaltung oder den R\u00fcckbau von 3G begonnen wird.<br \/>\nEs wird in Zukunft kein 2G, 3G, 4G und irgend wann mal 5G geben. 3G wird als erstes verschwinden.<\/p>\n"},"status":"1"},{"id":116579,"parent":116519,"author":0,"author_name":"Christian","author_email":"superuser123@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8c35c6fec7eb3a7c76895e86352cd7b3fca488d9500a349ea9ca40cede1b76ad?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8c35c6fec7eb3a7c76895e86352cd7b3fca488d9500a349ea9ca40cede1b76ad?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8c35c6fec7eb3a7c76895e86352cd7b3fca488d9500a349ea9ca40cede1b76ad?s=96&d=mm&r=g"},"date":"2019-11-16T20:48:03","cld_nonce":"b6d6726996","content":{"rendered":"<p>@golem du bist ja eine ganz schlaue Wurst&#8230; ist halt nur bl\u00f6d dass 3G oftmals sehr &#8222;\u00fcberlaufen&#8220; ist, so dass die praktische Verf\u00fcgbarkeit eben doch nicht so dolle ist, verglichen mit den zeitgleich verf\u00fcgbaren LTE.<\/p>\n"},"status":"1"},{"id":116581,"parent":116500,"author":0,"author_name":"Felix aus Bayern","author_email":"phanosworld@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/21ba38322f37faf7804c52d9a0b9e147578ff4cf4b1912636bc618309bb541ce?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/21ba38322f37faf7804c52d9a0b9e147578ff4cf4b1912636bc618309bb541ce?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/21ba38322f37faf7804c52d9a0b9e147578ff4cf4b1912636bc618309bb541ce?s=96&d=mm&r=g"},"date":"2019-11-16T21:06:43","cld_nonce":"b6d6726996","content":{"rendered":"<p>@golem<\/p>\n<p>Deine Aussage:<br \/>\n 3G. Gibts aktuell einfach nicht PUNKT.<br \/>\nLTE Only Zellen gibts nicht PUNKT. <\/p>\n<p>Entschuldige bitte, das ist v\u00f6lliger Unsinn.<br \/>\nGerade auf dem Land gibt es viele Basisstationen, die kein 3G (UMTS) k\u00f6nnen, die aber 4G (LTE) k\u00f6nnen.<br \/>\nVor allem Vodafone hat das gemacht, Grund daf\u00fcr, in Gegenden wo es kein DSL gibt, wollte Vodafone mit LTE 800 eine Internet Versorgung bereitstellen. Daf\u00fcr gab es von Vodafone auch eine eigene Box.<br \/>\nAnfangs war LTE 800 auch nur f\u00fcr die Internetversorgung per Box verf\u00fcgbar.<br \/>\nDie aller ersten Smartphones die LTE tauglich waren konnten kein LTE 800.<br \/>\nUnd wenn es auf dem Land eine Basisstation gab, die 3G konnte, wurde diese auf 4G umger\u00fcstet und 3G abgebaut. Also doch eine reine 4G Station.<\/p>\n"},"status":"1"},{"id":116595,"parent":116581,"author":0,"author_name":"Efu","author_email":"efu@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/2b95614bf3caab715c248979744df42b7625f558c76de1534bcd9b4a1163c0fd?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/2b95614bf3caab715c248979744df42b7625f558c76de1534bcd9b4a1163c0fd?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/2b95614bf3caab715c248979744df42b7625f558c76de1534bcd9b4a1163c0fd?s=96&d=mm&r=g"},"date":"2019-11-17T05:20:38","cld_nonce":"b6d6726996","content":{"rendered":"<p>Was f\u00fcr ein Schwachsinn!<\/p>\n"},"status":"1"},{"id":116597,"parent":116455,"author":0,"author_name":"Andreas","author_email":"andreas@kuropka.eu","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e0dcfe5cab115a95e05dfcaf88b187397a3b158f6f486180f18b1ad8d0bf9e6b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e0dcfe5cab115a95e05dfcaf88b187397a3b158f6f486180f18b1ad8d0bf9e6b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e0dcfe5cab115a95e05dfcaf88b187397a3b158f6f486180f18b1ad8d0bf9e6b?s=96&d=mm&r=g"},"date":"2019-11-17T07:58:33","cld_nonce":"b6d6726996","content":{"rendered":"<p>Im Ansatz hat er aber irgendwo recht.<\/p>\n<p>Die Quelle ist Information (News), der Artikel eher eine &#8222;Werbung&#8220; wie sie von Influencern auf Social Media geteilt werden.<\/p>\n<p>Das &#8222;ENDLICH (muss man schon so deutlich sagen)&#8220; ist schon lobpreisend.<\/p>\n"},"status":"1"},{"id":116598,"parent":116597,"author":1525,"author_name":"W8U","author_email":"windows-8-user@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"},"date":"2019-11-17T08:22:36","cld_nonce":"b6d6726996","content":{"rendered":"<p>Der Zusatz \u201eENDLICH (muss man schon so deutlich sagen)\u201c ist alles andere als lobpreisend. Eigentlich l\u00e4sst er 1&#038;1 richtig schlecht dastehen, weil sie erst im Jahr 2019 (!) mit LTE ankommen.<\/p>\n<p>Jeder dreht sich das doch hier so hin, wie es ihm Recht ist. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":116771,"parent":0,"author":0,"author_name":"woldofoldo","author_email":"woldofoldo@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/cca93a62ea51e01f27f000cbdc3b996a8fcb4a0b7715fe5dc30331d012b1967b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/cca93a62ea51e01f27f000cbdc3b996a8fcb4a0b7715fe5dc30331d012b1967b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/cca93a62ea51e01f27f000cbdc3b996a8fcb4a0b7715fe5dc30331d012b1967b?s=96&d=mm&r=g"},"date":"2019-11-21T09:02:12","cld_nonce":"b6d6726996","content":{"rendered":"<p>Naja die kostenlosen SIM.Karten sind ja in Ordnung, wobei ich 100MB echt wenig finde, daf\u00fcr haben die aber AllNet Flat und SMS Flat, das d\u00fcrfte f\u00fcr die Eltern\/Schwiegereltern reichen.<\/p>\n<p>Alle anderen Tarife sind meiner Meinung nach \u00fcberteuert:<br \/>\n19,99\u20ac f\u00fcr 2GB LTE Flat, AllNetFlat und SMS Flat? Da gehe ich lieber zu ja!mobil:<\/p>\n<p>Prepaid Smart<br \/>\n2 GB Surf-Flat inkl. LTE 25<br \/>\nTelefon Flat<br \/>\nNeu: SMS-Flat<br \/>\n7,99 \u20ac\/4 Wochen<\/p>\n<p>und das im Telekom Netz!<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>1&amp;1: D-Netz (Vodafone Netz) bekommt LTE - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1&amp;1: D-Netz (Vodafone Netz) bekommt LTE\" \/>\n<meta property=\"og:description\" content=\"Pers\u00f6nlich habe ich immer mal wieder mit dem Gedanken gespielt meinen Mobilfunkvertrag bei 1&amp;1 abzuschlie\u00dfen. F\u00fcr mich kam hier immer nur der D-Netz Tarif in Frage. Ausschlie\u00dfungsgrund war aber bislang, dass man im D-Netz kein LTE bekommen hat. Nun \u00e4ndert&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-15T17:38:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"869\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"1&#038;1: D-Netz (Vodafone Netz) bekommt LTE\",\"datePublished\":\"2019-11-15T17:38:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/\"},\"wordCount\":101,\"commentCount\":22,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/1und1-cover.jpg\",\"keywords\":[\"1 und 1 D-Netz LTE\"],\"articleSection\":{\"1\":\"Mobile\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/\",\"name\":\"1&1: D-Netz (Vodafone Netz) bekommt LTE - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/1und1-cover.jpg\",\"datePublished\":\"2019-11-15T17:38:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/1und1-cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/1und1-cover.jpg\",\"width\":1600,\"height\":869},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/11\\\/15\\\/11-d-netz-vodafone-netz-bekommt-lte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1&#038;1: D-Netz (Vodafone Netz) bekommt LTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1&1: D-Netz (Vodafone Netz) bekommt LTE - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/","og_locale":"de_DE","og_type":"article","og_title":"1&1: D-Netz (Vodafone Netz) bekommt LTE","og_description":"Pers\u00f6nlich habe ich immer mal wieder mit dem Gedanken gespielt meinen Mobilfunkvertrag bei 1&amp;1 abzuschlie\u00dfen. F\u00fcr mich kam hier immer nur der D-Netz Tarif in Frage. Ausschlie\u00dfungsgrund war aber bislang, dass man im D-Netz kein LTE bekommen hat. Nun \u00e4ndert&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2019-11-15T17:38:54+00:00","og_image":[{"width":1600,"height":869,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"1&#038;1: D-Netz (Vodafone Netz) bekommt LTE","datePublished":"2019-11-15T17:38:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/"},"wordCount":101,"commentCount":22,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover.jpg","keywords":["1 und 1 D-Netz LTE"],"articleSection":{"1":"Mobile"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/","url":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/","name":"1&1: D-Netz (Vodafone Netz) bekommt LTE - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover.jpg","datePublished":"2019-11-15T17:38:54+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover.jpg","width":1600,"height":869},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/11\/15\/11-d-netz-vodafone-netz-bekommt-lte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"1&#038;1: D-Netz (Vodafone Netz) bekommt LTE"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2016\/07\/1und1-cover.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/130143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=130143"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/130143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/67655"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=130143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=130143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=130143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}