{"id":128527,"date":"2019-10-15T13:48:08","date_gmt":"2019-10-15T11:48:08","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=128527"},"modified":"2019-10-15T13:48:08","modified_gmt":"2019-10-15T11:48:08","slug":"vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/","title":{"rendered":"Vodafone Pass: Ab Dezember auch in der EU nutzbar"},"content":{"rendered":"<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london.jpg\" rel=\"lightbox[128527]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-126802\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-500x360.jpg\" alt=\"\" width=\"500\" height=\"360\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-500x360.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-285x205.jpg 285w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-810x583.jpg 810w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Kurzinfo f\u00fcr die Vodafone User unter euch, welche vielleicht auch den &amp;ein oder anderen &#8222;Vodafone Pass&#8220; nutzen. Bislang k\u00f6nnen due Vorteile ha bekanntlich nur in Deutschland genutzt werden, was sich laut den Kollegen ab Dezember aber \u00e4ndern soll.<\/p>\n<p>Denn ab dem 13. Dezember soll ein hinzugebuchter Vodafone Pass in Gesamtgebiet der EU nutzbar sein. Als Vodafone-Kunde sollen einem dann 39 GB an Datenvolumen, unabh\u00e4ngig von der Anzahl der gebuchten P\u00e4sse, zur Verf\u00fcgung gestellt werden.<\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/www.mobiflip.de\/shortnews\/vodafone-pass-eu-ausland\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mobiflip<\/a> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Kurzinfo f\u00fcr die Vodafone User unter euch, welche vielleicht auch den &amp;ein oder anderen &#8222;Vodafone Pass&#8220; nutzen. Bislang k\u00f6nnen due Vorteile ha bekanntlich nur in Deutschland genutzt werden, was sich laut den Kollegen ab Dezember aber \u00e4ndern soll. Denn ab&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":126802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,231],"tags":[21380],"class_list":["post-128527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-mobile","tag-vodafone-pass"],"wp_featured_image":{"id":126802,"alt_text":"","description":"","media_type":"image","media_details":{"width":2174,"height":1565,"file":"2019\/09\/vodafone-logo-london.jpg","sizes":{"thumbnail":{"file":"vodafone-logo-london-285x205.jpg","width":285,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-285x205.jpg"},"medium":{"file":"vodafone-logo-london-500x360.jpg","width":500,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-500x360.jpg"},"large":{"file":"vodafone-logo-london-810x583.jpg","width":810,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-810x583.jpg"},"wp_review_large":{"file":"vodafone-logo-london-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-320x200.jpg"},"wp_review_small":{"file":"vodafone-logo-london-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-65x65.jpg"},"blog-large":{"file":"vodafone-logo-london-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-642x300.jpg"},"blog-medium":{"file":"vodafone-logo-london-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-306x205.jpg"},"recent-thumb":{"file":"vodafone-logo-london-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-350x316.jpg"},"service-featured":{"file":"vodafone-logo-london-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-600x330.jpg"},"wp_rp_thumbnail":{"file":"vodafone-logo-london-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london-150x150.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"iPhone SE","caption":"","created_timestamp":"1567779199","copyright":"","focal_length":"4.15","iso":"25","shutter_speed":"0.03030303030303","title":"","orientation":"1","keywords":[]}},"post":128527,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london.jpg"},"commentcount":1,"wp_comments":[{"id":113956,"parent":0,"author":0,"author_name":"Marc","author_email":"gundh@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/801dd52e1bd2f6dca5c0d08d5fc09958bc8e60c9963df4f0c59d3ec31d9a142f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/801dd52e1bd2f6dca5c0d08d5fc09958bc8e60c9963df4f0c59d3ec31d9a142f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/801dd52e1bd2f6dca5c0d08d5fc09958bc8e60c9963df4f0c59d3ec31d9a142f?s=96&d=mm&r=g"},"date":"2019-10-15T14:40:04","cld_nonce":"b6d6726996","content":{"rendered":"<p>leider bleibt aber die Schweiz immer au\u00dfen vor, was gerade in der Grenzregion interessant w\u00e4re.<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vodafone Pass: Ab Dezember auch in der EU nutzbar - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vodafone Pass: Ab Dezember auch in der EU nutzbar\" \/>\n<meta property=\"og:description\" content=\"Kurzinfo f\u00fcr die Vodafone User unter euch, welche vielleicht auch den &amp;ein oder anderen &#8222;Vodafone Pass&#8220; nutzen. Bislang k\u00f6nnen due Vorteile ha bekanntlich nur in Deutschland genutzt werden, was sich laut den Kollegen ab Dezember aber \u00e4ndern soll. Denn ab&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-15T11:48:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2174\" \/>\n\t<meta property=\"og:image:height\" content=\"1565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Vodafone Pass: Ab Dezember auch in der EU nutzbar\",\"datePublished\":\"2019-10-15T11:48:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/\"},\"wordCount\":91,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/vodafone-logo-london.jpg\",\"keywords\":[\"Vodafone Pass\"],\"articleSection\":{\"1\":\"Mobile\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/\",\"name\":\"Vodafone Pass: Ab Dezember auch in der EU nutzbar - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/vodafone-logo-london.jpg\",\"datePublished\":\"2019-10-15T11:48:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/vodafone-logo-london.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/vodafone-logo-london.jpg\",\"width\":2174,\"height\":1565},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/10\\\/15\\\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vodafone Pass: Ab Dezember auch in der EU nutzbar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vodafone Pass: Ab Dezember auch in der EU nutzbar - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/","og_locale":"de_DE","og_type":"article","og_title":"Vodafone Pass: Ab Dezember auch in der EU nutzbar","og_description":"Kurzinfo f\u00fcr die Vodafone User unter euch, welche vielleicht auch den &amp;ein oder anderen &#8222;Vodafone Pass&#8220; nutzen. Bislang k\u00f6nnen due Vorteile ha bekanntlich nur in Deutschland genutzt werden, was sich laut den Kollegen ab Dezember aber \u00e4ndern soll. Denn ab&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2019-10-15T11:48:08+00:00","og_image":[{"width":2174,"height":1565,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Vodafone Pass: Ab Dezember auch in der EU nutzbar","datePublished":"2019-10-15T11:48:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/"},"wordCount":91,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london.jpg","keywords":["Vodafone Pass"],"articleSection":{"1":"Mobile"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/","url":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/","name":"Vodafone Pass: Ab Dezember auch in der EU nutzbar - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london.jpg","datePublished":"2019-10-15T11:48:08+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london.jpg","width":2174,"height":1565},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/10\/15\/vodafone-pass-ab-dezember-auch-in-der-eu-nutzbar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Vodafone Pass: Ab Dezember auch in der EU nutzbar"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/vodafone-logo-london.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/128527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=128527"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/128527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/126802"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=128527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=128527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=128527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}