{"id":127880,"date":"2019-09-30T20:58:31","date_gmt":"2019-09-30T18:58:31","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=127880"},"modified":"2019-10-01T09:43:22","modified_gmt":"2019-10-01T07:43:22","slug":"apple-veroeffentlicht-ios-13-1-2","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/","title":{"rendered":"Apple ver\u00f6ffentlicht iOS 13.1.2"},"content":{"rendered":"<p>Weiter geht&#8217;s mit den Updates: Apple hat am Abend iOS 13.1.2 f\u00fcr iPhones und iPads ver\u00f6ffentlicht. Dabei handelt es sich um ein kleines Bugfix-Update &#8211; konkret hat man insbesondere Probleme mit der Kamera, der Taschenlampe und Bluetooth behoben. Weitere Fehlerbehebungen finden sich unten im Changelog.<\/p>\n<p>Das Update hatte bei mir auf dem iPhone eine Gr\u00f6\u00dfe von 41,9 MB. Sollte der Speicherplatz bei euch zu knapp sein, dann kann man das Update wie immer auch per iTunes einspielen. Zudem muss das Ger\u00e4t f\u00fcr die Installation mindestens 50% geladen oder ans Stromnetz angeschlossen sein.<\/p>\n<p>Das war im \u00dcbrigen jetzt schon Update Nummer 3 nach dem Release von iOS 13 vor weniger als 2 Wochen. Man fragt sich auch hier so langsam, wof\u00fcr das (Public-)Beta-Programm \u00fcberhaupt gut ist&#8230;<\/p>\n<h3>Changelog iOS 13.1.2 f\u00fcr iPhone, iPad und iPod touch<\/h3>\n<p>iOS 13.1.2 enth\u00e4lt Bugfixes und Verbesserungen f\u00fcr Ihr iPhone. Dieses Update:<\/p>\n<ul>\n<li>Behebt einen Fehler, bei dem der Fortschrittsbalken f\u00fcr iCloud Backup nach einem erfolgreichen Backup weiterhin angezeigt wurde<\/li>\n<li>Behebt ein Problem, bei dem die Kamera m\u00f6glicherweise nicht funktioniert<\/li>\n<li>Behebt ein Problem, bei dem die Taschenlampe m\u00f6glicherweise nicht aktiviert werden konnte<\/li>\n<li>Behebt einen Fehler, der zum Verlust von Display-Kalibrierungsdaten f\u00fchren konnte<\/li>\n<li>Behebt ein Problem, bei dem Kurzbefehle nicht vom HomePod aus ausgef\u00fchrt werden konnten<\/li>\n<li>Behebt ein Problem, bei dem Bluetooth bei Fahrzeugen getrennt wurde<\/li>\n<\/ul>\n<p>F\u00fcr Informationen \u00fcber den Sicherheitsinhalt von Apple Software-Updates besuchen Sie bitte diese Website:<br \/>\nhttps:\/\/support.apple.com\/kb\/HT201222<\/p>\n<p><i>Danke an Cluster Head f\u00fcr den Hinweis!<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Weiter geht&#8217;s mit den Updates: Apple hat am Abend iOS 13.1.2 f\u00fcr iPhones und iPads ver\u00f6ffentlicht. Dabei handelt es sich um ein kleines Bugfix-Update &#8211; konkret hat man insbesondere Probleme mit der Kamera, der Taschenlampe und Bluetooth behoben. Weitere Fehlerbehebungen&hellip; <\/p>\n","protected":false},"author":1525,"featured_media":126834,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[232],"tags":[98,63997,2445,1125,104],"class_list":["post-127880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ios","tag-apple","tag-ios-13-1-2","tag-ipad","tag-iphone","tag-update"],"wp_featured_image":{"id":126834,"alt_text":"","description":"","media_type":"image","media_details":{"width":2880,"height":1568,"file":"2019\/09\/ios-13.png","sizes":{"thumbnail":{"file":"ios-13-306x167.png","width":306,"height":167,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-306x167.png"},"medium":{"file":"ios-13-500x272.png","width":500,"height":272,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-500x272.png"},"large":{"file":"ios-13-810x441.png","width":810,"height":441,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-810x441.png"},"wp_review_large":{"file":"ios-13-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-320x200.png"},"wp_review_small":{"file":"ios-13-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-65x65.png"},"blog-large":{"file":"ios-13-642x300.png","width":642,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-642x300.png"},"blog-medium":{"file":"ios-13-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-306x205.png"},"recent-thumb":{"file":"ios-13-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-350x316.png"},"service-featured":{"file":"ios-13-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-600x330.png"},"wp_rp_thumbnail":{"file":"ios-13-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":126833,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13.png"},"commentcount":10,"wp_comments":[{"id":112696,"parent":0,"author":0,"author_name":"Rush","author_email":"djmajorrush@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=96&d=mm&r=g"},"date":"2019-09-30T21:31:01","cld_nonce":"b6d6726996","content":{"rendered":"<p>bitte nochmal den Text lesen und korrigieren <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":112697,"parent":112696,"author":0,"author_name":"eine neuer Kommentar...","author_email":"rest@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9ad6ca70c2ed9bd1094e96c304a28e5c9876876ebdab7c1dcfe36676bcc79070?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9ad6ca70c2ed9bd1094e96c304a28e5c9876876ebdab7c1dcfe36676bcc79070?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9ad6ca70c2ed9bd1094e96c304a28e5c9876876ebdab7c1dcfe36676bcc79070?s=96&d=mm&r=g"},"date":"2019-09-30T21:49:04","cld_nonce":"b6d6726996","content":{"rendered":"<p>Immer diese Kommentare &#8222;Text-lesen-und-korregieren&#8220;<br \/>\nAls h\u00e4ttest du eine perfekte absolute Rechtschreibung.<\/p>\n<p>Solche wie du suchen nach fehleren&#8230;<\/p>\n"},"status":"1"},{"id":112698,"parent":112697,"author":0,"author_name":"Rush","author_email":"djmajorrush@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=96&d=mm&r=g"},"date":"2019-09-30T22:21:47","cld_nonce":"b6d6726996","content":{"rendered":"<p>du bist ja ein lustiger fake <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":112700,"parent":112698,"author":3691,"author_name":"mcbloch","author_email":"mcbloch@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=96&d=mm&r=g"},"date":"2019-09-30T22:49:21","cld_nonce":"b6d6726996","content":{"rendered":"<p>Recht hat er aber schon ein wenig.<\/p>\n"},"status":"1"},{"id":112703,"parent":0,"author":0,"author_name":"Rainbird-1","author_email":"rainbird-1@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0050aa3499751080663bda27c14bb259f107c0299e16df68aa2721a2bd29e1db?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0050aa3499751080663bda27c14bb259f107c0299e16df68aa2721a2bd29e1db?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0050aa3499751080663bda27c14bb259f107c0299e16df68aa2721a2bd29e1db?s=96&d=mm&r=g"},"date":"2019-10-01T04:37:24","cld_nonce":"b6d6726996","content":{"rendered":"<p>@Rush<br \/>\ngebe Dir mit Deiner Ansicht recht. Wenn man nicht von offizieller Seite (Autoren, Verlage, etc.) eine saubere Grammatik und Rechtschreibung erwarten kann, von wem denn sonst? Wir sollten stolz auf unsere Sprache sein, akzeptieren aber immer mehr den  \u201eHey Alder, krasse Funktion\u201c Gangster Style. Das ist eine Art Resignation.<\/p>\n<p>Ich denke man kann auch in der heutigen WhatsApp Zeit immer noch Wert auf Grammatik und Rechtschreibung legen. Fr\u00fcher h\u00e4tte man beim Briefe schreiben auch nicht irgendwelche wahllosen Abk\u00fcrzungen benutzt. Die Sprache verk\u00fcmmert immer mehr!<\/p>\n<p>Und ja ich habe etwas weiter ausgeholt!<\/p>\n"},"status":"1"},{"id":112720,"parent":112698,"author":0,"author_name":"Rush","author_email":"djmajorrush@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f8e6ead7b0507ee23e2f9ded45c3941b6d2903892903aae5f1e43d22b6d1c166?s=96&d=mm&r=g"},"date":"2019-10-01T10:34:40","cld_nonce":"b6d6726996","content":{"rendered":"<p>Ach, der selbe Fake nochmal, blo\u00df mit anderem Namen &#8222;Hurra&#8220; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":112750,"parent":0,"author":4961,"author_name":"localhost","author_email":"werner@fpsoft.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8cd2f231959a5f3bcf77077e9692a4ad754655fe19da470f3caaf02f6d65ba39?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8cd2f231959a5f3bcf77077e9692a4ad754655fe19da470f3caaf02f6d65ba39?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8cd2f231959a5f3bcf77077e9692a4ad754655fe19da470f3caaf02f6d65ba39?s=96&d=mm&r=g"},"date":"2019-10-01T12:50:12","cld_nonce":"b6d6726996","content":{"rendered":"<p>ganz sch\u00f6n schlampig von Apple.<br \/>\nbei mir waren&#8217;s 71,4 MB<\/p>\n"},"status":"1"},{"id":112756,"parent":0,"author":4813,"author_name":"Nikolaus","author_email":"manfred.hamernik@gmx.at","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/21b46c4f7e47ff6bb28b51f3310a50ac0e9f8d0c05b986d3bec6f6cf90a0540c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/21b46c4f7e47ff6bb28b51f3310a50ac0e9f8d0c05b986d3bec6f6cf90a0540c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/21b46c4f7e47ff6bb28b51f3310a50ac0e9f8d0c05b986d3bec6f6cf90a0540c?s=96&d=mm&r=g"},"date":"2019-10-01T13:24:10","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hm, der Fehler mit dem flackern beim Slo-Mo Video ist immer noch nicht behoben. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":114033,"parent":0,"author":0,"author_name":"Axel60","author_email":"axel.schmeissner@web.dr","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/cdd70e69f14cd3a03852488cde7b733ed0120815e266add1c75f1d03c3fc27a9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/cdd70e69f14cd3a03852488cde7b733ed0120815e266add1c75f1d03c3fc27a9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/cdd70e69f14cd3a03852488cde7b733ed0120815e266add1c75f1d03c3fc27a9?s=96&d=mm&r=g"},"date":"2019-10-16T15:50:09","cld_nonce":"b6d6726996","content":{"rendered":"<p>13.1.3 ist da!<br \/>\nDas h\u00f6rt nicht auf!!!!<\/p>\n"},"status":"1"},{"id":114036,"parent":114033,"author":134,"author_name":"moinmoin","author_email":"moin-moin@hab-verschlafen.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"},"date":"2019-10-16T16:10:50","cld_nonce":"b6d6726996","content":{"rendered":"<p>Hat Apple doch gut von den anderen gelernt. Anstatt einmal ordentlich (wie fr\u00fcher) jetzt H\u00e4ppchenweise <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_lol.gif\" alt=\":lol:\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"}],"wp_author":{"id":1525,"name":"W8U","description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"}},"cld_nonce":"b6d6726996","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Apple ver\u00f6ffentlicht iOS 13.1.2 - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apple ver\u00f6ffentlicht iOS 13.1.2\" \/>\n<meta property=\"og:description\" content=\"Weiter geht&#8217;s mit den Updates: Apple hat am Abend iOS 13.1.2 f\u00fcr iPhones und iPads ver\u00f6ffentlicht. Dabei handelt es sich um ein kleines Bugfix-Update &#8211; konkret hat man insbesondere Probleme mit der Kamera, der Taschenlampe und Bluetooth behoben. Weitere Fehlerbehebungen&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-30T18:58:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-01T07:43:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-810x441.png\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"W8U\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/\"},\"author\":{\"name\":\"W8U\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\"},\"headline\":\"Apple ver\u00f6ffentlicht iOS 13.1.2\",\"datePublished\":\"2019-09-30T18:58:31+00:00\",\"dateModified\":\"2019-10-01T07:43:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/\"},\"wordCount\":257,\"commentCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ios-13.png\",\"keywords\":[\"Apple\",\"iOS 13.1.2\",\"iPad\",\"Iphone\",\"Update\"],\"articleSection\":[\"iOS\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/\",\"name\":\"Apple ver\u00f6ffentlicht iOS 13.1.2 - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ios-13.png\",\"datePublished\":\"2019-09-30T18:58:31+00:00\",\"dateModified\":\"2019-10-01T07:43:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ios-13.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ios-13.png\",\"width\":2880,\"height\":1568},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/09\\\/30\\\/apple-veroeffentlicht-ios-13-1-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apple ver\u00f6ffentlicht iOS 13.1.2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\",\"name\":\"W8U\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"caption\":\"W8U\"},\"description\":\"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/w8u\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Apple ver\u00f6ffentlicht iOS 13.1.2 - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/","og_locale":"de_DE","og_type":"article","og_title":"Apple ver\u00f6ffentlicht iOS 13.1.2","og_description":"Weiter geht&#8217;s mit den Updates: Apple hat am Abend iOS 13.1.2 f\u00fcr iPhones und iPads ver\u00f6ffentlicht. Dabei handelt es sich um ein kleines Bugfix-Update &#8211; konkret hat man insbesondere Probleme mit der Kamera, der Taschenlampe und Bluetooth behoben. Weitere Fehlerbehebungen&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2019-09-30T18:58:31+00:00","article_modified_time":"2019-10-01T07:43:22+00:00","og_image":[{"width":810,"height":441,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13-810x441.png","type":"image\/png"}],"author":"W8U","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/"},"author":{"name":"W8U","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469"},"headline":"Apple ver\u00f6ffentlicht iOS 13.1.2","datePublished":"2019-09-30T18:58:31+00:00","dateModified":"2019-10-01T07:43:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/"},"wordCount":257,"commentCount":10,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13.png","keywords":["Apple","iOS 13.1.2","iPad","Iphone","Update"],"articleSection":["iOS"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/","url":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/","name":"Apple ver\u00f6ffentlicht iOS 13.1.2 - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13.png","datePublished":"2019-09-30T18:58:31+00:00","dateModified":"2019-10-01T07:43:22+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13.png","width":2880,"height":1568},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/09\/30\/apple-veroeffentlicht-ios-13-1-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Apple ver\u00f6ffentlicht iOS 13.1.2"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469","name":"W8U","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","caption":"W8U"},"description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","url":"https:\/\/www.deskmodder.de\/blog\/author\/w8u\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/09\/ios-13.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/127880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/1525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=127880"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/127880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/126834"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=127880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=127880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=127880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}