{"id":123307,"date":"2019-07-20T10:59:34","date_gmt":"2019-07-20T08:59:34","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=123307"},"modified":"2019-07-20T11:00:26","modified_gmt":"2019-07-20T09:00:26","slug":"zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/","title":{"rendered":"Zwei Jahre altes Problem unter Windows 10 &#8211; Man \u00e4ndert mal einfach so das Datum"},"content":{"rendered":"<p>Gibt es ein Problem mit Windows, in dem Fall Windows 10 und es wird von Microsoft als &#8222;best\u00e4tigt&#8220; angesehen hinterl\u00e4sst man einen Eintrag unter support.microsoft. Auch heute ist wieder eine Meldung hereingekommen.<\/p>\n<p>Aber da ich bei diesen Eintr\u00e4gen immer sehr pessimistisch bin, suche ich erst im Google oder Bing Cache nach identischen Eintr\u00e4gen. So auch bei diesem Fehler, Stand 20.Juli 2019. Es geht darum, dass bei einem neuen Ger\u00e4t und dem ersten Start anstatt die Einrichtung des Benutzerkontos (OOBE Out of Box Experience) der Willkommensbildschirm mit &#8222;Anderer Benutzer&#8220; erscheint.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10.jpg\" rel=\"lightbox[123307]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-495x360.jpg\" alt=\"\" width=\"495\" height=\"360\" class=\"aligncenter size-medium wp-image-123309\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-495x360.jpg 495w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-282x205.jpg 282w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-801x583.jpg 801w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10.jpg 963w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/a><\/p>\n<p>Hier liegt ein Fehler vor, weil die dwm.exe nicht gestartet werden kann. Der Videotreiber sendet ein TDR (Timeout Detect Recovery) und es kommt  zu einer Schleife und dem Anmeldebildschirm f\u00fcr Anderer Benutzer. Der Workaround ist eigentlich einfach, rechts unten das Men\u00fc \u00f6ffnen, die Umschalttaste gedr\u00fcckt halten und auf Neustarten klicken. Wenn das nicht klappt die Power-Taste vom Rechner l\u00e4nger gedr\u00fcckt halten und dann neu starten, damit die dwm.exe geladen werden kann.<\/p>\n<p>Aber es geht gar nicht um den Fehler. Denn der identische Bericht, ohne dass nur ein Wort im Text ver\u00e4ndert wurde stammt vom September 2017. Seitdem hat es Microsoft nicht geschafft, den Fehler auszub\u00fcgeln. Ist ja sch\u00f6n, dass die Redmonder einen immer aktuell auf dem Laufenden halten. Aber ein fast zwei Jahre alter Bug?<\/p>\n<ul>\n<li><a href=\"https:\/\/support.microsoft.com\/en-us\/help\/3134791\/windows-10-device-starts-on-the-welcome-screen-and-as-other-user\" rel=\"noopener noreferrer\" target=\"_blank\">support.microsoft<\/a><\/li>\n<\/ul>\n<h3>Windows 10 Tutorials und Hilfe<\/h3>\n<p>In unserem <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 Wiki<\/a> findet ihr sehr viele hilfreiche Tipps und Tricks. Falls ihr Fragen habt, dann stellt diese ganz einfach bei uns im <a href=\"https:\/\/www.deskmodder.de\/phpBB3\/viewforum.php?f=326\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Forum<\/strong><\/a>.<\/p>\n<ul>\n<li><strong>Installationsmedien:<\/strong> Aktuelle Installationsdateien findet ihr hier immer in der rechten Sidebar. <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/03\/23\/1903-18362-iso-esd-deutsch-english\/\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 1903 ISO (18362)<\/a> <\/li>\n<li><strong>Installation:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_clean_neu_installieren\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 Clean installieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_1903_neu_installieren_Anleitung_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 1903 neu installieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_1809_neu_installieren_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 1809 neu installieren<\/a><\/li>\n<li><strong>Probleme bei der Installation:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_1809_bereitet_Probleme_bei_der_Installation_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Windows 10 1809 Probleme bei der Installation<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_1803_17134_l%C3%A4sst_sich_nicht_installieren_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 1803 l\u00e4sst sich nicht installieren<\/a><\/li>\n<li><strong>Reparaturen:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Inplace_Upgrade_Windows_10_schnell_reparieren\" rel=\"noopener noreferrer\" target=\"_blank\">Inplace Upgrade Reparatur<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_reparieren_wiederherstellen_mit_DISM_Inplace_Upgrade_und_vielen_weiteren_Varianten\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 reparieren  \u00fcber DISM, sfc und weiteres<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_Update_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Windows Update reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Startmen%C3%BC_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Startmen\u00fc reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Apps_reparieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Apps reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Store_reparieren\" rel=\"noopener noreferrer\" target=\"_blank\">Store reparieren<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Netzwerkverbindung_-adapter_reparieren_zur%C3%BCcksetzen_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Netzwerk reparieren<\/a><\/li>\n<li><strong>Anmeldung:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_automatisch_anmelden_ohne_Passworteingabe\" rel=\"noopener noreferrer\" target=\"_blank\">Win 10 automatische Anmeldung<\/a><\/li>\n<li><strong>Entfernen, Deinstallieren<\/strong>: <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Cortana_deaktivieren_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Cortana deaktivieren,<\/a>  <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Windows_10_Apps_entfernen_deinstallieren\" rel=\"noopener noreferrer\" target=\"_blank\">Apps deinstallieren<\/a><\/li>\n<li><strong>Datei Explorer:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Dieser_PC_Ordner_entfernen_Windows_10\" rel=\"noopener noreferrer\" target=\"_blank\">Ordner unter Dieser PC entfernen<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Datei_Explorer_Windows_10_Netzwerk_Heimnetzgruppe_OneDrive_entfernen\" rel=\"noopener noreferrer\" target=\"_blank\">Netzwerk, OneDrive u.a. im Explorer entfernen<\/a><\/li>\n<li><strong>Richtige Nutzung:<\/strong> <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Das_Windows_10_Startmen%C3%BC_richtig_einrichten_Tipps_und_Tricks\" rel=\"noopener noreferrer\" target=\"_blank\">Startmen\u00fc richtig nutzen<\/a>, <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Die_Suche_in_Windows_10_richtig_nutzen\" rel=\"noopener noreferrer\" target=\"_blank\">Suche richtig nutzen<\/a>,<\/li>\n<li><strong>Wichtig:<\/strong> In jedem Tutorial steht, f\u00fcr welche Version es geeignet ist.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Gibt es ein Problem mit Windows, in dem Fall Windows 10 und es wird von Microsoft als &#8222;best\u00e4tigt&#8220; angesehen hinterl\u00e4sst man einen Eintrag unter support.microsoft. Auch heute ist wieder eine Meldung hereingekommen. Aber da ich bei diesen Eintr\u00e4gen immer sehr&hellip; <\/p>\n","protected":false},"author":134,"featured_media":123309,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2689],"tags":[],"class_list":["post-123307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows-10"],"wp_featured_image":{"id":123309,"alt_text":"","description":"","media_type":"image","media_details":{"width":963,"height":701,"file":"2019\/07\/bug-windows-10.jpg","sizes":{"thumbnail":{"file":"bug-windows-10-282x205.jpg","width":282,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-282x205.jpg"},"medium":{"file":"bug-windows-10-495x360.jpg","width":495,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-495x360.jpg"},"large":{"file":"bug-windows-10-801x583.jpg","width":801,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-801x583.jpg"},"wp_review_large":{"file":"bug-windows-10-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-320x200.jpg"},"wp_review_small":{"file":"bug-windows-10-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-65x65.jpg"},"blog-large":{"file":"bug-windows-10-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-642x300.jpg"},"blog-medium":{"file":"bug-windows-10-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-306x205.jpg"},"recent-thumb":{"file":"bug-windows-10-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-350x316.jpg"},"service-featured":{"file":"bug-windows-10-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-600x330.jpg"},"wp_rp_thumbnail":{"file":"bug-windows-10-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":123307,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10.jpg"},"commentcount":4,"wp_comments":[{"id":106523,"parent":0,"author":0,"author_name":"Anas Issa","author_email":"anashosso20@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0fa339decdd7ab94bf642a55c0a440d859c043360f771befeb6ca1d40b2624c8?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0fa339decdd7ab94bf642a55c0a440d859c043360f771befeb6ca1d40b2624c8?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0fa339decdd7ab94bf642a55c0a440d859c043360f771befeb6ca1d40b2624c8?s=96&d=mm&r=g"},"date":"2019-07-20T19:38:47","cld_nonce":"82f011626f","content":{"rendered":"<p>Hallo ich habe einen Problem mit dem Windows 10 pro wenn ich ein Spiel spiele nach 10 min gibt mir Windows Applikation Crash ich wei\u00df nicht was ich machen soll bitte hilf mir<\/p>\n"},"status":"1"},{"id":106531,"parent":106523,"author":0,"author_name":"ordner","author_email":"ma18892013@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7dc0f3806789d157a90098cbf34863f702dbc34ad00e707a8e14577907c0a5bf?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7dc0f3806789d157a90098cbf34863f702dbc34ad00e707a8e14577907c0a5bf?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7dc0f3806789d157a90098cbf34863f702dbc34ad00e707a8e14577907c0a5bf?s=96&d=mm&r=g"},"date":"2019-07-20T21:58:59","cld_nonce":"82f011626f","content":{"rendered":"<p>welches spiel?  wenn es mit &#8222;\u00e4lteren&#8220; version lief:  einfach kompertibilit\u00e4tsmodus benutzen.<br \/>\ndesweiteren: fehlermeldungs nr?<\/p>\n<p>normal mu\u00df alles an xp\/7\/8\/8.1 software auf 10 laufen (ausser bei home!)<\/p>\n<p>wenn man eine zeit lang spielen kann&#8230;dann abbricht&#8230;kann auch ein anderes programm das verursachen: av software zB (auch defender).<\/p>\n"},"status":"1"},{"id":106571,"parent":0,"author":5657,"author_name":"anthropos","author_email":"forumsadresse@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9c60716a2ad6610693a32f9fb9e8c2b3536d49f422d321cea727bff1b3087dac?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9c60716a2ad6610693a32f9fb9e8c2b3536d49f422d321cea727bff1b3087dac?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9c60716a2ad6610693a32f9fb9e8c2b3536d49f422d321cea727bff1b3087dac?s=96&d=mm&r=g"},"date":"2019-07-21T12:39:54","cld_nonce":"82f011626f","content":{"rendered":"<p>Das gibt dem Wort Traditionsunternehmen gleich eine zus\u00e4tzliche Bedeutung<br \/>\n?<\/p>\n"},"status":"1"},{"id":106692,"parent":0,"author":0,"author_name":"SanVio","author_email":"sanchud@posteo.at","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9625237c374f1dfa6dd26bc05274a8b156477f03246ef96faf3fa05939d818a7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9625237c374f1dfa6dd26bc05274a8b156477f03246ef96faf3fa05939d818a7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9625237c374f1dfa6dd26bc05274a8b156477f03246ef96faf3fa05939d818a7?s=96&d=mm&r=g"},"date":"2019-07-22T17:15:18","cld_nonce":"82f011626f","content":{"rendered":"<p>Interessante &#8218;Aktualisierung&#8216;! Gut aufgepasst <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Zwei Jahre altes Problem unter Windows 10 - Man \u00e4ndert mal einfach so das Datum - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zwei Jahre altes Problem unter Windows 10 - Man \u00e4ndert mal einfach so das Datum\" \/>\n<meta property=\"og:description\" content=\"Gibt es ein Problem mit Windows, in dem Fall Windows 10 und es wird von Microsoft als &#8222;best\u00e4tigt&#8220; angesehen hinterl\u00e4sst man einen Eintrag unter support.microsoft. Auch heute ist wieder eine Meldung hereingekommen. Aber da ich bei diesen Eintr\u00e4gen immer sehr&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-20T08:59:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-20T09:00:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"963\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Zwei Jahre altes Problem unter Windows 10 &#8211; Man \u00e4ndert mal einfach so das Datum\",\"datePublished\":\"2019-07-20T08:59:34+00:00\",\"dateModified\":\"2019-07-20T09:00:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/\"},\"wordCount\":375,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/bug-windows-10.jpg\",\"articleSection\":[\"Windows 10\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/\",\"name\":\"Zwei Jahre altes Problem unter Windows 10 - Man \u00e4ndert mal einfach so das Datum - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/bug-windows-10.jpg\",\"datePublished\":\"2019-07-20T08:59:34+00:00\",\"dateModified\":\"2019-07-20T09:00:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/bug-windows-10.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/bug-windows-10.jpg\",\"width\":963,\"height\":701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/20\\\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zwei Jahre altes Problem unter Windows 10 &#8211; Man \u00e4ndert mal einfach so das Datum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zwei Jahre altes Problem unter Windows 10 - Man \u00e4ndert mal einfach so das Datum - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/","og_locale":"de_DE","og_type":"article","og_title":"Zwei Jahre altes Problem unter Windows 10 - Man \u00e4ndert mal einfach so das Datum","og_description":"Gibt es ein Problem mit Windows, in dem Fall Windows 10 und es wird von Microsoft als &#8222;best\u00e4tigt&#8220; angesehen hinterl\u00e4sst man einen Eintrag unter support.microsoft. Auch heute ist wieder eine Meldung hereingekommen. Aber da ich bei diesen Eintr\u00e4gen immer sehr&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2019-07-20T08:59:34+00:00","article_modified_time":"2019-07-20T09:00:26+00:00","og_image":[{"width":963,"height":701,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Zwei Jahre altes Problem unter Windows 10 &#8211; Man \u00e4ndert mal einfach so das Datum","datePublished":"2019-07-20T08:59:34+00:00","dateModified":"2019-07-20T09:00:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/"},"wordCount":375,"commentCount":4,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10.jpg","articleSection":["Windows 10"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/","url":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/","name":"Zwei Jahre altes Problem unter Windows 10 - Man \u00e4ndert mal einfach so das Datum - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10.jpg","datePublished":"2019-07-20T08:59:34+00:00","dateModified":"2019-07-20T09:00:26+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10.jpg","width":963,"height":701},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/20\/zwei-jahre-altes-problem-unter-windows-10-man-aendert-mal-einfach-so-das-datum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Zwei Jahre altes Problem unter Windows 10 &#8211; Man \u00e4ndert mal einfach so das Datum"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/bug-windows-10.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/123307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=123307"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/123307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/123309"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=123307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=123307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=123307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}