{"id":123011,"date":"2019-07-13T07:57:44","date_gmt":"2019-07-13T05:57:44","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=123011"},"modified":"2019-07-13T07:57:44","modified_gmt":"2019-07-13T05:57:44","slug":"deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/","title":{"rendered":"Deezer: &#8222;SongCatcher&#8220; Funktion nun auch f\u00fcr iOS verf\u00fcgbar"},"content":{"rendered":"<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840.jpg\" rel=\"lightbox[123011]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-123012\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-500x339.jpg\" alt=\"\" width=\"500\" height=\"339\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-500x339.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-303x205.jpg 303w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-810x549.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840.jpg 1240w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Kurzinfo f\u00fcr die Nutzer des Musik-Streamingdienstes Deezer unter iOS. Ab sofort geh\u00f6ren auch f\u00fcr euch unbekannte Songs der Vergangenheit an. Nachdem bereits im letzten Jahr die Android-User mit Deezers Musikerkennungsfunktion &#8222;SongCatcher&#8220; versorgt wurden, sind nun auch die User der entsprechenden iOS App von Deezer an der Reihe.<\/p>\n<p>Dazu muss die App nur aktualisiert werden und schon steht euch die SongCatcher Funktion zur Verf\u00fcgung. \u00dcber die Suche l\u00e4sst sich die Funktion starten. Erkannte Songs k\u00f6nnen dann auch direkt in einer Playlist oder als, Favorit gespeichert werden. Die SongCatcher Funktion steht \u00fcbrigens nicht nur den Premium-Usern sondern auch den Free-Usern zur Verf\u00fcgung.<\/p>\n<!-- WP-Appbox (Version: 4.5.13 \/\/ Store: appstore \/\/ ID: 292738169) -->\n<div class=\"wpappbox wpappbox-756095c609d3d5e9b04501f6b48bb87c appstore simple\">\n\t<div class=\"qrcode\"><img decoding=\"async\" src=\"https:\/\/api.qrserver.com\/v1\/create-qr-code\/?data=https%3A%2F%2Fapps.apple.com%2Fde%2Fapp%2Fdeezer-musik-podcast-player%2Fid292738169&size=200x200&ecc=M&margin=0\" alt=\"Deezer: Musik &amp; Podcast Player\" \/><\/div>\n\t<div class=\"appicon\">\n\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/apps.apple.com\/de\/app\/deezer-musik-podcast-player\/id292738169\" aria-label=\"Deezer: Musik &amp; Podcast Player\"><img decoding=\"async\" src=\"\/\/is5-ssl.mzstatic.com\/image\/thumb\/Purple113\/v4\/7a\/24\/15\/7a2415fd-1742-60d7-4710-67a9a4fb5347\/AppIcon-0-1x_U007emarketing-0-0-GLES2_U002c0-512MB-sRGB-0-0-0-85-220-0-0-0-10.png\/246x0w.jpg\" alt=\"Deezer: Musik &amp; Podcast Player\" \/><\/a>\n\t<\/div>\n\t<div class=\"applinks\">\n\t\t<div class=\"appbuttons\">\n\t\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/apps.apple.com\/de\/app\/deezer-musik-podcast-player\/id292738169\" aria-label=\"Deezer: Musik &amp; Podcast Player\">Download<\/a>\n\t\t\t<span onMouseOver=\"jQuery('.wpappbox-756095c609d3d5e9b04501f6b48bb87c .qrcode').show();\" onMouseOut=\"jQuery('.wpappbox-756095c609d3d5e9b04501f6b48bb87c .qrcode').hide();\">QR-Code<\/span>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"appdetails\">\n\t\t<div class=\"apptitle\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/apps.apple.com\/de\/app\/deezer-musik-podcast-player\/id292738169\" title=\"Deezer: Musik &amp; Podcast Player\" aria-label=\"Deezer: Musik &amp; Podcast Player\" class=\"apptitle\">Deezer: Musik & Podcast Player<\/a><\/div>\n\t\t<div class=\"developer\">\n\t\t\t<span class=\"label\">Entwickler: <\/span>\n\t\t\t<span class=\"value\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/apps.apple.com\/de\/developer\/deezer-sa\/id292738172\">DEEZER SA<\/a><\/span>\n\t\t<\/div>\n\t\t<div class=\"price\">\n\t\t\t<span class=\"label\">Preis: <\/span>\n\t\t\t<span class=\"value\">Kostenlos<sup>+<\/sup><\/span> \n\t\t\t<span class=\"rating\"><div title=\"4.5 von 5 Sternen\" class=\"rating-stars stars-monochrome stars45\"><\/div><\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div><!-- \/WP-Appbox -->\n<!-- WP-Appbox (Version: 4.5.13 \/\/ Store: googleplay \/\/ ID: deezer.android.app) -->\n<div class=\"wpappbox wpappbox-7db7b965e08f4baee874bb42d857ce33 googleplay simple\">\n\t<div class=\"qrcode\"><img decoding=\"async\" src=\"https:\/\/api.qrserver.com\/v1\/create-qr-code\/?data=https%3A%2F%2Fplay.google.com%2Fstore%2Fapps%2Fdetails%3Fid%3Ddeezer.android.app&size=200x200&ecc=M&margin=0\" alt=\"Deezer Musik Player: Songs, Radio &amp; Podcasts\" \/><\/div>\n\t<div class=\"appicon\">\n\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=deezer.android.app\" aria-label=\"Deezer Musik Player: Songs, Radio &amp; Podcasts\"><img decoding=\"async\" src=\"\/\/lh3.googleusercontent.com\/1pcRe66fgz-Px9XLd8gvKotNdFCEzUqhPm3ChnHPdnzSDLz6KOxhA7MGWvaMhmfRbmTg=s180\" alt=\"Deezer Musik Player: Songs, Radio &amp; Podcasts\" \/><\/a>\n\t<\/div>\n\t<div class=\"applinks\">\n\t\t<div class=\"appbuttons\">\n\t\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=deezer.android.app\" aria-label=\"Deezer Musik Player: Songs, Radio &amp; Podcasts\">Download<\/a>\n\t\t\t<span onMouseOver=\"jQuery('.wpappbox-7db7b965e08f4baee874bb42d857ce33 .qrcode').show();\" onMouseOut=\"jQuery('.wpappbox-7db7b965e08f4baee874bb42d857ce33 .qrcode').hide();\">QR-Code<\/span>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"appdetails\">\n\t\t<div class=\"apptitle\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=deezer.android.app\" title=\"Deezer Musik Player: Songs, Radio &amp; Podcasts\" aria-label=\"Deezer Musik Player: Songs, Radio &amp; Podcasts\" class=\"apptitle\">Deezer Musik Player: Songs, Radio &amp; Podcasts<\/a><\/div>\n\t\t<div class=\"developer\">\n\t\t\t<span class=\"label\">Entwickler: <\/span>\n\t\t\t<span class=\"value\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/play.google.com\/store\/apps\/developer?id=Deezer+Mobile\">Deezer Mobile<\/a><\/span>\n\t\t<\/div>\n\t\t<div class=\"price\">\n\t\t\t<span class=\"label\">Preis: <\/span>\n\t\t\t<span class=\"value\">Kostenlos<sup>+<\/sup><\/span> \n\t\t\t<span class=\"rating\"><div title=\"4.5 von 5 Sternen\" class=\"rating-stars stars-monochrome stars45\"><\/div><\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div><!-- \/WP-Appbox -->\n","protected":false},"excerpt":{"rendered":"<p>Kurzinfo f\u00fcr die Nutzer des Musik-Streamingdienstes Deezer unter iOS. Ab sofort geh\u00f6ren auch f\u00fcr euch unbekannte Songs der Vergangenheit an. Nachdem bereits im letzten Jahr die Android-User mit Deezers Musikerkennungsfunktion &#8222;SongCatcher&#8220; versorgt wurden, sind nun auch die User der entsprechenden&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":123012,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,232,152],"tags":[3734,1122,60065],"class_list":["post-123011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-ios","category-software","tag-deezer","tag-musikerkennung","tag-songcatcher-ios"],"wp_featured_image":{"id":123012,"alt_text":"","description":"","media_type":"image","media_details":{"width":1240,"height":840,"file":"2019\/07\/deezer-songcatcher-ios-1240x840.jpg","sizes":{"thumbnail":{"file":"deezer-songcatcher-ios-1240x840-303x205.jpg","width":303,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-303x205.jpg"},"medium":{"file":"deezer-songcatcher-ios-1240x840-500x339.jpg","width":500,"height":339,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-500x339.jpg"},"large":{"file":"deezer-songcatcher-ios-1240x840-810x549.jpg","width":810,"height":549,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-810x549.jpg"},"wp_review_large":{"file":"deezer-songcatcher-ios-1240x840-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-320x200.jpg"},"wp_review_small":{"file":"deezer-songcatcher-ios-1240x840-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-65x65.jpg"},"blog-large":{"file":"deezer-songcatcher-ios-1240x840-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-642x300.jpg"},"blog-medium":{"file":"deezer-songcatcher-ios-1240x840-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-306x205.jpg"},"recent-thumb":{"file":"deezer-songcatcher-ios-1240x840-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-350x316.jpg"},"service-featured":{"file":"deezer-songcatcher-ios-1240x840-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-600x330.jpg"},"wp_rp_thumbnail":{"file":"deezer-songcatcher-ios-1240x840-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":123011,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840.jpg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Deezer: &quot;SongCatcher&quot; Funktion nun auch f\u00fcr iOS verf\u00fcgbar - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deezer: &quot;SongCatcher&quot; Funktion nun auch f\u00fcr iOS verf\u00fcgbar\" \/>\n<meta property=\"og:description\" content=\"Kurzinfo f\u00fcr die Nutzer des Musik-Streamingdienstes Deezer unter iOS. Ab sofort geh\u00f6ren auch f\u00fcr euch unbekannte Songs der Vergangenheit an. Nachdem bereits im letzten Jahr die Android-User mit Deezers Musikerkennungsfunktion &#8222;SongCatcher&#8220; versorgt wurden, sind nun auch die User der entsprechenden&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-13T05:57:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Deezer: &#8222;SongCatcher&#8220; Funktion nun auch f\u00fcr iOS verf\u00fcgbar\",\"datePublished\":\"2019-07-13T05:57:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/\"},\"wordCount\":124,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/deezer-songcatcher-ios-1240x840.jpg\",\"keywords\":[\"Deezer\",\"Musikerkennung\",\"SongCatcher iOS\"],\"articleSection\":{\"1\":\"iOS\",\"2\":\"Software &amp; Updates\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/\",\"name\":\"Deezer: \\\"SongCatcher\\\" Funktion nun auch f\u00fcr iOS verf\u00fcgbar - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/deezer-songcatcher-ios-1240x840.jpg\",\"datePublished\":\"2019-07-13T05:57:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/deezer-songcatcher-ios-1240x840.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/deezer-songcatcher-ios-1240x840.jpg\",\"width\":1240,\"height\":840},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/13\\\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deezer: &#8222;SongCatcher&#8220; Funktion nun auch f\u00fcr iOS verf\u00fcgbar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Deezer: \"SongCatcher\" Funktion nun auch f\u00fcr iOS verf\u00fcgbar - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/","og_locale":"de_DE","og_type":"article","og_title":"Deezer: \"SongCatcher\" Funktion nun auch f\u00fcr iOS verf\u00fcgbar","og_description":"Kurzinfo f\u00fcr die Nutzer des Musik-Streamingdienstes Deezer unter iOS. Ab sofort geh\u00f6ren auch f\u00fcr euch unbekannte Songs der Vergangenheit an. Nachdem bereits im letzten Jahr die Android-User mit Deezers Musikerkennungsfunktion &#8222;SongCatcher&#8220; versorgt wurden, sind nun auch die User der entsprechenden&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2019-07-13T05:57:44+00:00","og_image":[{"width":1240,"height":840,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Deezer: &#8222;SongCatcher&#8220; Funktion nun auch f\u00fcr iOS verf\u00fcgbar","datePublished":"2019-07-13T05:57:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/"},"wordCount":124,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840.jpg","keywords":["Deezer","Musikerkennung","SongCatcher iOS"],"articleSection":{"1":"iOS","2":"Software &amp; Updates"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/","url":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/","name":"Deezer: \"SongCatcher\" Funktion nun auch f\u00fcr iOS verf\u00fcgbar - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840.jpg","datePublished":"2019-07-13T05:57:44+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840.jpg","width":1240,"height":840},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/13\/deezer-songcatcher-funktion-nun-auch-fuer-ios-verfuegbar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Deezer: &#8222;SongCatcher&#8220; Funktion nun auch f\u00fcr iOS verf\u00fcgbar"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deezer-songcatcher-ios-1240x840.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/123011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=123011"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/123011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/123012"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=123011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=123011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=123011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}