{"id":122819,"date":"2019-07-10T07:38:20","date_gmt":"2019-07-10T05:38:20","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=122819"},"modified":"2019-07-10T07:38:20","modified_gmt":"2019-07-10T05:38:20","slug":"windows-10-mobile-15254-575-update-9-juli","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/","title":{"rendered":"Windows 10 Mobile 15254.575 Update 9.Juli"},"content":{"rendered":"<p>Mal noch kurz nachgereicht. Auch die Windows 10 Mobile hat gestern ein weiteres kumulatives Update erhalten. Die ausgewiesene KB4509104 erscheint im Handy als 2019-07B Update f\u00fcr Windows 10 Version 1709 f\u00fcr arm-basierte Phone Ger\u00e4te.<\/p>\n<p>Wie immer werden hier die Updates der Windows 10 1709 integriert. Wovon einige Komponenten in der mobilen Version nicht enthalten sind. Aber da es sich um ein sicherheitsrelevantes Update handelt wurde hier einiges verbessert.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575.jpg\" rel=\"lightbox[122819]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-500x281.jpg\" alt=\"\" width=\"500\" height=\"281\" class=\"aligncenter size-medium wp-image-122821\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-500x281.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-306x172.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-810x456.jpg 810w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<ul>\n<li>Behebt ein Problem, das dazu f\u00fchren kann, dass BitLocker in den Wiederherstellungsmodus wechselt, wenn BitLocker gleichzeitig mit der Installation von Updates bereitgestellt wird. <\/li>\n<li>Sicherheitsupdates f\u00fcr Windows Wireless Networking, Windows Server, Microsoft Scripting Engine, Windows Speicher und Dateisysteme, Microsoft Grafikkomponente, Internet Explorer, Windows Eingabe und Zusammenstellung, Windows Virtualisierung, Windows App Plattform und Frameworks, Windows Grundlagen, Windows Kernel, Microsoft Edge und Windows Kryptographie. <\/li>\n<li><a href=\"https:\/\/support.microsoft.com\/de-de\/help\/4509104\/july-9-2019-kb4509104-os-build-15254-574\" rel=\"noopener noreferrer\" target=\"_blank\">support.microsoft<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mal noch kurz nachgereicht. Auch die Windows 10 Mobile hat gestern ein weiteres kumulatives Update erhalten. Die ausgewiesene KB4509104 erscheint im Handy als 2019-07B Update f\u00fcr Windows 10 Version 1709 f\u00fcr arm-basierte Phone Ger\u00e4te. Wie immer werden hier die Updates&hellip; <\/p>\n","protected":false},"author":134,"featured_media":122821,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3999],"tags":[59931,59930,7485],"class_list":["post-122819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windos-phone","tag-2019-07b-update","tag-kb4509104","tag-windows-10-mobile"],"wp_featured_image":{"id":122821,"alt_text":"","description":"","media_type":"image","media_details":{"width":2560,"height":1440,"file":"2019\/07\/windows-10-mobile-15254575.jpg","sizes":{"thumbnail":{"file":"windows-10-mobile-15254575-306x172.jpg","width":306,"height":172,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-306x172.jpg"},"medium":{"file":"windows-10-mobile-15254575-500x281.jpg","width":500,"height":281,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-500x281.jpg"},"large":{"file":"windows-10-mobile-15254575-810x456.jpg","width":810,"height":456,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-810x456.jpg"},"wp_review_large":{"file":"windows-10-mobile-15254575-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-320x200.jpg"},"wp_review_small":{"file":"windows-10-mobile-15254575-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-65x65.jpg"},"blog-large":{"file":"windows-10-mobile-15254575-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-642x300.jpg"},"blog-medium":{"file":"windows-10-mobile-15254575-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-306x205.jpg"},"recent-thumb":{"file":"windows-10-mobile-15254575-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-350x316.jpg"},"service-featured":{"file":"windows-10-mobile-15254575-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-600x330.jpg"},"wp_rp_thumbnail":{"file":"windows-10-mobile-15254575-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":122819,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575.jpg"},"commentcount":9,"wp_comments":[{"id":105613,"parent":0,"author":0,"author_name":"Ingridl","author_email":"Ingrid@attnetwork.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=96&d=mm&r=g"},"date":"2019-07-10T07:47:14","cld_nonce":"82f011626f","content":{"rendered":"<p>Und ich dachte mein 950 kriegt nichts mehr. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_razz.gif\" alt=\":-P\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":105614,"parent":0,"author":0,"author_name":"Blacktiger","author_email":"flabs@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/01ae7a1bf328c481be40fdd15000f7aac3c6946f3a0d561d0c6bee6dd79786ea?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/01ae7a1bf328c481be40fdd15000f7aac3c6946f3a0d561d0c6bee6dd79786ea?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/01ae7a1bf328c481be40fdd15000f7aac3c6946f3a0d561d0c6bee6dd79786ea?s=96&d=mm&r=g"},"date":"2019-07-10T08:00:24","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich dachte gerade auch so als ich das las. Na dann werde ich gleich mal mein 950 XL aktualisieren.<br \/>\nDanke Microsoft ? <\/p>\n<p><i>gepostet mit der <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.deskmodder\" >Deskmodder.de-App f\u00fcr Android<\/a><\/i><\/p>\n"},"status":"1"},{"id":105616,"parent":0,"author":0,"author_name":"trenQuo","author_email":"dan.bretschneider@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d0d04e5d04a4509d09a03a51ec1f408eba85fa8cdcfa1e04f013f4f6d4bb84d2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d0d04e5d04a4509d09a03a51ec1f408eba85fa8cdcfa1e04f013f4f6d4bb84d2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d0d04e5d04a4509d09a03a51ec1f408eba85fa8cdcfa1e04f013f4f6d4bb84d2?s=96&d=mm&r=g"},"date":"2019-07-10T08:30:11","cld_nonce":"82f011626f","content":{"rendered":"<p>Wenn dadurch auch Mail, Kalender und Kontakte wieder funktionieren \u2026<br \/>\nDie sind n\u00e4mlich leider seit 5 Tagen nicht mehr synchronisiert und werfen nur noch Fehlermeldungen. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_neutral.gif\" alt=\":|\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":105645,"parent":105616,"author":5617,"author_name":"Jacob","author_email":"verwaltung@jacobschindler.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b8c987d4b67c9f4baab0a7f73c947031c44c55fb9cdf3cb8c7ac3b923a1ecb32?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b8c987d4b67c9f4baab0a7f73c947031c44c55fb9cdf3cb8c7ac3b923a1ecb32?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b8c987d4b67c9f4baab0a7f73c947031c44c55fb9cdf3cb8c7ac3b923a1ecb32?s=96&d=mm&r=g"},"date":"2019-07-10T11:25:46","cld_nonce":"82f011626f","content":{"rendered":"<p>Ja, \u00c4hnliches auch bei meinem Lumia 650 DS. Die Synchronisierung l\u00e4uft, aber fehlerhaft. Viele Kontaktbilder zeigt die Kontakte-App im Lumia urpl\u00f6tzlich nicht mehr an, obwohl in Outlook 365, Web Outlook, Win 10 Kontakte App alle vorhanden sind und auch richtig dargestellt werden. Auch ein erneutes Verkn\u00fcpfen des MS-Kontos auf dem Lumia brachte keine L\u00f6sung.<br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":105807,"parent":105616,"author":0,"author_name":"FS","author_email":"sevenacids@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/859999bc2e9cb34e8480bea5abb12a4a072e6eb7d8e7e26ba94fede4c3ba65e0?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/859999bc2e9cb34e8480bea5abb12a4a072e6eb7d8e7e26ba94fede4c3ba65e0?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/859999bc2e9cb34e8480bea5abb12a4a072e6eb7d8e7e26ba94fede4c3ba65e0?s=96&d=mm&r=g"},"date":"2019-07-11T21:44:18","cld_nonce":"82f011626f","content":{"rendered":"<p>Kann ich nicht reproduzieren, Outlook-Mail und Kalender funktionieren hier einwandfrei, sowohl mit IMAP- als auch Exchange-Konten. Ich hatte nur eine Seltsamkeit, dass die Live Tiles nicht funktioniert haben und komplett leer angezeigt wurden, also auch kein Icon. Nach einem Neustart ging es aber wieder.<\/p>\n"},"status":"1"},{"id":105829,"parent":105807,"author":0,"author_name":"trenQuo","author_email":"dan.bretschneider@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d0d04e5d04a4509d09a03a51ec1f408eba85fa8cdcfa1e04f013f4f6d4bb84d2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d0d04e5d04a4509d09a03a51ec1f408eba85fa8cdcfa1e04f013f4f6d4bb84d2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d0d04e5d04a4509d09a03a51ec1f408eba85fa8cdcfa1e04f013f4f6d4bb84d2?s=96&d=mm&r=g"},"date":"2019-07-12T09:32:27","cld_nonce":"82f011626f","content":{"rendered":"<p>Hab&#8217;s Konto jetzt zum zweiten Mal entfernt und neu eingef\u00fcgt und es geht nun auch wieder. Allerdings hat sich dabei auch der Server hin zu outlook.office365.com ge\u00e4ndert. M\u00f6chte meinen, dass da zuvor etwas Anderes stand\u2026 Tats\u00e4chlich kam dieser Effekt auch schleichend. Zuerst war der Posteingang mit Relevanz weg, dann waren die Kalenderfarben anders und erst zwei oder drei Tage sp\u00e4ter ging nix mehr. ??<\/p>\n"},"status":"1"},{"id":105897,"parent":105829,"author":0,"author_name":"trenQuo","author_email":"dan.bretschneider@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d0d04e5d04a4509d09a03a51ec1f408eba85fa8cdcfa1e04f013f4f6d4bb84d2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d0d04e5d04a4509d09a03a51ec1f408eba85fa8cdcfa1e04f013f4f6d4bb84d2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d0d04e5d04a4509d09a03a51ec1f408eba85fa8cdcfa1e04f013f4f6d4bb84d2?s=96&d=mm&r=g"},"date":"2019-07-12T21:21:18","cld_nonce":"82f011626f","content":{"rendered":"<p>Irgendetwas ist trotzdem nicht ganz sauber. Jetzt funzt der Sync schon wieder nicht aufm Smartphone. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/><br \/>\nK\u00f6nnte irgendwelche Abh\u00e4ngigkeiten mit gekennzeichneten Mails in Microsoft ToDo vermuten, aber genau kann ich das auch nicht reproduzieren. Der Posteingang mit Relevanz ist zumindest weg &#8211; die Kalenderfarben passen hingegen noch. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":105959,"parent":0,"author":0,"author_name":"Skywriter","author_email":"weira91@munster.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/de91d46ccd44b639e9b988ba49cd47b814cbfddaec1154670760befa7b1ea0ba?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/de91d46ccd44b639e9b988ba49cd47b814cbfddaec1154670760befa7b1ea0ba?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/de91d46ccd44b639e9b988ba49cd47b814cbfddaec1154670760befa7b1ea0ba?s=96&d=mm&r=g"},"date":"2019-07-13T18:26:04","cld_nonce":"82f011626f","content":{"rendered":"<p>write:friert bei 2% ein &#8230;  <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_evil.gif\" alt=\":evil:\" class=\"wp-smiley\" \/> <\/p>\n<p><i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":105965,"parent":0,"author":0,"author_name":"weick siegfried","author_email":"weicksiegfried@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bda02e8932ccb19d33507b2b23dfe8b7ee77aa8905aef92fd07d0f58e88d8aa9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bda02e8932ccb19d33507b2b23dfe8b7ee77aa8905aef92fd07d0f58e88d8aa9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bda02e8932ccb19d33507b2b23dfe8b7ee77aa8905aef92fd07d0f58e88d8aa9?s=96&d=mm&r=g"},"date":"2019-07-13T22:22:57","cld_nonce":"82f011626f","content":{"rendered":"<p>Gott sei Dan hatte ich mit meinem Lumia 95 nie ernsthafte Probleme nur die Beh\u00f6rden stinken und<br \/>\nstrabazieren die Batterie trotz ausgeschaltetem GPS gestern z. B. habe ich in zwei Std. einkaufen 13%<br \/>\nBatterie verbraucht und jetzt zu hause in 30 Stunden nur 12% \u2026&#8230;und das ist mir schon x mal aufgefallen.<br \/>\nich bin gerade Rentner mit 65 Jahren nicht vorbestraft und keine Drogen ich Rauche nicht einmal<br \/>\nund drinke fast nur Bleifreies Bier &#8212;&#8211; Snowden hatte recht, hier werden unbeschlodete v\u00f6llig zu unrecht<br \/>\n\u00fcberwacht &#8212;-Sie machen weder vor dem Alter noch Rentnern halt &#8212;- Snowden ist der beste, denn der<br \/>\nhat gecheckt das nun alle Regierungen auf der Welt zu Mitlitante \u00dcberachungs Diktatoren werden \u2026\u2026\u2026\u2026.<br \/>\ndarum hoffe ich das Microsoft noch die Sicherheits Patches vom Lumia Windows Enterprices frei gibt<br \/>\nzum installieren &#8212;&#8212;&#8212;&#8212;&#8212; obwohl der Bill Gates daf\u00fcr war das IPhone zu Hacken und zu \u00fcberwachen,<br \/>\nda h\u00e4tten sich Gates und Steve Jobs bestimmt wieder gezofft &#8212;&#8211; man kann es mit Sicherheit auch  bis<br \/>\nzu Hitler und Nord Korea \u00fcbertreiben denn was den westen auszeichnete war Freiheit und annonymit\u00e4t,<br \/>\ndie jetzt Nord Korea in nichts nachsteht<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Windows 10 Mobile 15254.575 Update 9.Juli - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windows 10 Mobile 15254.575 Update 9.Juli\" \/>\n<meta property=\"og:description\" content=\"Mal noch kurz nachgereicht. Auch die Windows 10 Mobile hat gestern ein weiteres kumulatives Update erhalten. Die ausgewiesene KB4509104 erscheint im Handy als 2019-07B Update f\u00fcr Windows 10 Version 1709 f\u00fcr arm-basierte Phone Ger\u00e4te. Wie immer werden hier die Updates&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-10T05:38:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Windows 10 Mobile 15254.575 Update 9.Juli\",\"datePublished\":\"2019-07-10T05:38:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/\"},\"wordCount\":136,\"commentCount\":9,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/windows-10-mobile-15254575.jpg\",\"keywords\":[\"2019-07B Update\",\"KB4509104\",\"Windows 10 Mobile\"],\"articleSection\":[\"Windows Mobile\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/\",\"name\":\"Windows 10 Mobile 15254.575 Update 9.Juli - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/windows-10-mobile-15254575.jpg\",\"datePublished\":\"2019-07-10T05:38:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/windows-10-mobile-15254575.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/windows-10-mobile-15254575.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/10\\\/windows-10-mobile-15254-575-update-9-juli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Windows 10 Mobile 15254.575 Update 9.Juli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Windows 10 Mobile 15254.575 Update 9.Juli - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/","og_locale":"de_DE","og_type":"article","og_title":"Windows 10 Mobile 15254.575 Update 9.Juli","og_description":"Mal noch kurz nachgereicht. Auch die Windows 10 Mobile hat gestern ein weiteres kumulatives Update erhalten. Die ausgewiesene KB4509104 erscheint im Handy als 2019-07B Update f\u00fcr Windows 10 Version 1709 f\u00fcr arm-basierte Phone Ger\u00e4te. Wie immer werden hier die Updates&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2019-07-10T05:38:20+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Windows 10 Mobile 15254.575 Update 9.Juli","datePublished":"2019-07-10T05:38:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/"},"wordCount":136,"commentCount":9,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575.jpg","keywords":["2019-07B Update","KB4509104","Windows 10 Mobile"],"articleSection":["Windows Mobile"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/","url":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/","name":"Windows 10 Mobile 15254.575 Update 9.Juli - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575.jpg","datePublished":"2019-07-10T05:38:20+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/10\/windows-10-mobile-15254-575-update-9-juli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Windows 10 Mobile 15254.575 Update 9.Juli"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/windows-10-mobile-15254575.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/122819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=122819"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/122819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/122821"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=122819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=122819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=122819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}