{"id":122472,"date":"2019-07-04T19:35:01","date_gmt":"2019-07-04T17:35:01","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=122472"},"modified":"2019-07-12T19:05:15","modified_gmt":"2019-07-12T17:05:15","slug":"in-eigener-sache-blog-jetzt-mit-darkmode","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/","title":{"rendered":"In eigener Sache: Blog jetzt mit Darkmode"},"content":{"rendered":"<p>Er wurde sich immer wieder gew\u00fcnscht und auch in unseren Apps ist er sehr beliebt: Die Rede ist von einem Darkmode, der jetzt auch bei uns im Blog auf der Webseite verf\u00fcgbar ist.\u00a0Dieser ist automatisch aktiv, wenn man den Blog mit einem kompatiblen Browser (s.u.) aufruft und sein Betriebsystem auf das dunkle Farbschema eingestellt hat.<\/p>\n<div id=\"twenty20-1\" class=\"twenty20\" style=\"width: 100% !important; clear: both;\"><div class=\"twentytwenty-container twenty20-1 \"><img decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deskmodder-hell.jpg\" alt=\"Before image\" \/><img decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/deskmodder-dunkel.jpg\" alt=\"After image\" \/><\/div><\/div>\n<p>Aktuelle Versionen von Firefox und Safari unter Windows 10 bzw. macOS Mojave unterst\u00fctzen diese Funktion. Der Chrome-Browser \u00fcbernimmt ab Version 76 (erscheint am 30. Juli 2019) ebenfalls das Farbschema des Systems und ist dann auch mit unserem Darkmode kompatibel.\u00a0Android und iOS bekommen mit ihren n\u00e4chsten gro\u00dfen Updates im Herbst einen Darkmode spendiert.<\/p>\n<h4>Darkmode aktivieren unter Windows<\/h4>\n<ul>\n<li>Einstellungen -&gt; Personalisierung -&gt; Farben -&gt; Dunkel<\/li>\n<\/ul>\n<h4>Darkmode aktivieren unter macOS<\/h4>\n<ul>\n<li>Systemeinstellungen -&gt; Allgemein -&gt; Dunkel<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/macos-darkmode.png\" rel=\"lightbox[122472]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-122474\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/macos-darkmode-810x289.png\" alt=\"\" width=\"810\" height=\"289\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/macos-darkmode-810x289.png 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/macos-darkmode-306x109.png 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/macos-darkmode-500x178.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/07\/macos-darkmode.png 1586w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n<p><b>Hinweis 1:<\/b>\u00a0Einige Browser folgen nicht dem Farbschema des Betriebssystems und haben stattdessen eigene Einstellungen (z.B. Vivaldi o.\u00e4.). Will man nicht, dass der Firefox das Systemschema \u00fcbernimmt, dann kann man folgenden Eintrag unter &#8222;about:config&#8220; erstellen:<\/p>\n<pre>Name = ui.systemUsesDarkTheme\nTyp = Integer\n0 = hell\n1 = dunkel<\/pre>\n<p>Logischerweise gilt das dann f\u00fcr alle Webseiten mit einem solchen Darkmode und nicht nur f\u00fcr Deskmodder.<\/p>\n<p><b>Hinweis 2: <\/b>Eventuell m\u00fcsst ihr die Seite einmal &#8222;richtig&#8220; neu laden bzw. den Browser-Cache leeren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Er wurde sich immer wieder gew\u00fcnscht und auch in unseren Apps ist er sehr beliebt: Die Rede ist von einem Darkmode, der jetzt auch bei uns im Blog auf der Webseite verf\u00fcgbar ist.\u00a0Dieser ist automatisch aktiv, wenn man den Blog&hellip; <\/p>\n","protected":false},"author":1525,"featured_media":41749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[8279,24],"class_list":["post-122472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-darkmode","tag-deskmodder"],"wp_featured_image":{"id":41749,"alt_text":"","description":"","media_type":"image","media_details":{"width":820,"height":590,"file":"2015\/04\/deskmodder_a.png","sizes":{"thumbnail":{"file":"deskmodder_a-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a-150x150.png"},"medium":{"file":"deskmodder_a-150x108.png","width":150,"height":108,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a-150x108.png"},"large":{"file":"deskmodder_a-500x360.png","width":500,"height":360,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a-500x360.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":41708,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png"},"commentcount":34,"wp_comments":[{"id":105214,"parent":0,"author":0,"author_name":"Herta","author_email":"sdr@juz.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8ff64fa953e58093cafcdf08cd2385baa8a108a4102e3e12576e326f5e6f272f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8ff64fa953e58093cafcdf08cd2385baa8a108a4102e3e12576e326f5e6f272f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8ff64fa953e58093cafcdf08cd2385baa8a108a4102e3e12576e326f5e6f272f?s=96&d=mm&r=g"},"date":"2019-07-04T19:56:59","cld_nonce":"82f011626f","content":{"rendered":"<p>ALLES DUNKEL !!!<\/p>\n<p>Habe gerade meinen Browser untersucht, aber daran lag es nicht !!!<\/p>\n<p>ABER HALLO, SUPER, SUPER, SUPER  <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/> <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":105215,"parent":0,"author":4352,"author_name":"Knarf","author_email":"fic@mail.org","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f83d7eb5d26eb94d951c746ca33fc8ce17a5a215dc8b577d86658a35d96a9924?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f83d7eb5d26eb94d951c746ca33fc8ce17a5a215dc8b577d86658a35d96a9924?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f83d7eb5d26eb94d951c746ca33fc8ce17a5a215dc8b577d86658a35d96a9924?s=96&d=mm&r=g"},"date":"2019-07-04T19:57:42","cld_nonce":"82f011626f","content":{"rendered":"<p>L\u00fcppt unter Opera, sieht gut aus&#8230;<\/p>\n"},"status":"1"},{"id":105216,"parent":0,"author":3849,"author_name":"Dabbelju","author_email":"quadraturkreis@gmx.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ca5cd02b8c2c0baa4dd4678a0e7eaacacfa7b43cb3694ef51097ef95ebaef78b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ca5cd02b8c2c0baa4dd4678a0e7eaacacfa7b43cb3694ef51097ef95ebaef78b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ca5cd02b8c2c0baa4dd4678a0e7eaacacfa7b43cb3694ef51097ef95ebaef78b?s=96&d=mm&r=g"},"date":"2019-07-04T20:03:36","cld_nonce":"82f011626f","content":{"rendered":"<p>Jo, passt sehr gut !!!<\/p>\n"},"status":"1"},{"id":105218,"parent":105214,"author":0,"author_name":"Herta","author_email":"sdr@juz.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8ff64fa953e58093cafcdf08cd2385baa8a108a4102e3e12576e326f5e6f272f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8ff64fa953e58093cafcdf08cd2385baa8a108a4102e3e12576e326f5e6f272f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8ff64fa953e58093cafcdf08cd2385baa8a108a4102e3e12576e326f5e6f272f?s=96&d=mm&r=g"},"date":"2019-07-04T20:06:32","cld_nonce":"82f011626f","content":{"rendered":"<p>Der normale Opera bei mir nicht,<br \/>\nOpera GX funktioniert auch (Dark).<\/p>\n"},"status":"1"},{"id":105220,"parent":0,"author":4418,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2019-07-04T20:41:41","cld_nonce":"82f011626f","content":{"rendered":"<p>Hiiiilfe mein Monitor ist kapuutt <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_surprised.gif\" alt=\":o\" class=\"wp-smiley\" \/><\/p>\n<p><img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><\/p>\n<p>gibt es das evtl. f\u00fcr das Forum ???<\/p>\n"},"status":"1"},{"id":105223,"parent":0,"author":0,"author_name":"Atombunkschutzer","author_email":"kurtschnell@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dd2b2f2356b523c8b0c16d745e8d2fd4b4d4b7554b3bb113c5c9512d6cd6f91b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dd2b2f2356b523c8b0c16d745e8d2fd4b4d4b7554b3bb113c5c9512d6cd6f91b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dd2b2f2356b523c8b0c16d745e8d2fd4b4d4b7554b3bb113c5c9512d6cd6f91b?s=96&d=mm&r=g"},"date":"2019-07-04T21:25:32","cld_nonce":"82f011626f","content":{"rendered":"<p>???<\/p>\n"},"status":"1"},{"id":105224,"parent":0,"author":0,"author_name":"Daniel","author_email":"sth.daniel@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7be1f9dba36c1de76cbe24eb4fb45948830de12f40e73042e461e386a9534383?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7be1f9dba36c1de76cbe24eb4fb45948830de12f40e73042e461e386a9534383?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7be1f9dba36c1de76cbe24eb4fb45948830de12f40e73042e461e386a9534383?s=96&d=mm&r=g"},"date":"2019-07-04T21:31:39","cld_nonce":"82f011626f","content":{"rendered":"<p>Ist ja sch\u00f6n, dass die Webseite den Windows Einstellung folgt, es w\u00e4re aber trotzdem Hilfreich ein kleinen Schalter ein zu bauen, wo man es nachtr\u00e4glich \u00e4ndern kann. So kann auch jeder User selber entscheiden. ^^<\/p>\n"},"status":"1"},{"id":105225,"parent":105224,"author":4418,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2019-07-04T21:50:34","cld_nonce":"82f011626f","content":{"rendered":"<p>kann man doch, in den Einstellungen kann man w\u00e4hlen zwischen Hell \/ Dunkel &amp; Benutzerdefiniert<\/p>\n"},"status":"1"},{"id":105226,"parent":0,"author":4418,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2019-07-04T21:56:04","cld_nonce":"82f011626f","content":{"rendered":"<p>kleine Anmerkung,  vielleicht w\u00e4re es z.B. ( wie gepostetet Links in blau ) m\u00f6glich Fettschrift auch farblich darzustellen ?<\/p>\n"},"status":"1"},{"id":105227,"parent":0,"author":0,"author_name":"Hein Dattel","author_email":"hein.dattel@freenet.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/cc412428b94376f1fddfb8cdd66ef971e97a7337e97e3a640ffc74e138514461?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/cc412428b94376f1fddfb8cdd66ef971e97a7337e97e3a640ffc74e138514461?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/cc412428b94376f1fddfb8cdd66ef971e97a7337e97e3a640ffc74e138514461?s=96&d=mm&r=g"},"date":"2019-07-04T22:08:54","cld_nonce":"82f011626f","content":{"rendered":"<p>SUPER, sehr angenehm f\u00fcr die Augen, weiter so!<\/p>\n"},"status":"1"},{"id":105229,"parent":0,"author":3159,"author_name":"Scopeman","author_email":"thescopeman@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/d44eaed5cd70e7cb1528800b95980bce6d476caeb67dae710d1820c3e9fd7b87?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/d44eaed5cd70e7cb1528800b95980bce6d476caeb67dae710d1820c3e9fd7b87?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/d44eaed5cd70e7cb1528800b95980bce6d476caeb67dae710d1820c3e9fd7b87?s=96&d=mm&r=g"},"date":"2019-07-04T22:30:48","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich w\u00fcrde mir auch noch eine manuelle Einstellung der Webseite w\u00fcnschen, ich habe bei mir z.b den Windows-Modus auf Dunkel aber den App-Mods auf Hell. Ich mag den dunklen Explorer in Windows einfach nicht, kann ich micht nicht mit anfreunden. Dadurch wird die Webseite aber jetzt auch nicht dunkel. Meine Browser Chrome und Firefox habe ich manuell auf dunkel gestellt.<\/p>\n"},"status":"1"},{"id":105234,"parent":105225,"author":0,"author_name":"Daniel","author_email":"sth.daniel@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7be1f9dba36c1de76cbe24eb4fb45948830de12f40e73042e461e386a9534383?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7be1f9dba36c1de76cbe24eb4fb45948830de12f40e73042e461e386a9534383?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7be1f9dba36c1de76cbe24eb4fb45948830de12f40e73042e461e386a9534383?s=96&d=mm&r=g"},"date":"2019-07-04T23:54:08","cld_nonce":"82f011626f","content":{"rendered":"<p>Rede von der Webseite, nicht von Windows. Weiter unten ist ein \u00e4hnlich Post. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":105237,"parent":0,"author":3691,"author_name":"mcbloch","author_email":"mcbloch@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ff56e36a86e27ca9b7f00d90ece55ce3560732b7ead29c75c854c74c7cea7b4b?s=96&d=mm&r=g"},"date":"2019-07-05T03:50:07","cld_nonce":"82f011626f","content":{"rendered":"<p>Prima, klasse Idee.<br \/>\nWat freun sich meine \u00c4uglein.<\/p>\n"},"status":"1"},{"id":105238,"parent":0,"author":3658,"author_name":"ch4os","author_email":"court.miner@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b761210e941d1f99f21e75eb461a1a0ccc2d33b17eef5a84c43595a36eb5ec80?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b761210e941d1f99f21e75eb461a1a0ccc2d33b17eef5a84c43595a36eb5ec80?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b761210e941d1f99f21e75eb461a1a0ccc2d33b17eef5a84c43595a36eb5ec80?s=96&d=mm&r=g"},"date":"2019-07-05T04:08:54","cld_nonce":"82f011626f","content":{"rendered":"<p>M\u00fcsste das nicht auch unter iOS 13 schon funktionieren?<\/p>\n<p>Ich schau mir die Webseite gerade auf einem iPhone unter  Safari mit iOS 13 an, auf dem der Dark Mode aktiviert ist. Wird mir aber leider noch alles in wei\u00df angezeigt&#8230;<\/p>\n<p>Unter \u201eExperimental Features\u201c ist \u201eDark Mode CSS Support\u201c aktiviert.<\/p>\n"},"status":"1"},{"id":105239,"parent":105238,"author":1525,"author_name":"W8U","author_email":"windows-8-user@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"},"date":"2019-07-05T05:31:23","cld_nonce":"82f011626f","content":{"rendered":"<p>Ja, sollte auch unter iOS 13 (Beta) jetzt schon funktionieren. Hast du mal versucht, den Browsercache zu l\u00f6schen?<\/p>\n"},"status":"1"},{"id":105241,"parent":0,"author":4375,"author_name":"ll_h_a_r_r_y_ll","author_email":"ll_h_a_r_r_y_ll@yahoo.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/02ecb39f583fabf6bba0ecdc8418f5da5fb9ddbd9467349ef5678fa92024e098?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/02ecb39f583fabf6bba0ecdc8418f5da5fb9ddbd9467349ef5678fa92024e098?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/02ecb39f583fabf6bba0ecdc8418f5da5fb9ddbd9467349ef5678fa92024e098?s=96&d=mm&r=g"},"date":"2019-07-05T05:44:24","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich liebe den Darkroom &#8230;\u00e4hh Darkmode <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/> Fein gemacht.<br \/>\nOpera 62.0.3331.43<\/p>\n"},"status":"1"},{"id":105242,"parent":0,"author":3778,"author_name":"Grisu_1968","author_email":"ralferhardt@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/43359e66560020595daca0731f686b70ff9e2aabfbea2448b58316e993d2e4d2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/43359e66560020595daca0731f686b70ff9e2aabfbea2448b58316e993d2e4d2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/43359e66560020595daca0731f686b70ff9e2aabfbea2448b58316e993d2e4d2?s=96&d=mm&r=g"},"date":"2019-07-05T06:03:50","cld_nonce":"82f011626f","content":{"rendered":"<p>Edge in Windows fehlt noch und ein Schalter w\u00e4hre auch nicht schlecht. So wie es z.B Microsoft macht auf den docs Webseiten. -&gt; <a href=\"https:\/\/docs.microsoft.com\/de-de\/windows-hardware\/customize\/\" rel=\"nofollow ugc\">https:\/\/docs.microsoft.com\/de-de\/windows-hardware\/customize\/<\/a><\/p>\n"},"status":"1"},{"id":105244,"parent":0,"author":0,"author_name":"Ingridl","author_email":"Ingrid@attnetwork.net","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/13db960e39edc98e9bfa42cb4c2abad1b3f06a0a6015fdb1ca012025c04ffb13?s=96&d=mm&r=g"},"date":"2019-07-05T07:34:47","cld_nonce":"82f011626f","content":{"rendered":"<p>Kann sein das,das wer braucht <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_confused.gif\" alt=\":-?\" class=\"wp-smiley\" \/><br \/>\n<i>gepostet mit der <a href=\"https:\/\/www.microsoft.com\/store\/apps\/9wzdncrdfx92\" >Deskmodder.de-App<\/a><\/i><\/p>\n"},"status":"1"},{"id":105252,"parent":0,"author":3397,"author_name":"themaster","author_email":"scheaferchristian@hotmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/19fd7b1549908818a96b2adefadd7ef1faddce8775fe0aeb8031565ec41b2771?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/19fd7b1549908818a96b2adefadd7ef1faddce8775fe0aeb8031565ec41b2771?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/19fd7b1549908818a96b2adefadd7ef1faddce8775fe0aeb8031565ec41b2771?s=96&d=mm&r=g"},"date":"2019-07-05T09:20:41","cld_nonce":"82f011626f","content":{"rendered":"<p>Wie schon weiter oben gew\u00fcnscht bitte einen Schalter einbauen. On\/Off reicht ja. Danke.<\/p>\n"},"status":"1"},{"id":105257,"parent":0,"author":0,"author_name":"Nimda","author_email":"salve@salvete.ee","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4a71f9d9ec946a3e0526b3b30431f363ed8154c5453931902378c517ba712c07?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4a71f9d9ec946a3e0526b3b30431f363ed8154c5453931902378c517ba712c07?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4a71f9d9ec946a3e0526b3b30431f363ed8154c5453931902378c517ba712c07?s=96&d=mm&r=g"},"date":"2019-07-05T10:00:23","cld_nonce":"82f011626f","content":{"rendered":"<p>M\u00e4chtig gewaltig! Wie daheme&#8230; <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><br \/>\nWer braucht schon Cookies oder redundante Schalter? Das ist im Darknet so \u00fcberfl\u00fcssig, wie jahrelang herumgeschleppte wei\u00dfe Pixel an der Bommel. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_biggrin.gif\" alt=\":D\" class=\"wp-smiley\" \/><br \/>\n&#8211; Praktikant\/in ist informiert &#8211;<br \/>\nLG<\/p>\n"},"status":"1"},{"id":105260,"parent":0,"author":0,"author_name":"TiGo","author_email":"info@tinogottschalk.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3c90a63b17a4d5ba8774b079239cbe27f063554238465ac09f42f233222df61f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3c90a63b17a4d5ba8774b079239cbe27f063554238465ac09f42f233222df61f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3c90a63b17a4d5ba8774b079239cbe27f063554238465ac09f42f233222df61f?s=96&d=mm&r=g"},"date":"2019-07-05T10:55:47","cld_nonce":"82f011626f","content":{"rendered":"<p>like it !<\/p>\n"},"status":"1"},{"id":105261,"parent":0,"author":0,"author_name":"Micha","author_email":"m.b.1991@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e135d23e28766fe034ed5e1d484243da18e980fd02d25c9672295c9f8be681f?s=96&d=mm&r=g"},"date":"2019-07-05T10:56:57","cld_nonce":"82f011626f","content":{"rendered":"<p>Es schaut schon gut aus auch wenn ich die Apps f\u00fcr Windows und Android bevorzuge aber weiter so.  <\/p>\n<p><i>gepostet mit der <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.deskmodder\" >Deskmodder.de-App f\u00fcr Android<\/a><\/i><\/p>\n"},"status":"1"},{"id":105269,"parent":0,"author":0,"author_name":"danny_62","author_email":"danny.clover@outlook.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0af1df17a3bd23318f07385af3ae99a80c7b91794fd221c76c30ecbf5e7298c7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0af1df17a3bd23318f07385af3ae99a80c7b91794fd221c76c30ecbf5e7298c7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0af1df17a3bd23318f07385af3ae99a80c7b91794fd221c76c30ecbf5e7298c7?s=96&d=mm&r=g"},"date":"2019-07-05T13:35:31","cld_nonce":"82f011626f","content":{"rendered":"<p>Feine Sache&#8230;  <\/p>\n<p><i>gepostet mit der <a href='https:\/\/play.google.com\/store\/apps\/details?id=com.deskmodder' >Deskmodder.de-App f\u00fcr Android<\/a><\/i><\/p>\n"},"status":"1"},{"id":105281,"parent":0,"author":0,"author_name":"greedo","author_email":"greedo.ch@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e7b8a0b9547196e9e64fa6991495f316342bb3698ecfe20ef0201ad30a9941?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e7b8a0b9547196e9e64fa6991495f316342bb3698ecfe20ef0201ad30a9941?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e7b8a0b9547196e9e64fa6991495f316342bb3698ecfe20ef0201ad30a9941?s=96&d=mm&r=g"},"date":"2019-07-05T18:09:07","cld_nonce":"82f011626f","content":{"rendered":"<p>sehr sch\u00f6n! danke!<\/p>\n"},"status":"1"},{"id":105293,"parent":105220,"author":1525,"author_name":"W8U","author_email":"windows-8-user@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"},"date":"2019-07-05T20:09:53","cld_nonce":"82f011626f","content":{"rendered":"<p>Zurzeit ist noch nichts f\u00fcr das Forum (und auch das Wiki sowie die Tipp-Box) vorbereitet. Ich m\u00f6chte aber nicht ausschlie\u00dfen, dass wir irgendwann den Darkmode auch darauf ausweiten.<\/p>\n<p>Es steckt halt doch einiges an Arbeit drinnen, damit es auch alles schick ist und nicht nur so lieblos hingeklatscht wirkt.<\/p>\n"},"status":"1"},{"id":105299,"parent":105239,"author":3658,"author_name":"ch4os","author_email":"court.miner@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b761210e941d1f99f21e75eb461a1a0ccc2d33b17eef5a84c43595a36eb5ec80?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b761210e941d1f99f21e75eb461a1a0ccc2d33b17eef5a84c43595a36eb5ec80?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b761210e941d1f99f21e75eb461a1a0ccc2d33b17eef5a84c43595a36eb5ec80?s=96&d=mm&r=g"},"date":"2019-07-05T22:46:16","cld_nonce":"82f011626f","content":{"rendered":"<p>War tats\u00e4chlich die L\u00f6sung, danke dir <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/> Normaler Refresh hatte nicht geholfen.<\/p>\n"},"status":"1"},{"id":105300,"parent":105220,"author":4418,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2019-07-06T06:14:37","cld_nonce":"82f011626f","content":{"rendered":"<p>&#8222;&#8230; Ich m\u00f6chte aber nicht ausschlie\u00dfen&#8230;&#8220; &#8211; das ist doch schon mal eine Aussage ? und &#8222;Es steckt halt doch einiges an Arbeit drinnen&#8230;&#8220; denke ich dass das jedem klar sein d\u00fcrfte und nicht &#8222;mal eben&#8220; so in ein paar Minuten erledigt ist <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n<p>Hatte zwar ein &#8222;kleines Problem&#8220; diesen Darkmodus auch in 19H1 zu nutzen \/aktivieren<br \/>\n ( 20H1 und 2 weitere 19H1 sind als separate SSD\u00b4s vorhanden)<br \/>\n ( bei der 20H1 ging die Umstellung &#8222;automatisch&#8220;) &#8211; aber \u00e4hnlich wie bei dem Post<br \/>\n<a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/#comment-105239\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/#comment-105239<\/a><\/p>\n<p>funktionierte danach auch der Darkmodus in der 19H1 ( auf beiden 19H1 SSD\u00b4s ) <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n<p>gut gelungen ist \u00fcbrigens meines Erachtens die farblichen Unterschiede in der Sidebar der verschiedenen ISO\u00b4s ( rot &amp; blau ) wenn man mit der Maus dr\u00fcberf\u00e4hrt <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_wink.gif\" alt=\";)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":105878,"parent":0,"author":4291,"author_name":"Joern311","author_email":"joern.luehrs@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=96&d=mm&r=g"},"date":"2019-07-12T17:43:26","cld_nonce":"82f011626f","content":{"rendered":"<p>Moin,<br \/>\ngerade hat sich der Edge Canary , nach Update auf Version 218, auch auf Dark umgestellt.<br \/>\nSehr sch\u00f6n.<\/p>\n"},"status":"1"},{"id":105880,"parent":105878,"author":4418,"author_name":"Manny","author_email":"bluediversion63@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4df3fc4a774b00d7ea170af066c29586b73adb8f28bbf23cfbfccfadd55d8136?s=96&d=mm&r=g"},"date":"2019-07-12T17:47:30","cld_nonce":"82f011626f","content":{"rendered":"<p>ging aber schon vorher &#8211; zwar nicht bei allen System automatisch ( hatte ich auch ) aber  da half es den Browserverlauf zu l\u00f6schen , dann ging es auch da<\/p>\n<p>schrieb ich aber  auch schon da:<br \/>\n<a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/#comment-105300\" rel=\"ugc\">https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/#comment-105300<\/a><\/p>\n"},"status":"1"},{"id":105881,"parent":105880,"author":4291,"author_name":"Joern311","author_email":"joern.luehrs@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=96&d=mm&r=g"},"date":"2019-07-12T17:51:51","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich konnte mich nur dunkel an den Beitrag Erinnern und gerade nach dem Update wurde es pl\u00f6tzlich Dunkel.<br \/>\nAber ich hab auch gerade den Verlauf gel\u00f6scht, also deshalb <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":-)\" class=\"wp-smiley\" \/><br \/>\nSowas braucht der Vivaldi jetzt aber auch, Dringend!!<\/p>\n"},"status":"1"},{"id":105883,"parent":105880,"author":4241,"author_name":"Ben","author_email":"benderarsch@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3abca04fbbb53668b417dfa5443a66f6f95915a618be80392625a3e410e68440?s=96&d=mm&r=g"},"date":"2019-07-12T18:21:06","cld_nonce":"82f011626f","content":{"rendered":"<p>Strg+F5 sollte eigentlich auch reichen um die Seite komplett neu zu laden. Denn danach war sie bei mir dunkel, ohne das ich den Browserverlauf gel\u00f6scht habe.<\/p>\n"},"status":"1"},{"id":105885,"parent":105883,"author":4291,"author_name":"Joern311","author_email":"joern.luehrs@outlook.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e203520bc1637adc812561949b8524dc4f9e79551ce3c5cca229a2caafb5c2e5?s=96&d=mm&r=g"},"date":"2019-07-12T18:24:09","cld_nonce":"82f011626f","content":{"rendered":"<p>Jetzt hab ich es in der 20H1 auch. Da hat das l\u00f6schen des Verlaufs nicht gen\u00fcgt. Erst nachdem ich den Cache auch noch gereinigt habe wurde es Dunkel.<\/p>\n"},"status":"1"},{"id":105886,"parent":0,"author":1525,"author_name":"W8U","author_email":"windows-8-user@live.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"},"date":"2019-07-12T19:12:16","cld_nonce":"82f011626f","content":{"rendered":"<p>Kleine Erg\u00e4nzung: Oben unter Hinweis 1 ist jetzt eine M\u00f6glichkeit beschrieben, wie man den hellen oder dunklen Modus <strong>im Firefox<\/strong> unabh\u00e4ngig vom Systemschema erzwingen kann (f\u00fcr alle, die aktuell ohne einen Schalter bei uns auf der Seite gar nicht gl\u00fccklich sind).<\/p>\n"},"status":"1"},{"id":197195,"parent":0,"author":7813,"author_name":"-+_","author_email":"paradonym@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/de521e67b68e80c9ef1fe35ca56c9a53ea739da34c6c5ac6c4ef27bd9fed186f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/de521e67b68e80c9ef1fe35ca56c9a53ea739da34c6c5ac6c4ef27bd9fed186f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/de521e67b68e80c9ef1fe35ca56c9a53ea739da34c6c5ac6c4ef27bd9fed186f?s=96&d=mm&r=g"},"date":"2021-11-16T21:20:08","cld_nonce":"82f011626f","content":{"rendered":"<p>Das klappt leider bei mir unter Windows 11 nicht mehr. Firefox 94.0.1, system hat dark Mode aktiv und ui.systemUsesDarkTheme sitzt auf 1.<br \/>\nKomischerweise seit Reset des Firefox Profils als ich mir das ganze FF-Profil mal zerschossen habe&#8230;<\/p>\n"},"status":"1"}],"wp_author":{"id":1525,"name":"W8U","description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>In eigener Sache: Blog jetzt mit Darkmode - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In eigener Sache: Blog jetzt mit Darkmode\" \/>\n<meta property=\"og:description\" content=\"Er wurde sich immer wieder gew\u00fcnscht und auch in unseren Apps ist er sehr beliebt: Die Rede ist von einem Darkmode, der jetzt auch bei uns im Blog auf der Webseite verf\u00fcgbar ist.\u00a0Dieser ist automatisch aktiv, wenn man den Blog&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-04T17:35:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-12T17:05:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"W8U\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/\"},\"author\":{\"name\":\"W8U\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\"},\"headline\":\"In eigener Sache: Blog jetzt mit Darkmode\",\"datePublished\":\"2019-07-04T17:35:01+00:00\",\"dateModified\":\"2019-07-12T17:05:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/\"},\"wordCount\":216,\"commentCount\":34,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/deskmodder_a.png\",\"keywords\":[\"darkmode\",\"deskmodder\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/\",\"name\":\"In eigener Sache: Blog jetzt mit Darkmode - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/deskmodder_a.png\",\"datePublished\":\"2019-07-04T17:35:01+00:00\",\"dateModified\":\"2019-07-12T17:05:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/deskmodder_a.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/deskmodder_a.png\",\"width\":820,\"height\":590},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/07\\\/04\\\/in-eigener-sache-blog-jetzt-mit-darkmode\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In eigener Sache: Blog jetzt mit Darkmode\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\",\"name\":\"W8U\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"caption\":\"W8U\"},\"description\":\"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/w8u\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"In eigener Sache: Blog jetzt mit Darkmode - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/","og_locale":"de_DE","og_type":"article","og_title":"In eigener Sache: Blog jetzt mit Darkmode","og_description":"Er wurde sich immer wieder gew\u00fcnscht und auch in unseren Apps ist er sehr beliebt: Die Rede ist von einem Darkmode, der jetzt auch bei uns im Blog auf der Webseite verf\u00fcgbar ist.\u00a0Dieser ist automatisch aktiv, wenn man den Blog&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2019-07-04T17:35:01+00:00","article_modified_time":"2019-07-12T17:05:15+00:00","og_image":[{"width":820,"height":590,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png","type":"image\/png"}],"author":"W8U","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/"},"author":{"name":"W8U","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469"},"headline":"In eigener Sache: Blog jetzt mit Darkmode","datePublished":"2019-07-04T17:35:01+00:00","dateModified":"2019-07-12T17:05:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/"},"wordCount":216,"commentCount":34,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png","keywords":["darkmode","deskmodder"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/","url":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/","name":"In eigener Sache: Blog jetzt mit Darkmode - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png","datePublished":"2019-07-04T17:35:01+00:00","dateModified":"2019-07-12T17:05:15+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png","width":820,"height":590},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/07\/04\/in-eigener-sache-blog-jetzt-mit-darkmode\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"In eigener Sache: Blog jetzt mit Darkmode"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469","name":"W8U","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","caption":"W8U"},"description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","url":"https:\/\/www.deskmodder.de\/blog\/author\/w8u\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/04\/deskmodder_a.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/122472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/1525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=122472"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/122472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/41749"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=122472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=122472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=122472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}