{"id":116701,"date":"2019-03-06T16:59:34","date_gmt":"2019-03-06T15:59:34","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=116701"},"modified":"2019-03-06T17:58:42","modified_gmt":"2019-03-06T16:58:42","slug":"adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/","title":{"rendered":"Adware Apps vom Google Play Store simulieren nur eine Deinstallation und werkeln weiter"},"content":{"rendered":"<p>Lukas Stefanko (Eset) hat drei Apps im Google Play Store entdeckt, die vorgeben Kamera-Apps zu sein, aber nur Werbezwecken dienen. Denn nach der Installation und dem ersten Start der App, wird die Verkn\u00fcpfung auf dem Startbildschirm versteckt. Somit kann sie nicht mehr \u00fcber diesen Weg deinstalliert werden.<\/p>\n<p>Es handelt sich dabei um die Apps Excellent Camera, Ideal Camera: Full Featured Camera for Android und Super Camera Lite 2019 mit immerhin zusammen \u00fcber 700.000 Installationen. Damit es nicht auff\u00e4llt haben die Apps drei verschiedene Entwickler eingereicht.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps.jpg\" rel=\"lightbox[116701]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps-500x293.jpg\" alt=\"\" width=\"500\" height=\"293\" class=\"aligncenter size-medium wp-image-116703\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps-500x293.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps-306x180.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps.jpg 629w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Diese einfache Variante Apps zu deinstallieren wurde mit Android 6.0 &#8222;Marshmallow&#8220; eingef\u00fchrt, indem man die Verkn\u00fcpfung einfach nur nach oben zieht. Zum Gl\u00fcck gibt es aber noch andere M\u00f6glichkeiten, die Lukas Stefanko in dem kleinen Video zeigt.<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"de\">\n<p lang=\"en\" dir=\"ltr\">Remove is not Uninstall<\/p>\n<p>Found 3 apps on Google Play with over 700,000 installs that use interesting persistence technique.<\/p>\n<p>When user realizes app is not as described, he can only remove the app icon not uninstall the app itself.<\/p>\n<p>How it works I explained it in the video: <a href=\"https:\/\/t.co\/HrAVw6TTLq\">pic.twitter.com\/HrAVw6TTLq<\/a><\/p>\n<p>&mdash; Lukas Stefanko (@LukasStefanko) <a href=\"https:\/\/twitter.com\/LukasStefanko\/status\/1102889352118616064?ref_src=twsrc%5Etfw\">5. M\u00e4rz 2019<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Ist schon irre, auf welche Varianten die schwarzen Schafe doch immer wieder kommen. Denn ein normaler Nutzer, der nur noch den Weg \u00fcber den Startbildschirm kennt, wird sicherlich nicht weiter forschen und die App App sein lassen. Denn wer wei\u00df schon, dass sich die App zum Beispiel auch \u00fcber den Play Store auch wieder deinstallieren lassen.<\/p>\n<div class=\"viaquelle\">via: <a href=\"https:\/\/www.bleepingcomputer.com\/news\/security\/adware-apps-in-google-play-simulate-uninstall-for-persistence\/\" rel=\"noopener noreferrer\" target=\"_blank\">bleepingcomputer<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lukas Stefanko (Eset) hat drei Apps im Google Play Store entdeckt, die vorgeben Kamera-Apps zu sein, aber nur Werbezwecken dienen. Denn nach der Installation und dem ersten Start der App, wird die Verkn\u00fcpfung auf dem Startbildschirm versteckt. Somit kann sie&hellip; <\/p>\n","protected":false},"author":134,"featured_media":116703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[894],"tags":[53774,9747,53771,53772,53773],"class_list":["post-116701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-android","tag-adware-apps","tag-android","tag-excellent-camera","tag-ideal-camera-full-featured-camera-for-android","tag-super-camera-lite-2019"],"wp_featured_image":{"id":116703,"alt_text":"","description":"","media_type":"image","media_details":{"width":629,"height":369,"file":"2019\/03\/android-adware-apps.jpg","sizes":{"thumbnail":{"file":"android-adware-apps-306x180.jpg","width":306,"height":180,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps-306x180.jpg"},"medium":{"file":"android-adware-apps-500x293.jpg","width":500,"height":293,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps-500x293.jpg"},"wp_review_large":{"file":"android-adware-apps-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps-320x200.jpg"},"wp_review_small":{"file":"android-adware-apps-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps-65x65.jpg"},"blog-large":{"file":"android-adware-apps-629x300.jpg","width":629,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps-629x300.jpg"},"blog-medium":{"file":"android-adware-apps-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps-306x205.jpg"},"recent-thumb":{"file":"android-adware-apps-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps-350x316.jpg"},"service-featured":{"file":"android-adware-apps-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps-600x330.jpg"},"wp_rp_thumbnail":{"file":"android-adware-apps-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":116701,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps.jpg"},"commentcount":4,"wp_comments":[{"id":94948,"parent":0,"author":0,"author_name":"harald","author_email":"gagges@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a77634de171c0f14a5c530d83b30c80488fb52357948b9b4bc2bb0c8e12d9277?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a77634de171c0f14a5c530d83b30c80488fb52357948b9b4bc2bb0c8e12d9277?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a77634de171c0f14a5c530d83b30c80488fb52357948b9b4bc2bb0c8e12d9277?s=96&d=mm&r=g"},"date":"2019-03-06T22:43:13","cld_nonce":"82f011626f","content":{"rendered":"<p>&#8222;der normale User der nur den Weg mit nach oben schieben kennt &#8230;&#8220;  ist f\u00fcr mich jedenfalls ein unnormaler! Solche Kniffe sind doch absolut nirgens wirklich beschrieben. Wenn er sich schon solche Sachen aneignet wird er auch in der Lage sein ganz klassisch unter Einstellungen-&gt;Apps zu gehen und dort wie \u00fcblich alles zu machen. Wenn nicht &#8230; Unnormal.<\/p>\n"},"status":"1"},{"id":94949,"parent":0,"author":2371,"author_name":"Birkuli","author_email":"birkuli@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/779ab74708368fd5da13cb60a3093905cb0f2da05766b9cd0bb8b5249744b5a9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/779ab74708368fd5da13cb60a3093905cb0f2da05766b9cd0bb8b5249744b5a9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/779ab74708368fd5da13cb60a3093905cb0f2da05766b9cd0bb8b5249744b5a9?s=96&d=mm&r=g"},"date":"2019-03-06T22:46:45","cld_nonce":"82f011626f","content":{"rendered":"<p>Hersteller solcher Apps gleich eine fette Abmahnung verpassen und Minimum 1 Million \u20ac Strafe pro vergehen aufbrummen, wer so kriminell handelt sollte h\u00e4rtest bestraft werden!<br \/>\nUnd nat\u00fcrlich sofort aus dem Store schmei\u00dfen.<\/p>\n"},"status":"1"},{"id":94951,"parent":94948,"author":0,"author_name":"Micha","author_email":"NewRaven@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/dc810fd7df1490a85737f0d627615352d8bac4ad5c8d32ef045de2df3b0add2a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/dc810fd7df1490a85737f0d627615352d8bac4ad5c8d32ef045de2df3b0add2a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/dc810fd7df1490a85737f0d627615352d8bac4ad5c8d32ef045de2df3b0add2a?s=96&d=mm&r=g"},"date":"2019-03-06T22:56:23","cld_nonce":"82f011626f","content":{"rendered":"<p>Seh ich eigentlich auch so. Wer wirklich versucht eine App zu deinstallieren und dessen Kenntnisse, Motivation oder wegen mir auch Experimentierfreude schon damit ersch\u00f6pft ist, dass er nicht wei\u00df, wie er eine App abseits vom Drag-n-Drop auf dem Homescreen m\u00f6glicherweise noch deinstallieren kann, der hat vermutlich bei der Nutzung seines Smartphones noch ganz andere Probleme.<\/p>\n"},"status":"1"},{"id":94957,"parent":0,"author":0,"author_name":"Guido","author_email":"Radiohead@kabelmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/72c656d2e111fb9405f4b8078fbff5f668171f830dc65376e532d79c1d6241d5?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/72c656d2e111fb9405f4b8078fbff5f668171f830dc65376e532d79c1d6241d5?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/72c656d2e111fb9405f4b8078fbff5f668171f830dc65376e532d79c1d6241d5?s=96&d=mm&r=g"},"date":"2019-03-07T00:10:04","cld_nonce":"82f011626f","content":{"rendered":"<p>Die Verantwortung liegt bei Google. Da helfen auch keine Abmahnungen. ein Gro\u00dfteil der Android-Apps aus dem Google Play Store sind mit Tracker- und Werbemodule geradezu \u00bbzugepflastert\u00ab. Weiterhin haben wir keinen Einblick in die eigentliche Datenverarbeitung bzw. welche Daten bei der Nutzung \u00fcbermittelt werden.<\/p>\n<p>Ich beziehe meine Apps mittlerweile nur noch aus dem F-Droid Store.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adware Apps vom Google Play Store simulieren nur eine Deinstallation und werkeln weiter - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adware Apps vom Google Play Store simulieren nur eine Deinstallation und werkeln weiter\" \/>\n<meta property=\"og:description\" content=\"Lukas Stefanko (Eset) hat drei Apps im Google Play Store entdeckt, die vorgeben Kamera-Apps zu sein, aber nur Werbezwecken dienen. Denn nach der Installation und dem ersten Start der App, wird die Verkn\u00fcpfung auf dem Startbildschirm versteckt. Somit kann sie&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-06T15:59:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-06T16:58:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"629\" \/>\n\t<meta property=\"og:image:height\" content=\"369\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Adware Apps vom Google Play Store simulieren nur eine Deinstallation und werkeln weiter\",\"datePublished\":\"2019-03-06T15:59:34+00:00\",\"dateModified\":\"2019-03-06T16:58:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/\"},\"wordCount\":255,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/android-adware-apps.jpg\",\"keywords\":[\"Adware Apps\",\"Android\",\"Excellent Camera\",\"Ideal Camera: Full Featured Camera for Android\",\"Super Camera Lite 2019\"],\"articleSection\":[\"Android\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/\",\"name\":\"Adware Apps vom Google Play Store simulieren nur eine Deinstallation und werkeln weiter - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/android-adware-apps.jpg\",\"datePublished\":\"2019-03-06T15:59:34+00:00\",\"dateModified\":\"2019-03-06T16:58:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/android-adware-apps.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/android-adware-apps.jpg\",\"width\":629,\"height\":369},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/03\\\/06\\\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adware Apps vom Google Play Store simulieren nur eine Deinstallation und werkeln weiter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adware Apps vom Google Play Store simulieren nur eine Deinstallation und werkeln weiter - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/","og_locale":"de_DE","og_type":"article","og_title":"Adware Apps vom Google Play Store simulieren nur eine Deinstallation und werkeln weiter","og_description":"Lukas Stefanko (Eset) hat drei Apps im Google Play Store entdeckt, die vorgeben Kamera-Apps zu sein, aber nur Werbezwecken dienen. Denn nach der Installation und dem ersten Start der App, wird die Verkn\u00fcpfung auf dem Startbildschirm versteckt. Somit kann sie&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2019-03-06T15:59:34+00:00","article_modified_time":"2019-03-06T16:58:42+00:00","og_image":[{"width":629,"height":369,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps.jpg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Adware Apps vom Google Play Store simulieren nur eine Deinstallation und werkeln weiter","datePublished":"2019-03-06T15:59:34+00:00","dateModified":"2019-03-06T16:58:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/"},"wordCount":255,"commentCount":4,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps.jpg","keywords":["Adware Apps","Android","Excellent Camera","Ideal Camera: Full Featured Camera for Android","Super Camera Lite 2019"],"articleSection":["Android"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/","url":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/","name":"Adware Apps vom Google Play Store simulieren nur eine Deinstallation und werkeln weiter - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps.jpg","datePublished":"2019-03-06T15:59:34+00:00","dateModified":"2019-03-06T16:58:42+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps.jpg","width":629,"height":369},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/03\/06\/adware-apps-in-google-play-simulieren-nur-eine-deinstallation-und-werkeln-weiter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Adware Apps vom Google Play Store simulieren nur eine Deinstallation und werkeln weiter"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/03\/android-adware-apps.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/116701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=116701"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/116701\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/116703"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=116701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=116701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=116701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}