{"id":115211,"date":"2019-02-08T13:22:08","date_gmt":"2019-02-08T12:22:08","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=115211"},"modified":"2019-02-08T14:22:35","modified_gmt":"2019-02-08T13:22:35","slug":"ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/","title":{"rendered":"iOS 12.1.4 behebt FaceTime Bug &#8211; 14 j\u00e4hriger Bug-Finder erh\u00e4lt Zuschuss zur Ausbildung"},"content":{"rendered":"<p>Apple hat den FaceTime Bug (&#8222;CVE-2019-6223&#8220;) in der neuen Version  iOS 12.1.4 nun behoben. Der Fehler hatte es m\u00f6glich gemacht, dass man schon Stimmen von Leuten h\u00f6rte, die auf den Videoanruf noch nicht geantwortet hatten. Gefunden hat diesen Fehler ein 14-j\u00e4hriger aus Arizona.<\/p>\n<p>Anders als im <a href=\"https:\/\/www.deskmodder.de\/blog\/2019\/02\/07\/gravierende-sicherheitsluecke-in-apples-macos\/\" rel=\"noopener\" target=\"_blank\">gestrigen Bericht<\/a>, hat Apple diesmal einen Betrag freiwillig eine Belohnung bezahlt. In welcher H\u00f6he ist nicht bekannt. Apple will f\u00fcr Grant Thompson Geld in einen Fond f\u00fcr seine Ausbildung einzahlen. Fr\u00fcher wurden im Bug-Bounty Programm zwischen 25.000 und 200.000 Dollar bezahlt. Laut Reuters will Apple kommende Softwarefehler schneller auswerten und beheben.<\/p>\n<p>Neben der schon beschriebenen L\u00fccke hat FaceTime zus\u00e4tzlich noch ein Patch f\u00fcr die Live Fotos erhalten. Sowie einen Fix f\u00fcr das IOKit, der es Apps zuvor erlaubt hat, Code mit Kernel-Rechten auszuf\u00fchren. Mehr zum Update: <a href=\"https:\/\/support.apple.com\/en-us\/HT209520\" rel=\"noopener\" target=\"_blank\">support.apple.com\/en-us\/HT209520<\/a><\/p>\n<div class=\"quellenzeile\"><div class=\"quelle\">Quelle: <a href=\"https:\/\/uk.reuters.com\/article\/us-apple-patch\/apple-to-contribute-to-u-s-teens-education-for-spotting-facetime-bug-idUKKCN1PW2E0\" rel=\"noopener\" target=\"_blank\">reuters<\/a><\/div> <div class=\"viaquelle\">via: <a href=\"https:\/\/www.neowin.net\/news\/apple-releases-ios-1214-fixing-group-facetime-security-flaw\" rel=\"noopener\" target=\"_blank\">neowin<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apple hat den FaceTime Bug (&#8222;CVE-2019-6223&#8220;) in der neuen Version iOS 12.1.4 nun behoben. Der Fehler hatte es m\u00f6glich gemacht, dass man schon Stimmen von Leuten h\u00f6rte, die auf den Videoanruf noch nicht geantwortet hatten. Gefunden hat diesen Fehler ein&hellip; <\/p>\n","protected":false},"author":134,"featured_media":18014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[232],"tags":[98,52233],"class_list":["post-115211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ios","tag-apple","tag-ios-12-1-4"],"wp_featured_image":{"id":18014,"alt_text":"","description":"","media_type":"image","media_details":{"width":200,"height":221,"file":"2013\/12\/200px-Apple_1976_logo_svg.png","sizes":{"thumbnail":{"file":"200px-Apple_1976_logo_svg-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/200px-Apple_1976_logo_svg-150x150.png"},"medium":{"file":"200px-Apple_1976_logo_svg-135x150.png","width":135,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/200px-Apple_1976_logo_svg-135x150.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":17945,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/200px-Apple_1976_logo_svg.png"},"commentcount":2,"wp_comments":[{"id":93204,"parent":0,"author":0,"author_name":"Arno Nym","author_email":"arnonym@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ddcad946bd1723cebc7bd51c5d92778601c6340aed490a1b88207c9f1f4ed897?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ddcad946bd1723cebc7bd51c5d92778601c6340aed490a1b88207c9f1f4ed897?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ddcad946bd1723cebc7bd51c5d92778601c6340aed490a1b88207c9f1f4ed897?s=96&d=mm&r=g"},"date":"2019-02-08T14:01:39","cld_nonce":"82f011626f","content":{"rendered":"<p>Liebes Deskmodder-Team,<\/p>\n<p>diesen Artikel solltet Ihr nochmal dringend zur Korrektur lesen&#8230;<\/p>\n<p>Viele Gr\u00fc\u00dfe<br \/>\nArno Nym<\/p>\n"},"status":"1"},{"id":93334,"parent":0,"author":0,"author_name":"Mario Kr\u00e4mer","author_email":"swiffer25@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f48f387e4dfc06a149abc987c683fa877cec9a84bcc4f9c0e752d2d359be182e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f48f387e4dfc06a149abc987c683fa877cec9a84bcc4f9c0e752d2d359be182e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f48f387e4dfc06a149abc987c683fa877cec9a84bcc4f9c0e752d2d359be182e?s=96&d=mm&r=g"},"date":"2019-02-10T13:14:05","cld_nonce":"82f011626f","content":{"rendered":"<p>Das finde ich extrem fein von APPLE.<br \/>\nAusbildung kostet Geld, und in den USA sowieso.<br \/>\nGl\u00fcckwunsch an Grant Thompson <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_smile.gif\" alt=\":)\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>iOS 12.1.4 behebt FaceTime Bug - 14 j\u00e4hriger Bug-Finder erh\u00e4lt Zuschuss zur Ausbildung - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"iOS 12.1.4 behebt FaceTime Bug - 14 j\u00e4hriger Bug-Finder erh\u00e4lt Zuschuss zur Ausbildung\" \/>\n<meta property=\"og:description\" content=\"Apple hat den FaceTime Bug (&#8222;CVE-2019-6223&#8220;) in der neuen Version iOS 12.1.4 nun behoben. Der Fehler hatte es m\u00f6glich gemacht, dass man schon Stimmen von Leuten h\u00f6rte, die auf den Videoanruf noch nicht geantwortet hatten. Gefunden hat diesen Fehler ein&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-08T12:22:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-08T13:22:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/200px-Apple_1976_logo_svg.png\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"221\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"iOS 12.1.4 behebt FaceTime Bug &#8211; 14 j\u00e4hriger Bug-Finder erh\u00e4lt Zuschuss zur Ausbildung\",\"datePublished\":\"2019-02-08T12:22:08+00:00\",\"dateModified\":\"2019-02-08T13:22:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/\"},\"wordCount\":170,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/200px-Apple_1976_logo_svg.png\",\"keywords\":[\"Apple\",\"iOS 12.1.4\"],\"articleSection\":[\"iOS\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/\",\"name\":\"iOS 12.1.4 behebt FaceTime Bug - 14 j\u00e4hriger Bug-Finder erh\u00e4lt Zuschuss zur Ausbildung - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/200px-Apple_1976_logo_svg.png\",\"datePublished\":\"2019-02-08T12:22:08+00:00\",\"dateModified\":\"2019-02-08T13:22:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/200px-Apple_1976_logo_svg.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/200px-Apple_1976_logo_svg.png\",\"width\":200,\"height\":221},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/08\\\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"iOS 12.1.4 behebt FaceTime Bug &#8211; 14 j\u00e4hriger Bug-Finder erh\u00e4lt Zuschuss zur Ausbildung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"iOS 12.1.4 behebt FaceTime Bug - 14 j\u00e4hriger Bug-Finder erh\u00e4lt Zuschuss zur Ausbildung - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/","og_locale":"de_DE","og_type":"article","og_title":"iOS 12.1.4 behebt FaceTime Bug - 14 j\u00e4hriger Bug-Finder erh\u00e4lt Zuschuss zur Ausbildung","og_description":"Apple hat den FaceTime Bug (&#8222;CVE-2019-6223&#8220;) in der neuen Version iOS 12.1.4 nun behoben. Der Fehler hatte es m\u00f6glich gemacht, dass man schon Stimmen von Leuten h\u00f6rte, die auf den Videoanruf noch nicht geantwortet hatten. Gefunden hat diesen Fehler ein&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2019-02-08T12:22:08+00:00","article_modified_time":"2019-02-08T13:22:35+00:00","og_image":[{"width":200,"height":221,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/200px-Apple_1976_logo_svg.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"iOS 12.1.4 behebt FaceTime Bug &#8211; 14 j\u00e4hriger Bug-Finder erh\u00e4lt Zuschuss zur Ausbildung","datePublished":"2019-02-08T12:22:08+00:00","dateModified":"2019-02-08T13:22:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/"},"wordCount":170,"commentCount":2,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/200px-Apple_1976_logo_svg.png","keywords":["Apple","iOS 12.1.4"],"articleSection":["iOS"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/","url":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/","name":"iOS 12.1.4 behebt FaceTime Bug - 14 j\u00e4hriger Bug-Finder erh\u00e4lt Zuschuss zur Ausbildung - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/200px-Apple_1976_logo_svg.png","datePublished":"2019-02-08T12:22:08+00:00","dateModified":"2019-02-08T13:22:35+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/200px-Apple_1976_logo_svg.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/200px-Apple_1976_logo_svg.png","width":200,"height":221},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/08\/ios-12-1-4-behebt-facetime-bug-14-jaehriger-bug-finder-erhaelt-zuschuss-zur-ausbildung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"iOS 12.1.4 behebt FaceTime Bug &#8211; 14 j\u00e4hriger Bug-Finder erh\u00e4lt Zuschuss zur Ausbildung"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/12\/200px-Apple_1976_logo_svg.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/115211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=115211"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/115211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/18014"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=115211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=115211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=115211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}