{"id":114977,"date":"2019-02-05T10:14:02","date_gmt":"2019-02-05T09:14:02","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=114977"},"modified":"2019-02-05T12:26:17","modified_gmt":"2019-02-05T11:26:17","slug":"android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/","title":{"rendered":"Android Sicherheits-Patch Februar 2019 &#8211; OTA f\u00fcr Pixel und Nexus"},"content":{"rendered":"<p>Kurz notiert: Google hat das monatliche Sicherheitsupdate f\u00fcr den Februar 2019 bereitgestellt. Wie immer sind die Pixel und Nexus Ger\u00e4te die Ersten, die diesen Patch erhalten. Alle anderen werden je nach Hersteller nach und nach dieses Update dann erhalten. Der Patch enth\u00e4lt die aufgef\u00fchrten Schwachstellen vom 1.02.2019 und 4.02.2019.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/02\/screenshot-20190205-084149-1.png\" rel=\"lightbox[114977]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/02\/screenshot-20190205-084149-1-500x326.png\" alt=\"\" width=\"500\" height=\"326\" class=\"aligncenter size-medium wp-image-114971\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/02\/screenshot-20190205-084149-1-500x326.png 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/02\/screenshot-20190205-084149-1-306x200.png 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/02\/screenshot-20190205-084149-1-810x529.png 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/02\/screenshot-20190205-084149-1.png 1440w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Die Liste der behobenen Sicherheitsl\u00fccken ist sehr lang und betrifft soweit alle Komponenten. Google hatte mit 11 &#8222;kritischen&#8220; und 30 &#8222;problematischen&#8220; Problemen zu k\u00e4mpfen. Die meisten Fehler wurden im Qualcomm- und Systembereich gefunden und behoben. Das Update wird in Wellen verteilt und sollte im Laufe des Tages bei den entsprechenden Ger\u00e4ten erscheinen. Diese k\u00f6nnt ihr euch hier genauer anschauen <a href=\"https:\/\/source.android.com\/security\/bulletin\/2019-02-01\" rel=\"noopener\" target=\"_blank\">source.android.com\/security\/bulletin\/2019-02<\/a>.<\/p>\n<p>Wer keine Lust hat zu warten, kann sich die entsprechenden OTA Images oder Factory Images herunterladen.<\/p>\n<ul>\n<li><a href=\"https:\/\/developers.google.com\/android\/ota\" target=\"_blank\" rel=\"noopener\">OTA Images<\/a><\/li>\n<li><a href=\"https:\/\/developers.google.com\/android\/images\">Factory Images<\/a><\/li>\n<li><a href=\"https:\/\/source.android.com\/security\/bulletin\/pixel\/2019-02-01\">Pixel Update Bulletin<\/a><\/li>\n<li><a href=\"https:\/\/source.android.com\/security\/bulletin\/2019-02-01\">Android Security Bulletin<\/a><\/li>\n<\/ul>\n<p><em>Beitrag erweitert. Danke an  Jonas<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kurz notiert: Google hat das monatliche Sicherheitsupdate f\u00fcr den Februar 2019 bereitgestellt. Wie immer sind die Pixel und Nexus Ger\u00e4te die Ersten, die diesen Patch erhalten. Alle anderen werden je nach Hersteller nach und nach dieses Update dann erhalten. Der&hellip; <\/p>\n","protected":false},"author":134,"featured_media":43004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[894],"tags":[9747,52083,14644,4501,13276],"class_list":["post-114977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-android","tag-android","tag-februar-2019","tag-google-pixel","tag-nexus","tag-sicherheitspatch"],"wp_featured_image":{"id":43004,"alt_text":"","description":"","media_type":"image","media_details":{"width":500,"height":360,"file":"2015\/05\/category_android.png","sizes":{"thumbnail":{"file":"category_android-250x180.png","width":250,"height":180,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/05\/category_android-250x180.png"},"large":{"file":"category_android-700x504.png","width":700,"height":504,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/05\/category_android-700x504.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":42997,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/05\/category_android.png"},"commentcount":3,"wp_comments":[{"id":93027,"parent":0,"author":4730,"author_name":"JaDz","author_email":"j_a_d_z@gmx.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3fd00cb039970f36a65671928974ab391e6b9da30197702dd6cdfe3a7dcce995?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3fd00cb039970f36a65671928974ab391e6b9da30197702dd6cdfe3a7dcce995?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3fd00cb039970f36a65671928974ab391e6b9da30197702dd6cdfe3a7dcce995?s=96&d=mm&r=g"},"date":"2019-02-05T11:09:48","cld_nonce":"82f011626f","content":{"rendered":"<p>Welches Nexus-Ger\u00e4t ist denn diesmal eines der &#8222;Ersten, die diesen Patch erhalten&#8220;?<\/p>\n<p>;p<\/p>\n"},"status":"1"},{"id":93046,"parent":0,"author":0,"author_name":"Jonas b.","author_email":"jens@computerbase.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8e92e354a0a158b6c32be6dca8c6c40635ff4afe2ee77a9d01591fd7b89d308c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8e92e354a0a158b6c32be6dca8c6c40635ff4afe2ee77a9d01591fd7b89d308c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8e92e354a0a158b6c32be6dca8c6c40635ff4afe2ee77a9d01591fd7b89d308c?s=96&d=mm&r=g"},"date":"2019-02-05T18:04:16","cld_nonce":"82f011626f","content":{"rendered":"<p>Schlimm das die meisten Lecks in den ClosedSource Blobs von Nvidia und Qualcom stecken.<\/p>\n"},"status":"1"},{"id":97984,"parent":0,"author":2483,"author_name":"MrX1980","author_email":"dfinken@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/14d16a4a4d8343b8eae9de25d7c303406db1f32cd99c34fe0147c9c71261fcfa?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/14d16a4a4d8343b8eae9de25d7c303406db1f32cd99c34fe0147c9c71261fcfa?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/14d16a4a4d8343b8eae9de25d7c303406db1f32cd99c34fe0147c9c71261fcfa?s=96&d=mm&r=g"},"date":"2019-04-06T19:56:17","cld_nonce":"82f011626f","content":{"rendered":"<p>Gestern ist das Februar Update erst an meinem Motorola Moto x4 \/ Android 9 (Vodafone) angekommen.<\/p>\n"},"status":"1"}],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Android Sicherheits-Patch Februar 2019 - OTA f\u00fcr Pixel und Nexus - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Android Sicherheits-Patch Februar 2019 - OTA f\u00fcr Pixel und Nexus\" \/>\n<meta property=\"og:description\" content=\"Kurz notiert: Google hat das monatliche Sicherheitsupdate f\u00fcr den Februar 2019 bereitgestellt. Wie immer sind die Pixel und Nexus Ger\u00e4te die Ersten, die diesen Patch erhalten. Alle anderen werden je nach Hersteller nach und nach dieses Update dann erhalten. Der&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-05T09:14:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-05T11:26:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/05\/category_android.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Android Sicherheits-Patch Februar 2019 &#8211; OTA f\u00fcr Pixel und Nexus\",\"datePublished\":\"2019-02-05T09:14:02+00:00\",\"dateModified\":\"2019-02-05T11:26:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/\"},\"wordCount\":158,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/category_android.png\",\"keywords\":[\"Android\",\"Februar 2019\",\"Google Pixel\",\"Nexus\",\"Sicherheitspatch\"],\"articleSection\":[\"Android\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/\",\"name\":\"Android Sicherheits-Patch Februar 2019 - OTA f\u00fcr Pixel und Nexus - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/category_android.png\",\"datePublished\":\"2019-02-05T09:14:02+00:00\",\"dateModified\":\"2019-02-05T11:26:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/category_android.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/category_android.png\",\"width\":500,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2019\\\/02\\\/05\\\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Android Sicherheits-Patch Februar 2019 &#8211; OTA f\u00fcr Pixel und Nexus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Android Sicherheits-Patch Februar 2019 - OTA f\u00fcr Pixel und Nexus - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/","og_locale":"de_DE","og_type":"article","og_title":"Android Sicherheits-Patch Februar 2019 - OTA f\u00fcr Pixel und Nexus","og_description":"Kurz notiert: Google hat das monatliche Sicherheitsupdate f\u00fcr den Februar 2019 bereitgestellt. Wie immer sind die Pixel und Nexus Ger\u00e4te die Ersten, die diesen Patch erhalten. Alle anderen werden je nach Hersteller nach und nach dieses Update dann erhalten. Der&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2019-02-05T09:14:02+00:00","article_modified_time":"2019-02-05T11:26:17+00:00","og_image":[{"width":500,"height":360,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/05\/category_android.png","type":"image\/png"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Android Sicherheits-Patch Februar 2019 &#8211; OTA f\u00fcr Pixel und Nexus","datePublished":"2019-02-05T09:14:02+00:00","dateModified":"2019-02-05T11:26:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/"},"wordCount":158,"commentCount":3,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/05\/category_android.png","keywords":["Android","Februar 2019","Google Pixel","Nexus","Sicherheitspatch"],"articleSection":["Android"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/","url":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/","name":"Android Sicherheits-Patch Februar 2019 - OTA f\u00fcr Pixel und Nexus - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/05\/category_android.png","datePublished":"2019-02-05T09:14:02+00:00","dateModified":"2019-02-05T11:26:17+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/05\/category_android.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/05\/category_android.png","width":500,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2019\/02\/05\/android-sicherheits-patch-februar-2019-ota-fuer-pixel-und-nexus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Android Sicherheits-Patch Februar 2019 &#8211; OTA f\u00fcr Pixel und Nexus"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2015\/05\/category_android.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/114977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=114977"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/114977\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/43004"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=114977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=114977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=114977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}