{"id":111938,"date":"2018-12-02T13:12:05","date_gmt":"2018-12-02T12:12:05","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=111938"},"modified":"2018-12-02T13:12:05","modified_gmt":"2018-12-02T12:12:05","slug":"apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/","title":{"rendered":"Apple und Qualcomm &#8211; Gegen\u00fcberstellung vor Gericht am 15. April"},"content":{"rendered":"<p>Apple und Qualcomm konnten sich nicht einigen und weigerten sich, sich in ihrem Streit um die Patenteinnahmen f\u00fcr das iPhone zu bewegen. Aus diesem Grund sehen sich die beiden Parteien nun vor Gericht. Ein Bundesrichter in San Diego hat den Prozess der Unternehmen f\u00fcr den 15. April 2019 angesetzt. Qualcomm hatte einen Prozess im Februar gewollt, aber der Richter stellte fest, dass eine Verz\u00f6gerung notwendig sei, sowohl aufgrund des Zeitplans des Gerichts als auch der Komplexit\u00e4t des Falles. Es gab Ger\u00fcchte \u00fcber eine Einigung, aber Apple hat wiederholt betont, dass es keine laufenden Gespr\u00e4che gibt und dass sich die beiden Seiten seit &#8222;Monaten&#8220; nicht mehr getroffen haben.<\/p>\n<p>Apple hat Qualcomm beschuldigt, die Lizenzgeb\u00fchren f\u00fcr Patente doppelt zu verlangen, und zwar sowohl bei der Lizenzierung des Patentportfolios durch Apple als auch beim Verkauf von Mobilfunkchips\u00e4tzen. Qualcomm hat unterdessen behauptet, dass seine Patente \u00fcber Chips\u00e4tze hinausgehen und dass sein Lizenzansatz g\u00fcltig war. Man ist sogar so weit gegangen, dass man drohte den Verkauf des iPhone X zu blockieren, was nat\u00fcrlich rein symbolisch w\u00e4re.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo.png\" rel=\"lightbox[111938]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo.png\" alt=\"\" width=\"403\" height=\"290\" class=\"aligncenter size-full wp-image-109720\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo.png 403w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo-285x205.png 285w\" sizes=\"auto, (max-width: 403px) 100vw, 403px\" \/><\/a><\/p>\n<p>Das Timing erh\u00f6ht das Potenzial f\u00fcr einen weiteren langwierigen Patentkampf, \u00e4hnlich dem siebenj\u00e4hrigen Konflikt zwischen Apple und Samsung. Apple k\u00f6nnte jedoch einen Verb\u00fcndeten haben. Die FTC wird am 4. Januar wegen kartellrechtlicher Fragen gegen Qualcomm vor Gericht gehen, und das letztendliche Ergebnis dieses Falles k\u00f6nnte die Chancen des Chip-Designers gegen Apple beeinflussen. Wenn die FTC obsiegt, k\u00f6nnte Qualcomm Schwierigkeiten haben, das Gericht von San Diego davon zu \u00fcberzeugen, dass seine Lizenzpraktiken fair sind.<\/p>\n<p>Via: <a href=\"https:\/\/www.sandiegouniontribune.com\/business\/technology\/sd-fi-qualcomm-apple-trial-date-20181130-story.html\">San Diego Union-Tribune<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apple und Qualcomm konnten sich nicht einigen und weigerten sich, sich in ihrem Streit um die Patenteinnahmen f\u00fcr das iPhone zu bewegen. Aus diesem Grund sehen sich die beiden Parteien nun vor Gericht. Ein Bundesrichter in San Diego hat den&hellip; <\/p>\n","protected":false},"author":2550,"featured_media":109720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286,232],"tags":[98,9880,1125,13700,13004,2758,49251],"class_list":["post-111938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","category-ios","tag-apple","tag-gericht","tag-iphone","tag-lizenzen","tag-patente","tag-qualcomm","tag-streitigkeiten"],"wp_featured_image":{"id":109720,"alt_text":"","description":"","media_type":"image","media_details":{"width":403,"height":290,"file":"2018\/10\/apple-logo.png","sizes":{"thumbnail":{"file":"apple-logo-285x205.png","width":285,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo-285x205.png"},"wp_review_large":{"file":"apple-logo-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo-320x200.png"},"wp_review_small":{"file":"apple-logo-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo-65x65.png"},"blog-medium":{"file":"apple-logo-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo-306x205.png"},"recent-thumb":{"file":"apple-logo-350x290.png","width":350,"height":290,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo-350x290.png"},"wp_rp_thumbnail":{"file":"apple-logo-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":109718,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo.png"},"commentcount":1,"wp_comments":[{"id":87417,"parent":0,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=96&d=mm&r=g"},"date":"2018-12-02T16:52:18","cld_nonce":"82f011626f","content":{"rendered":"<p>Bin mal gespannt wie der Rechtsstreit entschieden wird. Insgesamt dauern solche Urheberrechtsprozesse in den USA Jahre. Ich kenne einen Fall, in dem Nissan mit einem guten Freund in einem Patentstreit in den USA verwickelt war. Mein Freund entwickelte eine Technik, mit der man in au\u00dfergew\u00f6hnlicher K\u00fcrze der Zeit, NiCd-Batterien f\u00fcr E-Autos wieder aufbereiten kann. Nissan hatte den l\u00e4ngeren finanziellen Atem und nutzt letztendlich ein Patent, das Nissan einfach geklaut und anschlie\u00dfend mit geringf\u00fcgigen Modifikationen plagiiert hat.<\/p>\n"},"status":"1"}],"wp_author":{"id":2550,"name":"MAX","description":"Begeisterter Technik-Enthusiast, der aktuell zwei Welten vereint. Windows auf PC sowie Xbox und iOS auf dem iPhone, als auch auf dem iPad. Gespaltene Pers\u00f6nlichkeit w\u00fcrde ich sagen. ;)","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Apple und Qualcomm - Gegen\u00fcberstellung vor Gericht am 15. April - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apple und Qualcomm - Gegen\u00fcberstellung vor Gericht am 15. April\" \/>\n<meta property=\"og:description\" content=\"Apple und Qualcomm konnten sich nicht einigen und weigerten sich, sich in ihrem Streit um die Patenteinnahmen f\u00fcr das iPhone zu bewegen. Aus diesem Grund sehen sich die beiden Parteien nun vor Gericht. Ein Bundesrichter in San Diego hat den&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-02T12:12:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"403\" \/>\n\t<meta property=\"og:image:height\" content=\"290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"MAX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@themximum\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/\"},\"author\":{\"name\":\"MAX\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/bd4b9506e83c661f1de1af925c726d7c\"},\"headline\":\"Apple und Qualcomm &#8211; Gegen\u00fcberstellung vor Gericht am 15. April\",\"datePublished\":\"2018-12-02T12:12:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/\"},\"wordCount\":275,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/apple-logo.png\",\"keywords\":[\"Apple\",\"gericht\",\"Iphone\",\"Lizenzen\",\"Patente\",\"Qualcomm\",\"Streitigkeiten\"],\"articleSection\":[\"Hardware\",\"iOS\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/\",\"name\":\"Apple und Qualcomm - Gegen\u00fcberstellung vor Gericht am 15. April - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/apple-logo.png\",\"datePublished\":\"2018-12-02T12:12:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/apple-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/apple-logo.png\",\"width\":403,\"height\":290},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/12\\\/02\\\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apple und Qualcomm &#8211; Gegen\u00fcberstellung vor Gericht am 15. April\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/bd4b9506e83c661f1de1af925c726d7c\",\"name\":\"MAX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g\",\"caption\":\"MAX\"},\"description\":\"Begeisterter Technik-Enthusiast, der aktuell zwei Welten vereint. Windows auf PC sowie Xbox und iOS auf dem iPhone, als auch auf dem iPad. Gespaltene Pers\u00f6nlichkeit w\u00fcrde ich sagen. ;)\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/themximum\\\/\",\"https:\\\/\\\/x.com\\\/themximum\"],\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/max\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Apple und Qualcomm - Gegen\u00fcberstellung vor Gericht am 15. April - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/","og_locale":"de_DE","og_type":"article","og_title":"Apple und Qualcomm - Gegen\u00fcberstellung vor Gericht am 15. April","og_description":"Apple und Qualcomm konnten sich nicht einigen und weigerten sich, sich in ihrem Streit um die Patenteinnahmen f\u00fcr das iPhone zu bewegen. Aus diesem Grund sehen sich die beiden Parteien nun vor Gericht. Ein Bundesrichter in San Diego hat den&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-12-02T12:12:05+00:00","og_image":[{"width":403,"height":290,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo.png","type":"image\/png"}],"author":"MAX","twitter_card":"summary_large_image","twitter_creator":"@themximum","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/"},"author":{"name":"MAX","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/bd4b9506e83c661f1de1af925c726d7c"},"headline":"Apple und Qualcomm &#8211; Gegen\u00fcberstellung vor Gericht am 15. April","datePublished":"2018-12-02T12:12:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/"},"wordCount":275,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo.png","keywords":["Apple","gericht","Iphone","Lizenzen","Patente","Qualcomm","Streitigkeiten"],"articleSection":["Hardware","iOS"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/","name":"Apple und Qualcomm - Gegen\u00fcberstellung vor Gericht am 15. April - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo.png","datePublished":"2018-12-02T12:12:05+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo.png","width":403,"height":290},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/12\/02\/apple-und-qualcomm-gegenueberstellung-vor-gericht-am-15-april\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Apple und Qualcomm &#8211; Gegen\u00fcberstellung vor Gericht am 15. April"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/bd4b9506e83c661f1de1af925c726d7c","name":"MAX","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a924a9e0119dd457d49c2eb1fa27ade332376ba6138336743cdd8c221e4a3a3?s=96&d=mm&r=g","caption":"MAX"},"description":"Begeisterter Technik-Enthusiast, der aktuell zwei Welten vereint. Windows auf PC sowie Xbox und iOS auf dem iPhone, als auch auf dem iPad. Gespaltene Pers\u00f6nlichkeit w\u00fcrde ich sagen. ;)","sameAs":["https:\/\/www.instagram.com\/themximum\/","https:\/\/x.com\/themximum"],"url":"https:\/\/www.deskmodder.de\/blog\/author\/max\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/10\/apple-logo.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/111938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2550"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=111938"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/111938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/109720"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=111938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=111938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=111938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}