{"id":110237,"date":"2018-10-30T18:30:05","date_gmt":"2018-10-30T17:30:05","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=110237"},"modified":"2018-10-30T18:33:41","modified_gmt":"2018-10-30T17:33:41","slug":"apple-veroeffentlicht-ios-12-1","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/","title":{"rendered":"Apple ver\u00f6ffentlicht iOS 12.1"},"content":{"rendered":"<p>Apple hat heute das Update auf iOS 12.1 f\u00fcr alle kompatiblen iPhones, iPads und iPods freigegeben. Damit werden unter anderem Gruppenanrufe mit FaceTime sowie der eSIM- bzw. Dual-SIM-Support f\u00fcr die neuen iPhone-Modelle nachgereicht. Zudem enth\u00e4lt die neue iOS-Version zahlreiche neue Emojis (<a href=\"https:\/\/www.deskmodder.de\/blog\/2018\/10\/03\/ios-12-1-70-neue-emojis-bringt-das-update\/\" target=\"_blank\" rel=\"noopener\">wir berichteten<\/a>).<\/p>\n<p>Das Update erforderte bei mir auf dem iPhone 359 MB freien Speicher und auf dem iPad 320,8 MB. Sollte der Speicherplatz bei euch zu knapp sein, dann kann man das Update auch \u00fcber iTunes einspielen. Zudem muss das Ger\u00e4t f\u00fcr die Installation wie immer mindest 50% geladen oder ans Stromnetz angeschlossen sein.<\/p>\n<p>Informationen zu den sicherheitsrelevanten Aspekten findet ihr auf dieser <a href=\"https:\/\/support.apple.com\/kb\/HT201222\" target=\"_blank\" rel=\"noopener\">Apple-Seite<\/a>. Das heutige Apple-Event haben wir zudem <a href=\"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-event-zusammenfassung-mit-macbook-air-mac-mini-und-neuem-ipad-pro\/\" target=\"_blank\" rel=\"noopener\">HIER<\/a> f\u00fcr euch zusammengefasst.<\/p>\n<h3>Changelog iOS 12.1<\/h3>\n<p>Mit iOS 12.1 gibt es Gruppen-FaceTime, mehr als 70 neue Emojis sowie Unterst\u00fctzung f\u00fcr Dual-SIM mit eSIM f\u00fcr iPhone XS, iPhone XS Max und iPhone XR. Dieses Update enth\u00e4lt auch Fehlerbehebungen und Verbesserungen.<\/p>\n<p><b>Gruppen-FaceTime<\/b><\/p>\n<ul>\n<li>Unterst\u00fctzung f\u00fcr Video- und Audioanrufe mit bis zu 32 Teilnehmern gleichzeitig.<\/li>\n<li>Konversationen sind mit Ende-zu-Ende-Verschl\u00fcsselung gesch\u00fctzt und bleiben privat.<\/li>\n<li>Gruppen-FaceTime kann direkt aus einem Gruppenchat in \u201eNachrichten\u201c gestartet werden und weitere Teilnehmer k\u00f6nnen einem aktiven Anruf jederzeit beitreten.<\/li>\n<\/ul>\n<p><b>Emojis<\/b><\/p>\n<ul>\n<li>\u00dcber 70 neue Emojis, einschlie\u00dflich Figuren mit rotem, grauem und lockigem Haar, Emojis f\u00fcr Personen ohne Haar sowie ausdrucksvollere Smileys und weitere Emojis f\u00fcr Tiere, Sport und Lebensmittel.<\/li>\n<\/ul>\n<p><b>Unterst\u00fctzung f\u00fcr Dual-SIM<\/b><\/p>\n<ul>\n<li>Einf\u00fchrung der Dual-SIM-Funktion mit eSIM, die auf iPhone XS, iPhone XS Max und iPhone XR die Verwendung von zwei Nummern auf einem Ger\u00e4t erm\u00f6glicht.<\/li>\n<\/ul>\n<p><b>Andere Verbesserungen und Fehlerbehebungen<\/b><\/p>\n<ul>\n<li>Einf\u00fchrung der Tiefenkontrolle in der Kameravorschau mit iPhone XS, iPhone XS Max und iPhone XR.<\/li>\n<li>Verbesserte Mobilfunkverbindung f\u00fcr iPhone XS, iPhone XS Max und iPhone XR.<\/li>\n<li>Neue M\u00f6glichkeit zum \u00c4ndern oder Zur\u00fccksetzen der Bildschirmzeit f\u00fcr Kinder mit Face ID oder Touch ID.<\/li>\n<li>Ein Problem mit der Auswahl des sch\u00e4rfsten Bezugsrahmens bei Aufnahmen mit der vorderen Kamera von iPhone XS, iPhone XS Max und iPhone XR wurde behoben.<\/li>\n<li>Ein Problem wurde behoben, bei dem mehrere Nachrichten in eine Konversation zusammengef\u00fchrt wurden, wenn beide Nutzer mit derselben Apple-ID auf mehreren iPhones angemeldet waren.<\/li>\n<li>Ein Problem mit der fehlenden Anzeige einiger Voicemails in der Telefon-App wurde behoben.<\/li>\n<li>Ein Problem in der Telefon-App mit Anzeige von Telefonnummern ohne den dazugeh\u00f6rigen Kontaktnamen wurde behoben.<\/li>\n<li>Ein Problem mit dem Auff\u00fchren von bestimmten Websites im Aktivit\u00e4tsbericht der Bildschirmzeit wurde behoben.<\/li>\n<li>Ein Problem mit dem Hinzuf\u00fcgen oder Entfernen von Familienmitgliedern zur Familienfreigabe wurde behoben.<\/li>\n<li>Ein Problem, bei dem Beschreibungen der Luftqualit\u00e4t falsch gekennzeichnet sein k\u00f6nnten, wurde behoben.<\/li>\n<li>F\u00fcgt eine Leistungsverwaltungsfunktion f\u00fcr iPhone X, iPhone 8 und iPhone 8 Plus hinzu, um zu verhindern, dass sich das Ger\u00e4t unerwartet ausschaltet, einschlie\u00dflich der Option, diese Funktion zu deaktivieren, sollte es dennoch zu einem unerwarteten Ausschalten kommen.<\/li>\n<li>\u00dcber die Funktion \u201eBatteriezustand\u201c k\u00f6nnen Nutzer jetzt informiert werden, wenn die Funktion nicht best\u00e4tigen kann, dass sich im iPhone XS, iPhone XS Max und iPhone XR eine echte Apple-Batterie befindet.<\/li>\n<li>Verbesserte Zuverl\u00e4ssigkeit von VoiceOver bei der Kamera, Siri und Safari.<\/li>\n<li>Ein Problem wurde behoben, das dazu f\u00fchren konnte, dass die Registrierung von MDM-Ger\u00e4ten in Unternehmen f\u00fcr einige Nutzer einen Fehler wegen ung\u00fcltigem Profil meldete.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Apple hat heute das Update auf iOS 12.1 f\u00fcr alle kompatiblen iPhones, iPads und iPods freigegeben. Damit werden unter anderem Gruppenanrufe mit FaceTime sowie der eSIM- bzw. Dual-SIM-Support f\u00fcr die neuen iPhone-Modelle nachgereicht. Zudem enth\u00e4lt die neue iOS-Version zahlreiche neue&hellip; <\/p>\n","protected":false},"author":1525,"featured_media":103040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,232],"tags":[98,5247,1174,88,13116,11358,46045,2445,1125,4124,4460],"class_list":["post-110237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-ios","tag-apple","tag-changelog","tag-deutsch","tag-download","tag-emojis","tag-facetime","tag-ios-12-1","tag-ipad","tag-iphone","tag-ipod","tag-neuerungen"],"wp_featured_image":{"id":103040,"alt_text":"","description":"","media_type":"image","media_details":{"width":2792,"height":1494,"file":"2018\/06\/ios-12.png","sizes":{"thumbnail":{"file":"ios-12-306x164.png","width":306,"height":164,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12-306x164.png"},"medium":{"file":"ios-12-500x268.png","width":500,"height":268,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12-500x268.png"},"large":{"file":"ios-12-810x433.png","width":810,"height":433,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12-810x433.png"},"wp_review_large":{"file":"ios-12-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12-320x200.png"},"wp_review_small":{"file":"ios-12-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12-65x65.png"},"blog-large":{"file":"ios-12-642x300.png","width":642,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12-642x300.png"},"blog-medium":{"file":"ios-12-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12-306x205.png"},"recent-thumb":{"file":"ios-12-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12-350x316.png"},"service-featured":{"file":"ios-12-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12-600x330.png"},"wp_rp_thumbnail":{"file":"ios-12-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":103024,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12.png"},"commentcount":0,"wp_comments":[],"wp_author":{"id":1525,"name":"W8U","description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Apple ver\u00f6ffentlicht iOS 12.1 - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apple ver\u00f6ffentlicht iOS 12.1\" \/>\n<meta property=\"og:description\" content=\"Apple hat heute das Update auf iOS 12.1 f\u00fcr alle kompatiblen iPhones, iPads und iPods freigegeben. Damit werden unter anderem Gruppenanrufe mit FaceTime sowie der eSIM- bzw. Dual-SIM-Support f\u00fcr die neuen iPhone-Modelle nachgereicht. Zudem enth\u00e4lt die neue iOS-Version zahlreiche neue&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-30T17:30:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-30T17:33:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12-810x433.png\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"W8U\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/\"},\"author\":{\"name\":\"W8U\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\"},\"headline\":\"Apple ver\u00f6ffentlicht iOS 12.1\",\"datePublished\":\"2018-10-30T17:30:05+00:00\",\"dateModified\":\"2018-10-30T17:33:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/\"},\"wordCount\":550,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/ios-12.png\",\"keywords\":[\"Apple\",\"changelog\",\"deutsch\",\"Download\",\"Emojis\",\"Facetime\",\"iOS 12.1\",\"iPad\",\"Iphone\",\"ipod\",\"neuerungen\"],\"articleSection\":{\"1\":\"iOS\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/\",\"name\":\"Apple ver\u00f6ffentlicht iOS 12.1 - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/ios-12.png\",\"datePublished\":\"2018-10-30T17:30:05+00:00\",\"dateModified\":\"2018-10-30T17:33:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/ios-12.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/ios-12.png\",\"width\":2792,\"height\":1494},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/30\\\/apple-veroeffentlicht-ios-12-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apple ver\u00f6ffentlicht iOS 12.1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\",\"name\":\"W8U\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"caption\":\"W8U\"},\"description\":\"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/w8u\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Apple ver\u00f6ffentlicht iOS 12.1 - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/","og_locale":"de_DE","og_type":"article","og_title":"Apple ver\u00f6ffentlicht iOS 12.1","og_description":"Apple hat heute das Update auf iOS 12.1 f\u00fcr alle kompatiblen iPhones, iPads und iPods freigegeben. Damit werden unter anderem Gruppenanrufe mit FaceTime sowie der eSIM- bzw. Dual-SIM-Support f\u00fcr die neuen iPhone-Modelle nachgereicht. Zudem enth\u00e4lt die neue iOS-Version zahlreiche neue&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-10-30T17:30:05+00:00","article_modified_time":"2018-10-30T17:33:41+00:00","og_image":[{"width":810,"height":433,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12-810x433.png","type":"image\/png"}],"author":"W8U","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/"},"author":{"name":"W8U","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469"},"headline":"Apple ver\u00f6ffentlicht iOS 12.1","datePublished":"2018-10-30T17:30:05+00:00","dateModified":"2018-10-30T17:33:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/"},"wordCount":550,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12.png","keywords":["Apple","changelog","deutsch","Download","Emojis","Facetime","iOS 12.1","iPad","Iphone","ipod","neuerungen"],"articleSection":{"1":"iOS"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/","name":"Apple ver\u00f6ffentlicht iOS 12.1 - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12.png","datePublished":"2018-10-30T17:30:05+00:00","dateModified":"2018-10-30T17:33:41+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12.png","width":2792,"height":1494},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/30\/apple-veroeffentlicht-ios-12-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Apple ver\u00f6ffentlicht iOS 12.1"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469","name":"W8U","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","caption":"W8U"},"description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","url":"https:\/\/www.deskmodder.de\/blog\/author\/w8u\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/ios-12.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/110237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/1525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=110237"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/110237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/103040"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=110237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=110237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=110237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}