{"id":109847,"date":"2018-10-22T15:44:38","date_gmt":"2018-10-22T13:44:38","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=109847"},"modified":"2018-10-22T16:05:40","modified_gmt":"2018-10-22T14:05:40","slug":"dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/","title":{"rendered":"Dauerl\u00e4ufer: FRITZ!Box 7390 erh\u00e4lt Wartungsupdate auf FRITZ!OS 6.85"},"content":{"rendered":"<p>Ich habe beim letzten Update schon gesagt, dass Totgesagte l\u00e4nger leben. Und nun ist das finale Update auf FRITZ!OS 6.85 auch f\u00fcr die FRITZ!Box 7390 verf\u00fcgbar. Das Update bringt deutlich mehr Stabilit\u00e4t und auch einige Bugfixes mit sich. Vor allem St\u00f6rungen und Probleme am VDSL-Anschluss sind in naher Vergangenheit geh\u00e4uft aufgetreten.<\/p>\n<div class=\"wpcmsdev-tabs\">\n<div class=\"tab\">\n<h3 class=\"tab-title\" data-tab-id=\"info\">Info<\/h3>\n<div id=\"tab-info\" class=\"tab-content\">\n<p>Wie AVM mitteilt, h\u00e4lt man den Support per Telefon und E-Mail noch einige Wochen aufrecht. Danach wird die Box in den &#8222;verdienten Ruhestand&#8220; gehen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>Das Update wird wohl das letzte verf\u00fcgbare Update f\u00fcr dieses Modell sein. Neben der 7390 haben auch die 7412, 7272 und 7360 ein Wartungsupdate erhalten. Es wurde schon vor einiger Zeit daf\u00fcr eine Laborversion bereitgestellt, sodass interessierte Nutzer die neuen Fixes vorher ausprobieren k\u00f6nnen.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/avm-fritzbox-7390-freigestellt-de.png\" rel=\"lightbox[109847]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-81949\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/avm-fritzbox-7390-freigestellt-de-491x360.png\" alt=\"\" width=\"491\" height=\"360\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/avm-fritzbox-7390-freigestellt-de-491x360.png 491w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/avm-fritzbox-7390-freigestellt-de-280x205.png 280w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/03\/avm-fritzbox-7390-freigestellt-de-795x583.png 795w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/a><\/p>\n<h4>Verbesserungen in FRITZ!OS 6.85:<\/h4>\n<p><strong>DSL: <\/strong><\/p>\n<ul>\n<li>Verbesserung: Stabilit\u00e4t an VDSL\/Vectoring-Anschl\u00fcssen weiter verbessert (spez. DSL-Vermittlungsstellen mit Broadcom Chipsets und aktiviertem G.Vector)<\/li>\n<\/ul>\n<p><strong>Internet: <\/strong><\/p>\n<ul>\n<li>Behoben &#8211; Bei Portfreigaben \u00e4ndert sich sporadisch der externe Port<\/li>\n<li>Behoben: kein Hinzuf\u00fcgen von IPv4-Portfreigaben f\u00fcr Ger\u00e4te mit IPv4 und IPv6 an Internetanschl\u00fcssen ohne IPv6<\/li>\n<li>Behoben: kein automatisches &#8222;Wake on LAN&#8220; bei Zugriff aus dem Internet<\/li>\n<li>Behoben: m\u00f6gliche fehlerhafte Sperre der Internetnutzung durch die Kindersicherung<\/li>\n<\/ul>\n<p><strong>DECT: <\/strong><\/p>\n<ul>\n<li>Verbesserung &#8211; Interoperabilit\u00e4t mit Handger\u00e4ten Speedphone 11 und 500 verbessert<\/li>\n<li>Verbesserung:\u00a0Telefonbuch-Transfer zwischen Gigaset\/Siemens-Produkten (ohne CAT-iq) und FRITZ!Box verbessert<\/li>\n<\/ul>\n<p><strong>WLAN: <\/strong><\/p>\n<ul>\n<li>Behoben: Schw\u00e4che in der WPA2-Schl\u00fcsselaushandlung bei Nutzung eines WLAN-Uplinks zu einem anderen Router<\/li>\n<\/ul>\n<p><strong>Sicherheit: <\/strong><\/p>\n<ul>\n<li>Verbesserung: zus\u00e4tzliche Best\u00e4tigung einer Einstellungs\u00e4nderung erweitert um DNS-Einstellungen und Setzen auf Werkseinstellung<\/li>\n<li>Verbesserung: Hinweise unter https:\/\/avm.de\/sicherheit\/ im Bereich &#8222;Updates erh\u00f6hen Sicherheit&#8220;<\/li>\n<\/ul>\n<p><strong>System: <\/strong><\/p>\n<ul>\n<li>Verbesserung: Stabilit\u00e4t<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ich habe beim letzten Update schon gesagt, dass Totgesagte l\u00e4nger leben. Und nun ist das finale Update auf FRITZ!OS 6.85 auch f\u00fcr die FRITZ!Box 7390 verf\u00fcgbar. Das Update bringt deutlich mehr Stabilit\u00e4t und auch einige Bugfixes mit sich. Vor allem&hellip; <\/p>\n","protected":false},"author":2650,"featured_media":102328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286,152],"tags":[7054,16208,16207,31607,3449,16023,17724,17889,104],"class_list":["post-109847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","category-software","tag-7054","tag-16208","tag-16207","tag-31607","tag-fritzbox","tag-fritzbox-7390","tag-fritzos-6-85","tag-mesh","tag-update"],"wp_featured_image":{"id":102328,"alt_text":"","description":"","media_type":"image","media_details":{"width":2138,"height":1536,"file":"2018\/05\/avm-fritzbox-7490-heimnetz.jpg","sizes":{"thumbnail":{"file":"avm-fritzbox-7490-heimnetz-285x205.jpg","width":285,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz-285x205.jpg"},"medium":{"file":"avm-fritzbox-7490-heimnetz-500x360.jpg","width":500,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz-500x360.jpg"},"large":{"file":"avm-fritzbox-7490-heimnetz-810x583.jpg","width":810,"height":583,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz-810x583.jpg"},"wp_review_large":{"file":"avm-fritzbox-7490-heimnetz-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz-320x200.jpg"},"wp_review_small":{"file":"avm-fritzbox-7490-heimnetz-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz-65x65.jpg"},"blog-large":{"file":"avm-fritzbox-7490-heimnetz-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz-642x300.jpg"},"blog-medium":{"file":"avm-fritzbox-7490-heimnetz-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz-306x205.jpg"},"recent-thumb":{"file":"avm-fritzbox-7490-heimnetz-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz-350x316.jpg"},"service-featured":{"file":"avm-fritzbox-7490-heimnetz-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz-600x330.jpg"},"wp_rp_thumbnail":{"file":"avm-fritzbox-7490-heimnetz-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"AVM GmbH","camera":"","caption":"Die neue FRITZ!Box 7490 kombiniert Gigabit-Geschwindigkeit, modernste Hardware und Vectoring-Technologie f\u00fcr noch schnelleres VDSL. Sie setzt auf WLAN AC mit 1.300 MBit\/s (5 GHz) und auf WLAN N mit 450 MBit\/s (2,4 GHz) und ist abw\u00e4rtskompatibel zu 802.11g\/b. Zur weiteren Ausstattung geh\u00f6ren 4 Gigabit-LAN und 2 USB 3.0-Anschl\u00fcsse. Eine integrierte Telefonanlage einschlie\u00dflich DECT-Basis rundet die Vollausstattung ab.\rThe new FRITZ!Box 7490 combines gigabit speed, the latest hardware and vectoring technology for even faster VDSL. It builds on Wireless AC standard with 1300 Mbit\/s (5 GHz) and Wireless N with 450 Mbit\/s (2.4 GHz), yet is downward compatible with 802.11a\/b\/g\/n. It is also equipped with 4 gigabit LAN and 2 USB 3.0 ports. An integrated telephone system including a DECT base station rounds out the comprehensive package.","created_timestamp":"1378684800","copyright":"\u00a9 AVM GmbH. Die Verwendung dieses Bildes ist f\u00fcr redaktionelle Zwecke honorarfrei.\r\u00a9 AVM GmbH. Use of this image for editoria","focal_length":"0","iso":"0","shutter_speed":"0","title":"AVM FRITZ!Box 7490","orientation":"1","keywords":["AVM","FRITZ!","FRITZ!Box","fritzbox","fritz-box","7490","FRITZ!Box-Modelle","DSL","VDSL","ADSL","Vectoring","Heimnetz","home network","Heimnetzwerk","Heimvernetzung","Netzwerk","Breitbandanschluss","broadband connection","Breitbandtechnologie","Gigabit Ethernet","Netzwerkspeicher","network storage","NAS","USB-Anschluss","Telefonanlage","telephone system","DECT","DECT-Basis","DECT-Basisstation","DECT base station","WLAN","kabellos","AC","WLAN AC","WIFI"]}},"post":102326,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz.jpg"},"commentcount":2,"wp_comments":[{"id":85463,"parent":0,"author":0,"author_name":"Herbert","author_email":"herbert.eberth@online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6fe7393f474758599c759ca8cdff4ed6714093862c9801004f49cd790bd1bc83?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6fe7393f474758599c759ca8cdff4ed6714093862c9801004f49cd790bd1bc83?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6fe7393f474758599c759ca8cdff4ed6714093862c9801004f49cd790bd1bc83?s=96&d=mm&r=g"},"date":"2018-11-01T00:10:56","cld_nonce":"82f011626f","content":{"rendered":"<p>Bedauerlich, dass es heutzutage zur Regel geworden ist, dass Elektronikhersteller guten Ger\u00e4ten wie z.B. der Fritz!Box 7390 nach nicht einmal 10 Jahren den Supporthahn abdrehen.<\/p>\n"},"status":"1"},{"id":104594,"parent":85463,"author":0,"author_name":"Peter Christian","author_email":"petercnowak@icloud.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bdd68544648abe37cdec72d9fec2a6f7cddbae789a5315e181e13d065d85a628?s=96&d=mm&r=g"},"date":"2019-06-26T21:37:05","cld_nonce":"82f011626f","content":{"rendered":"<p>Danke f\u00fcr den Hinweis, was die Unterst\u00fctzung der Hardware-Ger\u00e4te betrifft. In Anlehnung deines Kommentars m\u00f6cht ich sagen, den kann man durchaus auch auf Apple iPhone &#8222;extrapolieren&#8220;.<br \/>\nHabe noch ein phantastisch stabiles (auf vielen Drehs in Afrika und Neuseeland, USA, hervorragende Stabilit\u00e4t bewiesen) und handliches iPhone4. Klebt auf iOS7 oder so \u00e4hnlich. Kommt mit manchen modernen IT Seiten nicht mehr zurecht und auch scheinbar nicht mehr mit JavaScript. Schade, denn das Ger\u00e4t hat alle extremen Wetterbedingungen mitgemacht, tropischer Regenguss bis strahlender Sonnenschein in der W\u00fcste Namib mit entsprechenden Temperaturen. Nur ins Wasser ist es noch nicht gefallen. Aber ansonsten schon vor die Nase eines Salzwasser-Krokodils auf Borneo, was mich irgendwie auf dem falschen Fu\u00df erwischte.? Gl\u00fcck gehabt! Soll vorkommen. (Vom iPhone wollte es aber nichts wissen)<\/p>\n"},"status":"1"}],"wp_author":{"id":2650,"name":"TimboTillo","description":"Word, PowerPoint waren meine ersten Erfahrungen mit der Computer-Welt. Immer mehr lernte ich neue M\u00f6glichkeiten und Funktionen kennen. Richtig wohl f\u00fchle ich mich im Netzwerkbereich, mit Windows 11 und ganz viel WLAN :-)!","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dauerl\u00e4ufer: FRITZ!Box 7390 erh\u00e4lt Wartungsupdate auf FRITZ!OS 6.85 - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dauerl\u00e4ufer: FRITZ!Box 7390 erh\u00e4lt Wartungsupdate auf FRITZ!OS 6.85\" \/>\n<meta property=\"og:description\" content=\"Ich habe beim letzten Update schon gesagt, dass Totgesagte l\u00e4nger leben. Und nun ist das finale Update auf FRITZ!OS 6.85 auch f\u00fcr die FRITZ!Box 7390 verf\u00fcgbar. Das Update bringt deutlich mehr Stabilit\u00e4t und auch einige Bugfixes mit sich. Vor allem&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/timwesterhoffnoh\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-22T13:44:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-22T14:05:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2138\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"TimboTillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/TimWesterhoff98\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/\"},\"author\":{\"name\":\"TimboTillo\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3ef642d5524caf1553c054f014206d7\"},\"headline\":\"Dauerl\u00e4ufer: FRITZ!Box 7390 erh\u00e4lt Wartungsupdate auf FRITZ!OS 6.85\",\"datePublished\":\"2018-10-22T13:44:38+00:00\",\"dateModified\":\"2018-10-22T14:05:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/\"},\"wordCount\":289,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/avm-fritzbox-7490-heimnetz.jpg\",\"keywords\":[\"7360\",\"7390\",\"7490\",\"7590\",\"Fritz!Box\",\"Fritz!Box 7390\",\"Fritz!OS 6.85\",\"Mesh\",\"Update\"],\"articleSection\":[\"Hardware\",\"Software &amp; Updates\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/\",\"name\":\"Dauerl\u00e4ufer: FRITZ!Box 7390 erh\u00e4lt Wartungsupdate auf FRITZ!OS 6.85 - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/avm-fritzbox-7490-heimnetz.jpg\",\"datePublished\":\"2018-10-22T13:44:38+00:00\",\"dateModified\":\"2018-10-22T14:05:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/avm-fritzbox-7490-heimnetz.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/avm-fritzbox-7490-heimnetz.jpg\",\"width\":2138,\"height\":1536,\"caption\":\"Die neue FRITZ!Box 7490 kombiniert Gigabit-Geschwindigkeit, modernste Hardware und Vectoring-Technologie f\u00fcr noch schnelleres VDSL. Sie setzt auf WLAN AC mit 1.300 MBit\\\/s (5 GHz) und auf WLAN N mit 450 MBit\\\/s (2,4 GHz) und ist abw\u00e4rtskompatibel zu 802.11g\\\/b. Zur weiteren Ausstattung geh\u00f6ren 4 Gigabit-LAN und 2 USB 3.0-Anschl\u00fcsse. Eine integrierte Telefonanlage einschlie\u00dflich DECT-Basis rundet die Vollausstattung ab. The new FRITZ!Box 7490 combines gigabit speed, the latest hardware and vectoring technology for even faster VDSL. It builds on Wireless AC standard with 1300 Mbit\\\/s (5 GHz) and Wireless N with 450 Mbit\\\/s (2.4 GHz), yet is downward compatible with 802.11a\\\/b\\\/g\\\/n. It is also equipped with 4 gigabit LAN and 2 USB 3.0 ports. An integrated telephone system including a DECT base station rounds out the comprehensive package.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/10\\\/22\\\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dauerl\u00e4ufer: FRITZ!Box 7390 erh\u00e4lt Wartungsupdate auf FRITZ!OS 6.85\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3ef642d5524caf1553c054f014206d7\",\"name\":\"TimboTillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g\",\"caption\":\"TimboTillo\"},\"description\":\"Word, PowerPoint waren meine ersten Erfahrungen mit der Computer-Welt. Immer mehr lernte ich neue M\u00f6glichkeiten und Funktionen kennen. Richtig wohl f\u00fchle ich mich im Netzwerkbereich, mit Windows 11 und ganz viel WLAN :-)!\",\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/timwesterhoffnoh\",\"https:\\\/\\\/www.instagram.com\\\/tim_westerhoff\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/TimWesterhoff98\"],\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/timbotillo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dauerl\u00e4ufer: FRITZ!Box 7390 erh\u00e4lt Wartungsupdate auf FRITZ!OS 6.85 - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/","og_locale":"de_DE","og_type":"article","og_title":"Dauerl\u00e4ufer: FRITZ!Box 7390 erh\u00e4lt Wartungsupdate auf FRITZ!OS 6.85","og_description":"Ich habe beim letzten Update schon gesagt, dass Totgesagte l\u00e4nger leben. Und nun ist das finale Update auf FRITZ!OS 6.85 auch f\u00fcr die FRITZ!Box 7390 verf\u00fcgbar. Das Update bringt deutlich mehr Stabilit\u00e4t und auch einige Bugfixes mit sich. Vor allem&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_author":"http:\/\/www.facebook.com\/timwesterhoffnoh","article_published_time":"2018-10-22T13:44:38+00:00","article_modified_time":"2018-10-22T14:05:40+00:00","og_image":[{"width":2138,"height":1536,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz.jpg","type":"image\/jpeg"}],"author":"TimboTillo","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/TimWesterhoff98","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/"},"author":{"name":"TimboTillo","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3ef642d5524caf1553c054f014206d7"},"headline":"Dauerl\u00e4ufer: FRITZ!Box 7390 erh\u00e4lt Wartungsupdate auf FRITZ!OS 6.85","datePublished":"2018-10-22T13:44:38+00:00","dateModified":"2018-10-22T14:05:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/"},"wordCount":289,"commentCount":2,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz.jpg","keywords":["7360","7390","7490","7590","Fritz!Box","Fritz!Box 7390","Fritz!OS 6.85","Mesh","Update"],"articleSection":["Hardware","Software &amp; Updates"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/","name":"Dauerl\u00e4ufer: FRITZ!Box 7390 erh\u00e4lt Wartungsupdate auf FRITZ!OS 6.85 - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz.jpg","datePublished":"2018-10-22T13:44:38+00:00","dateModified":"2018-10-22T14:05:40+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz.jpg","width":2138,"height":1536,"caption":"Die neue FRITZ!Box 7490 kombiniert Gigabit-Geschwindigkeit, modernste Hardware und Vectoring-Technologie f\u00fcr noch schnelleres VDSL. Sie setzt auf WLAN AC mit 1.300 MBit\/s (5 GHz) und auf WLAN N mit 450 MBit\/s (2,4 GHz) und ist abw\u00e4rtskompatibel zu 802.11g\/b. Zur weiteren Ausstattung geh\u00f6ren 4 Gigabit-LAN und 2 USB 3.0-Anschl\u00fcsse. Eine integrierte Telefonanlage einschlie\u00dflich DECT-Basis rundet die Vollausstattung ab. The new FRITZ!Box 7490 combines gigabit speed, the latest hardware and vectoring technology for even faster VDSL. It builds on Wireless AC standard with 1300 Mbit\/s (5 GHz) and Wireless N with 450 Mbit\/s (2.4 GHz), yet is downward compatible with 802.11a\/b\/g\/n. It is also equipped with 4 gigabit LAN and 2 USB 3.0 ports. An integrated telephone system including a DECT base station rounds out the comprehensive package."},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/10\/22\/dauerlaeufer-fritzbox-7390-erhaelt-wartungsupdate-auf-fritzos-6-85\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Dauerl\u00e4ufer: FRITZ!Box 7390 erh\u00e4lt Wartungsupdate auf FRITZ!OS 6.85"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3ef642d5524caf1553c054f014206d7","name":"TimboTillo","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8f3cfe12065d1f5b2c9f09eb3c40047c39e05b0a63d4f2578251e4dc846d56a3?s=96&d=mm&r=g","caption":"TimboTillo"},"description":"Word, PowerPoint waren meine ersten Erfahrungen mit der Computer-Welt. Immer mehr lernte ich neue M\u00f6glichkeiten und Funktionen kennen. Richtig wohl f\u00fchle ich mich im Netzwerkbereich, mit Windows 11 und ganz viel WLAN :-)!","sameAs":["http:\/\/www.facebook.com\/timwesterhoffnoh","https:\/\/www.instagram.com\/tim_westerhoff\/","https:\/\/x.com\/https:\/\/twitter.com\/TimWesterhoff98"],"url":"https:\/\/www.deskmodder.de\/blog\/author\/timbotillo\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/05\/avm-fritzbox-7490-heimnetz.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/109847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2650"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=109847"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/109847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/102328"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=109847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=109847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=109847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}