{"id":108636,"date":"2018-09-27T17:44:11","date_gmt":"2018-09-27T15:44:11","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=108636"},"modified":"2018-09-27T18:40:31","modified_gmt":"2018-09-27T16:40:31","slug":"linktipp-sammlung-von-siri-kurzbefehlen","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/","title":{"rendered":"Linktipp: Sammlung von Siri-Kurzbefehlen"},"content":{"rendered":"<p>Seit iOS 12 gibt es mit den Siri-Kurzbefehlen und der dazugeh\u00f6rigen App ein ziemlich m\u00e4chtiges Werkzeug, um Arbeitsabl\u00e4ufe zu vereinfachen bzw. zu automatisieren. In der Kurzbefehle-App hat Apple selbst bereits eine Menge von Vorschl\u00e4gen zum Ausprobieren unter dem Reiter &#8222;Galerie&#8220; eingestellt.<\/p>\n<p>Wenn man allerdings mal schauen will, was andere Nutzer so f\u00fcr Kurzbefehle erstellt haben, dann lohnt sich ein Blick auf folgende Seiten:<\/p>\n<ul>\n<li><a href=\"https:\/\/shortcutsgallery.com\" target=\"_blank\" rel=\"noopener\">shortcutsgallery.com<\/a><\/li>\n<li><a href=\"https:\/\/routinehub.co\" target=\"_blank\" rel=\"noopener\">routinehub.co<\/a><\/li>\n<li><a href=\"https:\/\/www.reddit.com\/r\/shortcuts\" target=\"_blank\" rel=\"noopener\">reddit.com\/r\/shortcuts<\/a><\/li>\n<\/ul>\n<!-- WP-Appbox (Version: 4.5.13 \/\/ Store: appstore \/\/ ID: 915249334) -->\n<div class=\"wpappbox wpappbox-1896bc23e35a3c8401233bc9e9145fd7 appstore simple\">\n\t<div class=\"qrcode\"><img decoding=\"async\" src=\"https:\/\/api.qrserver.com\/v1\/create-qr-code\/?data=https%3A%2F%2Fitunes.apple.com%2Fde%2Fapp%2Fkurzbefehle%2Fid915249334%3Fmt%3D8&size=200x200&ecc=M&margin=0\" alt=\"Kurzbefehle\" \/><\/div>\n\t<div class=\"appicon\">\n\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/itunes.apple.com\/de\/app\/kurzbefehle\/id915249334?mt=8\" aria-label=\"Kurzbefehle\"><img decoding=\"async\" src=\"\/\/is4-ssl.mzstatic.com\/image\/thumb\/Purple118\/v4\/1c\/be\/bd\/1cbebd64-39b2-4b0d-e33a-9296c629e96f\/AppIcon-0-1x_U007emarketing-0-0-GLES2_U002c0-512MB-sRGB-0-0-0-85-220-0-0-0-7.png\/246x0w.jpg\" alt=\"Kurzbefehle\" \/><\/a>\n\t<\/div>\n\t<div class=\"applinks\">\n\t\t<div class=\"appbuttons\">\n\t\t\t<a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/itunes.apple.com\/de\/app\/kurzbefehle\/id915249334?mt=8\" aria-label=\"Kurzbefehle\">Download<\/a>\n\t\t\t<span onMouseOver=\"jQuery('.wpappbox-1896bc23e35a3c8401233bc9e9145fd7 .qrcode').show();\" onMouseOut=\"jQuery('.wpappbox-1896bc23e35a3c8401233bc9e9145fd7 .qrcode').hide();\">QR-Code<\/span>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"appdetails\">\n\t\t<div class=\"apptitle\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/itunes.apple.com\/de\/app\/kurzbefehle\/id915249334?mt=8\" title=\"Kurzbefehle\" aria-label=\"Kurzbefehle\" class=\"apptitle\">Kurzbefehle<\/a><\/div>\n\t\t<div class=\"developer\">\n\t\t\t<span class=\"label\">Entwickler: <\/span>\n\t\t\t<span class=\"value\"><a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/itunes.apple.com\/de\/developer\/apple\/id642218247?mt=8\">Apple<\/a><\/span>\n\t\t<\/div>\n\t\t<div class=\"price\">\n\t\t\t<span class=\"label\">Preis: <\/span>\n\t\t\t<span class=\"value\">Kostenlos<\/span> \n\t\t\t<span class=\"rating\"><div title=\"4.4 von 5 Sternen\" class=\"rating-stars stars-monochrome stars45\"><\/div><\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div><!-- \/WP-Appbox -->\n","protected":false},"excerpt":{"rendered":"<p>Seit iOS 12 gibt es mit den Siri-Kurzbefehlen und der dazugeh\u00f6rigen App ein ziemlich m\u00e4chtiges Werkzeug, um Arbeitsabl\u00e4ufe zu vereinfachen bzw. zu automatisieren. In der Kurzbefehle-App hat Apple selbst bereits eine Menge von Vorschl\u00e4gen zum Ausprobieren unter dem Reiter &#8222;Galerie&#8220;&hellip; <\/p>\n","protected":false},"author":1525,"featured_media":108638,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"Linktipp: Sammlung von Siri-Kurzbefehlen @siri_shortcuts","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[232],"tags":[88,7513,30124,45810,4376,956],"class_list":["post-108636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ios","tag-download","tag-galerie","tag-ios-12","tag-kurzbefehle","tag-siri","tag-ubersicht"],"wp_featured_image":{"id":108638,"alt_text":"","description":"","media_type":"image","media_details":{"width":1326,"height":898,"file":"2018\/09\/siri-kurzbefehle.jpg","sizes":{"thumbnail":{"file":"siri-kurzbefehle-303x205.jpg","width":303,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle-303x205.jpg"},"medium":{"file":"siri-kurzbefehle-500x339.jpg","width":500,"height":339,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle-500x339.jpg"},"large":{"file":"siri-kurzbefehle-810x549.jpg","width":810,"height":549,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle-810x549.jpg"},"wp_review_large":{"file":"siri-kurzbefehle-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle-320x200.jpg"},"wp_review_small":{"file":"siri-kurzbefehle-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle-65x65.jpg"},"blog-large":{"file":"siri-kurzbefehle-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle-642x300.jpg"},"blog-medium":{"file":"siri-kurzbefehle-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle-306x205.jpg"},"recent-thumb":{"file":"siri-kurzbefehle-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle-350x316.jpg"},"service-featured":{"file":"siri-kurzbefehle-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle-600x330.jpg"},"wp_rp_thumbnail":{"file":"siri-kurzbefehle-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":108636,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle.jpg"},"commentcount":2,"wp_comments":[{"id":83177,"parent":0,"author":0,"author_name":"Marv","author_email":"Master3000_wob@hotmail.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7f2e91b0430acbb1cce7d08576b5620c92ba573edaedf483db463bda0d8661ad?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7f2e91b0430acbb1cce7d08576b5620c92ba573edaedf483db463bda0d8661ad?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7f2e91b0430acbb1cce7d08576b5620c92ba573edaedf483db463bda0d8661ad?s=96&d=mm&r=g"},"date":"2018-09-29T16:33:04","cld_nonce":"82f011626f","content":{"rendered":"<p>Eine Sache verstehe ich noch nicht &#8211; wenn ich beispielsweise bei Reddit auf einen Link zu einem Shortcut klicke, bringt er mich auf die iCloud, wo ich &#8222;Kurzbefehl erhalten&#8220; klicken kann. Danach bringt er mich nur zum Download der Shortcut App an sich. <\/p>\n<p>Gibt es da irgendeinen Trick?<\/p>\n"},"status":"1"},{"id":331391,"parent":0,"author":0,"author_name":"Sascha","author_email":"7sascha7santori7@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/461a56e1ac368bca0c0a7548033c2e4cf4966326378f996b9c60ca0724f6c6cc?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/461a56e1ac368bca0c0a7548033c2e4cf4966326378f996b9c60ca0724f6c6cc?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/461a56e1ac368bca0c0a7548033c2e4cf4966326378f996b9c60ca0724f6c6cc?s=96&d=mm&r=g"},"date":"2026-03-23T14:14:07","cld_nonce":"82f011626f","content":{"rendered":"<p>Ich hoffe es funktioniert alles<\/p>\n"},"status":"1"}],"wp_author":{"id":1525,"name":"W8U","description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Linktipp: Sammlung von Siri-Kurzbefehlen - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Linktipp: Sammlung von Siri-Kurzbefehlen\" \/>\n<meta property=\"og:description\" content=\"Seit iOS 12 gibt es mit den Siri-Kurzbefehlen und der dazugeh\u00f6rigen App ein ziemlich m\u00e4chtiges Werkzeug, um Arbeitsabl\u00e4ufe zu vereinfachen bzw. zu automatisieren. In der Kurzbefehle-App hat Apple selbst bereits eine Menge von Vorschl\u00e4gen zum Ausprobieren unter dem Reiter &#8222;Galerie&#8220;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-27T15:44:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-27T16:40:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1326\" \/>\n\t<meta property=\"og:image:height\" content=\"898\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"W8U\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/\"},\"author\":{\"name\":\"W8U\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\"},\"headline\":\"Linktipp: Sammlung von Siri-Kurzbefehlen\",\"datePublished\":\"2018-09-27T15:44:11+00:00\",\"dateModified\":\"2018-09-27T16:40:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/\"},\"wordCount\":81,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/siri-kurzbefehle.jpg\",\"keywords\":[\"Download\",\"Galerie\",\"iOS 12\",\"Kurzbefehle\",\"siri\",\"\u00dcbersicht\"],\"articleSection\":[\"iOS\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/\",\"name\":\"Linktipp: Sammlung von Siri-Kurzbefehlen - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/siri-kurzbefehle.jpg\",\"datePublished\":\"2018-09-27T15:44:11+00:00\",\"dateModified\":\"2018-09-27T16:40:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/siri-kurzbefehle.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/siri-kurzbefehle.jpg\",\"width\":1326,\"height\":898},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/09\\\/27\\\/linktipp-sammlung-von-siri-kurzbefehlen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Linktipp: Sammlung von Siri-Kurzbefehlen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\",\"name\":\"W8U\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"caption\":\"W8U\"},\"description\":\"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/w8u\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Linktipp: Sammlung von Siri-Kurzbefehlen - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/","og_locale":"de_DE","og_type":"article","og_title":"Linktipp: Sammlung von Siri-Kurzbefehlen","og_description":"Seit iOS 12 gibt es mit den Siri-Kurzbefehlen und der dazugeh\u00f6rigen App ein ziemlich m\u00e4chtiges Werkzeug, um Arbeitsabl\u00e4ufe zu vereinfachen bzw. zu automatisieren. In der Kurzbefehle-App hat Apple selbst bereits eine Menge von Vorschl\u00e4gen zum Ausprobieren unter dem Reiter &#8222;Galerie&#8220;&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-09-27T15:44:11+00:00","article_modified_time":"2018-09-27T16:40:31+00:00","og_image":[{"width":1326,"height":898,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle.jpg","type":"image\/jpeg"}],"author":"W8U","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/"},"author":{"name":"W8U","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469"},"headline":"Linktipp: Sammlung von Siri-Kurzbefehlen","datePublished":"2018-09-27T15:44:11+00:00","dateModified":"2018-09-27T16:40:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/"},"wordCount":81,"commentCount":2,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle.jpg","keywords":["Download","Galerie","iOS 12","Kurzbefehle","siri","\u00dcbersicht"],"articleSection":["iOS"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/","name":"Linktipp: Sammlung von Siri-Kurzbefehlen - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle.jpg","datePublished":"2018-09-27T15:44:11+00:00","dateModified":"2018-09-27T16:40:31+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle.jpg","width":1326,"height":898},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/09\/27\/linktipp-sammlung-von-siri-kurzbefehlen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Linktipp: Sammlung von Siri-Kurzbefehlen"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469","name":"W8U","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","caption":"W8U"},"description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","url":"https:\/\/www.deskmodder.de\/blog\/author\/w8u\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/09\/siri-kurzbefehle.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/108636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/1525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=108636"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/108636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/108638"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=108636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=108636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=108636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}