{"id":106508,"date":"2018-08-19T08:34:11","date_gmt":"2018-08-19T06:34:11","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=106508"},"modified":"2018-08-19T08:34:11","modified_gmt":"2018-08-19T06:34:11","slug":"mediatek-arbeitet-am-helio-p80-p90","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/","title":{"rendered":"MediaTek arbeitet am Helio P80 &#038; P90"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15722\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg\" alt=\"\" width=\"620\" height=\"340\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg 620w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip-150x82.jpg 150w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip-500x274.jpg 500w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Auf dem diesj\u00e4hrigen Mobile World Congress in Barcelona hat uns MediaTek seinen neuen Helio P60 Octacore-Prozessor vorgestellt. Der Mittelklasse-Prozessor wurde bereits in diversen Ger\u00e4ten verbaut, bekommt nun aber aus eigenem Haus Konkurrenz. Denn wie Roland Quandt berichtet, arbeitet man bei MediaTek mit Hochdruck am Helio P80 und Helio P90.<\/p>\n<p>Details liegen hier noch nicht vor. Beide sollen nat\u00fcrlich deutlich leistungsf\u00e4higer und effizienter sein als der P60. Eine NPU f\u00fcr KI Aufgaben werden die kommenden Prozessoren wohl auch haben. OPPO soll \u00fcbrigens der erste Hersteller sein, welcher die beiden neuen Chips verbaut haben wird. Einen m\u00f6glichen Pr\u00e4sentationstermin gibt&#8217;s noch nicht.<\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/twitter.com\/rquandt\/status\/1030235310142226433?s=19\" target=\"_blank\" rel=\"noopener\">Roland Quandt<\/a> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Auf dem diesj\u00e4hrigen Mobile World Congress in Barcelona hat uns MediaTek seinen neuen Helio P60 Octacore-Prozessor vorgestellt. Der Mittelklasse-Prozessor wurde bereits in diversen Ger\u00e4ten verbaut, bekommt nun aber aus eigenem Haus Konkurrenz. Denn wie Roland Quandt berichtet, arbeitet man bei&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":15722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286,231],"tags":[43166,43167],"class_list":["post-106508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","category-mobile","tag-mediatek-helio-p80","tag-mediatek-helio-p90"],"wp_featured_image":{"id":15722,"alt_text":"","description":"","media_type":"image","media_details":{"width":620,"height":340,"file":"2013\/11\/mediatek-chip.jpg","sizes":{"thumbnail":{"file":"mediatek-chip-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip-150x150.jpg"},"medium":{"file":"mediatek-chip-150x82.jpg","width":150,"height":82,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip-150x82.jpg"},"large":{"file":"mediatek-chip-500x274.jpg","width":500,"height":274,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip-500x274.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":15721,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg"},"commentcount":1,"wp_comments":[{"id":81258,"parent":0,"author":0,"author_name":"xtx","author_email":"chiaoi@gmail.com","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/14b0d3de34ba6dd2d4d46a881cfae3a5e22ad559a13d9c43a382a67d956c63de?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/14b0d3de34ba6dd2d4d46a881cfae3a5e22ad559a13d9c43a382a67d956c63de?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/14b0d3de34ba6dd2d4d46a881cfae3a5e22ad559a13d9c43a382a67d956c63de?s=96&d=mm&r=g"},"date":"2018-09-13T21:29:21","cld_nonce":"82f011626f","content":{"rendered":"<p>Finde ich gut, nur gibt es recht wenig ger\u00e4te mit den Performance Chips\u00e4tzen,<br \/>\nheute machten ich und ein Freund mal Geekbench 4.2 an:<\/p>\n<p>Xperia M5 mit Helio X10: 1. Run 4323 \/ 3. Run 5371<br \/>\nGalaxy S7 Exynos 8890 : Durchweg 5396<\/p>\n<p>Core Pilot 2.0 von MT muss man wissen wie der funktioniert, ersten 2 Tests nur 6 Cores um das Thermische Budget aus zu loten, ab dem 3. sind alle 8 A53 Cores aktiv<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>MediaTek arbeitet am Helio P80 &amp; P90 - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MediaTek arbeitet am Helio P80 &amp; P90\" \/>\n<meta property=\"og:description\" content=\"Auf dem diesj\u00e4hrigen Mobile World Congress in Barcelona hat uns MediaTek seinen neuen Helio P60 Octacore-Prozessor vorgestellt. Der Mittelklasse-Prozessor wurde bereits in diversen Ger\u00e4ten verbaut, bekommt nun aber aus eigenem Haus Konkurrenz. Denn wie Roland Quandt berichtet, arbeitet man bei&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-19T06:34:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"MediaTek arbeitet am Helio P80 &#038; P90\",\"datePublished\":\"2018-08-19T06:34:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/\"},\"wordCount\":118,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/mediatek-chip.jpg\",\"keywords\":[\"MediaTek Helio P80\",\"MediaTek Helio P90\"],\"articleSection\":{\"1\":\"Hardware\",\"2\":\"Mobile\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/\",\"name\":\"MediaTek arbeitet am Helio P80 & P90 - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/mediatek-chip.jpg\",\"datePublished\":\"2018-08-19T06:34:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/mediatek-chip.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/mediatek-chip.jpg\",\"width\":620,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/08\\\/19\\\/mediatek-arbeitet-am-helio-p80-p90\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MediaTek arbeitet am Helio P80 &#038; P90\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MediaTek arbeitet am Helio P80 & P90 - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/","og_locale":"de_DE","og_type":"article","og_title":"MediaTek arbeitet am Helio P80 & P90","og_description":"Auf dem diesj\u00e4hrigen Mobile World Congress in Barcelona hat uns MediaTek seinen neuen Helio P60 Octacore-Prozessor vorgestellt. Der Mittelklasse-Prozessor wurde bereits in diversen Ger\u00e4ten verbaut, bekommt nun aber aus eigenem Haus Konkurrenz. Denn wie Roland Quandt berichtet, arbeitet man bei&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-08-19T06:34:11+00:00","og_image":[{"width":620,"height":340,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"MediaTek arbeitet am Helio P80 &#038; P90","datePublished":"2018-08-19T06:34:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/"},"wordCount":118,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg","keywords":["MediaTek Helio P80","MediaTek Helio P90"],"articleSection":{"1":"Hardware","2":"Mobile"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/","name":"MediaTek arbeitet am Helio P80 & P90 - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg","datePublished":"2018-08-19T06:34:11+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg","width":620,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/08\/19\/mediatek-arbeitet-am-helio-p80-p90\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"MediaTek arbeitet am Helio P80 &#038; P90"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2013\/11\/mediatek-chip.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/106508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=106508"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/106508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/15722"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=106508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=106508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=106508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}