{"id":104721,"date":"2018-07-11T15:51:16","date_gmt":"2018-07-11T13:51:16","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=104721"},"modified":"2023-01-14T17:10:02","modified_gmt":"2023-01-14T16:10:02","slug":"spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/","title":{"rendered":"Spectre 1.1 und Spectre 1.2 &#8211; CPU Sicherheitsl\u00fccken ver\u00f6ffentlicht"},"content":{"rendered":"<p>Es gibt nun schon so viel zu Spectre und Meltdown, dass man langsam den \u00dcberblick verliert. Jetzt haben Forscher neue Spectre Varianten ausfindig gemacht, die nicht nur in Intel-CPUs vorkommen. Auch ARM hat diese best\u00e4tigt. Nur AMD h\u00e4lt sich noch zur\u00fcck. Spectre 1.1 \u00e4hnelt der Spectre 1 und Spectre 4. Hier kann der Cache-Puffer der CPU zum \u00fcberlaufen gebracht werden, um b\u00f6sartigen Code zu schreiben und auszuf\u00fchren.<\/p>\n<p>Spectre 1.2 kann ausgenutzt werden, um in den CPU-Speichersektoren Schreibvorg\u00e4nge vorzunehmen, obwohl diese Schreibgesch\u00fctzt sind. Die Sandbox-Funktion wird dadurch ausgehebelt. Aber um euch nicht zu sehr zu beunruhigen diese L\u00fccken ben\u00f6tigen b\u00f6sartigen Code auf dem Rechner, damit diese ausgef\u00fchrt werden k\u00f6nnen. Sowie Updates zur Verf\u00fcgung stehen, sollten diese nat\u00fcrlich trotzdem installiert werden.<\/p>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251.jpg\" rel=\"lightbox[104721]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-468x360.jpg\" alt=\"http:\/\/www.stockvault.net\/photo\/174251\/cyber-security-concept\" width=\"468\" height=\"360\" class=\"aligncenter size-medium wp-image-92066\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-468x360.jpg 468w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-266x205.jpg 266w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251-758x583.jpg 758w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/10\/stockvault-cyber-security-concept174251.jpg 1205w\" sizes=\"auto, (max-width: 468px) 100vw, 468px\" \/><\/a><br \/>\nDas Forscherteam, bestehend aus zwei Personen hat drei hardwarebasierte Abschw\u00e4chungen vorgeschlagen. Microsoft, Oracle und Red Hat untersuchen derzeit diese L\u00fccken, ob ein Risiko auf Softwareebene besteht. Intel selber hat als Bug-Bounty den beiden 100.000 Dollar f\u00fcr das Auffinden der L\u00fccke gezahlt.<\/p>\n<p>Ob das ganze Thema jemals ein Ende finden wird ist ungewiss. Erst die neu erscheinenden CPUs von Intel sollen diese L\u00fccken nicht mehr enthalten. Aber bis dahin ist noch lang und die Forscher sicher aufmerksam. Aber jeder Fehler der jetzt gefunden wird hilft Intel die CPUs abzusichern.<\/p>\n<h3>Kurze \u00dcbersicht \u00fcber Spectre<\/h3>\n<ul>\n<li>Spectre v1 CVE-2017-5753 (Intel, AMD, ARM) <a href=\"https:\/\/spectreattack.com\/\" rel=\"noopener\" target=\"_blank\">spectreattack.com\/<\/a><\/li>\n<li>Spectre 1.1 CVE-2018-3693 (Bisher Intel, ARM) <a href=\"https:\/\/people.csail.mit.edu\/vlk\/spectre11.pdf\" rel=\"noopener\" target=\"_blank\">people.csail.mit.edu\/vlk\/spectre11.pdf<\/a><\/li>\n<li>Spectre 1.2 Keine CVE  (Bisher Intel, ARM) <a href=\"https:\/\/people.csail.mit.edu\/vlk\/spectre11.pdf\" rel=\"noopener\" target=\"_blank\">people.csail.mit.edu\/vlk\/spectre11.pdf<\/a><\/li>\n<li>Spectre v2 CVE-2017-5715 (Intel, AMD, ARM) <a href=\"https:\/\/spectreattack.com\/\" rel=\"noopener\" target=\"_blank\">spectreattack.com\/<\/a><\/li>\n<li>Meltdown CVE-2017-5754  (Intel) <a href=\"https:\/\/meltdownattack.com\/\" rel=\"noopener\" target=\"_blank\">meltdownattack.com\/<\/a><\/li>\n<li>Variant 3a CVE-2018-3640 (Intel, AMD, ARM, IBM) <a href=\"https:\/\/cve.mitre.org\/cgi-bin\/cvename.cgi?name=CVE-2018-3640\" rel=\"noopener\" target=\"_blank\">cve.mitre.org\/<\/a><\/li>\n<li>Spectre v4 CVE-2018-3639 (Intel, AMD, ARM, IBM) <a href=\"https:\/\/blogs.technet.microsoft.com\/srd\/2018\/05\/21\/analysis-and-mitigation-of-speculative-store-bypass-cve-2018-3639\/\" rel=\"noopener\" target=\"_blank\">blogs.technet.microsoft.com<\/a><\/li>\n<\/ul>\n<p>via und Danke f\u00fcr die \u00dcbersicht <a href=\"https:\/\/www.bleepingcomputer.com\/news\/security\/new-spectre-11-and-spectre-12-cpu-flaws-disclosed\/\" rel=\"noopener\" target=\"_blank\">bleepingcomputer<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es gibt nun schon so viel zu Spectre und Meltdown, dass man langsam den \u00dcberblick verliert. Jetzt haben Forscher neue Spectre Varianten ausfindig gemacht, die nicht nur in Intel-CPUs vorkommen. Auch ARM hat diese best\u00e4tigt. Nur AMD h\u00e4lt sich noch&hellip; <\/p>\n","protected":false},"author":134,"featured_media":83156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1286,2689,11],"tags":[574,480,40768,40769],"class_list":["post-104721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","category-windows-10","category-windows","tag-intel","tag-sicherheitslucke","tag-spectre-1-1","tag-spectre-1-2"],"wp_featured_image":{"id":83156,"alt_text":"","description":"","media_type":"image","media_details":{"width":640,"height":479,"file":"2017\/04\/secure.jpeg","sizes":{"thumbnail":{"file":"secure-274x205.jpeg","width":274,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure-274x205.jpeg"},"medium":{"file":"secure-481x360.jpeg","width":481,"height":360,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure-481x360.jpeg"},"wp_review_large":{"file":"secure-320x200.jpeg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure-320x200.jpeg"},"wp_review_small":{"file":"secure-65x65.jpeg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure-65x65.jpeg"},"blog-large":{"file":"secure-640x300.jpeg","width":640,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure-640x300.jpeg"},"blog-medium":{"file":"secure-306x205.jpeg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure-306x205.jpeg"},"recent-thumb":{"file":"secure-350x316.jpeg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure-350x316.jpeg"},"service-featured":{"file":"secure-600x330.jpeg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure-600x330.jpeg"},"wp_rp_thumbnail":{"file":"secure-150x150.jpeg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure-150x150.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":83153,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure.jpeg"},"commentcount":0,"wp_comments":[],"wp_author":{"id":134,"name":"moinmoin","description":"Ich bin nicht allwissend, was <a href=\"https:\/\/www.deskmodder.de\/wiki\/index.php?title=Kategorie:Windows_11\">Windows<\/a> angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. <i>J\u00fcrgen<\/i>","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Spectre 1.1 und Spectre 1.2 - CPU Sicherheitsl\u00fccken ver\u00f6ffentlicht - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spectre 1.1 und Spectre 1.2 - CPU Sicherheitsl\u00fccken ver\u00f6ffentlicht\" \/>\n<meta property=\"og:description\" content=\"Es gibt nun schon so viel zu Spectre und Meltdown, dass man langsam den \u00dcberblick verliert. Jetzt haben Forscher neue Spectre Varianten ausfindig gemacht, die nicht nur in Intel-CPUs vorkommen. Auch ARM hat diese best\u00e4tigt. Nur AMD h\u00e4lt sich noch&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-11T13:51:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-14T16:10:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moinmoin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/\"},\"author\":{\"name\":\"moinmoin\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\"},\"headline\":\"Spectre 1.1 und Spectre 1.2 &#8211; CPU Sicherheitsl\u00fccken ver\u00f6ffentlicht\",\"datePublished\":\"2018-07-11T13:51:16+00:00\",\"dateModified\":\"2023-01-14T16:10:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/\"},\"wordCount\":315,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/secure.jpeg\",\"keywords\":[\"Intel\",\"Sicherheitsl\u00fccke\",\"Spectre 1.1\",\"Spectre 1.2\"],\"articleSection\":[\"Hardware\",\"Windows 10\",\"Windows \u00e4lter\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/\",\"name\":\"Spectre 1.1 und Spectre 1.2 - CPU Sicherheitsl\u00fccken ver\u00f6ffentlicht - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/secure.jpeg\",\"datePublished\":\"2018-07-11T13:51:16+00:00\",\"dateModified\":\"2023-01-14T16:10:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/secure.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/secure.jpeg\",\"width\":640,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/11\\\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spectre 1.1 und Spectre 1.2 &#8211; CPU Sicherheitsl\u00fccken ver\u00f6ffentlicht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/a40b17a9503c4a1568ac4073bb54182a\",\"name\":\"moinmoin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g\",\"caption\":\"moinmoin\"},\"description\":\"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/moinmoin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Spectre 1.1 und Spectre 1.2 - CPU Sicherheitsl\u00fccken ver\u00f6ffentlicht - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/","og_locale":"de_DE","og_type":"article","og_title":"Spectre 1.1 und Spectre 1.2 - CPU Sicherheitsl\u00fccken ver\u00f6ffentlicht","og_description":"Es gibt nun schon so viel zu Spectre und Meltdown, dass man langsam den \u00dcberblick verliert. Jetzt haben Forscher neue Spectre Varianten ausfindig gemacht, die nicht nur in Intel-CPUs vorkommen. Auch ARM hat diese best\u00e4tigt. Nur AMD h\u00e4lt sich noch&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-07-11T13:51:16+00:00","article_modified_time":"2023-01-14T16:10:02+00:00","og_image":[{"width":640,"height":479,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure.jpeg","type":"image\/jpeg"}],"author":"moinmoin","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/"},"author":{"name":"moinmoin","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a"},"headline":"Spectre 1.1 und Spectre 1.2 &#8211; CPU Sicherheitsl\u00fccken ver\u00f6ffentlicht","datePublished":"2018-07-11T13:51:16+00:00","dateModified":"2023-01-14T16:10:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/"},"wordCount":315,"commentCount":0,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure.jpeg","keywords":["Intel","Sicherheitsl\u00fccke","Spectre 1.1","Spectre 1.2"],"articleSection":["Hardware","Windows 10","Windows \u00e4lter"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/","name":"Spectre 1.1 und Spectre 1.2 - CPU Sicherheitsl\u00fccken ver\u00f6ffentlicht - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure.jpeg","datePublished":"2018-07-11T13:51:16+00:00","dateModified":"2023-01-14T16:10:02+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure.jpeg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure.jpeg","width":640,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/11\/spectre-1-1-und-spectre-1-2-cpu-sicherheitsluecken-veroeffentlicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Spectre 1.1 und Spectre 1.2 &#8211; CPU Sicherheitsl\u00fccken ver\u00f6ffentlicht"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/a40b17a9503c4a1568ac4073bb54182a","name":"moinmoin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fab96769102f8886245ab411df9a42a235be79261e4b44aa7ab2a555da8b86b4?s=96&d=mm&r=g","caption":"moinmoin"},"description":"Ich bin nicht allwissend, was Windows angeht. Aber genau deshalb nehme ich Windows gerne auseinander und unter die Lupe, um all mein Wissen zu erweitern. J\u00fcrgen","url":"https:\/\/www.deskmodder.de\/blog\/author\/moinmoin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/04\/secure.jpeg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/104721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=104721"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/104721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/83156"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=104721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=104721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=104721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}