{"id":104584,"date":"2018-07-09T20:47:54","date_gmt":"2018-07-09T18:47:54","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=104584"},"modified":"2018-07-09T20:47:54","modified_gmt":"2018-07-09T18:47:54","slug":"apple-veroeffentlicht-ios-11-4-1","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/","title":{"rendered":"Apple ver\u00f6ffentlicht iOS 11.4.1"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Apple hat heute Abend ein kleines Bugfix-Update mit der Versionsnummer 11.4.1 f\u00fcr iOS ver\u00f6ffentlicht. Im Wesentlichen betreffen die Verbesserungen das Zusammenspiel mit den AirPods sowie die Synchronisation von Exchange-Accounts.<\/p>\n<p>Informationen zu den geschlossenen Sicherheitsl\u00fccken werden von Apple auf <a href=\"https:\/\/support.apple.com\/de-de\/HT201222\" target=\"_blank\" rel=\"noopener\">dieser Seite<\/a> ver\u00f6ffentlicht. Aktuell m\u00fcsst ihr euch aber noch etwas gedulden, weil Apple immer ein bisschen braucht, um die Seite zu aktualisieren.<\/p>\n<p>Ihr solltet f\u00fcr das Update wie immer ausreichend\u00a0Speicher frei halten und im Idealfall einen Akkustand von mindestens 50 Prozent haben.\u00a0Falls der Speicherplatz zu knapp sein sollte, gilt wie immer: iOS-Device an den PC oder Mac\u00a0anstecken und das Update per iTunes laden.<\/p>\n<h3>iOS 11.4.1 Changelog<\/h3>\n<p>iOS 11.4.1 enth\u00e4lt Fehlerbehebungen und verbessert die Sicherheit von iPhone und iPad. Dieses Update&#8230;<\/p>\n<ul>\n<li>behebt ein Problem, bei dem Benutzer bisweilen nicht den letzten bekannten Standort ihrer AirPods in \u201eMein iPhone suchen\u201c sehen konnten<\/li>\n<li>verbessert die Zuverl\u00e4ssigkeit beim Synchronisieren von E-Mails, Kontakten und Notizen mit Exchange-Accounts<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11.jpg\" rel=\"lightbox[104584]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-86182\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-810x410.jpg\" alt=\"\" width=\"810\" height=\"410\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-810x410.jpg 810w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-306x155.jpg 306w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-500x253.jpg 500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11.jpg 1861w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Apple hat heute Abend ein kleines Bugfix-Update mit der Versionsnummer 11.4.1 f\u00fcr iOS ver\u00f6ffentlicht. Im Wesentlichen betreffen die Verbesserungen das Zusammenspiel mit den AirPods sowie die Synchronisation von Exchange-Accounts. Informationen zu den geschlossenen Sicherheitsl\u00fccken werden von Apple auf dieser&hellip; <\/p>\n","protected":false},"author":1525,"featured_media":86182,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[232],"tags":[40606,5247,1174,88,40605,39166,104],"class_list":["post-104584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ios","tag-airpod-finden","tag-changelog","tag-deutsch","tag-download","tag-exchange-problem","tag-ios-11-4-1","tag-update"],"wp_featured_image":{"id":86182,"alt_text":"","description":"","media_type":"image","media_details":{"width":1861,"height":943,"file":"2017\/06\/ios11.jpg","sizes":{"thumbnail":{"file":"ios11-306x155.jpg","width":306,"height":155,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-306x155.jpg"},"medium":{"file":"ios11-500x253.jpg","width":500,"height":253,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-500x253.jpg"},"large":{"file":"ios11-810x410.jpg","width":810,"height":410,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-810x410.jpg"},"wp_review_large":{"file":"ios11-320x200.jpg","width":320,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-320x200.jpg"},"wp_review_small":{"file":"ios11-65x65.jpg","width":65,"height":65,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-65x65.jpg"},"blog-large":{"file":"ios11-642x300.jpg","width":642,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-642x300.jpg"},"blog-medium":{"file":"ios11-306x205.jpg","width":306,"height":205,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-306x205.jpg"},"recent-thumb":{"file":"ios11-350x316.jpg","width":350,"height":316,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-350x316.jpg"},"service-featured":{"file":"ios11-600x330.jpg","width":600,"height":330,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-600x330.jpg"},"wp_rp_thumbnail":{"file":"ios11-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":86149,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11.jpg"},"commentcount":2,"wp_comments":[{"id":76693,"parent":0,"author":0,"author_name":"Ingo","author_email":"ich@ingoboettcher.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5a0c425eb8c121489d0b36b2c85effdf0e649ea529265c4b90c7ce062790cf52?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5a0c425eb8c121489d0b36b2c85effdf0e649ea529265c4b90c7ce062790cf52?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5a0c425eb8c121489d0b36b2c85effdf0e649ea529265c4b90c7ce062790cf52?s=96&d=mm&r=g"},"date":"2018-07-09T22:55:28","cld_nonce":"82f011626f","content":{"rendered":"<p>Und kein Fix f\u00fcr das Battery-Drain Problem im 5 GHz WLAN? Na toll. <img src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/plugins\/classic-smilies\/img\/icon_sad.gif\" alt=\":(\" class=\"wp-smiley\" \/><\/p>\n"},"status":"1"},{"id":76766,"parent":0,"author":0,"author_name":"lottermann3","author_email":"archicom.rd@t-online.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ab1c1671ad9eccc84394b5fb1d76f84c99b634c24819459d143affa993ff1ab6?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ab1c1671ad9eccc84394b5fb1d76f84c99b634c24819459d143affa993ff1ab6?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ab1c1671ad9eccc84394b5fb1d76f84c99b634c24819459d143affa993ff1ab6?s=96&d=mm&r=g"},"date":"2018-07-11T09:35:39","cld_nonce":"82f011626f","content":{"rendered":"<p>Mein iPhone 7 startet seit dem Update sehr langsam, ebenso ist die Wlan-Verbindung auch langsam bis \u00fcberhauptnicht-baut keine Verbindung auf. Per LTE funktioniert alles. Fritzbox auch i.O.<br \/>\nHat das Problem noch wer?<\/p>\n"},"status":"1"}],"wp_author":{"id":1525,"name":"W8U","description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Apple ver\u00f6ffentlicht iOS 11.4.1 - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apple ver\u00f6ffentlicht iOS 11.4.1\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Apple hat heute Abend ein kleines Bugfix-Update mit der Versionsnummer 11.4.1 f\u00fcr iOS ver\u00f6ffentlicht. Im Wesentlichen betreffen die Verbesserungen das Zusammenspiel mit den AirPods sowie die Synchronisation von Exchange-Accounts. Informationen zu den geschlossenen Sicherheitsl\u00fccken werden von Apple auf dieser&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-09T18:47:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1861\" \/>\n\t<meta property=\"og:image:height\" content=\"943\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"W8U\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/\"},\"author\":{\"name\":\"W8U\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\"},\"headline\":\"Apple ver\u00f6ffentlicht iOS 11.4.1\",\"datePublished\":\"2018-07-09T18:47:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/\"},\"wordCount\":162,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/ios11.jpg\",\"keywords\":[\"Airpod finden\",\"changelog\",\"deutsch\",\"Download\",\"Exchange Problem\",\"iOS 11.4.1\",\"Update\"],\"articleSection\":[\"iOS\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/\",\"name\":\"Apple ver\u00f6ffentlicht iOS 11.4.1 - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/ios11.jpg\",\"datePublished\":\"2018-07-09T18:47:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/ios11.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/ios11.jpg\",\"width\":1861,\"height\":943},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/07\\\/09\\\/apple-veroeffentlicht-ios-11-4-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apple ver\u00f6ffentlicht iOS 11.4.1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/f3c70b4f4860c9fcc4c04057ed04f469\",\"name\":\"W8U\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g\",\"caption\":\"W8U\"},\"description\":\"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/w8u\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Apple ver\u00f6ffentlicht iOS 11.4.1 - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/","og_locale":"de_DE","og_type":"article","og_title":"Apple ver\u00f6ffentlicht iOS 11.4.1","og_description":"&nbsp; Apple hat heute Abend ein kleines Bugfix-Update mit der Versionsnummer 11.4.1 f\u00fcr iOS ver\u00f6ffentlicht. Im Wesentlichen betreffen die Verbesserungen das Zusammenspiel mit den AirPods sowie die Synchronisation von Exchange-Accounts. Informationen zu den geschlossenen Sicherheitsl\u00fccken werden von Apple auf dieser&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-07-09T18:47:54+00:00","og_image":[{"width":1861,"height":943,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11.jpg","type":"image\/jpeg"}],"author":"W8U","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/"},"author":{"name":"W8U","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469"},"headline":"Apple ver\u00f6ffentlicht iOS 11.4.1","datePublished":"2018-07-09T18:47:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/"},"wordCount":162,"commentCount":2,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11.jpg","keywords":["Airpod finden","changelog","deutsch","Download","Exchange Problem","iOS 11.4.1","Update"],"articleSection":["iOS"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/","name":"Apple ver\u00f6ffentlicht iOS 11.4.1 - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11.jpg","datePublished":"2018-07-09T18:47:54+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11.jpg","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11.jpg","width":1861,"height":943},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/07\/09\/apple-veroeffentlicht-ios-11-4-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Apple ver\u00f6ffentlicht iOS 11.4.1"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/f3c70b4f4860c9fcc4c04057ed04f469","name":"W8U","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1e9db99fdd71a9ae2c516203e3fcd390817fa98f868eb9ba6d4a77d1a815cd4?s=96&d=mm&r=g","caption":"W8U"},"description":"Technikliebhaber aus Niedersachsen und seit 2013 bei den Deskmoddern. Interessiert sich f\u00fcr (fast) alles, durch das Strom flie\u00dft: Computer, Smartphones, Tablets, Autos und so weiter.","url":"https:\/\/www.deskmodder.de\/blog\/author\/w8u\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2017\/06\/ios11.jpg","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/104584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/1525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=104584"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/104584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/86182"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=104584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=104584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=104584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}