{"id":103327,"date":"2018-06-13T18:11:33","date_gmt":"2018-06-13T16:11:33","guid":{"rendered":"https:\/\/www.deskmodder.de\/blog\/?p=103327"},"modified":"2018-06-13T18:11:33","modified_gmt":"2018-06-13T16:11:33","slug":"samsung-galaxy-note-9-das-sollen-die-farben-sein","status":"publish","type":"post","link":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/","title":{"rendered":"Samsung Galaxy Note 9: Das sollen die Farben sein"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-103331\" src=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124.png\" alt=\"\" width=\"1500\" height=\"1124\" srcset=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124.png 1500w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-274x205.png 274w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-480x360.png 480w, https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-778x583.png 778w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/p>\n<p>Am 9.August wird uns Samsung nach aktuellen Informationen auf einem Unpacked-Event das neue Galaxy Note 9 vorstellen. Dieses wird wieder mit allerlei Highend-Hardware ausgestattet sein aber auch in verschiedenen Farben erscheinen.<\/p>\n<p>Nachdem wir erst vor wenigen Tagen <a href=\"https:\/\/www.deskmodder.de\/blog\/2018\/06\/06\/samsung-galaxy-note-9-zahlreiche-render-bilder-eine-render-video\/\" target=\"_blank\" rel=\"noopener\">erste Render-Bilder und ein Render-Video <\/a>gesehen haben, haben nun einmal die Kollegen f\u00fcr uns die vermeintlichen Farbgebungen und man erkennt klar, dass es diesmal bunter wird. Neben Schwarz und Grau sollen auch Braun, Violett und Blau kommen. Ne sch\u00f6ne wei\u00dfe Version wie das OnePlus 6 Silk White oder ein Transparenzeffekt wie beim HTC U12+ w\u00e4ren aber auch nett gewesen. Aber vielleicht kommt da ja doch noch mehr.<\/p>\n<div class=\"quelle\">Quelle: <a href=\"https:\/\/allaboutsamsung.de\/2018\/06\/exklusiv-dies-koennten-die-farben-des-galaxy-note9-werden\/\" target=\"_blank\" rel=\"noopener\">Allaboutsamsung<\/a> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Am 9.August wird uns Samsung nach aktuellen Informationen auf einem Unpacked-Event das neue Galaxy Note 9 vorstellen. Dieses wird wieder mit allerlei Highend-Hardware ausgestattet sein aber auch in verschiedenen Farben erscheinen. Nachdem wir erst vor wenigen Tagen erste Render-Bilder und&hellip; <\/p>\n","protected":false},"author":2020,"featured_media":103331,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1286],"tags":[38425],"class_list":["post-103327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-hardware","tag-samsung-galaxy-note-9"],"wp_featured_image":{"id":103331,"alt_text":"","description":"","media_type":"image","media_details":{"width":1500,"height":1124,"file":"2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124.png","sizes":{"thumbnail":{"file":"galaxynote9allcolorsofficialaas20-1500x1124-274x205.png","width":274,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-274x205.png"},"medium":{"file":"galaxynote9allcolorsofficialaas20-1500x1124-480x360.png","width":480,"height":360,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-480x360.png"},"large":{"file":"galaxynote9allcolorsofficialaas20-1500x1124-778x583.png","width":778,"height":583,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-778x583.png"},"wp_review_large":{"file":"galaxynote9allcolorsofficialaas20-1500x1124-320x200.png","width":320,"height":200,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-320x200.png"},"wp_review_small":{"file":"galaxynote9allcolorsofficialaas20-1500x1124-65x65.png","width":65,"height":65,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-65x65.png"},"blog-large":{"file":"galaxynote9allcolorsofficialaas20-1500x1124-642x300.png","width":642,"height":300,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-642x300.png"},"blog-medium":{"file":"galaxynote9allcolorsofficialaas20-1500x1124-306x205.png","width":306,"height":205,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-306x205.png"},"recent-thumb":{"file":"galaxynote9allcolorsofficialaas20-1500x1124-350x316.png","width":350,"height":316,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-350x316.png"},"service-featured":{"file":"galaxynote9allcolorsofficialaas20-1500x1124-600x330.png","width":600,"height":330,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-600x330.png"},"wp_rp_thumbnail":{"file":"galaxynote9allcolorsofficialaas20-1500x1124-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":103327,"source_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124.png"},"commentcount":1,"wp_comments":[{"id":75179,"parent":0,"author":0,"author_name":"SirMarcvGoskon","author_email":"marcsenn@web.de","author_url":"","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/9e62520146b31fd00d34e0e668aa8f0006e7445dcb1f8ee2166fee7fef2be7a3?s=96&d=mm&r=g"},"date":"2018-06-14T05:13:15","cld_nonce":"82f011626f","content":{"rendered":"<p>Ne wei\u00df muss nicht sein.<br \/>\nMhhhh da lohnt sich doch gleich zu warten weil die s9 ist schon wider etwa 4 monate alt wenn ich am 15 august ein neues handy Aussuchen darf, und ein Note w\u00e4re auch mal was Geiles.?? In Blau nat\u00fcrlich Partner Look mit Realen TraumFrau.??<\/p>\n"},"status":"1"}],"wp_author":{"id":2020,"name":"Mike","description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","author_avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g"}},"cld_nonce":"82f011626f","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Samsung Galaxy Note 9: Das sollen die Farben sein - Deskmodder.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Samsung Galaxy Note 9: Das sollen die Farben sein\" \/>\n<meta property=\"og:description\" content=\"Am 9.August wird uns Samsung nach aktuellen Informationen auf einem Unpacked-Event das neue Galaxy Note 9 vorstellen. Dieses wird wieder mit allerlei Highend-Hardware ausgestattet sein aber auch in verschiedenen Farben erscheinen. Nachdem wir erst vor wenigen Tagen erste Render-Bilder und&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/\" \/>\n<meta property=\"og:site_name\" content=\"Deskmodder.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Deskmodder\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-13T16:11:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1124\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Deskmodder\" \/>\n<meta name=\"twitter:site\" content=\"@Deskmodder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/\"},\"author\":{\"name\":\"Mike\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\"},\"headline\":\"Samsung Galaxy Note 9: Das sollen die Farben sein\",\"datePublished\":\"2018-06-13T16:11:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/\"},\"wordCount\":118,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/galaxynote9allcolorsofficialaas20-1500x1124.png\",\"keywords\":[\"Samsung Galaxy Note 9\"],\"articleSection\":{\"1\":\"Hardware\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/\",\"name\":\"Samsung Galaxy Note 9: Das sollen die Farben sein - Deskmodder.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/galaxynote9allcolorsofficialaas20-1500x1124.png\",\"datePublished\":\"2018-06-13T16:11:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/galaxynote9allcolorsofficialaas20-1500x1124.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/galaxynote9allcolorsofficialaas20-1500x1124.png\",\"width\":1500,\"height\":1124},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/2018\\\/06\\\/13\\\/samsung-galaxy-note-9-das-sollen-die-farben-sein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Samsung Galaxy Note 9: Das sollen die Farben sein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"name\":\"Deskmodder.de\",\"description\":\"News zum Thema Microsoft, Windows 11 \\\/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#organization\",\"name\":\"Deskmodder\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"contentUrl\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/deskmodder-logo-app.png\",\"width\":281,\"height\":286,\"caption\":\"Deskmodder\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Deskmodder\",\"https:\\\/\\\/x.com\\\/Deskmodder\",\"https:\\\/\\\/mastodontech.de\\\/@Deskmodder\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/deskmodder\",\"https:\\\/\\\/mewe.com\\\/group\\\/5c83b5231add826fc80cdae1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/#\\\/schema\\\/person\\\/0d15dadb25ee420cb54f76ad120c98fa\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g\",\"caption\":\"Mike\"},\"description\":\"\u00dcber das Anpassen &amp; Abspecken von XP in die \\\"Windows-Welt\\\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.\",\"url\":\"https:\\\/\\\/www.deskmodder.de\\\/blog\\\/author\\\/mike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Samsung Galaxy Note 9: Das sollen die Farben sein - Deskmodder.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/","og_locale":"de_DE","og_type":"article","og_title":"Samsung Galaxy Note 9: Das sollen die Farben sein","og_description":"Am 9.August wird uns Samsung nach aktuellen Informationen auf einem Unpacked-Event das neue Galaxy Note 9 vorstellen. Dieses wird wieder mit allerlei Highend-Hardware ausgestattet sein aber auch in verschiedenen Farben erscheinen. Nachdem wir erst vor wenigen Tagen erste Render-Bilder und&hellip;","og_url":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/","og_site_name":"Deskmodder.de","article_publisher":"https:\/\/www.facebook.com\/Deskmodder","article_published_time":"2018-06-13T16:11:33+00:00","og_image":[{"width":1500,"height":1124,"url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124.png","type":"image\/png"}],"author":"Mike","twitter_card":"summary_large_image","twitter_creator":"@Deskmodder","twitter_site":"@Deskmodder","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/#article","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/"},"author":{"name":"Mike","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa"},"headline":"Samsung Galaxy Note 9: Das sollen die Farben sein","datePublished":"2018-06-13T16:11:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/"},"wordCount":118,"commentCount":1,"publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124.png","keywords":["Samsung Galaxy Note 9"],"articleSection":{"1":"Hardware"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/","url":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/","name":"Samsung Galaxy Note 9: Das sollen die Farben sein - Deskmodder.de","isPartOf":{"@id":"https:\/\/www.deskmodder.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/#primaryimage"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124.png","datePublished":"2018-06-13T16:11:33+00:00","breadcrumb":{"@id":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/#primaryimage","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124.png","width":1500,"height":1124},{"@type":"BreadcrumbList","@id":"https:\/\/www.deskmodder.de\/blog\/2018\/06\/13\/samsung-galaxy-note-9-das-sollen-die-farben-sein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.deskmodder.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Samsung Galaxy Note 9: Das sollen die Farben sein"}]},{"@type":"WebSite","@id":"https:\/\/www.deskmodder.de\/blog\/#website","url":"https:\/\/www.deskmodder.de\/blog\/","name":"Deskmodder.de","description":"News zum Thema Microsoft, Windows 11 \/ 10, sowie anderen Neuigkeiten aus dem Netz, viele Tipps und individuelle Hilfe bei Problemen in unserem Forum \u25cf Deskmodder - seit 2003","publisher":{"@id":"https:\/\/www.deskmodder.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deskmodder.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.deskmodder.de\/blog\/#organization","name":"Deskmodder","url":"https:\/\/www.deskmodder.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","contentUrl":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2019\/01\/deskmodder-logo-app.png","width":281,"height":286,"caption":"Deskmodder"},"image":{"@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deskmodder","https:\/\/x.com\/Deskmodder","https:\/\/mastodontech.de\/@Deskmodder","https:\/\/www.youtube.com\/user\/deskmodder","https:\/\/mewe.com\/group\/5c83b5231add826fc80cdae1"]},{"@type":"Person","@id":"https:\/\/www.deskmodder.de\/blog\/#\/schema\/person\/0d15dadb25ee420cb54f76ad120c98fa","name":"Mike","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a25a00ccc6c845d38ee2695915f64089ae7e42ad1a0e8247e29b357ef56b0fab?s=96&d=mm&r=g","caption":"Mike"},"description":"\u00dcber das Anpassen &amp; Abspecken von XP in die \"Windows-Welt\" gekommen, interessiere ich mich eigentlich f\u00fcr jedes gute St\u00fcck Technik. Neben Windows hat auch Android bei mir ein zu Hause gefunden. Und ich bin jedes Jahr gespannt, was mich Neues erwartet. Bloggen ist eine Leidenschaft von mir und ich teile diese hier gerne mit euch.","url":"https:\/\/www.deskmodder.de\/blog\/author\/mike\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.deskmodder.de\/blog\/wp-content\/uploads\/2018\/06\/galaxynote9allcolorsofficialaas20-1500x1124.png","_links":{"self":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/103327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/comments?post=103327"}],"version-history":[{"count":0,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/posts\/103327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media\/103331"}],"wp:attachment":[{"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/media?parent=103327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/categories?post=103327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deskmodder.de\/blog\/wp-json\/wp\/v2\/tags?post=103327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}